{"id":975,"date":"2005-07-17T00:00:00","date_gmt":"2005-07-16T22:00:00","guid":{"rendered":""},"modified":"2016-07-21T12:44:31","modified_gmt":"2016-07-21T10:44:31","slug":"delluguaglianza-e-del-problema-delle-classi","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/delluguaglianza-e-del-problema-delle-classi\/","title":{"rendered":"Dell&#8217;uguaglianza e del problema delle classi"},"content":{"rendered":"<div style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-36143\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/classi_sociali.jpg\" alt=\"classi_sociali\" width=\"154\" height=\"200\" \/>Tratto da:<strong> DIAGNOSI Saggio di fisiologia sociale<em><br \/>\n<\/em><\/strong><\/div>\n<p style=\"text-align: center;\">di<strong> Gustave Thibon<\/strong><\/p>\n<p style=\"text-align: justify;\">E&#8217; un fatto che mai, forse, si erano notati cos\u00ec pochi scambi e tanta distanza da una classe all&#8217;altra della societ\u00e0 o fra uomini di livello culturale diverso. L&#8217;influenza umana positiva delle \u00e9lites sul popolo \u00e8 ora pressoch\u00e9 nulla. Si era creduto, tuttavia &#8211; e fu uno dei maggiori miti del XIX secolo -, che la fraternit\u00e0, la comunione sinfonica degli uomini sarebbe nata dall&#8217;affievolimento dello spirito di classe e, in definitiva, nella soppressione delle barriere sociali. Ma ci\u00f2 che accade non \u00e8 paradossale che in apparenza.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">La confusione non unisce, ma separa: essa crea fra gli elementi confusi delle opposizioni irriducibili. Ogni reciprocit\u00e0 d&#8217;influenza implica una solida differenza di natura e di posizione. Proprio nelle societ\u00e0 fortemente diversificate e gerarchizzate, in cui il passaggio da un piano all&#8217;altro \u00e8 molto difficile, per non dire impossibile, si stabiliscono, fra i membri di tali gerarchie, gli scambi pi\u00f9 fecondi e duraturi: si pensi all&#8217;influenza secolare della monarchia, della nobilt\u00e0 o delle caste sacerdotali sul popolo.<\/p>\n<p style=\"text-align: justify;\">In simili formazioni politiche ciascuno, in virt\u00f9 proprio della stabilit\u00e0, della &#8220;fatalit\u00e0&#8221; della sua posizione, \u00e8 interamente disponibile per lavorare al bene della generalit\u00e0. Le classi in alto hanno le mani libere per dare, e quelle in basso per ricevere e gli scambi sono tanto pi\u00f9 profondi quanto pi\u00f9 \u00e8 difficile a scavalcare il fossato che separa i diversi strati sociali.<\/p>\n<p style=\"text-align: justify;\">La mistica democratica ha rovinato tutto ci\u00f2. Come potrebbero sussistere veri scambi all&#8217;interno della gerarchia, quando la stessa esistenza di tale gerarchia \u00e8 messa in dubbio? In tal caso l&#8217;inferiore, disgustato del suo ambiente, della sua posizione, di se stesso, da questo soffio d&#8217;aria di palude suscitato in lui dall&#8217;insegnamento dell&#8217;uguaglianza, non ha pi\u00f9 nulla da ricevere dal superiore, e non mira che a uguagliarsi a lui e a espellerlo.<\/p>\n<p style=\"text-align: justify;\">Il superiore, a sua volta, anzich\u00e9 governare avendo di mira il bene di tutti, tende soltanto a difendere la sua posizione minacciata. Da una parte l&#8217;invidia, dall&#8217;altra il timore inaridiscono tutti gli scambi vitali: questi non sono possibili che in quelle societ\u00e0 in cui il destino degli individui \u00e8 strettamente legato alla posizione che occupano e il passaggio da un piano all&#8217;altro della gerarchia esige una trasformazione e un&#8217;ascensione totale di colui che si eleva, e non il suo abbandonarsi alle grottesche combinazioni della finanza o del suffragio universale.<\/p>\n<p style=\"text-align: justify;\">Lo scambio sociale \u00e8 puro e fecondo solo in un mondo in cui il dirigente si sente sicuro in alto perch\u00e9 il subordinato si sente al suo posto in basso.Ma oggi possiamo ancora parlare di scambi? Oggi, in alto si tratta di difendere, in basso di conquistare. Con la sterile confusione delle classi comincia la sterile lotta delle classi. Non \u00e8 un paradosso affermare che le barriere sociali favoriscono assai spesso la comunione umana.<\/p>\n<p style=\"text-align: justify;\">Alla fine del secolo scorso nei nostri villaggi provenzali non ancora travagliati dalla febbre repubblicana, un&#8217;estrema familiarit\u00e0 regnava tra il signore del luogo e i contadini: giocavano insieme alle bocce dopo i vespri, le signorine della nobilt\u00e0 danzavano con i giovanotti del villaggio, ecc. Simili correnti di simpatia effettiva non erano possibili che nella misura in cui ogni classe restava legata alla sua posizione, al di fuori di ogni contestazione e di ogni invidia.<\/p>\n<p style=\"text-align: justify;\">In tali ambienti, in cui le differenze sociali erano accettate, vissute come indiscutibili necessit\u00e0, la familiarit\u00e0 tra una classe e l&#8217;altra poteva crescere sempre pi\u00f9 senza pericolo di promiscuit\u00e0: una fraternit\u00e0 profonda nasceva dall&#8217;accettazione dell&#8217;ineguaglianza.<\/p>\n<p style=\"text-align: justify;\">Il messianismo egalitario, al contrario, genera nel popolo la rivolta e la diffidenza nei riguardi dei capi e, nei capi, la preoccupazione di mantenere la distanza nei riguardi del popolo: da una parte un riflesso di aggressione, dall&#8217;altra un riflesso di difesa, la guerra al posto della comunione. Poich\u00e9 &#8211; qualunque sia la abitudine che la Rivoluzione francese ci ha dato di vedere accoppiate le due parole &#8211; la fraternit\u00e0 non ha quaggi\u00f9 peggior nemico dell&#8217;uguaglianza. Un nobile dell&#8217;anci\u00e9n regime poteva, senza cessare d&#8217;essere rispettato e obbedito, trattare i suoi servitori con un&#8217;estrema familiarit\u00e0; un moderno parvenu, \u00e8 obbligato a compensare mediante un autoritarismo morto l&#8217;assenza di autorit\u00e0 vivente, e di marcare tanto pi\u00f9 le distanze in quanto esse non esistono in realt\u00e0.<\/p>\n<p style=\"text-align: justify;\">L&#8217;egualitarismo pi\u00f9 malsano diventa fatale dal momento in cui la gerarchia sociale non si fonda pi\u00f9 che su diversit\u00e0 di patrimonio. Perch\u00e9 il popolo rispetti e segua spontaneamente coloro che lo governano, occorre senta che questi ultimi lo dominano per altro che non sia il denaro. Donde la necessit\u00e0 di diminuire fra gli uomini le disuguaglianze di fortuna a profitto delle differenze di casta, di tradizione, di cultura, ecc., o, quanto meno, di appoggiare le differenze di fortuna su delle differenze umane.<\/p>\n<p style=\"text-align: justify;\">Ma quale odiosa casta di padroni questa plebe coperta d&#8217;oro! Essa suscita, nell&#8217;animo del popolo, l&#8217;invidia pi\u00f9 nera e pi\u00f9 legittima, quel &#8220;perch\u00e9 non io&#8221; che, agitandosi a vuoto, scompagina le societ\u00e0. Chiunque, infatti, pu\u00f2 aspirare a esser ricco, dato che la conquista del denaro \u00e8 legata agli accidenti pi\u00f9 banali: non allo stesso modo si aspira alle ascensioni che costringono a un cambiamento profondo di costumi o di cultura, che portano con s\u00e8 un accrescimento di responsabilit\u00e0 e il cui fallimento viene fatalmente scontato &#8211; moralmente e materialmente &#8211; a breve scadenza.<\/p>\n<p style=\"text-align: justify;\">Non v&#8217;\u00e8 miglior freno all&#8217;invidiosit\u00e0 e allo spirito di rivolta delle masse della presenza di una \u00e9lite dirigente la cui autorit\u00e0 sia indipendente in larga misura dal denaro. Questa potenza (quella che proviene da una tradizione ereditaria o dal merito professionale) \u00e8 organica, specificata, localizzata; essa si esplica all&#8217;interno di certi quadri vitali ed \u00e8 feconda in virt\u00f9 della sua funzione propriamente umana e del suo adattamento a determinati tempi e a determinati luoghi; essa \u00e8 tutelata contro i suoi stessi abusi e la sua stessa attitudine a degenerare, da un ritmo di scambi continui con l&#8217;ambiente in cui vive e non pu\u00f2 distruggere nulla se non distruggendosi: i suoi interessi si confondono coi suoi doveri.<\/p>\n<p style=\"text-align: justify;\">La plutocrazia, invece, \u00e8 inorganica e non ha un suo ambiente specifico (un ricco \u00e8 ricco in ogni luogo); estranea all&#8217;ordine vivente della comunit\u00e0, non pu\u00f2 essere (e per di pi\u00f9 senza un freno, senza un correttivo) che un fattore di disordine e di parassitismo.<\/p>\n<p style=\"text-align: justify;\">Un sistema di paratie stagne fra le caste non \u00e8 n\u00e9 auspicabile n\u00e9 realizzabile nel nostro mondo occidentale e cristiano. Il passaggio dal popolo all&#8217;\u00e9lite deve essere possibile (altrimenti quest&#8217;ultima si estenua e degenera), ma deve essere difficile. Occorre che si elevino, da una classe all&#8217;altra e da una casta all&#8217;altra, dighe alte e robuste, in tal modo chi superer\u00e0 tali dighe sar\u00e0 veramente salito! Il tempio ove regna la classe dirigente dovrebbe portare sul suo frontone questa scritta: qui si entra salendo.<\/p>\n<p style=\"text-align: justify;\">La miseria dell&#8217;ideale sociale moderno consiste invece precisamente nello spianare le dighe e nello stabilire fra il popolo e l&#8217;\u00e9lite un piede di parit\u00e0 rovinoso. Di qui l&#8217;involgarirsi e il degenerare delle \u00e9lites: con la scomparsa di una distanza in senso verticale (e della selezione che tale distanza implica) perisce l&#8217;\u00e9lite.<\/p>\n<p style=\"text-align: justify;\">Una \u00e9lite collocata bene in alto, d&#8217;accesso difficile e rigorosa nell&#8217;accogliere, nobilita l&#8217;uomo del popolo che s&#8217;innalza fino a lei e nobilita col suo solo riverbero tutta quanta la massa popolare. Ma oggi, plebaglia in alto, plebaglia in basso, come diceva Nietzsche. Per amore del popolo e delle migliori possibilit\u00e0 che dormono in lui, importa anzitutto conservare e ricreare, al disopra di lui, un potere largamente indipendente da lui, una forza attrattiva e insieme regolatrice, capace di proteggere instancabilmente le riserve popolari di forza e di vita contro la bassezza e la cecit\u00e0 plebee. Altrimenti, questa bassezza e questa cecit\u00e0 sommergeranno tutto. Infatti il popolo porta in s\u00e8 quanto basta a tutto salvare e rigenerare, ma anche a tutto abbrutire e distruggere.<\/p>\n<p style=\"text-align: justify;\">Due correnti si incrociano nella sua anima:, una tende verso la dissoluzione e l&#8217;anarchia, e questa \u00e8 sufficiente a se stessa, l&#8217;altra \u00e8 portatrice di una ricchezza profonda, ma incompleta e come germinale, ed \u00e8 costretta senza sosta a fare appello, per realizzarsi, a un&#8217;influenza superiore. Come Barbusse, abbiamo fiducia &#8220;negli abissi del popolo&#8221;, ma a condizione che questi abissi siano rischiarati e fecondati dal di fuori, dall&#8217;alto.<\/p>\n<p style=\"text-align: justify;\">Essi possono creare ogni cosa come pure inghiottire ogni cosa. E la democrazia &#8211; e il termine stesso indica che niente \u00e8 al disopra del popolo, che il popolo \u00e8 solo &#8211; si \u00e8 troppo lungamente limitata a coltivare il lato brutale del popolo, la sua tendenza all&#8217;affogamento e all&#8217;autodistruzione. Perch\u00e9 il popolo basta a s\u00e8 per cadere, ma non per camminare.<\/p>\n<p style=\"text-align: justify;\">La soppressione delle paratie stagne \u00e8 oggi ormai acquisita e l&#8217;esistenza stessa delle classi \u00e8 minacciata. Non \u00e8 il caso n\u00e9 di lamentarcene n\u00e9 di gioirne, importa solo sapere a quali condizioni una simile societ\u00e0 pu\u00f2 restare sana. Ogni uomo pu\u00f2 ormai aspirare alle funzioni superiori. Affinch\u00e9 questa possibilit\u00e0 non sia per il popolo una ventata d&#8217;aria corrompitrice, occorrerebbe che i membri delle classi dirigenti conducessero un&#8217;esistenza assai dura e una vita in cui i doveri e i sacrifici avessero sempre pi\u00f9 il sopravvento sui privilegi, di maniera che l&#8217;uomo del popolo comprendesse chiaramente che non avrebbe niente da guadagnare dal punto di ,vista dei suoi interessi materiali a spostarsi fuori della sua classe verso l&#8217;alto. Solo cosi coloro che salissero verso le funzioni superiori salirebbero per vocazione e non per ambizione.<\/p>\n<p style=\"text-align: justify;\">Un clima ascetico \u00e8 tanto pi\u00f9 necessario alle sommit\u00e0 della gerarchia sociale quanto pi\u00f9 queste sommit\u00e0 sono accessibili al popolo. La Chiesa ha sempre pensato cos\u00ec. Essa \u00e8 aperta, in tutti i gradi della sua gerarchia, ai proletari, ma impone a quelli che aspirano alle funzioni sacerdotali un cambiamento tale di vita e sacrifici tali che la semplice attrattiva dei privilegi e degli onori non \u00e8 sufficiente (salvo nei periodi di estrema decadenza del clero) a suscitare molte false vocazioni. L&#8217;uomo del popolo, inasprito contro i suoi umili doveri di stato, pi\u00f9 facilmente brigher\u00e0 per la funzione di deputato che per quella di monaco!<\/p>\n<p style=\"text-align: justify;\">Un regime di tipo democratico non pu\u00f2 restare sano che nella misura in cui sussista, nei suoi dirigenti, uno spirito d&#8217;immolazione che ha una parentela con quello del sacerdozio, e della cavalleria. Del resto, il figlio del popolo, chiamato a guidare il popolo, ha bisogno, pi\u00f9 del principe o del nobile, di essere separato dal popolo. in virt\u00f9 della sua anima e dei suoi costumi; per far accettare al popolo la sua autorit\u00e0, occorre che egli supplisca, per merito del cambiamento profondo che s&#8217;\u00e8 operato in lui, all&#8217;ascendente spontaneo che il figlio di una casta superiore possiede.<\/p>\n<p style=\"text-align: justify;\">La Chiesa, che trae dal popolo la maggior parte dei suoi preti, sa rivestirli di solitudine e di mistero quanto basta perch\u00e9 possano guidare dall&#8217;alto la classe da cui sono usciti, con il massimo di prestigio e influenza. Vi \u00e8 democrazia e democrazia: in una societ\u00e0 come la Chiesa, il proletario esce dal popolo trasfigurato dalla vocazione della sua anima; nella maggior parte delle democrazie moderne, ne esce sfigurato dalle ambizioni del suo io. Concludiamo: un regime fondato sull&#8217;uguaglianza giuridica fra gli uomini ha bisogno d&#8217;essere incessantemente redento e purificato da un severo accrescimento delle ineguaglianze morali.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tratto da: DIAGNOSI Saggio di fisiologia sociale di Gustave Thibon E&#8217; un fatto che mai, forse, si erano notati cos\u00ec pochi scambi e tanta distanza da una classe all&#8217;altra della societ\u00e0 o fra uomini di livello culturale diverso. L&#8217;influenza umana positiva delle \u00e9lites sul popolo \u00e8 ora pressoch\u00e9 nulla. Si era creduto, tuttavia &#8211; e &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/delluguaglianza-e-del-problema-delle-classi\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":36143,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[53],"tags":[795,235,796],"class_list":["post-975","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-classi-sociali","tag-politica-2","tag-uguaglianza","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dell&#039;uguaglianza e del problema delle classi - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/delluguaglianza-e-del-problema-delle-classi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dell&#039;uguaglianza e del problema delle classi - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/delluguaglianza-e-del-problema-delle-classi\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2005-07-16T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-07-21T10:44:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/classi_sociali.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"197\" \/>\n\t<meta property=\"og:image:height\" content=\"256\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/delluguaglianza-e-del-problema-delle-classi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/delluguaglianza-e-del-problema-delle-classi\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Dell&#8217;uguaglianza e del problema delle classi\",\"datePublished\":\"2005-07-16T22:00:00+00:00\",\"dateModified\":\"2016-07-21T10:44:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/delluguaglianza-e-del-problema-delle-classi\\\/\"},\"wordCount\":1893,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/delluguaglianza-e-del-problema-delle-classi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/07\\\/classi_sociali.jpg\",\"keywords\":[\"classi sociali\",\"politica\",\"uguaglianza\"],\"articleSection\":[\"Politica\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/delluguaglianza-e-del-problema-delle-classi\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/delluguaglianza-e-del-problema-delle-classi\\\/\",\"name\":\"Dell'uguaglianza e del problema delle classi - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/delluguaglianza-e-del-problema-delle-classi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/delluguaglianza-e-del-problema-delle-classi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/07\\\/classi_sociali.jpg\",\"datePublished\":\"2005-07-16T22:00:00+00:00\",\"dateModified\":\"2016-07-21T10:44:31+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/delluguaglianza-e-del-problema-delle-classi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/delluguaglianza-e-del-problema-delle-classi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/delluguaglianza-e-del-problema-delle-classi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/07\\\/classi_sociali.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/07\\\/classi_sociali.jpg\",\"width\":197,\"height\":256},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/delluguaglianza-e-del-problema-delle-classi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dell&#8217;uguaglianza e del problema delle classi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dell'uguaglianza e del problema delle classi - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/delluguaglianza-e-del-problema-delle-classi\/","og_locale":"it_IT","og_type":"article","og_title":"Dell'uguaglianza e del problema delle classi - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/delluguaglianza-e-del-problema-delle-classi\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2005-07-16T22:00:00+00:00","article_modified_time":"2016-07-21T10:44:31+00:00","og_image":[{"width":197,"height":256,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/classi_sociali.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"9 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/delluguaglianza-e-del-problema-delle-classi\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/delluguaglianza-e-del-problema-delle-classi\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Dell&#8217;uguaglianza e del problema delle classi","datePublished":"2005-07-16T22:00:00+00:00","dateModified":"2016-07-21T10:44:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/delluguaglianza-e-del-problema-delle-classi\/"},"wordCount":1893,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/delluguaglianza-e-del-problema-delle-classi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/classi_sociali.jpg","keywords":["classi sociali","politica","uguaglianza"],"articleSection":["Politica"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/delluguaglianza-e-del-problema-delle-classi\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/delluguaglianza-e-del-problema-delle-classi\/","name":"Dell'uguaglianza e del problema delle classi - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/delluguaglianza-e-del-problema-delle-classi\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/delluguaglianza-e-del-problema-delle-classi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/classi_sociali.jpg","datePublished":"2005-07-16T22:00:00+00:00","dateModified":"2016-07-21T10:44:31+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/delluguaglianza-e-del-problema-delle-classi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/delluguaglianza-e-del-problema-delle-classi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/delluguaglianza-e-del-problema-delle-classi\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/classi_sociali.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/classi_sociali.jpg","width":197,"height":256},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/delluguaglianza-e-del-problema-delle-classi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Dell&#8217;uguaglianza e del problema delle classi"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/975","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=975"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/975\/revisions"}],"predecessor-version":[{"id":36144,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/975\/revisions\/36144"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/36143"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=975"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=975"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=975"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}