{"id":9540,"date":"2014-09-18T00:00:14","date_gmt":"2014-09-17T22:00:14","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=9540"},"modified":"2015-06-16T11:10:02","modified_gmt":"2015-06-16T09:10:02","slug":"il-neocolonialismo-cinese","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-neocolonialismo-cinese\/","title":{"rendered":"Il neocolonialismo cinese"},"content":{"rendered":"<div id=\"attachment_9543\" style=\"width: 200px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/09\/Cina-in-Africa.png\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-9543\" class=\" wp-image-9543 \" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/09\/Cina-in-Africa.png\" alt=\"Cina-in-Africa\" width=\"200\" height=\"250\" \/><\/a><p id=\"caption-attachment-9543\" class=\"wp-caption-text\">Nell\u2019immagine gli investimenti diretti della Cina in Africa (Foreign Direct Investment -FDI). Dati del 2011, fonte BloGobal, Osservatorio di Politica Internazionale.<\/p><\/div>\n<p><strong>Laogai Research Foundation<\/strong>, 24 agosto 2014<\/p>\n<p style=\"text-align: center;\"><strong>Gianni Taeshin Da Valle.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Un nuovo colonialismo vede come protagonisti gli Stati affamati di terra coltivabile<\/strong> (come la Cina anche gli stati del Medio Oriente), e grandi imprese occidentali allettate dal profitto che consegue alla produzione di carburanti biologici, o dalla speculazione sulla compra-vendita di terra.<\/p>\n<p style=\"text-align: justify;\"><strong>La Cina va a caccia di grandi terreni agricoli da coltivare in tutto il mondo<\/strong>, cos\u00ec da poter garantire che potr\u00e0 sfamare la sua popolazione anche in caso di iperinflazione e crisi dei raccolti. In Sud America, Australia e Nuova Zelanda, per\u00f2, la terra \u00e8 piuttosto cara: i governi e proprietari terrieri sono abbastanza evoluti e smaliziati da pretendere un giusto corrispettivo. Nel Sud asiatico la terra disponibile non \u00e8 poi cos\u00ec abbondante (per quanto Stati come il Vietnam e la Cambogia siano disposti a vendere di tutto pur di far entrare capitali stranieri). Perci\u00f2 le mire espansionistiche cinesi hanno trovato \u201cterreno fertile\u201d, specialmente in Africa, ricca com\u2019\u00e8, oltre che di terra estremamente prolifica, anche di petrolio e di altre materie prime.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\"><strong>I primi passi mossi dal PCC in terra d\u2019Africa<\/strong> risalgono negli anni 60,\u00a0ai tempi di Zhou Enlai: una delle prime infrastrutture realizzate dai cinesi, con 600 milioni di dollari e con pi\u00f9 di 15.000 operai cinesi, \u00e8 stata la ferrovia Tan Zam, nella prima met\u00e0 degli anni 70. Da allora la presenza della RPC in Africa \u00e8 stata sempre pi\u00f9 invadente perch\u00e9 il continente \u00e8 una risorsa strategica fondamentale per la Cina: nessuna invasione \u00e8 stata cos\u00ec tollerante, nascosta e ignorata come quella che la Repubblica Popolare sta portando avanti in Africa.<\/p>\n<p style=\"text-align: justify;\">Tra l\u2019altro il Continente Nero \u00e8 un vastissimo mercato per merci a basso costo: \u00e8 molto facile trovare giocattoli. Utensili da lavoro, mobili, casalinghi o medicinali che non vengano dalla Cina. Ci\u00f2 accade spesso anche in Europa, ma mentre qui da noi sono richiesti determinati standard di igiene e sicurezza, e le forze dell\u2019ordine si impegnano, per quel che possono, per la tutela dei consumatori,<b> <\/b>in Africa il prezzo \u00e8 il solo criterio che conta<b>: <\/b>le autorit\u00e0 non si preoccupano di igiene, sicurezza, biodegradabilit\u00e0 o altro e perci\u00f2 la Cina pu\u00f2 esportare in Africa i suoi prodotti di qualit\u00e0 infima.<\/p>\n<p style=\"text-align: justify;\">Un ministro della Sierra Leone disse una volta: \u201cSe si chiede a uno dei paesi del G7 di realizzare una infrastruttura come una strada, una diga o un ponte, questi partir\u00e0 da uno studio di impatto ambientale, per poi effettuare uno studio di fattibilit\u00e0 e passare via via alla bozza di progetto, al progetto definitivi, al coinvolgimento delle comunit\u00e0 locali, alle procedure anticorruzione, le gare, l\u2019analisi delle offerte, l\u2019assegnazione dei contratti e, finalmente, potr\u00e0 dare inizio ai lavori\u201d.<\/p>\n<p style=\"text-align: justify;\">Se chiedete lo stesso lavoro ai cinesi, costoro inizieranno i lavori un mese dopo, finendoli in sei mesi, con manodopera, macchinari, materie prime e qualsiasi altra cosa provenienti dalla Cina. Molti stati africani, inoltre, sono governati da tiranni o da governi di pochi, privi di scrupoli. Sono ben disposti perci\u00f2 a collaborare con la dittatura del PCC.<\/p>\n<p style=\"text-align: justify;\">Per esempio<b>, <\/b>il veto della Cina nel Consiglio di Sicurezza delle Nazioni Unite ha impedito la condanna delle atrocit\u00e0 e del genocidio che si era consumato nel Darfur. <em>I<\/em>l conflitto, iniziato nel febbraio del 2003, vede contrapposti i Janiawid (letteralmente \u201cdemoni a cavallo\u201d), un gruppo di miliziani arabi reclutati fra i membri delle locali tirib\u00f9 dei Baggara, e la popolazione non Baggara della regione (principalmente composta da trib\u00f9 dedite all\u2019agricoltura). Il governo sudanese, pur negando ufficialmente di sostenere i Janjawid, ha fornito loro armi e assistenza e ha partecipato ad attacchi congiunti rivolti sistematicamente contro i gruppi etnici Fur, Zaghawa e Masalit.<\/p>\n<p style=\"text-align: justify;\">Le stime delle vittime del conflitto variano a seconda delle fonti da 50.000 (Organizzazione Mondiale della Sanit\u00e0, settembre 2004) alle 450.000 (secondo Eric Reeves, 28 aprile 2006). La maggior parte delle ONG reputa credibile la cifra di 400.000 morti fornita dalla Coalition for International Justice e da allora sempre citata dalle Nazioni Unite. I mass media hanno utilizzato, per definire il conflitto, sia i termini di \u201cpulizia etnica\u201d sia quello di \u201cgenocidio\u201d. Il Governo degli Stati Uniti ha usato il termine genocidio, non cos\u00ec le Nazioni Unite.<\/p>\n<p style=\"text-align: justify;\">Diversi stati africani hanno appoggiato a loro volta le posizioni della Cina nell\u2019assemblea Generale dell\u2019ONU: \u00e8 anche grazie ad essi che la Cina ha potuto bloccare l\u2019ingresso a Taiwan nell\u2019Organizzazione Mondiale della Sanit\u00e0<b>, <\/b>ha evitato numerose condanne da parte della Commissione del\u2019ONU per i diritti umani, ha ottenuto l\u2019assegnazione delle Olimpiadi nel 2008 e dell\u2019Expo nel 2010.<\/p>\n<p style=\"text-align: justify;\"><strong>I prestiti occidentali sono di solito condizionati alla politica dei governi africani<\/strong>. Per ottenerli essi devono mostrare una particolare attenzione ai bisogni della popolazione, predisporre un programma di politiche economiche volte allo sviluppo e all\u2019attuazione dei principi generali della democrazia.<\/p>\n<p style=\"text-align: justify;\">I prestiti cinesi invece vengono erogati senza condizioni politiche, finanziano progetti di sviluppo che per\u00f2 devono essere appaltati , da almeno il 70% a imprese cinesi. Queste, poi, di solito utilizzano mano d\u2019opera importata dalla madrepatria , persino detenuti dei Laogai e vengono realizzati senza alcun riguardo per le persone e l\u2019ambiente. Pechino, infatti, in Africa esporta anche manodopera: decine di migliaia di agricoltori.<\/p>\n<p style=\"text-align: justify;\">Liu Jianjiun, della camera di commercio sino-africana ha creato un sistema di villaggi , ribattezzati<b> <\/b>\u201cvillaggi Baoding\u201d dal nome della cittadina dell\u2019Hebei nella quale vive, dove gli immigrati cinesi si concentrano. Pare che risiedano<b> <\/b>o finora abbiano risieduto in Africa quasi un milione di cinesi gi\u00e0 residenti, di cui 10mila sono i contadini dell\u2019Hebei spediti in diciotto Paesi diversi. In Sud Africa sarebbero 20mila i cinesi gi\u00e0 residenti, in Algeria ne risultavano 19mila nel 2007.<\/p>\n<p style=\"text-align: justify;\">Il lavoro offerto dalle ditte cinesi agli africani \u00e8 solo in fondo alle miniere, i dirigenti sono tutti cinesi<b>,<\/b> come pure buona parte dei <strong>tecnici<\/strong><b>. <\/b>I molti infortunati sul lavoro, invece, non sempre sono risarciti.<\/p>\n<p style=\"text-align: justify;\"><strong>Lavoratori e cittadini protestano che i \u201cpotenti stranieri\u201d fanno come vogliono, impongono loro le leggi<\/strong>, i diritti umani e dei lavoratori sono un intralcio in patria, figuriamoci in un altro continente; e allora con i dittatori si fanno affari senza problemi di sorta, vanificando il pur minimo effetto (troppo fioche) voci che da Occidente raramente si alzano contro i tiranni grandi e piccoli, da Mughe, ad Al Bashir, a Dos santos, che ancora infestano l\u2019Africa.<\/p>\n<p style=\"text-align: justify;\">_________________<\/p>\n<p style=\"text-align: justify;\"><b>Nota<\/b><\/p>\n<p style=\"text-align: justify;\">(*) Il Gruppo dei Sette (di solito abbreviato in<b> <\/b>G7) \u00e8 il vertice dei ministri dell\u2019economia delle sette nazioni sviluppate con la ricchezza netta pi\u00f9 grande al mondo (Canada, Francia, Germania,Giappone Italia, Regno Unito, e Stati Uniti) . Dal 1997 \u00e8 stato affiancato dal G8, la Russia per motivi prettamente politici)<\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>Laogai Research Foundation, 24 agosto 2014 Gianni Taeshin Da Valle. Un nuovo colonialismo vede come protagonisti gli Stati affamati di terra coltivabile (come la Cina anche gli stati del Medio Oriente), e grandi imprese occidentali allettate dal profitto che consegue alla produzione di carburanti biologici, o dalla speculazione sulla compra-vendita di terra. La Cina va &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-neocolonialismo-cinese\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":9543,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[39,56,108],"tags":[2393,2395],"class_list":["post-9540","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-africa","category-cina","category-paesi-e-continenti","tag-africa","tag-cina","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il neocolonialismo cinese - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-neocolonialismo-cinese\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il neocolonialismo cinese - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-neocolonialismo-cinese\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2014-09-17T22:00:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-06-16T09:10:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/09\/Cina-in-Africa.png\" \/>\n\t<meta property=\"og:image:width\" content=\"240\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-neocolonialismo-cinese\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-neocolonialismo-cinese\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Il neocolonialismo cinese\",\"datePublished\":\"2014-09-17T22:00:14+00:00\",\"dateModified\":\"2015-06-16T09:10:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-neocolonialismo-cinese\\\/\"},\"wordCount\":1105,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-neocolonialismo-cinese\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/09\\\/Cina-in-Africa.png\",\"keywords\":[\"Africa\",\"Cina\"],\"articleSection\":[\"Africa\",\"Cina\",\"Paesi e continenti\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-neocolonialismo-cinese\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-neocolonialismo-cinese\\\/\",\"name\":\"Il neocolonialismo cinese - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-neocolonialismo-cinese\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-neocolonialismo-cinese\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/09\\\/Cina-in-Africa.png\",\"datePublished\":\"2014-09-17T22:00:14+00:00\",\"dateModified\":\"2015-06-16T09:10:02+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-neocolonialismo-cinese\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-neocolonialismo-cinese\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-neocolonialismo-cinese\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/09\\\/Cina-in-Africa.png\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/09\\\/Cina-in-Africa.png\",\"width\":240,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-neocolonialismo-cinese\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il neocolonialismo cinese\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il neocolonialismo cinese - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-neocolonialismo-cinese\/","og_locale":"it_IT","og_type":"article","og_title":"Il neocolonialismo cinese - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-neocolonialismo-cinese\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2014-09-17T22:00:14+00:00","article_modified_time":"2015-06-16T09:10:02+00:00","og_image":[{"width":240,"height":300,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/09\/Cina-in-Africa.png","type":"image\/png"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-neocolonialismo-cinese\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-neocolonialismo-cinese\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Il neocolonialismo cinese","datePublished":"2014-09-17T22:00:14+00:00","dateModified":"2015-06-16T09:10:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-neocolonialismo-cinese\/"},"wordCount":1105,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-neocolonialismo-cinese\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/09\/Cina-in-Africa.png","keywords":["Africa","Cina"],"articleSection":["Africa","Cina","Paesi e continenti"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-neocolonialismo-cinese\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-neocolonialismo-cinese\/","name":"Il neocolonialismo cinese - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-neocolonialismo-cinese\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-neocolonialismo-cinese\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/09\/Cina-in-Africa.png","datePublished":"2014-09-17T22:00:14+00:00","dateModified":"2015-06-16T09:10:02+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-neocolonialismo-cinese\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-neocolonialismo-cinese\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-neocolonialismo-cinese\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/09\/Cina-in-Africa.png","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/09\/Cina-in-Africa.png","width":240,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-neocolonialismo-cinese\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Il neocolonialismo cinese"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/9540","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=9540"}],"version-history":[{"count":3,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/9540\/revisions"}],"predecessor-version":[{"id":26346,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/9540\/revisions\/26346"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/9543"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=9540"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=9540"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=9540"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}