{"id":949,"date":"2005-07-17T00:00:00","date_gmt":"2005-07-16T22:00:00","guid":{"rendered":""},"modified":"2015-11-26T15:31:54","modified_gmt":"2015-11-26T14:31:54","slug":"carl-gustav-jung-1875-1961","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/carl-gustav-jung-1875-1961\/","title":{"rendered":"Carl Gustav Jung (1875-1961)"},"content":{"rendered":"<p align=\"center\">I.D.I.S. &#8211; Istituto per la Dottrina e l&#8217;Informazione Sociale<\/p>\n<p align=\"center\"><strong>Voci per un Dizionario del Pensiero Forte<\/strong><\/p>\n<p align=\"center\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/Carl-Gustav-Jung.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-28109\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/Carl-Gustav-Jung.jpg\" alt=\"Carl Gustav Jung\" width=\"250\" height=\"200\" \/><\/a><\/p>\n<p align=\"center\">di<b><i> <\/i>Ermanno Pavesi<\/b><\/p>\n<p><!--more--><strong>1. La vita<\/strong><\/p>\n<p style=\"text-align: justify;\">Carl Gustav Jung nasce il 26 luglio 1875 in un piccolo paese sulla costa svizzera del lago di Costanza, Kesswil, dove il padre era pastore protestante. Studia medicina a Basilea, si laurea nel 1900 e nello stesso anno diventa assistente alla clinica psichiatrica dell\u2019universit\u00e0 di Zurigo, distinguendosi con le sue ricerche anche a livello internazionale.<\/p>\n<p style=\"text-align: justify;\">Nel 1907 Jung incontra Sigmund Freud (1859-1939), ne diventa stretto collaboratore, venendo cos\u00ec a costistituire il primo contatto fra psicoanalisi e ambienti universitari. Nel 1909 rinuncia alla carriera accademica per dedicarsi totalmente alla ricerca psicologica; due anni dopo viene nominato presidente della Societ\u00e0 psicoanalitica internazionale, ma la pubblicazione, nel 1912, della prima edizione dell\u2019opera <i>Simboli della trasformazione<\/i>, nella quale formula una teoria della <i>libido<\/i> che si discosta da quella psicoanalitica, lo porta alla rottura con Freud e all\u2019elaborazione di un proprio sistema: la psicologia analitica.<\/p>\n<p style=\"text-align: justify;\">Lo psichiatra svizzero raccoglie attorno a s\u00e9 un gruppo inizialmente sparuto di collaboratori con i quali, nel 1916, costituisce il Club Psicologico di Zurigo. Dal 1933 al 1942 \u00e8 docente al Politecnico federale di quella citt\u00e0 e dal 1944 al 1945 all\u2019universit\u00e0 di Basilea. Allo scopo di organizzare l\u2019insegnamento e la ricerca della psicologia analitica, nel 1948 a K\u00fcsnacht, cittadina a pochi chilometri da Zurigo, sul lago omonimo, viene fondato l\u2019Istituto Carl Gustav Jung. E a K\u00fcsnacht Jung muore il 6 giugno 1961.<\/p>\n<p style=\"text-align: justify;\"><strong>2. La formazione<\/strong><\/p>\n<p style=\"text-align: justify;\">Nell\u2019autobiografia &#8211; <i>Ricordi, Sogni, Riflessioni<\/i>, pubblicata nel 1961 &#8211; lo psichiatra svizzero ricorda di aver provato un precoce interesse per le questioni esistenziali e religiose e di essersi appassionato, all\u2019universit\u00e0, ai temi dell\u2019irrazionale, trattati da vari autori romantici tedeschi come Carl Gustav Carus (1789-1869), e allo spiritismo: <i>&#8220;<\/i>[&#8230;]<i> per quanto bizzarre e discutibili mi sembrassero le osservazioni degli spiritisti, furono la prima testimonianza che avessi mai avuto di fenomeni psichici obiettivi. <\/i>[&#8230;]<i> virtualmente lessi tutta la letteratura sull\u2019argomento allora reperibile <\/i>[&#8230;]<i> e lessi sette volumi di Swedenborg <\/i>[Emanuel, 1688-1772]<i>&#8220;<\/i>.<\/p>\n<p style=\"text-align: justify;\">In questi anni partecipa a sedute spiritiche, raccogliendo esperienze che successivamente utilizza nella tesi di laurea, <i>Psicologia e patologia dei cosiddetti fenomeni occulti<\/i>, del 1902. L\u2019approfondimento della psicoanalisi costituisce una svolta fondamentale, consentendogli d\u2019inquadrare in modo nuovo i fenomeni paranormali ai quali s\u2019interessa.<\/p>\n<p style=\"text-align: justify;\">Nella prefazione all\u2019opera <i>La psicoanalisi<\/i> di Wolfgang M\u00fcller Kranefeldt (1892- 1974), del 1930, Jung postula l\u2019esistenza di un filone che va dall\u2019alchimia fino al magnetismo animale, alla filosofia romantica e alla psicoanalisi, considerata come la forma pi\u00f9 moderna di psicologia: <i>&#8220;Un giorno apparir\u00e0 chiaramente per quali tortuosi sentieri la psicologia moderna e modernissima abbia trovato la strada che l\u2019ha condotta fuori dagli oscuri laboratori alchimistici, attraverso gli stadi intermedi del mesmerismo e del magnetismo <\/i>[&#8230;]<i> verso le anticipazioni filosofiche di Schopenhauer <\/i>[Arthur, 1788-1860]<i>, di Carus e Hartmann <\/i>[Eduard von, 1842-1906]<i>, e come, dall\u2019oscuro terreno materno delle esperienze pratiche quotidiane di un Li\u00e9beault <\/i>[Auguste Ambroise, 1823-1904] <i>e dell\u2019ancor pi\u00f9 vecchio <\/i>Quimby<i> <\/i>[Phineas Parkhurst, 1802-1866] <i>(il padre spirituale della Christian Science) attraverso le teorie sull\u2019ipnosi della scuola francese, sia giunta a Freud&#8221;<\/i>.<\/p>\n<p style=\"text-align: justify;\">Jung critica la pretesa di Freud di costruire una teoria dell\u2019inconscio e della psiche partendo dalla patologia psichica in quanto, come afferma nell\u2019edizione definitiva dell\u2019opera <i>Simboli della trasformazione<\/i>, del 1952, <i>&#8220;un po\u2019 di patologia e di teoria delle nevrosi non bastano assolutamente in questo caso; questo tipo di conoscenze mediche consente unicamente d\u2019essere informati su una malattia, ma ignora tutto dell\u2019anima che \u00e8 malata&#8221;<\/i>.<\/p>\n<p style=\"text-align: justify;\">Jung invece \u00e8 attratto dalla complessit\u00e0 della psiche umana e dalle sue profondit\u00e0 misteriose. Gi\u00e0 nella tesi di laurea sottolinea la sorprendente somiglianza fra il sistema descritto in <i>trance<\/i> da una <i>medium<\/i> e alcuni sistemi gnostici dell\u2019antichit\u00e0. Se Freud interpreta la religione come una nevrosi, Jung constata l\u2019esistenza di somiglianze fra il materiale prodotto da pazienti e i temi della mitologia e cerca di cogliere l\u2019elemento profondamente esistenziale, e in ultima analisi religioso, dei disturbi psichici.<\/p>\n<p style=\"text-align: justify;\">Nel corso degli anni si dedica allo studio dello gnosticismo, dell\u2019alchimia e della mitologia di popoli antichi e primitivi, considerati come proiezioni molteplici degli archetipi, cio\u00e8 dei contenuti inconsci comuni a tutta l\u2019umanit\u00e0.<\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"font-size: 12px;\">3. Inconscio collettivo e archetipi<\/span><\/strong><\/p>\n<p style=\"text-align: justify;\">La psicologia analitica formula una teoria dell\u2019inconscio pi\u00f9 complessa di quella psicoanalitica.<\/p>\n<p style=\"text-align: justify;\">Nel volume <i>La struttura della psiche<\/i>, del 1931, Jung distingue <i>&#8220;<\/i>[&#8230;]<i> nella psiche tre strati: 1) la <\/i>coscienza<i>; 2) l\u2019<\/i>inconscio personale<i> <\/i>[&#8230;]<i>; 3) l\u2019<\/i>inconscio collettivo<i>, che \u00e8 un patrimonio ereditario di possibilit\u00e0 rappresentative non individuale, ma comune a tutti gli uomini e forse a tutti gli animali, e costituisce la vera e propria base della psiche individuale&#8221;<\/i>.<\/p>\n<p style=\"text-align: justify;\">Nel volume <i>Istinto e inconscio<\/i>, del 1919, egli descrive l\u2019inconscio collettivo come la somma degl\u2019istinti, cio\u00e8 delle <i>&#8220;forme tipiche dell\u2019agire&#8221;<\/i> e degli archetipi, <i>&#8220;forme tipiche della comprensione&#8221;<\/i>: gl\u2019istinti determinano le costanti del comportamento, e le singole conoscenze vengono inquadrate sulla base di forme preesistenti.<\/p>\n<p style=\"text-align: justify;\">Per esempio, Jung ritiene che il modo con cui ogni individuo vive il rapporto con la madre dipenda da un archetipo inconscio, quello della <i>&#8220;grande madre&#8221;<\/i>. Gli archetipi non sono di natura spirituale, ma forme immanenti alla materia in cui si sono sviluppati nel corso prima dell\u2019evoluzione e poi della storia, e sono contenuti nel patrimonio genetico dell\u2019uomo: <i>&#8220;A mio parere <\/i>&#8211; sostiene nel volume <i>Psicologia dell\u2019inconscio<\/i>, del 1943 &#8211; <i>la loro origine non \u00e8 spiegabile se non supponendo che sono sedimenti di esperienze sempre ripetute dall\u2019umanit\u00e0&#8221;<\/i>.<\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"font-size: 12px;\">4. La teoria della persona<\/span><\/strong><\/p>\n<p style=\"text-align: justify;\">Per la psicologia analitica non esiste un\u2019anima individuale: gli elementi individuali dell\u2019anima sono effimeri e perituri, mentre la parte impersonale della psiche mette in rapporto il singolo con un\u2019anima unica, comune non solo agli uomini ma anche alla natura: <i>&#8220;L\u2019anima non \u00e8 di oggi!<\/i> &#8211; si legge in <i>Simboli della trasformazione<\/i> &#8211; <i>Essa conta molti milioni di anni. Ma la coscienza individuale \u00e8 solo il fiore e il frutto di una stagione, germogliato dal perenne rizoma sotterraneo&#8221;<\/i>. Nel volume <i>Il problema psichico dell\u2019uomo moderno<\/i>, del 1931, Jung riprende anche alcune teorie del teosofo svedese Swedenborg: <i>&#8220;In un certo modo noi siamo parte di una grande anima unitaria, o, per esprimerci con Swedenborg, di un unico, immenso essere umano&#8221;<\/i>.<\/p>\n<p style=\"text-align: justify;\">La dimensione personale dell\u2019uomo non viene considerata autonoma e reale, ma artificiale, una specie d\u2019interfaccia fra l\u2019inconscio collettivo e la societ\u00e0, un ruolo che la societ\u00e0 impone all\u2019individuo, una maschera che consente di manifestare alcuni contenuti dell\u2019inconscio collettivo, ma che ne cela la maggior parte.<\/p>\n<p style=\"text-align: justify;\">L\u2019identificazione con una determinata personalit\u00e0 risulta limitativa e riduttiva, impedisce la completa autorealizzazione e causa conflitti, in quanto porterebbe a una certa polarizzazione fra i contenuti inconsci accettabili e quelli invece inconciliabili con i princ\u00ecpi della societ\u00e0 e destinati a rimanere inconsci, formando &#8211; secondo un\u2019espressione junghiana &#8211; l\u2019<i>&#8220;ombra&#8221;<\/i> della personalit\u00e0 cosciente. Uno degli scopi della terapia consiste nel superamento di tale unilateralit\u00e0 e della pretesa di raggiungere la perfezione, cercando piuttosto la completezza attraverso l\u2019integrazione dell\u2019<i>&#8220;ombra&#8221;<\/i>.<\/p>\n<p style=\"text-align: justify;\"><b style=\"font-size: 12px;\">5. La religione<\/b><\/p>\n<p style=\"text-align: justify;\"><b style=\"font-size: 12px;\"><\/b>La psicologia analitica, da un lato, ha grande considerazione per la religione, considerata come espressione e formulazione di archetipi, e riconosce l\u2019importanza dei riti religiosi, che consentirebbero a tutti, indipendentemente dalle loro capacit\u00e0, di vivere certi archetipi; dall\u2019altra parte, per\u00f2, \u00e8 critica nei confronti delle forme religiose istituzionalizzate, quando contrastano la realizzazione degli archetipi.<\/p>\n<p style=\"text-align: justify;\">La critica pi\u00f9 severa riguarda per\u00f2 le pretese metafisiche delle religioni: per Jung l\u2019esperienza religiosa \u00e8 di natura psichica, una ierofania, all\u2019interno della psiche, di archetipi e di potenze esterne all\u2019Io cosciente ma intrapsichiche. Nel volume <i>Psicologia e religione<\/i>, del 1940, egli considera la fede nell\u2019esistenza reale di esseri spirituali solo come proiezione all\u2019esterno di potenze interiori di natura meramente psicologica: <i>&#8220;<\/i>[&#8230;]<i> non pu\u00f2 neppure essere sostenuta una dottrina della deit\u00e0 nel senso di un\u2019esistenza non psicologica&#8221;<\/i>.<\/p>\n<p style=\"text-align: justify;\">Questo vale anche per l\u2019esistenza di Dio: nel saggio <i>Die Psychologie der unbewussten Prozesse<\/i>, &#8220;La psicologia dei processi inconsci&#8221;, del 1917, Jung aveva definito il problema dell\u2019esistenza di Dio addirittura come <i>&#8220;<\/i>[&#8230;]<i> uno dei problemi pi\u00f9 stupidi che ci si possa porre&#8221;<\/i>. La psicologia analitica pu\u00f2 solo dimostrare la presenza di un\u2019immagine archetipica della divinit\u00e0 nell\u2019inconscio.<\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"font-size: 12px;\">6. Cristianesimo ed Era dell\u2019Acquario<\/span><\/strong><\/p>\n<p style=\"text-align: justify;\">Jung sottolinea che l\u2019inizio dell\u2019evo cristiano corrisponde pressappoco all\u2019inizio dell\u2019astrologica Era dei Pesci, della durata di circa duemila anni, che sar\u00e0 seguita dall\u2019Era dell\u2019Acquario. L\u2019Era dei Pesci sarebbe contraddistinta dalla contrapposizione fra due princ\u00ecpi differenti, apparentemente inconciliabili: bene e male, Cristo e Satana, mentre l\u2019Era dell\u2019Acquario sarebbe caratterizzata dal superamento delle contrapposizioni, dalla loro sintesi e quindi anche dall\u2019ineluttabile declino del cristianesimo.<\/p>\n<p style=\"text-align: justify;\">Nell\u2019Occidente cristiano la polarizzazione dell\u2019Era dei Pesci avrebbe portato alla rimozione nell\u2019inconscio, del singolo ma anche dei popoli, di contenuti non conciliabili con il cristianesimo, formando un\u2019<i>&#8220;ombra&#8221;<\/i> pagana e anticristiana. Ma con l\u2019avvicinarsi della nuova era diminuirebbe progressivamente la capacit\u00e0 della civilt\u00e0 cristiana di tener repressi elementi pagani, che tendono a emergere con forza sempre maggiore nella coscienza del singolo e dei popoli gi\u00e0 cristianizzati. Nella fase di passaggio all\u2019Era dell\u2019Acquario Jung ritiene necessario prestare attenzione a questi contenuti emergenti e cercare di integrarli nella vita cosciente.<\/p>\n<p style=\"text-align: justify;\">Con questo schema egli interpreta anche i fenomeni politici del tempo, individuando gli albori della nuova era nell\u2019affermazione del neopaganesimo nazionalsocialista nella Germania degli anni 1930.<\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"font-size: 12px;\">7. Conclusione<\/span><\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12px;\">La psicologia analitica di Jung si distingue nettamente dalla psicoanalisi per il suo atteggiamento positivo nei confronti della religione, grazie al quale ha conquistato molte simpatie in ambienti religiosi. Infatti l\u2019affermazione dell\u2019esistenza, anche se solamente psicologica, di certi archetipi religiosi pu\u00f2 costituire la base per un dialogo interdisciplinare, perch\u00e9 lo studio comparato di diverse forme di spiritualit\u00e0 offre spunti stimolanti, ma non si deve dimenticare che Jung considera la metafisica unicamente come una proiezione e professa una religiosit\u00e0 immanentistica.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12px;\"> Il tentativo di fondare il suo sistema sull\u2019esperienza religiosa personale, indipendentemente da codificazioni teologiche, corrisponde a certe esigenze della cultura del secolo XX e non stupisce il fatto che egli rappresenti uno degli autori pi\u00f9 apprezzati nell\u2019ambito della nuova religiosit\u00e0 del New Age.<\/span><\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"font-size: 12px;\">Per approfondire:\u00a0<\/span><\/strong>la ricca produzione pubblicistica dello psichiatra svizzero \u00e8 raccolta nei diciotto volumi delle <i>Opere di C. G. Jung<\/i>, trad. it., Boringhieri, Torino 1969-1991; su di lui vedi anche <i>Ricordi, sogni, riflessioni di C. G. Jung<\/i>, raccolti ed editi da Aniela Jaff\u00e9, trad. it., Biblioteca Universale Rizzoli, Milano 1997; e Jolande Jacobi (1890-1983), <i>La psicologia di Carl Gustav Jung<\/i>, trad. it., Bollati Boringhieri, Torino 1997.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I.D.I.S. &#8211; Istituto per la Dottrina e l&#8217;Informazione Sociale Voci per un Dizionario del Pensiero Forte di Ermanno Pavesi<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/carl-gustav-jung-1875-1961\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":28109,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18,105],"tags":[816,815],"class_list":["post-949","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-personaggi","category-psichiatria-e-psicanalisi","tag-c-gustav-jung","tag-psicanalisi","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Carl Gustav Jung (1875-1961) - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/carl-gustav-jung-1875-1961\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carl Gustav Jung (1875-1961) - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/carl-gustav-jung-1875-1961\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2005-07-16T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-11-26T14:31:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/Carl-Gustav-Jung.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"251\" \/>\n\t<meta property=\"og:image:height\" content=\"201\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/carl-gustav-jung-1875-1961\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/carl-gustav-jung-1875-1961\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Carl Gustav Jung (1875-1961)\",\"datePublished\":\"2005-07-16T22:00:00+00:00\",\"dateModified\":\"2015-11-26T14:31:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/carl-gustav-jung-1875-1961\\\/\"},\"wordCount\":1742,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/carl-gustav-jung-1875-1961\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/07\\\/Carl-Gustav-Jung.jpg\",\"keywords\":[\"C. Gustav Jung\",\"psicanalisi\"],\"articleSection\":[\"Personaggi\",\"Psichiatria\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/carl-gustav-jung-1875-1961\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/carl-gustav-jung-1875-1961\\\/\",\"name\":\"Carl Gustav Jung (1875-1961) - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/carl-gustav-jung-1875-1961\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/carl-gustav-jung-1875-1961\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/07\\\/Carl-Gustav-Jung.jpg\",\"datePublished\":\"2005-07-16T22:00:00+00:00\",\"dateModified\":\"2015-11-26T14:31:54+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/carl-gustav-jung-1875-1961\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/carl-gustav-jung-1875-1961\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/carl-gustav-jung-1875-1961\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/07\\\/Carl-Gustav-Jung.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/07\\\/Carl-Gustav-Jung.jpg\",\"width\":251,\"height\":201},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/carl-gustav-jung-1875-1961\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Carl Gustav Jung (1875-1961)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Carl Gustav Jung (1875-1961) - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/carl-gustav-jung-1875-1961\/","og_locale":"it_IT","og_type":"article","og_title":"Carl Gustav Jung (1875-1961) - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/carl-gustav-jung-1875-1961\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2005-07-16T22:00:00+00:00","article_modified_time":"2015-11-26T14:31:54+00:00","og_image":[{"width":251,"height":201,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/Carl-Gustav-Jung.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"9 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/carl-gustav-jung-1875-1961\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/carl-gustav-jung-1875-1961\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Carl Gustav Jung (1875-1961)","datePublished":"2005-07-16T22:00:00+00:00","dateModified":"2015-11-26T14:31:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/carl-gustav-jung-1875-1961\/"},"wordCount":1742,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/carl-gustav-jung-1875-1961\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/Carl-Gustav-Jung.jpg","keywords":["C. Gustav Jung","psicanalisi"],"articleSection":["Personaggi","Psichiatria"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/carl-gustav-jung-1875-1961\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/carl-gustav-jung-1875-1961\/","name":"Carl Gustav Jung (1875-1961) - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/carl-gustav-jung-1875-1961\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/carl-gustav-jung-1875-1961\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/Carl-Gustav-Jung.jpg","datePublished":"2005-07-16T22:00:00+00:00","dateModified":"2015-11-26T14:31:54+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/carl-gustav-jung-1875-1961\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/carl-gustav-jung-1875-1961\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/carl-gustav-jung-1875-1961\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/Carl-Gustav-Jung.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/Carl-Gustav-Jung.jpg","width":251,"height":201},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/carl-gustav-jung-1875-1961\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Carl Gustav Jung (1875-1961)"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/949","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=949"}],"version-history":[{"count":3,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/949\/revisions"}],"predecessor-version":[{"id":28110,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/949\/revisions\/28110"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/28109"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=949"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=949"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=949"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}