{"id":9472,"date":"2014-09-11T00:00:04","date_gmt":"2014-09-10T22:00:04","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=9472"},"modified":"2014-08-27T11:02:37","modified_gmt":"2014-08-27T09:02:37","slug":"iraq-era-meglio-saddam","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/iraq-era-meglio-saddam\/","title":{"rendered":"Iraq: era meglio Saddam?"},"content":{"rendered":"<p style=\"text-align: center;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/08\/sciiti-massacre.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-9474 alignright\" alt=\"sciiti massacre\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/08\/sciiti-massacre.jpg\" width=\"250\" height=\"134\" \/><\/a>Studi Cattolici<\/strong><\/p>\n<p style=\"text-align: center;\">n.641\/42 luglio-agosto 2014<\/p>\n<p style=\"text-align: justify;\"><em><span style=\"font-size: 12px;\">Riprendiamo da <\/span><\/em>Il Foglio<em><span style=\"font-size: 12px;\"> d<\/span><span style=\"font-size: 12px;\">el 3 luglio 2014 questa illuminante ricostruzione delle guerre di religione fra arabi che stanno insanguinando il Medioriente, con milioni di morti.<\/span><\/em><\/p>\n<p style=\"text-align: center;\">di <strong>Carlo Panella<\/strong><\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Sciiti e sunniti si massacrano in Iraq per colpa e responsabilit\u00e0 di George W. Bush e della sua \u00abdissennata guerra\u00bb? A ogni crisi irachena ci viene propinata questa verit\u00e0 indiscutibile: se Saddam Hussein fosse ancora al potere col suo pugno di ferro, sciiti e sunniti iracheni sarebbero in pace. Questa sciocchezza ribadita da un coro unanime &#8211; uniche eccezioni Tony Blair e pochi altri saggi &#8211; \u00e8 il metro perfetto dell&#8217;incultura che permea l&#8217;Occidente, sintomo della sua falsa coscienza, quasi che bere pozioni che obnubilano la memoria, anche dei fatti pi\u00f9 recenti, possa dare serenit\u00e0 a un Occidente che si sente vivo solo quando trova il modo di vergognarsi di s\u00e9 stesso. Non \u00e8 cos\u00ec. E a chi sostiene che sciiti e sunniti si stanno massacrando in Iraq e Siria solo a causa della caduta di Saddam Hussein vanno ricordate alcune verit\u00e0 storiche.<\/p>\n<p style=\"text-align: justify;\">La prima &#8211; lontana ma fondante &#8211; \u00e8 che nel 1744, mentre in Europa si affermava l&#8217;illuminismo e si strutturava la modernit\u00e0, prodromi delle grandi rivoluzioni democratiche, nasceva e si affermava nell&#8217;isl\u00e0m uno scisma oscurantista, il <i>wahabismo<\/i> salafita della casa dei Saud, che aveva nell&#8217;eliminazione fisica degli sciiti la propria principale vocazione. La motivazione di questa prassi wahabita \u00e8 semplice nella rozza teologia di Muhammed al Wahab: gli sciiti accostano al culto di Allah quello dei 12 Imam di cui venerano i santuari. Quindi sono politeisti, idolatri, traditori della fede nell&#8217;unico Dio. Sono \u00abfalsi musulmani che diffondono corruzione sulla terra\u00bb. Vanno spazzati via.<\/p>\n<p style=\"text-align: justify;\"><b>Soldati sciiti massacrati a freddo<\/b><\/p>\n<p style=\"text-align: justify;\">Oggi, quando il wahabita Abu Bakr al Baghdadi, il leader dell&#8217;Isis che assedia Baghdad e massacra a freddo soldati sciiti, promette che \u00abmetter\u00e0 a ferro e fuoco\u00bb le citt\u00e0 sante sciite di Kerbala e Najaf, ripropone l&#8217;obiettivo della distruzione e del saccheggio di quei santuari gi\u00e0 messo a segno nel lontano 1802 dal wahabita re Abdulaziz ibn Saud (morto poi per mano di un sicario sciita).<\/p>\n<p style=\"text-align: justify;\">Da allora la vicenda della regione \u00e8 costellata di scannamenti tra sunniti e sciiti, obbligati nel 1925 da un altro Abdulaziz ibn Saud a pagare la Jiza, la tassa di sottomissione imposta a ebrei e cristiani, a chi non \u00e8 musulmano. Questo \u00e8 l&#8217;indispensabile punto di riferimento per mettere a fuoco le ragioni profonde dello sterminio reciproco a cui assistiamo dal 1979 in poi.<\/p>\n<p style=\"text-align: justify;\">Gli scannamenti brutali tra sciiti e sunniti riprendono con forza dopo la vittoria nel 1979 della rivoluzione sciita di Khomeini in Iran, che contesta la custodia dei luoghi santi da parte dei Saud wahabiti e che \u00e8 specularmente vissuta dai wahabiti come la minacciosa affermazione di un&#8217;idolatria nel corpo dell&#8217;isl\u00e0m. Centinaia sono i morti degli scontri tra pellegrini sciiti e sunniti alla Mecca nel corso degli <i>Haji <\/i>dei primi anni &#8217;80.<\/p>\n<p style=\"text-align: justify;\">Negli stessi anni Riad manda 25 mila uomini della Guardia nazionale per schiacciare la rivolta degli operai del petrolio sciiti nella regione di Hasa. Centinaia di morti conta la rivolta sciita nel Kuwait. Tra il 1980 e il 1988 la stessa guerra tra Iran sciita e Iraq con governo sunnita, che costa 500 mila morti, \u00e8 combattuta dall&#8217;una e dall&#8217;altra parte anche come <i>jihad. <\/i>Nel frattempo Saddam impicca l&#8217;ayatollah Baqir al Sadr (zio di Moqtada al Sadr) e centinaia di suoi accoliti accusandoli di apostasia e attentato alla sicurezza dello Stato.<\/p>\n<p style=\"text-align: justify;\">Nel 1991, alla fine disastrosa della guerra del Golfo, la rivolta sciita del sud Iraq \u00e8 schiacciata da Saddam Hussein con non meno di 15 mila vittime. Questo \u00e8 il prezzo della pax sunnita che Saddam Hussein impone all&#8217;Iraq che tanta nostalgia suscita oggi nelle anime belle che esecrano la sua deposizione da parte di George W. Bush. Pochi anni dopo, in Afghanistan, i talebani arrivati al potere massacrano l&#8217;etnia sciita degli Hazara. Da allora sanguinosi attentati sunniti contro fedeli in preghiera dentro moschee sciite si succedono non solo in Iraq, ma anche in Bangladesh e Pakistan.<\/p>\n<p style=\"text-align: justify;\">La realt\u00e0 di cui l&#8217;Occidente si rifiuta di prendere atto \u00e8 che si sta combattendo nel mondo musulmano una <i>Fitna, <\/i>una guerra di religione che contrappone lo scisma wahabita agli sciiti e in particolare al nuovo scisma in ambito sciita che \u00e8 stato delineato dall&#8217;ayatollah Khomeini. Questo \u00e8 il contesto culturale e politico che produce il terrorismo islamista. Questa \u00e8 la ragione per cui la strategia di contrasto di Barack Obama basata sugli assassinii mirati e sui droni \u00e8 ai limiti dell&#8217;assurdo. Stiamo assistendo allo sviluppo esponenziale di un&#8217;inarrestabile guerra di religione tra musulmani, che si combatte anche in ambito sciita tra khomeinisti e antikhomeinisti.<\/p>\n<p style=\"text-align: justify;\"><b>Guardare la foresta, non solo gli alberi<\/b><\/p>\n<p style=\"text-align: justify;\">II 10 aprile 2003 a Najaf il potente e famoso ayatollah sciita Abdul Majid al Khoei, appena rientrato dall&#8217;esilio londinese, viene assassinato a colpi di mannaia dai sicari armati dallo sciita Moqtada al Sadr, che l&#8217;anno successivo minaccia di uccidere l&#8217;ayatollah Ali al Sistani e attacca Najaf e Kerbala. Abdul Majid al Khoei era amico di Tony Blair, il suo ispiratore nello schierarsi a fianco di George W. Bush nella guerra contro Saddam. Era figlio del grande ayatollah Abu al Kassim al Khoei, maestro dell&#8217;attuale grande ayatollah Ali al Sistani, arrestato da Saddam Hussein e morto nel 1992 agli arresti domiciliari. Era esponente di rilievo della componente sciita avversa al khomeinismo (e a Baqir al Sadr) e la sua morte costa un prezzo enorme alla coalizione dei volenterosi.<\/p>\n<p style=\"text-align: justify;\">Con al Khoei scompare l&#8217;indispensabile mediatore tra la coalizione occidentale e la situazione interna irachena e si perde il contatto con la fondamentale componente religiosa sciita affidata incautamente dall&#8217;America ai laici lyad Allawi e Ahmed Chalabi (suggeritore della disastrosa decisione di sciogliere l&#8217;esercito iracheno e i suoi vertici sunniti).<\/p>\n<p style=\"text-align: justify;\">Infine, ma non per ultimo, se si vuole guardare la foresta e non solo gli alberi, un dato secco: dal 1956 a oggi, se si guarda ai conflitti in Indonesia, Pakistan-Bangladesh, Giordania, Oman, Ciad, Sudan-Sudan del sud, Yemen, Iran-Iraq, Siria, Libano, Algeria Marocco, si vede che tra i 4 e i 6 milioni di musulmani sono stati uccisi da altri musulmani in guerre civili, attentati e conflitti di religione (statistiche precise sono impossibili). In questo contesto pi\u00f9 di un milione e mezzo di arabi sono stati uccisi da arabi. Senza alcun intervento dell&#8217;Occidente, n\u00e9 di Israele.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Studi Cattolici n.641\/42 luglio-agosto 2014 Riprendiamo da Il Foglio del 3 luglio 2014 questa illuminante ricostruzione delle guerre di religione fra arabi che stanno insanguinando il Medioriente, con milioni di morti. di Carlo Panella<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/iraq-era-meglio-saddam\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":9474,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[161],"class_list":["post-9472","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-islam","tag-islam-2","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Iraq: era meglio Saddam? - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/iraq-era-meglio-saddam\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Iraq: era meglio Saddam? - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/iraq-era-meglio-saddam\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2014-09-10T22:00:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/08\/sciiti-massacre.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"290\" \/>\n\t<meta property=\"og:image:height\" content=\"174\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/iraq-era-meglio-saddam\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/iraq-era-meglio-saddam\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Iraq: era meglio Saddam?\",\"datePublished\":\"2014-09-10T22:00:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/iraq-era-meglio-saddam\\\/\"},\"wordCount\":1056,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/iraq-era-meglio-saddam\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/08\\\/sciiti-massacre.jpg\",\"keywords\":[\"islam\"],\"articleSection\":[\"Islam\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/iraq-era-meglio-saddam\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/iraq-era-meglio-saddam\\\/\",\"name\":\"Iraq: era meglio Saddam? - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/iraq-era-meglio-saddam\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/iraq-era-meglio-saddam\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/08\\\/sciiti-massacre.jpg\",\"datePublished\":\"2014-09-10T22:00:04+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/iraq-era-meglio-saddam\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/iraq-era-meglio-saddam\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/iraq-era-meglio-saddam\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/08\\\/sciiti-massacre.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/08\\\/sciiti-massacre.jpg\",\"width\":290,\"height\":174},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/iraq-era-meglio-saddam\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Iraq: era meglio Saddam?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Iraq: era meglio Saddam? - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/iraq-era-meglio-saddam\/","og_locale":"it_IT","og_type":"article","og_title":"Iraq: era meglio Saddam? - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/iraq-era-meglio-saddam\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2014-09-10T22:00:04+00:00","og_image":[{"width":290,"height":174,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/08\/sciiti-massacre.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/iraq-era-meglio-saddam\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/iraq-era-meglio-saddam\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Iraq: era meglio Saddam?","datePublished":"2014-09-10T22:00:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/iraq-era-meglio-saddam\/"},"wordCount":1056,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/iraq-era-meglio-saddam\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/08\/sciiti-massacre.jpg","keywords":["islam"],"articleSection":["Islam"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/iraq-era-meglio-saddam\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/iraq-era-meglio-saddam\/","name":"Iraq: era meglio Saddam? - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/iraq-era-meglio-saddam\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/iraq-era-meglio-saddam\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/08\/sciiti-massacre.jpg","datePublished":"2014-09-10T22:00:04+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/iraq-era-meglio-saddam\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/iraq-era-meglio-saddam\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/iraq-era-meglio-saddam\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/08\/sciiti-massacre.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/08\/sciiti-massacre.jpg","width":290,"height":174},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/iraq-era-meglio-saddam\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Iraq: era meglio Saddam?"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/9472","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=9472"}],"version-history":[{"count":1,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/9472\/revisions"}],"predecessor-version":[{"id":9475,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/9472\/revisions\/9475"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/9474"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=9472"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=9472"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=9472"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}