{"id":9238,"date":"2014-09-04T00:00:30","date_gmt":"2014-09-03T22:00:30","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=9238"},"modified":"2014-08-19T10:56:07","modified_gmt":"2014-08-19T08:56:07","slug":"leconomia-sociale-una-risposta-alla-crisi","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/leconomia-sociale-una-risposta-alla-crisi\/","title":{"rendered":"L\u2019economia sociale? Una risposta alla crisi"},"content":{"rendered":"<p><b><a href=\"http:\/\/www.corrieredelsud.it\/nsite\/\" target=\"_blank\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/08\/Belloc-Chesterton.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-9239 alignright\" alt=\"Belloc-Chesterton\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/08\/Belloc-Chesterton.jpg\" width=\"242\" height=\"188\" \/><\/a>Il Corriere del Sud<\/a> n.6 21 luglio 2014<\/b><\/p>\n<p style=\"text-align: center;\"><b><\/b>di Cristiano Ottaviani<\/p>\n<p style=\"text-align: justify;\">L\u2019impresa sociale e l\u2019economia sociale possono essere risposte alla crisi? La connotazione etica della domanda \u00e8 evidente, pi\u00f9 incerte le reali prospettive economiche. A questa contraddizione ha provato a rispondere il convegno organizzalo dall\u2019UCID \u2013 <i>Unione Cristiana<\/i> <i>Imprenditori Dirigenti <\/i>sezione di Roma, intitolato <i>&#8220;Impresa sociale<\/i><i> sostenibile: realt\u00e0 o illusione?&#8221;.<\/i><\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">All&#8217;appuntamento organizzato dall\u2019UCID il 16 aprile 2014 a Palazzo Alteri a Roma, hanno partecipato protagonisti e studiosi del settore, come il prof. Malico Caroli &#8211; Direttore Area Ricerca Consulenza Universita LUISS Guido Carli, la Dott.ssa Marina Miglioralo &#8211; Responsabile CSR Enel SpA. il prof. Fabio Abenavoli &#8211; Presidente &#8220;Emergenza Sorrisi&#8221;, ed il Doli. Federico Mento \u2014 Coordinatore di &#8220;Human Foundation&#8221;, moderati da Marco Franzelli, giornalista del TG Uno della <i>RAI<\/i><\/p>\n<p style=\"text-align: justify;\">Nell&#8217;incontro ci si \u00e8 soffermati su come la crisi, iniziata nel 2008 e giunta al suo sesto anno, possa ridare scopo alla nostra economia. I difficili anni di recessione che stiamo vivendo, potrebbero avere un senso infatti, se venissero utilizzati per far capire i limiti del nostro modello capitalistico e farci comprendere da dove ripartire. Non si tratta di abbracciare improbabili &#8220;decrescite felici&#8221; e astratte semplificazioni demagogiche, tanto fumose nella teorie, quanto inconcludenti nelle loro applicazioni pratiche perch\u00e8 poco attente alle effettive logiche del mercato e della produzione, ma di trovare all&#8217;interno del capitalismo soluzioni nuove e vincenti.<\/p>\n<p style=\"text-align: justify;\">La retorica sul &#8220;sociale&#8221; non risolve da s\u00e9 i problemi di una economia motivata solo dal profitto e incapace di lungimiranza. Negli interventi i relatori dell\u2019<i>Ucid<\/i> non hanno mancato di sottolineare come anche imprese con apparentemente, un forte &#8220;marchio'&#8221; sociale siano risultate, in alcuni casi, colpevoli di irregolarit\u00e0 gravi e di pesanti violazioni delle normative. La logica dei <i>politicamente corretto <\/i>rischia infatti di ridurre l&#8217;eticit\u00e0 delle aziende a un maquillage teso a colorare il proprio spirito aziendale di un fittizio &#8220;sociale&#8221;, sempre pi\u00f9 gradito ad un pubblico assettato di solidariet\u00e0, ma confuso dalla babele dei media.<\/p>\n<p style=\"text-align: justify;\">La tavola rotonda ha evidenziato anche il ruolo delle cooperative sociali, una delle poche realt\u00e0 in attivo nel nostro Paese nonostante la crisi. Il motivo di questo successo controcorrente \u00e8 da collegarsi alla specificit\u00e0 giuridica di queste organizzazioni, che vincolanop il loro capitale ad una logica di lungo termine senza avere l\u2019esigenza\u00a0 di dover continuamente distribuire profitti, potendo avere cos\u00ec una gestione aziendale pi\u00f9 attenta alle esigenze d\u2019impresa. Nonostante le facili strumentalizzazioni politiche, tese a rivendicare le cooperative come specifiche della tradizione della sinistra italiana, la storia di questo movimento \u00e8 pi\u00f9 complessa e variegata.<\/p>\n<p style=\"text-align: justify;\">Se \u00e8 impossibile infatti non parlare di cooperazione senza pensare alla tradizione cattolica sociale, \u00e8 opportuno ricordare come le cooperative siano in grado di favorire una cultura pi\u00f9 civica e comunitaria, un tessuto di relazioni sociali ampio, un contatto attivo con le realt\u00e0 associative e spesso anche, come nel caso delle cooperative sociali di inserimento lavorativo, l\u2019integrazione di soggetti svantaggiati. Si tratta di un modello a bassa conflittualit\u00e0 aziendale, grazie all&#8217;ottica dei ristorni ai soci che, proporzionati ad eventuali attivi di impresa, favoriscono tra i lavoratori una mentalit\u00e0 non meramente rivendicativa, ma attenta alla produzione.<\/p>\n<p style=\"text-align: justify;\">Il convegno non ha mancato di indicare come nella Dottrina Sociale della Chiesa, con una tradizione che inizia da Papa Leone XIII e va avanti fino alla recente <i>&#8220;Caritas in Veritate&#8221;, <\/i>ci siano importanti antidoti ai problemi che stiamo vivendo. Appartiene infatti alla cultura cattolica una nozione di profitto pi\u00f9 estesa rispetto a quella attuale. Con l&#8217;ultima enciclica del 2009 Papa Benedetto XVI ha individuato non solo nella valorizzazione del Terzo Settore, ma nel pieno coinvolgimento di tutti gli attori economici e sociali, la giusta sinergia con cui costruire una societ\u00e0 pi\u00f9 sana e umana. La <i>&#8220;Caritas in Veritate&#8221;&#8217; <\/i>afferma infatti che <i>&#8220;la maggiore forza a servizio dello sviluppo&#8221; <\/i>\u00e8 <i>&#8220;l&#8217;umanesimo cristiano &#8221; <\/i>capace di ravvivare <i>&#8220;la carit\u00e0&#8221; <\/i>e di farsi guidare <i>&#8220;dalla verit\u00e0, accogliendo l&#8217;una e l&#8217;altra come dono per<\/i><i>manente di Dio&#8221;.<\/i><\/p>\n<p style=\"text-align: justify;\">L&#8217;Italia \u00e8 un paese particolare che, proprio per voler negare (almeno da parte della sua classe dirigente) le sue radici cristiane, \u00e8 drammaticamente alle prese con problemi di identit\u00e0. Negare in maniera isterica il legame con le nostre pi\u00f9 profonde tradizioni civiche e religiose, respingendo le nostre radici senza capirne il valore \u00e8 attualmente il principale problema nazionale.<\/p>\n<p style=\"text-align: justify;\">Abituati alla facile retorica di chi politicamente ha vinto i grandi conflitti di potere della modernit\u00e0, ci siamo dimenticati di quanto la nostra storia abbia una propria originalit\u00e0 anche economica, che meriterebbe invece di essere valorizzata e offerta alle altre culture.<\/p>\n<p style=\"text-align: justify;\">Se \u00e8 giusto dire che il modello marxista ha fallito e che il socialismo, clientelare, assistenziale, nemico della razionalit\u00e0 economica, che alla fine \u00e8 anche civile ed etica, \u00e8 stato travolto con il XX secolo; va ammesso anche, che la crisi attuale sta dimostrando come l\u2019iper-liberismo sia sempre pi\u00f9 obsoleto. Da qui l&#8217;esigenza di riattualizzare quanto insegnato in economia dalla tradizione cattolica e indirettamente presente anche nelle specificit\u00e0 del nostro umanesimo, attraverso la valorizzazione dell&#8217; &#8220;economia civile&#8221; che, come ci ricorda il consulente economico di Papa Benedetto XVI il professor Stefano Zamagni, ha in Italia la sua origine e la sua storia pi\u00f9 importante.<\/p>\n<p style=\"text-align: justify;\">Gi\u00e0 prima del pensiero tomistico, la scolastica aveva consentilo di armonizzare il diritto romano nelle sue componenti associativi e organizzative con il solidarismo cristiano, estendendo la carit\u00e0 non solo a tutti i membri attivi della collettivit\u00e0, ma anche a quelli pi\u00f9 deboli e improduttivi. Attraverso la creazione di strutture ordinate di societ\u00e0, che si realizzarono nell&#8217;epoca dei comuni, fu possibile favorire l&#8217;aumento di ricchezza, una produzione di manufatti lungimirante e tutelare le esigenze collettive.<\/p>\n<p style=\"text-align: justify;\">Si tratta di una specificit\u00e0 non compresa a pieno dai nostri politici, desiderosi di scimmiottare tutto ci\u00f2 che \u00e8 straniero, e che andrebbe arricchita da destra con un ripensamento originale di alcuni filoni del pensiero economico; come le idee neocorporative, il liberismo umanistico di Einaudi e Ropke, ma anche il pi\u00f9 moderno <i>Distributismo.<\/i><\/p>\n<p style=\"text-align: justify;\">I padri fondatori del <i>Movimen<\/i><i>to Distributista <\/i>internazionale, da Gilbert Keith Chestcrton a Hilaire Belloc per arrivare a Padre Vincent McNabb (1868-1943), erano tutti cattolici che desideravano porre le questioni della dignit\u00e0 della persona, della tutela della famiglia, della diffusione della piccola propriet\u00e0 come altrettante vie d&#8217;uscita dalla secca dei modelli utopistici e ideologici della <i>modernit\u00e0.<\/i><\/p>\n<p style=\"text-align: justify;\">Tale critica, come ha scritto Fabio Trevisan, co-fondatore dei Gruppi Chestertoniani veronesi e grande esperto di Chesterton e Belloc, <i>\u00absi radi<\/i><i>ca in alcuni principi intangibili (da qui la consonanza con i &#8220;principi non negoziabili &#8220;) a tutela dell&#8217;autentica libert\u00e0 nella verit\u00e0 della persona. Per questo motivo avevano auspicato, un secolo fa, un ripensamento profondo del modello capitalistico e di tutte le sue conseguenze brutali e disumane che appaiono visibilmente ora nella loro drammatica evidenza. A distanza di un secolo le loro analisi non sono state ancora prese in considerazione, nonostante si possano riscontrare i deleteri effetti del sistema liberal-capitalista\u00bb (Il Distributismo: una proposta ragionevole per uscire dalla crisi, <\/i>in <i>Vita Nuova, <\/i>19 aprile 2013).<\/p>\n<p style=\"text-align: justify;\">L&#8217;universo cooperativo e dell&#8217;imprenditoria sociale, le piccole medie aziende a carattere ancora prevalentemente famigliare, il tessuto vivissimo di associazioni volontarie tipiche della nostra economia e societ\u00e0, nonostante le storture subite, ci riportano ad una natura congegnale. Si tratta di un patrimonio, che non merita di essere monopolizzato da quelle forze che desiderano barattare aiuti impropri con interferenze indebite, ma che andrebbe valorizzato con una cultura capace di trattare con realismo e seriet\u00e0, lo sviluppo in modo veramente alternativo.<\/p>\n<p style=\"text-align: justify;\">La nostra speranza \u00e8 che da destra, da chi cio\u00e8 dovrebbe essere pi\u00f9 incline a valorizzare la specificit\u00e0 della tradizione e la difesa della sovranit\u00e0 nazionale, venga la consapevolezza e l&#8217;orgoglio con cui ridare linfa a questa nostra antica, ma ancora florida, identit\u00e0.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Corriere del Sud n.6 21 luglio 2014 di Cristiano Ottaviani L\u2019impresa sociale e l\u2019economia sociale possono essere risposte alla crisi? La connotazione etica della domanda \u00e8 evidente, pi\u00f9 incerte le reali prospettive economiche. A questa contraddizione ha provato a rispondere il convegno organizzalo dall\u2019UCID \u2013 Unione Cristiana Imprenditori Dirigenti sezione di Roma, intitolato &#8220;Impresa &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/leconomia-sociale-una-risposta-alla-crisi\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":9239,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,13],"tags":[410,146,2389],"class_list":["post-9238","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dottrina-sociale","category-economia","tag-distributismo","tag-dottrina-sociale-2","tag-economia","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L\u2019economia sociale? Una risposta alla crisi - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/leconomia-sociale-una-risposta-alla-crisi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019economia sociale? Una risposta alla crisi - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/leconomia-sociale-una-risposta-alla-crisi\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2014-09-03T22:00:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/08\/Belloc-Chesterton.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"242\" \/>\n\t<meta property=\"og:image:height\" content=\"188\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/leconomia-sociale-una-risposta-alla-crisi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/leconomia-sociale-una-risposta-alla-crisi\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"L\u2019economia sociale? Una risposta alla crisi\",\"datePublished\":\"2014-09-03T22:00:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/leconomia-sociale-una-risposta-alla-crisi\\\/\"},\"wordCount\":1278,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/leconomia-sociale-una-risposta-alla-crisi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/08\\\/Belloc-Chesterton.jpg\",\"keywords\":[\"distributismo\",\"dottrina sociale\",\"Economia\"],\"articleSection\":[\"Dottrina sociale\",\"Economia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/leconomia-sociale-una-risposta-alla-crisi\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/leconomia-sociale-una-risposta-alla-crisi\\\/\",\"name\":\"L\u2019economia sociale? Una risposta alla crisi - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/leconomia-sociale-una-risposta-alla-crisi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/leconomia-sociale-una-risposta-alla-crisi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/08\\\/Belloc-Chesterton.jpg\",\"datePublished\":\"2014-09-03T22:00:30+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/leconomia-sociale-una-risposta-alla-crisi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/leconomia-sociale-una-risposta-alla-crisi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/leconomia-sociale-una-risposta-alla-crisi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/08\\\/Belloc-Chesterton.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/08\\\/Belloc-Chesterton.jpg\",\"width\":242,\"height\":188},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/leconomia-sociale-una-risposta-alla-crisi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u2019economia sociale? Una risposta alla crisi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u2019economia sociale? Una risposta alla crisi - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/leconomia-sociale-una-risposta-alla-crisi\/","og_locale":"it_IT","og_type":"article","og_title":"L\u2019economia sociale? Una risposta alla crisi - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/leconomia-sociale-una-risposta-alla-crisi\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2014-09-03T22:00:30+00:00","og_image":[{"width":242,"height":188,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/08\/Belloc-Chesterton.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/leconomia-sociale-una-risposta-alla-crisi\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/leconomia-sociale-una-risposta-alla-crisi\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"L\u2019economia sociale? Una risposta alla crisi","datePublished":"2014-09-03T22:00:30+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/leconomia-sociale-una-risposta-alla-crisi\/"},"wordCount":1278,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/leconomia-sociale-una-risposta-alla-crisi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/08\/Belloc-Chesterton.jpg","keywords":["distributismo","dottrina sociale","Economia"],"articleSection":["Dottrina sociale","Economia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/leconomia-sociale-una-risposta-alla-crisi\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/leconomia-sociale-una-risposta-alla-crisi\/","name":"L\u2019economia sociale? Una risposta alla crisi - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/leconomia-sociale-una-risposta-alla-crisi\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/leconomia-sociale-una-risposta-alla-crisi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/08\/Belloc-Chesterton.jpg","datePublished":"2014-09-03T22:00:30+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/leconomia-sociale-una-risposta-alla-crisi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/leconomia-sociale-una-risposta-alla-crisi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/leconomia-sociale-una-risposta-alla-crisi\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/08\/Belloc-Chesterton.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/08\/Belloc-Chesterton.jpg","width":242,"height":188},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/leconomia-sociale-una-risposta-alla-crisi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"L\u2019economia sociale? Una risposta alla crisi"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/9238","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=9238"}],"version-history":[{"count":2,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/9238\/revisions"}],"predecessor-version":[{"id":9241,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/9238\/revisions\/9241"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/9239"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=9238"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=9238"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=9238"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}