{"id":918,"date":"2005-07-17T00:00:00","date_gmt":"2005-07-16T22:00:00","guid":{"rendered":""},"modified":"2016-04-20T17:14:21","modified_gmt":"2016-04-20T15:14:21","slug":"lanti-integrismo-come-disintegrazione-della-fede","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lanti-integrismo-come-disintegrazione-della-fede\/","title":{"rendered":"L&#8217;anti-integrismo come disintegrazione della fede"},"content":{"rendered":"<div style=\"text-align: center;\">\n<div id=\"attachment_33229\" style=\"width: 119px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-33229\" class=\"wp-image-33229 size-full\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/Sorge.jpg\" alt=\"Sorge\" width=\"119\" height=\"200\" \/><p id=\"caption-attachment-33229\" class=\"wp-caption-text\">p. Bartolomeo Sorge<\/p><\/div>\n<p>Articolo\u00a0pubblicato nel 1978 sul n. 37 di <strong>Cristianit\u00e0<\/strong><\/div>\n<div style=\"text-align: center;\"><\/div>\n<p style=\"text-align: center;\">\n<p style=\"text-align: center;\"><em>Il contributo de &#8220;La Civilt\u00e0 Cattolica&#8221; al &#8220;compromesso culturale&#8221;<\/em><\/p>\n<p style=\"text-align: center;\">di <strong>Giovanni Cantoni<\/strong><\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">Mentre si fa pi\u00f9 urgente la necessit\u00e0 che i cattolici si confermino nella fede &#8211; nella imminenza di scontri sempre pi\u00f9 drammatici tra la Rivoluzione, la Chiesa e quanto sopravvive della civilt\u00e0 cristiana -, i padri Sorge e De Rosa inventano l&#8217;integrismo, per potere imitare la destalinizzazione e liberarsi dalla dottrina cattolica tradizionale. Nella loro analisi l&#8217;integrismo si rivela essere semplicemente lo sforzo di aderire senza riserve alla totalit\u00e0 del Magistero e la fedelt\u00e0 assoluta alle sue direttive tradizionali, anche in campo politico e sociale. L&#8217;ambigua nozione di &#8220;identit\u00e0 cristiana&#8221;. Le affermazioni di mons. Bettazzi sulla dottrina sociale e sul significato della lettera apostolica <em>Octogesima adveniens<\/em> di Paolo VI<em>.<\/em><\/div>\n<p style=\"text-align: justify;\">L&#8217;ormai famosa lettera dell&#8217;on. Berlinguer a mons. Bettazzi, vescovo di Ivrea, costituisce senza dubbio alcuno il manifesto del &#8220;compromesso culturale&#8221; offerto dai comunisti ai cattolici, &#8211; meglio, al personale dirigente del mondo cattolico -, perch\u00e9 lo svelamento del &#8220;compromesso storico&#8221; sia il pi\u00f9 possibile indolore, le reazioni siano modiche, prevedibili e recuperabili, e il passaggio del Partito Comunista dal potere sulla societ\u00e0 civile alla titolarit\u00e0 del potere sullo Stato, cio\u00e8 al governo, avvenga, in Italia e forse in Europa, senza quelle difficolt\u00e0 e quell&#8217;alea che hanno caratterizzato l&#8217;infortunio cileno.<\/p>\n<p style=\"text-align: justify;\">Tale &#8220;compromesso culturale&#8221; prevede e auspica una sostanziale degradazione della cultura cattolica &#8211; presupposto di ogni civilt\u00e0 cattolica e quindi di ogni societ\u00e0 cattolica -, cio\u00e8 una sua intrinseca vanificazione, un suo svuotamento, che la renda disponibile alla assunzione di nuovi contenuti e alla giustificazione del cedimento presentandolo come una conquista (1).<\/p>\n<p style=\"text-align: justify;\">Sulla strada del &#8220;compromesso culturale&#8221; &#8211; e quindi di quello &#8220;storico&#8221; &#8211; si erge, da poco tempo, una pietra miliare, un manufatto &#8220;cattolico&#8221;, teso a ridurre pressoch\u00e9 a nulla gli elementi di dottrina sociale cogenti per un fedele, o almeno a gettare un&#8217;ombra di sospetto su tutto il Magistero sociale pre-conciliare.<\/p>\n<p style=\"text-align: justify;\">Tale pietra miliare \u00e8 costituita da un recente impegnativo fondo de <em>La Civilt\u00e0 Cattolica<\/em>, intitolato <em>Fede cristiana ed integrismo<\/em>, e firmato in coppia dai padri Bartolomeo Sorge S. J., direttore della rivista, e Giuseppe De Rosa S. J., autorevole redattore della stessa (2). L&#8217;articolo trae spunto dall&#8217;uso e dall&#8217;abuso, nel linguaggio corrente, del termine &#8220;integrismo&#8221; e del corrispondente aggettivo &#8220;integrista&#8221;, e pi\u00f9 concretamente da scritti di occasione di Franco Rodano, comparsi su <em>Paese Sera <\/em>a commento delle elezioni per i distretti scolastici.<\/p>\n<div id=\"attachment_33230\" style=\"width: 250px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-33230\" class=\"wp-image-33230\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/De-Rosa.jpg\" alt=\"De Rosa\" width=\"250\" height=\"139\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/De-Rosa.jpg 301w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/De-Rosa-300x166.jpg 300w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" \/><p id=\"caption-attachment-33230\" class=\"wp-caption-text\">p. Giuseppe De Rosa<\/p><\/div>\n<p style=\"text-align: justify;\">Perch\u00e9 &#8220;<em>non si lancino con eccessiva leggerezza accuse di integrismo a chi non le merita, e <\/em>[&#8230;] <em>si eviti di cadere in forme nuove di integrismo, ripetendo vecchi errori, tanto meno comprensibili e scusabili oggi quanto pi\u00f9 chiaramente e decisamente, col Concilio Vaticano II, la Chiesa li ha definitivamente superati<\/em>&#8220;, i due padri gesuiti si accingono a chiarire ogni possibile equivoco in proposito e, allo scopo, ritengono anzitutto di dovere ricercare la genesi storica del concetto di integrismo.<\/p>\n<p style=\"text-align: center;\">* \u00a0* \u00a0*<\/p>\n<p style=\"text-align: justify;\">&#8220;<em>Di integrismo <\/em>&#8211; scrivono &#8211; <em>si \u00e8 cominciato a parlare solo dall&#8217;inizio di questo secolo, durante la polemica antimodernista. In questo periodo integrismo &#8211; derivato da <\/em>integer <em>(integro-intero) &#8211; e integralismo &#8211; derivato da <\/em>integralis <em>(integrale-totale) &#8211; significavano l&#8217;adesione senza riserve alla totalit\u00e0 dell&#8217;insegnamento della Chiesa e la fedelt\u00e0 assoluta alle sue direttive, anche in campo politico e sociale, cosicch\u00e9 quei cattolici che intendevano aderire a tutto ci\u00f2 che la Chiesa insegnava e prescriveva si chiamavano &#8220;<\/em>cattolici integrali<em>&#8220;. Poich\u00e9, per\u00f2, l&#8217;attacco tanto dei modernisti sul piano della fede, quanto dei liberali sul piano politico, era diretto contro la Chiesa romana questi cattolici si chiamavano &#8220;<\/em>cattolici romani integrali<em>&#8220;. <\/em><\/p>\n<p style=\"text-align: justify;\"><em>Con questo si voleva indicare che essi si opponevano, da una parte, ai modernisti, che rifiutavano l&#8217;insegnamento della Chiesa in campo dogmatico o lo interpretavano in modo non conforme alla Tradizione e al Magistero, ma secondo i postulati del razionalismo e dello scientismo; dall&#8217;altra, a tutti coloro che pretendevano di sottrarsi alle direttive della Chiesa, sia in campo politico (i cattolici &#8220;<\/em>liberali<em>&#8220;), sia in campo sociale (i cattolici &#8220;<\/em>sociali<em>&#8220;).<\/em>&#8220;<\/p>\n<p style=\"text-align: justify;\"><em>Il &#8220;<\/em>cattolicesimo liberale<em>&#8221; o liberalismo cattolico, era una corrente di pensiero che intendeva &#8220;<\/em>cattolicizzare il liberalismo<em>&#8221; integrando nella visione cristiana alcuni principi del liberalismo che si potevano conciliare con essa, in primo luogo, il principio della libert\u00e0 e della indipendenza reciproca tra la Chiesa e lo Stato &#8211; <\/em>l&#8217;Eglise libre dans une nation elle m\u00e9me libre<em>, scriveva Montalembert nel 1862 -, rifiuto quindi dell&#8217;alleanza tra trono ed altare; in secondo luogo il principio del governo &#8220;<\/em>misto<em>&#8221; in cui il potere \u00e8 esercitato dal capo dello Stato, ma secondo una Costituzione e sotto il controllo d&#8217;un parlamento eletto con suffragio popolare, e quindi opposizione tanto all&#8217;assolutismo monocratico quanto all&#8217;assolutismo democratico; infine, il principio del diritto dei popoli a disporre di s\u00e9 stessi, e quindi interesse per la difesa delle nazioni oppresse. <\/em><\/p>\n<p style=\"text-align: justify;\"><em>A questa corrente che nell&#8217;Ottocento aveva avuto rappresentanti illustri in molti Paesi &#8211; in Francia: Lacordaire, Montalembert, Dupanloup, Maret; in Italia: Rosmini, Gioberti, Manzoni, Lambruschini; in Inghilterra: Newman; in Germania: Eckstein &#8211; gli integralisti rivolgevano l&#8217;accusa di accettare &#8220;<\/em>il liberalismo, il progresso e la civilt\u00e0 moderna<em>&#8221; ponendosi in tal modo contro l&#8217;enciclica <\/em>Mirari vos <em>ed il <\/em>Sillabo<em>. Soprattutto li accusavano di voler conciliare la Chiesa con lo Stato risorgimentale, anticlericale e massonico, e di rinunciare al potere temporale del Papa. <\/em><\/p>\n<p style=\"text-align: justify;\"><em>Di qui la polemica tra &#8220;<\/em>intransigenti<em>&#8221; e &#8220;<\/em>conciliatoristi<em>&#8220;, tra i quali spiccava il vescovo di Cremona, mons. G. Bonomelli.<\/em> &#8220;<em>Ma gli integristi non si opponevano solo ai cattolici &#8216;<\/em>liberali<em>&#8216; e &#8220;<\/em>conciliatoristi<em>&#8220;; con non minore vigore si opponevano a quei cattolici &#8220;<\/em>sociali<em>&#8221; che, in contrasto con le direttive pontificie &#8211; la rigida disciplina del <\/em>non expedit <em>fu allentata, ma non abolita, solo nel 1905 -, volevano passare dal campo della democrazia &#8220;<\/em>sociale<em>&#8220;, quale l&#8217;aveva delineata il Toniolo, al campo della democrazia &#8220;<\/em>politica<em>&#8220;, e quindi formare un partito politico cristiano (la &#8220;<\/em>democrazia cristiana<em>&#8221; di R. Murri), sottratto al controllo della Gerarchia; si opponevano, soprattutto, a quella corrente di cattolici &#8220;<\/em>sociali<em>&#8221; che in Francia si raccoglieva intorno al Sillon di M. Sangnier e che Pio X condann\u00f2 nel 1910 con la lettera <\/em>Notre charge apostolique<em>, per la sua pretesa di &#8220;<\/em>sottrarsi ostinatamente alla direzione di coloro che hanno ricevuto dal Cielo la missione di guidare gli individui e le societ\u00e0 nel retto cammino della verit\u00e0 e del bene<em>&#8221; respingendo il &#8220;<\/em>potere dottrinale e direttivo dell&#8217;autorit\u00e0 ecclesiastica<em>&#8220;; potere che esiste anche nel campo politico ed economico, poich\u00e9 &#8220;<\/em>i tre elementi, politico, economico e morale, sono subordinati l&#8217;uno all&#8217;altro, ed \u00e8 l&#8217;elemento morale che \u00e8 il principale<em>&#8220;.<\/em><\/p>\n<p style=\"text-align: justify;\">&#8220;Le osservazioni che si potrebbero fare, entrando nel merito di ogni singola affermazione, sono letteralmente innumerevoli, e quindi mi limito a due. La prima riguarda i &#8220;<em>principi del liberalismo che si potevano conciliare<\/em>&#8221; con la &#8220;<em>visione cristiana<\/em>&#8220;, tra i quali \u00e8 citato &#8220;<em>il principio della libert\u00e0 e della indipendenza reciproca tra la Chiesa e lo Stato<\/em>&#8220;, espresso con la formula di Montalembert, ma pi\u00f9 noto in Italia con quella di Cavour, &#8220;<em>libera Chiesa in libero Stato<\/em>&#8220;: sono sicuri gli estensori dell&#8217;articolo che si tratti di principio conciliabile con la dottrina cattolica?<\/p>\n<p style=\"text-align: justify;\">Non \u00e8 malizioso presentarlo come opposto alla &#8220;<em>alleanza tra trono ed altare<\/em>&#8220;, quando \u00e8 evidentemente relativo al rapporto di qualsiasi Stato, qualunque sia il suo reggimento, con la Chiesa?<\/p>\n<p style=\"text-align: justify;\">La seconda osservazione riguarda le ragioni della condanna del <em>Sillon<\/em>, identificata come censura di un tentativo di sottrarsi alla <em>potestas indirecta <\/em>della Chiesa <em>in temporalibus<\/em>, o addirittura a un debordamento di tale <em>potestas indirecta<\/em>, tentata di divenire <em>directa<\/em>: che ne \u00e8 rimasto delle ragioni dottrinali, cio\u00e8 del tentativo di confondere il Vangelo e la Rivoluzione, e della pretesa di considerare il regime democratico come necessariamente derivante dal cristianesimo e quindi preferenziale, rispetto a ogni altra forma di governo, per tutti i cattolici?<\/p>\n<p style=\"text-align: justify;\">Comunque, almeno fino a questo punto, la narrazione potrebbe parere accettabile &#8211; nonostante le riserve sopra esposte e altre molte &#8211; se, oltre il distacco ostentato dagli estensori del fondo che sto esaminando, non apparisse chiaro, tragicamente sempre pi\u00f9 chiaro, come l&#8217;intento soggiacente sia quello di accreditare la tesi secondo cui quella che viene sommariamente illustrata in un articolo con scopi di pratica e contingente chiarificazione di un termine abusato, altro non sia che una ben nota querelle di scuole e di tendenze in <em>sinu gremioque Ecclesiae<\/em>, come tante ve ne sono state nel corso della storia, eventualmente mediata dalla autorit\u00e0 ecclesiastica.<\/p>\n<p style=\"text-align: justify;\">Dal testo, infatti, non appare con sufficiente evidenza e con la dovuta chiarezza che il modernismo, il cattolicesimo &#8220;liberale&#8221; e il cattolicesimo &#8220;sociale&#8221; sono, all&#8217;inizio del nostro secolo, avversati da cattolici integrali, cio\u00e8 da cattolici <em>tout court<\/em>, non sulla base di opinioni personali o di scuola, ma nello sforzo di ottemperare alle indicazioni anzitutto dottrinali e quindi pastorali non di <em>quidam de populo<\/em>, sia pure <em>de populo Dei<\/em>, ma della gerarchia ecclesiastica e delle massime istanze della Chiesa! Lo scontro tra il custode e il ladro non pu\u00f2 essere visto dal padrone come una diatriba tra cittadini, da sedare equamente distribuendo responsabilit\u00e0 e meriti!<\/p>\n<p style=\"text-align: justify;\">A conferma della prospettiva, basterebbe procedere alla erezione del catalogo dei rappresentanti dell&#8217;antiliberalismo nell&#8217;Ottocento, per rendersi conto di quanto sarebbe insufficiente elencare i nomi degli esponenti del pensiero cattolico contro-rivoluzionario, eventualmente dimenticando quelli di Gregorio XVI, del servo di Dio Pio IX e di Leone XIII; e quanto sarebbe inesatto presentare lo scontro tra &#8220;cattolici liberali&#8221; e cattolici conseguentemente antiliberali come una <em>querelle <\/em>di scuole nel seno della santa Chiesa.<\/p>\n<p style=\"text-align: justify;\">Anche a volere considerare l&#8217;antiliberalismo cattolico dell&#8217;Ottocento una &#8220;corrente&#8221;, i due padri gesuiti avrebbero fatto cosa pi\u00f9 corretta dichiarandola almeno autorevole, anche a fronte dell&#8217;ostentato catalogo di &#8220;esponenti della cultura&#8221;, del cui coinvolgimento, almeno nel caso di qualcuno, mi pare manchino prove sufficienti e che si tratti, piuttosto, di operazione surrettizia.<\/p>\n<p style=\"text-align: center;\">* \u00a0* \u00a0*<\/p>\n<p style=\"text-align: justify;\">Immediatamente proseguendo, padre Sorge e padre De Rosa sembrano smentire, almeno parzialmente, le osservazioni appena fatte, dal momento che paiono calare di tono e aggiustare il tiro, precisando meglio il bersaglio. &#8220;<em>In realt\u00e0 <\/em>&#8211; scrivono infatti &#8211;<em>, l&#8217;integrismo ebbe la sua massima espressione con la creazione nel 1909 &#8211; due anni dopo la condanna del modernismo da parte dell&#8217;enciclica Pascendi (1907) &#8211; del <\/em>Sodalitium Pianum <em>(da Pio V), fondato da mons. U. Benigni, il quale, spesso ricorrendo alla delazione e alla calunnia, estese l&#8217;accusa di modernismo a tutte quelle persone che, in un modo o in un altro, sembravano essere favorevoli alle nuove tendenze, sia in campo teologico (specialmente biblico), sia in campo sociale; cos\u00ec furono accusati o sospettati di modernismo o di &#8220;semi-modernismo&#8221; persone di indubitabile ortodossia e di assoluta fedelt\u00e0 alla Chiesa, solo perch\u00e9 erano favorevoli ad un rinnovamento nel campo della storia ecclesiastica, dell&#8217;esegesi e della dottrina sociale&#8221;<\/em>.<\/p>\n<p style=\"text-align: justify;\">&#8220;<em>Gli integristi si spinsero tanto oltre che Benedetto XV nella sua prima enciclica dovette intervenire per ribadire che &#8220;<\/em>nessun privato, con la pubblicazione di libri o di giornali o con discorsi pubblici, si atteggi a maestro nella Chiesa. Tutti sanno a chi \u00e8 stato affidato da Dio il magistero della Chiesa <em>[\u2026]<\/em>.<\/p>\n<p style=\"text-align: justify;\">Circa quelle questioni a proposito delle quali, senza detrimento della fede o della disciplina, si pu\u00f2 discutere il pro e il contro, perch\u00e9 la Santa Sede non ha ancora deciso nulla, non \u00e8 proibito a nessuno di dire la sua opinione e di difenderla [&#8230;]. Ciascuno sostenga la sua opinione liberamente, ma lo faccia con moderazione e non creda di poter muovere a coloro che tengono un&#8217;opinione contraria, per questo solo motivo, il rimprovero di fede sospetta o di mancanza di disciplina<em>&#8221; (Ad beatissimi, 1\u00b0 nov. 1914, in AAS 6, 576 sg.).<\/em><\/p>\n<p style=\"text-align: justify;\">&#8220;<em>Il <\/em>Sodalitium Pianum <em>fu soppresso per le sue gravi intemperanze nel 1921 dalla Congregazione del Concilio, ma lo spirito integrista che lo animava non mor\u00ec con esso. Cos\u00ec, esso si \u00e8 manifestato a varie riprese negli ultimi cinquant&#8217;anni con la tendenza a &#8220;<\/em>maggiorare<em>&#8221; le esigenze del dogma, della disciplina e della morale ed a restare fortemente legati ad alcuni atteggiamenti del passato, alla &#8220;<\/em>tradizione<em>&#8221; (intesa in senso materiale di fedelt\u00e0 a tutto il passato, senza distinguere in essa ci\u00f2 che \u00e8 solo contingenza storica), respingendo ogni novit\u00e0 come pericolosa per l&#8217;integrit\u00e0 della fede e vedendo in ogni sforzo di aggiornamento un cedimento al male e all&#8217;errore<\/em>&#8220;.<\/p>\n<p style=\"text-align: justify;\">Dunque, dicevo, le considerazioni sembrano farsi pi\u00f9 puntuali e permettere la identificazione di un avversario preciso, da descrivere e da denunciare come modello di integrismo. In questione sono il <em>Sodalitium Pianum <\/em>e mons. Umberto Benigni. Anche in questo caso i fatti da chiarire sarebbero innumerevoli, ma mi limiter\u00f2 a quelli che hanno rilevanza in questa sede e nella prospettiva in cui si situa l&#8217;esame dell&#8217;articolo de <em>La Civilt\u00e0 Cattolica<\/em>.<\/p>\n<p style=\"text-align: justify;\">Dunque, il <em>Sodalitium Pianum <\/em>fu una organizzazione internazionale &#8211; in prospettiva, forse, un istituto secolare -, avente il fine di appoggiare con energia l&#8217;opera di san Pio X, non soltanto contro il modernismo in senso stretto, ma anche contro le sue manifestazioni velate in ogni settore della vita cattolica, tenendo conto del fatto che &#8220;<em>i modernisti, anche dopo che l&#8217;enciclica <\/em>Pascendi dominici gregis<em> (8 settembre 1907) ha strappato la maschera con cui si coprivano, non hanno abbandonato i loro disegni di turbare la pace della Chiesa. Non hanno smesso, infatti, di cercare e di raccogliere in una associazione segreta nuovi adepti, e di inoculare con essi, nelle vene della societ\u00e0 cristiana, il veleno delle loro opinioni <\/em>[&#8230;]&#8221; (3).<\/p>\n<p style=\"text-align: justify;\">Il <em>Sodalitium Pianum<\/em>, inoltre, ricevette da san Pio X un contributo finanziario annuale e una approvazione generica quanto alla idea generale; nonch\u00e9 significativi autografi in cui, tra l&#8217;altro, si pu\u00f2 leggere: &#8220;<em>Esortiamo nel Signore i nostri cari figli, membri del S.P., a proseguire l&#8217;opera bene iniziata, combattendo la buona battaglia della fede, in particolare contro gli errori e gli inganni del modernismo dalle svariate forme<\/em>&#8220;; e ancora: &#8220;<em>Esortiamo nel Signore i nostri cari figli, membri del S.P., che hanno ben meritato dalla causa cattolica, a continuare a combattere la buona battaglia per la Chiesa di Dio e la Santa Sede contro i loro nemici di dentro e di fuori<\/em>&#8221; (4).<\/p>\n<p style=\"text-align: justify;\">Secondo il <em>Rapporto Antonelli<\/em>, poi, pubblicato nel 1950 e che utilizza le deposizioni fatte sotto giuramento al processo canonico per la beatificazione di Pio X e gli archivi delle congregazioni romane, l&#8217;accusa rivolta al <em>Sodalitium Pianum <\/em>&#8220;<em>di spionaggio e di delazione organizzata \u00e8 semplicemente senza fondamento<\/em>&#8221; (5). Va inoltre ricordato che esso fu spontaneamente soppresso da mons. Benigni stesso alla morte di san Pio X, e che fu quindi ricostituito nel 1915 con l&#8217;accordo esplicito del cardinale de Lai, e quindi sciolto definitivamente il 25 novembre 1921 dalla congregazione del Concilio, &#8220;<em>nelle mutate circostanze attuali<\/em>&#8220;, &#8220;<em>non vere ex nostra culpa<\/em>&#8220;, come comment\u00f2 lo stesso mons.Benigni: &#8220;<em>Unde calumniae <\/em>[&#8230;] <em>hoc ipso dilabuntur. Christus Vincit!<\/em>&#8221; (6).<\/p>\n<p style=\"text-align: justify;\">Cosa pensare del riemergere a tanto tempo di distanza di queste calunnie? Come non ricordare la possibile sopravvivenza della &#8220;<em>setta modernista<\/em>&#8221; attraverso il reclutamento di &#8220;<em>nuovi adepti<\/em>&#8220;? Posto tutto questo, che senso ha, infatti, parlare del ricorso, da parte del <em>Sodalitium Pianum<\/em>, &#8220;<em>alla delazione e alla calunnia<\/em>&#8220;, e attribuirne la soppressione alle &#8220;<em>sue gravi intemperanze<\/em>&#8220;? Come non immaginare l&#8217;intento di colpire, anche in questa occasione, l&#8217;autorit\u00e0 ecclesiastica, e nel caso san Pio X, attraverso i cattolici fedeli? Come non cogliere l&#8217;intento volutamente ellittico di una espressione impropria come quella che dichiara &#8220;<em>la condanna del modernismo<\/em>&#8221; avvenuta &#8220;<em>da parte dell&#8217;enciclica Pascendi<\/em>&#8220;?<\/p>\n<p style=\"text-align: justify;\">Quanto, infine, al passo della enciclica <em>Ad beatissimi <\/em>di Benedetto XV, citato a prova di eccessi integristi, \u00e8 opportuno notare che riguarda esclusivamente eventuali eccessi operativi; che da esso non si possono evincere i caratteri di nessuna dottrina non solo <em>damnata <\/em>ma neppure <em>damnabilis<\/em>; che fa riferimento a &#8220;<em>quelle questioni a proposito delle quali, senza detrimento della fede e della disciplina, si pu\u00f2 discutere il pro e il contro, perch\u00e9 la S. Sede non ha ancora deciso nulla<\/em>&#8220;, ma non certamente a quanto \u00e8 stato, nelle dovute forme, esposto dalla gerarchia ecclesiastica e che \u00e8 entrato a fare parte di quel <em>depositum <\/em>di cui ogni fedele, anche se a diverso titolo, \u00e8 naturale custode.<\/p>\n<p style=\"text-align: center;\">* \u00a0* \u00a0*<\/p>\n<p style=\"text-align: justify;\">Le considerazioni precedenti, fatte a margine della ricostruzione storica operata dai due padri gesuiti, autorizzano a dubitare della esistenza di qualcosa che si possa definire con precisione come integrismo, se non come eventuale eccesso nella difesa della verit\u00e0 e dell&#8217;autorit\u00e0 che l&#8217;ha proclamata, eccesso del custode nella difesa del bene del padrone dalle insidie del ladro. [\u2026] Come si vede, il diavolo, anche fra i gesuiti, con tutta la venerazione per sant&#8217;Ignazio, fa le pentole ma non i coperchi!<\/p>\n<p style=\"text-align: center;\">* \u00a0* \u00a0*<\/p>\n<p style=\"text-align: justify;\">&#8220;<em>In conclusione <\/em>&#8211; scrivono i nostri &#8211; <em>sembra si possa dire che, storicamente, l&#8217;integrismo si \u00e8 presentato con i seguenti caratteri:<\/em> &#8220;- <em>tendenza ad estendere eccessivamente il campo delle verit\u00e0 dogmatiche e, conseguentemente, a restringere il campo della libera discussione e della ricerca tra i cattolici<\/em>; &#8220;- <em>tendenza a ritenere che la Chiesa, avendo il pieno possesso della verit\u00e0, non pu\u00f2 nulla ricevere n\u00e9 imparare da nessuno; sono, invece, gli altri che devono imparare da essa ed accettarne gli insegnamenti e la guida; perci\u00f2, la Chiesa non pu\u00f2 entrare in dialogo con gli altri essendo essa &#8220;maestra di verit\u00e0&#8221;<\/em>;&#8221;- <em>tendenza a ritenere che tutto \u00e8 gi\u00e0 risolto dalla Chiesa e che basta, quindi, rivolgersi al passato per trovarvi la soluzione dei problemi di oggi: quindi, avversione ad ogni &#8220;<\/em>novit\u00e0<em>&#8220;, che \u00e8 vista conte un pericolo per la fede e come un segno, in chi la ricerca, di poca fede nella Chiesa e di scarso attaccamento alla tradizione;<\/em> &#8220;<em>&#8211; tendenza a vedere nel mondo &#8220;moderno&#8221; solo male ed errore, cio\u00e8 solo apostasia da Dio, rifiuto del cristianesimo, ribellione contro la fede e la morale cristiana, avversione e lotta alla Chiesa: quindi tendenza a vedere nei movimenti di idee e nei movimenti politici che ne sono espressione (liberalismo, socialismo-comunismo, massoneria) gli avversari della Chiesa e del cristianesimo, con i quali non \u00e8 possibile non solo accordarsi e collaborare, ma neppure dialogare pur con le necessarie cautele e senza farsi strumentalizzare<\/em>&#8220;.<\/p>\n<p style=\"text-align: justify;\">Se \u00e8 vero, come \u00e8 vero, che l&#8217;amore di Dio non ha limiti &#8211; &#8220;<em>causa diligendi Deum, Deus est: modus, sine modo diligere<\/em>&#8220;, &#8220;<em>il motivo di amare Dio \u00e8 Dio stesso; la misura \u00e8 amarlo senza misura<\/em>&#8221; (8) -, e che quindi anche la sua legge merita di essere amata in modo eccessivo piuttosto che restrittivo; se \u00e8 vero che il &#8220;<em>dialogo non pu\u00f2 essere una debolezza rispetto all&#8217;impegno verso la nostra fede<\/em>&#8221; (9); che &#8220;<em>l&#8217;apostolato non pu\u00f2 transigere con un compromesso ambiguo rispetto ai principi di pensiero e di azione che devono qualificare la nostra professione cristiana<\/em>&#8221; (10), e che &#8220;<em>solo chi \u00e8 pienamente fedele alla dottrina di Cristo pu\u00f2 essere efficacemente apostolo<\/em>&#8221; (11); se \u00e8 vero, infine, che la tradizione \u00e8 &#8220;<em>verit\u00e0 trasmessa<\/em>&#8221; e che &#8220;<em>moderno<\/em>&#8221; non coincide con &#8220;<em>contemporaneo<\/em>&#8221; ma piuttosto con &#8220;<em>mondano<\/em>&#8220;, i caratteri attribuiti all&#8217;integrismo sembrano essere, <em>sic et simpliciter<\/em>, quelli del cattolicesimo, quelli di chi ha la &#8220;tendenza&#8221; a essere cattolico, solo cattolico, nient&#8217;altro che cattolico.<\/p>\n<p style=\"text-align: justify;\">E bisogna essere grati ai due scrittori de <em>La Civilt\u00e0 Cattolica <\/em>per avere cos\u00ec opportunamente sintetizzato la dottrina del Magistero, che per il fedele \u00e8 <em>regula proxima fidei<\/em>, anche se con una aggettivazione che certo non indica simpatia per l&#8217;oggetto descritto; e la prova che l&#8217;oggetto descritto \u00e8 vero e buono, \u00e8 che esso vive anche con l&#8217;aggettivazione di cui \u00e8 caricato!<\/p>\n<p style=\"text-align: justify;\">Dopo l&#8217;esame storico, i padri Sorge e De Rosa ci guidano all&#8217;analisi del problema dell&#8217;integrismo sotto il profilo teoretico, allo scopo di tentarne una definizione. A questo fine fanno la risibile premessa &#8211; risibile dopo le insufficienze storiche indicate &#8211; secondo cui &#8220;<em>si deve evitare una definizione che abbia il solo scopo di porre sotto accusa certe persone e certi movimenti, e, invece, cercarne una che sia seriamente fondata sulla ragione e sulla storia<\/em>&#8220;.<\/p>\n<p style=\"text-align: justify;\">&#8220;<em>Che cos&#8217;\u00e8, allora, l&#8217;integrismo?<\/em>&#8220;, si chiedono i nostri mentori, e ne individuano due aspetti, uno psicologico e uno teoretico-pratico. A questo punto lo studio (pur sempre ostentando sufficienza e distacco dalla materia, allo scopo evidente di accreditare sicurezza e fiducia nelle conclusioni) si fa terribilmente confuso e contraddittorio, perch\u00e9 passa da considerazioni fenomenologiche a considerazioni dottrinali, rese ancora pi\u00f9 complesse dalla identificazione di un integrismo confessionale e di un integrismo ideologico.<\/p>\n<p style=\"text-align: justify;\">L&#8217;esame, poi preventivo, dell&#8217;aspetto psicologico rispetto a quello dottrinale &#8211; detto teoretico-pratico &#8211; produce effetti altamente equivoci, dal momento che, nonostante l&#8217;ostentato respiro filosofico del discorso, l&#8217;integrista <em>vis\u00e9 <\/em>\u00e8 solo o almeno principalmente quello confessionale, cio\u00e8- il cattolico fedele, i cui caratteri vengono attribuiti anche all&#8217;integralista ideologico.<\/p>\n<p style=\"text-align: justify;\">Che senso ha, infatti, affermare che, dal punto di vista psicologico, &#8220;<em>la mentalit\u00e0 integrista comporta <\/em>[&#8230;] <em>la convinzione che la storia umana, per quanto riguarda la conoscenza della verit\u00e0 e i comportamenti morali, non cammina, sia pure a fatica e con gravi insuccessi, verso il vero e il bene, Ma verso l&#8217;errore e il male<\/em>&#8220;, e quindi, dopo avere definito l&#8217;integrismo ideologico come affermazione del &#8220;<em>carattere assoluto di un&#8217;ideologia<\/em>&#8221; e come adeguamento di &#8220;<em>tutta la vita politica e sociale a tale ideologia con tutti i mezzi, anche con la forza ecc.<\/em>&#8220;, che senso ha sostenere che &#8220;<em>oggi l&#8217;integrismo ideologico \u00e8 molto diffuso<\/em>&#8221; e che esso &#8220;<em>vige, anzitutto, nei paesi in cui il comunismo \u00e8 al potere, dove c&#8217;\u00e8 un unico modello di societ\u00e0, dedotto dall&#8217;ideologia marx-leninista ecc.<\/em>&#8220;?<\/p>\n<p style=\"text-align: justify;\">E&#8217; corretto affermare che l&#8217;ideologia marxista-leninista comporta, sul piano psicologico, una mentalit\u00e0 che crede a una marcia della storia verso l&#8217;errore e il male? E&#8217; un presupposto valido per un dialogo serio, e segno di comprensione autentica per il marxista-leninista? Che dire, poi, sempre a proposito dell&#8217;integrista marxista-leninista, della veridicit\u00e0 nell&#8217;attribuirgli una tendenza <em>a &#8220;idealizzare il passato e a criticare aspramente il presente ecc.<\/em>&#8220;?<\/p>\n<p style=\"text-align: justify;\">Bastano certamente queste autentiche &#8220;perle&#8221; per rivelare che tutto il discorso mira a ben altro che a combattere opposti integrismi, nonch\u00e9, evidentemente, a qualificare in modo inequivocabile la seriet\u00e0 e la scientificit\u00e0 degli asserti dei due padri gesuiti. Se continuo a esaminare il loro testo non \u00e8 certo, ormai, per confutarlo, dal momento che si affossa da solo con le sue evidenti contraddizioni e le sue falsificazioni palmari.<\/p>\n<p style=\"text-align: justify;\">Continuo semplicemente per favorire una sempre migliore comprensione della prassi culturale proditoria e compromissoria di cui il testo \u00e8 documento rilevante, sia per la sede che lo ospita che per gli estensori. Dunque, saltando le classificazioni fumose e pseudoscientifiche, vengo alla descrizione del nemico reale, l&#8217;integrismo confessionale.<\/p>\n<p style=\"text-align: justify;\">Con toni da Linneo, i due gesuiti cos\u00ec si esprimono: &#8220;[&#8230;] <em>si ha integrismo confessionale, quando si deduce direttamente ed immediatamente &#8211; cio\u00e8, senza le necessarie mediazioni culturali &#8211; tra la fede, che \u00e9 il campo dell&#8217;assoluto e del trascendente, e la storia, che \u00e8 il campo del relativo, del contingente e dell&#8217;immanente dalla rivelazione cristiana un modello di societ\u00e0 la &#8220;<\/em>societ\u00e0 cristiana<em>&#8221; -, una prassi politica e sociale &#8211; la &#8220;<\/em>politica cristiana<em>&#8221; &#8211; e lo strumento che, per realizzare la societ\u00e0 cristiana, attui la politica cristiana &#8211; il &#8220;<\/em>partito cristiano<em>&#8221; &#8211;<\/em>&#8220;. A questo punto la normale classificazione non basta pi\u00f9, e si introduce la nozione di &#8220;<em>massimo dell&#8217;integrismo<\/em>&#8220;.<\/p>\n<p style=\"text-align: justify;\">Eccone i termini: &#8220;<em>Il massimo dell&#8217;integrismo confessionale si ha quando la &#8220;<\/em>societ\u00e0 cristiana<em>&#8221; sia ritenuta l&#8217;unica deducibile dalla fede cristiana; quando la &#8220;<\/em>politica cristiana<em>&#8221; sia ritenuta l&#8217;unica conforme alla fede; quando il &#8220;<\/em>partito cristiano<em>&#8221; sia ritenuto l&#8217;unico capace di realizzare una societ\u00e0 cristianamente ispirata. Cos\u00ec, per l&#8217;integrismo confessionale, dall&#8217;unica fede &#8211; c&#8217;\u00e8 una sola Incarnazione, un solo Vangelo, una sola Chiesa &#8211; deriverebbe, per &#8220;<\/em>emanazione<em>&#8220;, non per &#8220;<\/em>ispirazione<em>&#8220;, un&#8217;unica forma possibile di impegno sociale per i cristiani ed un unico modello di societ\u00e0 conforme al Vangelo; la necessit\u00e0 dell&#8217;unit\u00e0 politica dei credenti deriverebbe dalla stessa fede.<\/em><\/p>\n<p style=\"text-align: justify;\">&#8220;<em>Si ha ancora integrismo confessionale, quando da una parte si lega l&#8217;autonomia non solo assoluta ma anche relativa delle realt\u00e0 terrestri, e dall&#8217;altra si sostiene che la Gerarchia abbia riti &#8220;<\/em>potere decisionale<em>&#8221; sulle stesse opzioni temporali dei laici. <\/em>[&#8230;]&#8221;<em>Infine, si ha integrismo confessionale, quando, in nome dell&#8217;assoluta verit\u00e0 della fede, non si tollera nemmeno che esista l&#8217;errore, e quindi si combattono le persone che lo professano, negando loro spazio sociale e politico; quando si ritiene che il cristiano, per il fatto di avere nella fede la verit\u00e0 e la luce stessa di Dio, pu\u00f2 solo dare agli altri, ma non pu\u00f2 riceverne nulla; non pu\u00f2 perci\u00f2 n\u00e9 dialogare n\u00e9 confrontarsi, e tanto meno collaborare con i non credenti, i quali non potrebbero apportare mai nulla di valido<\/em>&#8220;.<\/p>\n<p style=\"text-align: justify;\">La descrizione \u00e8 ormai completa: i nomi mancano, ma oltre la caricatura &#8211; come, per esempio, una ipotetica negazione della autonomia &#8220;anche relativa&#8221; delle realt\u00e0 terrestri! -, appare talora in filigrana, spesso in rilievo e non sempre basso, e in qualche caso addirittura in tutto tondo l&#8217;oggetto sempre meno misterioso dell&#8217;attacco, cio\u00e8 il Magistero sociale della Chiesa e una pastorale pi\u00f9 che secolare, se non plurisecolare. Basta, infatti, avere una sia pure minima dimestichezza con i testi del Magistero sociale per sentirne, dietro le deformazioni, l&#8217;eco.<\/p>\n<p style=\"text-align: center;\">* \u00a0* \u00a0*<\/p>\n<p style=\"text-align: justify;\">Chiariti i termini della manovra &#8211; che intende colpire o almeno gettare ombra sulla dottrina del Magistero tradizionale della Chiesa in materia sociale attraverso le eventuali imprecisioni o limitazioni del fedele pi\u00f9 o meno qualificato che se ne fa veicolo -, seguo ancora le evoluzioni dei due padri gesuiti, dal momento che si danno a descrivere i termini differenziati di integrismo e &#8220;<em>identit\u00e0 cristiana<\/em>&#8220;, e quindi, ultimamente, si chiedono se la fede cristiana sia &#8220;<em>per sua natura integrista<\/em>&#8220;.<\/p>\n<p style=\"text-align: justify;\">Sul primo punto asseriscono &#8220;<em>che non \u00e8 integrismo o segno di spirito integrista la volont\u00e0 di ispirarsi alla fede cristiana nella propria azione sociale e politica. Bisogna, infatti, attentamente distinguere tra l&#8217; &#8220;<\/em>ispirarsi<em>&#8221; alla fede nell&#8217;attivit\u00e0 sociale e politica e il &#8220;<\/em>dedurre<em>&#8221; immediatamente e rigorosamente un modello di societ\u00e0 e di azione socio-politica dalla fede. La deduzione immediata e rigorosa d&#8217;un modello di societ\u00e0 dalla fede comporterebbe la delineazione d&#8217;una &#8220;<\/em>societ\u00e0 cristiana<em>&#8221; come unico modello valido di convivenza, oggettivamente ritenuto obbligatorio non solo per i cristiani, ma per tutti. Invece, &#8220;<\/em>ispirare<em>&#8221; la vita sociale e politica alla fede significa che nella costruzione di un modello di societ\u00e0 &#8220;<\/em>umana<em>&#8221; &#8211; cio\u00e8 non dedotta dalla rivelazione, ma fondata sulla ragione e sul vero e sul bene che la ragione mostra essere tali, (quindi fondata su valori umani &#8220;<\/em>comuni<em>&#8221; a tutti e da tutti accettabili) &#8211; il cristiano chiede alla fede solo la luce che essa proietta sull&#8217;uomo, stilla sua origine, sulla sua dignit\u00e0 e sul suo destino, e la forza che i valori cristiani mettono al servizio dell&#8217;uomo, in primo luogo la forza della carit\u00e0.<\/em><\/p>\n<p style=\"text-align: justify;\">&#8220;<em>Ma con quale fine? Non certo per imporre anche a chi non crede la concezione cristiana dell&#8217;uomo, quale risulta dalla fede; ma perch\u00e9 l&#8217;azione dei cristiani a favore dell&#8217;uomo e della societ\u00e0 umana, proprio in quanto \u00e8 illuminata da una luce pi\u00f9 alta di quella della ragione e quindi pi\u00f9 capace di cogliere in profondit\u00e0 il mistero dell&#8217;uomo, serva alla crescita dell&#8217;uomo e della societ\u00e0. Il cristiano, cio\u00e8, ispirando la sua azione politica e sociale ai valori evangelici non intende imporli agli altri o tradurli in modo &#8220;<\/em>confessionale<em>&#8221; nella vita politica e sociale, ma intende tradurli in modo &#8220;<\/em>laico<em>&#8220;, accettabile &#8211; per quanto possibile &#8211; da tutti gli uomini di buona volont\u00e0. <\/em><\/p>\n<p style=\"text-align: justify;\"><em>Egli vuole farne il lievito della societ\u00e0 umana, che da una parte metta in crisi gli pseudo-valori che si rivelano disumanizzanti, e dall&#8217;altra aiuti la societ\u00e0 a divenire pi\u00f9 umana, cio\u00e8 pi\u00f9 giusta e pi\u00f9 fraterna. In altre parole, l&#8217;ispirazione cristiana non tende a far divenire confessionale la societ\u00e0, ma a farla divenire pi\u00f9 umana<\/em>&#8220;.<\/p>\n<p style=\"text-align: justify;\">Rimando il commento e passo al secondo punto, a proposito del quale, dopo avere rilevato &#8220;<em>che non sono mancate nella storia della Chiesa tendenze e forme, anche assai pronunziate e dure, di integrismo<\/em>&#8220;, dichiarano di non volersi porre il problema storico, ma quello teorico: &#8220;<em>Il cristianesimo, cio\u00e8, \u00e8 per sua natura integrista, cosicch\u00e9 le forme storiche d&#8217;integrismo non hanno fatto altro se non rivelarne la natura profonda, oppure non lo \u00e8 per sua natura, cosicch\u00e9 le forme integriste a cui talvolta ha dato origine sono frutto di interpretazioni eccessive o abusive della fede cristiana, di errori e di debolezze dei cristiani, condizionati dalla cultura del tempo nel modo di interpretare e di vivere il rapporto della fede con la storia?<\/em>&#8220;.<\/p>\n<p style=\"text-align: justify;\">Al quesito &#8211; che suona contrappunto alla questione comunista se lo stalinismo sia marxista o una deviazione del marxismo -, ai padri gesuiti &#8220;<em>sembra di dover rispondere con certezza che la fede cristiana non \u00e8 integrista e che, perci\u00f2, ogni tentativo di giustificare tendenze o pratiche integriste con l&#8217;appello alla fede \u00e8 destituito di fondamento, sotto il profilo teologico<\/em>&#8220;, e di potere concludere che &#8220;<em>la ragione specifica della presenza dei cattolici nella vita sociale e politica non \u00e8 la difesa e la propagazione della fede e neppure la difesa dei diritti della Chiesa <\/em>[&#8230;]<em>, ma la creazione d&#8217;una societ\u00e0 umana pi\u00f9 giusta e pi\u00f9 fraterna, da costruire con l&#8217;apporlo dei valori cristiani di giustizia, di fraternit\u00e0 e di carit\u00e0<\/em>&#8220;.<\/p>\n<p style=\"text-align: justify;\">Posto che lo sforzo compiuto dai due redattori de <em>La Civilt\u00e0 Cattolica <\/em>di identificare un integrismo storico \u00e8 miseramente fallito nella segnalazione di zelanti operatori delle direttive pontificie; posto che il tentativo di delineare l&#8217;integrismo dal punto di vista psicologico e soprattutto dottrinale si \u00e8 tradotto in una silloge male truccata di affermazioni del Magistero ecclesiastico tradizionale; posto tutto questo, forse non meriterebbero attenzione particolare i passaggi citati, che non escono dall&#8217;ottica falsa e falsificante che ho brevemente denunciato come tesa a sottoporre il cattolicesimo al <em>pendant <\/em>del processo di destalinizzazione cui \u00e8 stato ed \u00e8 sottoposto il marxismo &#8211; leninismo.<\/p>\n<p style=\"text-align: justify;\">Mi spingono a insistere, per\u00f2, come ho gi\u00e0 detto, e l&#8217;importanza del tema e la ormai usurpata autorevolezza della rivista, che ospita le tesi anodine che ho ampiamente riportato. Nella impossibilit\u00e0 oggettiva di sottoporre tutte le affermazioni a esame adeguato, concentrer\u00f2 la mia attenzione sul termine &#8220;fede&#8221;, che ampiamente e reiteratamente ricorre, a fondare la distanza tra i principi e la realt\u00e0 sociale e la non deducibilit\u00e0 di una dottrina ampiamente definita e univoca.<\/p>\n<p style=\"text-align: justify;\">Escludo che il termine stia a significare quanto precisa padre Reginaldo Garrigou-Lagrange, secondo cui &#8220;<em>in senso tecnico \u00e8 l&#8217;adesione dell&#8217;intelletto, sotto l&#8217;influenza della Grazia, a una verit\u00e0 rivelata da Dio, non per ragioni d&#8217;intrinseca evidenza, ma per l&#8217;autorit\u00e0 di colui che la rivela<\/em>&#8221; (12).<\/p>\n<p style=\"text-align: justify;\">Se la fede cui si fa riferimento nell&#8217;articolo de <em>La Civilt\u00e0 Cattolica <\/em>fosse questa, l&#8217;asserto dei due padri gesuiti potrebbe parere fondato, anche se ne risentirebbe abbondantemente l&#8217;articolo stesso, inutile e talora privo di senso! La situazione non migliora se dalla fede come adesione dell&#8217;intelletto passiamo alla fede come indicante una verit\u00e0 rivelata da Dio e non intrinsecamente evidente, cio\u00e8 un mistero. Al limite, infatti, si configura un biblismo di marca squisitamente protestantica; e non mi pare che, nonostante tutta la cattiva volont\u00e0, si possa accusare i cattolici fedeli di essere potenziali o almeno tendenziali seguaci di Cromwell!<\/p>\n<p style=\"text-align: justify;\">Resta la possibilit\u00e0 che il termine sia assunto in senso lato, a indicare la dottrina cristiana nel suo insieme di verit\u00e0 necessarie alla salvezza. Al dire di san Tommaso, in un testo omiletico, tali verit\u00e0 sono tre: &#8220;<em>Per conseguire la salvezza, l&#8217;uomo deve conoscere alcune nozioni di base: cosa credere, cosa desiderare e infine cosa fare. Alla prima esigenza ha risposto il Simbolo, che raccoglie gli articoli della rivelazione; alla seconda, la preghiera del <\/em>Padre nostro<em>; e alla terza, la legge<\/em>&#8221; (13).<\/p>\n<p style=\"text-align: justify;\">Se questo \u00e8 il senso del termine &#8220;fede&#8221; in tutto il testo dell&#8217;articolo che sto esaminando, non riesco a vedere in che cosa consista la inopportunit\u00e0 e la impugnabilit\u00e0 del dedurre elementi di dottrina sociale dalla legge, dal decalogo, rivelazione di necessit\u00e0 morale, resa cio\u00e8 necessaria dall&#8217;offuscamento della legge naturale nel cuore dell&#8217;uomo in seguito al peccato originale.<\/p>\n<p style=\"text-align: justify;\">E&#8217; inopportuno e improprio che la societ\u00e0 umana si ordini secondo la legge naturale, riflesso di quella eterna e modello di quella positiva? Se non si hanno dubbi sulla esistenza di una natura e di un ordine divino, dov&#8217;\u00e8 l&#8217;errore nel dedurre dal decalogo &#8211; parte della fede cristiana &#8211; gli elementi per restaurare la vita sociale, dal momento che non si tratta di mistero, ma di rivelazione di necessit\u00e0 morale, e che il pervenire ai suoi precetti non \u00e8 impossibile alla retta ragione, anche se reso tanto difficile dal peccato originale da necessitare del richiamo divino?<\/p>\n<p style=\"text-align: justify;\">Quando, se non in pratiche liminali, mai teorizzate, e sempre censurate, si \u00e8 proposta la coazione al mistero? Ma \u00e8 illecita la difesa del razionale e la sua promozione anche sociale? E&#8217; un mistero che Dio c&#8217;\u00e8? che si deve coglierne la volont\u00e0? E&#8217; un mistero la famiglia monogamica e indissolubile? e la gerarchia sociale? Sono un mistero il rispetto della vita innocente o il fine dell&#8217;atto sessuale? E&#8217; un mistero il rispetto dei beni altrui? della fama altrui, della donna d&#8217;altri?<\/p>\n<p style=\"text-align: justify;\">Se tutto questo non \u00e8 mistero, ma legge di natura, non si pu\u00f2 pretenderne il rispetto da parte della societ\u00e0, cio\u00e8 dai nostri conviventi? O il pretenderlo \u00e8 integrismo, perch\u00e9 si tratta di materia ricordata da Dio nel decalogo, e quindi parte della fede in senso lato? E se la pratica della legge di natura \u00e8 difficile &#8211; e ordinariamente perfino impossibile -, \u00e8 integrismo ricordare il peccato originale, la redenzione e la grazia, la Chiesa e i sacramenti, e favorire il loro riconoscimento anche sociale? Oppure bisogna astenersene, per non correre rischio di &#8220;<em>far divenire confessionale la societ\u00e0<\/em>&#8220;?<\/p>\n<p style=\"text-align: justify;\">E se il riconoscimento sociale della verit\u00e0, non solo naturale ma anche rivelata in senso stretto, ha prove anche storiche del suo carattere benefico, per la salvezza degli uomini e la gloria di Dio, come non essere propagandisti di tale riconoscimento e promotori della conversione della societ\u00e0? Di pi\u00f9. L&#8217;integrismo \u00e8 forse il tentativo di applicare alla societ\u00e0 i princ\u00ecpi che si ricavano da quell&#8217;ormai pi\u00f9 che secolare commento ed esplicitazione del decalogo che \u00e8 la dottrina sociale della Chiesa?<\/p>\n<p style=\"text-align: justify;\">Oppure, come scrive mons. Bettazzi, &#8220;<em>l&#8217;idea antica di una &#8220;<\/em>dottrina sociale cristiana<em>&#8220;, che proponesse una volta per sempre il modello di una &#8220;<\/em>societ\u00e0 cristiana<em>&#8220;, \u00e8 ormai superata<\/em>&#8221; (14), a partire dalla <em>Octogesima adveniens <\/em>del regnante Pontefice, nella quale, sempre secondo il vescovo di Ivrea, &#8220;<em>il Papa insinua il superamento di una Dottrina Sociale della Chiesa, in nome dei &#8220;<\/em>princ\u00ecpi cristiani<em>&#8221; a cui ispirarsi<\/em>&#8220;? (15).<\/p>\n<p style=\"text-align: justify;\">Come possono espressioni di questo tipo non scandalizzare profondamente, e non sollevare problemi gravissimi? Come pu\u00f2 una &#8220;<em>parte integrante della visione cristiana della vita<\/em>&#8221; (16) essere superata, senza danno per tutta la visione cristiana della vita? Come pu\u00f2 contrapporsi ad altri &#8220;<em>principi cristiani<\/em>&#8220;? Forse Papa scaccia Papa ed enciclica enciclica?<\/p>\n<p style=\"text-align: center;\">* \u00a0* \u00a0*<\/p>\n<p style=\"text-align: justify;\">Nella morale certezza di avere costellato le mie considerazioni di domande retoriche, credo di potere concludere che certi tentativi di espungere un presunto integrismo dalla Chiesa e dalla sua dottrina si risolvono in una &#8220;dis-integrazione&#8221; della fede, contro la quale disintegrazione bisogna lottare apertamente e con coraggio, facendo proprio l&#8217;ammonimento: di Sant&#8217;Agostino: &#8220;<em>Sine superbia de veritate praesumite. Senza superbia siate fieri della verit\u00e0!<\/em>&#8221; (17).<\/p>\n<p style=\"text-align: justify;\"><strong>Note:<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>(1)<\/strong> Cfr. il mio <em>Il &#8220;compromesso culturale&#8221;<\/em>, in <em>Cristianit\u00e0<\/em>, anno V, n. 31, novembre 1977.<\/p>\n<div align=\"center\">\n<div align=\"justify\">\n<div align=\"center\">\n<div align=\"justify\">\n<div align=\"center\">\n<div align=\"justify\">\n<div align=\"center\">\n<div align=\"justify\">\n<div><strong>(2)<\/strong> Cfr. BARTOLOMEO SORGE S. J. &#8211; GIUSEPPE DE ROSA S. J., <em>Fede cristiana ed integrismo<\/em>, in <em>La Civilt\u00e0 Cattolica<\/em>, anno 129 n. 3064, 18-2-1978, pp. 313-324. Tutte le citazioni senza indicazioni di fonte sono tratte da questo articolo.<\/div>\n<div><strong>(3)<\/strong> SAN PIO X, Motu proprio <em>Sacrorum Antistitum<\/em>, dell&#8217;l-9-1910, in Actes, <em>Editions de La documentation catholique<\/em>, Parigi, s.d., vol. V, p. 141.<\/div>\n<div><strong>(4)<\/strong> I testi sono riportati in RAYMOND DULAC, <em>Simple note sur le Sodalitium Pianum<\/em>, in <em>La pens\u00e9e catholique. <\/em><em>Cahiers de synth\u00e8se<\/em>, n. 23, 1952, pp. 89-90.<\/div>\n<div><strong>(5)<\/strong> Ibid., p. 91. Dello stesso autore, sullo stesso argomento, cfr. <em>Les devoirs du journaliste catholique selon le bienheureux Pie X<\/em>, ibid., pp. 68-87.Cfr. anche JEAN MADIRAN, <em>L&#8217;integrisme. Histoire d&#8217;un histoire<\/em>, Nouvelles \u00c9ditions Latines, Parigi 1964 (con le osservazioni di D.A.C., <em>O integrismo. Caviloso mito publicitario<\/em>, in <em>Catolicismo<\/em>, anno XIV, n. 164, agosto 1964); EMILE POULAT, <em>Int\u00e9grisme et catholicisme int\u00e9gral<\/em>, Casterman, Tournai 1969 e FRAN\u00c7OIS DUCAUD-BOURGET, <em>La ma\u00e7onnerie noire ou la v\u00e9rit\u00e9 sur l&#8217;int\u00e9grisme d&#8217;apr\u00e8s les documents authentiques du Proc\u00e8s de Beatification de S. Pie X<\/em>, Nicolas-Imbert td., Niort 1974.<\/div>\n<div><strong>(6)<\/strong> Testi in FRAN\u00c7OIS DUCAUD-BOURGET, op. cit., pp. 24-25.<br \/>\n<strong>(7)<\/strong> Cfr. <em>Cristianit\u00e0<\/em>, anno IV, n. 19-20, settembre-dicembre 1976.<br \/>\n<strong>(8)<\/strong> SAN BERNARDO DI CHIARAVALLE <em>Del dovere di amare Dio<\/em> e <em>Sermoni sul Cantico dei Cantici<\/em>, trad. it., UTET, Torino 1947, P. 19.<br \/>\n<strong>(9)<\/strong> PAOLO VI, Enciclica <em>Ecclesiam Suam<\/em>, del 6-8-1964, in <em>Insegnamenti <\/em>(1963-1970). Encicliche, p. 42.<br \/>\n<strong>(10)<\/strong> <em>Ibidem<\/em>.<br \/>\n<strong>(11)<\/strong> <em>Ibidem<\/em>.<br \/>\n<strong>(12)<\/strong> P. REGINALDO GARRIGOU-LAGRANGE O. P., sub voce, in <em>Enciclopedia Cattolica<\/em>, vol. V, col. 1076.<br \/>\n<strong>(13)<\/strong> SAN TOMMASO D&#8217;AQUINO, <em>Commento ai due precetti della carit\u00e0 e ai dieci comandamenti<\/em>, in <em>Opuscoli teologico-spirituali<\/em>, trad. it., Edizioni Paoline, Alba 1976, p. 169.<br \/>\n<strong>(14)<\/strong> MONS. LUIGI BETTAZZI, <em>al di l\u00e0&#8230; al di dentro&#8230; lettera a un amico un p\u00f2 materialista e ateo<\/em>. Con appendici, Gribaudi, Torino 1978, p. 102.<br \/>\n<strong>(15)<\/strong> Ibid., p. 109.<br \/>\n<strong>(16)<\/strong> GIOVANNI XXIII, Enciclica <em>Mater et Magistra<\/em>, del 15-5-1961, in FRANCESCO VITO, <em>Introduzione alle encicliche e ai messaggi sociali. Da Leone XIII a Giovanni XXIII<\/em>, Vita e Pensiero, Milano 1962, p. 309.<br \/>\n<strong>(<\/strong><strong>17)<\/strong> SANT&#8217;AGOSTINO, <em>Contra litteras Petiliani<\/em>, 1, 29, 31, in PL 43, 259.<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Articolo\u00a0pubblicato nel 1978 sul n. 37 di Cristianit\u00e0 Il contributo de &#8220;La Civilt\u00e0 Cattolica&#8221; al &#8220;compromesso culturale&#8221; di Giovanni Cantoni<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lanti-integrismo-come-disintegrazione-della-fede\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":33229,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,45],"tags":[824,555,789],"class_list":["post-918","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chiesa","category-progressismo-cattolico","tag-anti-integrismo","tag-gesuiti","tag-progressismo-cattolico-2","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&#039;anti-integrismo come disintegrazione della fede - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lanti-integrismo-come-disintegrazione-della-fede\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;anti-integrismo come disintegrazione della fede - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lanti-integrismo-come-disintegrazione-della-fede\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2005-07-16T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-04-20T15:14:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/Sorge.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"119\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"30 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lanti-integrismo-come-disintegrazione-della-fede\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lanti-integrismo-come-disintegrazione-della-fede\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"L&#8217;anti-integrismo come disintegrazione della fede\",\"datePublished\":\"2005-07-16T22:00:00+00:00\",\"dateModified\":\"2016-04-20T15:14:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lanti-integrismo-come-disintegrazione-della-fede\\\/\"},\"wordCount\":6161,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lanti-integrismo-come-disintegrazione-della-fede\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/07\\\/Sorge.jpg\",\"keywords\":[\"anti-integrismo\",\"gesuiti\",\"progressismo cattolico\"],\"articleSection\":[\"Chiesa\",\"Progressismo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lanti-integrismo-come-disintegrazione-della-fede\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lanti-integrismo-come-disintegrazione-della-fede\\\/\",\"name\":\"L'anti-integrismo come disintegrazione della fede - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lanti-integrismo-come-disintegrazione-della-fede\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lanti-integrismo-come-disintegrazione-della-fede\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/07\\\/Sorge.jpg\",\"datePublished\":\"2005-07-16T22:00:00+00:00\",\"dateModified\":\"2016-04-20T15:14:21+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lanti-integrismo-come-disintegrazione-della-fede\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lanti-integrismo-come-disintegrazione-della-fede\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lanti-integrismo-come-disintegrazione-della-fede\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/07\\\/Sorge.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/07\\\/Sorge.jpg\",\"width\":119,\"height\":200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lanti-integrismo-come-disintegrazione-della-fede\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&#8217;anti-integrismo come disintegrazione della fede\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'anti-integrismo come disintegrazione della fede - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lanti-integrismo-come-disintegrazione-della-fede\/","og_locale":"it_IT","og_type":"article","og_title":"L'anti-integrismo come disintegrazione della fede - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lanti-integrismo-come-disintegrazione-della-fede\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2005-07-16T22:00:00+00:00","article_modified_time":"2016-04-20T15:14:21+00:00","og_image":[{"width":119,"height":200,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/Sorge.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"30 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lanti-integrismo-come-disintegrazione-della-fede\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lanti-integrismo-come-disintegrazione-della-fede\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"L&#8217;anti-integrismo come disintegrazione della fede","datePublished":"2005-07-16T22:00:00+00:00","dateModified":"2016-04-20T15:14:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lanti-integrismo-come-disintegrazione-della-fede\/"},"wordCount":6161,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lanti-integrismo-come-disintegrazione-della-fede\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/Sorge.jpg","keywords":["anti-integrismo","gesuiti","progressismo cattolico"],"articleSection":["Chiesa","Progressismo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lanti-integrismo-come-disintegrazione-della-fede\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lanti-integrismo-come-disintegrazione-della-fede\/","name":"L'anti-integrismo come disintegrazione della fede - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lanti-integrismo-come-disintegrazione-della-fede\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lanti-integrismo-come-disintegrazione-della-fede\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/Sorge.jpg","datePublished":"2005-07-16T22:00:00+00:00","dateModified":"2016-04-20T15:14:21+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lanti-integrismo-come-disintegrazione-della-fede\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lanti-integrismo-come-disintegrazione-della-fede\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lanti-integrismo-come-disintegrazione-della-fede\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/Sorge.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/Sorge.jpg","width":119,"height":200},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lanti-integrismo-come-disintegrazione-della-fede\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"L&#8217;anti-integrismo come disintegrazione della fede"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/918","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=918"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/918\/revisions"}],"predecessor-version":[{"id":33231,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/918\/revisions\/33231"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/33229"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=918"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=918"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=918"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}