{"id":90,"date":"2004-11-10T11:57:04","date_gmt":"2004-11-10T10:57:04","guid":{"rendered":""},"modified":"2024-01-05T15:42:12","modified_gmt":"2024-01-05T14:42:12","slug":"storia-del-fondamentalismo-islamico","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/storia-del-fondamentalismo-islamico\/","title":{"rendered":"Storia del fondamentalismo islamico"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-32696 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2004\/11\/Mecca.jpg\" alt=\"\" width=\"284\" height=\"213\" \/>Abstract:\u00a0 s<\/strong><em>toria del fondamentalismo islamico. Gli ultimi decenni dell&#8217;ottocento sono stati contrassegnati dal risveglio del mondo islamico, fomentato da personalit\u00e0 religiose e intellettuali rappresentative del movimento riformista ortodosso. Si tratt\u00f2 di un fenomeno politico e religioso ori-ginato dall&#8217;unione di due correnti di pensiero: la prima, di ispirazione religiosa, si fondava sull&#8217;ideologia riformista nata alla fine del settecento; la seconda era origine profana e di orientamento modernista.<\/em><\/span><\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: center;\">Articolo pubblicato su\u00a0<a href=\"https:\/\/www.ebay.it\/itm\/334689067501\" target=\"_blank\" rel=\"noopener\"><strong>MILLENOVECENTO<\/strong><\/a>\u00a0n.12 ottobre 2003<\/p>\n<h3 style=\"text-align: center;\"><span style=\"color: #000000;\">Allah \u00e8 tutto<\/span><\/h3>\n<h4 style=\"text-align: center;\"><strong>Breve storia del fondamentalismo islamico\/1<\/strong><\/h4>\n<div style=\"text-align: justify;\">\n<h4 style=\"text-align: center;\"><strong>LE ORIGINI E LO SVILUPPO<\/strong><\/h4>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-32696\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2004\/11\/Mecca.jpg\" alt=\"Mecca\" width=\"250\" height=\"187\" \/><\/p>\n<p style=\"text-align: center;\">Di <strong>Mirella Galletti <\/strong>(*)<\/p>\n<\/div>\n<p style=\"text-align: justify;\">Gli ultimi decenni dell&#8217;ottocento sono stati contrassegnati dal risveglio del mondo islamico, fomentato da personalit\u00e0 religiose e intellettuali rappresentative del movimento riformista ortodosso. Si tratt\u00f2 di un fenomeno politico e religioso ori-ginato dall&#8217;unione di due correnti di pensiero: la prima, di ispirazione religiosa, si fondava sull&#8217;ideologia riformista nata alla fine del settecento; la seconda era origine profana e di orientamento modernista. Mentre le energie impegnate sotto il segno nascita (Nahda) cercavano di su pera re i ritardi socioculturali del mondo islamico, le ricerche ispirate a motivazioni religiose tentava no di favorire una dinamica di rinnova mento e di riforma (Islah) nella prospettiva di un&#8217;armonizzazione tra la tradizione e la vita moderna.<\/p>\n<p style=\"text-align: justify;\"><strong>IL WAHABISMO FU ADOTTATO IN ARABIA<\/strong>\u00a0nella seconda met\u00e0 del settecento dall\u2019emergente dinastia saudita. Propugnava un puritanesimo intransigente teso a ri-portare l&#8217;lslam alle origini, a ricondurre il culto e il dogma alla purezza originale. Gli elementi di modernit\u00e0 erano dati dalla volont\u00e0 di rivitalizzare nei musulmani una dinamica socioculturale e politica che li riportasse alla grandezza del passato. E fu quindi un&#8217;arma contro il colonialismo. L&#8217;incontro dell&#8217;lslam con i modelli culturali europei sar\u00e0 il tema dominante del dibattito nell&#8217;ottocento e vi entrarono a pieno titolo lo spirito critico, razionalit\u00e0, libera ricerca, individualismo, progresso sociale. Fu predominante nella generazione tra il 1880 e il 1920 il tema del ritardo dei popoli musulmani in rapporto all&#8217;Europa.<\/p>\n<p style=\"text-align: justify;\">I grandi riformatori Giamal al-Din al-Afghani e Muhammad Abduh cercarono di dare una risposta alla sfida della modernit\u00e0 e dei blocchi psicoculturali propri delle societ\u00e0 di tradizione islamica. Ma \u00e8 nella prima met\u00e0 del ventesimo secolo che emergono i movimenti islamici radicali come i Fra-telli musulmani, che iniziano la loro attivit\u00e0 in Egitto nel 1929 sotto la guida di Hasan al-Banna, prototipo degli odierni movimenti islamici: al Banna sosteneva che l&#8217;lslam ha una valenza sia pubblica sia privata e l&#8217;obiettivo dell&#8217;organizzazione era l&#8217;applicazione di un sistema islamico di governo e di giurisprudenza: al-Banna in-centivava la vocazione missionaria del movimento con la formazione di predicatori e con una struttura ramificata nella societ\u00e0 con proprie scuole, imprese, cooperative. Fu quindi un movimento dinamico, con una crescente influenza nel mondo islamico. Lo stato era percepito come una entit\u00e0 atea e materialista e gli venne contrapposta un contro-societ\u00e0 fondata sui principi islamici. Il movimento fu duramente represso, anche se molti militanti occupavano centri di potere nelle scuole e nel campo dell&#8217;istruzione, nell&#8217;amministrazione e nell&#8217;esercito.<\/p>\n<p style=\"text-align: justify;\">Il filosofo iraniano Ali Shariati \u00e8 considerato uno del principali ideologi del rinnovamento e ha ispirato profondamente la rivoluzione islamica. Riteneva che il popolo in Iran fosse oppresso da tre poteri: il governo, il capitale, la religione. Quando condannava la religione si riferiva all&#8217;uso strumentale che ne venne fatto nel periodo safavide (dal 16\u00b0 al 18\u00b0 secolo), in cui lo sciismo di vent\u00f2 religione di stato. Soprat tutto accus\u00f2 il regime dello sci\u00e0 Muhammad Reza Pahlavi di ser virsi dell&#8217;lslam per consolidare il potere e denunci\u00f2 quei religiosi che avevano accettato di soste nere la politica della corona.<\/p>\n<p style=\"text-align: justify;\"><strong>ALI SHARIATI CAMBI\u00d2 IL PENSIERO ISLAMICO<\/strong><b>\u00a0<\/b>iraniano nel riattualizzare lo sciismo, cercando di adattarlo ai tempi moderni, alla lotta delle classi oppresse e di farne uno strumento della lotta antimperialista. La sua dottrina ha superato le frontiere dell&#8217;Iran e anche dello sciismo, nella ricerca di una identit\u00e0 e di una dignit\u00e0 perduta. Originario di Mashad, figlio di un noto teologo, le sue lezioni all&#8217;universit\u00e0 sulle origini dello sciismo e sulla vita dei mar tiri e del Profeta erano considerate troppo sovversive. Nel 1964, con l&#8217;esilio di Khomeini e l&#8217;arre sto dei capi religiosi, venne chiamato come predicatore nel nuovo centro culturale islamico di Teheran, costruito dalle genti del bazar. La sua oratoria attir\u00f2 folle sempre pi\u00f9 numerose, il pubblico era formato soprattutto da re ligiosi, studenti e commercianti. Ali Shariati sosteneva che il mar tirio di Husein a Kerbela era un fenomeno attuale e che il popolo iraniano allora come adesso era vittima della tirannia del regime al potere.<\/p>\n<p style=\"text-align: justify;\">L&#8217;attualizzazione dello sciismo gli valse carcere e torture. Mor\u00ec in esilio a Londra nel 1977. E&#8217; considerato un martire. Durante la rivoluzione islamica molti giovani manifestarono agitando il ritratto di Svariati oltre che quello di Khomeini e degli altri capi religiosi. L&#8217;idea missionaria si \u00e8 sviluppata nel mondo islamico nella prima met\u00e0 del XX secolo e gli \u00e8 succeduta una presa di coscienza dei nuovi imperativi dell&#8217;apostolato all&#8217;interno e all&#8217;esterno della umma (comunit\u00e0), in base alle necessit\u00e0 dell&#8217;epoca e delle possibilit\u00e0 offerte dalle tecnologie moderne (mass media). Il nuovo slancio missionario testimonia la fedelt\u00e0 all&#8217;lslam originario (come esprimono le diverse tendenze fondamenta liste), la volont\u00e0 di iniettare una dinamica socio-culturale e politica comparabile a quella vissuta dalla civilt\u00e0 islamica nella sua grandezza originaria e la tentazione di formare un insieme monolitico. Negli anni settanta la rinascita fu stimolata dal boom petrolifero che ha accresciuto enormemente la ricchezza e il potere di molti stati islamici come quelli saudita e libico, che hanno finanziato l&#8217;ascesa islamica.<\/p>\n<p style=\"text-align: justify;\">Questo sviluppo fu sostenuto an che da altissi mi tassi di crescita demografica, spesso oltre il 2-3%. Nel 1980 i mu sul mani costituivano il 18% della popolazione mondiale, si prevede che nel 2025 supereranno il 30%. Il radicalismo islamico \u00e8 emerso sia a livello politico sia negli aspetti della vita quotidiana legati alla religione (la frequentazione della moschea, l&#8217;osservanza del digiuno del Ramadan, il rifiuto dell&#8217;alcol) con la proliferazione della letteratura religiosa, la nascita di nuove associazioni e di movimenti che intendono islamizzare la popolazione.<\/p>\n<p style=\"text-align: justify;\"><strong>NELLO STESSO PERIODO l&#8217;ISLAM<\/strong><b>\u00a0<\/b>si \u00e8 imposto anche nella vita pubblica con partiti, simboli, slogan, ideologie, esponenti legati a doppio filo alla religione. Governi e movimenti di opposizione hanno cercato di rafforzare la propria legittimit\u00e0 e di mobilitare la popolazione. E\u2019 inoltre importante la scelta dei termini. \u00abIl fatto che gli esponenti del radicalismo musulmano abbiano adottato il nome di islamiyyun (letteralmente &#8220;islamici&#8221;) al posto del comune muslimun (&#8220;musulmani&#8221;) sta a significare l&#8217;importanza che essi attribuiscono all&#8217;aspetto istituzionale della religione\u00bb. (1) Nel mondo musulmano, secolarizzazione o laicit\u00e0 dello stato significano perdere il proprio patrimonio, non solo religioso, ma di identificazione sociale e culturale, una perdita che equi vale alla colonizzazione culturale dell&#8217;occidente.<\/p>\n<p style=\"text-align: justify;\">Non a caso quando la Turchia kemalista ha avviato la secolarizzazione del paese riducendo l&#8217;influenza dell&#8217;lslam, ha contemporaneamente com piuto una riappropriazione dei miti nazionalisti e culturali dell&#8217;antico Turan, sede della civilt\u00e0 turca. Nel 1973 la guerra arabo-israeliana e l&#8217;embargo del petrolio e nel 1978-79 la rivoluzione iraniana produssero un profondo senso di orgoglio e potere. Altrettanto importanti furono gli effetti negativi della modernizzazione, quali la vertiginosa urba-nizzazione. Nelle citt\u00e0 sovraffollate si assisteva alla rottura della famiglia tradizionale e dei valori religiosi e sociali, e si finiva con l&#8217;adottare uno stile di vita occidentale. considerato come fonte di declino. morale (corruzione, disoccupazione, distribuzione ineguale della ricchezza). Per questo l&#8217;integralismo islamico apparve come la sola alternativa a un modello occidentale cui sembrava ormai impensabile ispirarsi sperando di preservare la propria identit\u00e0. E, come ha sottolineato, suscitando scalpore, Samuel Huntington ci siamo avviati non verso il dialogo, ma verso \u00ablo scontro delle civilt\u00e0\u00bb (2).<\/p>\n<p style=\"text-align: justify;\"><strong>NELL&#8217;ULTIMO QUARTO DEL MILLENOVECENTO,<\/strong>\u00a0l&#8217;integralismo antioccidentale si \u00e8 sviluppato impetuosamente. Ma la comunit\u00e0 islamica, con oltre un miliardo di fedeli, non rappresenta un mondo monolitico. L&#8217;occidente ha raccolto quanto ha contribuito a seminare: nella sua lotta contro il nazionalismo progressista, che ha per modello il nasserismo sostenuto dall&#8217;Urss, si era alleato alla propaganda islamica della monarchia saudita, nemica giurata del regime egiziano. Sostenendo i Fratelli musulmani contro il presidente egiziano Gamal Abdel Nasser, Riad finanziava e accoglieva sul proprio suolo, con l&#8217;aiuto della Ci a, la maggior parte della nebulosa internazionale del l&#8217;integralismo islamico. AI mo mento della decomposizione del nasserismo, i regimi della restaurazione pro-occidentale avevano riprodotto questa alleanza per combattere la sinistra e i sostenitori dell\u2019antico regime.<\/p>\n<p style=\"text-align: justify;\"><strong>A PARTIRE DAGLI ANNI SETTANTA L&#8217;ISLAMIZZAZIONE<\/strong>\u00a0ha toccato qua- si tutte le societ\u00e0 musulmane dal Marocco all&#8217;Indonesia e dalla Nigeria al Kazakistan. Di norma si \u00e8 manifestata prima in campo culturale, per poi diffondersi nella sfera sociale e politica. Agli inizi del XXI secolo tutti i paesi musulmani sono pi\u00f9 islamici dal punto di vista culturale, sociale e politico di quanto lo fossero stati un quarto di secolo prima. Un elemento fondamentale del processo di islamizzazione \u00e8 lo sviluppo di organizzazioni sociali islamiche, con particolare attenzione alla fondazione di scuole islamiche e all&#8217;espansione dell&#8217;influenza islamica nelle strutture scolastiche statali. Questi gruppi danno vita a una societ\u00e0 civile islamica che cerca di affiancare e soppiantare le istituzioni della societ\u00e0 civile laica.<\/p>\n<p style=\"text-align: justify;\"><strong>L&#8217;ATTIVISMO ISLAMICO<\/strong>\u00a0ha anche una forza socio-politica che opera all&#8217;interno del sistema, in organizzazioni quali scuole, ospedali, banche, case editrici e offre una vasta gamma di servizi sociali. Una nuova generazione di quadri medio-alti, con istruzione moderna, pi\u00f9 favorevole all&#8217;lslam che alla secolarizzazione, si \u00e8 diffusa tra medici, ingegneri, insegnanti e operatori sociali che cercano di applicare i modelli di societ\u00e0 islamica. D&#8217;altra parte, la richiesta di democratizzazione politica ha comportato sia una maggiore liberalizzazione sia l&#8217;acuirsi della repressione.<\/p>\n<p style=\"text-align: justify;\"><strong>QUANDO I GOVERNI<\/strong><b>\u00a0<\/b>hanno avviato l\u2019apertura del sistema politico, le organizzazioni islamiche hanno partecipato alle elezioni e sono emerse come la principale forza di opposizione. Come si \u00e8 verificato in Egitto, Tunisia, Giordania. Nei primi anni novanta, in Algeria, quando il Fronte islamico della salvezza vinse le elezioni municipali e parlamentari, intervenne l&#8217;esercito. I successi dei movimenti islamici nelle elezioni politiche hanno indotto i governi algerino, egiziano, tunisino a dare vita alla repressione politica con il pretesto che i fondamentalisti religiosi usano il sistema politico per giungere al potere per poi imporre la propria visione. Taluni indicano il fondamentalismo islamico come la maggiore minaccia alla stabilit\u00e0 sociale e politica mondiale. Altri invece sottolineano la distinzione tra autentici movimenti populisti desiderosi di partecipazione e coloro che rigettano ogni soluzione pacifica nella ricerca della rivoluzione violenta per rovesciare i governi. Dopo anni di lotta anticomunista e antinazionalista condotta sotto la bandiera dell&#8217;lslam piuttosto che quella della democrazia liberale, il nazionalismo in bancarotta e la sinistra impotente hanno lasciato campo libero all&#8217;integralismo islamico (3)<\/p>\n<p style=\"text-align: justify;\"><strong><i>*<\/i><\/strong><em>MIRELLA GALLETTI si occupa di medio Oriente da circa 30 anni. Collabora con diverse riviste scientifiche ed \u00e8 autrice di saggi e ricerche<\/em><\/p>\n<h4 style=\"text-align: justify;\"><b>Note:<\/b><\/h4>\n<p style=\"text-align: justify;\"><b><\/b><b>(1)<\/b> Paolo Branca,<span style=\"color: #0000ff;\">\u00a0<\/span><a href=\"https:\/\/www.ibs.it\/musulmani-ebook-paolo-branca\/e\/9788815330185\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\"><em>I musulmani<\/em><\/span>,<\/a> Bologna, Il Mulino, 2000, p. 117 lino, 2000, p. 117.<\/p>\n<div style=\"text-align: justify;\">\n<p><b>(2)<\/b> Samuel P. Huntington,\u00a0<a href=\"https:\/\/www.garzanti.it\/libri\/samuel-p-huntington-lo-scontro-delle-civilta-e-il-nuovo-ordine-mondiale-9788811674993\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\"><em>Lo scontro delle civilt\u00e0 e il nuovo ordine mondiale<\/em><\/span><\/a>, Milano, Garzanti, 1997, pp. 499.<\/p>\n<\/div>\n<div style=\"text-align: justify;\">\n<p><b>(3)<\/b> Gilbert Achcar,\u00a0<a href=\"https:\/\/www.monde-diplomatique.fr\/1997\/06\/ACHCAR\/4759\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\"><em>Le monde arabe orphelin de la d\u00e9mocratie<\/em><\/span>,<\/a> Le Monde diplomatique, Juin 1997, p. 7<\/p>\n<p style=\"text-align: center;\">______________________________<\/p>\n<h4 style=\"text-align: center;\"><strong>IL CORANO COME MODELLO<\/strong><\/h4>\n<p>Il Corano \u00e8 il libro sacro dell&#8217;lslam, ma anche il modello su cui si fondano la lingua araba e il diritto musulmano. E&#8217; l&#8217;asse portante su cui si manifesta il nazionalismo arabo e delle popolazioni musulmane non arabe (Iran, Afghani-stan, Pakistan, Indonesia, e cos\u00ec via). L&#8217;lslam \u00e8 una religione che \u00e8 alla base di un sistema socio-culturale e che ha una funzione ideologica globalizzante. E&#8217; un elemento di emancipazione politico-culturale per i popoli islamici che, grazie al petrolio, hanno preso coscienza di essere una potenza economica e vogliono quindi emergere anche come potenza politica.<\/p>\n<p>L&#8217;lslam \u00e8 quindi un tramite perch\u00e9 rappresenta l&#8217;unico patrimonio autoctono e il principale strumenti di mobilitazione delle masse per la riappropriazione dell&#8217;identit\u00e0 nazionale. L&#8217;lslam \u00e8 nato nell&#8217;Hegiaz, regione della penisola araba, e si \u00e8 espanso dall&#8217;oceano Atlantico all&#8217;Indonesia. I popoli del Libro, cio\u00e8 i credenti nella Bibbia (ebrei e cristiani), poterono praticare le proprie fedi e parteciparono alla costruzione dello stato islamico. L&#8217;lslam incarna l&#8217;identit\u00e0 nazionale, la linfa del nazionalismo delle societ\u00e0 arabe e musulmane. All&#8217;lslam si richiamano i governanti della conservatrice Arabia Saudita e del rivoluzionario Iran.<\/p>\n<p>La moschea non rappresenta solo il ruolo di culto, ma il centro sociale e culturale dove la comunit\u00e0 trova una reale possibilit\u00e0 di aggregazione. Negli anni della giovinezza il leader libico Muammar Gheddafi frequentava una scuola in citt\u00e0, lontano dai genitori; non avendo il denaro per prendere in affitto una stanza, dormiva nella moschea. Nel 1978 in Iran i soldati che avevano disertato per non sparare sulla popolazione che manifestava contro lo sci\u00e0 trovarono rifugio nelle moschee per vari mesi. In Egitto molti studenti studiano nelle moschee, poich\u00e9 la povert\u00e0 e il sovraffollamento impediscono loro di studiare in casa.<\/p>\n<p>L&#8217;lslam contiene elementi di egualitarismo e di giustizia sociale.E&#8217; proclamato religione di stato in quasi tutti i paesi musulmani dove le costituzioni sanciscono che le leggi devono conformarsi ai principi generali dell&#8217;lslam. La legge canonica (shari&#8217;ah) regola la sfera politica e privata del credente. Si basa sul Corano e sulla tradizione risalente a Muhammad e suoi compagni. I giuristi hanno formato nella storia dell&#8217;lslam una categoria che si \u00e8 arrogata la delega del potere, trasformandosi in un &#8220;corpus&#8221; dotato di potere decisionale in molti settori<\/p>\n<\/div>\n<p style=\"text-align: center;\">\u00a0______________________________________<\/p>\n<h4 style=\"text-align: center;\"><strong>FRA SCITI E SUNNITI<\/strong><\/h4>\n<p style=\"text-align: justify;\">Le diverse interpretazioni del diritto sono alla base delle differenziazioni all&#8217;interno delle correnti islamiche. I sunniti si considerano i veri seguaci della Sunnah (azioni, parole o silenzi di Muhammad assunti come norma di condotta) e gli ortodossi dell&#8217;lslam. Sono maggioritari nel mon- do arabo e non hanno un clero gerarchizzato. Lo sciismo (Shi&#8217;ah) nacque come partito di Ali, genero di Muhammad, e sostenitore dei diritti della sua fami glia al califfato (o imamato come preferirono de- nominarlo). l&#8217;imamato \u00e8 cos\u00ec diventato l&#8217;elemento caratterizzante lo sciismo. l&#8217;imam \u00e8 il solo capo legittimo della comunit\u00e0 musulmana, designato per volont\u00e0 divina alla carica suprema. E&#8217; un di scendente diretto del Profeta attraverso la figlia Fatima e il marito Ali. E&#8217; un capo spirituale e religioso, ma anche secolare, dotato di un potere misterioso trasmessogli dal suo predecessore. Come tale, egli occupa una posizione molto superiore a quella di ogni altro essere umano.<\/p>\n<p style=\"text-align: justify;\">Lo sciismo ha varie correnti (shi&#8217;ah duodecimana, ismailita, ibadita, ecc.) \u00e8 diffuso soprattutto in Iran e Iraq. La shi&#8217;ah duodecimana \u00e8 religione di stato in Iran. I duodecimani pensa no a una catena di imam, la cui funzione \u00e8 stata delegata di padre in figlio, nel ramo cadetto dei discendenti di Ali e Fatima, che continua fino al dodicesimo imam (da qui il nome). l&#8217;imam del tempo attuale non \u00e8 morto ma nascosto, ed \u00e8 garante della verit\u00e0 in cui opera la sua comunit\u00e0, guidata da un corpo di interpreti ufficiali.<\/p>\n<p style=\"text-align: justify;\">\u00abLo sciismo duodecimano presuppone un intermediario tra divinit\u00e0 e credente. Il clero ha cos\u00ec potuto sviluppare un proprio ruolo autonomo religioso, sociale e di implicazione politica. In Persia dal cinquecento a oggi il clero si \u00e8 organizzato con proprie istituzioni e si configura come un corpo sociale autonomo dal punto di vista ideologico ed economico. Ha una gerarchia che fa da contrappeso allo stato, gestisce i proventi degli oboli destinati ai numerosi santuari e dell&#8217;amministrazione dei beni waqf: un quinto (khoms) dell&#8217;usufrutto di propriet\u00e0 e di redditi dei fedeli abbienti \u00e8 devoluto a esponenti autorevoli del clero\u00bb, ha affermato Angelo Michele Piemontese, ordinario di lingua e letteratura persiana all&#8217;universit\u00e0 La Sapienza a Roma, in una conferenza tenuta a Milano nel 1992. \u00abl&#8217;insediamento al potere del clero ha modificato un corpo che prima era separato dallo stato. Ha emarginato e dissolto gruppi organizzati di tipo moderno: comunisti, nazionalisti e altri movimenti laici. In Iran ha assunto un ruolo che in altri stati sarebbe stato assunto dai militari, come funzione di controllo e dominio dello stato. Non \u00e8 teocrazia, ma clerocrazia. La clerocrazia si basa su un ceto sociale costituito da religiosi e professionisti della religione. Prima la religione controllava lo stato, ora deve fare i conti con la ragione di stato. Ora lo stato domina la religione. E&#8217; di tipo autoritario, ma non totalitario e monolita anche se vi sono richiami organizzativi di tipo sovietico\u00bb<\/p>\n<p>_________________________________________<\/p>\n<p><span style=\"color: #000000;\"><strong>Leggi la seconda parte:<\/strong><\/span><\/p>\n<p><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lintegralismo-di-massa\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">L\u2019integralismo di massa<\/span><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Abstract:\u00a0 storia del fondamentalismo islamico. Gli ultimi decenni dell&#8217;ottocento sono stati contrassegnati dal risveglio del mondo islamico, fomentato da personalit\u00e0 religiose e intellettuali rappresentative del movimento riformista ortodosso. Si tratt\u00f2 di un fenomeno politico e religioso ori-ginato dall&#8217;unione di due correnti di pensiero: la prima, di ispirazione religiosa, si fondava sull&#8217;ideologia riformista nata alla fine &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/storia-del-fondamentalismo-islamico\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":32696,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16,36],"tags":[161,501],"class_list":["post-90","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-islam","category-fondamentalismo-islamico","tag-islam-2","tag-islam-fondamentalismo","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Storia del fondamentalismo islamico - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Storia del fondamentalismo islamico\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/storia-del-fondamentalismo-islamico\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Storia del fondamentalismo islamico - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Storia del fondamentalismo islamico\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/storia-del-fondamentalismo-islamico\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2004-11-10T10:57:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-05T14:42:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2004\/11\/Mecca.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"259\" \/>\n\t<meta property=\"og:image:height\" content=\"194\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"15 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/storia-del-fondamentalismo-islamico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/storia-del-fondamentalismo-islamico\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Storia del fondamentalismo islamico\",\"datePublished\":\"2004-11-10T10:57:04+00:00\",\"dateModified\":\"2024-01-05T14:42:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/storia-del-fondamentalismo-islamico\\\/\"},\"wordCount\":2718,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/storia-del-fondamentalismo-islamico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2004\\\/11\\\/Mecca.jpg\",\"keywords\":[\"islam\",\"Islam fondamentalismo\"],\"articleSection\":[\"Islam\",\"Islam fondamentalismo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/storia-del-fondamentalismo-islamico\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/storia-del-fondamentalismo-islamico\\\/\",\"name\":\"Storia del fondamentalismo islamico - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/storia-del-fondamentalismo-islamico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/storia-del-fondamentalismo-islamico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2004\\\/11\\\/Mecca.jpg\",\"datePublished\":\"2004-11-10T10:57:04+00:00\",\"dateModified\":\"2024-01-05T14:42:12+00:00\",\"description\":\"Storia del fondamentalismo islamico\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/storia-del-fondamentalismo-islamico\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/storia-del-fondamentalismo-islamico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/storia-del-fondamentalismo-islamico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2004\\\/11\\\/Mecca.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2004\\\/11\\\/Mecca.jpg\",\"width\":259,\"height\":194},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/storia-del-fondamentalismo-islamico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Storia del fondamentalismo islamico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Storia del fondamentalismo islamico - Rassegna Stampa Cattolica","description":"Storia del fondamentalismo islamico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/storia-del-fondamentalismo-islamico\/","og_locale":"it_IT","og_type":"article","og_title":"Storia del fondamentalismo islamico - Rassegna Stampa Cattolica","og_description":"Storia del fondamentalismo islamico","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/storia-del-fondamentalismo-islamico\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2004-11-10T10:57:04+00:00","article_modified_time":"2024-01-05T14:42:12+00:00","og_image":[{"width":259,"height":194,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2004\/11\/Mecca.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"15 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/storia-del-fondamentalismo-islamico\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/storia-del-fondamentalismo-islamico\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Storia del fondamentalismo islamico","datePublished":"2004-11-10T10:57:04+00:00","dateModified":"2024-01-05T14:42:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/storia-del-fondamentalismo-islamico\/"},"wordCount":2718,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/storia-del-fondamentalismo-islamico\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2004\/11\/Mecca.jpg","keywords":["islam","Islam fondamentalismo"],"articleSection":["Islam","Islam fondamentalismo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/storia-del-fondamentalismo-islamico\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/storia-del-fondamentalismo-islamico\/","name":"Storia del fondamentalismo islamico - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/storia-del-fondamentalismo-islamico\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/storia-del-fondamentalismo-islamico\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2004\/11\/Mecca.jpg","datePublished":"2004-11-10T10:57:04+00:00","dateModified":"2024-01-05T14:42:12+00:00","description":"Storia del fondamentalismo islamico","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/storia-del-fondamentalismo-islamico\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/storia-del-fondamentalismo-islamico\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/storia-del-fondamentalismo-islamico\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2004\/11\/Mecca.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2004\/11\/Mecca.jpg","width":259,"height":194},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/storia-del-fondamentalismo-islamico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Storia del fondamentalismo islamico"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/90","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=90"}],"version-history":[{"count":3,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/90\/revisions"}],"predecessor-version":[{"id":58877,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/90\/revisions\/58877"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/32696"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=90"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=90"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=90"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}