{"id":888,"date":"2005-07-13T00:00:00","date_gmt":"2005-07-12T22:00:00","guid":{"rendered":""},"modified":"2016-05-10T19:23:07","modified_gmt":"2016-05-10T17:23:07","slug":"giovannino-il-sovversivo","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/giovannino-il-sovversivo\/","title":{"rendered":"Giovannino il sovversivo"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-34033\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/Giovanni-Guareschi.jpg\" alt=\"Giovanni Guareschi\" width=\"250\" height=\"192\" \/>Il Foglio <\/strong>9 luglio 2005<\/div>\n<p style=\"text-align: center;\"><em>&#8220;Non muoio neanche se mi ammazzano&#8221;. Guareschi contro tutti<\/em><\/p>\n<p style=\"text-align: center;\">di <strong>Francesco Agnoli<\/strong><\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">Alla morte di Giovannino Guare\u00adschi (a sessant\u2019anni, nel 1968), nes\u00adsun messaggio giunge dalle autorit\u00e0 di governo, nessuno da uomini politici. Solo tante calunnie, aspre e velenose, dai giornali pi\u00f9 diffusi e da quelli di partito. Colui che aveva creato e diret\u00adto il settimanale pi\u00f9 letto d\u2019Italia, <em>il Candido<\/em>, lo scrittore italiano pi\u00f9 tra\u00addotto al mondo, veniva dimenticato dall\u2019Italia ufficiale, piena di fretta di seppellirlo, ma non dalla gente della Bassa, accorsa in massa al suo funera\u00adle.<\/div>\n<p style=\"text-align: justify;\">Nella predica il parroco apre un li\u00adbro del defunto, e legge. <em>\u201cAdesso vi racconto tutto di me: ho l\u2019et\u00e0 di chi \u00e8 nato nel 1908, conduco una vita molto semplice, non mi piace viaggiare, non pratico nessuno sport, non credo in tante fantasticherie. Ma in compenso credo in Dio\u201d<\/em>. Poi il parroco prosegue: <em>\u201cSu questa terra noi piantiamo la cro\u00adce di Cristo, del tuo Cristo che hai sa\u00adputo far vibrare nei cuori e nelle co\u00adscienze degli italiani e di tanti altri mi\u00adlioni di uomini, soprattutto nell\u2019ora della lotta\u201d<\/em>.<\/p>\n<p style=\"text-align: justify;\">La fretta di seppellire Guareschi continua ancor oggi, nel volenteroso sforzo di farlo dimenticare, ad esem\u00adpio eliminandolo dalle antologie sco\u00adlastiche, in cui invece trovano spazio autori noiosissimi, che non hanno mai avuto vera fortuna presso il pubblico, ma solo presso l\u2019onnipotente giudizio della critica. Ma chi era Giovannino Guareschi? Un uomo senz\u2019altro eccezionale, sin dalla prima giovinezza. I compagni ri\u00adcordano il suo spirito goliardico, la sua\u00a0 intraprendenza, la sua intelligenza vi\u00advace.<\/p>\n<p style=\"text-align: justify;\">Scrive di lui Cesare Zavattini, suo istitutore in quinta ginnasio: \u201cTroppo spiritoso. La sua verve \u00e8 spesso inopportuna. Le sue mancanze sono conseguenza d\u2019irrefrenabili doti umo\u00adristiche. Veramente intelligente, ottie\u00adne per lo studio, con i minimi mezzi, i massimi risultati\u201d. Finita la scuola, iscrittosi all\u2019universit\u00e0, pi\u00f9 per parte\u00adcipare alle feste studentesche che al\u00adtro, si cimenta in una grande variet\u00e0 di mestieri: elettricista, caricaturista, car\u00adtellonista, scenografo, custode di de\u00adpositi di biciclette ecc.<\/p>\n<p style=\"text-align: justify;\">Finalmente rie\u00adsce ad approdare al mondo del gior\u00adnalismo: lavora dapprima per alcuni quotidiani emiliani, finch\u00e9 nel 1936 si trasferisce a Milano, con la moglie En\u00adnia, per lavorare al <em>Bertoldo<\/em>, insieme ad Achille Campanile, Giovanni Mosca e Cesare Zavattini. Dal 1940 collabora anche col <em>Corriere della Sera<\/em>. Fin dai primi anni di giornalismo Guareschi snobba le conventicole de\u00adgli intellettuali e degli scrittori che si elogiano e si premiano a vicenda, e col suo stile semplice e pieno d\u2019umorismo svillaneggia la retorica ufficiale.<\/p>\n<p style=\"text-align: justify;\">L\u2019umorismo gli appare il nemico giurato di ogni retorica di regime, di ogni men\u00adzogna ufficializzata e consacrata: <em>\u201cLi\u00adberiamoci dalla parte peggiore di noi stessi, guardiamoci allo specchio e ri\u00addiamo della nostra tracotanza, del no\u00adstro barocco messianismo, della nostra retorica. Guardiamoci allo specchio dell\u2019umorismo, cos\u00ec come ho fatto tante volte io, cittadino-niente, che, quan\u00addo mi specchio e vedo sul mio viso un truce cipiglio, scuoto il capo e dico: Giovannino, quanto sei fesso!\u201d<\/em>.<\/p>\n<p style=\"text-align: justify;\">Nel 1942 Guareschi viene arrestato dai fascisti, <em>\u201cper aver comunicato al rione Gustavo Modena, Ciro Menotti, Castelmorrone ci\u00f2 che in quel mo\u00admento pensavo di tutta la faccenda. Si tratta di un episodio poco onorevole in quanto accade che io, la notte del 14 ottobre 1942 \u2013 riempitomi di grappa fi\u00adno agli occhi in casa di amici \u2013 per tor\u00adnare alla mia casa di via Ciro Menotti, che \u00e8 lontana non pi\u00f9 di ottocento me\u00adtri, impieghi due ore. E in quelle due ore urlo delle cose che poi l\u2019indomani trovo registrate diligentemente in quattro pagine di protocollo\u2026 Gli ami\u00adci mettono in moto l\u2019eterna macchina della camorra italiana in modo da sot\u00adtrarmi alle giuste sanzioni della legge, e, per prudenza, mi fanno richiamare alle armi\u201d<\/em>. Sembra insomma, chiosa Guareschi, <em>\u201cche per perdere la guerra ci sia assoluto bisogno della mia colla\u00adborazione\u201d<\/em>.<\/p>\n<p style=\"text-align: justify;\">Cos\u00ec finisce in Egitto, per alcuni mesi. Dopo l\u20198 settembre si tro\u00adva di fronte alla grande decisione: col\u00adlaborare coi fascisti e coi tedeschi, di\u00adventare partigiano o restare fedele al giuramento fatto al re. Giovannino opta per la terza scelta, e la paga duramente, con due anni di lager, durante i quali rifiuta pi\u00f9 volte l\u2019opportunit\u00e0 di venir liberato in cambio di una colla\u00adborazione, anche solo di penna.<\/p>\n<p style=\"text-align: justify;\">Nell\u2019atmosfera cupa e angosciante del la\u00adger non si d\u00e0 per vinto: organizza tea\u00adtrini, inventa favole piene di speranza, promuove chiacchierate e discussioni tra internati, tenendo desto il deside\u00adrio di vivere di chi lo circonda. Chi scrive ha conosciuto persone che de\u00advono alla sua vitalit\u00e0 e alla sua forza di non essere sprofondate nella dispera\u00adzione e, forse, nella morte.<em> \u201cNon muoio neanche se mi ammazzano\u201d<\/em>, \u00e8 il suo motto di quei giorni.<\/p>\n<p style=\"text-align: justify;\">Ma lo sconforto prende talora il sopravvento anche in un animo fiero come il suo:<em> \u201cLe mie ore si annullano in questa sabbia, e ogni ora mi ruba una goccia di vita, un sorriso dei miei figli, e io vedo me stes\u00adso scendere gradino per gradino la scala che non si risale mai pi\u00f9. Questa noia che sa di catrame come l\u2019aria di questa terra ostile\u2026 Un anno \u00e8 finito. Un anno comincia. La noia continua, niente di nuovo\u201d<\/em>.<\/p>\n<p style=\"text-align: center;\">* * *<\/p>\n<p style=\"text-align: justify;\">Finalmente arriva la liberazione, e Guareschi pu\u00f2 tornare a casa: <em>\u201cPer ventiquattro mesi ho calpestato sabbia di lager e la sabbia non d\u00e0 suono, e co\u00ads\u00ec il mio passo ha perso la sua voce. Ora ritrovo sulle lastre del porticato la voce del mio passo\u2026 Non ho notizie dei miei da troppo tempo. La guerra \u00e8 passata l\u00ec vicino: li ritrover\u00f2 tutti? Qualcuno? Nessuno? E proprio e solo adesso, quando l\u2019avventura \u00e8 finita, ho paura e mi sfascio sulla riva del fosso, come uno straccio\u2026 Quando arrivo da\u00advanti a casa mia sta schiarendo e io rimango seduto sulla sponda del fosso e aspetto che il sole si sia ben levato e intanto guardo le finestre chiuse e sof\u00adfro come non ho mai sofferto neanche lass\u00f9. Perch\u00e9 lass\u00f9 si aveva un po\u2019 l\u2019idea che tutto si fosse fermato, a casa nostra, e soltanto al nostro ritorno la vita avrebbe ripreso il suo naturale corso. Poi, a un tratto, sento una voce gridare qualcosa: ed \u00e8 la mia voce e io ne sono terrorizzato e attendo con gli occhi sbarrati che tutte le finestre si aprano e conto le teste che spuntano fuori: una, due, tre, quattro. Ne manca una, la pi\u00f9 piccola. Allora lascio il sac\u00adco in riva al fosso e corro dentro e, sperduta in un enorme letto, trovo la signorina Carlotta che dorme. E dico \u2018Cinque!\u2019, anche se la prima cosa che vedo non \u00e8 una testa, ma un sederino rosa\u2026 Ennia \u00e8 pi\u00f9 magra di me. E\u2019 un sacchetto d\u2019ossa tenute insieme soltanto dal desiderio di farsi ritrovare viva da me al mio ritorno\u201d<\/em>.<\/p>\n<p style=\"text-align: justify;\">Ma il ritorno tanto desiderato si tin\u00adge presto di scuro. Non c\u2019\u00e8, ad accoglierlo, un paese unito, desideroso di rialzarsi, di ricominciare. Non c\u2019\u00e8 uno spirito comunitario, un sentimento di fratellanza, come quello che si era creato tra compagni di lager, nell\u2019ora del dolore, della nostalgia e della spe\u00adranza: <em>\u201cGli italiani non hanno impara\u00adto niente dalla guerra. E\u2019 triste: nelle guerre imparano qualcosa soltanto i morti\u201d<\/em>. Infatti l\u2019Italia \u00e8 divisa dall\u2019odio di classe, dal veleno di un\u2019altra ideolo\u00adgia, non meno terribile di quelle scon\u00adfitte. Alla guerra mondiale si \u00e8 sosti\u00adtuita la guerra civile, il rancore e l\u2019odio tra compaesani e connazionali.<\/p>\n<p style=\"text-align: justify;\">Guare\u00adschi ricorda soprattutto, come segno evidente di questo clima appestato, il riso di disprezzo di una ragazza seduta su una panchina: <em>\u201cOgni tanto, tra una raffica e l\u2019altra di riso, urla qualcosa sui miei baffi, sui miei capelli. E io che rido tanto degli altri e che non mi ar\u00adrabbio se qualcuno ride di me, per quel riso non mi offendo: mi sgomen\u00adto\u2026 La ragazza non ha nessuna ragio\u00adne. Non sa nemmeno chi sono: a lei non piacciono i miei baffi e i miei ca\u00adpelli, perch\u00e9 un uomo che li porta di quel genere \u00e8 uno degli altri. Un rap\u00adpresentante della classe odiata che bi\u00adsogna impiccare\u201d<\/em>.<\/p>\n<p style=\"text-align: justify;\">Di fronte a tutto ci\u00f2 Guareschi ricorre ancora all\u2019unica arma che conosce, la sua penna, e fonda, nel dicembre 1945, il <em>Candido<\/em>, il gior\u00adnale che sveler\u00e0, puntualmente, le stragi comuniste, specie in Emilia Ro\u00admagna e in Toscana; che denuncer\u00e0 il passaggio in massa degli intellettuali fascisti al comunismo; che consacrer\u00e0 le figure di Peppone e di don Camillo, destinate a rimanere nell\u2019immaginario collettivo per molti anni.<\/p>\n<p style=\"text-align: justify;\">Bisogna leg\u00adgere queste storie, piene di umorismo leggero, di umanit\u00e0, ma anche profon\u00addamente storiche, per capire l\u2019atmosfera di quegli anni: <em>\u201cL\u2019ambiente in cui i miei personaggi operano \u00e8 il mio pae\u00adse. E\u2019 la Bassa. Alla Bassa, dove il sole d\u2019estate spacca la testa alla gente, e do\u00adve, d\u2019inverno, non si capisce pi\u00f9 quale sia il paese e quale il cimitero, basta una sciocchezza come una gallina ac\u00adcoppata a sassate o un cane bastonato per mettere due famiglie in guerra per\u00adpetua\u2026 Alla Bassa, dove le strade sono lunghe e diritte, da una parte c\u2019\u00e8 l\u2019alba e dall\u2019altra il tramonto, piacciono i tipi con una fisionomia precisa, facili da amare e facili da odiare\u201d<\/em>.<\/p>\n<p style=\"text-align: justify;\"><em>Candido<\/em> diviene cos\u00ec il giornale che, insieme ai Comitati civici di Luigi Ged\u00adda, segna la sconfitta dei comunisti e la vittoria della Dc nel 1948. Ben pi\u00f9 di De Gasperi, col suo aspetto <em>\u201csecco e fu\u00adnereo\u201d<\/em>, ben pi\u00f9 degli uomini di partito, contano, in questa splendida campa\u00adgna elettorale, le vignette e i manifesti elettorali di Guareschi, e l\u2019azione so\u00adlerte e instancabile dei ragazzi delle parrocchie. Giovannino Guareschi, mo\u00adnarchico, cattolico, destrorso, antifa\u00adscista e reduce da due anni di lager in Germania, si trova quindi a combatte\u00adre ancora una volta per la libert\u00e0, e lo fa, ancora una volta, senza risparmiar\u00adsi.<\/p>\n<p style=\"text-align: justify;\">Ma pur risultando vincitore non re\u00adclama alcuna prebenda, n\u00e9 alcun onore: vuole tenersi libero, non vuole le\u00adgarsi a nessun carro, a nessun partito, a nessun padrone. Cos\u00ec, pochi anni do-po, nel 1953, nel suo diario pu\u00f2 scrive\u00adre: <em>\u201cCon Candido contro lo strapotere Dc\u201d<\/em>. La Dc lo ha deluso, sotto molti aspetti: Giovannino vede gi\u00e0 le busta\u00adrelle, il rinnegamento dei principi a vantaggio delle poltrone, i nepotismi di De Gasperi, <em>\u201cceleberrimo sistematore di parenti\u201d<\/em>.<\/p>\n<p style=\"text-align: justify;\">Allo statista trentino dedica diverse vignette. In una di queste De Gasperi avanza, seguito da uno stuolo di parenti, con una bandiera su cui \u00e8 disegnato un sole, e dentro la scritta: <em>\u201cHo famiglia\u201d<\/em>. Sopra vi \u00e8 scritto:<em> \u201cFor\u00adza Alcide, che non sei solo\u201d<\/em>. A lato al\u00adcuni versi: <em>\u201cSu fratelli, su cognati\/ su venite in fitta schiera:\/ sulla libera ban\u00addiera\/ splende il Sol dell\u2019avvenir\u201d<\/em>.<\/p>\n<p style=\"text-align: justify;\">In poche parole Guareschi finisce per ini\u00admicarsi, oltre a Luigi Einaudi, per una vignetta irriverente, anche Alcide De Gasperi. Il processo intentatogli da quest\u2019ultimo \u00e8 una sorta di farsa, alla fine della quale Guareschi finisce in galera: <em>\u201cPer rimanere liberi <\/em>\u2013 scrive \u2013 <em>bisogna a un bel momento prendere senza esitare la via della prigione\u201d<\/em>. E ancora: <em>\u201cMonarchico in una repubbli\u00adca; di destra in un paese che cammina decisamente, inflessibilmente verso si\u00adnistra; sostenitore dell\u2019iniziativa priva\u00adta in tempi di statalismo, assertore di italianit\u00e0 in tempi di antinazionalismo; cattolico intransigente in tempi di de\u00admocristianismo, io non sono stato \u2013 co\u00adme poteva sembrare \u2013 un indipenden\u00adte, bens\u00ec un anarchico. Non un uomo li\u00adbero, ma un sovversivo. E perci\u00f2 \u00e8 giu\u00adsto che mi venga tolta la parola e la li\u00adbert\u00e0\u201d<\/em>.<\/p>\n<p style=\"text-align: justify;\">Anche in questa occasione Gua\u00adreschi rifiuta sconti e amnistie di sorta. Rimane in galera sino alla fine, pog\u00adgiando sulla sua incredibile fiducia nella Provvidenza: <em>\u201cCompleta \u00e8 la mia fiducia nella Provvidenza che, per essere veramente tale, non deve mai essere vincolata da scadenze. Mai preoc\u00adcuparsi del disagio di oggi, ma aver sempre l\u2019occhio fisso nel bene finale che verr\u00e0 quando sar\u00e0 giusto che ven\u00adga. I giorni della sofferenza non sono giorni persi: nessun istante \u00e8 perso, \u00e8 inutile, del tempo che Dio ci concede. Altrimenti non ce lo concederebbe\u201d<\/em>.<\/p>\n<p style=\"text-align: justify;\">Lo aiuta, anche, il suo senso dell\u2019umorismo, la sua capacit\u00e0 di divertirsi, almeno un po\u2019, in ogni circostanza. In ga\u00adlera scrive versetti simpatici, disegna, decora l\u2019asse del cesso con un origina\u00adle \u201cmerdometro\u201d, costituito dalla foto\u00adgrafia dell\u2019odiato Scelba. In un bollet\u00adtino inviato agli amici, sulle sue condi\u00adzioni, scrive: <em>\u201cCos\u2019ero, or son due mesi, appena entrato?\/ Un fuorilegge, un po\u00advero spostato:\/ adesso grazie alla pri\u00adgione\/ marciando sto verso la reden\u00adzione.\/ La squadra \u00e8 gi\u00e0 passata\/ a bat\u00adter l\u2019inferiata.\/ I ferri sono a posto, niente buchi nel muro.\/ E io mi sento pi\u00f9 sicuro\u201d.<\/em><\/p>\n<p style=\"text-align: center;\">* * *<\/p>\n<p style=\"text-align: justify;\">Negli ultimi anni della sua vita Gua\u00adreschi assiste al cambiamento cultura\u00adle dell\u2019Italia. Non gli piace affatto il nuovo mondo che sta nascendo: <em>\u201cTra i grattacieli del miracolo economico sof\u00adfia un vento caldo che sa di cadavere, di sesso e di fogna\u201d<\/em>. Sono gli ultimi an\u00adni, in cui, dopo tanta sofferenza, l\u2019umore si fa, talora, acido, amaro. Per lui l\u2019attuale generazione di italiani <em>\u201cpi\u00f9 che una generazione \u00e8 una degenera\u00adzione\u201d<\/em>: si alimenta coi nuovi miti della bellezza fisica a ogni costo e a ogni et\u00e0, coi divi della tv, col benessere mate\u00adriale che ammalia anche gli uomini del passato.<\/p>\n<p style=\"text-align: justify;\">Guarda sconsolato certe anziane signore di citt\u00e0, che non sanno pi\u00f9 invecchiare: <em>\u201cHanno gli occhi di\u00adpinti di verde o di blu e i seni conve\u00adnientemente sistemati: il seno destro \u00e8 stato passato sulla spalla sinistra, il si\u00adnistro sulla destra, quindi ambedue sono stati incrociati sulla schiena, co\u00adme i tubolari dei corridori ciclisti, per venire annodati solidamente sull\u2019uno e sull\u2019altro fianco\u201d<\/em>.<\/p>\n<p style=\"text-align: justify;\">Uno dei motori di questi cambia\u00admenti sociali e culturali \u00e8 senz\u2019altro la televisione: <em>\u201cLa tv col suo incessante martellare, condito con piacevoli mu\u00adsichette e divertenti spettacoli di va\u00adriet\u00e0, crea nelle famiglie problemi, bi\u00adsogni, o addirittura necessit\u00e0 pratica\u00admente inesistenti. Cos\u00ec come crea dal nulla dei valori e degli idoli. Crea una mentalit\u00e0, un costume, un linguaggio\u201d<\/em>, si insinua nelle case, interrompendo il dialogo, raffreddando il confronto, in\u00adgessando, condizionando, omologando le personalit\u00e0.<\/p>\n<p style=\"text-align: justify;\">In questi anni nasce cos\u00ec l\u2019ultimo ca\u00adpolavoro: <em>\u201cDon Camillo e i giovani d\u2019oggi\u201d<\/em>. E\u2019 uno sguardo, sereno, diver\u00adtente, ma realistico, sull\u2019evoluzione dei costumi, dei rapporti famigliari e della Chiesa. Don Camillo non \u00e8 pi\u00f9 alle prese con i veri comunisti, alla Peppone, ma col malcontento misto a noia dei giovani, dei cappelloni alla Veleno e delle ragazze emancipate co\u00adme Cat.<\/p>\n<p style=\"text-align: justify;\">Soprattutto, in questo breve romanzo, compare la figura di Don Chich\u00ec, che rappresenta il pretino standard post Concilio Vaticano II: con la sua mezza voce, i suoi mezzi termi\u00adni, la mania del dialogo sopra ogni cosa, lo sperimentalismo liturgico, stile <em>\u201ctavola calda di Lercaro\u201d<\/em>\u2026 E\u2019 don Chi\u00adch\u00ec il vero, ultimo <em>\u201cavversario\u201d<\/em> di Gua\u00adreschi, non i giovani che stanno per scatenare il \u201968.<\/p>\n<p style=\"text-align: justify;\">A loro si rivolge, pa\u00adternamente, temendo solo che siano ingannati, che riempiano il loro vuoto di violenza spacciata per ideale: <em>\u201c(O giovani) diffidate di chi vi sorride e vi d\u00e0 importanza eccezionale. Vuole rifi\u00adlarvi un giornale, un libro, un disco, una rivista pornografica, un intruglio gasato, una chitarra, un allucinogeno, una pillola, una scheda elettorale, un cartello, un manganello, un mitra. Pro\u00adtesto perch\u00e9 sono stato giovane e bug\u00adgerato come saranno immancabilmen\u00adte buggerati i giovani d\u2019oggi\u2026\u201d<\/em>.<\/p>\n<p style=\"text-align: justify;\">Il 1968 \u00e8 anche l\u2019anno della morte di Guare\u00adschi, a Cervia, nella sua amata terra.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Foglio 9 luglio 2005 &#8220;Non muoio neanche se mi ammazzano&#8221;. Guareschi contro tutti di Francesco Agnoli<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/giovannino-il-sovversivo\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":34033,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25],"tags":[752],"class_list":["post-888","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sguardo-sul-nostro-tempo","tag-guareschi","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Giovannino il sovversivo - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/giovannino-il-sovversivo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Giovannino il sovversivo - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/giovannino-il-sovversivo\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2005-07-12T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-05-10T17:23:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/Giovanni-Guareschi.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"256\" \/>\n\t<meta property=\"og:image:height\" content=\"197\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"13 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/giovannino-il-sovversivo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/giovannino-il-sovversivo\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Giovannino il sovversivo\",\"datePublished\":\"2005-07-12T22:00:00+00:00\",\"dateModified\":\"2016-05-10T17:23:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/giovannino-il-sovversivo\\\/\"},\"wordCount\":2612,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/giovannino-il-sovversivo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/07\\\/Giovanni-Guareschi.jpg\",\"keywords\":[\"Guareschi\"],\"articleSection\":[\"Sguardo sul nostro tempo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/giovannino-il-sovversivo\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/giovannino-il-sovversivo\\\/\",\"name\":\"Giovannino il sovversivo - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/giovannino-il-sovversivo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/giovannino-il-sovversivo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/07\\\/Giovanni-Guareschi.jpg\",\"datePublished\":\"2005-07-12T22:00:00+00:00\",\"dateModified\":\"2016-05-10T17:23:07+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/giovannino-il-sovversivo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/giovannino-il-sovversivo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/giovannino-il-sovversivo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/07\\\/Giovanni-Guareschi.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/07\\\/Giovanni-Guareschi.jpg\",\"width\":256,\"height\":197},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/giovannino-il-sovversivo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Giovannino il sovversivo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Giovannino il sovversivo - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/giovannino-il-sovversivo\/","og_locale":"it_IT","og_type":"article","og_title":"Giovannino il sovversivo - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/giovannino-il-sovversivo\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2005-07-12T22:00:00+00:00","article_modified_time":"2016-05-10T17:23:07+00:00","og_image":[{"width":256,"height":197,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/Giovanni-Guareschi.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"13 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/giovannino-il-sovversivo\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/giovannino-il-sovversivo\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Giovannino il sovversivo","datePublished":"2005-07-12T22:00:00+00:00","dateModified":"2016-05-10T17:23:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/giovannino-il-sovversivo\/"},"wordCount":2612,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/giovannino-il-sovversivo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/Giovanni-Guareschi.jpg","keywords":["Guareschi"],"articleSection":["Sguardo sul nostro tempo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/giovannino-il-sovversivo\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/giovannino-il-sovversivo\/","name":"Giovannino il sovversivo - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/giovannino-il-sovversivo\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/giovannino-il-sovversivo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/Giovanni-Guareschi.jpg","datePublished":"2005-07-12T22:00:00+00:00","dateModified":"2016-05-10T17:23:07+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/giovannino-il-sovversivo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/giovannino-il-sovversivo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/giovannino-il-sovversivo\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/Giovanni-Guareschi.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/Giovanni-Guareschi.jpg","width":256,"height":197},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/giovannino-il-sovversivo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Giovannino il sovversivo"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/888","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=888"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/888\/revisions"}],"predecessor-version":[{"id":34034,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/888\/revisions\/34034"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/34033"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=888"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=888"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=888"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}