{"id":87,"date":"2004-11-10T11:15:17","date_gmt":"2004-11-10T10:15:17","guid":{"rendered":""},"modified":"2024-01-05T17:47:22","modified_gmt":"2024-01-05T16:47:22","slug":"come-nasce-lintegralismo-islamico-2","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/come-nasce-lintegralismo-islamico-2\/","title":{"rendered":"4 &#8211; Come nasce l&#8217;integralismo islamico"},"content":{"rendered":"<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-32702\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2004\/11\/sauditi.jpg\" alt=\"sauditi\" width=\"250\" height=\"161\" \/><strong><span style=\"color: #000000;\">Abstract: <\/span><\/strong><em><span style=\"color: #000000;\">c<\/span><span style=\"color: #000000;\">ome nasce l&#8217;integralismo islamico. Quando si parla di &#8220;moderati&#8221; bisognerebbe sempre ricordarsi che si tratta d\u00ec un\u2019espressione di comodo, un termine che non indica affatto un\u2019identit\u00e0 politica \u00abModeratismo\u00bb una categoria tipicamente occidentale che pu\u00f2 risultare utile soltanto per stabilire il grado di vicinanza di questo o quel governo al sistema politico europeo o americano. Ma in se, applicata al Medio Oriente o al Nordafrica, non vuol dire granch\u00e9<\/span><\/em><\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: center;\">Articolo pubblicato su<b>\u00a0<\/b><a href=\"https:\/\/www.secoloditalia.it\/\" target=\"_blank\" rel=\"noopener\"><strong>Il Secolo d&#8217;Italia<\/strong><\/a>\u00a0dell&#8217;11 ottobre 2001<\/p>\n<h3 style=\"text-align: center;\">Misteri sauditi<\/h3>\n<h4 style=\"text-align: center;\"><strong>Ricostruendo la genesi dell&#8217;integralismo islamico<\/strong>\u00a0\/ 4<\/h4>\n<p style=\"text-align: center;\">di\u00a0<strong>Aldo Di Lello<\/strong><\/p>\n<p style=\"text-align: justify;\">Si fa presto a dire \u00abmoderati\u00bb Quando si applica questa etichetta alla gran parte degli Stati arabi! Bisognerebbe sempre ricordarsi che si tratta d\u00ec un\u2019espressione di comodo, un termine che non indica affatto un\u2019identit\u00e0 politica \u00abModeratismo\u00bb una categoria tipicamente occidentale che pu\u00f2 risultare utile soltanto per stabilire il grado di vicinanza di questo o quel governo al sistema politico europeo o americano. Ma in se, applicata al Medio Oriente o al Nordafrica, non vuol dire granch\u00e9<\/p>\n<p style=\"text-align: justify;\">\u00abModerati\u00bb sono i governi dell\u2019Egitto, della Giordania, del Marocco, della Tunisia. \u00abModerati\u00bb sono anche i governi della penisola arabica Ma tra gli uni e gli altri, esistono differenze abissali Mubarak e Ben \u2018All sono politici laici, o per lo meno provengono da un\u2019ideologia laica, il panarabismo. E laico, non che panarabista, \u00e8 anche lo stravagante Gheddaffi Ma \u00e8 tutt\u2019altro che un moderato, aldil\u00e0 dell\u2019eccitante approvazione che ha espresso riguardo all\u2019intervento americano contro i Talebani.<\/p>\n<p style=\"text-align: justify;\">L\u2019Arabia Saudita di re Fahd \u00e8, viceversa, il Paese moderato\u00bb per eccellenza, il bastione pi\u00f9 solido dell\u2019Occidente in Medio Oriente. Ma \u00e8 l\u2019esatto opposto di un Paese laico In Arabia Saudita si rischia l\u2019arresto se dal proprio collo pende una catenina con il crocifisso, Non c\u2019\u00e8 nulla di pi\u00f9 distante dall\u2019Occidente che il wahhabismo imperante tra i sauditi, R. A. Segre ha descritto cos\u00ec, su \u00abil Giornale\u00bb, il regime dire Fahd: \u00abIl potere \u00e8 una simbiosi di tribalismo (solo caso al mondo di uno Stato sovrano che porta il nome di un clan, quello dei Saud) e di una corrente religiosa puritana, legata anch\u2019essa a un clan, quello di Al Wahab, in questo momento in fase di grossa crisi morale e ideologica\u00bb.<\/p>\n<p style=\"text-align: justify;\">Tutto questo per dire che il mondo politico arabo musulmano che combatte l\u2019islamismo radicale fin dai suo sorgere lo fa, al di l\u00e0 delle ragioni di convenienza politica, per motivi del tutto diversi.<\/p>\n<p style=\"text-align: justify;\">Se l\u2019Egitto di Mubarak \u00e8 \u00abgeneticamente\u00bb ostile agli integralisti per regioni di incompatibilit\u00e0 ideologica, non altrettanto pu\u00f2 dirsi dell\u2019Arabia Saudita dove il motivo di conflitto \u00e8 soltanto politico, dove gli islamisti sono considerati un fattore di destabilizzazione e di eversione, ma dove per\u00f2 l\u2019 \u00abislamizzazione della modernit\u00e0\u00bb, cavallo di battaglia degli ideologi della\u00a0<em>jihad<\/em>\u00a0\u00e8 stata gi\u00e0 realizzata (almeno apparentemente), non grazie a un\u2019elaborazione politica particolarmente raffinata, ma in virt\u00f9 del privilegio d\u00ec poter usufruire dell\u2019immensa rendita petrolifera.<\/p>\n<p style=\"text-align: justify;\">Di una mentalit\u00e0. integralista, l\u2019Arabia Saudita \u00e8 il santuario, e non solo perch\u00e9 custodisce i \u00abluoghi santi\u00bb dell\u2019islam, ma anche per il fatto d\u00ec essere riuscita a officiare le nozze tra benessere e tradizione, tra telefono cellulare e Corano, tra antenne satellitare e\u00a0<em>shari\u2019a.<\/em>\u00a0Che la modernit\u00e0 vera non sia questa, che dietro la tecnologia vi sia una cultura da assorbire criticamente o da inserire nel proprio sistema di valori, che la potenza di una nazione moderna nasce sempre da un\u2019alta sintesi fra memoria del passato e visione futuro, tutte queste idee, che hanno per esempio permesso al Giappone shintoista di diventare la seconda potenza economica del mondo rimanendo fedele a se stesso, non sfiorano minimamente i principi del petrolio arabico.<\/p>\n<p style=\"text-align: justify;\">Le ingenti risorse ricavate dalla vendita dell\u2019oro nero sono un \u00abdono d\u00ec Allah\u00bb come tali non vanno utilizzate per modernizzare l\u2019intera economia e per sviti. colare il meccanismo di produzione della ricchezza dalla dipendenza petrolifera. Finiscono tutte nello sfarzo da \u00abMille o una notte\u00bb e in una gigantesca macchina mangia-soldi. La penisola arabica poteva davvero diventare la \u00ablocomotiva\u00bb dello sviluppo mediorentale. E si \u00e8 invece rivelata un luogo di contraddizioni esasperate, una zona d\u2019ombre sempre pi\u00f9 ambigua, un pianeta misterioso e impenetrabile. Re Fahd, garante del patto di ferro tra Arabia Saudita e Occidente, \u00e8 anziano e malato. Il Regno \u00e8 affidato al reggente, il principe Abdullah. L\u2019amicizia tra la dinastia wahhabita e gli Usa \u00e8 solida e strutturale Tale rimarr\u00e0, per quel che ne sappiamo, anche in futuro.<\/p>\n<p style=\"text-align: justify;\">Ma le lacerazioni prodotte, dieci anni fa, al tempo della guerra del Golfo, non si sono ancora sanate. La presenza dei marines sulla terra dei \u201cLuoghi santi\u201d si \u00e8 rivelata un\u2019arma a doppio taglio, Ha rafforzato i sauditi rispetto ai nemici esterni, ma li ha anche costretti a fronteggiare nuovi nemici interni. Se la ricchezza viene da Allah, la stabilit\u00e0 politica pu\u00f2 venire dall\u2019America?<\/p>\n<p style=\"text-align: justify;\">La contraddizione, nella terra del wahabbisnio, nella terra in cui s\u2019afferm\u00f2, fin dall\u2019Ottocento, il puritanesimo integrale dei Profeta, una tale contraddizione, nel luogo da cui partono, da decenni, sovvenzioni, per la costruzione delle moschee di tutto il mondo, non poteva essere pi\u00f9 drammatica. Il dissenso dei \u00abpunisti\u00bb dei \u00abLuoghi santi\u00bb si manifest\u00f2 clamorosamente nel maggio del 1991 con una \u00ablettera di rimostranze\u00bb che centosette predicatori e accademici islamici inviarono a re Fahd. Il \u00abmovimento\u00bb, se lo vogliamo chiamare cos\u00ec, era capeggiato da due giovani e dinamici imam. Gilles Kepel ce li descrive cos\u00ec: \u00abDue predicatori, in particolare, i cui sermoni venivano diffusi tramite cassetta, si distinsero per la virulenza delle loro critiche contro la presenza dei militari occidentali, considerati nuovi crociati. Il primo, Salrnan.al\u2019Auda, di 36 anni, era l\u2019imam di una moschea del contro agricolo di Burayda, nella, nella provincia del Qasim, vicino Riyadh, non molto toccata dal boom petrolifero; l\u2019altro, Safar al Hawaii, di cinque anni pi\u00f9 vecchio, era un promettente rampollo dell\u2019establishment religioso saudita, formatosi all\u2019universit\u00e0 di Medina (gestita dal Fratelli Musulmani) e alla Mecca, membro di una famiglie appartenente a una delle trib\u00f9 dominanti del regno\u00bb.<\/p>\n<p style=\"text-align: justify;\">Due anni dopo, altri sei esponenti religiosi, fondarono un\u2019associazione che si proponeva di portare, anche all\u2019estero, la voce del dissenso che stava montando nelle moschee e nelle universit\u00e0.<\/p>\n<p style=\"text-align: justify;\">L\u2019associazione si present\u00f2 al mondo con una denominazione dall\u2019aria vagamente garantista: \u201cComitato per la difesa dei diritti legittimi. C\u2019era solo un\u00a0<em>piccolo<\/em>\u00a0dettaglio: non si trattava dei diritti dell\u2019uomo ma dei diritti di Allah. Non furono certo di iniziative capaci di minare la stabilit\u00e0 del Regno. Ma era comunque grave che le basi religiose della legittimit\u00e0 politica saudita cominciassero a essere messe in discussione. E vale la pena ricordare che, in questo clima di dissenso politico-religioso, nel saudita\u00a0<em>jihadista<\/em>\u00a0Osama Bin Laden mont\u00f2 sia l\u2019odio antiamericano sia l\u2019irriducibile opposizione al regime di re Fahd Lo sceicco del terrore aveva ereditato un patrimonio d\u00ec oltre seicento miliardi ma la sua organizzazione ricevette aiuti da alcuni \u00abbenefattori\u00bb sauditi. Se dalle moschee si levava la riprovazione degli imam, dalla ricchezza di Allah cominciavano a partire schegge di guerra santa.<\/p>\n<p style=\"text-align: justify;\">Con il tempo, queste \u00abschegge\u00bb s\u00ec sono fatte sempre pi\u00f9 consistenti. Osserva Antonio Ferrari sul \u00abCorriere della Sera\u00bb del 23 settembre: \u00abProprio dietro quel flusso di denaro, generosamente inviato da singoli sostenitori del radicalismo islamico pi\u00f9 estremo, si nascondono probabilmente alcune radici della nebulosa finanziaria che ha consentito a Bin Laden e ai suoi di diventare la prima vera multinazionale del terrore\u00bb.<\/p>\n<p style=\"text-align: justify;\">Lampi minacciosi compaiono ogni tanto nell\u2019immobile cielo d\u2019Arabia. Salman. al. Auda \u00e8 in carcere da setto anni, al pari del suo sodalo Safar al Hawali. Ma continua a lanciare messaggi inquietanti. \u00ab\u00c9 riuscito &#8211; scrive Guido Olimpio sul \u201cCorriere della Sera\u201d del 5 ottobre &#8211; a far uscire dalla sua cella una cassetta registrata, il \u201csermone della morte\u201d; dove invita gli intellettuali sauditi al martirio contro i \u201ccrociati\u201d\u00bb.<\/p>\n<p style=\"text-align: justify;\">C\u2019\u00e8 qualcosa di strano, di incomprensibilmente vischioso, nel modo in. cui l\u2019intero sistema saudita fronteggia l\u2019aggressione dell\u2019islamismo estremista. Nell\u2019agosto scorso \u00e8 stato silurato iI capo dei servizi segreti, il principe Al Turki. \u00abA lui &#8211; scrive sempre Olimpio &#8211; era stato affidato il compito dell\u2019arresto di Osama Bin Laden e di tagliare i finanziamenti economici ai fondamentalisti. Al Turki non ha fatto nessuna delle due cose. E per giunta ha permesso alla madre di Osama di partecipare alle nozze di suo nipote, il figlio di Bin Laden, nel rifugio di Kandahar\u00bb Giulietto Chiesa, nel quaderno speciale di \u00abLimes\u00bb dedicato alla guerra del terrore, paventa addirittura la presenza di una \u00abCupola\u00bb al di sopra di Bin Laden. Ne farebbero parte \u00abalti finanzieri del petrolio\u00bb, \u00abferoci rampolli di dinastie minacciate\u00bb, \u00abcommercianti miliardari che vivono nel mercato capitalistico senza essersi mai convertiti alla idee dell\u2019Occidente\u00bb.<\/p>\n<p style=\"text-align: justify;\">Forse si tratta di un\u2019ipotesi azzardata, tipica espressione del \u00abcomplottismo\u00bb di una parte delle stampa italiana. Certo \u00e8 che l\u2019Arabia Saudita appare avvolta in un alone di mistero sempre pi\u00f9 fitto e condizionata da un umore sempre pi\u00f9 nero.<\/p>\n<div style=\"text-align: justify;\">\n<p>Nero come il petrolio di Allah<\/p>\n<\/div>\n<p style=\"text-align: center;\">(<em>Le puntate sono state pubblicate il<\/em><i>\u00a0<\/i><em><b><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=84\">4<\/a>,<\/b> il<\/em><i>\u00a0<\/i><em><b><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=85\">5<\/a><\/b>, il<\/em><i>\u00a0<\/i><em><b><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=86\">10<\/a><\/b><\/em><b><i>\u00a0<\/i><\/b><em>, l\u2019<\/em><i>\u00a0<\/i><em><b><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=87\">11<\/a><\/b><\/em><b><i>\u00a0<\/i><\/b><i>e<b> il <a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=88\">12<\/a> <\/b><\/i><em>ottobre<\/em>)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Abstract: come nasce l&#8217;integralismo islamico. Quando si parla di &#8220;moderati&#8221; bisognerebbe sempre ricordarsi che si tratta d\u00ec un\u2019espressione di comodo, un termine che non indica affatto un\u2019identit\u00e0 politica \u00abModeratismo\u00bb una categoria tipicamente occidentale che pu\u00f2 risultare utile soltanto per stabilire il grado di vicinanza di questo o quel governo al sistema politico europeo o americano. &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/come-nasce-lintegralismo-islamico-2\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":32702,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16,36],"tags":[161,501],"class_list":["post-87","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-islam","category-fondamentalismo-islamico","tag-islam-2","tag-islam-fondamentalismo","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>4 - Come nasce l&#039;integralismo islamico - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Come nasce l&#039;integralismo islamico. Il termine &quot;moderati&quot; \u00e8 un\u2019espressione di comodo, un termine che non indica affatto un\u2019identit\u00e0 politica\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/come-nasce-lintegralismo-islamico-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"4 - Come nasce l&#039;integralismo islamico - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Come nasce l&#039;integralismo islamico. Il termine &quot;moderati&quot; \u00e8 un\u2019espressione di comodo, un termine che non indica affatto un\u2019identit\u00e0 politica\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/come-nasce-lintegralismo-islamico-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2004-11-10T10:15:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-05T16:47:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2004\/11\/sauditi.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"280\" \/>\n\t<meta property=\"og:image:height\" content=\"180\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/come-nasce-lintegralismo-islamico-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/come-nasce-lintegralismo-islamico-2\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"4 &#8211; Come nasce l&#8217;integralismo islamico\",\"datePublished\":\"2004-11-10T10:15:17+00:00\",\"dateModified\":\"2024-01-05T16:47:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/come-nasce-lintegralismo-islamico-2\\\/\"},\"wordCount\":1511,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/come-nasce-lintegralismo-islamico-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2004\\\/11\\\/sauditi.jpg\",\"keywords\":[\"islam\",\"Islam fondamentalismo\"],\"articleSection\":[\"Islam\",\"Islam fondamentalismo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/come-nasce-lintegralismo-islamico-2\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/come-nasce-lintegralismo-islamico-2\\\/\",\"name\":\"4 - Come nasce l'integralismo islamico - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/come-nasce-lintegralismo-islamico-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/come-nasce-lintegralismo-islamico-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2004\\\/11\\\/sauditi.jpg\",\"datePublished\":\"2004-11-10T10:15:17+00:00\",\"dateModified\":\"2024-01-05T16:47:22+00:00\",\"description\":\"Come nasce l'integralismo islamico. Il termine \\\"moderati\\\" \u00e8 un\u2019espressione di comodo, un termine che non indica affatto un\u2019identit\u00e0 politica\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/come-nasce-lintegralismo-islamico-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/come-nasce-lintegralismo-islamico-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/come-nasce-lintegralismo-islamico-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2004\\\/11\\\/sauditi.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2004\\\/11\\\/sauditi.jpg\",\"width\":280,\"height\":180},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/come-nasce-lintegralismo-islamico-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"4 &#8211; Come nasce l&#8217;integralismo islamico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"4 - Come nasce l'integralismo islamico - Rassegna Stampa Cattolica","description":"Come nasce l'integralismo islamico. Il termine \"moderati\" \u00e8 un\u2019espressione di comodo, un termine che non indica affatto un\u2019identit\u00e0 politica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/come-nasce-lintegralismo-islamico-2\/","og_locale":"it_IT","og_type":"article","og_title":"4 - Come nasce l'integralismo islamico - Rassegna Stampa Cattolica","og_description":"Come nasce l'integralismo islamico. Il termine \"moderati\" \u00e8 un\u2019espressione di comodo, un termine che non indica affatto un\u2019identit\u00e0 politica","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/come-nasce-lintegralismo-islamico-2\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2004-11-10T10:15:17+00:00","article_modified_time":"2024-01-05T16:47:22+00:00","og_image":[{"width":280,"height":180,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2004\/11\/sauditi.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"9 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/come-nasce-lintegralismo-islamico-2\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/come-nasce-lintegralismo-islamico-2\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"4 &#8211; Come nasce l&#8217;integralismo islamico","datePublished":"2004-11-10T10:15:17+00:00","dateModified":"2024-01-05T16:47:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/come-nasce-lintegralismo-islamico-2\/"},"wordCount":1511,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/come-nasce-lintegralismo-islamico-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2004\/11\/sauditi.jpg","keywords":["islam","Islam fondamentalismo"],"articleSection":["Islam","Islam fondamentalismo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/come-nasce-lintegralismo-islamico-2\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/come-nasce-lintegralismo-islamico-2\/","name":"4 - Come nasce l'integralismo islamico - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/come-nasce-lintegralismo-islamico-2\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/come-nasce-lintegralismo-islamico-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2004\/11\/sauditi.jpg","datePublished":"2004-11-10T10:15:17+00:00","dateModified":"2024-01-05T16:47:22+00:00","description":"Come nasce l'integralismo islamico. Il termine \"moderati\" \u00e8 un\u2019espressione di comodo, un termine che non indica affatto un\u2019identit\u00e0 politica","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/come-nasce-lintegralismo-islamico-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/come-nasce-lintegralismo-islamico-2\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/come-nasce-lintegralismo-islamico-2\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2004\/11\/sauditi.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2004\/11\/sauditi.jpg","width":280,"height":180},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/come-nasce-lintegralismo-islamico-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"4 &#8211; Come nasce l&#8217;integralismo islamico"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/87","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=87"}],"version-history":[{"count":5,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/87\/revisions"}],"predecessor-version":[{"id":58886,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/87\/revisions\/58886"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/32702"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=87"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=87"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=87"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}