{"id":868,"date":"2005-07-10T00:00:00","date_gmt":"2005-07-09T22:00:00","guid":{"rendered":""},"modified":"2016-02-26T10:42:26","modified_gmt":"2016-02-26T09:42:26","slug":"il-superesercito-di-kim","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-superesercito-di-kim\/","title":{"rendered":"Il superesercito di Kim"},"content":{"rendered":"<div style=\"text-align: center;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/nord_Corea_army.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-31022\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/nord_Corea_army.jpg\" alt=\"nord_Corea_army\" width=\"250\" height=\"172\" \/><\/a>Articolo pubblicato su la <strong>Repubblica<\/strong><\/div>\n<div style=\"text-align: center;\">del 27 luglio 2004<\/div>\n<p style=\"text-align: center;\"><em>\u00abIn divisa per avere rispetto\u00bb<\/em><\/p>\n<p style=\"text-align: center;\">di <strong>Marcello Ansaldo <\/strong>(inviato)<\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">KAESONG (COREA DEL NORD) &#8211; Viaggiando in Corea del Nord capita spesso di imbattersi in sciami di scolari che tornano al villaggio con l\u2019immancabile divisa, talvolta imbrattata di terra. \u00abQuanti anni hanno?\u00bb, si chiede indicando una classe di alunni che sembrano di seconda elementare. \u00abUndici\u00bb, \u00e8 la risposta. E che cosa mangiano?\u00a0 \u00abRiso, verdure\u00bb. E poi? \u00abQuello che trovano, anche bacche, foglie, radici\u00bb.<\/div>\n<p style=\"text-align: justify;\">Se nella capitale Pyongyang i bambini sono festosi e paffuti, lo stesso non pu\u00f2 dirsi dei loro compagni che vivono nella periferia pi\u00f9 profonda del Regno eremita. Jong Sun, un paio di treccine nere dietro uno sguardo smunto, \u00e8 figlia di agricoltori di Kaesong, non lontano dal confine che divide la penisola. Ha 7 anni ma \u00e8 20 centimetri pi\u00f9 bassa e pesa una decina di chili in meno rispetto a una sua coetanea della Corea del Sud. I 200 grammi che racimola in giro ogni giorno la portano, assieme a pochi altri alimenti, al misero totale di 700 calorie, essendo proteine e grassi di solito non disponibili nella dieta.<\/p>\n<p style=\"text-align: justify;\">I nordcoreani oggi non muoiono pi\u00f9 di fame, ma il men\u00f9 del regime \u00e8 scarso e varia a seconda delle zone e dell\u2019attivit\u00e0 svolta. A Pyongyang si mangia di pi\u00f9 e meglio rispetto a Kaesong. N\u00e9 mancano i ristoranti. Ogni citt\u00e0, grande o piccola, ne ha di buoni: puliti e aerati, con le tovaglie linde, il pesce secco o fresco condito nei piattini di ceramica colorata, le zuppe fumanti servite da eleganti cameriere con l\u2019immancabile distintivo di K\u00ecm Il Sung appuntato sulla giacca rossa.<\/p>\n<p style=\"text-align: justify;\">I clienti non mancano: turisti, funzionari, diplomatici, quadri del partito, operatori umanitari, ospiti. Il conto \u00e8 salato, eppure esistono famiglie disposte a sacrificare l\u2019equivalente dello stipendio mensile di un impiegato per andare una sera a mangiar fuori in un posto decente e ben illuminato. Le razioni migliori spettano per\u00f2 all\u2019esercito. Ecco perch\u00e9 molti ragazzi, terminato il periodo di leva definito \u00abvolontario\u00bb che varia dai 5 agli 8 anni (fino a 6 per le donne), decidono per la ferma. Entrare nelle forze armate significa salire nella scala e nella considerazione sociale.<\/p>\n<p style=\"text-align: justify;\">All\u2019ombra delle caserme che, recintate e inaccessibili, spuntano ovunque nel montagnoso paesaggio coreano, ci sono cibo e vestiti. E possibilit\u00e0 di accedere alle cariche del partito dei lavoratori del popolo. Poco importa se durante gli anni di leva non siano previsti congedi, e ogni dodici mesi le lettere ammesse alla famiglia siano appena un paio.<\/p>\n<p style=\"text-align: justify;\">Le scuole appaiono disadorne, ma disciplina e istruzione sono ferree. Le condizioni peggiori appartengono per\u00f2 agli ospedali. Norbert Vollertsen, un medico tedesco, le definisce \u00aborrbili\u00bb. \u00abSono senza riscaldamento o senz\u2019acqua &#8211; spiega &#8211; alcune cliniche sembrano ferme all\u2019et\u00e0 della pietra. Ho riscontrato malnutrizione, infezioni, disordini intestinali dovuti a deficienza vitaminiche e alimentari, ma le diagnosi pi\u00f9 importanti riguardano stati di depressione e paura\u00bb.<\/p>\n<p style=\"text-align: justify;\">Non pochi ospedali nordcoreani dispongono di strutture decenti e personale competente, formatosi soprattutto in Germania Est. E\u2019 il materiale a scarseggiare. Non ci sono antibiotici, anestetici, siringhe, guanti chirurgici. Al posto delle flebo vengono appese delle lattine di birra.<\/p>\n<p style=\"text-align: justify;\">La Corea comunista non mangia, ma si arma. Spende un terzo del suo Pil in progetti di Difesa. vende missili balistici a Siria, Iran e Yemen. Produce armi chimiche e biologiche. L\u2019esercito, che risponde direttamente agli ordini di Kim Jong Il, \u00e8 composto da un milione e duecentomila uomini. Addentrarsi nelle pieghe interne del paese significa imbattersi ogni giorno, a ogni angolo, in giovani vestiti di panno verde bloccati sull\u2019attenti, immobili, solitari, con l\u2019evidente consegna di coprire il punto di visuale consentito dalla posizione occupata. nelle campagne soldati impenetrabili si succedono uno ogni cento metri. Sbucano dietro gli alberi, sopra un cippo, dopo una galleria, regalando all\u2019ospite la sensazione di una realt\u00e0 sigillata.<\/p>\n<p style=\"text-align: justify;\">Kaesong, cittadina che conduce all\u2019ingresso della zona smilitarizzata di Panmunjom sul fatidico 38mo parallelo e che si raggiunge da Pyongyang con un treno piombato, pullula di soldati. A Goseong, altro varco fra le due Coree, le pattuglie di frontiera hanno la faccia truce, i modi spicci e le baionette innestate sui fucili. Un\u2019atmosfera da Guerra fredda.<\/p>\n<p style=\"text-align: justify;\">Sul regime grava il sospetto di dotarsi, o di essere in procinto di farlo, della bomba atomica. Quanto meno di possedere nella centrale di Yongbyon plutonio sufficiente ad assemblare pi\u00f9 ordigni nucleari. Pyongyang ha ora ammesso per la prima volta di brandire l\u2019arma letale. \u00abIl nostro paese &#8211; recita un comunicato del ministero degli Esteri &#8211; ha ripreso l\u2019attivit\u00e0 nucleare per scopi pacifici. Stiamo costruendo un nuovo reattore a grafite per il quale abbiamo terminato la conversione di 8 mila barre di combustibile spento, ma in futuro, per far fronte all\u2019atteggiamento ostile degli Stati Uniti, il plutonio cos\u00ec ottenuto potrebbe essere destinato ad aumentare la nostra forza di deterrenza atomica\u00bb.<\/p>\n<p style=\"text-align: justify;\">Il caso nucleare \u00e8 adesso oggetto di una complicata partita diplomatica a sei, dove i tentativi di Usa, Russia, Giappone e Corea del Sud di far accedere la Corea del Nord (affiancata dall\u2019alleata Cina) dai suoi minacciosi propositi, si scontrano su un tavolo esagonale il cui colore verde d\u00e0 un tocco di ottimismo alla flebile speranza di un accordo. ma l\u2019impressione generale \u00e8 che prima di muovere qualsiasi passo, Pyongyang attenda il responso delle urne americane.<\/p>\n<p style=\"text-align: justify;\">La vittoria dei democratici \u00e8 infatti guardata con una certa impazienza dal Regno eremita, che ha sperimentato le intransigenze di Bush dopo le generose aperture di Clinton, capace di inviare la Albright da Kim Jon Il.<\/p>\n<p style=\"text-align: justify;\">Una leggenda metropolitana che circola sul 38mo parallelo evidenzia la preferenza accordata dal \u00abCaro leader\u00bb allo sfidante Kerry. Nella recente visita compiuta dal premier giapponese Koizumi a Pyongyang, la delegazione nipponica avrebbe lasciato nelle mani degli agenti i telefoni cellulari, non ammessi in Corea del Nord. Si narra che le guardie del corpo di Kim, giocando con l\u2019agenda elettronica del primo ministro di Tokyo abbiano trovato il numero del presidente Usa e gli abbiano inviato a nome del governo del Sol levante il seguente messaggio in inglese: UR a loser, Kerry 4 prez (sei un perdente, Kerry diventi presidente).<\/p>\n<p style=\"text-align: justify;\">Croller\u00e0 prima o poi Kim Jong Il? \u00abSono sicura di no &#8211; dice con filo di voce una donna di 67 anni, maestra di danza, che ne ha passati 8 nel campo di concentramento di Yodok per il solo aver spettegolato sulla moglie del Capo, da lui accantonata per un\u2019attrice &#8211; quando Kim Il Sung ha tramandato il potere al figlio gli ha detto: lascia perdere l\u2019amministrazione, guarda piuttosto alla potenza militare\u00bb.<\/p>\n<p style=\"text-align: justify;\">Sono i gulag infatti lo spauracchio di oppositori e nemici. Oggi ammonterebbero a 23, concentrati soprattutto nell\u2019est del paese. Duecentomila prigionieri. Le storie raccontate dai rari fuggiaschi, una volta raggiunto il confine pi\u00f9 permeabile, quello cinese, non promettono nulla di buono sulla prospettiva di rimettere insieme famiglie separate da 50 ani di aperta ostilit\u00e0.<\/p>\n<p style=\"text-align: justify;\">\u00abKorea is one\u00bb, ripetono come automi\u00a0i sudditi del Nord a ogni visitatore. Ma nonostante i proclami dell\u2019una e dell\u2019altra capitale la riunificazione appare un sogno irrealistico, il suo desiderio un\u2019ipocrisia. Specie per l\u2019insopportabile atteggiamento da colonizzatori adottato da molti sudcoreani mentre, varcando la frontiera, visitano terre che a dar loro retta gli apparterrebbero da sempre.<\/p>\n<p style=\"text-align: justify;\">Ammette un diplomatico occidentale: \u00abNon lo si pu\u00f2 dire, ma in realt\u00e0 nessuno, tranne la Corea del Nord, vuole la riunificazione. Non la vogliono, per motivi diversi, le grandi potenze che vedrebbero modificare l\u2019attuale assetto geopolitica. E non la cerca il governo del Sud, che si vedrebbe cadere addosso il fardello di 22 milioni di disperati\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Articolo pubblicato su la Repubblica del 27 luglio 2004 \u00abIn divisa per avere rispetto\u00bb di Marcello Ansaldo (inviato)<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-superesercito-di-kim\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":31022,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[32,71,108],"tags":[139,2397],"class_list":["post-868","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-filosofia-del-comunismo","category-corea-del-nord","category-paesi-e-continenti","tag-comunismo","tag-corea-del-nord","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il superesercito di Kim - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-superesercito-di-kim\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il superesercito di Kim - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-superesercito-di-kim\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2005-07-09T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-02-26T09:42:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/nord_Corea_army.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"271\" \/>\n\t<meta property=\"og:image:height\" content=\"186\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-superesercito-di-kim\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-superesercito-di-kim\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Il superesercito di Kim\",\"datePublished\":\"2005-07-09T22:00:00+00:00\",\"dateModified\":\"2016-02-26T09:42:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-superesercito-di-kim\\\/\"},\"wordCount\":1258,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-superesercito-di-kim\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/07\\\/nord_Corea_army.jpg\",\"keywords\":[\"comunismo\",\"Corea del Nord\"],\"articleSection\":[\"Comunismo\",\"Corea del Nord\",\"Paesi e continenti\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-superesercito-di-kim\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-superesercito-di-kim\\\/\",\"name\":\"Il superesercito di Kim - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-superesercito-di-kim\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-superesercito-di-kim\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/07\\\/nord_Corea_army.jpg\",\"datePublished\":\"2005-07-09T22:00:00+00:00\",\"dateModified\":\"2016-02-26T09:42:26+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-superesercito-di-kim\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-superesercito-di-kim\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-superesercito-di-kim\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/07\\\/nord_Corea_army.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/07\\\/nord_Corea_army.jpg\",\"width\":271,\"height\":186},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-superesercito-di-kim\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il superesercito di Kim\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il superesercito di Kim - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-superesercito-di-kim\/","og_locale":"it_IT","og_type":"article","og_title":"Il superesercito di Kim - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-superesercito-di-kim\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2005-07-09T22:00:00+00:00","article_modified_time":"2016-02-26T09:42:26+00:00","og_image":[{"width":271,"height":186,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/nord_Corea_army.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-superesercito-di-kim\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-superesercito-di-kim\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Il superesercito di Kim","datePublished":"2005-07-09T22:00:00+00:00","dateModified":"2016-02-26T09:42:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-superesercito-di-kim\/"},"wordCount":1258,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-superesercito-di-kim\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/nord_Corea_army.jpg","keywords":["comunismo","Corea del Nord"],"articleSection":["Comunismo","Corea del Nord","Paesi e continenti"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-superesercito-di-kim\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-superesercito-di-kim\/","name":"Il superesercito di Kim - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-superesercito-di-kim\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-superesercito-di-kim\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/nord_Corea_army.jpg","datePublished":"2005-07-09T22:00:00+00:00","dateModified":"2016-02-26T09:42:26+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-superesercito-di-kim\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-superesercito-di-kim\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-superesercito-di-kim\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/nord_Corea_army.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/nord_Corea_army.jpg","width":271,"height":186},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-superesercito-di-kim\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Il superesercito di Kim"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/868","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=868"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/868\/revisions"}],"predecessor-version":[{"id":31023,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/868\/revisions\/31023"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/31022"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=868"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=868"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=868"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}