{"id":844,"date":"2005-07-06T14:09:03","date_gmt":"2005-07-06T12:09:03","guid":{"rendered":""},"modified":"2016-03-22T17:25:10","modified_gmt":"2016-03-22T16:25:10","slug":"la-forza-dellidentit","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-forza-dellidentit\/","title":{"rendered":"La forza dell&#8217;identit&agrave;"},"content":{"rendered":"<div style=\"text-align: center;\">\n<div id=\"attachment_32043\" style=\"width: 146px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-32043\" class=\"wp-image-32043\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/Marcello_Pera.jpg\" alt=\"Marcello_Pera\" width=\"146\" height=\"200\" \/><p id=\"caption-attachment-32043\" class=\"wp-caption-text\">Marcello Pera<\/p><\/div>\n<p>Discorso pronunciato dal Presidente del Senato <strong>Marcello Pera<\/strong><\/div>\n<div style=\"text-align: center;\">alla Fundaci\u00f2n para el an\u00e0lisis y los estudios sociales<\/div>\n<p style=\"text-align: justify;\"><em>L&#8217;europa e l&#8217;occidente di fronte alle conseguenze dell&#8217;odio relativista verso le proprie radici, la salvezza \u00e8 nella forza dell&#8217;identit\u00e0 cristiana, valida\u00a0sia per chi crede e anche per chi non crede<\/em><\/p>\n<p style=\"text-align: center;\">Madrid, 4 luglio 2005<\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\"><strong>1. L<\/strong><strong>&#8216;Europa<\/strong><\/div>\n<p style=\"text-align: justify;\">Ho scelto di dedicare questo mio intervento alla forza dell&#8217;identit\u00e0 perch\u00e9 questa forza oggi ci manca e perch\u00e9 sono convinto che questa mancanza sia all&#8217;origine delle nostre difficolt\u00e0. Cercher\u00f2 di dare risposta a tre domande. A chi manca la forza dell&#8217;identit\u00e0? Perch\u00e9 manca la forza dell&#8217;identit\u00e0? Come si conquista la forza dell&#8217;identit\u00e0?<\/p>\n<p style=\"text-align: justify;\">Entro subito in argomento e comincio con la risposta alla prima domanda. Il primo soggetto a cui manca la forza dell&#8217;identit\u00e0 \u00e8 l&#8217;Europa.<\/p>\n<p style=\"text-align: justify;\">Consideriamo la situazione prima dell&#8217;attuale fallimento della Costituzione europea. L&#8217;Europa aveva davanti a s\u00e9 due strade. Una era quella di diventare una grande area di libero mercato con le minime istituzioni economiche necessarie a farla funzionare. L&#8217;altra strada era quella di diventare una grande forza geopolitica. Le due strade non sono necessariamente incompatibili, perch\u00e9 una grande forza geopolitica \u00e8 anche una grande forza economica. Ma le due strade non sono necessariamente convergenti, perch\u00e9 possono esistere grandi aree economiche senza grande peso politico.<\/p>\n<p style=\"text-align: justify;\">L&#8217;Europa oggi \u00e8 esattamente questo caso, perch\u00e9 non ha imboccato nessuna di queste due strade. Non ha imboccato la prima strada, perch\u00e9 l&#8217;Europa di oggi \u00e8 s\u00ec un&#8217;area di elevato benessere economico, ma non \u00e8 competitiva rispetto ad altre aree. Non \u00e8 competitiva con l&#8217;America che continua ad avanzarla, e cresce meno della Cina e dell&#8217;India.<\/p>\n<p style=\"text-align: justify;\">Quando si rese conto di questa situazione, l&#8217;Europa si dette un&#8217;agenda, l&#8217;agenda di Lisbona 2000. Se uno la rileggesse e confrontasse quanto l\u00ec \u00e8 scritto con la situazione di oggi, difficilmente si sottrarrebbe all&#8217;impressione di trovarsi di fronte ad uno di quei famosi piani decennali con cui l&#8217;Unione Sovietica, prima di scomparire senza che lo sapesse, si riprometteva di l\u00ec a poco di superare gli Stati Uniti.<\/p>\n<p style=\"text-align: justify;\">In quel documento si stabil\u00ec che, in dieci anni, l&#8217;Europa sarebbe diventata \u00abla societ\u00e0 basata sulla conoscenza pi\u00f9 competitiva e dinamica del mondo, capace di crescita economica con pi\u00f9 e migliori posti di lavoro e pi\u00f9 coesione economica\u00bb.<\/p>\n<p style=\"text-align: justify;\">Guardiamoci attorno e tratteniamoci dall&#8217;ironia. La strada indicata a Lisbona l&#8217;Europa non l&#8217;ha imboccata. Ha detto pochi giorni fa, il 23 giugno, il premier Tony Blair a Strasburgo: \u00abDitemi: che tipo di modello sociale \u00e8 quello in cui ci sono venti milioni di disoccupati in Europa, che fa calare i tassi di produttivit\u00e0 sotto quelli americani, che produce pi\u00f9 laureati in scienze in India che in Europa?\u00bb.<\/p>\n<p style=\"text-align: justify;\">Pi\u00f9 di un anno fa, il premier Jos\u00e9 Aznar, intervistato da <em>Le Monde,<\/em> aveva dichiarato la stessa cosa: \u00abNon c&#8217;\u00e8 da vantarsi di un modello che produce milioni di disoccupati\u00bb. Ma l&#8217;Europa non ha preso neppure la seconda strada. Una grande potenza geopolitica \u00e8 una potenza che assume su di s\u00e9, da sola o assieme ad altre, responsabilit\u00e0 politiche internazionali. \u00c8 un soggetto mondiale con compiti mondiali. Non pu\u00f2 stare chiusa in casa, n\u00e9 pu\u00f2 stare alla finestra a guardare i suoi problemi sperando che passino e siano risolti da altri.<\/p>\n<p style=\"text-align: justify;\">Invece, questo \u00e8 proprio ci\u00f2 che ha fatto l&#8217;Europa.\u00a0L&#8217;ha fatto con la guerra in Iraq, e continua a farlo con Israele, il Medio Oriente, l&#8217;Iran, e tutte quelle crisi in cui l&#8217;Europa si astiene dal prendere posizione o intervenire. Come se essa non fosse interessata, come se potesse fare da spettatrice, come se potesse delegare all&#8217;America &#8211; salvo poi a criticare l&#8217;America &#8211; le proprie responsabilit\u00e0 e decisioni.<\/p>\n<p style=\"text-align: justify;\">Ritengo che sia stato un errore pensare di costruire l&#8217;Europa come un &#8220;contrappeso&#8221; dell&#8217;America o aver cercato di allargare l&#8217;Oceano atlantico opponendo una &#8220;visione europea&#8221; a una diversa e opposta &#8220;visione americana&#8221;. Su questo punto, condivido ci\u00f2 che Jos\u00e9 Aznar dichiar\u00f2 a La Vanguardia nel gennaio 2003: \u00abMi sembra assolutamente ingiusto da parte degli europei accusare gli Stati Uniti di unilateralismo e allo stesso tempo rifiutare di assumere responsabilit\u00e0 in materia di sicurezza\u00bb.<\/p>\n<p style=\"text-align: justify;\">Ora che questo disegno ha mostrato i suoi limiti e la Costituzione europea &#8211; un macigno di diritto e un monumento di velleit\u00e0 &#8211; \u00e8 fallita, trovo inutile spargere eurolacrime, cos\u00ec come prima mi sembrava vacuo spargere euroretorica. Dobbiamo piuttosto partire da capo. In due modi. Con le riforme economiche e sociali senza le quali l&#8217;Europa \u00e8 grossa ma non grande, e cio\u00e8 la flessibilit\u00e0, la competivit\u00e0, la riduzione dello stato sociale, le liberalizzazioni, le privatizzazioni, l&#8217;innovazione tecnologica, la ricerca scientifica. Ma, in primo luogo, cominciando a chiederci in che cosa consista la nostra identit\u00e0. Perch\u00e9 solo chi ha identit\u00e0 \u00e8 un soggetto che ha obiettivi.<\/p>\n<p style=\"text-align: justify;\"><strong>2. L<\/strong><strong>&#8216;Occidente<\/strong><\/p>\n<p style=\"text-align: justify;\">L&#8217;altro soggetto cui manca o rischia di mancare la forza dell&#8217;identit\u00e0 \u00e8 l&#8217;intero Occidente. Il senso di identit\u00e0 nasce spesso, negli individui e nei popoli, per contrasto, quando le circostanze della storia o della vita ci costringono a distinguere &#8220;noi&#8221; dagli &#8220;altri&#8221;. In Occidente, ci\u00f2 sarebbe potuto accadere di fronte al fenomeno della rinascita islamica. Ma non \u00e8 accaduto, o \u00e8 accaduto raramente e prevalentemente in America.<\/p>\n<p style=\"text-align: justify;\">In un agghiacciante comunicato diffuso dopo il massacro di Madrid dell&#8217;11 marzo 2004, si dice che \u00aboggi Al Qaeda, qualunque denominazione locale assuma, ha distrutto negli occidentali, educati dai loro media a ritenere ormai minimizzato il pericolo del terrorismo, il loro senso di sicurezza\u00bb. In centinaia di altri comunicati si proclama la \u00abjihad contro ebrei e crociati\u00bb. Ci\u00f2 significa che noi diventiamo bersaglio, in quanto occidentali, non per quello che facciamo, ma per quello che siamo. La nostra colpa non \u00e8 l&#8217;agire, ma l&#8217;essere. In altri termini, per i terroristi, la nostra colpa \u00e8 la nostra identit\u00e0.<\/p>\n<p style=\"text-align: justify;\">Come abbiamo reagito? Abbiamo forse rivendicato la nostra identit\u00e0 di ebrei e crociati? Ne abbiamo provato orgoglio? Il contrario. Di fronte al fondamentalismo e al terrorismo islamico, si \u00e8 sparso per l&#8217;Occidente un senso di rassegnazione, di rimozione e anche di resa. Il pensiero medio e diffuso \u00e8 stato pi\u00f9 o meno il seguente.<\/p>\n<p style=\"text-align: justify;\">Se ci sono fondamentalisti e terroristi che ci definiscono &#8220;il Grande Satana&#8221;, che ci considerano una civilt\u00e0 degradata, che ci dichiarano la jihad, allora deve esserci una ragione. Se c&#8217;\u00e8 una ragione, essa deriva da un&#8217;ingiustizia. Se c&#8217;\u00e8 un&#8217;ingiustizia, qualcuno l&#8217;ha provocata. Se qualcuno l&#8217;ha provocata, allora \u00e8 l&#8217;Occidente ricco che \u00e8 colpevole. E se l&#8217;Occidente \u00e8 colpevole, alla fine la jihad \u00e8 la ricompensa dei suoi misfatti.<\/p>\n<p style=\"text-align: justify;\">Alcuni leader europei hanno ragionato pi\u00f9 o meno cos\u00ec, pensando all&#8217;America. Milioni di pacifisti occidentali li hanno seguiti. Molti intellettuali li hanno guidati. Noam Chomsky, ad esempio, ha sostenuto che gli Stati Uniti sono \u00abuno Stato guida del terrorismo\u00bb. Jos\u00e9 Saramago ha scritto che \u00abIsraele deve ancora imparare parecchio se non \u00e8 capace di comprendere le ragioni che possono portare un essere umano a trasformarsi in una bomba\u00bb.<\/p>\n<p style=\"text-align: justify;\">Accanto a tanti che hanno preso le difese o sostenuto le ragioni dei fondamentalisti, non \u00e8 mancato chi ha fatto di tutta l&#8217;erba un solo fascio occidentale. Nel suo libro<em> Al Qaeda e che cosa significa essere moderno<\/em> (2003), il professor John Gray della London School of Economics ha scritto: \u00abil comunismo sovietico, il nazionalsocialismo e il fondamentalismo islamico sono stati tutti descritti come assalti all&#8217;Occidente. In realt\u00e0, ciascuno di questi tre disegni si capisce meglio se lo si intende come un tentativo di realizzare un moderno ideale europeo\u00bb.<\/p>\n<p style=\"text-align: justify;\">Ecco come si presenta oggi l&#8217;Occidente: come una terra di penitenti che si battono il petto ogni volta che qualcuno gli sferra un colpo.<\/p>\n<p style=\"text-align: justify;\"><strong>3. Il relativismo<\/strong><\/p>\n<p style=\"text-align: justify;\">Perch\u00e9? Siamo con ci\u00f2 alla seconda questione che mi sono posto: qual \u00e8 la ragione di questo indebolimento della nostra identit\u00e0?<\/p>\n<p style=\"text-align: justify;\">A questa ragione ho dato pi\u00f9 volte un nome: relativismo culturale. \u00c8 noto di che cosa si tratta. Si tratta dell&#8217;idea che le tradizioni, le culture, le civilt\u00e0, sono sistemi autonomi e chiusi, ciascuna con propri criteri di valore, procedure, istituzioni. Si tratta dell&#8217;idea correlata che questi sistemi chiusi sono tra loro non commensurabili, per cui non pu\u00f2 esistere una scala comune lungo la quale collocarle e misurarle tutte in termini di superiorit\u00e0, desiderabilit\u00e0, attrattivit\u00e0, bont\u00e0, giustezza, eccetera. Alla fine, si tratta dell&#8217;idea che questi sistemi hanno tutti la stessa dignit\u00e0 etica, politica, sociale, sono tutti da rispettare, sono tutti uguali. Tutti: i fondamentalisti come i democratici, i fanatici come i liberali, i violenti come gli umanitari, gli intolleranti come i dialoganti.<\/p>\n<p style=\"text-align: justify;\">Quello che oggi, in Occidente, si chiama &#8220;linguaggio politicamente corretto&#8221; \u00e8 il linguaggio del relativismo. Esso \u00e8 una sorta di &#8220;neolingua&#8221; orwelliana con cui in apparenza si descrivono le cose con parole educate, ma in sostanza si usano le parole per nascondere le cose sgradite.<\/p>\n<p style=\"text-align: justify;\">Guardate gli effetti di questa \u00abrieducazione linguistica\u00bb. Fra noi, in Occidente, possiamo dirci molte cose e fissare molte gerarchie. Ad esempio, possiamo dire che Gaud\u00ec \u00e8 migliore di Le Courbusier, o che il Rioja \u00e8 migliore della Coca Cola, o che la Sacher torte \u00e8 migliore del Turron.Ma degli altri o delle cose degli altri non possiamo dire altrettanto. E se qualcuno cerca di dirlo, scatta la censura linguistica e la scomunica politica. Cos\u00ec accade, ad esempio, quando volessimo dire che una democrazia occidentale \u00e8 migliore di una teocrazia islamica, che una costituzione liberale \u00e8 migliore della sharia, che la libera societ\u00e0 civile \u00e8 migliore della umma, che la sentenza di un tribunale indipendente \u00e8 migliore di una fatwa, e cos\u00ec via.<\/p>\n<p style=\"text-align: justify;\">Torna la domanda: perch\u00e9? La mia risposta \u00e8: perch\u00e9 l&#8217;Occidente, affetto da relativismo, pensa che se affermasse i propri princ\u00ecpi e valori e mostrasse la forza della propria identit\u00e0, allora sarebbe un Occidente arrogante, sprezzante, protervo. E siccome l&#8217;Occidente intende invece essere aperto e dialogante con tutti, ecco che, piuttosto che difendere se stesso, indebolisce e nasconde la propria identit\u00e0. Samuel Huntington, che \u00e8 stranamente considerato il fautore dello scontro fra civilt\u00e0 mentre invece ne \u00e8 un esorcizzatore, ha scritto: \u00abla fede occidentale nella validit\u00e0 universale della propria cultura ha tre difetti: \u00e8 falsa; \u00e8 immorale; \u00e8 pericolosa\u00bb.<\/p>\n<p style=\"text-align: justify;\">Se questo \u00e8 il pensiero occidentale, se davvero si crede che la parit\u00e0 fra uomo e donna valga solo per noi, che la democrazia sia un costume nostro, che la libert\u00e0 della societ\u00e0 civile sia valida fra le nostre mura, che le libere istituzioni siano buone solo per noi, insomma, se davvero si crede che tutto ci\u00f2 che vale per noi non vale per gli altri, allora non c&#8217;\u00e8 da meravigliarsi che noi storciamo il naso quando si parla di esportazione o diffusione della democrazia, o arrossiamo quando si discute di diritti umani, o ci blocchiamo quando si deve stendere una lista di organizzazioni terroristiche, o ci nascondiamo quando vediamo rinascere l&#8217;antisemitismo.<\/p>\n<p style=\"text-align: justify;\"><strong>4. La forza dell&#8217;identit\u00e0<\/strong><\/p>\n<p style=\"text-align: justify;\">Sono all&#8217;ultimo punto. Come invertire la rotta della perdita progressiva della nostra identit\u00e0? Gli aspetti del problema sono molti e qui desidero richiamarne uno, quello dei valori, in particolare dei valori cristiani.<\/p>\n<p style=\"text-align: justify;\">Non sono un credente, sono un laico. Ma una precisazione \u00e8 fondamentale: non sono un laicista. Laico \u00e8 colui che non aderisce ad una religione o confessione specifica, laicista \u00e8 colui che, nel nome della laicit\u00e0 dello Stato e della politica, impone una propria religione di Stato e una propria religione politica. Faccio qualche esempio. \u00c8 laicista quello Stato che vieta il velo nelle scuole alle ragazze musulmane.<\/p>\n<p style=\"text-align: justify;\">\u00c8 laicista quello Stato che vietasse il crocefisso o le preghiere nelle scuole o nei luoghi pubblici. \u00c8 laicista quello Stato che proibisse agli uomini di chiesa di predicare la propria missione o di prendere posizione su questioni pubbliche. Ed \u00e8 laicista quello Stato che fa sulla societ\u00e0 esperimenti di ingegneria per cambiare o cancellare con la forza della legge istituti fondati su valori della religione e della tradizione, come la famiglia e il matrimonio.<\/p>\n<p style=\"text-align: justify;\">In Italia il pensiero laicista ha imposto un referendum al Paese contro una legge di compromesso approvata dal Parlamento su materie delicatissime come la procreazione assistita e la manipolazione degli embrioni per la ricerca medica. In quel referendum il laicismo \u00e8 stato sconfitto in modo clamoroso grazie ad una alleanza niente affatto clericale tra la Chiesa, il sentimento profondo dei cittadini, e una minoranza di laici non laicisti.<\/p>\n<p style=\"text-align: justify;\">Questa alleanza aveva tutti contro: i grandi giornali, il ceto intellettuale, attori del cinema, divi della scienza, quasi tutta l&#8217;area politica cosiddetta &#8220;progressista&#8221; e &#8220;illuminista&#8221;. Costoro hanno perso non perch\u00e9 gli italiani siano diventati clericali o oscurantisti o medievali, ma perch\u00e9 si sono ribellati all&#8217;arroganza del pensiero elitario laicista e si sono preoccupati di porre limiti all&#8217;onnipotenza della scienza in nome della tutela della vita.<\/p>\n<p style=\"text-align: justify;\">In Spagna le cose sono andate diversamente. Qui l&#8217;attacco \u00e8 stato mosso all&#8217;idea stessa di matrimonio con una manovra a tenaglia: da un lato il divorzio lampo, dall&#8217;altro il matrimonio omosessuale. Cos\u00ec una bella fetta della nostra identit\u00e0 se ne \u00e8 volata via. Come evolver\u00e0 la situazione non posso dire. Una cosa per me \u00e8 chiara: \u00e8 falso che si tratti di &#8220;conquiste civili&#8221; o di misure &#8220;contro le discriminazioni&#8221; o di &#8220;estensione dell&#8217;uguaglianza&#8221;; si tratta piuttosto del trionfo di quel laicismo che pretende di trasformare i desideri, e talvolta anche i capricci, in diritti umani fondamentali.<\/p>\n<p style=\"text-align: justify;\">Questo laicismo a me sembra antistorico e anche pericoloso. L&#8217;Europa in particolare ne \u00e8 vittima. Quella stessa Europa che, nella sua Costituzione, vieta la \u00abclonazione riproduttiva\u00bb, aprendo la strada a quella terapeutica e, con essa, a qualunque esperimento sugli embrioni. O quell&#8217;Europa che, sempre nella sua Costituzione, riconosce \u00abil diritto di sposarsi e di costruire una famiglia\u00bb, senza precisare chi con chi, legittimando cos\u00ec, anche da defunta, legislazioni come quella spagnola.<\/p>\n<p style=\"text-align: justify;\">Oppure quell&#8217;Europa, che, nel preambolo generale alla sua Costituzione, afferma di ispirarsi alle sue \u00aberedit\u00e0 culturali, religiose e umanistiche\u00bb, e, nel preambolo alla seconda parte della stessa Costituzione, parla del suo \u00abpatrimonio spirituale e morale\u00bb, ma senza specificare mai quali religioni e quale religione in particolare.<\/p>\n<p style=\"text-align: justify;\">Credo che nascondere la nostra tradizione cristiana sia, oltre che un omaggio al laicismo, anche un passo falso. Coloro che pi\u00f9 lo hanno compiuto oggi pi\u00f9 ne pagano il prezzo. A fronte alla crisi dell&#8217;Europa, e al senso di incertezza., insicurezza, diffidenza, paura che si diffonde fra i nostri cittadini, rinasce prepotente un sentimento del sacro, un bisogno di fede, una voglia di spiritualit\u00e0. E cos\u00ec ci\u00f2 che si \u00e8 voluto espungere dalle carte europee riemerge nelle famiglie, nelle piazze, nelle chiese, fra la gente. \u00c8 una richiesta di identit\u00e0, che \u00e8 pericoloso sfidare, e che invece dobbiamo comprendere, indirizzare, governare.<\/p>\n<p style=\"text-align: justify;\">Noi, compresi noi laici non credenti, esclusi naturalmente i laicisti, siamo cristiani. Siamo cristiani per i valori che professiamo e i princ\u00ecpi in cui crediamo. Siamo cristiani anche quando proclamiamo la separazione fra Stato e Chiesa e fra politica e religione. Siamo cristiani o, pi\u00f9 precisamente, siamo giudaico-cristiani per storia anche quando non lo siamo per fede.<\/p>\n<p style=\"text-align: justify;\">\u00c8 vero, siamo anche una mescolanza. Siamo figli di Atene e di Gerusalemme, di Roma e di Betlemme, e di tante altre cose ancora. Ma ovunque si cerchi la nostra genealogia pi\u00f9 profonda, comunque si cerchi la nostra identit\u00e0, si finisce sempre l\u00ec, al Sinai e al Golgota. \u00c8 l\u00ec che abbiamo avuto la legge ed \u00e8 l\u00ec che ci siamo scoperti uguali o fratelli.<\/p>\n<p style=\"text-align: justify;\">Chi nega questa realt\u00e0 rischia la fine dell&#8217;apprendista stregone: prima si indebolisce poi diventa vittima. Noi invece questa realt\u00e0 dobbiamo ritrovarla. Non per diventare protervi custodi di un&#8217;unica verit\u00e0, ma per affermare la nostra e riscoprire noi stessi. Fallibili, aperti a chi vuole parlarci, disponibili a chi vuole incontrarci, ma sempre noi stessi, con la forza della nostra identit\u00e0.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Discorso pronunciato dal Presidente del Senato Marcello Pera alla Fundaci\u00f2n para el an\u00e0lisis y los estudios sociales L&#8217;europa e l&#8217;occidente di fronte alle conseguenze dell&#8217;odio relativista verso le proprie radici, la salvezza \u00e8 nella forza dell&#8217;identit\u00e0 cristiana, valida\u00a0sia per chi crede e anche per chi non crede Madrid, 4 luglio 2005<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-forza-dellidentit\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":32043,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[439,467],"class_list":["post-844","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-europa-e-ue","tag-europa-ue","tag-radici-cristiane-ue-2","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La forza dell&#039;identit&agrave; - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-forza-dellidentit\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La forza dell&#039;identit&agrave; - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-forza-dellidentit\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2005-07-06T12:09:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-03-22T16:25:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/Marcello_Pera.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"185\" \/>\n\t<meta property=\"og:image:height\" content=\"254\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"13 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-forza-dellidentit\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-forza-dellidentit\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"La forza dell&#8217;identit&agrave;\",\"datePublished\":\"2005-07-06T12:09:03+00:00\",\"dateModified\":\"2016-03-22T16:25:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-forza-dellidentit\\\/\"},\"wordCount\":2600,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-forza-dellidentit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/07\\\/Marcello_Pera.jpg\",\"keywords\":[\"Europa UE\",\"radici cristiane Ue\"],\"articleSection\":[\"Europa e UE\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-forza-dellidentit\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-forza-dellidentit\\\/\",\"name\":\"La forza dell'identit&agrave; - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-forza-dellidentit\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-forza-dellidentit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/07\\\/Marcello_Pera.jpg\",\"datePublished\":\"2005-07-06T12:09:03+00:00\",\"dateModified\":\"2016-03-22T16:25:10+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-forza-dellidentit\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-forza-dellidentit\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-forza-dellidentit\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/07\\\/Marcello_Pera.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/07\\\/Marcello_Pera.jpg\",\"width\":185,\"height\":254},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-forza-dellidentit\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La forza dell&#8217;identit&agrave;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La forza dell'identit&agrave; - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-forza-dellidentit\/","og_locale":"it_IT","og_type":"article","og_title":"La forza dell'identit&agrave; - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-forza-dellidentit\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2005-07-06T12:09:03+00:00","article_modified_time":"2016-03-22T16:25:10+00:00","og_image":[{"width":185,"height":254,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/Marcello_Pera.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"13 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-forza-dellidentit\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-forza-dellidentit\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"La forza dell&#8217;identit&agrave;","datePublished":"2005-07-06T12:09:03+00:00","dateModified":"2016-03-22T16:25:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-forza-dellidentit\/"},"wordCount":2600,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-forza-dellidentit\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/Marcello_Pera.jpg","keywords":["Europa UE","radici cristiane Ue"],"articleSection":["Europa e UE"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-forza-dellidentit\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-forza-dellidentit\/","name":"La forza dell'identit&agrave; - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-forza-dellidentit\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-forza-dellidentit\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/Marcello_Pera.jpg","datePublished":"2005-07-06T12:09:03+00:00","dateModified":"2016-03-22T16:25:10+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-forza-dellidentit\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-forza-dellidentit\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-forza-dellidentit\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/Marcello_Pera.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/Marcello_Pera.jpg","width":185,"height":254},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-forza-dellidentit\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"La forza dell&#8217;identit&agrave;"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/844","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=844"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/844\/revisions"}],"predecessor-version":[{"id":32044,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/844\/revisions\/32044"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/32043"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=844"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=844"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=844"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}