{"id":842,"date":"2005-07-03T00:00:00","date_gmt":"2005-07-02T22:00:00","guid":{"rendered":""},"modified":"2016-06-15T14:12:48","modified_gmt":"2016-06-15T12:12:48","slug":"parlare-daborto","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/parlare-daborto\/","title":{"rendered":"Parlare d\u2019aborto"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-34874\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/legge_194.jpg\" alt=\"legge_194\" width=\"240\" height=\"154\" \/>Il Foglio<\/strong> 30 giugno 2005<\/div>\n<p style=\"text-align: justify;\"><em>Consideriamolo per quello che \u00e8 e chiediamoci se la 194 \u00e8 applicata nello spirito e nella lettera<\/em><\/p>\n<p style=\"text-align: center;\"><strong>Francesco Agnoli<\/strong><\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">E\u2019 evidente che il recente dibattito sulla legge 40 non aveva nulla a che vedere con quello sulla 194\/\u201978. Eppure tornare a parlare della 194, quasi trent\u2019anni dopo, non pu\u00f2 essere un tab\u00f9, l\u2019unico rimasto, in un tempo in cui le leggi cambiano di continuo e la scienza progredisce ogni giorno. E\u2019 difficile infatti misconoscere il fatto che la legge che regola l\u2019aborto legale e gratuito in Italia sia nata anche sulla scia di statistiche fasulle, di concetti ideologici estremi e di conoscenze scientifiche insufficienti.<\/div>\n<p style=\"text-align: justify;\">Oggi, ad esempio, nessuno pi\u00f9 argomenterebbe a favore dell\u2019aborto con lo spauracchio della sovrappopolazione, utilizzato all\u2019epoca da Loris Fortuna, promotore della legge, e da Aurelio Peccei, fondatore dell\u2019influentissimo\u201cClub di Roma\u201d. Il primo, infatti, affermava: \u201c7 miliardi gli individui che nel 2000 popoleranno la terra\u2026 ipotizzabile, come evento futuro, ma non incerto, la catastrofe\u201d. Il secondo, dal canto suo, scriveva: \u201cCos\u2019\u00e8 l\u2019Homo Sapiens? Il capolavoro della natura o un refuso sfuggito al controllo della selezione immediata?<\/p>\n<p style=\"text-align: justify;\">Salvo gli insetti, sono rare le specie che si moltiplicano in modo cos\u00ec selvaggio e cieco; una proliferazione che non si pu\u00f2 definire che cancerosa\u201d (\u201cCento pagine per l\u2019avvenire\u201d, Mondadori). Argomentazioni come queste, in un paese che vive il dramma umano ed economico della denatalit\u00e0, non sono pi\u00f9 credibili.<\/p>\n<p style=\"text-align: justify;\">Il panorama \u00e8 mutato anche dal punto di vista scientifico: \u00e8 un po\u2019 arduo, oggi, definire il feto come \u201cgrumo di sangue\u201d, \u201cbrufolo\u201d, \u201cparassita a bordo\u201d, o con espressioni analoghe.<\/p>\n<p style=\"text-align: justify;\">E neppure \u00e8 pi\u00f9 lecito rimanere sul piano astrattamente filosofico, come voleva in quegli anni l\u2019Unit\u00e0: \u201cIl problema dell\u2019aborto dovrebbe essere discusso in ambito squisitamente etico-morale e non attraverso considerazioni di natura biologica\u201d (25\/2\/\u201977).<\/p>\n<p style=\"text-align: justify;\">Tecniche moderne, come la nuova ecografia tridimensionale, permettono infatti di osservare\u201cespressioni e comportamenti\u201d, \u201csorrisi e sbadigli\u201d di un feto di tre mesi(Corriere della Sera, 29\/6\/2005).<\/p>\n<p style=\"text-align: justify;\">E\u2019 dunque evidente che l\u2019aborto \u00e8 l\u2019eliminazione di una vita umana gi\u00e0 perfettamente formata: senza giri di parole, un omicidio, come ammetteva Natalia Ginzburg. Questo per dare alle cose il loro nome: anche chi \u00e8 favorevole alla legalizzazione dell\u2019aborto deve partire da qui per valutare attentamente e scrupolosamente quali siano le condizioni in cui permetterlo.<\/p>\n<p style=\"text-align: justify;\"><strong>Leggere con attenzione i dati<\/strong><\/p>\n<p style=\"text-align: justify;\">Dobbiamo allora, anzitutto, chiederci: funziona bene una legge che da circa dieci anni vede il numero degli aborti sempre costante, senza sostanziali diminuzioni? Non credo, se consideriamo che in realt\u00e0 il tasso annuale di aborti non cresce non per merito della legge, ma per altri motivi: \u00e8 diminuita la fertilit\u00e0 generale; sono diminuite le coppie in et\u00e0 fertile; \u00e8 aumentato enormemente il numero degli aborti farmacologici; cresce di continuo, secondo stime attendibili, il numero di bambini abbandonati per strada o nei cassonetti dopo il parto; aumentano i bambini salvati dall\u2019aborto dai Centri di aiuto alla Vita (circa 9.000 all\u2019anno), spesso ignorati o addirittura ostacolati per motivi ideologici; permangono gli abortifici clandestini, non adeguatamente perseguiti dalla 194; aumenta, infine, il numero di aborti in rapporto ai bambini nati vivi.<\/p>\n<p style=\"text-align: justify;\">Che fare, allora? E\u2019 evidente che bisogna, almeno, applicare la legge con pi\u00f9 seriet\u00e0, ad esempio laddove afferma, all\u2019articolo 1, che occorre \u201cevitare che l\u2019aborto sia usato ai fini della limitazione delle nascite\u201d. Sappiamo invece che questo non sempre succede: \u201cTrentamila donne all\u2019anno che riabortiscono. Due, tre, fino a sei volte\u2026 nel 2002 gli aborti ripetuti sono stati il 24,2 per cento del totale\u2026 Il 17 per cento circa delle donne sono alla seconda esperienza, il 4,7 alla terza, l\u20191,5 alla quarta, lo 0,8 alla quinta o pi\u00f9\u201d (Corriere della Sera, 11\/8\/2004). Come evitare il pi\u00f9 possibile questi drammi spaventosi, come pure la tendenza sempre pi\u00f9 diffusa ad eliminare i figli con qualche difetto, magari solo un labbro leporino o le dita dei piedi attaccate?<\/p>\n<p style=\"text-align: justify;\">Senza dubbio con una battaglia culturale.<\/p>\n<p style=\"text-align: justify;\">Riportando cio\u00e8 l\u2019attenzione sul soggetto- figlio, combattendo i folli sogni dell\u2019eugenetica, come pure il concetto di figlio come prodotto, che pu\u00f2 essere eliminato, o assemblato, a seconda del capriccio. E poi, certamente, applicando ogni forma di sostegno alla maternit\u00e0, a partire da una riforma di quegli stessi consultori contemplati nella194: aprendoli anche ai gruppi di volontariato disposti a farsi carico di un aiuto concreto, e al personale obiettore, che costituisce la maggioranza in Italia, affinch\u00e9 la donna non trovi pi\u00f9 sul suo cammino, come succede spesso, solo pasdaran dell\u2019Ivg come diritto, o annoiati compilatori di certificati.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Foglio 30 giugno 2005 Consideriamolo per quello che \u00e8 e chiediamoci se la 194 \u00e8 applicata nello spirito e nella lettera Francesco Agnoli<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/parlare-daborto\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":34874,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[2386],"class_list":["post-842","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aborto","tag-aborto","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Parlare d\u2019aborto - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/parlare-daborto\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Parlare d\u2019aborto - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/parlare-daborto\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2005-07-02T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-06-15T12:12:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/legge_194.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"281\" \/>\n\t<meta property=\"og:image:height\" content=\"180\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/parlare-daborto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/parlare-daborto\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Parlare d\u2019aborto\",\"datePublished\":\"2005-07-02T22:00:00+00:00\",\"dateModified\":\"2016-06-15T12:12:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/parlare-daborto\\\/\"},\"wordCount\":736,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/parlare-daborto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/07\\\/legge_194.jpg\",\"keywords\":[\"Aborto\"],\"articleSection\":[\"Aborto\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/parlare-daborto\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/parlare-daborto\\\/\",\"name\":\"Parlare d\u2019aborto - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/parlare-daborto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/parlare-daborto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/07\\\/legge_194.jpg\",\"datePublished\":\"2005-07-02T22:00:00+00:00\",\"dateModified\":\"2016-06-15T12:12:48+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/parlare-daborto\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/parlare-daborto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/parlare-daborto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/07\\\/legge_194.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/07\\\/legge_194.jpg\",\"width\":281,\"height\":180},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/parlare-daborto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Parlare d\u2019aborto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Parlare d\u2019aborto - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/parlare-daborto\/","og_locale":"it_IT","og_type":"article","og_title":"Parlare d\u2019aborto - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/parlare-daborto\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2005-07-02T22:00:00+00:00","article_modified_time":"2016-06-15T12:12:48+00:00","og_image":[{"width":281,"height":180,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/legge_194.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/parlare-daborto\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/parlare-daborto\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Parlare d\u2019aborto","datePublished":"2005-07-02T22:00:00+00:00","dateModified":"2016-06-15T12:12:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/parlare-daborto\/"},"wordCount":736,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/parlare-daborto\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/legge_194.jpg","keywords":["Aborto"],"articleSection":["Aborto"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/parlare-daborto\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/parlare-daborto\/","name":"Parlare d\u2019aborto - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/parlare-daborto\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/parlare-daborto\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/legge_194.jpg","datePublished":"2005-07-02T22:00:00+00:00","dateModified":"2016-06-15T12:12:48+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/parlare-daborto\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/parlare-daborto\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/parlare-daborto\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/legge_194.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/legge_194.jpg","width":281,"height":180},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/parlare-daborto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Parlare d\u2019aborto"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/842","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=842"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/842\/revisions"}],"predecessor-version":[{"id":34876,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/842\/revisions\/34876"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/34874"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=842"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=842"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=842"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}