{"id":798,"date":"2005-06-30T12:05:27","date_gmt":"2005-06-30T10:05:27","guid":{"rendered":""},"modified":"2016-01-29T13:15:19","modified_gmt":"2016-01-29T12:15:19","slug":"la-massoneria-e-le-origini-dei-testimoni-di-geova","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-massoneria-e-le-origini-dei-testimoni-di-geova\/","title":{"rendered":"La massoneria e le origini dei testimoni di Geova"},"content":{"rendered":"<div style=\"text-align: center;\">\n<div id=\"attachment_30076\" style=\"width: 250px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/06\/Russell_tomb.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-30076\" class=\"wp-image-30076\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/06\/Russell_tomb.jpg\" alt=\"Russell_tomb\" width=\"250\" height=\"187\" \/><\/a><p id=\"caption-attachment-30076\" class=\"wp-caption-text\">Tomba del pastore Russell<\/p><\/div>\n<p>di \u00a0<strong>Ernesto Zucchini<\/strong><\/div>\n<p><strong>I. La &#8220;religione incivile&#8221; negli Stati Uniti<\/strong><\/p>\n<p style=\"text-align: justify;\">Uno degli aspetti pi\u00f9 caratteristici della vita sociale e culturale americana \u00e8 la presenza di una &#8220;religione civile&#8221;, di un minimo comune denominatore morale, patriottico e vagamente &#8220;spirituale&#8221; che si suppone condiviso dalla grande maggioranza degli americani, pure separati da una straordinaria molteplicit\u00e0 di appartenenze religiose (1).<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Tra gli aspetti della &#8220;religione civile&#8221; americana messi in luce dai sociologi ce n\u2019\u00e8 uno discutibile ma non per questo meno essenziale: la necessit\u00e0 per rafforzare l\u2019identit\u00e0 nazionale e spirituale di designare continuamente avversari, che servono a sottolineare la distinzione fra &#8220;noi&#8221; e &#8220;loro&#8221; in quanto vengono presentati come &#8220;stranieri&#8221;, &#8220;altri&#8221;, estranei alla patria e ai suoi simboli. Lo stesso sociologo che ha reso celebre negli ultimi decenni la teoria della &#8220;religione civile&#8221;, Robert Bellah, ha suggerito l\u2019espressione &#8220;religione incivile&#8221; per designare questo aspetto di ostilit\u00e0 all\u2019estraneo che accompagna come un\u2019ombra la &#8220;religione civile&#8221; americana (2).<\/p>\n<p style=\"text-align: justify;\">Chi sono gli stranieri designati come estranei all\u2019ethos nazionale americano dalla &#8220;religione incivile&#8221;? Bellah e i suoi collaboratori hanno mostrato che \u00e8 esistita nella giovane nazione americana nascente una tradizione antisemita, ma ben presto gli ebrei sono stati riconosciuti come parte integrante e non estranea della vita civile e sociale degli Stati Uniti.<\/p>\n<p style=\"text-align: justify;\">Nell\u2019Ottocento i due gruppi particolarmente denunciati come &#8220;stranieri&#8221; e &#8220;non americani&#8221; sono i cattolici e i mormoni. Bench\u00e9 gi\u00e0 dalla met\u00e0 del secolo scorso i cattolici siano diventati il gruppo religioso di maggioranza relativa negli Stati Uniti &#8211; e i mormoni, naturalmente, siano una religione americana fondata da americani &#8211; venivano percepiti come estranei alla &#8220;religione civile&#8221; in particolare due elementi: la struttura gerarchica della Chiesa cattolica e della Chiesa mormone, considerata incompatibile con l\u2019ideale democratico statunitense; e il segreto (segreto del tempio mormone, segreto del confessionale cattolico), ritenuto inconciliabile con una democrazia dove tutto avviene in pubblico. Cattolici e mormoni vennero cos\u00ec considerati degli outsider, degli estranei, e spesso perseguitati.<\/p>\n<p style=\"text-align: justify;\">C\u2019\u00e8 per\u00f2 un terzo gruppo che viene spesso accostato ai cattolici e ai mormoni e attaccato in quanto estraneo alle tradizioni americane, gerarchico e segreto: la massoneria. Molti tra i padri fondatori degli Stati Uniti erano massoni e, da un certo punto di vista, la massoneria americana si considera la custode della &#8220;religione civile&#8221;.<\/p>\n<p style=\"text-align: justify;\">Tuttavia negli anni che vanno dalla Rivoluzione francese al 1850 nacque negli Stati Uniti un forte movimento contro la massoneria (3); venne perfino fondato un partito politico chiamato &#8220;Partito Anti-Massonico&#8221; che per una quindicina di anni riusc\u00ec ad ottenere un certo successo (4). \u00c8 interessante notare che gli stessi gruppi &#8211; protestanti conservatori, patrioti &#8220;nativisti&#8221;, difensori della &#8220;religione civile&#8221; &#8211; attaccavano la massoneria, la Chiesa cattolica e i mormoni, e addirittura gli stessi romanzi popolari venivano ripubblicati identici cambiando l\u2019identit\u00e0 degli &#8220;avversari&#8221; o dei &#8220;cattivi&#8221;:<\/p>\n<p style=\"text-align: justify;\">il cattivo e corrotto mormone o massone di un opuscolo diventava il cattivo gesuita di un altro, ma la trama rimaneva la stessa (5). Per di pi\u00f9 i tre gruppi &#8220;stranieri&#8221; venivano considerati in contatto e in lega fra loro: si affermava facilmente che la massoneria era segretamente diretta dal Vaticano, che i mormoni erano in realt\u00e0 massoni, oppure erano cripto-cattolici, e cos\u00ec via. In una letteratura che si situa alle frange pi\u00f9 estreme del protestantesimo fondamentalista queste accuse sono ripetute ancora oggi.<\/p>\n<p style=\"text-align: justify;\">Tuttavia, a partire dalla fine dell\u2019Ottocento, qualche cosa ha cominciato a cambiare. I cattolici (sempre pi\u00f9 numerosi, e ormai non sempre identificati con i ceti pi\u00f9 poveri) e i mormoni (dopo la rinuncia alla poligamia nel 1890) hanno iniziato una marcia verso il centro della scena religiosa e civile americana, e &#8211; se i pregiudizi non sono del tutto scomparsi &#8211; molti oggi li accettano come americani a pieno titolo, non pi\u00f9 outsider o stranieri.<\/p>\n<p style=\"text-align: justify;\">Accanto ai massoni &#8211; sempre attaccati da una certa letteratura protestante, anche se i tempi del &#8220;Partito Anti-Massonico&#8221; sono certamente passati &#8211; i nemici della &#8220;religione civile&#8221; sono stati cercati altrove. Negli ultimi anni gli &#8220;stranieri&#8221; per eccellenza sono i nuovi movimenti religiosi, le &#8220;sette&#8221;, i &#8220;culti&#8221;: Hare Krishna, Scientologi, Bambini di Dio, seguaci del reverendo Moon. Ma &#8211; prima dei &#8220;culti&#8221; pi\u00f9 recenti, e per molti anni &#8211; il posto dei mormoni e dei cattolici come gruppo pericoloso da criticare e denunciare \u00e8 stato largamente preso dai testimoni di Geova (6).<\/p>\n<p style=\"text-align: justify;\">Il meccanismo della &#8220;religione incivile&#8221; \u00e8 sempre lo stesso: tutti coloro che sono estranei alla &#8220;religione civile&#8221; fanno parte di un complotto e sono in lega fra loro. Cos\u00ec alcuni anti-cattolici, duri a morire, sostengono ancora oggi che i testimoni di Geova (come del resto i massoni) sono segretamente ispirati dal Vaticano e che tra i membri del Corpo Direttivo ci sono gesuiti sotto mentite spoglie (7). E altri insistono sulle relazioni fra i testimoni di Geova e la massoneria.<\/p>\n<p style=\"text-align: justify;\">Un esempio di questa letteratura &#8211; che rimarrebbe incomprensibile senza il quadro di riferimento della &#8220;religione incivile&#8221; americana e della sua tradizione &#8211; \u00e8 costituito dalle attivit\u00e0 dell\u2019organizzazione anti-geovista Witness Inc. Uno dei suoi &#8220;missionari&#8221;, Fritz Springmeier di Portland, nell\u2019Oregon, insiste particolarmente sui collegamenti massonici dei primi Studenti Biblici &#8211; da cui originano gli attuali testimoni di Geova &#8211; e sostiene, tipicamente, che anche &#8220;i leader cattolici del Vaticano sono quasi tutti massoni&#8221; (8).<\/p>\n<p style=\"text-align: justify;\">Se si aggiunge che i testi di Springmeier sono distribuiti da Saints Alive, un gruppo anti-mormone dello Stato di Washington che accusa di collegamenti massonici sia i mormoni che i cattolici, il quadro \u00e8 completo e mostra la persistenza della &#8220;religione incivile&#8221;, che da anni ha incluso i testimoni di Geova in una sua teoria del complotto che gi\u00e0 dalla prima met\u00e0 del secolo scorso collegava la massoneria, la Chiesa cattolica e la Chiesa mormone.<\/p>\n<p style=\"text-align: justify;\">Parallela alla letteratura sui collegamenti massonici dei testimoni di Geova ne esiste un\u2019altra che cerca nelle loro pubblicazioni e attivit\u00e0 tracce di occultismo e perfino di satanismo. In un libro che ha avuto un certo successo &#8211; e che ogni tanto viene citato anche in Italia &#8211; Darek Barefoot ha sostenuto che all\u2019interno di illustrazioni che compaiono sulla Torre di Guardia e nei libri dei testimoni di Geova sarebbero nascosti simboli occulti e anche satanici, che si possono identificare solo scomponendo le figure (9).<\/p>\n<p style=\"text-align: justify;\">Le argomentazioni di Barefoot sono spesso francamente incredibili, e scomponendo figure apparentemente innocue &#8211; magari con l\u2019aiuto di un computer &#8211; si potrebbero trovare simboli sinistri e demoniaci pressoch\u00e9 ovunque.<\/p>\n<p style=\"text-align: justify;\">Si tratta di una letteratura che ha un interesse sociologico, nell\u2019intreccio fra &#8220;religione civile&#8221; e &#8220;religione incivile&#8221;. In questa sede, tuttavia, voglio affrontare il problema da un altro punto di vista, prendendo sul serio la tesi relativa ai rapporti fra massoneria e testimoni di Geova a prescindere dal contesto bizzarro e fantastico in cui viene spesso presentata. Mi chiedo allora: c\u2019\u00e8 qualche cosa di vero?<\/p>\n<p style=\"text-align: justify;\">Tra le fonti del moderno Geovismo c\u2019\u00e8 anche la massoneria? Naturalmente gli attuali testimoni di Geova &#8211; come gli attuali mormoni e, da sempre, i cattolici &#8211; si esprimono a proposito della massoneria esclusivamente in chiave critica: oggi ai testimoni di Geova viene fortemente sconsigliato di aderire a organizzazioni di tipo massonico, e anzi la massoneria viene denunciata come &#8220;satanica&#8221;.<\/p>\n<p style=\"text-align: justify;\">Questa circostanza non \u00e8 per\u00f2 decisiva per quanto riguarda le fonti del fondatore degli Studenti Biblici, il pastore Charles Taze Russell (1852-1916). Mi propongo quindi di esaminare gli argomenti salienti degli autori anti-geovisti che sostengono un legame fra Studenti Biblici e massoneria, proponendone una valutazione critica e formulando quindi qualche conclusione. Mi asterr\u00f2 dall\u2019esaminare gli argomenti di carattere puramente speculativo o teorico, e mi atterr\u00f2 agli elementi di fatto, esponendoli in forma di tesi.<\/p>\n<p style=\"text-align: center;\">II. Charles Taze Russell e la massoneria: le tesi<\/p>\n<p style=\"text-align: justify;\"><strong>1. &#8220;Charles Taze Russell era affiliato alla massoneria&#8221;<\/strong><\/p>\n<p style=\"text-align: justify;\">Fritz Springmeier sostiene di avere, dopo una lunga ricerca, rinvenuto le prove della affiliazione di Charles Taze Russell alla massoneria e in particolare ai Cavalieri Templari (Knights Templar), un sistema di &#8220;alti gradi&#8221; massonici particolarmente popolare nelle Isole Britanniche e negli Stati Uniti, sulle cui origini si dibatte ma che \u00e8 oggi associato al Rito di York, la maggiore alternativa &#8211; nel mondo anglosassone &#8211; al Rito scozzese.<\/p>\n<p style=\"text-align: justify;\">Giacch\u00e9 i Cavalieri Templari della Pennsylvania a cui il fondatore degli Studenti Biblici era affiliato derivavano la loro regolarit\u00e0 da una patente irlandese, i documenti relativi alla affiliazione massonica di Charles Taze Russell sarebbero conservati a Dublino (10). Se questa informazione fosse esatta, la questione dell\u2019appartenenza alla massoneria dell\u2019uomo che si situa alle origini dei testimoni di Geova sarebbe risolta in senso affermativo, posto che non \u00e8 possibile senza essere maestri massoni entrare tra i Cavalieri Templari.<\/p>\n<p style=\"text-align: justify;\">Tuttavia la questione della appartenenza massonica di questo o quel personaggio storico si presenta quasi sempre con caratteristiche ambigue e infide. Non \u00e8 difficile falsificare documenti e patenti. Per il momento la documentazione che Fritz Springmeier ha fornito non \u00e8 sufficiente a risolvere in modo definitivo la questione.<\/p>\n<p style=\"text-align: justify;\">A proposito della massoneria Charles Taze Russell ha formulato delle obiezioni critiche esposte in tono pi\u00f9 moderato rispetto alle accuse di &#8220;satanismo&#8221; dei suoi successori. Il 15 giugno 1895 scriveva sulla Torre di Guardia che &#8220;l\u2019Ordine dei Massoni, se lo giudichiamo dalla sua storia passata, ha degli obiettivi e schemi segreti che vanno al di l\u00e0 del mutuo aiuto finanziario in caso di malattia o di morte.<\/p>\n<p style=\"text-align: justify;\">Per quanto possiamo giudicare c\u2019\u00e8 nei riti di questo ordine &#8211; e di alcuni altri &#8211; una certa dose di ritualit\u00e0 profana e di parata, che gli adepti non capiscono ma che in molti casi serve a soddisfare l\u2019inclinazione naturale verso il rito, e pertanto distoglie i membri dall\u2019autentico rito dove si adora Dio in spirito e verit\u00e0 attraverso l\u2019unico vero Mediatore e Gran Maestro, Ges\u00f9 Cristo&#8221; (11).<\/p>\n<p style=\"text-align: justify;\">D\u2019altro canto, nell\u2019ambiente di commercianti di Pittsburgh dove Charles Taze Russell si era formato l\u2019affiliazione alla massoneria era piuttosto comune. Se pure il futuro pastore si era affiliato alla massoneria nei suoi anni giovanili, sembra che nel 1895 considerasse le attivit\u00e0 massoniche secondarie e vi vedesse un rischio di distogliere gli adepti dagli interessi spirituali. Peraltro, il fondatore degli Studenti Biblici non sembra avere aderito alle campagne anti-massoniche che caratterizzavano diverse denominazioni e movimenti protestanti della sua epoca.<\/p>\n<p style=\"text-align: justify;\"><strong>2. &#8220;Charles Taze Russell si \u00e8 servito di un linguaggio massonico nei suoi sermoni&#8221;<\/strong><\/p>\n<p style=\"text-align: justify;\">Ci sono in effetti diversi sermoni in cui Charles Taze Russell dimostra una notevole familiarit\u00e0 con il linguaggio massonico. Il primo sermone raccolto nel volume I Sermoni del Pastore Russell si intitola Potete conoscere i segreti di Dio ed \u00e8 tutto giocato sulla metafora di Dio come &#8220;fondatore di una societ\u00e0 segreta&#8221;. Gli uomini si entusiasmano per la massoneria &#8211; che, afferma il pastore, &#8220;non \u00e8 parte della mia missione attaccare&#8221; &#8211; ma gli Studenti Biblici offrono la possibilit\u00e0 di entrare in un ordine pi\u00f9 grande, l\u2019&#8221;Ordine segreto di Melchisedec&#8221; dove si pu\u00f2 &#8220;passare di grado in grado&#8221;, cio\u00e8 &#8220;di grazia in grazia&#8221; e avere l\u2019orgoglio di essere iniziati all\u2019&#8221;Ordine segreto del Signore&#8221; (12).<\/p>\n<p style=\"text-align: justify;\">In un altro sermone dello stesso volume, Il desiderio di tutte le Nazioni, il pastore osserva che molti movimenti spirituali attendono la seconda venuta di un messia: i cristiani attendono Ges\u00f9 Cristo e i massoni attendono Hiram Abiff, &#8220;il grande Maestro Massone la cui morte, glorificazione e futuro avvento sono continuamente menzionati dalle lettere poste sulle loro pietre angolari. Egli mor\u00ec di morte violenta, dicono, per la sua lealt\u00e0 ai segreti divini di cui era tipo il Tempio di Salomone. Egli deve tornare sulla terra, dicono, perch\u00e9 il grande tempio antitipico sia completato e il suo grande servizio per Israele e per tutti i popoli possa essere compiuto&#8221; (13).<\/p>\n<p style=\"text-align: justify;\">Come si vede, Charles Taze Russell si serviva del linguaggio massonico con una certa dovizia di particolari e precisione. Da questa circostanza, peraltro, non si devono trarre conclusioni affrettate. A proposito dell\u2019uso del linguaggio massonico da parte di Joseph Smith, il fondatore dei mormoni (che, a differenza del pastore Russell, era stato certamente iniziato alla massoneria), il sociologo Armand Mauss ha osservato che si trattava di un linguaggio familiare e noto ai ceti medi dell\u2019America ottocentesca e che Joseph Smith se ne serviva per mettere a suo agio un certo tipo di interlocutore e trasmettergli un contenuto molto diverso da quello massonico (14).<\/p>\n<p style=\"text-align: justify;\">Anche nel sermone che ho citato Charles Taze Russell si serve della forma massonica &#8211; che indubbiamente mostra di conoscere bene &#8211; per far passare un contenuto diverso, di cui afferma reiteratamente la superiorit\u00e0 rispetto a quanto i suoi contemporanei potevano apprendere frequentando la massoneria.<\/p>\n<p style=\"text-align: justify;\"><strong>3. &#8220;Charles Taze Russell si \u00e8 servito di simboli massonici&#8221;<\/strong><\/p>\n<p style=\"text-align: justify;\">Il fondatore degli Studenti Biblici \u00e8 stato accusato di utilizzare abitualmente diversi simboli massonici. Anzitutto, non sembra possa essere revocato il dubbio che il pastore Russell fosse straordinariamente affezionato al simbolo usato dai Cavalieri Templari massonici americani costituito da una corona al cui interno si trova una croce. Si tratta di una rielaborazione massonica tardo-settecentesca o ottocentesca di simboli medievali, molto pi\u00f9 popolare presso i Templari massonici americani di quanto non sia in Inghilterra, e presentata come &#8220;simbolo crociato&#8221;.<\/p>\n<p style=\"text-align: justify;\">Charles Taze Russell utilizz\u00f2 questo simbolo per alcuni anni sulle copertine della Torre di Guardia (15) e della rivista interdenominazionale People\u2019s Pulpit; lo esponeva nelle grandi riunioni pubbliche e lo teneva in bella evidenza nel suo studio (16). Questo simbolo \u00e8 tuttora utilizzato da diversi gruppi scismatici &#8220;russelliti&#8221; che si denominano Studenti Biblici, in polemica con gli attuali testimoni di Geova che lo hanno invece abbandonato. \u00c8 tuttora uno dei simboli ufficiali dei Cavalieri Templari massonici.<\/p>\n<p style=\"text-align: justify;\">Springmeier e altri autori anti-geovisti si dimenticano per\u00f2 di precisare che, nonostante la sua origine massonica (e il ruolo di Charles Taze Russell nella sua diffusione) si tratta di un simbolo che con il significato di &#8220;crociata cristiana&#8221; ha acquisito nel nostro secolo una diffusione negli Stati Uniti anche in ambienti protestanti evangelici, ostili sia ai massoni che ai testimoni di Geova. Viene per esempio riprodotto sull\u2019&#8221;anello dell\u2019Alleanza&#8221; proposto ai protestanti evangelici come segno di identificazione (17).<\/p>\n<p style=\"text-align: justify;\">Naturalmente gli attuali testimoni di Geova non lo usano pi\u00f9, perch\u00e9 &#8211; a differenza del pastore Russell &#8211; non riconoscono pi\u00f9 la croce come simbolo di Ges\u00f9 Cristo: insegnano che Ges\u00f9 mor\u00ec su un palo di tortura e che la croce \u00e8 un simbolo pagano.<\/p>\n<p style=\"text-align: justify;\">Sulla copertina di diversi libri di Charles Taze Russell a partire dal 1910 figura il simbolo del sole alato (18). L\u2019origine del simbolo \u00e8 evidentemente orientale ed egiziana, e il pastore poteva averlo visto nei suoi viaggi in Egitto, ma ai suoi tempi il simbolo solare era usato anche dalla Societ\u00e0 Teosofica e dalla massoneria di rito scozzese, come simbolo del 33\u00b0 grado. Non si tratta evidentemente di un simbolo soltanto massonico, ma era certamente un simbolo popolare nella massoneria.<\/p>\n<p style=\"text-align: justify;\">L\u2019elemento che mi sembra pi\u00f9 significativo \u00e8 per\u00f2 un altro. Charles Taze Russell si \u00e8 interessato per tutta la sua vita alle speculazioni esoteriche sulla Grande Piramide, che riteneva costruita su istruzioni di Dio, forse da Melchisedec, &#8220;una Bibbia di pietra eretta con lo scopo di trasmettere le verit\u00e0 essenziali sulla infinita saggezza e preveggenza di Dio&#8221; (19).<\/p>\n<p style=\"text-align: justify;\">Gli insegnamenti sulla Grande Piramide saranno espunti dalla dottrina dei testimoni di Geova dal successore del pastore Russell, l\u2019avvocato Joseph Franklin Rutherford (1869-1942), comunemente chiamato &#8220;giudice Rutherford&#8221; per avere esercitato per breve tempo le funzioni di magistrato onorario; anche questi temi sono conservati oggi solo da alcuni gruppi &#8220;russelliti&#8221; scismatici.<\/p>\n<p style=\"text-align: justify;\">Il tema della Grande Piramide non indica univocamente una relazione con la massoneria, perch\u00e9 nell\u2019Ottocento era largamente diffuso in un\u2019ampia letteratura esoterica, sia massonica che non massonica. Pi\u00f9 interessante \u00e8 la circostanza che il Pastore Russell abbia voluto essere sepolto sotto una piramide la cui punta era separata dal tronco da una linea continua, che ripete il tema dell\u2019&#8221;occhio sopra la piramide&#8221; noto a tutti gli americani perch\u00e9 compare sul dollaro.<\/p>\n<p style=\"text-align: justify;\">Un popolare studioso di simboli contemporaneo, Joseph Campbell, ha confermato le origini massoniche di questo simbolo americano (20). Sulla piramide che faceva da monumento funebre a Russell era stato scolpito del resto anche il prediletto emblema templare.<\/p>\n<p style=\"text-align: justify;\"><strong>4. \u00abIl tema della necessit\u00e0 di conoscere un nome di Dio, che \u00e8 Geova, per salvarsi \u00e8 un tema massonico\u00bb<\/strong><\/p>\n<p style=\"text-align: justify;\">Anche nei sistemi di &#8220;alti gradi&#8221; massonici &#8211; successivi ai primi tre &#8211; si insegna che \u00abil segreto essenziale della massoneria\u00bb \u00e8 &#8220;il Grande e Sacro Nome&#8221; che \u00e8 il nome di Dio. Questo &#8220;segreto&#8221; viene comunicato nel rito scozzese nel 13\u00b0 e nel 14\u00b0 grado e nel rito di York nel 7\u00b0 e 9\u00b0 grado. Con particolare enfasi si insiste sul nome di Dio nella massoneria dell\u2019Arco Reale (attuale 7\u00b0 grado del rito di York): viene comunicato prima il nome &#8220;Jah-Bul-On&#8221; (Jehovah-Baal-Osiride, a simboleggiare che il Dio a cui ci si rivolge \u00e8 il Dio di tutte le religioni, non di una sola), quindi il nome &#8220;Jehovah&#8221; (il Dio giudaico-cristiano di cui le quattro lettere del nome avrebbero per\u00f2 un valore universale) (21).<\/p>\n<p style=\"text-align: justify;\">L\u2019Arco Reale esisteva da cento anni quando Charles Taze Russell fond\u00f2 gli Studenti Biblici, e pertanto egli potrebbe avere semplicemente derivato l\u2019idea dell\u2019importanza centrale del &#8220;nome&#8221; di Dio e la stessa enfasi del nome Geova dalla massoneria. Questa conclusione \u00e8 plausibile, anche se non \u00e8 ovvia. Infatti anche nel protestantesimo evangelico anglo-americano &#8211; non tutto filo-massonico, anzi in parte anti-massonico &#8211; verso la met\u00e0 dell\u2019Ottocento teologi come Alexander MacWhorter e Frederick Leonard Chappell avevano reso popolare la tesi che Dio ha un nome che deve essere usato per salvarsi.<\/p>\n<p style=\"text-align: justify;\">Da questi teologi (che, certo, possono essere stati influenzati da teorie massoniche) e non direttamente dall\u2019Arco Reale deriva una vasta corrente di &#8220;movimenti del Sacro Nome&#8221; (22) diversi dai testimoni di Geova, che in parte esistono ancora oggi. E\u2019 vero, peraltro, che la massoneria era molto pi\u00f9 diffusa negli Stati Uniti all\u2019epoca della formazione del pastore Russell di quanto non fossero i &#8220;movimenti del Sacro Nome&#8221;.<\/p>\n<p style=\"text-align: justify;\"><strong>5. \u00abIn certe epoche della loro storia gli Studenti Biblici &#8211; e i loro successori, i testimoni di Geova &#8211; si sono mostrati alleati della massoneria\u00bb<\/strong><\/p>\n<p style=\"text-align: justify;\">Si allega in particolare che, soprattutto all\u2019epoca di Joseph F.Rutherford la Torre di Guardia e Golden Age, precursore di Svegliatevi!, hanno difeso la massoneria contro gli attacchi della Chiesa cattolica, del fascismo e del nazional-socialismo (23). \u00c8 difficile vedere qui pi\u00f9 di un tentativo di alleanza tattica perch\u00e9 si tratta della stessa epoca in cui &#8211; lontani dalla moderazione di Charles Taze Russell &#8211; indagando Come ha avuto origine la Massoneria? i testimoni di Geova concludevano che &#8220;\u00e8 nata dal Demonio&#8221; (24).<\/p>\n<p style=\"text-align: justify;\">Si afferma pure che la massoneria avrebbe favorito le missioni dei testimoni di Geova in chiave anticattolica. Le prove portate non sembrano decisive: si tratterebbe in ogni caso di una strategia di carattere generale favorevole a proposte &#8220;alternative&#8221; rispetto alla Chiesa cattolica, non di una promozione speciale dei testimoni di Geova. Infine, il sionismo di Charles Taze Russell era legato al suo calendario profetico, che prevedeva il ritorno degli ebrei in Palestina, e non deve essere definito troppo frettolosamente &#8220;massonico&#8221; perch\u00e9 da una parte non tutte le correnti massoniche della sua epoca erano sioniste, dall\u2019altra &#8211; per ragioni profetiche analoghe &#8211; il sionismo era ampiamente diffuso presso ambienti evangelici millenaristi che erano nello stesso tempo ostili alla massoneria (25).<\/p>\n<p style=\"text-align: center;\">III. Conclusioni<\/p>\n<p style=\"text-align: justify;\">Per terminare, mi limiter\u00f2 ad esporre alcune conclusioni in forma di tesi:<\/p>\n<p style=\"text-align: justify;\">1. Charles Taze Russell dimostrava di avere eccellenti informazioni sul linguaggio e i simboli massonici: se non era massone (il contrario resta da dimostrare) aveva evidentemente frequentato un ambiente dove la massoneria era diffusa e comune.<\/p>\n<p style=\"text-align: justify;\">2. Alcune idee e simboli &#8211; particolarmente rilevante \u00e8 la teoria del nome di Dio, ma per Russell erano molto importanti anche le speculazioni sulla Grande Piramide e il simbolo della croce nella corona &#8211; sono comuni agli Studenti Biblici e alla massoneria del loro tempo. Si ritrovano per\u00f2 anche in altri ambienti. Quando li troviamo presso Russell non possiamo immediatamente concludere che sono di derivazione massonica, ma &#8211; soprattutto per la teoria cruciale del nome di Dio &#8211; la tesi di un influsso massonico \u00e8 plausibile.<\/p>\n<p style=\"text-align: justify;\">3. La discussione sui rapporti fra le origini dei testimoni di Geova e la massoneria \u00e8 importante perch\u00e9 mostra come i testimoni di Geova non siano un fenomeno assolutamente unico, nuovo, inaudito: fanno parte (come la massoneria) dell\u2019ambiente della &#8220;nuova religiosit\u00e0&#8221; e da questo ambiente hanno attinto idee, argomenti, simboli.<\/p>\n<p style=\"text-align: justify;\">4. Il ruolo della massoneria fra le possibili fonti del materiale rielaborato da Charles Taze Russell per creare il primo abbozzo del Geovismo (che nella sua forma attuale nascer\u00e0 solo con Joseph F. Rutherford) non \u00e8 stato &#8211; probabilmente &#8211; irrilevante, ma non deve essere esagerato. Il pastore Russell ha infatti trovato nell\u2019ambiente della &#8220;nuova religiosit\u00e0&#8221; dell\u2019epoca &#8211; un ambiente su cui esercitava la sua influenza anche la massoneria &#8211; un linguaggio, dei temi e dei simboli, che ha per\u00f2 utilizzato creativamente al servizio di un progetto certamente diverso da quello massonico.<\/p>\n<p style=\"text-align: justify;\"><strong>Note:<\/strong><\/p>\n<p style=\"text-align: justify;\">(1) Cfr., sul punto, i saggi raccolti in Massimo Introvigne (a cura di), Tra Leghe e nazionalismi. &#8220;Religione civile&#8221; e nuovi simboli politici, Effedieffe, Milano 1993.<\/p>\n<p style=\"text-align: justify;\">(2) Cfr. Robert Bellah &#8211; Frederick E.Greenspahn (a cura di), Uncivil Religion. Interreligious Hostility in America, Crossroad, New York 1987.<\/p>\n<p style=\"text-align: justify;\">(3) Cfr. per uno sguardo riassuntivo Paul Goodman, Towards a Christian Republic. Antimasonry and the Great Transition in New England 1826-1836, Oxford University Press, New York-Oxford 1988.<\/p>\n<p style=\"text-align: justify;\">(4) Cfr. William Preston Vaughn, The Anti-Masonic Party in the United States 1826-1843, University Press of Kentucky, Lexington (Kentucky) 1983.<\/p>\n<p style=\"text-align: justify;\">(5) Cfr. David Brion Davis, &#8220;Some Themes of Countersubversion: An Analysis of Anti-Masonic, Anti-Catholic, and Anti-Mormon Literature&#8221;, Mississippi Valley Historical Review, vol.47 (1960), pp. 205-224.<\/p>\n<p style=\"text-align: justify;\">(6) Cfr. Lawrence Foster, &#8220;Cults in Conflict: New Religious Movements and the Mainstream Religious Tradition in America&#8221;, in R.E.Bellah &#8211; F.E.Greenspahn, op.cit., pp. 185-204.<\/p>\n<p style=\"text-align: justify;\">(7) Questa tesi ritorna negli albi a fumetti anti-cattolici pubblicati in numerose lingue dalla Chick Publications di Chino (California).<\/p>\n<p style=\"text-align: justify;\">(8) Fritz Springmeier, The Watchtower &amp; The Masons, 2a ed., presso l\u2019Autore, Portland (Oregon) 1992, p.X. Le tesi di Springmeier sono state ulteriormente esposte nel suo Be Wise as a Serpent, presso l\u2019Autore, Portland (Oregon) 1993 e in una serie di interviste radiofoniche trasmesse dalla WWCR, in cui Springmeier \u00e8 arrivato a sostenere che ancora &#8220;oggi la massoneria controlla i testimoni di Geova&#8221;.<\/p>\n<p style=\"text-align: justify;\">(9) Cfr. Darek Barefoot, Hour of Darkness. A Battle against Occult Subversion and Blind Faith, Grand Valley Press, Grand Junction (Colorado) 1992<\/p>\n<p style=\"text-align: justify;\">(10) Ibid., p.VIII e tavola fuori testo a fronte di p. VIII.<\/p>\n<p style=\"text-align: justify;\">(11) Watch Tower June 15, 1895, pp. 142-144 (nei Reprints pubblicati dai Chicago Bible Students, s.d., vol.IV, pp. 1827-1828).<\/p>\n<p style=\"text-align: justify;\">(12) Pastor Russell\u2019s Sermons, IBSA &#8211; People\u2019s Pulpit Association, Brooklyn (New York) 1917, pp. 5-17.<\/p>\n<p style=\"text-align: justify;\">(13) Ibid., p. 113<br \/>\n(14) Armand Mauss, &#8220;Culture, Charisma and Change: Reflections on Mormon Temple Worship&#8221;, Dialogue: A Journal of Mormon Thought, vol.20, n. 4, inverno 1987, pp.77-86. Per una discussione pi\u00f9 ampia cfr. Massimo Introvigne, I Mormoni, ed.it. ampliata, Interlogos, Schio (Vicenza) e Libreria Editrice Vaticana, Citt\u00e0 del Vaticano 1993.<\/p>\n<p style=\"text-align: justify;\">(15) Cfr. per esempio The Watch Tower, 18 gennaio 1911.<\/p>\n<p style=\"text-align: justify;\">(16) Secondo una fotografia riprodotta in F.SPRINGMEIER, op.cit., p. 98, della cui autenticit\u00e0 non sembra ci siano ragioni per dubitare.<\/p>\n<p style=\"text-align: justify;\">(17) Cfr., per un solo esempio, la pubblicit\u00e0 del Covenant Ring a p. 51 del numero dell\u20198 novembre 1993 della pi\u00f9 diffusa rivista evangelica americana, Christianity Today.<\/p>\n<p style=\"text-align: justify;\">(18) Cfr.per esempio Charles Taze Russell, What Say the Scriptures About Our Lord\u2019s Return, International Bible Students Association, Brooklyn (New York) 1917, copertina.<\/p>\n<p style=\"text-align: justify;\">(19) Charles Taze Russell, Studies in the Scriptures. Series III: Thy Kingdom Come, reprint, Dawn Bible Students Association, East Rutherford (New Jersey) s.d. (1a ed.: 1891), pp. 309-376.<\/p>\n<p style=\"text-align: justify;\">(20) Joseph Campbell-Bill Moyers, The Power of Myth, Doubleday, New York 1988, pp. 24-25.<\/p>\n<p style=\"text-align: justify;\">(21) Cfr.per un riassunto la voce Religion in Coil\u2019s Masonic Encyclopedia, nuova ed., Macoy Publishing &amp; Masonic Supply Company, New York 1961, pp. 511-522.<\/p>\n<p style=\"text-align: justify;\">(22) Su cui cfr. Massimo Introvigne, Le nuove Religioni, SugarCo, Milano 1989, pp. 127-129.<\/p>\n<p style=\"text-align: justify;\">(23) Cfr.per esempio Golden Age, 9 ottobre 1935, p.21; Golden Age, 20 novembre 1935.<\/p>\n<p style=\"text-align: justify;\">(24) &#8220;How Masonry Originated?&#8221;, in Golden Age, 3 settembre 1930.<\/p>\n<p style=\"text-align: justify;\">(25) Cfr.l\u2019opera principale sul sionismo di Russell, opera di un &#8220;russellita&#8221; contemporaneo: David Horowitz, Pastor Charles Taze Russell: An Early American Christian Zionist, Philosophical Library, New York 1986.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>di \u00a0Ernesto Zucchini I. La &#8220;religione incivile&#8221; negli Stati Uniti Uno degli aspetti pi\u00f9 caratteristici della vita sociale e culturale americana \u00e8 la presenza di una &#8220;religione civile&#8221;, di un minimo comune denominatore morale, patriottico e vagamente &#8220;spirituale&#8221; che si suppone condiviso dalla grande maggioranza degli americani, pure separati da una straordinaria molteplicit\u00e0 di appartenenze &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-massoneria-e-le-origini-dei-testimoni-di-geova\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":30076,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[69,63],"tags":[2396,714],"class_list":["post-798","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-massoneria","category-nuove-religioni-sette","tag-massoneria","tag-testimoni-di-geova","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La massoneria e le origini dei testimoni di Geova - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-massoneria-e-le-origini-dei-testimoni-di-geova\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La massoneria e le origini dei testimoni di Geova - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-massoneria-e-le-origini-dei-testimoni-di-geova\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2005-06-30T10:05:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-01-29T12:15:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/06\/Russell_tomb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"259\" \/>\n\t<meta property=\"og:image:height\" content=\"194\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"20 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-massoneria-e-le-origini-dei-testimoni-di-geova\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-massoneria-e-le-origini-dei-testimoni-di-geova\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"La massoneria e le origini dei testimoni di Geova\",\"datePublished\":\"2005-06-30T10:05:27+00:00\",\"dateModified\":\"2016-01-29T12:15:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-massoneria-e-le-origini-dei-testimoni-di-geova\\\/\"},\"wordCount\":3957,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-massoneria-e-le-origini-dei-testimoni-di-geova\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/06\\\/Russell_tomb.jpg\",\"keywords\":[\"Massoneria\",\"testimoni di geova\"],\"articleSection\":[\"Massoneria\",\"Nuove religioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-massoneria-e-le-origini-dei-testimoni-di-geova\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-massoneria-e-le-origini-dei-testimoni-di-geova\\\/\",\"name\":\"La massoneria e le origini dei testimoni di Geova - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-massoneria-e-le-origini-dei-testimoni-di-geova\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-massoneria-e-le-origini-dei-testimoni-di-geova\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/06\\\/Russell_tomb.jpg\",\"datePublished\":\"2005-06-30T10:05:27+00:00\",\"dateModified\":\"2016-01-29T12:15:19+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-massoneria-e-le-origini-dei-testimoni-di-geova\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-massoneria-e-le-origini-dei-testimoni-di-geova\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-massoneria-e-le-origini-dei-testimoni-di-geova\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/06\\\/Russell_tomb.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/06\\\/Russell_tomb.jpg\",\"width\":259,\"height\":194},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-massoneria-e-le-origini-dei-testimoni-di-geova\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La massoneria e le origini dei testimoni di Geova\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La massoneria e le origini dei testimoni di Geova - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-massoneria-e-le-origini-dei-testimoni-di-geova\/","og_locale":"it_IT","og_type":"article","og_title":"La massoneria e le origini dei testimoni di Geova - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-massoneria-e-le-origini-dei-testimoni-di-geova\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2005-06-30T10:05:27+00:00","article_modified_time":"2016-01-29T12:15:19+00:00","og_image":[{"width":259,"height":194,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/06\/Russell_tomb.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"20 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-massoneria-e-le-origini-dei-testimoni-di-geova\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-massoneria-e-le-origini-dei-testimoni-di-geova\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"La massoneria e le origini dei testimoni di Geova","datePublished":"2005-06-30T10:05:27+00:00","dateModified":"2016-01-29T12:15:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-massoneria-e-le-origini-dei-testimoni-di-geova\/"},"wordCount":3957,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-massoneria-e-le-origini-dei-testimoni-di-geova\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/06\/Russell_tomb.jpg","keywords":["Massoneria","testimoni di geova"],"articleSection":["Massoneria","Nuove religioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-massoneria-e-le-origini-dei-testimoni-di-geova\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-massoneria-e-le-origini-dei-testimoni-di-geova\/","name":"La massoneria e le origini dei testimoni di Geova - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-massoneria-e-le-origini-dei-testimoni-di-geova\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-massoneria-e-le-origini-dei-testimoni-di-geova\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/06\/Russell_tomb.jpg","datePublished":"2005-06-30T10:05:27+00:00","dateModified":"2016-01-29T12:15:19+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-massoneria-e-le-origini-dei-testimoni-di-geova\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-massoneria-e-le-origini-dei-testimoni-di-geova\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-massoneria-e-le-origini-dei-testimoni-di-geova\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/06\/Russell_tomb.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/06\/Russell_tomb.jpg","width":259,"height":194},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-massoneria-e-le-origini-dei-testimoni-di-geova\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"La massoneria e le origini dei testimoni di Geova"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/798","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=798"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/798\/revisions"}],"predecessor-version":[{"id":30077,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/798\/revisions\/30077"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/30076"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=798"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=798"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}