{"id":783,"date":"2005-06-30T00:00:00","date_gmt":"2005-06-29T22:00:00","guid":{"rendered":""},"modified":"2016-03-16T09:22:54","modified_gmt":"2016-03-16T08:22:54","slug":"i-maghi-son-tornati","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-maghi-son-tornati\/","title":{"rendered":"I maghi son tornati"},"content":{"rendered":"<div style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-31814\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/06\/Introvigne_cover.jpg\" alt=\"Introvigne_cover\" width=\"130\" height=\"200\" \/>Articolo pubblicato su <strong>Avvenire <\/strong>gioved\u00ec 11 ottobre 199<\/div>\n<p style=\"text-align: center;\"><em>\u00abUna linea esoterica persino nelle Br\u00bb<\/em><\/p>\n<p style=\"text-align: center;\">di <strong>Maurizio Blondet<\/strong><\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">E\u2019 sorprendente scoprirlo: ma il nostro mondo contemporaneo e tecnologico (e anche la nostra Italia secolarizzata e disincantata) formicolano di gruppi occultisti, di conventicole dedite all\u2019evocazione dei d\u00e9moni. Agiscono fra noi decine di cerchie occulte, tenebrose o solari, neo-pagane e neo-gnostiche. Alcuni nomi: Fraternit\u00e0 di Urantia, Ordine Spiritista Cristiano, Culto di Zos Kia, Riti di Memphis e Misraim\u2026<\/div>\n<p style=\"text-align: justify;\">Sono tutti l\u00ec, puntigliosamente catalogati nelle 487 pagine de <em>Il Cappello del Mago<\/em> (Sugarco, lire 44.000) dell\u2019ultima fatica di Massimo Introvigne, il coltissimo avvocato torinese che dirige il Csnur, Centro (cattolico) per lo Studio delle Nuove Religioni, uno dei massimi esperti mondiali, e consulente del Vaticano, per le \u00abreligiosit\u00e0 alternative\u00bb.<\/p>\n<p style=\"text-align: justify;\">L\u2019anno scorso, Sugarco aveva pubblicato il suo sterminato studio intitolato appunto <em>Le Nuove Religioni<\/em>, dedito alla catalogazione ragionata dei gruppi settari (dai Testimoni di Geova agli Hare Krishna) che giustamente preoccupano la Chiesa. Ora, questo suo libro sulla \u00abnuova magia\u00bb: denso di informazioni di prima mano raccolte \u00abdal vivo\u00bb nelle pi\u00f9 chiuse conventicole, parimenti voluminoso, e anche pi\u00f9 inquietante.<\/p>\n<p style=\"text-align: justify;\"><strong>Perch\u00e9 questo libro? Il fenomeno della magia \u00e8 davvero cos\u00ec rilevante nel mondo d\u2019oggi?<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00abIl fisco italiano &#8211; esordisce Introvigne &#8211; ha censito 11 mila &#8220;professionisti dell\u2019occulto&#8221;, per i quali ha creato una particolare categoria Iva: posto che costoro denunciano guadagni non mediocri (dai 30 ai 50 milioni l\u2019anno), e stimato che ciascuno di loro abbia un centinaio di clienti, si arriva facilmente a un milione e passa di persone che qualche volta ha consultato un &#8220;mago&#8221;. Non tutti costoro, beninteso, frequentano anche conventicole magiche vere e proprie, i cenacoli chiusi dove si praticano rituali. Ma costituiscono un &#8220;ambiente interessato&#8221; che \u00e8 certamente assai vasto: e spiega come gruppuscoli con un numero minimo di aderenti raccolgano, quando escono allo scoperto in conferenze pubbliche, una quantit\u00e0 sorprendente di ascoltatori che sono, evidentemente, al corrente. Cos\u00ec un piccolo gruppo d\u2019origine francese, battezzatosi <em>Arista<\/em>, con un centinaio di adepti dediti a presunti viaggi astrali, nel dicembre \u201989 tenne un convegno a cui accorsero, nella sola Torino, mille uditori. Non a caso i vescovi piemontesi hanno, ancora recentemente, segnalato il fenomeno con preoccupazione. Se \u00e8 vero che i cenacoli &#8220;chiusi&#8221; sono piccoli, diffondono idee che vengono assorbite da porzioni ragguardevoli della popolazione. Per esempio, un italiano su 5 crede nella reincarnazione. E se i tesserati ufficiali della vecchia Societ\u00e0 Spiritica sono pochi quelli che fanno sedute spiritiche sono legione\u00bb.<\/p>\n<p style=\"text-align: justify;\"><strong>E poi ci sono quelli che rubano ostie consacrate da utilizzare in riti magico-satanici.<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00abA Torino, come si sa, casi del genere furono oggetto di una indagine ecclesiastica, sotto il cardinale Ballestrero. Ma ci sono anche &#8220;piccole chiese&#8221; d\u2019orientamento gnostico, che hanno messo gran cura nell\u2019accaparrarsi linee sacerdotali cattoliche, con vescovi e sacerdoti &#8220;illeciti&#8221; capaci &#8211; secondo alcuni dei pochissimi teologi che si sono occupati dell\u2019argomento &#8211; di consacrare &#8220;illecitamente&#8221; ma &#8220;validamente&#8221; le ostie\u00bb<\/p>\n<p style=\"text-align: justify;\"><strong>Per poi profanarle?<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00abAll\u2019Universit\u00e0 di California, gli studiosi di sociologia religiosa sono riusciti a mettere insieme un elenco di un migliaio di vescovi &#8220;illeciti&#8221; (fra cui 30 italiani) vaganti per il mondo, cio\u00e8 di persone che probabilmente possono consacrare in modo &#8220;efficace&#8221;. Non tutti sono occultisti; ci sono, per esempio, anche i capi di gruppi cattolici scismatici ultra-tradizionali, che stanno a destra di Lef\u00e8bvre, che non userebbero mai il Sacramento per scopi blasfemi. Ma il fenomeno, sia pur limitato, esiste\u00bb.<\/p>\n<p style=\"text-align: justify;\"><strong>Ma chi sono le persone che credono nella magia? Povri ignoranti? Deboli mentali?<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00abAl contrario. Quando sono andato a trovare Michael Berthiaux, un &#8220;mago&#8221; di Chicago che mescola la magia europea al woodoo haitiano, mi son trovato di fronte un signore importante, supervisore dei servizi di assistenza sociale della citt\u00e0, che mi ha chiesto fra l\u2019altro cosa pensassi del rapporto fra Giovanni Gentile e Ugo Spirito: due filosofi italiani che, in America, non credo siano noti a pi\u00f9 di una decina di studiosi. La sociologa americana Tanja Luhrmann, che ha indagato per cinque anni nel mondo della stregoneria inglese, ha scoperto che, fra gli adepti, la professione pi\u00f9 rappresentata \u00e8 quella dei programmatori di computer. E la sociologa Maria Immacolata Ma ciocchi ha scoperto fra i &#8220;maghi&#8221; italiani o i loro seguaci parecchi laureati con conoscenze di lingue straniere. Io stesso ho incontrato spesso, in questo mondo, persone con lauree scientifiche\u00bb.<\/p>\n<p style=\"text-align: justify;\"><strong>Assurdo<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00abAnzi, il fenomeno \u00e8 comprensibile. Nella nostra societ\u00e0 industriale complessa, dove i &#8220;centri d\u2019autorit\u00e0&#8221; sono tanti e mandano segnali contraddittorii, sono possibili due reazioni di tipo religioso: i socialmente \u00abperdenti\u00bb trovano nelle sette religiose un isolamento dalla societ\u00e0 (pensiamo ai pensionati, alle casalinghe, agli immigrati che sono attratti dai Testimoni di Geova); ma le persone affermate &#8220;fin troppo entusiaste&#8221; &#8211; come ha detto Del Noce &#8211; della modernit\u00e0 e della sua complessit\u00e0, possono aderire alla magia: sia come modo sincretistico capace di &#8220;abbracciare tutte le contraddizioni&#8221; (nella magia, si pu\u00f2 essere uomini eppure sperarsi non mortali; essere corporei e credersi capaci di attraversare i muri), sia perch\u00e9 la magia, al contrario della religione, non richiede un atto di fede: come la scienza la magia consta di &#8220;operazioni&#8221;, pretende di fornire prove sperimentali. Fin dal principio, occultismo e spiritismo si sono affermati proprio ngli ambienti positivisti. Auguste Comte, il fondatore del positivismo filosofico, fond\u00f2 una sua &#8220;chiesa&#8221;, con riti riservatissimi che avevano luogo in casa sua. Conan Doyle, l\u2019inventore di Sherlock Holmes, era convinto che si potessero fotografare le fate\u00bb.<\/p>\n<p style=\"text-align: justify;\"><strong>Dicono che anche i politici non disdegnano i poteri della magia\u2026<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00abNelle mie indagini, ho raccolto numerose testimonianze a proposito dei capi di due partiti &#8220;laici&#8221; rappresentati in Parlamento &#8211; di cui non faccio i nomi a scanso di querele &#8211; che sarebbero adepti di una conventicola, la Fraternit\u00e0 di Miriam . Non \u00e8 un fenomeno nuovo. Mazzini, fervido reincarnazionista, negli ultimi anni della sua vita cominci\u00f2 a credere anche negli extraterrestri. Gli interessi occulti di Garibaldi sono troppo noti per essere ricordati. Engels, il collaboratore di Marx, attaccava ferocemente la religione ma inneggiava ai medium. Della Fraternit\u00e0 di Miriam, del resto, fu <em>magna pars<\/em> Leone Castani, amico personale di Salvemini, deputato della Sinistra prima del Fascismo\u2026\u00bb<\/p>\n<p style=\"text-align: justify;\"><strong>Di sinistra?<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00ab\u2026come Paolo Fogagnolo, gi\u00e0 membro della colonna milanese &#8220;Lo Muscio&#8221; delle Brigate Rosse, a cui devo molte notizie preziose su brigatisti interessati ad alchimia ed esoterismo. Ne parlo nel mio libro. Arrestato, Fogagnolo ebbe nell\u201981 in carcere &#8211; in occasione di uno sciopero della fame &#8211; esperienze &#8220;mistiche&#8221;. Da allora ha imboccato decisamente la strada dell\u2019esoterismo. Ha fondato un suo cenacolo, il gruppo Prometeo Agape, ma partecipa a parecchi altri. Potrei citare Sandino, eroe eponimo del movimento sandinista in Nicaragua, che evocava gli spiriti di Mos\u00e8 e Zoroastro. O persino Lenin, che visit\u00f2 presso Ascona il celebre circolo occultista-vegetariano e teosofco-pacifista &#8220;Monte Verit\u00e0&#8221;.<\/p>\n<p style=\"text-align: justify;\"><strong>Ci\u00f2 che lei dice fa pensare che ci sia qualcosa di vero nella tesi di un &#8220;complotto&#8221; politico universale, teleguidato da occulti &#8220;maghi&#8221; che, dal chiuso delle loro cerchie, influirebbero sulle scelte politiche mondiali. S\u2019\u00e8 detto che Hitler stesso fosse &#8220;guidato&#8221; da una societ\u00e0 segreta.<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00abSu questo s\u2019\u00e8 molto esagerato, ma questa tesi del complotto \u00e8 ricorrente. In America l\u2019accusa \u00e8 stata lanciata, da sinistra, sul presidente Gorge Bush, per la sua appartenenza ad una societ\u00e0 segreta chiamata &#8220;Teschio e Tibie&#8221;, nata nell\u2019Universit\u00e0 di Yale da cui sono usciti molti uomini politici di rilievo. Il fatto interessante \u00e8 che Bush continui ad ignorare queste critiche, e trovi il tempo di continuare a frequentare la conventicola. Io stesso ho raccolto notizie su un segretissimo &#8220;Ordine di Mantos&#8221;, filiato dall\u2019Ordine di Osiride, che in Italia, attorno al 1940, raccoglieva adepti soprattutto fra i nostri diplomatici, attorno a un programma di ricostruzione del mondo\u2026 Che alcuni di questi gruppi abbiano avuto l\u2019ambizione di &#8220;governare il mondo dietro le quinte&#8221; , \u00e8 probabile. Che ci siano mai riusciti, non lo credo. Credo che a questo scopo siano pi\u00f9 efficaci i circoli dei potenti dell\u2019economia e della finanza, come la riservata, ma non &#8220;occulta&#8221; Commissione Trilaterale\u00bb.<\/p>\n<p style=\"text-align: justify;\"><strong>Dal suo libro, appare che i gruppi &#8220;magici&#8221; s\u2019ostinino in riti che comprendono atti sessuali. Che l\u2019occulto sia un alibi per gente che vuol darsi alla d\u00e9bauche?<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00abTemo che, oggi, il libertinismo non abbia bisogno di simili alibi. No, il motivo \u00e8 un altro. Le &#8220;operazioni&#8221; magiche ruotano attorno a due motivi profondi: il primo \u00e8 quello della &#8220;evocazione&#8221; di angeli, che il &#8220;mago&#8221; spera, con appositi rituali, di ridurre in suo potere. Il secondo, non meno profondo, \u00e8 mosso da una vera e propria ossessione: quella di strappare a Dio il potere creatore, il potere sulla vita. Per questo il &#8220;mago&#8221; manipola magicamente la sessualit\u00e0, o meglio il liquido seminale. Ho letto con sgomento una lettera inedita di Aleister Crowley, il celeberrimo occultista, morto nel 1947 e ispiratore di quasi tutti i gruppi esoterici &#8211; tra l\u2019altro si faceva chiamare &#8220;La Grande Bestia&#8221; &#8211; in cui egli profetizza: &#8220;Quando uno di noi riuscir\u00e0 a far nascere un bimbo fuori dall\u2019utero, la magia avr\u00e0 vinto la sua battaglia contro il cristianesimo&#8221;. Ora, con la fecondazione in vitro, pare proprio che sia la scienza a riuscire l\u00e0 dove i maghi hanno fallito\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Articolo pubblicato su Avvenire gioved\u00ec 11 ottobre 199 \u00abUna linea esoterica persino nelle Br\u00bb di Maurizio Blondet<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-maghi-son-tornati\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":31814,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[68,47],"tags":[690,487],"class_list":["post-783","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esoterismo","category-magia","tag-esoterismo-2","tag-magia-2","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>I maghi son tornati - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-maghi-son-tornati\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"I maghi son tornati - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-maghi-son-tornati\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2005-06-29T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-03-16T08:22:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/06\/Introvigne_cover.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"181\" \/>\n\t<meta property=\"og:image:height\" content=\"278\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-maghi-son-tornati\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-maghi-son-tornati\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"I maghi son tornati\",\"datePublished\":\"2005-06-29T22:00:00+00:00\",\"dateModified\":\"2016-03-16T08:22:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-maghi-son-tornati\\\/\"},\"wordCount\":1512,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-maghi-son-tornati\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/06\\\/Introvigne_cover.jpg\",\"keywords\":[\"esoterismo\",\"magia\"],\"articleSection\":[\"Esoterismo\",\"Magia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-maghi-son-tornati\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-maghi-son-tornati\\\/\",\"name\":\"I maghi son tornati - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-maghi-son-tornati\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-maghi-son-tornati\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/06\\\/Introvigne_cover.jpg\",\"datePublished\":\"2005-06-29T22:00:00+00:00\",\"dateModified\":\"2016-03-16T08:22:54+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-maghi-son-tornati\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-maghi-son-tornati\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-maghi-son-tornati\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/06\\\/Introvigne_cover.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/06\\\/Introvigne_cover.jpg\",\"width\":181,\"height\":278},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-maghi-son-tornati\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"I maghi son tornati\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"I maghi son tornati - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-maghi-son-tornati\/","og_locale":"it_IT","og_type":"article","og_title":"I maghi son tornati - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-maghi-son-tornati\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2005-06-29T22:00:00+00:00","article_modified_time":"2016-03-16T08:22:54+00:00","og_image":[{"width":181,"height":278,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/06\/Introvigne_cover.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"8 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-maghi-son-tornati\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-maghi-son-tornati\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"I maghi son tornati","datePublished":"2005-06-29T22:00:00+00:00","dateModified":"2016-03-16T08:22:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-maghi-son-tornati\/"},"wordCount":1512,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-maghi-son-tornati\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/06\/Introvigne_cover.jpg","keywords":["esoterismo","magia"],"articleSection":["Esoterismo","Magia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-maghi-son-tornati\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-maghi-son-tornati\/","name":"I maghi son tornati - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-maghi-son-tornati\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-maghi-son-tornati\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/06\/Introvigne_cover.jpg","datePublished":"2005-06-29T22:00:00+00:00","dateModified":"2016-03-16T08:22:54+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-maghi-son-tornati\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-maghi-son-tornati\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-maghi-son-tornati\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/06\/Introvigne_cover.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/06\/Introvigne_cover.jpg","width":181,"height":278},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-maghi-son-tornati\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"I maghi son tornati"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/783","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=783"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/783\/revisions"}],"predecessor-version":[{"id":31815,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/783\/revisions\/31815"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/31814"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=783"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=783"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=783"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}