{"id":769,"date":"2005-06-16T15:35:31","date_gmt":"2005-06-16T13:35:31","guid":{"rendered":""},"modified":"2016-04-28T11:01:37","modified_gmt":"2016-04-28T09:01:37","slug":"paura-diffidenza-e-menzogna","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/paura-diffidenza-e-menzogna\/","title":{"rendered":"Paura, diffidenza e menzogna."},"content":{"rendered":"<div style=\"text-align: center;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-33659\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/06\/Gulag.jpg\" alt=\"Gulag\" width=\"250\" height=\"181\" \/>Il Foglio<\/strong> 21 maggio 2005<\/div>\n<p style=\"text-align: center;\"><strong>Ecco quello che il popolo sovietico impar\u00f2 nei lager<\/strong><\/p>\n<p style=\"text-align: justify;\"><em>\u201cGulag\u201d della Applebaum ha il merito di essere l\u2019anatomia di un incubo, ma lo scopo dell\u2019autrice non \u00e8 fare in modo che questo non si ripeta.\u00a0 <\/em><em>Gli appunti critici del pi\u00f9 grande sovietologo polacco<\/em><\/p>\n<p style=\"text-align: center;\">di <strong>Jerzy Pomianowski<\/strong><\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">Non occorre essere traduttore di Solzenitsyn in polacco \u2013 come lo \u00e8 chi scrive \u2013 per aprire il libro di Anne Applebaum con raccoglimento, leggerlo con crescente interesse e terminarne la lettura con ammirazione. Ci sono buone ragioni per farlo.<\/div>\n<p style=\"text-align: justify;\">L\u2019opera della Applebaum non \u00e8 solo una descrizione dettagliata della struttura, della crescita e delle cause del declino del sistema dei lager in Urss. E\u2019 anche un\u2019enciclopedia della sofferenza umana. La parte centrale del libro \u00e8 un registro obiettivo, privo d\u2019enfasi, di tutti i mezzi di repressione di massa e dei metodi di degradazione usati per sfruttare e tenere sotto controllo le masse dei condannati.Tutti i libri di memorie e i testi pubblicistici sono pieni di simili descrizioni. Gli esempi di brutalit\u00e0 vengono usati allo scopo di suscitare compassione verso le vittime, ma soprattutto per coprire d\u2019infamia i perpetratori di quelle atrocit\u00e0. Questo \u00e8 un calcolo sbagliato.<\/p>\n<p style=\"text-align: justify;\">L\u2019inflazione di motivi martirologici nella letteratura e nel cinema del dopoguerra ha portato a una banalizzazione del male, lo ha reso in qualche modo pi\u00f9 accessibile o addirittura naturale.<\/p>\n<p style=\"text-align: justify;\">L\u2019autrice di \u201cGulag\u201d (Mondadori) scrive nell\u2019epilogo: \u201cQuesto libro non \u00e8 nato per fare in modo che questo non si ripeta. L\u2019ho scritto perch\u00e9 quasi certamente questo si ripeter\u00e0. Le ideologie totalitarie hanno trovato e continuano a trovare buona accoglienza presso milioni di persone\u201d. Una di queste \u00e8 Antonio Pennacchi, l\u2019autore di \u201cL\u2019autobus di Stalin. Appunti per un elogium\u201d (Limes 6\/2004).<\/p>\n<p style=\"text-align: justify;\">Questo saggio differisce favorevolmente dalle tortuose elucubrazioni dei dotti necrofili del comunismo. E\u2019 stato scritto in buon linguaggio colloquiale e non maschera affatto le sue ardite tesi. La pi\u00f9 audace \u00e8 che le folle delle vittime dei lager e delle deportazioni in Urss (40 milioni o solo 7 \u2013 a lui non importa) partecipavano a \u201cflussi migratori\u201d indispensabili per la popolazione e\u201ccolonizzazione degli enormi spazi vuoti della Siberia e dell\u2019estremo oriente\u2026 Magari invece qualcuno campa ancora adesso\u201d.<\/p>\n<p style=\"text-align: justify;\">L\u2019autore in questione sostiene, che questi \u201cflussi migratori\u201d di imprigionati, torturati durante le istruttorie e trasportati per settimane in carri per bestiame sono pienamente paragonabili con la migrazione \u201cper fame o per piacere\u201d di centinaia di migliaia di calabresi e siciliani verso le fabbriche di Torino e Milano. Scrive il Pennacchi: \u201cL\u2019unica differenza \u00e8 tra dirigismo e fenomeni indotti\u2026 La differenza \u00e8 assai minima\u201d. Il libro della Applebaum \u00e8 stato tradotto in 23 lingue ma non in russo.<\/p>\n<p style=\"text-align: justify;\">Pazienza, i russi hanno il loro Solzenitsyn. E\u2019 un peccato, per\u00f2, che non sia stato loro tradotto l\u2019articolo del Pennacchi. Potrebbero spiegargli che la differenza fra questi due \u201cflussi migratori\u201d \u00e8 come la differenza fra le forbici del barbiere e la ghigliottina. E potrebbero forse aggiungere un loro detto, il vero fior fiore del folclore russo: leggere simili frottole \u00e8 come fottere una tigre \u2013 \u00e8 insieme ridicolo e orribile. Non basta stigmatizzare i metodi e i mezzi crudeli, perch\u00e9 quell\u2019accoglienza favorevole delle ideologie totalitarie non abbia le conseguenze che sappiamo.<\/p>\n<p style=\"text-align: justify;\">Sento per\u00f2 la risposta di qualche sostenitore di Pennacchi: \u201cVittime? Torture? D\u2019accordo, ma forse ne valeva la pena. Forse questo era inevitabile perch\u00e9 indispensabile per il Fine. Il nostro fine vale il sudore, le lacrime e il sangue di tutti coloro che solo con la violenza si possono costringere a lavorare per la giusta causa. Vittime casuali? Dove si spacca la legna, volano schegge. L\u2019individuo \u00e8 zero. A noi importa il bene della societ\u00e0\u201d.<\/p>\n<p style=\"text-align: justify;\">Bisogna riconoscere che per sostenere questa vecchia tesi i comunisti avevano un argomento in pi\u00f9, rispetto ai sostenitori di altri movimenti totalitari: la loro ideologia era rivolta a tutti, infatti proclamava l\u2019internazionalismo. I nazisti invece avevano uno scopo che non poteva essere accettato da altri: il dominio della loro nazione su tutto il resto. Tuttavia siamo in grado ormai di scoprire la sostanza di quel giusto fine, non solo perch\u00e9 nell\u2019Urss e dintorni si \u00e8 arrivati abbastanza vicino alla sua realizzazione, ma anche grazie all\u2019anatomia di questo processo, quale ci \u00e8 offerta dal libro della Applebaum.<\/p>\n<p style=\"text-align: justify;\">L\u2019autrice dice: \u201cNella pratica, l\u2019ideologia comunista era la negazione di ci\u00f2 che essa proclamava\u201d. Nel libro non mancano argomenti in favore di questa tesi. Importante \u00e8 la dimostrazione che il salto dal regno della necessit\u00e0 al regno della libert\u00e0 di cui aveva parlato Engels, si ridusse al passaggio nel regno del lavoro forzato, il quale del resto\u2013 attenzione! \u2013 si rivel\u00f2 non redditizio. Non si tratta solo del fatto che il lavoro forzato era molto meno produttivo di quello della mano d\u2019opera libera (ci\u00f2 era previsto fin dall\u2019inizio): risult\u00f2 che nessun lager era economicamente autosufficiente, e che il deficit che lo Stato doveva coprire cresceva continuamente.<\/p>\n<p style=\"text-align: justify;\">Fu questa, in fondo, la causa del fallimento dell\u2019idea dei campi di lavoro come \u201ccuore dell\u2019economia sovietica\u201d (come li ha definiti Stalin) e la causa della riduzione del loro numero. Di pi\u00f9: l\u2019idea di usare milioni di mani nude invece di macchine costose fren\u00f2 lo sviluppo della tecnica, dell\u2019inventiva, della scienza, e condusse a una netta arretratezza dell\u2019Unione Sovietica perfino nel settore degli armamenti. La Applebaum cita alcuni esempi impressionanti: ricordiamo il caso di Tupolev, il costruttore di aerei, che fu trasferito da un lager a un campo fuori serie per scienziati.<\/p>\n<p style=\"text-align: justify;\">Qualcuno come Antonio Pennacchi forse ci dir\u00e0: \u201cMa, dopo tutto, il gulag era un altro mondo, era un margine, sia pure un margine ampio, della vita sovietica! Il lager era un mezzo, sia pure un mezzo radicale, per raggiungere il fine, e il fine era la trasformazione dell\u2019intera societ\u00e0 civile\u201d.<\/p>\n<p style=\"text-align: justify;\">Ebbene, c\u2019\u00e8 per\u00f2 una sola affermazione, nel libro di Anne Applebaum, su cui non siamo d\u2019accordo: \u201cLa vita nei campi di lavoro rispecchiava, in una certa misura, la vita nell\u2019intera Unione Sovietica\u201d. A nostro parere, \u00e8 vero il contrario: la vita nei lager e il loro regime divennero l\u2019idea platonica dell\u2019ordine sociale nell\u2019Unione Sovietica.<\/p>\n<p style=\"text-align: justify;\">Il gulag non era una forma estrema, snaturata, di quell\u2019ordine, bens\u00ec la sua matrice, il suo modello maneggevole e gradito. Aleksandr Solzenitsyn aveva ragione quando scriveva che l\u2019esistenza dell\u2019Arcipelago influiva sulla forma della vita nel Grande Continente. Non si tratta solo di un rapporto di interdipendenza.<\/p>\n<p style=\"text-align: justify;\">E\u2019 lecito pensare che l\u2019intenzione di Stalin fosse quella di adattare sistematicamente la vita nell\u2019Unione Sovietica a quell\u2019ideale. Una prova possiamo trovarla nel regime della Corea del Nord, questo clone dell\u2019Urss del tempo di Stalin.<\/p>\n<p style=\"text-align: justify;\">Il primo dei fattori che determinavano quella forma era il principio della coercizione, fin dall\u2019inizio funzionante nell\u2019economia. Il secondo era l\u2019estensione di questo principio a tutti i settori della vita sociale. Condizione del successo di questa operazione totale era evidentemente l\u2019obbedienza delle masse sottoposte ad essa. Nei campi di concentramento l\u2019obbedienza era assicurata non solo dalle guardie armate, ma anche e soprattutto dai prigionieri stessi, pi\u00f9 precisamente da due categorie di detenuti: da coloro che svolgevano ufficialmente delle funzioni ausiliarie, e dai delatori.<\/p>\n<p style=\"text-align: justify;\">L\u2019autrice descrive dettagliatamente il ruolo, le divisioni e le rivalit\u00e0 all\u2019interno della prima di queste categorie. Sulla seconda si sa naturalmente meno. Certo \u00e8 che nel Grande Continente, man mano che il Sistema si rafforzava e ampliava, il delatore svolgeva un ruolo crescente, e per di pi\u00f9 doppio. La sua attivit\u00e0 segreta permetteva al potere bolscevico di avvicinarsi all\u2019ideale: possedere una conoscenza completa, raccolta in dossier, di tutti i dettagli della vita e di tutti i pensieri di tutti i sudditi.<\/p>\n<p style=\"text-align: justify;\">L\u2019esistenza di tale progetto e della moltitudine dei suoi realizzatori non era tenuta segreta. Anzi, il potere era interessato a diffondere la convinzione che ciascuno \u2013 il vicino di casa, un collega, un parente \u2013 potesse rivelarsi un informatore dell\u2019apparato di repressione. Questo era uno dei compiti pi\u00f9 semplici del settore disinformazione, e rendeva possibile economizzare personale e materiali. La convinzione generale che ogni telefono e ogni locale fosse sotto controllo permetteva all\u2019Nkvd di risparmiare tonnellate di apparecchi.<\/p>\n<p style=\"text-align: justify;\">Ci\u00f2 aveva come risultato la presenza costante, nella coscienza e nel comportamento dei cittadini, di due potenti fattori: paura e diffidenza. Il riflesso di difesa, per l\u2019uomo sovietico, consisteva nell\u2019evitare la sincerit\u00e0 \u2013 non solo nei confronti del potere, ma con qualsiasi interlocutore: chiunque potesse essere un delatore.<\/p>\n<p style=\"text-align: justify;\">La necessit\u00e0 di mentire era particolarmente insopportabile: una prova di questo \u00e8 l\u2019esplosione di speranza e il sollievo con cui furono accolte nell\u2019Urss le rivelazioni e le risoluzioni del XX Congresso.<\/p>\n<p style=\"text-align: justify;\">Alle speranze succedette poi un senso di impotenza. La triade composta menzogna aveva inevitabilmente deformato la mentalit\u00e0 non soltanto dei prigionieri del gulag, ma anche della maggioranza dei cittadini.<\/p>\n<p style=\"text-align: justify;\">Tra questa maggioranza assoluta delle vittime del sistema prevalevano i lavoratori russi, ovvero i presunti padroni del paese. E\u2019 in quest\u2019atmosfera che essi passavano la loro vita, nello stato descritto da Pennacchi come \u201clo Stato degli operai e contadini, degli sfruttati cio\u00e8 che s\u2019erano stufati di essere sfruttati\u201d. Infatti si erano definitivamente stufati di settant\u2019anni di uno sfruttamento tale che neanche un capitalismo dickensiano sarebbe riuscito a imporre. Per questa ragione l\u2019implosione dell\u2019Urss \u00e8 avvenuta in silenzio, senza una goccia di sangue e senza resistenza.<\/p>\n<p style=\"text-align: justify;\">Oggi la Georgia, l\u2019Ucraina, la Moldavia, la Kirghisia si separano dalla Centrale non perch\u00e9 istigate da Bush ma piuttosto perch\u00e9 temono la rifondazione del sistema della coercizione centralizzata.<\/p>\n<p style=\"text-align: justify;\">Se lo scopo dei bolscevichi era stata la trasformazione della societ\u00e0 e il risanamento dei rapporti umani, questo risultato dei loro sforzi merita una condanna pi\u00f9 dura di quella che meritano i mezzi cos\u00ec eloquentemente descritti in questo libro. Anne Applebaum ci ha dato una lezione di anatomia di un incubo, la quale costringe il lettore a trarre delle conclusioni politiche, sebbene l\u2019autrice non le imponga. Tali conclusioni torneranno utili non soltanto ai lettori d\u2019America e dei 23 paesi menzionati sopra.<\/p>\n<p style=\"text-align: justify;\">Gli errori nel libro sono poco numerosi e riguardano per lo pi\u00f9 dettagli secondari; per esempio: la sostanza usata per colorare le carte da gioco prodotte clandestinamente nei lager non era la streptomicina, che \u00e8 un antibiotico incolore, ma lo streptocida, uno dei primi sulfamidici, che in Urss era comunemente usato per colorare la biancheria femminile.<\/p>\n<p>_____________________________________<\/p>\n<p><strong>Anne\u00a0Applebaum<\/strong> <a href=\"http:\/\/lnx.theseuslibri.it\/product.asp?Id=162\" target=\"_blank\">Gulag. Storia dei campi di concentramento sovietici,<\/a> Oscar Mondadori -20&#8217;4; pag 696<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Foglio 21 maggio 2005 Ecco quello che il popolo sovietico impar\u00f2 nei lager \u201cGulag\u201d della Applebaum ha il merito di essere l\u2019anatomia di un incubo, ma lo scopo dell\u2019autrice non \u00e8 fare in modo che questo non si ripeta.\u00a0 Gli appunti critici del pi\u00f9 grande sovietologo polacco di Jerzy Pomianowski<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/paura-diffidenza-e-menzogna\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":33659,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[32,17,84],"tags":[139,138,265,175],"class_list":["post-769","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-filosofia-del-comunismo","category-libri","category-urss","tag-comunismo","tag-gulag","tag-libri-2","tag-urss-2","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Paura, diffidenza e menzogna. - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/paura-diffidenza-e-menzogna\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Paura, diffidenza e menzogna. - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/paura-diffidenza-e-menzogna\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2005-06-16T13:35:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-04-28T09:01:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/06\/Gulag.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"264\" \/>\n\t<meta property=\"og:image:height\" content=\"191\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/paura-diffidenza-e-menzogna\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/paura-diffidenza-e-menzogna\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Paura, diffidenza e menzogna.\",\"datePublished\":\"2005-06-16T13:35:31+00:00\",\"dateModified\":\"2016-04-28T09:01:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/paura-diffidenza-e-menzogna\\\/\"},\"wordCount\":1734,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/paura-diffidenza-e-menzogna\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/06\\\/Gulag.jpg\",\"keywords\":[\"comunismo\",\"gulag\",\"libri\",\"Urss\"],\"articleSection\":[\"Comunismo\",\"Libri\",\"URSS\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/paura-diffidenza-e-menzogna\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/paura-diffidenza-e-menzogna\\\/\",\"name\":\"Paura, diffidenza e menzogna. - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/paura-diffidenza-e-menzogna\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/paura-diffidenza-e-menzogna\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/06\\\/Gulag.jpg\",\"datePublished\":\"2005-06-16T13:35:31+00:00\",\"dateModified\":\"2016-04-28T09:01:37+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/paura-diffidenza-e-menzogna\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/paura-diffidenza-e-menzogna\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/paura-diffidenza-e-menzogna\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/06\\\/Gulag.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/06\\\/Gulag.jpg\",\"width\":264,\"height\":191},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/paura-diffidenza-e-menzogna\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Paura, diffidenza e menzogna.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Paura, diffidenza e menzogna. - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/paura-diffidenza-e-menzogna\/","og_locale":"it_IT","og_type":"article","og_title":"Paura, diffidenza e menzogna. - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/paura-diffidenza-e-menzogna\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2005-06-16T13:35:31+00:00","article_modified_time":"2016-04-28T09:01:37+00:00","og_image":[{"width":264,"height":191,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/06\/Gulag.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"9 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/paura-diffidenza-e-menzogna\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/paura-diffidenza-e-menzogna\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Paura, diffidenza e menzogna.","datePublished":"2005-06-16T13:35:31+00:00","dateModified":"2016-04-28T09:01:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/paura-diffidenza-e-menzogna\/"},"wordCount":1734,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/paura-diffidenza-e-menzogna\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/06\/Gulag.jpg","keywords":["comunismo","gulag","libri","Urss"],"articleSection":["Comunismo","Libri","URSS"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/paura-diffidenza-e-menzogna\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/paura-diffidenza-e-menzogna\/","name":"Paura, diffidenza e menzogna. - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/paura-diffidenza-e-menzogna\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/paura-diffidenza-e-menzogna\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/06\/Gulag.jpg","datePublished":"2005-06-16T13:35:31+00:00","dateModified":"2016-04-28T09:01:37+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/paura-diffidenza-e-menzogna\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/paura-diffidenza-e-menzogna\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/paura-diffidenza-e-menzogna\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/06\/Gulag.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/06\/Gulag.jpg","width":264,"height":191},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/paura-diffidenza-e-menzogna\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Paura, diffidenza e menzogna."}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/769","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=769"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/769\/revisions"}],"predecessor-version":[{"id":33660,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/769\/revisions\/33660"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/33659"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=769"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=769"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=769"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}