{"id":7593,"date":"2014-05-27T09:39:34","date_gmt":"2014-05-27T07:39:34","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=7593"},"modified":"2015-06-15T17:43:49","modified_gmt":"2015-06-15T15:43:49","slug":"la-crisi-giuridica-ovvero-lingiustizia-legale","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-crisi-giuridica-ovvero-lingiustizia-legale\/","title":{"rendered":"La crisi giuridica ovvero l\u2019ingiustizia legale"},"content":{"rendered":"<p style=\"text-align: center;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/05\/culturpol.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-7594 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/05\/culturpol-300x156.jpg\" alt=\"culturpol\" width=\"250\" height=\"180\" \/><\/a>Osservatorio Internazionale <\/strong><\/p>\n<p style=\"text-align: center;\"><strong>Cardinale Van Thuan<\/strong><\/p>\n<p style=\"text-align: center;\">11 febbraio 2014<\/p>\n<p style=\"text-align: justify;\"><i>Marted\u00ec 11 febbraio\u00a0<\/i><i style=\"font-size: 12px;\">2014 Stefano Fontana e Fabio Trevisan hanno presentato a Verona il V Rapporto sulla Dottrina sociale della Chiesa del nostro Osservatorio. Pubblichiamo qui di seguito il testo dell\u2019intervento di Stefano Fontana.<\/i><\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: center;\"><b>La crisi giuridica ovvero l\u2019ingiustizia legale<\/b><\/p>\n<p style=\"text-align: center;\"><b>nel V Ra<\/b><b style=\"font-size: 12px;\">pporto sulla Dottrina sociale della Chiesa nel mondo<\/b><\/p>\n<p style=\"text-align: center;\"><i>Verona, 11 febbraio 2014<\/i><\/p>\n<p style=\"text-align: center;\"><b>Stefano Fontana<\/b><\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Il V Rapporto sulla Dottrina sociale della Chiesa nel mondo dell\u2019Osservatorio Cardinale Van Thu\u00e2n \u00e8 dedicato quest\u2019anno alla crisi giuridica. I fenomeni di crisi giuridica sono molti e diversi. Il Rapporto non ne fa un inventario, ma si sofferma su un aspetto particolare della crisi giuridica, ritenendolo fondamentale.<\/p>\n<p style=\"text-align: justify;\">Questo aspetto emerge con grande chiarezza in quello che il Rapporto considera il \u201ccaso dell\u2019anno\u201d, dato il suo valore emblematico. Mi riferisco alla sentenza del 28 novembre 2012 con cui la Corte interamericana per i Diritti Umani ha condannato lo Stato del Costa Rica per non avere ancora una legge che preveda il riconoscimento delle coppie omosessuali e che permetta l\u2019inseminazione artificiale. A leggere la sentenza appare con grande chiarezza perch\u00e9 questo caso sia emblematico. In essa la Corte afferma che \u00abl\u2019embrione umano non pu\u00f2 essere considerato persona\u00bb, che il concepimento \u00abha luogo da quando l\u2019embrione viene impiantato nell\u2019utero\u00bb e che \u00abla protezione del diritto alla vita [\u2026] non \u00e8 assoluta, ma graduale e incrementale in relazione allo sviluppo\u00bb.<\/p>\n<p style=\"text-align: justify;\">E\u2019 di assoluta evidenza che in questo caso siamo davanti ad una sentenza \u201cmetafisica\u201d. La Corte pretende di definire cosa debba intendersi per persona umana, di stabilire che l\u2019embrione umano non possiede le caratteristiche della persona, di precisare quando si possa dire che nasce una nuova vita e quindi cosa si debba intendere per vita, e di elencare le caratteristiche che delimitano il diritto alla vita.<\/p>\n<p style=\"text-align: justify;\">Faccio notare un aspetto su cui dovremo poi riflettere. Il contesto culturale attuale \u00e8 di pensiero debole e di relativismo accentuato. La ragione non ritiene ormai pi\u00f9 possibile conoscere nessuna verit\u00e0 oltre agli aspetti misurabili della realt\u00e0. Come diceva Benedetto XVI, la ragione ha ceduto ad un suo processo interno di \u201cautolimitazione\u201d. Prevale la filosofia dell\u2019uguaglianza. Tutto \u00e8 lo stesso. Ci si potrebbe allora aspettare che le Corti di giustizia, davanti a problematiche come quelle di cui si parla nel caso del Costa Rica, si astenessero e non entrassero in un campo cos\u00ec impegnativo sul fronte della verit\u00e0. Se non c\u2019\u00e8 verit\u00e0, ogni Stato dovrebbe potersi comportare come meglio crede.<\/p>\n<p style=\"text-align: justify;\">Su questioni di quel genere, ossia tali che per il pensiero mondano di oggi \u00e8 impossibile conoscere cosa sia vero e cosa no, le Corti di giustizia diventerebbero inutili, non dovrebbero occuparsene. Invece cos\u00ec non \u00e8. La Corte in questione, in una cultura radicalmente antimetafisica, ha emesso delle sentenze metafisiche. Dicendo che la vita inizia non con la fecondazione ma con l\u2019impianto dell\u2019embrione ha addirittura contraddetto ogni evidenza scientifica, e non ha avuto alcun pudore a farlo.<\/p>\n<p style=\"text-align: justify;\">Cosa significa tutto ci\u00f2? La cultura debole e relativista che oggi domina il mondo non accetta le definizioni metafisiche della dottrina cattolica e della intelligenza filosofica.\u00a0 Ma questo non vuol dire che essa si tiri fuori dal gioco delle definizioni metafisiche, ne emette altre esattamente contrarie a quelle della dottrina cattolica e dell\u2019intelligenza filosofica. Dire che l\u2019embrione \u00e8 un grumo di cellule \u00e8 un costrutto metafisico, dire che l\u2019embrione non \u00e8 persona \u00e8 una espressione metafisica, dire che la famiglia \u00e8 anche quella tra due omosessuali \u00e8 una definizione metafisica.<\/p>\n<p style=\"text-align: justify;\">Quella Corte di giustizia ha voluto ripensare l\u2019essere. Ha sposato la visione gender, che \u00e8 una ri- plasmazione dell\u2019umanit\u00e0, una \u201cnuova creazione\u201d contraria a auella voluta da Dio. L\u2019aspetto tragico di tutto questo consiste nel fatto che i cattolici hanno smesso di coltivare la metafisica e non intendono pi\u00f9 i dogmi della propria fede in senso metafisico bens\u00ec esperienziale o esistenziale o dialogico. Mentre il mondo, anche tramite le Corti di giustizia, ri-definisce metafisicamente la struttura dell\u2019essere, i cattolici smettono di definirlo e dimenticano che la loro fede contiene una metafisica. Una simile vocazione al suicidio \u00e8 difficile da comprendere con ragioni solo umane.<\/p>\n<p style=\"text-align: justify;\">Lasciamo per il momento riposare questo tema delle Corti internazionali indicato dal Rapporto ed esaminiamone un altro, sempre a proposito della crisi della giustizia.<\/p>\n<p style=\"text-align: justify;\">I giudici dovrebbero applicare la legge. Invece, il Rapporto osserva che sempre di pi\u00f9 essi fanno la legge, sostituendosi al potere legislativo. Ci\u00f2 avviene in due modi: quando c\u2019\u00e8 un vuoto legislativo i giudici intervengono con una sentenza che di fatto riempie quel vuoto e costringe il legislatore ad intervenire. Di solito qui si innesca un processo dal difficile esito. Il secondo modo avviene tramite sentenze che sgretolano la legge e provocano ricorsi alla Corte Costituzionale che di solito d\u00e0 ragione alle sentenze giurisprudenziali. Il caso di Eluana Englaro \u00e8 stato molto chiaro in proposito.<\/p>\n<p style=\"text-align: justify;\">Il Rapporto ricorda un caso che ha fatto scuola avvenuto nel 2012 a Cagliari. Nel novembre 2012 un giudice del tribunale di Cagliari ha stabilito il diritto di una coppia alla diagnosi preimpianto, contrariamente a quanto statuito dalla legge 40 sulla fecondazione assistita. La motivazione era stata la seguente: se si pu\u00f2 abortire un feto malato, perch\u00e9 proibire di saperlo prima, cos\u00ec da evitare di impiantarlo?<\/p>\n<p style=\"text-align: justify;\">In questo modo e con un\u2019unica sentenza il giudice ha agito su tre piani: ha modificato di fatto la legge 40 contro il disegno del legislatore; ha posto inizio ad una fase di ricorsi alla Corte costituzionale la quale avrebbe cos\u00ec potuto considerare anticostituzionali alcune parti della legge in questione; \u00e8 andato sui giornali e ha costruito nell\u2019opinione pubblica una mentalit\u00e0 favorevole all\u2019ampliamento della legge 40. In altri termini, il giudice ha cambiato la legge, prefigurato l\u2019iter futuro di sviluppo e modifica della legge e creato il contesto culturale per giustificare tutto questo. Il tutto con un\u2019unica sentenza.<\/p>\n<p style=\"text-align: justify;\">A questo proposito si possono fare le medesime osservazioni svolte prima a proposito della sentenza sul Costa Rica. Anche in questo caso si assiste a sentenze che impegnano se stesse sul terreno di ripensare il reale. Nasce, tra l\u2019altro, il grave problema di difendere le leggi dai giudici ordinari, oltre che dalle Corti internazionali di giustizia. Ma nasce soprattutto la gravissima urgenza di reinserire le leggi nella legge e quest\u2019ultima nell\u2019ordine dell\u2019essere, ossia nel creato.<\/p>\n<p style=\"text-align: justify;\">Oggi il diritto, nelle forme delle sentenze delle Corti internazionali e nelle sentenze giurisprudenziali, ri-norma la legge nella pretesa di ri-normare la realt\u00e0 delle cose. Il giudice \u00e8 come un Demiurgo che, impunemente, viola la legge modificando le leggi, produce leggi ingiuste con le sue sentenze e pretende di normare <i>ex novo<\/i> l\u2019essere e la vita.<\/p>\n<p style=\"text-align: justify;\">Il Rapporto invita quindi a riflettere su un terzo aspetto della crisi giuridica, che riguarda le Carte costituzionali. Queste dovrebbero rappresentare il quadro normativo condiviso. In realt\u00e0 sono oggetto di tensioni che fanno ormai capo a opposte visioni del mondo. Sulle Costituzioni si sta celebrando una nuova guerra di religione. Le sentenze come quella sul Costa Rica, confliggono con il dettato delle Costituzioni di Paesi come il Costa Rica. Condannare il Costa Rica comporta condannare la sua Costituzione.<\/p>\n<p style=\"text-align: justify;\">Difendere la propria Costituzione comporta di opporsi alle pressioni sempre pi\u00f9 invadenti degli organismi internazionali. Introdurre nuove leggi di questo genere vuol dire modificare la Costituzione. All\u2019opposto: se non si vuole che certe leggi vengano approvate bisogna blindare la Costituzione, come ha fatto la Croazia. Negli Stati Uniti la riforma sanitaria di Obama \u00e8 in contrasto con la Costituzione.<\/p>\n<p style=\"text-align: justify;\">Nel 2012 in Argentina sono giunte a compimento le seguenti leggi: il \u201cProtocolo para la Atenci\u00f3n Integral de Personas V\u00edctimas de Violaciones Sexuales\u201d obbliga le strutture sanitarie statali a praticare l\u2019aborto; la \u201cLey de muerte digna\u201d permette l\u2019eutanasia; la \u201cLey de femicidio\u201d discrimina sulla base della teoria del gender; le disposizioni per \u201cla inscripci\u00f3n de hijos de matrimonios del mismo sexo\u201d permettono di registrare come figlio di due donne il bambino avuto da una donna unita con un\u2019altra donna prima dell\u2019entrata in vigore della legge sul matrimonio civile; la modifica della \u201cley de sangre\u201d impedisce di chiedere ai donatori di sangue informazioni sul loro orientamento sessuale, ponendo cos\u00ec a grave rischio la salute della popolazione; il progetto di \u201cfecundaci\u00f3n artificial\u201d garantisce l\u2019accesso integrale ai trattamenti medico\u2013assistenziali di riproduzione medicalmente assistita con prestazione obbligatoria, con copertura integrale in tutti i servizi medico assistenziali e con l\u2019esclusione dell\u2019obiezione di coscienza; l\u2019\u201cAnteproyecto de Reforma de los C\u00f3digos Civil y Comercial\u201d permetter\u00e0 di manipolare e distruggere gli embrioni umani prodotti in vitro e non trasferiti in utero. Su tutte queste leggi pende la certezza di incostituzionalit\u00e0.<\/p>\n<p style=\"text-align: justify;\">La Costituzione dovrebbe essere un punto di arrivo in cui tutti si riconoscono. Sar\u00e0, invece, sempre pi\u00f9 un terreno di lotta tra assoluti e i cattolici saranno sempre pi\u00f9 chiamati a fare obiezione di coscienza alle istituzioni perch\u00e9 anche le riforme costituzionali avranno la pretesa di ri-formare la realt\u00e0.<\/p>\n<p style=\"text-align: justify;\">Ecco alcuni aspetti della crisi giuridica di cui parla il Rapporto. In esso c\u2019\u00e8 sempre anche un capitolo dedicato al magistero del Sommo Pontefice nell\u2019anno di riferimento. Nel corso del 2012 Benedetto XVI ha fatto tanti discorsi illuminanti. Qui ne ricordo solo due di cui parla ampiamente il Rapporto perch\u00e9 hanno una forte connessione con la crisi giuridica.<\/p>\n<p style=\"text-align: justify;\">Nel discorso del 19 gennaio 2012 ad un gruppo di Vescovi americani in visita\u00a0<i>ad limina<\/i>, Benedetto XVI ha esposto i seguenti concetti: a) la nostra tradizione non parla a partire da una fede cieca ma dalla certezza che l\u2019universo possiede una logica interna accessibile alla ragione; b) la legge naturale \u00e8 una lingua che permette di comprendere noi stessi; c) contro tutto ci\u00f2 emergono oggi minacce molto gravi che devono essere comprese con chiarezza a livello ecclesiale; d) il rispetto della giusta autonomia del temporale deve tenere conto che non esiste un regno di questioni terrene che possa essere sottratto al Creatore e al suo dominio.<\/p>\n<p style=\"text-align: justify;\">Il secondo discorso \u00e8 quello pronunciato il 21 dicembre 2012, che contiene una delle pi\u00f9 alte critiche alla teoria del gender. Dopo aver spiegato che questa teoria \u00e8 \u201cl\u2019uomo che si vuole fare da s\u00e9\u201d, Benedetto XVI conclude dicendo che \u201csi rende evidente che l\u00e0 dove Dio viene negato, si dissolve anche la dignit\u00e0 dell\u2019uomo. Chi difende Dio difende l\u2019uomo\u201d.<\/p>\n<p style=\"text-align: justify;\">Benedetto XVI, come si vede, ci invita a cogliere la reale posta in gioco e a prendere atto della violenza dello scontro. La crisi giuridica oggi nasce dalla volont\u00e0 di ri-plasmare l\u2019essere e dare vita ad una anti-creazione nichilista nella quale non ci sia pi\u00f9 alcun posto per Dio. Le Corti di giustizia internazionali, certe sentenze giurisprudenziali e le stesse Costituzioni sono\u00a0 strumenti per tutto ci\u00f2. Niente di meno.<\/p>\n<p style=\"text-align: justify;\">\ufffd\ufffdanno di riferimento. Nel corso del 2012 Benedetto XVI ha fatto tanti discorsi illuminanti. Qui ne ricordo solo due di cui parla ampiamente il Rapporto perch\u00e9 hanno una forte connessione con la crisi giuridica.<\/p>\n<p style=\"text-align: justify;\">Nel discorso del 19 gennaio 2012 ad un gruppo di Vescovi americani in visita\u00a0<i>ad limina<\/i>, Benedetto XVI ha esposto i seguenti concetti: a) la nostra tradizione non parla a partire da una fede cieca ma dalla certezza che l\u2019universo possiede una logica interna accessibile alla ragione; b) la legge naturale \u00e8 una lingua che permette di comprendere noi stessi; c) contro tutto ci\u00f2 emergono oggi minacce molto gravi che devono essere comprese con chiarezza a livello ecclesiale; d) il rispetto della giusta autonomia del temporale deve tenere conto che non esiste un regno di questioni terrene che possa essere sottratto al Creatore e al suo dominio.<\/p>\n<p style=\"text-align: justify;\">Il secondo discorso \u00e8 quello pronunciato il 21 dicembre 2012, che contiene una delle pi\u00f9 alte critiche alla teoria del gender. Dopo aver spiegato che questa teoria \u00e8 \u201cl\u2019uomo che si vuole fare da s\u00e9\u201d, Benedetto XVI conclude dicendo che \u201csi rende evidente che l\u00e0 dove Dio viene negato, si dissolve anche la dignit\u00e0 dell\u2019uomo. Chi difende Dio difende l\u2019uomo\u201d.<\/p>\n<p style=\"text-align: justify;\">Benedetto XVI, come si vede, ci invita a cogliere la reale posta in gioco e a prendere atto della violenza dello scontro. La crisi giuridica oggi nasce dalla volont\u00e0 di ri-plasmare l\u2019essere e dare vita ad una anti-creazione nichilista nella quale non ci sia pi\u00f9 alcun posto per Dio. Le Corti di giustizia internazionali, certe sentenze giurisprudenziali e le stesse Costituzioni sono\u00a0 strumenti per tutto ci\u00f2. Niente di meno.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Osservatorio Internazionale Cardinale Van Thuan 11 febbraio 2014 Marted\u00ec 11 febbraio\u00a02014 Stefano Fontana e Fabio Trevisan hanno presentato a Verona il V Rapporto sulla Dottrina sociale della Chiesa del nostro Osservatorio. Pubblichiamo qui di seguito il testo dell\u2019intervento di Stefano Fontana. La crisi giuridica ovvero l\u2019ingiustizia legale nel V Rapporto sulla Dottrina sociale della Chiesa &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-crisi-giuridica-ovvero-lingiustizia-legale\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":7594,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,11],"tags":[430],"class_list":["post-7593","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-diritto","category-dottrina-sociale","tag-diritto-dottrina-sociale","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La crisi giuridica ovvero l\u2019ingiustizia legale - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-crisi-giuridica-ovvero-lingiustizia-legale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La crisi giuridica ovvero l\u2019ingiustizia legale - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-crisi-giuridica-ovvero-lingiustizia-legale\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2014-05-27T07:39:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-06-15T15:43:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/05\/culturpol.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"311\" \/>\n\t<meta property=\"og:image:height\" content=\"162\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-crisi-giuridica-ovvero-lingiustizia-legale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-crisi-giuridica-ovvero-lingiustizia-legale\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"La crisi giuridica ovvero l\u2019ingiustizia legale\",\"datePublished\":\"2014-05-27T07:39:34+00:00\",\"dateModified\":\"2015-06-15T15:43:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-crisi-giuridica-ovvero-lingiustizia-legale\\\/\"},\"wordCount\":2040,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-crisi-giuridica-ovvero-lingiustizia-legale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/05\\\/culturpol.jpg\",\"keywords\":[\"diritto. dottrina sociale\"],\"articleSection\":[\"Diritto\",\"Dottrina sociale\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-crisi-giuridica-ovvero-lingiustizia-legale\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-crisi-giuridica-ovvero-lingiustizia-legale\\\/\",\"name\":\"La crisi giuridica ovvero l\u2019ingiustizia legale - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-crisi-giuridica-ovvero-lingiustizia-legale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-crisi-giuridica-ovvero-lingiustizia-legale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/05\\\/culturpol.jpg\",\"datePublished\":\"2014-05-27T07:39:34+00:00\",\"dateModified\":\"2015-06-15T15:43:49+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-crisi-giuridica-ovvero-lingiustizia-legale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-crisi-giuridica-ovvero-lingiustizia-legale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-crisi-giuridica-ovvero-lingiustizia-legale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/05\\\/culturpol.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/05\\\/culturpol.jpg\",\"width\":311,\"height\":162},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-crisi-giuridica-ovvero-lingiustizia-legale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La crisi giuridica ovvero l\u2019ingiustizia legale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La crisi giuridica ovvero l\u2019ingiustizia legale - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-crisi-giuridica-ovvero-lingiustizia-legale\/","og_locale":"it_IT","og_type":"article","og_title":"La crisi giuridica ovvero l\u2019ingiustizia legale - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-crisi-giuridica-ovvero-lingiustizia-legale\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2014-05-27T07:39:34+00:00","article_modified_time":"2015-06-15T15:43:49+00:00","og_image":[{"width":311,"height":162,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/05\/culturpol.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"10 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-crisi-giuridica-ovvero-lingiustizia-legale\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-crisi-giuridica-ovvero-lingiustizia-legale\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"La crisi giuridica ovvero l\u2019ingiustizia legale","datePublished":"2014-05-27T07:39:34+00:00","dateModified":"2015-06-15T15:43:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-crisi-giuridica-ovvero-lingiustizia-legale\/"},"wordCount":2040,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-crisi-giuridica-ovvero-lingiustizia-legale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/05\/culturpol.jpg","keywords":["diritto. dottrina sociale"],"articleSection":["Diritto","Dottrina sociale"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-crisi-giuridica-ovvero-lingiustizia-legale\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-crisi-giuridica-ovvero-lingiustizia-legale\/","name":"La crisi giuridica ovvero l\u2019ingiustizia legale - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-crisi-giuridica-ovvero-lingiustizia-legale\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-crisi-giuridica-ovvero-lingiustizia-legale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/05\/culturpol.jpg","datePublished":"2014-05-27T07:39:34+00:00","dateModified":"2015-06-15T15:43:49+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-crisi-giuridica-ovvero-lingiustizia-legale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-crisi-giuridica-ovvero-lingiustizia-legale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-crisi-giuridica-ovvero-lingiustizia-legale\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/05\/culturpol.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/05\/culturpol.jpg","width":311,"height":162},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-crisi-giuridica-ovvero-lingiustizia-legale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"La crisi giuridica ovvero l\u2019ingiustizia legale"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/7593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=7593"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/7593\/revisions"}],"predecessor-version":[{"id":26280,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/7593\/revisions\/26280"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/7594"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=7593"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=7593"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=7593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}