{"id":7480,"date":"2014-05-16T12:00:09","date_gmt":"2014-05-16T10:00:09","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=7480"},"modified":"2014-05-16T12:03:04","modified_gmt":"2014-05-16T10:03:04","slug":"divorzio-sprint-40-anni-dopo-e-adesso-che-fare","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/divorzio-sprint-40-anni-dopo-e-adesso-che-fare\/","title":{"rendered":"Divorzio sprint 40 anni dopo. E adesso che fare?"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/05\/divorzio.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-7481 alignleft\" alt=\"divorzio\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/05\/divorzio.jpg\" width=\"250\" height=\"166\" \/><\/a>Comunit\u00e0 Ambrosiana<\/strong><\/div>\n<p align=\"center\">Newsletter di Alleanza Cattolica in Milano<\/p>\n<p align=\"center\">n.134 \u2013 maggio 2014<\/p>\n<p style=\"text-align: center;\"><b>Marco Invernizzi<\/b><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Care amiche, cari amici<\/p>\n<p style=\"text-align: justify;\">Proprio negli stessi giorni in cui il Parlamento italiano si appresta a varare il \u201cdivorzio breve\u201d, in realt\u00e0 brevissimo, \u201csprint\u201d come \u00e8 stato definito da Alfredo Mantovano, \u00e8 stato ricordato il quarantesimo anniversario del referendum che nel 1974 sanc\u00ec l\u2019approvazione della legge Fortuna-Baslini che appunto introduceva il divorzio nell\u2019ordinamento giuridico italiano.<\/p>\n<p style=\"text-align: justify;\">L\u2019evento \u00e8 stato celebrato come liberatorio da quasi tutti i mezzi di comunicazione. Fra le poche eccezioni una serie di servizi de <i>il Foglio<\/i>, con un articolo dello statistico <a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=7474\" target=\"_blank\">Roberto Volpi<\/a> che ricorda quanto gi\u00e0 scritto nei suoi libri, e cio\u00e8 che con il referendum cominci\u00f2 il declino demografico degli italiani e la diminuzione dei matrimoni, oltre ovviamente all\u2019incremento delle separazioni. Sempre <i>il Foglio<\/i>, in un articolo firmato da Maurizio Crippa, ricorda un punto nodale di quella stagione (e ancora attuale), ossia il motivo della mancata unit\u00e0 dei cattolici nella difesa dell\u2019indissolubilit\u00e0 del matrimonio a causa della loro ignoranza del diritto naturale.<\/p>\n<p style=\"text-align: justify;\">In poche parole, avvenne che pochi compresero l\u2019insegnamento della Chiesa secondo cui l\u2019indissolubilit\u00e0 del matrimonio \u00e8 un principio della legge naturale e non deve essere difeso nel dibattito civile e politico in quanto sacramento della fede cristiana. Lo comprese il comitato promotore del referendum e il suo Presidente, il docente di diritto romano Gabrio Lombardi, che pose questa tesi al centro della campagna referendaria. Lo disse il Consiglio permanente della Conferenza Episcopale, ma questa idea non penetr\u00f2 in profondit\u00e0 nel mondo cattolico.<\/p>\n<p style=\"text-align: justify;\">I sostenitori dell\u2019abrogazione della legge divorzista furono cos\u00ec in difficolt\u00e0 di fronte ai divorzisti che li accusavano di voler imporre la fede e le sue conseguenze morali a chi non credeva. Se sei cattolico non divorzierai, ma se non lo sei perch\u00e9 non dovresti poterlo fare? Quante volte questa tesi \u00e8 risuonata durante quegli antichi dibattiti, senza ottenere risposte adeguate, e spostando cos\u00ec centinaia di migliaia di voti da un fronte all\u2019altro.<\/p>\n<p style=\"text-align: justify;\">Ricordare \u00e8 utile se serve per evitare di ripetere errori gi\u00e0 commessi. O si riesce a spiegare che il matrimonio \u00e8 un fatto che riguarda tutti gli uomini e che la sua indissolubilit\u00e0 \u00e8 un valore universale che prescinde dalla fede, oppure non si comincer\u00e0 mai a risalire la china. Certo, lo smarrimento della fede ha influito moltissimo nella perdita del significato del matrimonio, ma se vogliamo spiegare agli uomini contemporanei le ragioni dell\u2019indissolubilit\u00e0 dobbiamo partire da un discorso di ragione.<\/p>\n<p style=\"text-align: justify;\"><b>Il mondo \u00e8 cambiato profondamente<\/b><\/p>\n<p style=\"text-align: justify;\">Il mondo \u00e8 profondamente cambiato da allora. E\u2019 cambiata la geopolitica dopo il 1989, \u00e8 cambiato il costume dopo il Sessantotto. Allora si trattava di difendere un istituto ancora forte e che comunque veniva ritenuto fondamentale anche se non si conosceva ancora, nel 1974, quanto l\u2019attacco portato alla famiglia a partire dal 1968 fosse realmente penetrato nella cultura e nel costume.<\/p>\n<p style=\"text-align: justify;\">Oggi lo abbiamo capito. Abbiamo compreso quant\u2019acqua \u00e8 passata sotto i ponti da allora e quanto quella generazione abbia dovuto subire lo scardinamento dei princ\u00ecpi.<\/p>\n<p style=\"text-align: justify;\">Se allora si trattava di difendere oggi bisogna riconquistare. Si tratta della stessa differenza fra difendere la Chiesa assediata, come \u00e8 accaduto per due secoli, l\u2019Ottocento e il Novecento, e invece riproporre il Vangelo dopo la fine di questa epoca, durata due secoli (1789-1989), che ha cambiato i connotati di una generazione.<\/p>\n<p style=\"text-align: justify;\">La nuova evangelizzazione \u00e8 proprio questa cosa. Si tratta di riproporre la salvezza dell\u2019unico Salvatore a un popolo profondamente segnato da questi ultimi 40 anni di scristianizzazione. E nel cuore della nuova evangelizzazione c\u2019\u00e8 un istituto naturale, la cui importanza fondamentale pu\u00f2 essere colta anche dalla ragione di ogni uomo, e proprio per questo pu\u00f2 essere protetta e promossa dalle leggi.<\/p>\n<p style=\"text-align: justify;\">Bisognerebbe avere l\u2019accortezza di mettere a fuoco queste cose quando si ricordano questi anniversari, altrimenti si rischia di diventare culturalmente succubi di Pannella che, celebrando il referendum, ha detto che i veri cattolici stavano con lui, nel 1974. Forse i \u201ccattolici adulti\u201d, anche se allora si autodefinivano \u201ccattolici-democratici\u201d, quelli che preferiscono disobbedire e sono prossimi all\u2019eresia, o l\u2019hanno gi\u00e0 abbracciata.<\/p>\n<p style=\"text-align: justify;\"><b>Che fare oggi?<\/b><\/p>\n<p style=\"text-align: justify;\">Ma allora come oggi i cattolici veri stanno da un\u2019altra parte. Stanno con il Magistero e con il diritto naturale, anche quando i loro preti non ne parlano mai.<\/p>\n<p style=\"text-align: justify;\">Certo, ci rendiamo conto di come sia profondamente cambiato, in peggio, il nostro mondo. Ci rendiamo conto che oggi non si tratta di difendere, ma soprattutto di riconquistare, e di ricominciare. Si tratta di \u201cuscire\u201d come dice papa Francesco, di essere visibili sulle piazze per interrogare anche chi, quasi il 90% in Italia, non frequenta la Chiesa e quindi non ha nessuna nozione di diritto naturale perch\u00e9 se quest\u2019ultimo \u00e8 stato dimenticato dai cattolici, \u00e8 stato abbandonato molto prima e molto pi\u00f9 profondamente da tutti gli altri.<\/p>\n<p style=\"text-align: justify;\">Oggi c\u2019\u00e8 poco da difendere e tutto, o quasi, da riconquistare, con pazienza e con molta umilt\u00e0, senza lanciare anatemi, senza scoraggiarsi, senza scandalizzarsi e con una grande pazienza, quella \u201cpazienza storica\u201d che manca completamente nell\u2019epoca del \u201ctutto e subito\u201d.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\"><b>Per approfondire<\/b><\/p>\n<p style=\"text-align: justify;\"><b>Pannella<\/b><i>: \u201cCon noi i cattolici veri\u201d<\/i>, intervista di Giacomo Galeazzi, <i>Vatican insider<\/i>, 12 maggio 2014<\/p>\n<p style=\"text-align: justify;\"><b>Roberto Volpi<\/b>, <a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=7474\" target=\"_blank\"><i>Mappa del disastro famigliare<\/i> <\/a>e Maurizio Crippa, <i>Fanfani, Pasolini e storie cattoliche<\/i>, <i>il Foglio<\/i>, 13 maggio 2014<\/p>\n<p style=\"text-align: justify;\"><b>Marco Invernizzi<\/b>, <i>\u201cDivorzio corto\u201d<\/i>, in <i>Cristianit\u00e0<\/i>, n. 143, marzo 1987<\/p>\n<p style=\"text-align: justify;\"><b>M. Invernizzi<\/b>, <i>Appunti sulla storia e sul &#8216;progetto&#8217; dei &#8216;cattolici democratici&#8217;<\/i>,\u00a0<i>ibid.<\/i>, n. 156-157<\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>Comunit\u00e0 Ambrosiana Newsletter di Alleanza Cattolica in Milano n.134 \u2013 maggio 2014 Marco Invernizzi &nbsp; &nbsp; &nbsp;<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/divorzio-sprint-40-anni-dopo-e-adesso-che-fare\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":7481,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[315,156],"class_list":["post-7480","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-famiglia","tag-divorzio","tag-famiglia-2","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Divorzio sprint 40 anni dopo. E adesso che fare? - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/divorzio-sprint-40-anni-dopo-e-adesso-che-fare\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Divorzio sprint 40 anni dopo. E adesso che fare? - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/divorzio-sprint-40-anni-dopo-e-adesso-che-fare\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2014-05-16T10:00:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2014-05-16T10:03:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/05\/divorzio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"271\" \/>\n\t<meta property=\"og:image:height\" content=\"186\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/divorzio-sprint-40-anni-dopo-e-adesso-che-fare\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/divorzio-sprint-40-anni-dopo-e-adesso-che-fare\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Divorzio sprint 40 anni dopo. E adesso che fare?\",\"datePublished\":\"2014-05-16T10:00:09+00:00\",\"dateModified\":\"2014-05-16T10:03:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/divorzio-sprint-40-anni-dopo-e-adesso-che-fare\\\/\"},\"wordCount\":890,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/divorzio-sprint-40-anni-dopo-e-adesso-che-fare\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/05\\\/divorzio.jpg\",\"keywords\":[\"divorzio\",\"famiglia\"],\"articleSection\":[\"Famiglia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/divorzio-sprint-40-anni-dopo-e-adesso-che-fare\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/divorzio-sprint-40-anni-dopo-e-adesso-che-fare\\\/\",\"name\":\"Divorzio sprint 40 anni dopo. E adesso che fare? - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/divorzio-sprint-40-anni-dopo-e-adesso-che-fare\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/divorzio-sprint-40-anni-dopo-e-adesso-che-fare\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/05\\\/divorzio.jpg\",\"datePublished\":\"2014-05-16T10:00:09+00:00\",\"dateModified\":\"2014-05-16T10:03:04+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/divorzio-sprint-40-anni-dopo-e-adesso-che-fare\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/divorzio-sprint-40-anni-dopo-e-adesso-che-fare\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/divorzio-sprint-40-anni-dopo-e-adesso-che-fare\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/05\\\/divorzio.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/05\\\/divorzio.jpg\",\"width\":271,\"height\":186},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/divorzio-sprint-40-anni-dopo-e-adesso-che-fare\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Divorzio sprint 40 anni dopo. E adesso che fare?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Divorzio sprint 40 anni dopo. E adesso che fare? - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/divorzio-sprint-40-anni-dopo-e-adesso-che-fare\/","og_locale":"it_IT","og_type":"article","og_title":"Divorzio sprint 40 anni dopo. E adesso che fare? - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/divorzio-sprint-40-anni-dopo-e-adesso-che-fare\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2014-05-16T10:00:09+00:00","article_modified_time":"2014-05-16T10:03:04+00:00","og_image":[{"width":271,"height":186,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/05\/divorzio.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/divorzio-sprint-40-anni-dopo-e-adesso-che-fare\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/divorzio-sprint-40-anni-dopo-e-adesso-che-fare\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Divorzio sprint 40 anni dopo. E adesso che fare?","datePublished":"2014-05-16T10:00:09+00:00","dateModified":"2014-05-16T10:03:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/divorzio-sprint-40-anni-dopo-e-adesso-che-fare\/"},"wordCount":890,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/divorzio-sprint-40-anni-dopo-e-adesso-che-fare\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/05\/divorzio.jpg","keywords":["divorzio","famiglia"],"articleSection":["Famiglia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/divorzio-sprint-40-anni-dopo-e-adesso-che-fare\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/divorzio-sprint-40-anni-dopo-e-adesso-che-fare\/","name":"Divorzio sprint 40 anni dopo. E adesso che fare? - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/divorzio-sprint-40-anni-dopo-e-adesso-che-fare\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/divorzio-sprint-40-anni-dopo-e-adesso-che-fare\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/05\/divorzio.jpg","datePublished":"2014-05-16T10:00:09+00:00","dateModified":"2014-05-16T10:03:04+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/divorzio-sprint-40-anni-dopo-e-adesso-che-fare\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/divorzio-sprint-40-anni-dopo-e-adesso-che-fare\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/divorzio-sprint-40-anni-dopo-e-adesso-che-fare\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/05\/divorzio.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/05\/divorzio.jpg","width":271,"height":186},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/divorzio-sprint-40-anni-dopo-e-adesso-che-fare\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Divorzio sprint 40 anni dopo. E adesso che fare?"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/7480","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=7480"}],"version-history":[{"count":3,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/7480\/revisions"}],"predecessor-version":[{"id":7485,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/7480\/revisions\/7485"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/7481"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=7480"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=7480"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=7480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}