{"id":736,"date":"2005-06-14T15:12:38","date_gmt":"2005-06-14T13:12:38","guid":{"rendered":""},"modified":"2016-04-19T09:49:57","modified_gmt":"2016-04-19T07:49:57","slug":"la-famiglia-dello-scudo-rosso-i-rothschild","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-famiglia-dello-scudo-rosso-i-rothschild\/","title":{"rendered":"La famiglia dello scudo rosso: i Rothschild"},"content":{"rendered":"<div style=\"text-align: center;\">\n<div id=\"attachment_33023\" style=\"width: 250px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-33023\" class=\"wp-image-33023\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/06\/Rothschild_famiglia.jpg\" alt=\"Rothschild_famiglia\" width=\"250\" height=\"195\" \/><p id=\"caption-attachment-33023\" class=\"wp-caption-text\">Famiglia Rothschild<\/p><\/div>\n<p><strong>www.disinformazione.it<strong><br \/>\n<\/strong><\/strong><\/div>\n<p style=\"text-align: center;\">di <strong>Marcello Pamio<\/strong><\/p>\n<p style=\"text-align: justify;\">Ho letto con molto interesse libri, fascicoli e siti internet su cosiddette teorie cospirative secondo le quali dietro alle vicende politiche ed economiche ci sarebbero potenti logge massoniche. Fin qui nulla di strano. Non si pu\u00f2 negare infatti che la maggior parte di queste societ\u00e0 segrete fin dalle loro origini erano composte da influenti personaggi della vita pubblica, politica e militare. La cosa per\u00f2 che ha destato la mia curiosit\u00e0 \u00e8 l\u2019onnipresenza di un nome ben preciso. Un comun denominatore rappresentato dai Rothschild. Questa famiglia, perch\u00e9 di famiglia si tratta, appartiene secondo molti all\u2019organizzazione elitaria chiamata gli <em>Illuminati di Baviera <\/em>(1) e governerebbe l\u2019intero sistema bancario mondiale con tutto quello che ne consegue.<\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">Se \u00e8 vero che questo gruppo di burattinai muove le fila della finanza, dell\u2019economia e della politica mondiale perch\u00e9 allora il nome non figura mai da nessuna parte? Avete mai letto su giornali o sentito alla televisione dei Rothschild e delle loro vicissitudini? Sarebbero dietro le quinte di tutti i pi\u00f9 importanti affari e nessuno ne parla, non \u00e8 un po\u2019 strano?<\/div>\n<p style=\"text-align: justify;\">Per la verit\u00e0 vedremo alla fine che qualcosa \u00e8 trapelato dai media. Chi ha ragione? Gli autori di svariati libri che puntano il dito contro un sistema occulto, in cui la famiglia Rothschild riveste un ruolo di primaria importanza, in grado di controllare l\u2019intero sistema o invece chi al contrario afferma che tali ipotesi sono semplicemente frutto di menti malate in preda ad allucinazioni e manie di persecuzioni?<\/p>\n<p style=\"text-align: justify;\">L\u2019esperienza mi suggerisce che la verit\u00e0 sta sempre nel mezzo! Quindi prima di avanzare qualsiasi ipotesi in merito andiamo a vedere chi sono e soprattutto cosa fanno oggi i Rothschild. Per ripercorrere le origini torniamo indietro nel tempo di circa duecento anni spostandosi in Germania, precisamente a Francoforte. L\u2019anno \u00e8 il 1743.<\/p>\n<p style=\"text-align: justify;\">L\u2019Adamo non proprio biblico della nostra storia \u00e8 Amschel Moses Bauer, un semplice orafo tedesco con la <em>passione, <\/em>che oggi possiamo chiamarla predisposizione, per prestiti e finanziamenti. Semplice orafo per modo di dire naturalmente, visto che \u00e8 il capostipite che ha dato origine a un impero economico da mille e una notte. Un impero nato sotto le ali protettive dell\u2019aquila romana contornata da uno scudo rosso. Tale infatti \u00e8 il sigillo che Amschel aveva collocato sull\u2019entrata della propria azienda.<\/p>\n<p style=\"text-align: justify;\">Un logo che divenne presto la rappresentazione figurata dell\u2019attivit\u00e0 di Bauer. &#8220;La ditta dello Scudo Rosso&#8221; veniva infatti chiamata. D\u2019altronde abbiamo tantissimi esempi anche nostrani di queste associazioni: uno per tutti il Cavallino Rampante per indicare la Ferrari. Quello che non tutti sanno invece \u00e8 che lo Scudo Rosso in lingua tedesca \u00e8 Rothschild. Per essere pi\u00f9 precisi: Scudo Rosso &#8211; Red Schield &#8211; Rothen Schild &#8211; Rothschild. Questo particolare \u00e8 molto importante perch\u00e9 quando il figlio di Moses, Mayer Amschel eredit\u00f2 da suo padre la societ\u00e0 cambi\u00f2 nome in Rothschild, e tale \u00e8 rimasto immutato fino ai giorni nostri.<\/p>\n<p style=\"text-align: justify;\">Mayer Rothschild da Gertrude Schnapper ebbe cinque figli: Amschel (1773-1855), Salomon (1774-1855), Nathan (1777-1836), Karl (1788-1855) e Jacob (1792-1868). Non appena i ragazzi furono istruiti a dovere sull\u2019attivit\u00e0 economica e finanziaria partirono alla volta di altrettante capitali europee per aprire filiali ed espandere l\u2019impero esclusivamente patriarcale. Le donne avevano un ruolo secondario nella gestione.<\/p>\n<p style=\"text-align: justify;\">Il primogenito Amschel essendo il pi\u00f9 anziano rimase a Francoforte per controllare la societ\u00e0 base, Salomon invece and\u00f2 a Vienna, Nathan a Londra, Karl a Napoli e Jakob a Parigi. La famiglia cresce, e cresce anche la necessit\u00e0 di un nuovo emblema che li rappresenti al meglio. Cinque frecce che s\u2019incrociano intersecandosi in un unico punto \u00e8 il nuovo stemma. Le frecce rappresentano i cinque fratelli e il punto d\u2019intersezione \u00e8 lo scopo che unisce tutta la famiglia. Avrete gi\u00e0 capito qual \u00e8 questo scopo.<\/p>\n<p style=\"text-align: justify;\">Senza nulla togliere all\u2019operato dei fratelli, \u00e8 d\u2019obbligo \u201cspezzare una freccia\u201d -visto che siamo in tema- a favore di Nathan il quale si distinse immediatamente per fiuto e capacit\u00e0 imprenditoriali. Ricordiamo che agli inizi dell\u2019Ottocento l\u2019Europa stava cambiando velocemente e questo poteva creare certamente molte occasioni per uomini intelligenti e soprattutto ricchi. Nathan approfitt\u00f2 di questa situazione e apr\u00ec a Manchester una impresa tessile.<\/p>\n<p style=\"text-align: justify;\">Il rapido declino delle esportazioni tessili britanniche durante il blocco continentale costrinsero per\u00f2 Nathan a tornare a Londra per estendere le proprie attivit\u00e0 in ambito finanziario. Le attivit\u00e0 del <em>figliol prodigo<\/em> s\u2019impennarono in potenza e prestigio grazie anche al matrimonio con Hannah Barent Cohen (1783-1850), la figlia di uno dei pi\u00f9 ricchi mercanti ebrei londinesi (2) I conti li sapeva fare molto bene! Conti che dirottavano sempre pi\u00f9 verso operazioni finanziarie speculative su titoli britannici ed esteri, cambi valute, metalli preziosi, ecc.<\/p>\n<p style=\"text-align: justify;\">Qualche esempio? Il Duca di Wellington non avrebbe potuto pagare il suo esercito nella battaglia di Waterloo senza la mano, anzi il portafogli, dei Rothschild (3). Dopo questa vittoria, la banca di Nathan vinse il contratto per i pagamenti dei tributi agli alleati europei (4). Anche il governo francese dovette usufruire dei fondi privati per rimpinguare le casse nazionali svuotate dall\u2019estenuante guerra franco-prussiana (5). Salomon Rothschild a Vienna finanziava intanto il debito estero austriaco attraverso contratti di prestito al Principe Metternich (6).<\/p>\n<p style=\"text-align: justify;\">I cinque fratelli pur lavorando a distanza portavano avanti la stessa tecnica, quella della riserva frazionale bancaria. Questo permise la loro autonomia e indipendenza in ogni paese in cui operavano. Con queste enormi risorse economiche riuscirono a intervenire persino a favore della Banca d\u2019Inghilterra, quando la crisi di liquidit\u00e0 del 1826 pieg\u00f2 le gambe al governo britannico. Grazie ad una immissione di un grosso quantitativo di oro fu scongiurato il peggio (7).<\/p>\n<p style=\"text-align: justify;\">Ma la storia non finisce qui, perch\u00e9 nel settore pubblico si distinsero per i finanziamenti della rete ferroviaria in Francia, Italia, Austria, per il Canale di Suez, permisero l\u2019acquisto dei terreni minerari in Spagna, Sud America, Sud Africa e Africa Occidentale. L\u2019oro era cos\u00ec importante e fondamentale per i Rothschild che dal 1919 fino ai nostri giorni la banca ha ospitato e presieduto per due volte al giorno il fixing mondiale del prezzo dell\u2019oro (8).<\/p>\n<p style=\"text-align: justify;\">Vi rendete conto: stabilivano anche il prezzo mondiale dell\u2019oro! Addirittura sembrerebbe, e il condizionale \u00e8 d\u2019obbligo, che una banca della famiglia abbia finanziato John D. Rockefeller per la sua monopolizzazione della raffinazione del petrolio che port\u00f2 alla fondazione della Standard Oil.<\/p>\n<p style=\"text-align: justify;\">Cosa dire delle ricostruzioni postbelliche? Nelle guerre si sa, non vi sono mai vincitori. Di per s\u00e9 una guerra \u00e8 sempre una sconfitta sia per chi la provoca ma soprattutto per chi la subisce. Dall\u2019ottica di un banchiere per\u00f2, una guerra \u00e8 sempre una ghiotta opportunit\u00e0 di investimenti, di prestiti, di ricostruzioni. Infatti dopo la Prima Guerra Mondiale, precisamente nel 1922 i Rothschild misero a disposizione fondi per la ricostruzione in numerosi paesi come Francia, Germania, Cecoslovacchia, Ungheria.<\/p>\n<p style=\"text-align: justify;\">A questo punto ho dovuto scacciare con la forza dalla mia mente un dubbio tremendo. E\u2019 possibile che banchieri senza scrupoli fomentino a proprio piacimento le guerre, magari finanziando entrambe le fazioni e innescando la miccia fornendo poi i soldi per la ricostruzione? In via molto ipotetica s\u00ec. Scatenare una guerra non \u00e8 cos\u00ec difficile: si forniscono le armi a entrambe le parti e si trova una motivazione sufficiente: religione, petrolio, terrorismo, ecc.<\/p>\n<p style=\"text-align: justify;\">No! La perfidia umana non pu\u00f2 arrivare a tanto! Giusto? A questo punto negare o far finta di non vedere che l\u2019impero dei Rothschild fin dai primi anni del secolo XIX ha influenzato la politica, l\u2019economia e la finanza del mondo intero \u00e8 un\u2019offesa alla comune intelligenza.<\/p>\n<p style=\"text-align: justify;\">E oggi? Come sono messi, anzi, visto che interessa pure la nostra cara Italia come siamo messi? Forse la famiglia si \u00e8 ritirata a vita privata e si sta godendo un meritato riposo? Sbagliato. Certamente la vita \u00e8 rimasta sempre molto privata. Non riesco infatti ancora a spiegarmi come la stampa, sempre pi\u00f9 ricca di pettegolezzi e gossip e meno di informazioni utili, non s\u2019interessi della vita di questi personaggi affascinanti e al limite del misterosofico. Riescono \u2013i media- a scovare una star televisiva che si sta abbronzando nuda dentro la caldera di un vulcano in pieno inverno e nessuno fa un servizio sugli appartenenti alla famiglia pi\u00f9 potente del pianeta. Non \u00e8 un po\u2019 strano?<\/p>\n<p style=\"text-align: justify;\">Lungi da me l\u2019idea che gli editor <em>non possano<\/em> fare servizi su certi banchieri internazionali, rimane allora la spiegazione che forse a nessuno interesserebbe. Strano perch\u00e9 personalmente preferirei leggere qualcosa sui \u00abveri controllori\u00bb piuttosto che leggere e\/o vedere qualche personaggetto estivo che pur di apparire nei giornali venderebbe la propria anima al diavolo, in questo caso fotografi e giornalisti.<\/p>\n<p style=\"text-align: justify;\">Tornando al discorso di prima, oggi la famiglia Rothschild non ha perso prestigio e potere, semmai con il passare degli anni lo ha consolidato ulteriormente. Incredibile ma vero. Passano gli anni e i loro sistemi si adeguano. Oggi hanno sviluppato una divisione per il finanziamento d\u2019impresa al servizio di fusioni e acquisizioni. Operazioni queste all\u2019ordine del giorno. Basta aprire un qualsiasi giornale finanziario per leggere che la multinazionale ics si \u00e8 unita, o \u00e8 in procinto di farlo, con la transnazionale ipsilon.<\/p>\n<p style=\"text-align: justify;\">Fusioni il cui unico risultato \u00e8 la creazione di megacorporazioni amministrate da pochissimi e composte da migliaia tra affiliate e holding. In fisica per innescare una fusione nucleare tra atomi serve molta energia qui le fusioni necessitano solo di soldi. Moltissimi soldi. Chi possiede tutti questi soldi se non i banchieri? Vediamo adesso nel dettaglio dove i tentacoli economici dei Rothschild sono arrivati nel 3\u00b0 Millennio.<\/p>\n<p style=\"text-align: justify;\">Per problemi di spazio cito solamente le societ\u00e0 pi\u00f9 conosciute e\/o riguardanti il nostro paese, ma chiunque volesse approfondire consiglio di entrare nel sito ufficiale della famiglia e stamparsi l\u2019elenco completo. Fate scorta di carta! Tra le straniere spiccano: <em>De Beers<\/em> quella dei diamanti, la <em>Enron<\/em> fallita da poco, <em>British Telecom, France Telecom, Deutch Telekom, Alcatel, Eircom, Mannesmann, AT&amp;T, BBC, Petro China, Petro Bras, Canal +, Vivendi, Aventis, Unilever, Royal Canin, Pfaff, Deutch Po<\/em>st (9), e moltissime altre.<\/p>\n<p style=\"text-align: justify;\">Torniamo adesso un momento in Italia poich\u00e9 ce n\u2019\u00e8 per tutti i gusti: Tiscali, Seat Pagine Gialle, Eni, Rai, Banca di Roma, Banco di Napoli, BNL Banca Nazionale del Lavoro, Banca Intesa, Bipop-Carire, Banca Popolare di Lodi, Monte dei Paschi di Siena, Rolo Banca 1473, Finmeccanica (10). Vi pu\u00f2 bastare? Penso proprio di s\u00ec! Mi avvio a concludere nella speranza che questa piccola e incompleta illustrazione possa almeno aver fatto nascere qualche dubbio e\/o curiosit\u00e0 in pi\u00f9 su questa incredibile e decisamente atipica famigliola.<\/p>\n<p style=\"text-align: justify;\">Non posso confermare ma neppure smentire le pesanti e inquietanti affermazioni che svariati autori pubblicano sui Rothschild. Tengo a sottolineare che la cosa pi\u00f9 incredibile \u00e8 come i media in generale evitano di trattare tali argomentazioni. Passi il discorso sulla cospirazione globalizzata alla George Orwell, ma qui i fatti parlano chiaro. Le trame e gli intrecci economici pure. Sono sotto gli occhi di tutti. Almeno di chi vuol vedere.<\/p>\n<p style=\"text-align: justify;\">Non posso accontentarmi di leggere su La Stampa del 7 giugno 1996 che Lady Rothschild era l\u2019ipotetica spia del KGB a Londra, o su Il Giorno del 29 agosto 2000 la cronaca della morte per overdose all\u2019et\u00e0 di 23 anni di Raphael figlio di Nathaniel Rothschild. Queste rientrano nel deleterio e purtroppo tanto seguito gossip. Le cose serie e importanti sono altre.<\/p>\n<p style=\"text-align: justify;\"><strong>Note<\/strong><\/p>\n<p style=\"text-align: justify;\">(1) Gruppo elitario fondato dal prof. di Giurisprudenza all\u2019Universit\u00e0 dei Gesuiti, Adam Weishaupt (Spartacus) in Baviera il primo maggio 1776<\/p>\n<div style=\"text-align: justify;\" align=\"justify\">(2) Universit\u00e0 di Bologna, facolt\u00e0 di Scienze Politiche: <a href=\"www.spbo.unibo.it\" target=\"_blank\">www.spbo.unibo.it<\/a><\/div>\n<div style=\"text-align: justify;\" align=\"justify\">(3) Sito ufficiale della famiglia Rothscild. <a href=\"http:\/\/www.rothscild.com\/\" target=\"_blank\">http:\/\/www.rothscild.com\/<\/a><\/div>\n<div style=\"text-align: justify;\" align=\"justify\">(4) Universit\u00e0 di Bologna, facolt\u00e0 di Scienze Politiche: <a href=\"www.spbo.unibo.it\" target=\"_blank\">www.spbo.unibo.it<\/a><\/div>\n<div style=\"text-align: justify;\" align=\"justify\">(5) Idem<\/div>\n<div style=\"text-align: justify;\" align=\"justify\">(6) Idem<\/div>\n<div style=\"text-align: justify;\" align=\"justify\">(7) Idem<\/div>\n<div style=\"text-align: justify;\" align=\"justify\">(8) Sito ufficiale della famiglia Rothscild. <a href=\"http:\/\/www.rothscild.com\/\" target=\"_blank\">http:\/\/www.rothscild.com\/<\/a><\/div>\n<div style=\"text-align: justify;\" align=\"justify\">(9) Idem<\/div>\n<div style=\"text-align: justify;\" align=\"justify\">(10) Idem<\/div>\n","protected":false},"excerpt":{"rendered":"<p>www.disinformazione.it di Marcello Pamio Ho letto con molto interesse libri, fascicoli e siti internet su cosiddette teorie cospirative secondo le quali dietro alle vicende politiche ed economiche ci sarebbero potenti logge massoniche. Fin qui nulla di strano. Non si pu\u00f2 negare infatti che la maggior parte di queste societ\u00e0 segrete fin dalle loro origini erano &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-famiglia-dello-scudo-rosso-i-rothschild\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":33023,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13,61],"tags":[2389,271,672],"class_list":["post-736","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia","category-mondialismo-e-globalizzazione","tag-economia","tag-mondialismo","tag-rothschild","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La famiglia dello scudo rosso: i Rothschild - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-famiglia-dello-scudo-rosso-i-rothschild\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La famiglia dello scudo rosso: i Rothschild - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-famiglia-dello-scudo-rosso-i-rothschild\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2005-06-14T13:12:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-04-19T07:49:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/06\/Rothschild_famiglia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"254\" \/>\n\t<meta property=\"og:image:height\" content=\"198\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-famiglia-dello-scudo-rosso-i-rothschild\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-famiglia-dello-scudo-rosso-i-rothschild\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"La famiglia dello scudo rosso: i Rothschild\",\"datePublished\":\"2005-06-14T13:12:38+00:00\",\"dateModified\":\"2016-04-19T07:49:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-famiglia-dello-scudo-rosso-i-rothschild\\\/\"},\"wordCount\":1924,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-famiglia-dello-scudo-rosso-i-rothschild\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/06\\\/Rothschild_famiglia.jpg\",\"keywords\":[\"Economia\",\"mondialismo\",\"Rothschild\"],\"articleSection\":[\"Economia\",\"Mondialismo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-famiglia-dello-scudo-rosso-i-rothschild\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-famiglia-dello-scudo-rosso-i-rothschild\\\/\",\"name\":\"La famiglia dello scudo rosso: i Rothschild - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-famiglia-dello-scudo-rosso-i-rothschild\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-famiglia-dello-scudo-rosso-i-rothschild\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/06\\\/Rothschild_famiglia.jpg\",\"datePublished\":\"2005-06-14T13:12:38+00:00\",\"dateModified\":\"2016-04-19T07:49:57+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-famiglia-dello-scudo-rosso-i-rothschild\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-famiglia-dello-scudo-rosso-i-rothschild\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-famiglia-dello-scudo-rosso-i-rothschild\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/06\\\/Rothschild_famiglia.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/06\\\/Rothschild_famiglia.jpg\",\"width\":254,\"height\":198},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-famiglia-dello-scudo-rosso-i-rothschild\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La famiglia dello scudo rosso: i Rothschild\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La famiglia dello scudo rosso: i Rothschild - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-famiglia-dello-scudo-rosso-i-rothschild\/","og_locale":"it_IT","og_type":"article","og_title":"La famiglia dello scudo rosso: i Rothschild - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-famiglia-dello-scudo-rosso-i-rothschild\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2005-06-14T13:12:38+00:00","article_modified_time":"2016-04-19T07:49:57+00:00","og_image":[{"width":254,"height":198,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/06\/Rothschild_famiglia.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"10 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-famiglia-dello-scudo-rosso-i-rothschild\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-famiglia-dello-scudo-rosso-i-rothschild\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"La famiglia dello scudo rosso: i Rothschild","datePublished":"2005-06-14T13:12:38+00:00","dateModified":"2016-04-19T07:49:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-famiglia-dello-scudo-rosso-i-rothschild\/"},"wordCount":1924,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-famiglia-dello-scudo-rosso-i-rothschild\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/06\/Rothschild_famiglia.jpg","keywords":["Economia","mondialismo","Rothschild"],"articleSection":["Economia","Mondialismo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-famiglia-dello-scudo-rosso-i-rothschild\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-famiglia-dello-scudo-rosso-i-rothschild\/","name":"La famiglia dello scudo rosso: i Rothschild - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-famiglia-dello-scudo-rosso-i-rothschild\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-famiglia-dello-scudo-rosso-i-rothschild\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/06\/Rothschild_famiglia.jpg","datePublished":"2005-06-14T13:12:38+00:00","dateModified":"2016-04-19T07:49:57+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-famiglia-dello-scudo-rosso-i-rothschild\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-famiglia-dello-scudo-rosso-i-rothschild\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-famiglia-dello-scudo-rosso-i-rothschild\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/06\/Rothschild_famiglia.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/06\/Rothschild_famiglia.jpg","width":254,"height":198},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-famiglia-dello-scudo-rosso-i-rothschild\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"La famiglia dello scudo rosso: i Rothschild"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/736","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=736"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/736\/revisions"}],"predecessor-version":[{"id":33024,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/736\/revisions\/33024"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/33023"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=736"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=736"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}