{"id":703,"date":"2005-06-12T00:00:00","date_gmt":"2005-06-11T22:00:00","guid":{"rendered":""},"modified":"2025-02-19T12:58:41","modified_gmt":"2025-02-19T11:58:41","slug":"prospettive-teologiche-e-pastorali-in-tema-di-dialogo-e-dimmigrazionei-problemi-pastorali-posti-dallimmigrazione","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/prospettive-teologiche-e-pastorali-in-tema-di-dialogo-e-dimmigrazionei-problemi-pastorali-posti-dallimmigrazione\/","title":{"rendered":"I problemi pastorali posti dall&#8217;immigrazione"},"content":{"rendered":"\n<p class=\"has-text-align-center\">pubblicato in <strong><a href=\"https:\/\/alleanzacattolica.org\/\" target=\"_blank\" rel=\"noreferrer noopener\">Cristianit\u00e0<\/a>,<\/strong> 307 (2001)<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center\">Prospettive teologiche e pastorali in tema di dialogo e d\u2019immigrazione<\/h3>\n\n\n\n<p><em>Intervento d\u2019apertura del convegno sul tema <\/em>Multiculturalit\u00e0 e identit\u00e0 oggi<em> &#8211; organizzato nei giorni 20, 21 e 22 settembre 2001 presso l\u2019Oratorio di San Filippo Neri, nel capoluogo emiliano, dall\u2019Istituto &#8220;Veritatis Splendor&#8221; -, tenuto da <strong>S. E. il card. Giacomo Biffi<\/strong>, arcivescovo di Bologna e presidente del Consiglio Scientifico dell\u2019Istituto promotore. Testo diffuso dall\u2019Ufficio Stampa dell\u2019arcidiocesi. Titolo redazionale. Le note sono state portate al piede e sono state fatte inserzioni &#8211; pure redazionali &#8211; fra parentesi quadre.<\/em><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/06\/immigrazione.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"285\" height=\"177\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/06\/immigrazione.jpg\" alt=\"\" class=\"wp-image-26738\" style=\"width:483px;height:auto\"\/><\/a><\/figure><\/div>\n\n\n<!--more-->\n\n\n\n<p>Voglio congratularmi con l\u2019Istituto &#8220;Veritatis Splendor&#8221; per l\u2019iniziativa di questo Convegno. Le tematiche che qui saranno toccate non soltanto sono per se stesse di grande rilievo, ma anche si connotano di un\u2019attualit\u00e0 viva e (sembra di poter dire) crescente. La felice pluralit\u00e0 delle voci sapr\u00e0 ben lumeggiare, ne sono certo, i vari argomenti; argomenti distinti tra loro e multiformi, ma contigui e anzi in pi\u00f9 di un caso vicendevolmente connessi.<\/p>\n\n\n\n<p>Per parte mia, vorrei richiamare l\u2019attenzione su due differenti questioni, che gi\u00e0 altra volta mi hanno dato l\u2019occasione di esprimere qualche convincimento: quella dell\u2019identit\u00e0 cristiana entro la dominante &#8220;cultura del dialogo&#8221; (1) e quella dell\u2019immigrazione nelle nostre terre (2). Dico subito che, se la mia <em>forma mentis<\/em> \u00e8 quella del teologo (sia pure di un teologo in disarmo), le mie prospettive e i miei interessi sono quelli del pastore.<\/p>\n\n\n\n<h4 class=\"wp-block-heading has-text-align-center\"><strong>La questione del &#8220;dialogo&#8221;<\/strong><\/h4>\n\n\n\n<p>La necessit\u00e0 del dialogo &#8211; oggi enfaticamente asserita un po\u2019 in tutti i contesti, fino a essere quasi ossessiva &#8211; \u00e8 quasi un\u2019ovviet\u00e0. Come potrebbero vivere gli abitanti di un pianeta cos\u00ec fortemente comunicante e unificato come il nostro, senza parlarsi e confrontarsi tra loro? Possiamo anzi essere d\u2019accordo anche sulla doverosa ricerca della reciproca comprensione attraverso una benevola attenzione all\u2019&#8221;altro&#8221; (questo pare sia oggi il senso culturale del termine &#8220;dialogo&#8221;).<\/p>\n\n\n\n<p>\u00c8 tuttavia innegabile che nella concretezza esistenziale del rapporto tra non credenti e credenti (almeno quei credenti che non vogliono smarrire la loro originale identit\u00e0) emerge a questo proposito qualche problema, che deve essere correttamente affrontato.<\/p>\n\n\n\n<p>Baster\u00e0 pensare alla pubblicazione, lo scorso anno 2000, da parte della Congregazione per la dottrina della fede della Dichiarazione <em>Dominus Iesus<\/em>: non era mai capitato &#8211; in venti secoli di cristianesimo &#8211; che si sentisse il bisogno di ricordare ai discepoli di Ges\u00f9 una verit\u00e0 cos\u00ec elementare e primaria come questa: il Figlio di Dio fatto uomo, morto per noi e risorto, \u00e8 l\u2019unico necessario Salvatore di tutti. Evidentemente si \u00e8 temuto che di questi tempi Ges\u00f9 Cristo potesse diventare l\u2019illustre vittima del dialogo interreligioso.<\/p>\n\n\n\n<p>Paolo VI [1963-1978] &#8211; che con l\u2019enciclica <em>Ecclesiam suam<\/em> (1964) ha introdotto ufficialmente il tema nei documenti del Magistero &#8211; ha chiarito le opportunit\u00e0, i metodi, i fini, ma si \u00e8 volutamente astenuto da dare alla proposta di &#8220;dialogo&#8221; una vera e propria fondazione teologica. Il che \u00e8 forse alla fonte delle intemperanze e delle ambiguit\u00e0 che hanno poi aduggiato la cristianit\u00e0 (3).<\/p>\n\n\n\n<p>Nel tentativo di attenuare tale inconveniente e nella speranza che il discorso sia poi proseguito dagli addetti ai lavori (possibilmente senza eccessive precomprensioni ideologiche e senza troppo indulgere alla moda del &#8220;politicamente corretto&#8221;), mi prover\u00f2 a elencare alcuni elementi di riflessione a mio avviso incontestabili e ineludibili.<\/p>\n\n\n\n<p><strong>1.<\/strong> L\u2019evento salvifico &#8211; nei due fatti costitutivi dell\u2019incarnazione del Verbo e della risurrezione di Ges\u00f9 &#8211; sta all\u2019origine del cristianesimo e ne rappresenta in forma perenne e definitiva il senso e il cuore. Essendo dei &#8220;fatti&#8221;, essi non sono &#8220;trattabili&#8221;: chi &#8220;crede&#8221; non li pu\u00f2, restando logico, n\u00e9 attenuare n\u00e9 mettere tra parentesi; chi &#8220;non crede&#8221; non li pu\u00f2 razionalmente accettare.<\/p>\n\n\n\n<p>Sono dunque culturalmente &#8220;laceranti&#8221;. Il che \u00e8 chiaramente insegnato dalla parola di Dio in alcuni testi oggi abbondantemente censurati:<\/p>\n\n\n\n<p>&#8211; <em>&#8220;Egli \u00e8 qui per la rovina e la risurrezione di molti in Israele, segno di contraddizione perch\u00e9 siano svelati i pensieri di molti cuori&#8221;<\/em> (<em>Lc<\/em>. 2, 34-35).<\/p>\n\n\n\n<p>&#8211; <em>&#8220;Non crediate che io sia venuto a portare pace sulla terra; non sono venuto a portare pace, ma una spada&#8221;<\/em> (<em>Mt<\/em>. 10, 34).<\/p>\n\n\n\n<p>&#8211; <em>&#8220;La pietra che i costruttori hanno scartata \u00e8 diventata testata d\u2019angolo&#8230; Chi cadr\u00e0 su questa pietra sar\u00e0 sfracellato; e qualora essa cada su qualcuno, lo stritoler\u00e0&#8221;<\/em> (<em>Mt<\/em>. 21, 42.44).<\/p>\n\n\n\n<p>Alla luce di questi insegnamenti, il principio che &#8220;bisogna guardare pi\u00f9 a ci\u00f2 che ci unisce che a quello che ci divide&#8221; (utilissimo nella sua accezione &#8220;politica&#8221; e comportamentale) diventa ambiguo fino a essere deviato e alienante nell\u2019ambito del dialogo interreligioso: il cristiano guarda &#8211; e non pu\u00f2 mai cessare di guardare &#8211; soprattutto a ci\u00f2 che la Rivelazione gli ha indicato come eminente e sostanziale.<\/p>\n\n\n\n<p><strong>2.<\/strong> Nel cristiano la fede \u00e8 un\u2019intelligenza assolutamente nuova e imparagonabile, che gli deriva dalla luce comunicatagli dallo Spirito del Signore risorto: tale luce ha come effetto proprio di far partecipare alla conoscenza stessa che possiede il Signore Ges\u00f9. Chi ne \u00e8 privo, manca del principio conoscitivo adeguato a cogliere il significato ultimo di questo ordine di cose concretamente esistente (che \u00e8 incentrato in Cristo ed \u00e8 dunque &#8220;soprannaturale&#8221;).<\/p>\n\n\n\n<p>\u00c8 l\u2019insegnamento esplicito e inequivocabile di san Paolo, che chiarisce la differenza e la fatale incomunicabilit\u00e0 che c\u2019\u00e8 tra l\u2019uomo <em>pneumatik\u00f2s<\/em> e l\u2019uomo <em>psychik\u00f2s<\/em>: <em>&#8220;Noi non abbiamo ricevuto lo spirito del mondo, ma lo Spirito di Dio per conoscere tutto ci\u00f2 che Dio ci ha donato. L\u2019uomo &#8220;psichico&#8221; invece non comprende le cose dello Spirito di Dio; esse sono follia per lui e non \u00e8 capace di intenderle, perch\u00e9 se ne pu\u00f2 giudicare per mezzo dello Spirito&#8221;<\/em> (<em>1 Cor<\/em>. 2, 12-15).<\/p>\n\n\n\n<p><strong>3.<\/strong> Secondo la dottrina di san Paolo, tutto dall\u2019inizio \u00e8 stato pensato e voluto in Cristo (cfr. <em>Col<\/em>. 1, 15-20). E dunque ogni uomo \u00e8 stato esemplato su Cristo: proprio in quanto uomo, egli \u00e8 una iniziale immagine del Figlio di Dio. Si deve dunque pensare che nessun uomo, in questa &#8220;economia&#8221; cristocentrica, sia abbandonato entro i confini della pura naturalit\u00e0 e sia lasciato senza alcun aiuto che lo proporzioni almeno per qualche aspetto alla soprannaturalit\u00e0 dell\u2019universo come in realt\u00e0 esiste.<\/p>\n\n\n\n<p><strong>4. <\/strong><em>&#8220;Lo Spirito <\/em>&#8211; ha detto Ges\u00f9 &#8211;<em> spira dove vuole&#8221;<\/em> (<em>Gv<\/em>. 3, 8). Non \u00e8 da sottovalutare la libera azione illuminante che \u00e8 propria dello Spirito Santo, effuso sull\u2019umanit\u00e0 dal Signore che sta alla destra del Padre. \u00c8 un\u2019azione alla quale noi non possiamo <em>a priori<\/em> assegnare nessun confine.<\/p>\n\n\n\n<p>Le intelligenze umane, anche se di solito non arrivano a percepirlo, sono spesso &#8220;pneumatizzate&#8221; quando si pongono sinceramente al servizio della verit\u00e0.<\/p>\n\n\n\n<p>In un\u2019opera attribuita un tempo a sant\u2019Ambrogio [339 ca.-397) si trova a questo proposito un\u2019affermazione illuminante (ripetutamente ricordata da san Tommaso d\u2019Aquino [1225 ca.-1274]): <em>&#8220;Quidquid verum a quocumque dicitur, a Sancto dicitur Spiritu&#8221;<\/em>&nbsp; (4).<\/p>\n\n\n\n<p>Come si vede, la risposta al problema se sia o no possibile un dialogo tra il credente e non credente non \u00e8 semplice perch\u00e9 \u00e8 una risposta &#8220;dialettica&#8221;, e sono diversi gli elementi che interagiscono.<\/p>\n\n\n\n<p>Certo, non c\u2019\u00e8 alcuna possibilit\u00e0 di intesa tra la fede e l\u2019incredulit\u00e0, considerate come atteggiamenti mentali e spirituali totalmente estranei e tra loro antitetici. Ma noi dobbiamo sempre cercare di avvalorare (e rendere auspicabilmente feconda di verit\u00e0) l\u2019iniziale conformit\u00e0 a Cristo che si trova in ogni uomo. Senza dire che il non credente pu\u00f2 essere portavoce inconsapevole dello Spirito Santo; sicch\u00e9 <em>a priori<\/em> non possiamo trascurare di ascoltarlo con qualche speranza; e, nel caso pi\u00f9 fortunato, di convenire con lui.<\/p>\n\n\n\n<h4 class=\"wp-block-heading has-text-align-center\"><strong>La questione dell\u2019immigrazione<\/strong><\/h4>\n\n\n\n<p>Sull\u2019immigrazione mi limito a richiamare schematicamente quanto ho avuto occasione di dire lo scorso anno. Alle comunit\u00e0 cristiane proponevo tre persuasioni semplici ed essenziali.<\/p>\n\n\n\n<p><strong>1. <\/strong>Non \u00e8 per s\u00e9 compito della Chiesa e delle singole comunit\u00e0 risolvere i problemi sociali che la storia di volta in volta ci presenta. Noi non dobbiamo perci\u00f2 nutrire nessun complesso di colpa a causa delle emergenze anche imperiose che non ci riesce di affrontare efficacemente.<\/p>\n\n\n\n<p><strong>2.<\/strong> Dovere statutario del popolo di Dio e compito di ogni battezzato \u00e8 di far conoscere Ges\u00f9 di Nazaret, il Figlio di Dio morto per noi e risorto, e il suo necessario messaggio di salvezza. \u00c8 un preciso ordine del Signore e non ammette deroga alcuna. Egli non ci ha detto: &#8220;Predicate il Vangelo a ogni creatura, tranne i musulmani, gli ebrei e il Dalai Lama&#8221;.<\/p>\n\n\n\n<p><strong>3.<\/strong> Allo stesso modo, \u00e8 nostro dovere l\u2019osservanza del comando dell\u2019amore.<\/p>\n\n\n\n<p>Di fronte a un uomo in difficolt\u00e0 &#8211; quale che sia la sua razza, la sua cultura, la sua religione, la legalit\u00e0 della sua presenza &#8211; i discepoli di Ges\u00f9 hanno il dovere di amarlo operosamente e di aiutarlo a misura delle loro concrete possibilit\u00e0.<\/p>\n\n\n\n<p>Tre convincimenti esprimevo anche nei confronti dello Stato italiano.<\/p>\n\n\n\n<p><strong>1.<\/strong> Di fronte al fenomeno dell\u2019immigrazione, lo Stato non pu\u00f2 sottrarsi al dovere di regolamentarlo positivamente con progetti realistici (circa il lavoro, l\u2019abitazione, l\u2019inserimento sociale), che mirino al vero bene sia dei nuovi arrivati sia delle nostre popolazioni.<\/p>\n\n\n\n<p><strong>2.<\/strong> Poich\u00e9 non \u00e8 pensabile che si possano accogliere tutti, \u00e8 ovvio che si imponga una selezione. La responsabilit\u00e0 di scegliere non pu\u00f2 essere che dello Stato italiano, non di altri; e tanto meno si pu\u00f2 consentire che la selezione sia di fatto lasciata al caso o, peggio, alla prepotenza.<\/p>\n\n\n\n<p><strong>3.<\/strong> I criteri di scelta non dovranno essere unicamente economici e previdenziali: criterio determinante dovr\u00e0 essere quello della pi\u00f9 facile integrabilit\u00e0 nel nostro tessuto nazionale o quanto meno di una prevedibile coesistenza non conflittuale. Un &#8220;ecumenismo politico&#8221; (per cos\u00ec dire), astratto e imprevidente, che disattendesse questa elementare regola di buon senso amministrativo, potrebbe preparare anche per il nostro popolo un futuro di lacrime e di sangue.<\/p>\n\n\n\n<p>Ho la presunzione di avere con ci\u00f2 enunciato in termini estremamente chiari delle proposte del tutto ragionevoli (anzi, se si vuole, &#8220;laicamente&#8221; ragionevoli). E moltissimi le hanno intese e apprezzate.<\/p>\n\n\n\n<p>Mi sfugge invece come sia stato possibile muovere a questa posizione da parte di altri accuse come quelle di integralismo, di prevaricazione clericale, di intolleranza, di atteggiamento antievangelico, eccetera. L\u2019ipotesi pi\u00f9 misericordiosa che mi si presenta \u00e8 che da parte dei miei critici, per il brigoso impegno di parlare, non si sia trovato il tempo di leggere ci\u00f2 che io avevo scritto.<\/p>\n\n\n\n<p>Quella dell\u2019immigrazione \u00e8 una questione difficile e complessa, e va affrontata con seriet\u00e0 di informazione e di indagine. Non si tratta perci\u00f2 soltanto di leggere ci\u00f2 che si vuol contestare (che \u00e8 il minimo che si deve fare); bisogna anche &#8211; per dirla col Manzoni [1785-1873] &#8211; <em>&#8220;<\/em>[&#8230;] <em>osservare, ascoltare, paragonare, pensare, prima di parlare<\/em>.<\/p>\n\n\n\n<p><em>&#8220;Ma parlare, &#8211; continua il Manzoni con la sua saggezza al tempo stesso sorridente e impietosa &#8211;<em> questa cosa cos\u00ec sola, \u00e8 talmente pi\u00f9 facile di tutte quell\u2019altre insieme, che anche noi, dico noi uomini in generale, siamo un po\u2019 da compatire&#8221;<\/em> (5).<\/em><\/p>\n\n\n\n<p>Tanto pi\u00f9 quindi mi compiaccio dell\u2019accurato programma di ricerca, di analisi, di discussione, che arricchir\u00e0 le giornate di questo Convegno. Al quale auguro di cuore un lavoro sereno e fruttuoso.<\/p>\n\n\n\n<p class=\"has-text-align-right\">+ <strong>Cardinale Giacomo Biffi<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-right\"><strong>Arcivescovo di Bologna<\/strong><\/p>\n\n\n\n<p>____________________<\/p>\n\n\n\n<p><strong>Note<\/strong><\/p>\n\n\n\n<p><strong>(1)<\/strong> Cfr. Giacomo Biffi, <em>Il dialogo. Riflessione teologica<\/em>, Piemme, Casale Monferrato (Alessandria) 1998.<\/p>\n\n\n\n<p><strong>(2)<\/strong> Cfr. Idem, <em>Sull\u2019immigrazione. Intervento al Seminario della Fondazione &#8220;Migrantes<\/em>, Elledici, Leumann (Torino) 2000.<\/p>\n\n\n\n<p><strong>(3)<\/strong> \u00c8 significativo che il Segretariato per i non credenti concludeva una sua nota del 10 luglio 1970 ammonendo: <em>&#8220;Non si deve fare un <\/em>mito<em> del dialogo, favorendo l\u2019illusione di possedere con esso la capacit\u00e0 di tutto comprendere e di tutto risolvere, addomesticando problemi e prefabbricando adeguate risposte&#8221;<\/em>[Nota <em>Ampliores rationes circa studium atheismi et institutionem ad dialogum cum non credentibus habendum<\/em>, V, 11, in <em>Enchiridion Vaticanum. Documenti ufficiali della Santa Sede<\/em>, vol. III,<em> 1968-1970<\/em>, EDB. Edizioni Dehoniane Bologna, Bologna 1977, pp. 1576-1591 (p. 1591)].<\/p>\n\n\n\n<p><strong>(4)<\/strong> [&#8220;Qualunque verit\u00e0, da chiunque detta, \u00e8 detta dallo Spirito Santo&#8221;] (Ambrosiaster, <em>In primam ad Cor.<\/em> XII, 23).<\/p>\n\n\n\n<p><strong>(5)<\/strong> Alessandro Manzoni, <em>I promessi sposi<\/em>, cap. XXXI.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>intervento del card. Biffi al convegno Multiculturalit\u00e0 e identit\u00e0 oggi<\/p>\n","protected":false},"author":6,"featured_media":26738,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,38],"tags":[2256,1825],"class_list":["post-703","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chiesa","category-immigrazione","tag-dialogo","tag-pastorale","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>I problemi pastorali posti dall&#039;immigrazione - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"I problemi pastorali posti dall&#039;immigrazione. Intervento del card. Giacomo Biffi convegno sul tema Multiculturalit\u00e0 e identit\u00e0 oggi\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/prospettive-teologiche-e-pastorali-in-tema-di-dialogo-e-dimmigrazionei-problemi-pastorali-posti-dallimmigrazione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"I problemi pastorali posti dall&#039;immigrazione - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"I problemi pastorali posti dall&#039;immigrazione. Intervento del card. Giacomo Biffi convegno sul tema Multiculturalit\u00e0 e identit\u00e0 oggi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/prospettive-teologiche-e-pastorali-in-tema-di-dialogo-e-dimmigrazionei-problemi-pastorali-posti-dallimmigrazione\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2005-06-11T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-19T11:58:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/06\/immigrazione.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"285\" \/>\n\t<meta property=\"og:image:height\" content=\"177\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/prospettive-teologiche-e-pastorali-in-tema-di-dialogo-e-dimmigrazionei-problemi-pastorali-posti-dallimmigrazione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/prospettive-teologiche-e-pastorali-in-tema-di-dialogo-e-dimmigrazionei-problemi-pastorali-posti-dallimmigrazione\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"I problemi pastorali posti dall&#8217;immigrazione\",\"datePublished\":\"2005-06-11T22:00:00+00:00\",\"dateModified\":\"2025-02-19T11:58:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/prospettive-teologiche-e-pastorali-in-tema-di-dialogo-e-dimmigrazionei-problemi-pastorali-posti-dallimmigrazione\\\/\"},\"wordCount\":1921,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/prospettive-teologiche-e-pastorali-in-tema-di-dialogo-e-dimmigrazionei-problemi-pastorali-posti-dallimmigrazione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/06\\\/immigrazione.jpg\",\"keywords\":[\"dialogo\",\"pastorale\"],\"articleSection\":[\"Chiesa\",\"Immigrazione\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/prospettive-teologiche-e-pastorali-in-tema-di-dialogo-e-dimmigrazionei-problemi-pastorali-posti-dallimmigrazione\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/prospettive-teologiche-e-pastorali-in-tema-di-dialogo-e-dimmigrazionei-problemi-pastorali-posti-dallimmigrazione\\\/\",\"name\":\"I problemi pastorali posti dall'immigrazione - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/prospettive-teologiche-e-pastorali-in-tema-di-dialogo-e-dimmigrazionei-problemi-pastorali-posti-dallimmigrazione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/prospettive-teologiche-e-pastorali-in-tema-di-dialogo-e-dimmigrazionei-problemi-pastorali-posti-dallimmigrazione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/06\\\/immigrazione.jpg\",\"datePublished\":\"2005-06-11T22:00:00+00:00\",\"dateModified\":\"2025-02-19T11:58:41+00:00\",\"description\":\"I problemi pastorali posti dall'immigrazione. Intervento del card. Giacomo Biffi convegno sul tema Multiculturalit\u00e0 e identit\u00e0 oggi\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/prospettive-teologiche-e-pastorali-in-tema-di-dialogo-e-dimmigrazionei-problemi-pastorali-posti-dallimmigrazione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/prospettive-teologiche-e-pastorali-in-tema-di-dialogo-e-dimmigrazionei-problemi-pastorali-posti-dallimmigrazione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/prospettive-teologiche-e-pastorali-in-tema-di-dialogo-e-dimmigrazionei-problemi-pastorali-posti-dallimmigrazione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/06\\\/immigrazione.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/06\\\/immigrazione.jpg\",\"width\":285,\"height\":177},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/prospettive-teologiche-e-pastorali-in-tema-di-dialogo-e-dimmigrazionei-problemi-pastorali-posti-dallimmigrazione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"I problemi pastorali posti dall&#8217;immigrazione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"I problemi pastorali posti dall'immigrazione - Rassegna Stampa Cattolica","description":"I problemi pastorali posti dall'immigrazione. Intervento del card. Giacomo Biffi convegno sul tema Multiculturalit\u00e0 e identit\u00e0 oggi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/prospettive-teologiche-e-pastorali-in-tema-di-dialogo-e-dimmigrazionei-problemi-pastorali-posti-dallimmigrazione\/","og_locale":"it_IT","og_type":"article","og_title":"I problemi pastorali posti dall'immigrazione - Rassegna Stampa Cattolica","og_description":"I problemi pastorali posti dall'immigrazione. Intervento del card. Giacomo Biffi convegno sul tema Multiculturalit\u00e0 e identit\u00e0 oggi","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/prospettive-teologiche-e-pastorali-in-tema-di-dialogo-e-dimmigrazionei-problemi-pastorali-posti-dallimmigrazione\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2005-06-11T22:00:00+00:00","article_modified_time":"2025-02-19T11:58:41+00:00","og_image":[{"width":285,"height":177,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/06\/immigrazione.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"11 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/prospettive-teologiche-e-pastorali-in-tema-di-dialogo-e-dimmigrazionei-problemi-pastorali-posti-dallimmigrazione\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/prospettive-teologiche-e-pastorali-in-tema-di-dialogo-e-dimmigrazionei-problemi-pastorali-posti-dallimmigrazione\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"I problemi pastorali posti dall&#8217;immigrazione","datePublished":"2005-06-11T22:00:00+00:00","dateModified":"2025-02-19T11:58:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/prospettive-teologiche-e-pastorali-in-tema-di-dialogo-e-dimmigrazionei-problemi-pastorali-posti-dallimmigrazione\/"},"wordCount":1921,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/prospettive-teologiche-e-pastorali-in-tema-di-dialogo-e-dimmigrazionei-problemi-pastorali-posti-dallimmigrazione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/06\/immigrazione.jpg","keywords":["dialogo","pastorale"],"articleSection":["Chiesa","Immigrazione"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/prospettive-teologiche-e-pastorali-in-tema-di-dialogo-e-dimmigrazionei-problemi-pastorali-posti-dallimmigrazione\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/prospettive-teologiche-e-pastorali-in-tema-di-dialogo-e-dimmigrazionei-problemi-pastorali-posti-dallimmigrazione\/","name":"I problemi pastorali posti dall'immigrazione - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/prospettive-teologiche-e-pastorali-in-tema-di-dialogo-e-dimmigrazionei-problemi-pastorali-posti-dallimmigrazione\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/prospettive-teologiche-e-pastorali-in-tema-di-dialogo-e-dimmigrazionei-problemi-pastorali-posti-dallimmigrazione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/06\/immigrazione.jpg","datePublished":"2005-06-11T22:00:00+00:00","dateModified":"2025-02-19T11:58:41+00:00","description":"I problemi pastorali posti dall'immigrazione. Intervento del card. Giacomo Biffi convegno sul tema Multiculturalit\u00e0 e identit\u00e0 oggi","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/prospettive-teologiche-e-pastorali-in-tema-di-dialogo-e-dimmigrazionei-problemi-pastorali-posti-dallimmigrazione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/prospettive-teologiche-e-pastorali-in-tema-di-dialogo-e-dimmigrazionei-problemi-pastorali-posti-dallimmigrazione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/prospettive-teologiche-e-pastorali-in-tema-di-dialogo-e-dimmigrazionei-problemi-pastorali-posti-dallimmigrazione\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/06\/immigrazione.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/06\/immigrazione.jpg","width":285,"height":177},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/prospettive-teologiche-e-pastorali-in-tema-di-dialogo-e-dimmigrazionei-problemi-pastorali-posti-dallimmigrazione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"I problemi pastorali posti dall&#8217;immigrazione"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/703","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=703"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/703\/revisions"}],"predecessor-version":[{"id":62169,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/703\/revisions\/62169"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/26738"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=703"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=703"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}