{"id":6588,"date":"2014-04-03T10:41:42","date_gmt":"2014-04-03T08:41:42","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=6588"},"modified":"2015-06-12T13:27:02","modified_gmt":"2015-06-12T11:27:02","slug":"il-codice-di-deontologia-medica-non-cediamo-al-disamore","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-codice-di-deontologia-medica-non-cediamo-al-disamore\/","title":{"rendered":"Il codice di deontologia medica: non cediamo al disamore"},"content":{"rendered":"<h2 align=\"center\"><span style=\"color: #2c2b2b; font-family: arial, sans-serif; font-size: 12px; line-height: 18px;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/images.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-6674 size-full\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/images.jpg\" alt=\"images\" width=\"240\" height=\"180\" \/><\/a>Avvenire.it<\/strong> 3 aprile 2014<\/span><\/h2>\n<p align=\"center\">di <b>Carlo Bellieni<\/b><\/p>\n<p style=\"text-align: justify;\">Il Codice di deontologia medica \u00e8 sul punto di cambiare: la nuova versione ha aspetti positivi e punti nevralgici da migliorare, ma c\u2019\u00e8 una domanda che lo mette sotto giudizio: perch\u00e9 per secoli \u00e8 bastato un codice ippocratico di dieci righe e ora serve un documento di 80 articoli?<\/p>\n<p style=\"text-align: justify;\">Gi\u00e0: l\u2019attuale Codice \u00e8 un lungo insieme di mansioni, impegni e clausole con tante pagine e articoli a ribadire quello che gi\u00e0 la legge o il buon senso prescrivono: infatti c\u2019\u00e8 davvero bisogno di sancire che \u00abil medico fonda l\u2019esercizio delle proprie competenze tecnico\u00adprofessionali sui principi di efficacia e appropriatezza\u00bb, o che \u00abpersegue l\u2019uso ottimale delle risorse pubbliche e private\u00bb, come se questo non fosse un presupposto intrinseco e ovvio?<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Ma tanti dettagli normativi servono a far fronte a una perdita di unit\u00e0, cio\u00e8 di un\u2019etica che si condensava in poche parole riconosciute e accettate da tutti: onorabilit\u00e0, rispetto della vita, discrezione, sapienza. Scompare anche la parola \u00abcoscienza\u00bb (articolo 22) quando si parla di far valere le proprie convinzioni, lasciando solo il riferimento ai \u00abpropri convincimenti etici\u00bb, come se la coscienza non ne fosse una necessaria integrazione. Ora per portare il flusso dell\u2019attivit\u00e0 medica negli stessi argini occorrono lunghi discorsi, e si cerca di far fronte con tante regole a un unico disamore.<\/p>\n<p style=\"text-align: justify;\">Gi\u00e0, il disamore: la deontologia medica dovrebbe risolvere, in primis, il paradosso di una professione che si \u00e8 burocratizzata, ma che al tempo stesso tratta intimamente e drammaticamente con la vita e la sofferenza: cosa disorientante e ambivalente per i medici e i malati. E che provoca, appunto, disamore. Urge formare e supportare un medico che unisca \u2013 non per contratto, ma per passione \u2013 il saper curare col saper comunicare (anzitutto saper comunicare se stessi per dare fiducia). Ma c\u2019\u00e8 traccia di questo nel nuovo Codice deontologico medico? Si prova a invogliare alla comunicazione col paziente, ma il Codice sembra annoverarla minuziosamente nell\u2019orario di lavoro (articolo 20) lasciandola in un quadro di freddezza e distacco.<\/p>\n<p style=\"text-align: justify;\">D\u2019altronde questo \u00e8 quasi ovvio in un Occidente dove gli ospedali diventano aziende, i pazienti si trasformano in \u00abutenza\u00bb, i medici sono \u00abfornitori di servizio\u00bb o \u00abdirigenti\u00bb\u2019. Ma \u00e8 di questo che c\u2019\u00e8 bisogno? Di medici-capitreno (con tutto il rispetto per i capitreno) che ti portino laddove per contratto stabiliscono di portarti? Qualche volta si pensa che gi\u00e0 questo sarebbe tanto, ma equivarrebbe ad abbassare il tiro. Dalla deontologia medica ci aspetteremmo una riaffermazione di poche cose, ma chiare: che<\/p>\n<p style=\"text-align: justify;\">Curare vuol dire \u2018avere a cuore\u2019, che guarire significa \u2018fare schermo al debole\u2019, che la salute non \u00e8 un utopico completo benessere psicofisico, ma sentirsi a proprio agio anche nel caso la malattia non sia guaribile e la disabilit\u00e0 non si risolva.<\/p>\n<p style=\"text-align: justify;\">Oggi davvero pochi sono quelli che insegnano tutto questo. Troppo facile, come fanno molti, \u00e8 identificare il medico con \u2018colui che fa passare il male\u2019, e se non ce la fa ha fallito o delega ad altri il cammino accanto al paziente che i medici di un tempo si ostinavano con coerenza e vigore a chiamare \u2018cura\u2019.<\/p>\n<p style=\"text-align: justify;\">L\u2019antico giuramento di Ippocrate riassumeva l\u2019arte medica in queste parole: \u00abCon innocenza e purezza io custodir\u00f2 la mia vita e la mia arte\u00bb, con la promessa di rispettare vita e salute, di non rivelare segreti dei pazienti e di regolare \u00abil tenore di vita per il bene dei malati secondo le mie forze e il mio giudizio\u00bb. Queste poche parole sono bastate per secoli. I tempi cambiano, e le parti \u2018non politicamente corrette\u2019 del giuramento sono sparite, si sono moltiplicati i precetti e gli articoli. Come avviene quando si perde la semplicit\u00e0 di un\u2019arte, e si resta obbligati a sostituire smarriti la passione con le regole.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avvenire.it 3 aprile 2014 di Carlo Bellieni Il Codice di deontologia medica \u00e8 sul punto di cambiare: la nuova versione ha aspetti positivi e punti nevralgici da migliorare, ma c\u2019\u00e8 una domanda che lo mette sotto giudizio: perch\u00e9 per secoli \u00e8 bastato un codice ippocratico di dieci righe e ora serve un documento di 80 &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-codice-di-deontologia-medica-non-cediamo-al-disamore\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":6674,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[2388,253],"class_list":["post-6588","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bioetica","tag-bioetica","tag-deontologia-medica","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il codice di deontologia medica: non cediamo al disamore - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-codice-di-deontologia-medica-non-cediamo-al-disamore\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il codice di deontologia medica: non cediamo al disamore - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-codice-di-deontologia-medica-non-cediamo-al-disamore\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2014-04-03T08:41:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-06-12T11:27:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/images.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"240\" \/>\n\t<meta property=\"og:image:height\" content=\"180\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-codice-di-deontologia-medica-non-cediamo-al-disamore\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-codice-di-deontologia-medica-non-cediamo-al-disamore\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Il codice di deontologia medica: non cediamo al disamore\",\"datePublished\":\"2014-04-03T08:41:42+00:00\",\"dateModified\":\"2015-06-12T11:27:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-codice-di-deontologia-medica-non-cediamo-al-disamore\\\/\"},\"wordCount\":626,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-codice-di-deontologia-medica-non-cediamo-al-disamore\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/images.jpg\",\"keywords\":[\"Bioetica\",\"deontologia medica\"],\"articleSection\":[\"Bioetica\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-codice-di-deontologia-medica-non-cediamo-al-disamore\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-codice-di-deontologia-medica-non-cediamo-al-disamore\\\/\",\"name\":\"Il codice di deontologia medica: non cediamo al disamore - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-codice-di-deontologia-medica-non-cediamo-al-disamore\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-codice-di-deontologia-medica-non-cediamo-al-disamore\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/images.jpg\",\"datePublished\":\"2014-04-03T08:41:42+00:00\",\"dateModified\":\"2015-06-12T11:27:02+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-codice-di-deontologia-medica-non-cediamo-al-disamore\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-codice-di-deontologia-medica-non-cediamo-al-disamore\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-codice-di-deontologia-medica-non-cediamo-al-disamore\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/images.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/images.jpg\",\"width\":240,\"height\":180},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-codice-di-deontologia-medica-non-cediamo-al-disamore\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il codice di deontologia medica: non cediamo al disamore\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il codice di deontologia medica: non cediamo al disamore - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-codice-di-deontologia-medica-non-cediamo-al-disamore\/","og_locale":"it_IT","og_type":"article","og_title":"Il codice di deontologia medica: non cediamo al disamore - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-codice-di-deontologia-medica-non-cediamo-al-disamore\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2014-04-03T08:41:42+00:00","article_modified_time":"2015-06-12T11:27:02+00:00","og_image":[{"width":240,"height":180,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/images.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-codice-di-deontologia-medica-non-cediamo-al-disamore\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-codice-di-deontologia-medica-non-cediamo-al-disamore\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Il codice di deontologia medica: non cediamo al disamore","datePublished":"2014-04-03T08:41:42+00:00","dateModified":"2015-06-12T11:27:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-codice-di-deontologia-medica-non-cediamo-al-disamore\/"},"wordCount":626,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-codice-di-deontologia-medica-non-cediamo-al-disamore\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/images.jpg","keywords":["Bioetica","deontologia medica"],"articleSection":["Bioetica"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-codice-di-deontologia-medica-non-cediamo-al-disamore\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-codice-di-deontologia-medica-non-cediamo-al-disamore\/","name":"Il codice di deontologia medica: non cediamo al disamore - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-codice-di-deontologia-medica-non-cediamo-al-disamore\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-codice-di-deontologia-medica-non-cediamo-al-disamore\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/images.jpg","datePublished":"2014-04-03T08:41:42+00:00","dateModified":"2015-06-12T11:27:02+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-codice-di-deontologia-medica-non-cediamo-al-disamore\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-codice-di-deontologia-medica-non-cediamo-al-disamore\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-codice-di-deontologia-medica-non-cediamo-al-disamore\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/images.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/images.jpg","width":240,"height":180},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-codice-di-deontologia-medica-non-cediamo-al-disamore\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Il codice di deontologia medica: non cediamo al disamore"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/6588","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=6588"}],"version-history":[{"count":3,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/6588\/revisions"}],"predecessor-version":[{"id":26208,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/6588\/revisions\/26208"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/6674"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=6588"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=6588"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=6588"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}