{"id":6544,"date":"2014-03-20T10:18:19","date_gmt":"2014-03-20T09:18:19","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=6544"},"modified":"2015-06-12T13:54:09","modified_gmt":"2015-06-12T11:54:09","slug":"6544","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/6544\/","title":{"rendered":"I principi non negoziabili: perch\u00e8 bisogna parlarne ancora"},"content":{"rendered":"<p align=\"center\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/03\/principi1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-6695\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/03\/principi1.jpg\" alt=\"principi\" width=\"230\" height=\"168\" \/><\/a>Osservatorio Internazionale Cardinale Van Thuan &#8211; <b>Newsletter<\/b> n.486 del 18 marzo 2014<\/p>\n<p style=\"text-align: center;\"><strong>Stefano Fontana<\/strong><\/p>\n<p style=\"text-align: center;\">(<em><strong>in english too<\/strong><\/em>)<\/p>\n<p>&nbsp;<\/p>\n<p><!--more--><\/p>\n<p><b><\/b><i style=\"font-size: 12px;\">Parrocchia San Pietro Apostolo<\/i><\/p>\n<p><i style=\"font-size: 12px;\">Verona 11 marzo 2014<\/i><\/p>\n<p><b>Cosa sono<\/b><\/p>\n<p style=\"text-align: justify;\">Spesso si parla di \u201cvalori\u201d non negoziabili anzich\u00e9 di \u201cprincipi\u201d non negoziabili, ma si tratta di un errore di impostazione.<\/p>\n<p style=\"text-align: justify;\">Principio vuol dire fondamento e criterio. Il principio \u00e8 l\u2019elemento che regge e illumina un certo ambito. Il principio tiene insieme le cose e le indirizza, le orienta al loro fine. Ne consegue che il principio non pu\u00f2 essere un elemento della serie, nemmeno il primo. Essere un principio non vuol dire stare cronologicamente all\u2019inizio, come il primo gennaio sta al principio dell\u2019anno. Il principio ha un primato: viene prima, ove l\u2019avverbio prima non \u00e8 solo temporale.<\/p>\n<p style=\"text-align: justify;\">Cos\u2019\u00e8, invece, un valore? Una cosa ha valore quando \u00e8 apprezzabile. Ora, la vita o la famiglia o la libert\u00e0 di educazione \u2013 per citare qui i principali tra i principi non negoziabili \u2013 sono certamente dei valori, sono degni di apprezzamento e di promozione. Come tanti altri aspetti della vita umana e sociale, del resto. Come l\u2019arte, la solidariet\u00e0, la conoscenza, la salute, la buona cucina.<\/p>\n<p style=\"text-align: justify;\">Come si vede essere un valore non vuol dire anche essere un principio. La casa in propriet\u00e0 \u00e8 un valore ma non \u00e8 un principio ordinatore della vita sociale. Ci\u00f2 non toglie che un valore possa essere anche un principio. La vita umana, per esempio, \u00e8 un valore ma \u00e8 anche un principio, in quanto \u00e8 in grado di illuminare con la sua luce l\u2019intera vita sociale e politica. Se si offusca il rispetto della vita non si offusca solo un valore, ma anche altri valori ed altri aspetti della vita che quel principio illumina.<\/p>\n<p style=\"text-align: justify;\">Il bene comune non \u00e8 un insieme di valori aventi tutti lo stesso peso, ma \u00e8 un insieme ordinato. Per essere ordinato vuol dire che qualche valore ha una funzione arichitettonica, ossia indica i fondamenti del bene comune e, cos\u00ec facendo, illumina di senso anche tutti gli altri. Senza un criterio non c\u2019\u00e8 bene comune ma somma di beni particolari e questo criterio ci proviene dai principi non negoziabili.<\/p>\n<p style=\"text-align: justify;\">Abbiamo allora stabilito cosa voglia dire la parola principio. Vediamo adesso cosa voglia dire l\u2019espressione \u201cnon negoziabile\u201d. Se si tratta di principi, ossia se sono qualcosa che viene prima e che fonda, essi non dipendono da quanto viene dopo ed hanno valore di assolutezza, non sono disponibili. Non sono negoziabili perch\u00e9 assoluti e sono assoluti perch\u00e9 sono dei principi. Se fossero relativi non potrebbero essere principi, non starebbero prima, sarebbero uno dei tanti elementi della serie.<\/p>\n<p style=\"text-align: justify;\">O si nega l\u2019esistenza di principi, oppure se si ammette la loro esistenza essi devono essere assoluti ossia non negoziabili. Tale valore di assolutezza risulta anche dall\u2019esperienza della loro mancanza. Quando manca il riferimento ad essi una societ\u00e0 perde la bussola e subisce una involuzione. Questo vuol dire che non sono essi ad essere relativi alla societ\u00e0 ma \u00e8 la societ\u00e0 ad essere relativa ad essi. Ecco quindi il motivo ultimo del perch\u00e9 non possono essere negoziabili: perch\u00e9 non sono stati negoziati.<\/p>\n<p style=\"text-align: justify;\">Se una cosa viene negoziata, allora vuol dire che \u00e8 negoziabile e pu\u00f2 in seguito essere rinegoziata. Ma un principio non pu\u00f2 essere rinegoziato perch\u00e9 non era mai stato negoziato prima, in quanto non negoziabile. Altrimenti che principio sarebbe? In una societ\u00e0 senza principi non negoziabili tutto \u00e8 negoziabile, compresa la negoziabilit\u00e0.<\/p>\n<p style=\"text-align: justify;\">I principi non negoziabili, quindi, sono tali in quanto precedono la societ\u00e0. E da dove derivano? Essi sono non negoziabili perch\u00e9 radicati nella natura umana. Proprio perch\u00e9 fanno tutt\u2019uno con la natura umana, non possono essere presi a certe dosi, un po\u2019 s\u00ec e un po\u2019 no: o si prendono o si lasciano. Questa \u00e8 vita umana o non lo \u00e8. Questa \u00e8 famiglia o non lo \u00e8. I principi non negoziabili demarcano l\u2019umano dal non umano e quindi sono il criterio per una convivenza umana.<\/p>\n<p style=\"text-align: justify;\">Da un altro punto di vista, per\u00f2, essi non sono propriamente dei principi primi, perch\u00e9 non sono capaci di fondarsi da soli. Come abbiamo visto, essi si basano sulla natura umana, ma la natura umana su cosa si fonda? I principi non negoziabili esprimono un ordine che rimanda al Creatore.<\/p>\n<p style=\"text-align: justify;\">Se non esistono principi non negoziabili la ragione non trova un ordine che rinvia al Creatore. Essa non incontra pi\u00f9 la fede e la fede non incontra pi\u00f9 la ragione. Ci\u00f2 significa l\u2019espulsione della religione dall\u2019ambito pubblico. La vita sociale e politica sarebbe solo il regno del relativo. Cosa ci starebbe a fare la fede in un simile contesto? Dio si sarebbe scomodato a parlarci per aggiungere la sua opinione alle nostre?<\/p>\n<p style=\"text-align: justify;\"><b>Quali sono<\/b><\/p>\n<p style=\"text-align: justify;\">Precisare quali sono i principi non negoziabili \u00e8 di fondamentale importanza. I testi fondamentali del magistero sono tre.<\/p>\n<p style=\"text-align: justify;\">Al paragrafo 4 della <i>Nota dottrinale su alcune questioni riguardanti l\u2019impegno e il comportamento dei cattolici nella vita politica\u00a0<\/i>Congregazione per la Dottrina della Fede (24 novembre 2002) sono indicati i seguenti principi non negoziabili: vita, famiglia, libert\u00e0 di educazione, tutela sociale dei minori, libert\u00e0 religiosa, economia a servizio della persona, pace.<\/p>\n<p style=\"text-align: justify;\">Nell\u2019Esortazione apostolica post sinodale <i>Sacramentum caritatis <\/i>sull\u2019Eucaristia del 22 febbraio 2007 (par. 83), Benedetto XVI cita vita, famiglia e libert\u00e0 di educazione a cui aggiunge il bene comune.<\/p>\n<p style=\"text-align: justify;\">Nel Discorso ai Partecipanti al Convegno del Partito Popolare Europeo del 30 marzo 2006, Benedetto XVI elenca vita, famiglia e libert\u00e0 di educazione.<\/p>\n<p style=\"text-align: justify;\">Entriamo nel merito di questi elenchi. La prima cosa da osservare \u00e8 che tre principi sono sempre presenti e sempre collocati all\u2019inizio di ogni elenco, in posizione quindi eminente; vita, famiglia e libert\u00e0 di educazione.<\/p>\n<p style=\"text-align: justify;\">Questo indica che quei tre principi hanno un carattere fondativo: nessun altro dei principi successivi pu\u00f2 essere n\u00e9 adeguatamente compreso n\u00e9 efficacemente perseguito senza di essi. E\u2019 possibile, per esempio, garantire la tutela sociale dei minori se ai minori si impedisce di nascere? E\u2019 possibile farlo impedendo loro di godere di una famiglia unita e stabile? E\u2019 possibile ottenere questo risultato esautorando la famiglia del suo diritto-dovere di educare i figli? Se rimane sana la famiglia, alla lunga anche le varie forme di disagio sociale dei minori trovano soluzione.<\/p>\n<p style=\"text-align: justify;\">Secondariamente indica che quei tre principi ci pongono davanti a degli assoluti morali, ossia ad azioni che non si devono mai fare in nessuna circostanza. Per gli altri principi elencati nella Nota del 2002 non \u00e8 cos\u00ec. Per esempio, essa annoverava tra i principi non negoziabili anche una \u201ceconomia a servizio della persona\u201d. Non c\u2019\u00e8 dubbio che la lotta alla disoccupazione sia un elemento importante del bene comune. Tuttavia, per perseguire la piena occupazione le strade possono essere diverse.<\/p>\n<p style=\"text-align: justify;\">Nel caso, invece, dei tre principi di cui ci stiamo occupando, non ci sono strade diverse. Anzi, in quei casi di strade non ce ne sono proprio. La differenza dipende dal fatto che la frase \u201cnon uccidere\u201d e la frase \u201csviluppa l\u2019occupazione\u201d sono molto diverse quanto a cogenza morale. La prima impone un assoluto morale negativo, qualcosa quindi che non si deve mai fare, la seconda propone un precetto morale positivo, indica cosa si deve fare.<\/p>\n<p style=\"text-align: justify;\">Ora, mentre il male assoluto non si deve mai fare, il bene pu\u00f2 essere fatto in molti modi. La coscienza, assieme alla virt\u00f9 della prudenza, non viene esercitata nel caso dei precetti morali negativi &#8211; sacrificare due embrioni umani invece che tre non \u00e8 un male morale minore; abortire una volta anzich\u00e9 due non \u00e8 un male morale minore &#8211; mentre pu\u00f2 esercitarsi nei casi di quelli positivi.<\/p>\n<p style=\"text-align: justify;\">Molti accettano queste mie considerazioni per i primi due principi \u2013 la vita e la famiglia \u2013 ma non l\u2019accettano per il terzo: la libert\u00e0 di educazione. La libert\u00e0 di educazione \u00e8 fondamentale in quanto pone o toglie la possibilit\u00e0 che l\u2019anima del bambino sia iniziata alla verit\u00e0 piuttosto che all\u2019errore, al bene piuttosto che al male, a Dio piuttosto che al Principe delle tenebre. Il problema \u00e8 quello della educazione e del suo ruolo decisivo nella nostra vita. Se \u00e8 possibile educare allora tutto \u00e8 rimediabile, ma se alle famiglie e alla Chiesa viene tolta la possibilit\u00e0 di educare \u00e8 la fine per tutti e per tutto.<\/p>\n<p style=\"text-align: justify;\">C\u2019\u00e8 solo un altro principio tra quelli elencati nella Nota del 2002 che potrebbe contendere il \u201cprimato\u201d a questi tre: il principio della libert\u00e0 di religione. Esso nasce dal dovere di cercare la verit\u00e0 fino alla radice, ossia fino a misurarsi con Dio. Per\u00f2 il diritto alla libert\u00e0 religiosa non \u00e8 assoluto, in quanto vale solo dentro il rispetto della legge di natura, il cui rispetto \u00e8 fondamentale per il bene comune. \u00a0Professare e praticare una religione che contenga elementi contrari alla legge naturale non pu\u00f2 essere un diritto n\u00e9 avrebbe titolo morale per un riconoscimento pubblico.<\/p>\n<p style=\"text-align: justify;\">Da queste considerazione si deriva che tra i primi tre principi elencati e gli altri c\u2019\u00e8 una differenza. Se mancano i primi tre, tutto l\u2019elenco viene meno, mentre se ci fossero solo i primi tre, ci sarebbe gi\u00e0 il nucleo portante di tutto il discorso. Ed infatti capita spesso, come abbiamo visto, che il magistero elenchi solo i primi tre, ma non capita mai che ne elenchi altri senza questi tre.<\/p>\n<p style=\"text-align: justify;\"><b>Equivoci sui principi non negoziabili<\/b><\/p>\n<p style=\"text-align: justify;\">Molti cattolici criticano o perfino irridono i principi non negoziabili, considerandoli un impedimento al dialogo. Altri fanno notare che il dialogo per essere significativo ha bisogno di limiti, dati appunto da questi principi. Ne nascono molti equivoci.<\/p>\n<p style=\"text-align: justify;\">Su un primo equivoco, ossia intenderli come valori e non come principi, ho gi\u00e0 detto. Esso comporta per esempio il classico errore di valutazione: se un partito propone l\u2019aborto e lotte efficaci alla povert\u00e0 mentre un altro partito \u00e8 contro l\u2019aborto ma ha misure meno efficaci contro la povert\u00e0 io posso decidere liberamente per ambedue perch\u00e9 si tratta solo di valori.<\/p>\n<p style=\"text-align: justify;\">Un altro degli equivoci pi\u00f9 frequenti \u00e8 pensare che i principi non negoziabili comporterebbero la rinuncia da parte dei cattolici ad un pensiero politico completo in luogo della richiesta di garanzie su singoli temi specifici. I principi non negoziabili non sono singoli temi ma principi e quindi riferirsi ad essi comporta sempre l\u2019accettazione di una prospettiva, che si ripercuote inevitabilmente anche su altri punti. In certe fasi storiche si \u00e8 costretti ad attestarsi maggiormente sui singoli principi, perch\u00e9 le minacce sono incombenti. Ma questo non vuol dire che se ne dimentichi il valore illuminante per l\u2019intero programma sociale e politico.<\/p>\n<p style=\"text-align: justify;\">Un terzo equivoco consiste nel considerare i principi non negoziabili come contrari all\u2019essenza della democrazia. Questa sarebbe il sistema che ha al centro la persona umana, ma siccome la persona \u00e8 continuamente da approfondire nel dialogo e non si arriver\u00e0 mai al punto finale, serve il confronto politico e serve anche affidarsi in conclusione alla legge della maggioranza.<\/p>\n<p style=\"text-align: justify;\">Che una realt\u00e0 debba essere continuamente approfondita secondo il principio di coerenza \u00e8 vero, ma questo non vuol dire che non si possa conoscere niente di certo e definitivo su di essa, talmente certo e definitivo da doverlo porre al riparo anche dalla legge della maggioranza. I principi non negoziabili non pretendono di dirci tutto su una societ\u00e0 umana ma di dirci gli aspetti senza dei quali non \u00e8 societ\u00e0 umana. Se la panoramica completa dell\u2019uomo non ci \u00e8 data \u2013 almeno quaggi\u00f9 -, questi ci sono dati in tutta la loro chiarezza e cogenza.<\/p>\n<p style=\"text-align: justify;\">Un quarto equivoco riguarda i mezzi e i fini. Si dice che la politica riguarda i mezzi e non i fini. Infatti, si sostiene, esistono diversi partiti politici perch\u00e9 i cittadini possano prudentemente adoperare l\u2019uno o l\u2019altro partito per realizzare i loro fini. Questo giustificherebbe la presenza dei cattolici in tutti i partiti. Cittadini che hanno fini uguali si dividono poi nella scelta del partito che, come un mezzo, pu\u00f2 realizzare meglio i fini. Di solito si tira in campo la virt\u00f9 della prudenza con la quale la coscienza morale cala nella situazione concreta i principi morali generali, insomma sceglie i mezzi pi\u00f9 idonei per realizzare i fini.<\/p>\n<p style=\"text-align: justify;\">La prima cosa da dire \u00e8 che la politica riguarda anche i fini e non solo i mezzi. La seconda cosa da dire \u00e8 che i mezzi sono ordinati al fine, quindi non possono contraddirlo. La prudenza applicata ai mezzi cattivi diventa imprudenza. Se per conseguire il fine della difesa della vita io mi affido al mezzo di un partito che promuove l\u2019aborto non ho esercitato la prudenza, ma sono stato imprudente. La scelta del partito ha a che fare con i fini, dato che la politica riguarda anche i fini, ed ha poi a che fare con la scelta dei mezzi, che devono per\u00f2 essere buoni, ossia congrui rispetto al fine. Questo discorso sta alla base del fatto che se si accettano i principi non negoziabili non si pu\u00f2 aderire indifferentemente a tutti i partiti, perch\u00e9 alcuni di essi sono connessi con altri fini contrari e altri di essi sono dei mezzi inadatti al fine.<\/p>\n<p style=\"text-align: justify;\">Un ultimo frequente equivoco \u00e8 di ritenere che ammettere i principi non negoziabili significhi negare la laicit\u00e0 della politica, facendola dipendere da principi confessionali. I principi non negoziabili sono dei principi ragionevoli che possono essere riconosciuti da tutti gli uomini. La stranezza non sta nel fatto che siano riconosciuti, ma semmai nel fatto che siano negati. Quindi appartengono al campo della laicit\u00e0, se per laicit\u00e0 intendiamo l\u2019ambito della ralgione pubblica, la quale stabilisce i principi e i fini del vivere comunitario. Se, invece, per laicit\u00e0 si intende l\u2019assenza di qualsiasi verit\u00e0 assoluta, anche di tipo razionale, allora non si tratta di vera laicit\u00e0, ma di una nuova religione dell\u2019individuo assoluto e dei suoi desideri.<\/p>\n<p style=\"text-align: justify;\">Dipendendo dai principi non negoziabili, quindi, la politica non dipende da principi confessionali, ma semplicemente dal \u201csenso\u201d di se stessa.<\/p>\n<p style=\"text-align: justify;\"><b>Principi non negoziabili ed obiezione di coscienza<\/b><\/p>\n<p style=\"text-align: justify;\">Poich\u00e9 la politica assume sempre di pi\u00f9 l\u2019arroganza di contrastare i principi non negoziabili l\u2019obiezione di coscienza oggi \u00e8 sempre di pi\u00f9 un problema politico e non solo morale.<\/p>\n<p style=\"text-align: justify;\">Fanno obiezione di coscienza i farmacisti, che non vogliono vendere la pillola del giorno dopo in quanto ha effetti abortivi, \u00a0le ostetriche e i medici che non vogliono collaborare nel praticare aborti, anche se la legge lo permette, gli impiegati comunali, che non vogliono registrare le coppie omosessuali negli appositi registri pubblici o che non vogliono celebrare pubblicamente matrimoni che tali non sono, molti insegnanti che non vogliono piegarsi all\u2019ideologia del gender,\u00a0 i genitori, quando decidono di non far partecipare i propri figli a distruttivi corsi scolastici di educazione sessuale, i lavoratori che non rinunciano al loro diritto di esibire un segno religioso quando sono in servizio, mentre l\u2019amministrazione da cui dipendono lo vieta, le infermiere, quando reagiscono al divieto dell\u2019amministrazione sanitaria di confortare religiosamente i morenti, invitano all\u2019obiezione di coscienza in Vescovi americani contro la riforma sanitaria di Obama, fanno obiezione di coscienza gli operatori del consultori della Toscana dove adesso dovranno anche somministrare la pillola abortiva. \u00a0Ci sono persone che perdono il posto di lavoro per la fedelt\u00e0 ai principi non negoziabili.<\/p>\n<p style=\"text-align: justify;\">Perch\u00e9 avviene questo? Perch\u00e9 ci sono dei principi non negoziabili, davanti ai quali la nostra coscienza, come quella di Socrate o di Antigone, trova la forza di dire un no assoluto. Ora, mi chiedo, perch\u00e9 questo non dovrebbe valere in politica? Perch\u00e9 in politica si dovrebbe comunque arrivare ad un compromesso? E a questo compromesso in politica si dovrebbe anche dimostrare rispetto e deferenza, lodando la persona che \u00e8 scesa a mediazione come un esempio di saggezza, prudenza e perfino coraggio?<\/p>\n<p style=\"text-align: justify;\">La cosa \u00e8 ancora pi\u00f9 evidente se la si esamina dal punto di vista della testimonianza. Quante volte si dice che il cattolico \u00e8 in politica per dare una testimonianza. Per\u00f2, se non esiste la possibilit\u00e0 del sacrificio, se non c\u2019\u00e8 mai nessun \u201cno\u201d da dire a costo di perdere qualcosa, la testimonianza come si misura? E\u2019 facile impegnarsi in politica applauditi e ben retribuiti. E non \u00e8 sufficiente non commettere illeciti o immoralit\u00e0. Bisogna anche essere disposti a pagare davanti a dei principi che la nostra coscienza ritiene non negoziabili. A Socrate il suo amico Critone aveva proposto la fuga, ma Socrate ha risposto di no.<\/p>\n<p style=\"text-align: justify;\">Politicamente parlando, il principale sacrificio per un uomo politico sono le dimissioni. Bisogna riconoscere che sono rarissimi i politici che pur di non dare il loro assenso ad una legge contraria alla legge morale naturale si siano dimessi dal loro incarico. Nella memoria collettiva \u00e8 pure ancora presente l\u2019autosospensione temporanea del re del Belgio Baldovino, che non volle apporre la propria firma sotto la legge sull\u2019aborto, in ci\u00f2 non seguito nei giorni scorsi da suo nipote Filippo a proposito della legge sull\u2019eutanasia dei bambini.<\/p>\n<p style=\"text-align: justify;\">Il vero uomo politico \u00e8 colui che sa anche rinunciare alla politica. Si \u00e8 uomini prima e dopo la politica. E\u2019 questo che d\u00e0 senso alla politica stessa. Se tengo aperto il campo della mia umanit\u00e0 tramite una fedelt\u00e0 alla retta coscienza che giudica la stessa politica, faccio respirare anche la politica. Molti dicono: non si deve abbandonare il campo (per esempio con le dimissioni) perch\u00e9 in questo modo lo si lascia agli altri e si recede dalla doverosa lotta politica. Ma la politica la si pu\u00f2 fare in tanti modi e in tanti luoghi. Senza contare che, anche un eventuale atto di dimissioni per motivi di coscienza sarebbe gi\u00e0 un atto politico, denso di possibili conseguenze politiche imprevedibili in quel momento. Del resto, un vero leader politico \u00e8 uno che sa dire anche di no. Lo sa dire agli altri perch\u00e9 lo sa dire a se stesso. Chi non sa dirlo a se stesso non ha diritto di dirlo agli altri.<\/p>\n<p style=\"text-align: justify;\">E\u2019 evidente che l\u2019obiezione di coscienza in politica \u00e8 possibile se in politica si danno principi non negoziabili. Si cerca in tutti i modi di eliminare la libert\u00e0 di coscienza per eliminare i principi non negoziabili e si cerca di eliminare i principi non negoziabili per eliminare la libert\u00e0 di coscienza. L\u2019esistenza dei principi non negoziabili rende libera la nostra coscienza.<\/p>\n<p style=\"text-align: justify;\">Quando un uomo politico fa obiezione di coscienza in quanto uomo politico, il fatto ha valore politico e non solo personale. Ammettiamo che gli uomini di Stato e di governo che hanno sottoscritto nel 1978 la legge 194 sull\u2019aborto in Italia avessero fatto obiezione di coscienza e si fossero dimessi dalla loro carica. Sarebbe stato un atto politico di primaria importanza, un atto che avrebbe continuato a fare politica nei secoli.<\/p>\n<p style=\"text-align: justify;\">Questo perch\u00e9 avrebbe significato la denuncia di un ordine sociale che si stava costruendo come disordine. Non si sarebbe trattato di una semplice fedelt\u00e0 ad una opinione personale, n\u00e9 ad una semplice, anche se importante, convinzione di coscienza, ma il tutto si sarebbe riferito ad un ordine sociale legittimo e ad uno illegittimo. Inevitabilmente il discorso si sarebbe dislocato sul prima, su quanto precede e fonda la comunit\u00e0 e su quanto merita riconoscimento pubblico e quanto no. Chi pu\u00f2 negare con assoluta certezza che un atto del genere non avrebbe cambiato la storia politica del nostro Paese?<\/p>\n<p style=\"text-align: justify;\">Ecco perch\u00e9 oggi c\u2019\u00e8 la necessit\u00e0 di insistere sui principi non negoziabili in ordine alla obiezione di coscienza in campo politico. Da essa dipende il collegamento della politica con il prima che la precede e la fonda.<\/p>\n<p style=\"text-align: justify;\">In questo modo la politica \u00e8 costretta a fare i conti con la modernit\u00e0. Questa, infatti, ha annullato il \u201cprima\u201d e ha preteso di cominciare da zero, nella forma del contratto sociale. E\u2019 stato giustamente osservato che il primo moderno \u00e8 stato Guglielmo di Occam, secondo il quale dietro all\u2019ordine delle cose e dietro all\u2019ordine morale non c\u2019era un disegno ma l\u2019arbitraria volont\u00e0 divina. Su questa piazza pulita la politica moderna di Hobbes o Rousseau costru\u00ec il convenzionalismo del contratto sociale. Se si eliminano i principi non negoziabili finisce il \u201cprima\u201d della politica e la visione moderna avrebbe irrimediabilmente vinto senza possibilit\u00e0 di alcun riscatto. La consegna al contratto sociale sarebbe definitiva.<\/p>\n<p style=\"text-align: justify;\">Per\u00f2 della modernit\u00e0 fa parte anche Tommaso Moro, che Giovanni Paolo II ha proclamato Protettore dei politici. E Tommaso Moro fece obiezione di coscienza, ben sapendo che in quel modo egli esercitava un supremo atto politico, denso di conseguenze politiche nei secoli. Il suo atto, infatti, divenne simbolo dell\u2019indipendenza della legge morale sul potere e aliment\u00f2 le lotte per la difesa della libert\u00e0 di coscienza lungo la storia moderna.<\/p>\n<p style=\"text-align: center;\">__________________<\/p>\n<p style=\"text-align: justify;\">Osservatorio Internazionale Cardinale Van Thuan &#8211; <b>Newsletter<\/b> n.486 del 18 marzo 2014<\/p>\n<p align=\"center\">The non negotiable Principles: why they still demand attention.<\/p>\n<p align=\"center\"><b>Stefano Fontana<\/b><\/p>\n<p><i>Parish of St. Peter Apostle<\/i><\/p>\n<p><i>Verona 11 March 2014<\/i><\/p>\n<p><b>What they are<\/b><\/p>\n<p style=\"text-align: justify;\">Often spoken about are non negotiable \u201cvalues\u201d instead of non negotiable \u201cprinciples\u201d, but this is an error of approach.<\/p>\n<p style=\"text-align: justify;\">Principle means foundation and criterion. The principle is the element that supports and enlightens a certain ambit. The principle holds things together, directing and orienting them to their end. It therefore follows that the principle cannot be one element in the series, not even the first one. Being a principle means being chronologically at the beginning, just as 1 January is the first day of the new year. The principle enjoys primacy: it comes before, and in this case the adverb \u2018before\u2019 is not temporal alone.<\/p>\n<p style=\"text-align: justify;\">On the other hand, what is a value? Something has value when it is commendable, significant. Now, life, the family or freedom of education \u2013 just to mention the main non negotiable principles \u2013 certainly are values; worthy are they of recognition and promotion. And this just like many other aspects of human and social life, such as art, solidarity, knowledge, health, good food, etc.<\/p>\n<p style=\"text-align: justify;\">As we can see, being a value does not also mean being a principle. Home ownership is a value, but it isn\u2019t a regulative principle of social life. This does not take away from the fact that a value may also be a principle. Human life, for example, is a value, but it is also a principle insofar as able to bring its light to bear on social and political life at large. When the respect for life is obfuscated, obscured is not only one value, but also other values and other aspects of the life illuminated by that principle.<\/p>\n<p style=\"text-align: justify;\">The common good is not a cluster of values of equal weight, but rather ordered cluster. Being ordered means that some value has an architectural function in the sense of indicating the foundations of the common good, and, in so doing, illuminating with sense all the others as well. Without a criterion there is no common good, but rather a sum of individual goods, and this criterion comes to us from the non negotiable principles.<\/p>\n<p style=\"text-align: justify;\">We have therefore established what the word \u2018principle\u2019 means. Now let\u2019s take a took at what \u2018non negotiable\u2019 means. If it is a question of principles in the sense of what comes first and is foundational, they do not depend on what comes afterwards and have the value of absoluteness and are not disposable. They are non negotiable because they are absolute and are absolute because they are principles. If they were relative they could not be principles, would not come first, and would be one of many elements in a series. Either we deny the existence of principles, or, if we admit their existence, they must be absolute, that is to say non negotiable. This value of absoluteness also becomes evident when we experience their absence. When lacking is any reference to them a society loses its bearings and undergoes an involution. This means society is relative to them, and not they to society. And here is the ultimate reason why they cannot be negotiable; because they weren\u2019t negotiated. If something has been negotiated it means it is negotiable and can be renegotiated at a later stage. But a principle cannot be renegotiated because it had never been negotiated beforehand insofar as non negotiable. Otherwise what principle would it be? In a society without non negotiable principles everything is open to negotiation, including negotiability in itself.<\/p>\n<p style=\"text-align: justify;\">Non negotiable principles, therefore, are such insofar as they precede society. And where do they come from? They are non negotiable because they are rooted in human nature. Precisely because they are part and parcel of human nature they cannot be taken in doses: a little bit, yes; that other bit, no. It is a question of taking them or leaving them. This is family or it isn\u2019t. The non negotiable principles demarcate human from non human, and are hence the criterion for human life in common.<\/p>\n<p style=\"text-align: justify;\">From another point of view, however, there are not really prime principles because they are not able to be their own foundation . As we have seen, they are based on human nature, but what is human nature founded upon? The non negotiable principles express an order referring to and evoking the Creator.<\/p>\n<p style=\"text-align: justify;\">If non negotiable principles do not exist, reason finds no order evoking the Creator. It no longer encounters faith, and faith no longer encounters reason. This means the expulsion of religion from the public sphere. Social and political life would only be the reign of relativeness. What would faith be there to do in such a context? Would God have gone out of His way to speak to us in order to add His opinion to ours.<\/p>\n<p style=\"text-align: justify;\"><b>Which ones they are<\/b><\/p>\n<p style=\"text-align: justify;\">Specifying which are the non negotiable principles is of fundamental importance. In this regard, three are the basic texts of the Magisterium.<\/p>\n<p style=\"text-align: justify;\">Indicated in paragraph 4 of the\u00a0<i>Doctrinal Note on some questions regarding the commitment and behavior of Catholics in political life (<\/i>Congregation for the Doctrine of the Faith, 24 November 2002) are the following non negotiable principles: life, family, freedom of education, social protection of minors, freedom of religion, economy at the service of the individual, and peace.<\/p>\n<p style=\"text-align: justify;\">In the Post Synodal Apostolic Exhortation <i>Sacramentum caritatis<\/i> on the Eucharist dated 22 February 2007 (para. 83) Benedict XVI cites life, family and freedom of education, to which he adds the common good.<\/p>\n<p style=\"text-align: justify;\">In an address to the participants at the Conference of the European People\u2019s Party on 30 March 2006, Benedict XVI lists life, family and freedom of education.<\/p>\n<p style=\"text-align: justify;\">Let us now delve deeper into these lists. The first thing worthy of attention is that three principles are always present at the beginning of each list and hence situated in an eminent position: life, family and freedom of education.<\/p>\n<p style=\"text-align: justify;\">This indicates that these three principles are foundational in nature; in other words, no other successive principles may be either properly understood or effectively pursued without them. Is it possible, for example, to guarantee the social protection of minors if minors are prevented from being born? Is it possible to do so by preventing them from growing up in a united and stable family? Is it possible to obtain this result by depriving the family of its right-responsibility to educate its children? If the family remains sound, all the various forms of social malaise experienced by minors can be solved in the long run.<\/p>\n<p style=\"text-align: justify;\">Secondly, this listing indicates that these three principles bring us face to face with moral absolutes in the sense of acts that must never be perpetrated under any circumstances whatsoever. This is not the case for the other principles listed in the Doctrinal Note of 2002. For example, listed among the non negotiable principles is also \u201can economy at the service of the individual\u201d. There is no doubt that efforts to eliminate unemployment is an important element of the common good.<\/p>\n<p style=\"text-align: justify;\">Nonetheless, there can be different ways to pursue full employment. In the case of the three principles at the centre of our attention, however, there are no different ways. In fact, there are no ways at all. The difference depends on the fact that the words \u201cdo not kill\u201d and the words \u201cincrease employment\u201d are very different in terms of their respective compulsory nature in moral terms.<\/p>\n<p style=\"text-align: justify;\">The former imposes an absolute moral negative, and therefore something that must never be done, while the latter proposes a positive moral precept indicating what is to be done. Now, while absolute evil must never be perpetrated, good can be done in a myriad of ways. Conscience, together with the virtue of prudence, is never exercised in the case of negative moral precepts \u2013 sacrifice two human embryos instead of three is not a lesser moral evil; aborting once instead of twice is not a lesser moral evil \u2013 while it does come into the picture in the case of positive moral precepts.<\/p>\n<p style=\"text-align: justify;\">Many are those who accept these considerations of mine for the first two principles \u2013 life and the family, but not for the third one: freedom of education. Freedom of education is fundamental insofar as it posits or removes the possibility for the soul of a child to be initiated to truth rather than error, to good rather than evil, to God rather than the Prince of darkness. The issue at stake is that of education and its decisive role in our life. If it is possible to educate, there is a remedy for everything, but if families and the Church are deprived of the possibility to educate, this marks the end of everyone and everything.<\/p>\n<p style=\"text-align: justify;\">There is only one other principle among those listed in the Doctrinal Note of 2002 that could compete for the \u2018primacy\u2019 attributed to the first three, and that is the principle of the freedom of religion. This principle issues forth from the duty to seek the truth all the way to its roots, and this means coming to terms with God. The right to religious freedom, however, is not absolute insofar as it applies only within the sphere of respect for the law of nature, whose respect is fundamental for the common good. To profess and practice a religion containing elements contrary to natural law cannot be a right and would have no moral grounds for public recognition.<\/p>\n<p style=\"text-align: justify;\">Stemming forth from these considerations is the fact that there is a difference between the first three principles listed and the other ones. If the first three are lacking, the entire list disappears, while if only the first three are present we would already have the hard core, the nucleus supporting everything we have been saying. As we have seen, in fact, it often happens that the Magisterium only lists the first three, but it never lists others without these three.<\/p>\n<p><b>Misunderstandings about the non negotiable principles<\/b><\/p>\n<p style=\"text-align: justify;\">Many Catholics criticize or even deride the non negotiable principles, considering them to be a barrier to dialogue. Others point out that dialogue needs limits in order to be meaningful, and these limits are set down by these principles. In fact, many are the misunderstandings that do arise.<\/p>\n<p style=\"text-align: justify;\">Regarding the first misunderstanding, or taking them as values and not principles, I have already illustrated my position. This, for example entails the classical error of evaluation: if a political party sponsors abortion and works efficiently to reduce poverty, while another party is against abortion but is less efficacious in the fight against poverty I can freely decide for both of them because it is a matter of values alone.<\/p>\n<p style=\"text-align: justify;\">One of the other more frequent misunderstandings is to think that the non negotiable principles would entail the foregoing of global political thought on the part of Catholics in exchange for the request for guarantees on individual and specific issues. Far from being single issues, the non negotiable principles are principles and hence reference to them always involves the acceptance of a perspective that inevitably has an impact on other points. During certain phases of history there has been the need to focus more on individual principles because of impending threats. But this does not mean that forgotten is their value of enlightenment for an entire social and political programme.<\/p>\n<p style=\"text-align: justify;\">A third misunderstanding consists in considering the non negotiable principles as contrary to the essence of democracy. This would be the system that has the human person at its centre, but since this human person is to be deepened in ongoing dialogue, and there will be no end to that, needed is political debate and the ensuing application of the law of the majority. The fact that a given reality has to be constantly explored and deepened according to the principle of consistency is true, but this does not mean it is not possible to know anything certain and definitive about it, so certain and definitive that it has to be shielded from the law of the majority. The non negotiable principles claim not to tell us everything about human society, but to tell us about the aspects without which it isn\u2019t human society. If the complete overview of man is not given to us \u2013 at least down here \u2013 these principles are given to us in all their clarity and mandatory nature.<\/p>\n<p style=\"text-align: justify;\">A fourth misunderstanding has to do with means and ends. People say politics concerns means and not ends. In fact, it is argued that there are different political parties so citizens may, with due prudence, avail themselves of one or another party to pursue and attain their ends. This would justify the presence of Catholics in all parties. Citizens who have equal ends then divide up in the choice of the party, which, as a means, is better able to attain the aspired ends. People ordinarily bring into the picture the virtue of prudence with which the moral conscience applies the general moral principles in a concrete situation, choosing the means best suited to achieve the end.<\/p>\n<p style=\"text-align: justify;\">The first thing to be said is that politics has to do with ends and not means atone. The second thing is that the means are ordered to the end, and hence cannot contradict it. Prudence applied to bad means becomes imprudence. If in order to attain the end of the defence of life I place my trust in the means of a party that promotes abortion, I have not exercised prudence and have been imprudent. The choice of the party has to do with the ends, and then has to do with the means, which must be good ones, must be fitting and suitable with respect to the end in mind. What I am saying is at the very basis of the fact that if we accept the non negotiable principles we cannot adhere to all parties without distinction, because some of them are linked to other contrary ends, and others are means unsuited to the end.<\/p>\n<p style=\"text-align: justify;\">One last and rather frequent misunderstanding is to retain that admitting non negotiable principles would mean to deny the laicity of politics, making it depend on confessional principles. The non negotiable principles are reasonable principles that can be acknowledged by all men. What\u2019s strange is not the fact that they may be acknowledged, but the fact that they may be denied. Therefore, they do belong to the sphere of laicity, if by laicity we understand the ambit of public religion, which establishes the principles and the ends of living in human community. On the other hand, if we understand laicity as the absence of any absolute truth, even rational truth, it is not true laicity, but a new religion of the absolute individual and his or her whims.<\/p>\n<p style=\"text-align: justify;\">Depending on non negotiable principles, therefore, politics depends not on confessional principles, but quite simply on its selfsame \u201csense\u201d.<\/p>\n<p style=\"text-align: justify;\"><b>Non negotiable principles and conscientious objection<\/b><\/p>\n<p style=\"text-align: justify;\">Since politics is becoming increasingly arrogant in disputing and seeking to thwart non negotiable principles, conscientious objection is nowadays becoming more and more of a political issue and not just a moral one.<\/p>\n<p style=\"text-align: justify;\">Numbered among conscientious objectors are: pharmacists, who do not want to sell the \u2018day after\u2019 pill because of its abortive effects; obstetricians and physicians, who do not want to collaborate in abortion procedures even if they are legal; municipal employees, who do not want to register same-sex couples in special public records, or do not want to publicly celebrate marriages, which are not marriages; many teachers, who do not want to give in to gender ideology; parents, when they decide not to have their children attend destructive sex education courses at school; workers, who do not forego their right to wear a religious symbol or sign when at work, while their employers or administrations prohibit that; nurses, when they react to the public health care prohibition to provide religious comfort to the moribund; American bishops, who call for the application of conscientious objection against the Obama health care reform; the staff members of a day care clinic in Tuscany, who will now be expected to hand out the \u201cabortion pill\u201d. There are people who lose their jobs out of fidelity to non negotiable principles.<\/p>\n<p style=\"text-align: justify;\">Why is this happening? Because there are non negotiable principles in the face of which our conscience, like that of Socrates or Antigone, finds the force to voice an absolute no. Now, I wonder why this should not hold true in politics? Why should reaching a compromise at any cost be the litmus test in politics? And manifesting both respect and deference for this compromise, praising the person who mediated the matter as an example of wisdom, prudence and even courage?<\/p>\n<p style=\"text-align: justify;\">This becomes all the more evident if we take a took at it from the viewpoint of witness. How often is it said that a Catholic is in politics in order to bear witness. Nonetheless, if there is no possibility of sacrifice, if there is never anything akin to a \u2018no\u2019 to be said at the risk of losing something, how do we measure witness? It is easy to be an applauded and well paid politician. And it is not enough to refrain from committing illegal or immoral acts. It is necessary to be prepared and willing to pay a price in the face of principles which our conscience deems non negotiable. Socrates had been advised by his friend Crito to take flight, but Socrates had replied \u2018no\u2019!.<\/p>\n<p style=\"text-align: justify;\">Politically speaking, the main sacrifice for a politician is resignation from his office or position. It is necessary to acknowledge the fact that rare indeed are the politicians who have resigned from office in order not to give their consent to a law contrary to natural moral law. And yet ever present in collective memory is the case of self-suspension from office on the part of King Baudoin of Belgium, who did not want to place his signature on the abortion law and thereby give it Royal Assent. His example was not followed some days ago by his nephew Philippe with respect to the law on the euthanasia of children.<\/p>\n<p style=\"text-align: justify;\">The true politician is he who knows how to give up politics. He is man before and after politics. This is what gives sense to politics itself. If I keep the field of my humanity open through fidelity to the upright conscience that judges politics itself, I also help politics to breathe. Many are those who say the field of engagement must not be abandoned (for example, resignation) because this would be an act of withdrawal from due political battle, leaving everything in the hands of others. And yet there are many ways and many places where \u2018politics\u2019\u00a0 may be practiced. Without forgetting that a possible resignation for reasons of conscience would already be a political act replete with possible political consequences unforeseeable at that moment. Then again, a true political leader is a person who also knows how to say \u201cno\u201d, and knows how to say it because he knows how to say it to himself. He who does not know how to say \u201cno\u201d to himself has no right to say it to others.<\/p>\n<p style=\"text-align: justify;\">It is evident that conscientious objection in politics is possible if non negotiable principles are embraced. All possible means are being deployed to eliminate freedom of conscience in order to eliminate non negotiable principles, and eliminate non negotiable principles in order to eliminate freedom of conscience. The existence of non negotiable principles is what renders our conscience free.<\/p>\n<p style=\"text-align: justify;\">When a politician practices conscientious objection insofar as a politician, his act has a political value and not just a personal one. Let\u2019s consider this hypothetical scenario: what if the men of state and government who undersigned Law 194 on abortion in Italy in 1978 had exercised conscientious objection and resigned from office. This would have been a political act of primary importance, an act that would have continued to impact politics for centuries.<\/p>\n<p style=\"text-align: justify;\">This is true because such an act would have been tantamount to exposing a social order that was erecting itself as sheer disorder. It would not have been a matter of mere fidelity to a personal opinion, or a straightforward but important issue of following one\u2019s conscience, but everything would have referred to a legitimate social order and an illegitimate social order.<\/p>\n<p style=\"text-align: justify;\">The discussion would have inevitably shifted to focus on the \u2018before\u2019, on what comes before, on what merits public recognition and what doesn\u2019t. Who can deny in absolutely certain terms that such an act wouldn\u2019t have changed the political history of our country?<\/p>\n<p style=\"text-align: justify;\">This is why it is necessary today to insist on the non negotiable principles with respect to conscientious objection in the political arena. Dependent thereupon is politics\u2019 linkage with beforeness, with what precedes it and founds it.<\/p>\n<p style=\"text-align: justify;\">In this manner politics is forced to come to terms with modernity, which, in fact, cancelled the \u201cbefore\u201d and claimed to begin everything from scratch in the form of a social contract. It has been correctly pointed out that the first \u2018modernist\u2019 was William of Ockham, who held that behind the order of things and behind the moral order there was no plan, but rather arbitrary divine will. On this clean slate the modern politics of Hobbes and Rousseau constructed the conventionalism of the social contract. If non negotiable principles are eliminated, the \u201cbefore\u201d of politics abruptly ends and the modern vision would have irreparably won the day without any possibility of deliverance there from.\u00a0 The \u2018handing over\u2019 to the social contract would be definitive.<\/p>\n<p style=\"text-align: justify;\">Likewise part of modernity, however, was Thomas More, who was declared Protector of Politicians by Pope John Paul II. And Thomas More had made an act of conscientious objection, well aware that in that manner he was exercising a supreme political act replete with political consequences for centuries to come. In fact, his act became a symbol of the independence of the moral law from power, and fanned the flames of battles for the defence of the freedom of conscience throughout modern history.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Osservatorio Internazionale Cardinale Van Thuan &#8211; Newsletter n.486 del 18 marzo 2014 Stefano Fontana (in english too) &nbsp;<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/6544\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":6695,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,11,53],"tags":[2388,146,235,372],"class_list":["post-6544","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bioetica","category-dottrina-sociale","category-politica","tag-bioetica","tag-dottrina-sociale-2","tag-politica-2","tag-principi-non-negoziabili","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>I principi non negoziabili: perch\u00e8 bisogna parlarne ancora  - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/6544\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"I principi non negoziabili: perch\u00e8 bisogna parlarne ancora  - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/6544\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2014-03-20T09:18:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-06-12T11:54:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/03\/principi1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"209\" \/>\n\t<meta property=\"og:image:height\" content=\"153\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"35 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/6544\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/6544\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"I principi non negoziabili: perch\u00e8 bisogna parlarne ancora\",\"datePublished\":\"2014-03-20T09:18:19+00:00\",\"dateModified\":\"2015-06-12T11:54:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/6544\\\/\"},\"wordCount\":7046,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/6544\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/03\\\/principi1.jpg\",\"keywords\":[\"Bioetica\",\"dottrina sociale\",\"politica\",\"principi non negoziabili\"],\"articleSection\":[\"Bioetica\",\"Dottrina sociale\",\"Politica\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/6544\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/6544\\\/\",\"name\":\"I principi non negoziabili: perch\u00e8 bisogna parlarne ancora - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/6544\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/6544\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/03\\\/principi1.jpg\",\"datePublished\":\"2014-03-20T09:18:19+00:00\",\"dateModified\":\"2015-06-12T11:54:09+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/6544\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/6544\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/6544\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/03\\\/principi1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/03\\\/principi1.jpg\",\"width\":209,\"height\":153},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/6544\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"I principi non negoziabili: perch\u00e8 bisogna parlarne ancora\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"I principi non negoziabili: perch\u00e8 bisogna parlarne ancora  - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/6544\/","og_locale":"it_IT","og_type":"article","og_title":"I principi non negoziabili: perch\u00e8 bisogna parlarne ancora  - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/6544\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2014-03-20T09:18:19+00:00","article_modified_time":"2015-06-12T11:54:09+00:00","og_image":[{"width":209,"height":153,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/03\/principi1.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"35 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/6544\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/6544\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"I principi non negoziabili: perch\u00e8 bisogna parlarne ancora","datePublished":"2014-03-20T09:18:19+00:00","dateModified":"2015-06-12T11:54:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/6544\/"},"wordCount":7046,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/6544\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/03\/principi1.jpg","keywords":["Bioetica","dottrina sociale","politica","principi non negoziabili"],"articleSection":["Bioetica","Dottrina sociale","Politica"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/6544\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/6544\/","name":"I principi non negoziabili: perch\u00e8 bisogna parlarne ancora - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/6544\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/6544\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/03\/principi1.jpg","datePublished":"2014-03-20T09:18:19+00:00","dateModified":"2015-06-12T11:54:09+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/6544\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/6544\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/6544\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/03\/principi1.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/03\/principi1.jpg","width":209,"height":153},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/6544\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"I principi non negoziabili: perch\u00e8 bisogna parlarne ancora"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/6544","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=6544"}],"version-history":[{"count":7,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/6544\/revisions"}],"predecessor-version":[{"id":26217,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/6544\/revisions\/26217"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/6695"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=6544"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=6544"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=6544"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}