{"id":6535,"date":"2014-03-19T12:58:12","date_gmt":"2014-03-19T11:58:12","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=6535"},"modified":"2015-06-12T14:01:50","modified_gmt":"2015-06-12T12:01:50","slug":"il-fratello-di-nino-bixio","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-fratello-di-nino-bixio\/","title":{"rendered":"Il fratello di Nino Bixio"},"content":{"rendered":"<p style=\"text-align: center;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/03\/bixio.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-6702 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/03\/bixio.jpg\" alt=\"bixio\" width=\"242\" height=\"208\" \/><\/a>Il Timone<\/strong> n.130 febbraio 2014<\/p>\n<p style=\"text-align: center;\">di<strong> Rino Cammilleri<\/strong><\/p>\n<p style=\"text-align: justify;\">Ges\u00f9 aveva detto chiaramente di essere venuto a portare non la pace sulla terra ma la spada, profetizzando che il suo messaggio avrebbe diviso anche le famiglie. Ci\u00f2 si \u00e8 verificato in tutte le epoche e fin dall&#8217;inizio, con case ebraiche in cui uno seguiva l&#8217;insegnamento del Nazareno e un altro che restava fariseo o sinedrita, e pure nell&#8217;impero romano c&#8217;erano figli e mogli cristiani con padri e mariti pagani. E non di rado il dissidio finiva pure in tribunale e con esecuzioni capitali.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Non \u00e8 il caso qui di ripercorrere tutta la storia umana dopo Cristo, ma la divisione intrafamiliare \u00e8 stata pi\u00f9 che evidente con l&#8217;avvento delle ideologie. Per restare pi\u00f9 vicini a noi, pensiamo alla rivoluzione giacobina italica, cio\u00e8 il Risorgimento. Non pochi &#8220;piemontesi&#8221; di primo piano ebbero congiunti che militarono nell&#8217;altra parte della barricata. Massimo D&#8217;Azeglio aveva un fratello gesuita, Luigi, che fu addirittura tra i fondatori de &#8220;La civilt\u00e0 cattolica&#8221;. Il fratello maggiore di Cavour, Cesare,aveva fatto parte delle &#8220;Amicizie cristiane&#8221; antinapoleoniche fondate dal venerabile Pio Bruno Lan-teri. Pure Silvio Pellico aveva un fratello gesuita, e fu anche processato per avergli dato rifugio quando quello era braccato dal governo liberale.<\/p>\n<p style=\"text-align: justify;\">Meno noto \u00e8 il fatto che anche Gerolamo Bixio detto Nino, braccio destro di Garibaldi e fucilatore di contadini a Bronte, aveva un fratello gesuita, Giuseppe (gli altri due fratelli Bixio, Alessandro e Gianbattista, erano uno banchiere a Parigi e l&#8217;altro arruolato nella Royal Navy). Nino, carbonaro, mazziniano e anticlericalissimo, spos\u00f2 la figlia di sua sorella e, dopo una vita densa di battaglie e avventure, and\u00f2 a morire di febbre gialla a Sumatra.<\/p>\n<p style=\"text-align: justify;\">Il fratello Giuseppe, che \u00e8 quello che ci interessa, entr\u00f2 nella Compagnia di Ges\u00f9 e fu ordinato sacerdote. Fin\u00ec a fare il missionario negli Stati Uniti, prima nel Maryland e poi nell&#8217;Oregon, dove prese le parti degli indiani Nez-Perc\u00e9s (o Nasi Forati) contro le vessazioni dei bianchi. Nel suo diario scriveva di non aver visto mai \u00abun indiano ubriaco, non ho mai conosciuto un indiano ladro o assassino, non ho mai visto un indiano sparare per primo\u00bb. Aveva visto, invece, \u00abcapanne bruciate, fosse comuni, accordi di pace stracciati\u00bb. Gli indiani nordamericani chiamavano i gesuiti \u00abmanti neri\u00bb per via dell&#8217;abito, e ne ricevevano istruzione. E, per quanto possibile, protezione. Ma ai bianchi w.a.s.p. (&#8220;<em>White Anglo-Saxon Protestant<\/em>&#8220;) quei preti papisti e per giunta gesuiti facevano un baffo.<\/p>\n<p style=\"text-align: justify;\">Cos\u00ec, i Nez-Perc\u00e9s dovettero riparare in Canada e padre Bixio si spost\u00f2 in California, dove nel 1855 fond\u00f2 con due confratelli italiani il Saint Ignatius College (poi divenuto l&#8217;Universit\u00e0 di San Francisco). Cinque anni pi\u00f9 tardi si trasfer\u00ec in Virginia, dove divenne parroco. Ma subito scoppi\u00f2 la Guerra di Secessione e padre Bixio, senza pensarci due volte, si arruol\u00f2 come cappellano nell&#8217;esercito confederato. Il caso \u00e8 descritto da Gilberto Oneto nel libro <em>Unit\u00e0 o libert\u00e0. Italiani e padani nella Guerra di Secessione americana<\/em>, II Cerchio).<\/p>\n<p style=\"text-align: justify;\">Perch\u00e9 la scelta di campo sudista? Forse la risposta va cercata in questa sua lettera: \u00abHo ancora negli occhi i villaggi degli indiani attaccati dai soldati blu, le donne e i bambini infilzati dalle loro sciabole come agnelli allo spiedo (&#8230;). Loro, gli yankee, questo lo chiamano progresso\u00bb. Durante la guerra, da buon Bixio, non si limit\u00f2 a fare il cappellano ma, vestito da capitano, collabor\u00f2 con l&#8217;intelligence confederata infiltrandosi spericolatamente, e pi\u00f9 volte, nelle linee nemiche, tanto da diventare una specie di leggenda vivente per i soldati sudisti.<\/p>\n<p style=\"text-align: justify;\">L&#8217;episodio pi\u00f9 clamoroso \u00e8 del 1864, quando si trovava ad Atlanta assediata dai nordisti (la citt\u00e0 sar\u00e0 poi incendiata e il fatto immortalato sul grande schermo in Via col vento, dove, in un<br \/>\na delle scene pi\u00f9 epiche, Rhett Butler porta in salvo Scarlett O&#8217;Hara tra le fiamme). Padre Bixio trov\u00f2 il corpo di un cappellano nordista e gli prese l&#8217;uniforme. Con quella indosso si present\u00f2 addirittura al generale Sherman e lo convinse a rilasciargli un salvacondotto che us\u00f2 per trafugare un carico di vettova glie e portarlo nella citt\u00e0 assediata. Quando Sherman venne a sapere dell&#8217;ammanco e colleg\u00f2 i due fatti, diede ordine a uno squadrone di cavalleria di inseguire il fuggitivo e di appenderlo a un albero appena acciuffato. Ma quello non fu preso e, a guerra finita, scamp\u00f2 alla vendetta dei vincitori dimostrando di aver sempre soccorso i feriti, anche nordisti.<\/p>\n<p style=\"text-align: justify;\">Ritroviamo il nostro battagliero gesuita nel 1871 a San Francisco, dove capeggi\u00f2 un corteo di cattolici che manifestavano contro la presa di Roma da parte dei piemontesi. In testa, lui e il capo dei Nez-Perc\u00e9s, battezzato come Marcel. Dopo qualche anno, eccolo in Australia, a Melbourne. Torn\u00f2 negli Usa nel 1880 e nove anni dopo mor\u00ec a Santa Clara. Fu sepolto con accanto le divise nordista e sudista (le aveva usate entrambe), un coltello e una pistola.<\/p>\n<p style=\"text-align: justify;\">Ma, come racconta il libro di Oneto, non era l&#8217;unico italiano ad aver combattuto nella guerra civile americana. Parecchi erano i nostri connazionali nei due campi, ma pi\u00f9 numerosi in quello confederato. Particolarmente interessante \u00e8 la vicenda degli ex borbonici che militarono per due volte per il Sud, italico e americano, e in entrambi i casi finirono sconfitti.<\/p>\n<p style=\"text-align: justify;\">Dopo la battaglia del Volturno (1 ottobre 1860) gli &#8220;italiani&#8221; si trovarono con moltissimi prigionieri duosiciliani che rifiutavano di giurare fedelt\u00e0 al Savoia. Liberarli non si poteva, perch\u00e9 sarebbero finiti a rimpinguare i ranghi della resistenza (poi chiamata &#8220;brigantaggio&#8221;). La soluzione venne pochi giorni dopo, il 6 novembre, quando Lincoln divent\u00f2 presidente.<\/p>\n<p style=\"text-align: justify;\">Poich\u00e9 era chiaro a tutti cosa sarebbe successo negli Usa, il garibaldino americano Chatam R. Wheat, che era della Louisiana, propose a Garibaldi il trasferimento dei prigionieri a New Orleans, perch\u00e9 i sudisti erano in grave svantaggio numerico nei confronti del Nord. Garibaldi, pur simpatizzando apertamente per Lincoln (questi, a guerra scoppiata, gli propose un comando nelle truppe unioniste ma l&#8217;Eroe rifiut\u00f2 perch\u00e9 avrebbe accettato solo quello supremo), trov\u00f2 buona l&#8217;idea (dimostrando, con ci\u00f2, che della causa antischiavista non gli importava pi\u00f9 di tanto, ndr).<\/p>\n<p style=\"text-align: justify;\">Il 7 arriv\u00f2 a Napoli il re Vittorio Emanuele e fu d&#8217;accordo. A gestire il tutto fu il solito don Liborio Romano, \u00abche la sera prima del cambio di regime \u00e8 ministro di Francesco II e il mattino dopo del governo Garibaldi\u00bb. Fu cos\u00ec che migliaia di ex soldati borbonici vennero imbarcati in pi\u00f9 riprese, e i sudisti americani poterono contare sull&#8217;incremento di militari addestrati e pure veterani. Naturalmente, alte proteste si levarono da parte di Lincoln nei confronti di Cavour, che fu costretto a cessare con gli imbarchi. I nordisti, dal canto loro, misero in atto il blocco navale contro i confederati. E i restanti prigionieri borbonici finirono nei lager di Fenestrelle e di altri luoghi.<\/p>\n<p style=\"text-align: justify;\">Con la caduta di Gaeta, di Messina e quella finale di Civitella del Trento, i prigionieri &#8220;irriducibili&#8221; furono talmente tanti che il nuovo regime pens\u00f2 di mandarli in campi di concentramento esteri. La prima idea fu l&#8217;Australia, che gi\u00e0 gli inglesi usavano come colonia penale. Ma i britannici risposero picche. La seconda idea fu la Patagonia, ma anche qui l&#8217;Argentina non ne volle sapere. Idem per l&#8217;Indonesia o il Mar Rosso. Disperato, Cavour contatt\u00f2 perfino Lincoln e fu mandato educatamente a quel paese. Ma qui non seguiremo ulteriormente la sorte dei prigionieri napoletani in mano ai &#8220;fratelli d&#8217;Italia&#8221;.<\/p>\n<p style=\"text-align: justify;\">Andremo invece a vedere come and\u00f2 a quelli finiti in uniforme grigia. Vennero inquadrati nelle <em>Italian Guards<\/em> e nelle <em>Garibaldi Guards<\/em>. Ma, quando questi ultimi &#8211; che naturalmente non capivano l&#8217;inglese &#8211; si resero conto del nome che era stato loro assegnato, protestarono con forza e ottennero di essere chiamati <em>Bourbon Dragoons,<\/em> nome anche pi\u00f9 gradito agli americani perch\u00e9 ricordava loro la pregiata qualit\u00e0 di whisky (prodotta nella citt\u00e0 di Bourbon, cos\u00ec battezzata in onore della monarchia francese che aveva aiutato gli americani nella guerra d&#8217;indipendenza).<\/p>\n<p style=\"text-align: justify;\">Eh, gli americani, poverini, bisogna capirli. In quegli anni, per loro, tutti gli italiani in armi erano &#8220;garibaldi&#8221;, tanto era stato il martellamento propagandistico sull&#8217;Eroe de Due Mondi nel monde anglofono. Credo che ancora adesso per parecchi stranieri &#8220;garibaldi&#8221; sia l&#8217;unica parole italiana (insieme a &#8220;pizza&#8221; e &#8220;spaghetti&#8221;, naturalmente) che conoscono. Ne ho avuto personale esperienze quando, anni fa, in visita a un amico inglese che abitava in Italia, citofonai e mi rispose suo padre, che non parlava italiano cos\u00ec: \u00abHi, garibaldi! garibaldi!\u00bb.<\/p>\n<p style=\"text-align: justify;\">Tra le storie dei sudisti italiani spiccano quelle di Angelo Vaccaro, fatto prigioniero a Nashvilk nel 1864: si rifiut\u00f2 di passare coi nordisti cos\u00ec come aveva fatto coi piemontesi nelle guerra civile italiana. Francesco Angelo faceva parte dei rangers a cavallo di John S Mosby detto &#8220;Gray Ghost&#8221; (fantasma grigio), terrore dei nordisti. Carlo Patti era fratello della celebre soprano Adelina, contesa da tutte le corti europee. Giovanbattista Garibaldi (cognome piuttosto comuni in Liguria) sotto il famoso generale &#8220;Stone wall&#8221; Jackson prese parte alle battaglie pi\u00f9 importanti, come Harpers Ferry, Chancel lorsville, Gettysburg, ed ebbe l&#8217;onore di venire sepolto a Lexington accanto al generale Lee, comandante in capo dei confederati.<\/p>\n<p style=\"text-align: justify;\">Purtroppo, gran parte dei documenti sudisti sono andati distrutti o perduti, per ci\u00f2 le notizie sui combattenti italiani sono scarse e frammentarie. Abbondano, naturalmente, quelle sui nordisti, perch\u00e9 la storia la racconta sempre chi vince. Ma, almeno qui, rendiamo onore a quei meridionali che ben per due volte, fedeli al loro giuramento, combatterono e caddero per Ia parte &#8220;sbagliata&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Timone n.130 febbraio 2014 di Rino Cammilleri Ges\u00f9 aveva detto chiaramente di essere venuto a portare non la pace sulla terra ma la spada, profetizzando che il suo messaggio avrebbe diviso anche le famiglie. Ci\u00f2 si \u00e8 verificato in tutte le epoche e fin dall&#8217;inizio, con case ebraiche in cui uno seguiva l&#8217;insegnamento del &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-fratello-di-nino-bixio\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":6702,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[101,76,24,96],"tags":[369,370,368],"class_list":["post-6535","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-risorgimento","category-stati-uniti","category-storia","category-storia-italiana","tag-bixio","tag-borbonici","tag-guerra-di-secessione","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il fratello di Nino Bixio - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-fratello-di-nino-bixio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il fratello di Nino Bixio - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-fratello-di-nino-bixio\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2014-03-19T11:58:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-06-12T12:01:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/03\/bixio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"242\" \/>\n\t<meta property=\"og:image:height\" content=\"208\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-fratello-di-nino-bixio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-fratello-di-nino-bixio\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Il fratello di Nino Bixio\",\"datePublished\":\"2014-03-19T11:58:12+00:00\",\"dateModified\":\"2015-06-12T12:01:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-fratello-di-nino-bixio\\\/\"},\"wordCount\":1567,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-fratello-di-nino-bixio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/03\\\/bixio.jpg\",\"keywords\":[\"Bixio\",\"borbonici\",\"guerra di secessione\"],\"articleSection\":[\"Risorgimento\",\"Stati Uniti\",\"Storia\",\"Storia italiana\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-fratello-di-nino-bixio\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-fratello-di-nino-bixio\\\/\",\"name\":\"Il fratello di Nino Bixio - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-fratello-di-nino-bixio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-fratello-di-nino-bixio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/03\\\/bixio.jpg\",\"datePublished\":\"2014-03-19T11:58:12+00:00\",\"dateModified\":\"2015-06-12T12:01:50+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-fratello-di-nino-bixio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-fratello-di-nino-bixio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-fratello-di-nino-bixio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/03\\\/bixio.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/03\\\/bixio.jpg\",\"width\":242,\"height\":208},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-fratello-di-nino-bixio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il fratello di Nino Bixio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il fratello di Nino Bixio - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-fratello-di-nino-bixio\/","og_locale":"it_IT","og_type":"article","og_title":"Il fratello di Nino Bixio - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-fratello-di-nino-bixio\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2014-03-19T11:58:12+00:00","article_modified_time":"2015-06-12T12:01:50+00:00","og_image":[{"width":242,"height":208,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/03\/bixio.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"8 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-fratello-di-nino-bixio\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-fratello-di-nino-bixio\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Il fratello di Nino Bixio","datePublished":"2014-03-19T11:58:12+00:00","dateModified":"2015-06-12T12:01:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-fratello-di-nino-bixio\/"},"wordCount":1567,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-fratello-di-nino-bixio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/03\/bixio.jpg","keywords":["Bixio","borbonici","guerra di secessione"],"articleSection":["Risorgimento","Stati Uniti","Storia","Storia italiana"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-fratello-di-nino-bixio\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-fratello-di-nino-bixio\/","name":"Il fratello di Nino Bixio - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-fratello-di-nino-bixio\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-fratello-di-nino-bixio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/03\/bixio.jpg","datePublished":"2014-03-19T11:58:12+00:00","dateModified":"2015-06-12T12:01:50+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-fratello-di-nino-bixio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-fratello-di-nino-bixio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-fratello-di-nino-bixio\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/03\/bixio.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/03\/bixio.jpg","width":242,"height":208},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-fratello-di-nino-bixio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Il fratello di Nino Bixio"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/6535","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=6535"}],"version-history":[{"count":5,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/6535\/revisions"}],"predecessor-version":[{"id":26219,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/6535\/revisions\/26219"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/6702"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=6535"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=6535"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=6535"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}