{"id":64262,"date":"2026-02-12T01:05:00","date_gmt":"2026-02-12T00:05:00","guid":{"rendered":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=64262"},"modified":"2026-02-06T11:54:36","modified_gmt":"2026-02-06T10:54:36","slug":"che-fine-hanno-fatto-le-buone-maniere","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/che-fine-hanno-fatto-le-buone-maniere\/","title":{"rendered":"Che fine hanno fatto le buone maniere?"},"content":{"rendered":"\n<p class=\"has-text-align-center\"><strong><a href=\"https:\/\/lisandermag.substack.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Lisander<\/a>\u00a0 <\/strong>22 Dicembre 2025<\/p>\n\n\n\n<p class=\"has-text-align-center\">di <strong>Guia Soncini<\/strong><\/p>\n\n\n\n<p><strong>Quando \u00e8 cominciata l\u2019epoca in cui viviamo? Direi nell\u2019autunno del 2010, quando \u00e8 uscito un film di quel genere che avrebbe poi quasi monopolizzato l\u2019industria dello spettacolo<\/strong> negli anni successivi: biografie (o episodi di cronaca) rielaborate in finzioni narrative. In quel film l\u00ec,&nbsp;<em>The social network<\/em>, Mark Zuckerberg era un universitario stronzo che bisticciava con la fidanzata. Poi tornava in cameretta, scriveva delle cose terribili di lei su internet, e gi\u00e0 che c\u2019era faceva ci\u00f2 che i geni, se maschi, spesso hanno fatto nella storia: conseguire un risultato professionale gigantesco solo nella speranza che quella che non li voleva li notasse. Insomma: Mark inventa Facebook. Erica, quando lo rivede, gli dice che sar\u00e0 pure un genio, ma quel che ha detto di lei resta per sempre: \u00abL\u2019internet non \u00e8 scritta a matita, Mark\u00bb.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/10\/galateo.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"160\" height=\"175\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/10\/galateo.jpg\" alt=\"\" class=\"wp-image-10923\" style=\"width:242px;height:auto\"\/><\/a><\/figure><\/div>\n\n\n<!--more-->\n\n\n\n<p>Sono passati quindici anni, e&nbsp;<strong>la lezione pi\u00f9 importante dell\u2019epoca in cui viviamo ancora non l\u2019abbiamo appresa. Non importa quanta gente si ritrovi, se non la reputazione, almeno la giornata rovinata dalla diffusione di qualcosa che ha messo in circolo sulla rete illudendosi restasse tra quattro amici: non impariamo mai<\/strong>. Si continua, nell\u2019epoca in cui ogni messaggio \u00e8 fotografabile dallo schermo del telefono con un solo dito, \u00e8 inoltrabile a migliaia di persone con un solo dito, a parlare male degli assenti, inviare foto intime, vagare come gattini ciechi sull\u2019invisibile confine tra pubblico e privato.<\/p>\n\n\n\n<p>Vi ricordate l\u2019ipocrisia? Era un fluidificante sociale, ha funzionato per millenni. Poi \u00e8 arrivato questo secolo qui, in cui ogni volta che apro un social ci trovo qualcuna che si accende la telecamera del telefono in faccia e fa un\u2019arringa contro qualche amica che ha fatto quel che da sempre si fa educatamente: ha inventato una scusa per non vederla. Era ci\u00f2 che si faceva prima del feticismo della trasparenza. Adesso, l\u2019amica \u00e8 accusata di non avere il coraggio di dirglielo in faccia, alla tizia con telecamera, che non vuole vederla.&nbsp;<strong>\u00c8 diventato pi\u00f9 educato dire \u00abpiuttosto che uscire con te mi faccio monaca\u00bb che inventare una zia in fin di vita? Se ho capito bene, \u00e8 che la zia morta valeva finch\u00e9 tutto era privato; ora che tutto \u00e8 pubblico, tra tag e geolocalizzazione nessuna zia morta regge, e una pietosa bugia, ove scoperta, si qualifica come insulto massimo. Ti distrai un attimo e cambia tutto<\/strong>.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/10\/giovani_internet.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/10\/giovani_internet-1024x683.jpg\" alt=\"\" class=\"wp-image-44560\" style=\"width:413px;height:auto\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/10\/giovani_internet-1024x683.jpg 1024w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/10\/giovani_internet-300x200.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/10\/giovani_internet-768x513.jpg 768w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/10\/giovani_internet.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/div>\n\n\n<p><strong>\u00c8 sempre il 2010 (ve l\u2019avevo detto che era un anno fondativo), sono su un treno<\/strong>. A parte me, il vagone \u00e8 interamente riempito da fan di Vasco Rossi, che la sera prima ha fatto un concerto nella citt\u00e0 da cui siamo partiti. \u00abA parte me\u00bb significa che io ero l\u00ec per altre ragioni, non ho preso il treno per tornare dal concerto; ma, scoprir\u00f2 presto, significa anche che non ho i codici comportamentali previsti dalla societ\u00e0 costituita da questo vagone di treno. <strong>Uno dei fan mette a tutto volume una canzone, e io sono stravolta da questa invasione dello spazio pubblico<\/strong>.&nbsp;<strong>Lo so che adesso \u00e8 difficile da ricordare, perch\u00e9 il 2010 \u00e8 lontanissimo, ma fidatevi di me: non era normale ascoltare cose ad alto volume in luoghi pubblici<\/strong>. Dico: scusi, se vuole ascoltare la musica metta le cuffie. Vengo assalita dalla suscettibilit\u00e0 dei fan offesi: cio\u00e8 non ti piace Vasco?!<\/p>\n\n\n\n<p>Tento di spiegare che non \u00e8 un problema di gusto \u2013 a chi non piace Vasco, diamine, sono pure emiliana, ho le credenziali \u2013 ma che imporre la propria musica agli altri non si fa, non \u00e8 una cosa educata, non \u00e8 accettabile. Vengo spernacchiata da un intero vagone di passeggeri, tra i quali ricordo con particolare stupore una ragazza che, su un braccio, aveva tatuato il testo della canzone Sally. Quindi posso datare al 2010 il momento in cui la vita mi ha detto che ormai era normale tatuarsi, ed era normale ascoltare cose in pubblico a volume alto imponendone l\u2019ascolto a tutti i presenti. E io, come Mark Zuckerberg e otto miliardi di persone di fronte al concetto dell\u2019internet non scritta a matita, ho continuato a non capire, e a stravolgermi ogni volta.<\/p>\n\n\n\n<p>Adesso, il tema della gente che ascolta cose in pubblico ad alto volume senza preoccuparsi di dar fastidio viene dibattuto ovunque: non si pu\u00f2 aprire un social senza trovarsi davanti qualcuno di indignato perch\u00e9 il vicino di posto in metr\u00f2 ha scandito i dettagli della propria colonoscopia in viva voce, non si pu\u00f2 passare mezz\u2019ora in una sala d\u2019attesa senza ascoltare tutta la telecronaca della partita che sta guardando il tizio seduto a destra, la telefonata al cognato di quello a sinistra, e chi pi\u00f9 ne ha. Poi, se la sala d\u2019attesa \u00e8 d\u2019un ospedale, quando sar\u00e0 il nostro turno ci chiameranno solo con l\u2019iniziale del cognome: per la privacy. Puoi ascoltare tutti i fatti miei, ma non il mio cognome.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/06\/cellulare_dipensenza.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"275\" height=\"183\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/06\/cellulare_dipensenza.jpg\" alt=\"\" class=\"wp-image-34627\" style=\"width:411px;height:auto\"\/><\/a><\/figure><\/div>\n\n\n<p>Avendo quindici anni di vantaggio, ho fatto in tempo a venire a capo della ragione di questo eccesso d\u2019esibizionismo: \u00e8 il touchscreen. Il touchscreen fa s\u00ec che il telefono non si possa pi\u00f9 tenere all\u2019orecchio come le persone normali, perch\u00e9 se lo fai i tuoi lobi toccheranno qualcosa che ammutolir\u00e0 il microfono, o comporr\u00e0 un\u2019altra chiamata, o far\u00e0 cadere la linea. Quindi, <strong>la gente tiene il telefono orizzontale e in vivavoce, come fosse da sola nella propria cucina, anche se \u00e8 su un autobus affollato<\/strong>. Si potrebbe risolvere con le cuffiette. Sarebbe comunque una soluzione parziale, perch\u00e9 se parli con le cuffie in un posto pubblico non sentir\u00f2 il tuo interlocutore ma sento comunque te. Ma, se non stai facendo una telefonata ma magari ascoltando dei messaggi vocali, le cuffiette sono perfette. Solo che la modernit\u00e0 le ha rese senza fili, e quindi le persone le perdono, e alla terza volta non hanno pi\u00f9 voglia di ricomprarle. <strong>Le buone maniere sono come la legge finanziaria: non sono a budget infinito<\/strong>.<\/p>\n\n\n\n<p>Nel 1998, in un telefilm americano intitolato <em>Seinfeld<\/em>, il personaggio di Elaine veniva redarguito dagli amici perch\u00e9 chiamava un\u2019amica col padre in ospedale: essendosi dimenticata di chiamarla da casa, lo faceva dal cellulare. \u00abFaux pas!\u00bb, le dicevano loro, newyorkesi, in francese, la lingua del bon ton. Il passo falso, ventisette anni fa, era usare un cellulare, facendo pensare alla tua amica che per te la salute di suo padre fosse cos\u00ec poco importante da non meritare una tranquilla telefonata da casa ma una chiamata cos\u00ec, al volo, tra un impegno e l\u2019altro. Sembrano passati ventisette secoli: quand\u2019\u00e8 l\u2019ultima volta che avete detto a voi stessi \u00abquesta chiamata la faccio da casa\u00bb? \u00c8 un altro mondo.<\/p>\n\n\n\n<p><strong>Il fatto \u00e8 che un mondo nuovo ha bisogno di regole nuove, ma non \u00e8 cos\u00ec semplice, perch\u00e9 le regole hanno bisogno di poggiare su punti fermi, e invece qui \u00e8 tutto in movimento<\/strong>, i confini sono scivolosi, e \u2013 come avrebbe detto il braccio tatuato di quella ragazza sul treno \u2013 \u00e8 tutto un equilibrio sopra la follia.<\/p>\n\n\n\n<p>Si d\u00e0 ancora la mano a qualcuno che s\u2019incontra, per salutarlo? \u00c8 forse decaduto il motivo che aveva creato l\u2019usanza \u2013 mostrare a quel qualcuno che non ho in mano un pugnale con cui intendo accoltellarlo \u2013 ma non so se sia decaduto anche il motivo del disuso: siamo ancora gente che teme i germi altrui, quasi sei anni dopo la pandemia? Dipende: qualcuno s\u00ec e qualcuno no. Come si elaborano nuove regole sociali quando ognuno di noi si percepisce portatore di bisogni specialissimi che \u00e8 dovere di tutti assecondare?<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/12\/Facebook_censura_social.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"425\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/12\/Facebook_censura_social.jpg\" alt=\"\" class=\"wp-image-55337\" style=\"width:424px;height:auto\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/12\/Facebook_censura_social.jpg 640w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/12\/Facebook_censura_social-300x199.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><\/figure><\/div>\n\n\n<p>Vent\u2019anni fa organizzavamo tutti cene, adesso no. \u00c8 perch\u00e9 siamo invecchiati? Anche. \u00c8 perch\u00e9 trovare una sera che vada bene a tutti \u00e8 un incubo, ora che il marted\u00ec io non ho la babysitter, il venerd\u00ec tu hai il padel? Anche. Ma dipende soprattutto dal fatto che non c\u2019\u00e8 pi\u00f9 nessuno che non ti fornisca l\u2019elenco delle cose che non mangia. Sono una cafona io se non chiedo agli ospiti se hanno allergie, intolleranze, convinzioni religiose, diete dimagranti da rispettare, e non preparo poi undici menu differenziati per gli undici commensali? O sono cafoni loro a non fare quel che in epoche pi\u00f9 civili abbiamo fatto sempre quando a cena c\u2019era roba che non ci piaceva: sorridere, spostare la roba nel piatto senza mangiarla, tornare a casa e farci un panino?<\/p>\n\n\n\n<p><strong>Siamo tutti abbastanza vecchi da aver vissuto in anni in cui era considerato d\u2019estrema cafonaggine telefonare mentre la famiglia era a tavola<\/strong>. Per\u00f2 la cafonaggine poteva essere salvifica: la sorella di mio padre telefonava mentre eravamo a pranzo, e questo permetteva a lui di non annoiarsi con moglie e figlia. E neanche con la sorella: lei monologava, lui appoggiava la cornetta sulla panca su cui si trovava l\u2019apparecchio telefonico, andava in cucina, si accendeva una sigaretta, tornava, riprendeva la cornetta, lei stava ancora monologando. Io, che sono figlia unica, ero invidiosissima della sua scusa per alzarsi da tavola.<\/p>\n\n\n\n<p>Tuttavia erano anche anni in cui era perfettamente normale citofonare senza avvisare. Quando leggo che i giovani di oggi sono molto soli e si rifugiano nel telefono e cercano di ovviare alla solitudine rendendo di gruppo attivit\u00e0 che sono sempre state solitarie, come la lettura, io penso alla casa dei miei genitori, dove gli amici si presentavano non invitati. Citofonavano, dicendo \u00abpassavo di qua\u00bb o senza neanche sentire il bisogno di quella specie di scusa, si fermavano a cena. Oggi nessuno si permetterebbe di presentarsi a casa non invitato, e nessuno resterebbe a cena senza aver prima avvisato delle proprie restrizioni alimentari. Oggi, senza avvisare, neanche si telefona: se qualcuno fa squillare una chiamata senza prima un WhatsApp che dica \u00abDisturbo se ti telefono?\u00bb, chiamiamo la buoncostume. Non \u00e8 un\u2019epidemia di solitudine, come leggo ovunque: \u00e8 un\u2019epidemia di gente che, a \u00abposso chiamarti?\u00bb, risponde \u00abscrivi\u00bb.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2026\/02\/Telefono_telefonare_analogico.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"745\" height=\"495\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2026\/02\/Telefono_telefonare_analogico.jpg\" alt=\"\" class=\"wp-image-64263\" style=\"width:467px;height:auto\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2026\/02\/Telefono_telefonare_analogico.jpg 745w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2026\/02\/Telefono_telefonare_analogico-300x199.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2026\/02\/Telefono_telefonare_analogico-595x395.jpg 595w\" sizes=\"auto, (max-width: 745px) 100vw, 745px\" \/><\/a><\/figure><\/div>\n\n\n<p>Ho una conoscente che non conosco: \u00e8 un\u2019altra delle bizzarrie del presente, avere conversazioni costanti con gente che non hai mai visto. I pen pal esistevano anche nel Novecento, ma li avevamo conosciuti al mare o in qualche vacanza studio, li avevamo prima o poi incontrati e poi, per non perderci di vista, eravamo passati alle cartoline e alle lettere. Per non perderci di vista, e perch\u00e9 le interurbane erano costose. Adesso no, <strong>adesso gente che non hai incontrato mai ti scrive in toni confidenziali perch\u00e9 ha visto una foto che ti sei scattata in bagno su Instagram<\/strong>, e nel sottoscala della ragione le \u00e8 rimasta \u2013 dai secoli precedenti \u2013 la contezza che se ho visto il tuo bagno significa che siamo abbastanza intimi da potermi io rivolgere a te in toni amicali.<\/p>\n\n\n\n<p>Comunque, ho questa conoscente che non conosco, ci scriviamo nonostante nessuna delle due abbia visto il bagno dell\u2019altra. Io non metto il bagno su Instagram perch\u00e9 non mi pare interessante, e lei non lo mette perch\u00e9 di mestiere insegna bon ton, e credo che il precetto \u00abnon autoscattarti nello specchio sopra al lavandino facendo vedere alle tue spalle l\u2019asse del gabinetto\u00bb venga ancora prima della prima lezione. Quando la mia sconosciuta conoscente apre il box domande, io mi diverto moltissimo, ma per spiegarvi come funziona il mio divertimento devo prima fare una divagazione sul box domande.<\/p>\n\n\n\n<p>Il box domande \u00e8 una modalit\u00e0 di Instagram utilizzata da chi su Instagram guadagna o da chi \u00e8 molto insicuro. La prima categoria apre il box domande per compiacere il pubblico (che sui social non sta come davanti a un palco ma come davanti a uno specchio): io, pubblico, ti chiedo come devo fare con Tizio che dice di amarmi ma non lascia la moglie (una sorta di posta del cuore \u00e8 l\u2019utilizzo pi\u00f9 diffuso del box domande), tu rispondi a me proprio a me, e io mi sento speciale. La seconda categoria lo apre perch\u00e9 ha bisogno di conferme: ogni volta che chiedi al tuo pubblico d\u2019intervenire, ci sar\u00e0 immancabilmente qualcuno che ti dice che hai i pi\u00f9 favolosi addominali o le pi\u00f9 fantastiche ipotassi del pianeta, e tu di quel qualcuno rilanci l\u2019intervento, in genere dicendo \u00abtroppo buoni, non merito tanti complimenti\u00bb, ma comunque rendendo noto a tutti che i complimenti ti arrivano. Una cafonata impareggiabile.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2026\/02\/social_istagram_cellulare.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"240\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2026\/02\/social_istagram_cellulare.jpg\" alt=\"\" class=\"wp-image-64264\" style=\"width:394px;height:auto\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2026\/02\/social_istagram_cellulare.jpg 320w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2026\/02\/social_istagram_cellulare-300x225.jpg 300w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/><\/a><\/figure><\/div>\n\n\n<p>La mia sconosciuta conoscente il box domande lo apre perch\u00e9 chi la segue va coltivato, sono quelli una minuscola percentuale dei quali magari s\u2019iscriver\u00e0 ai suoi seminari o comprer\u00e0 i suoi manuali. L\u2019economia dell\u2019internet ha un funzionamento delirante: devi dare roba gratis a mille per incassare da uno. E quindi ella chiede se il pubblico abbia domande di bon ton, e il pubblico le ha. Solo che quelle domande non sono, chess\u00f2, che posate devo usare se servo l\u2019orata, o quanti soldi devo mettere nella busta di Natale per il portinaio. Quelle domande sono richieste di rassicurazioni. \u00abIl battesimo di mio figlio \u00e8 di sera, per me \u00e8 pi\u00f9 elegante il nero\u00bb. Cosa rispondi, se sei una docente di bon ton che ha gi\u00e0 detto sette milioni di volte su piattaforme gratuite e a pagamento che il nero solo ai funerali e comunque mai nella vita ai matrimoni o ai battesimi? Non \u00e8 che tu possa dire \u00abper me sei una cafona\u00bb. Ovvio che ti vestirai, tu che hai domandato, come vuoi, ovvio che le buone maniere non sono prescrittive, ma tu stai scrivendo a una che non di codice penale si occupa ma proprio di quello, delle buone maniere che sei determinata a non seguire: per\u00f2 tu vuoi s\u00ec trasgredirle, ma con la benedizione dell\u2019autorit\u00e0.&nbsp;<strong>Che sia cominciato tutto quando i genitori hanno iniziato a comprare i profilattici ai figli, invece di farli passare per l\u2019umiliazione di vergognarsi in farmacia come avevano fatto alla loro et\u00e0?<\/strong><\/p>\n\n\n\n<p>C\u2019\u00e8 una cosa che scrisse Umberto Eco nella primavera del 1990, quando mor\u00ec Greta Garbo. Gli aveva telefonato un giornalista chiedendogli di commentarne la morte, quegli articoli disperatissimi in cui si pensa di poter sostituire un\u2019idea con le parole di qualcuno di famoso. Eco aveva detto, riferiva, le solite banalit\u00e0, una leggenda del cinema, una perdita incolmabile. Il giornalista deluso gli aveva domandato: non avrebbe qualcosa di pi\u00f9 originale? E lui nella sua Bustina di Minerva sbottava: cosa devo dire, cagna e troia, se non moriva l\u2019ammazzavo io? Ci ripenso spessissimo, quando guardo il box domande della mia sconosciuta conoscente, e la gente che le scrive chiedendo la sua benedizione per dire alla cognata che il regalo di compleanno ricevuto era una schifezza. Cosa volete che vi risponda, questa povera donna, \u00abma certo, le dica di vergognarsi, e l\u2019anno prossimo di non osare presentarsi con qualcosa che non sia costoso e sofisticato, anche se per poterselo permettere dovr\u00e0 affamare i figli\u00bb?<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2026\/02\/autobus_trasporti_citta.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"215\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2026\/02\/autobus_trasporti_citta.jpg\" alt=\"\" class=\"wp-image-64265\" style=\"width:454px;height:auto\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2026\/02\/autobus_trasporti_citta.jpg 350w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2026\/02\/autobus_trasporti_citta-300x184.jpg 300w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/><\/a><\/figure><\/div>\n\n\n<p>Il ministro dei trasporti degli Stati Uniti d\u2019America ha detto che si adoperer\u00e0 acciocch\u00e9 tornino i tempi in cui in aereo non si saliva in pigiama. I giornali americani si sono imbizzarriti: certo che c\u2019\u00e8 stato un tempo in cui viaggiavamo in giacca e cravatta, ma era anche un tempo in cui in aereo ci servivano da mangiare con le posate d\u2019argento, non dovevamo vagabondare per ore per l\u2019aeroporto perch\u00e9 il volo era in ritardo e non c\u2019era da sedersi, e a bordo non ci vendevano i biglietti della lotteria (questa l\u2019ho aggiunta io: chiunque abbia preso un low cost in quest\u2019epoca di degradanti voli a poco prezzo sa che la voce che ti vuole vendere i biglietti della lotteria dovrebbe essere rubricata come tortura). Certo che ci mettevamo eleganti, quando un aereo era una circostanza eccezionale. Certo che abbiamo la pretesa di star comodi ora, che in un anno prendiamo pi\u00f9 voli di quanti i nostri genitori ne prendessero in una vita. <strong>\u00c8 una buona notizia, se siamo cafoni: \u00e8 segno di benessere economico. In tempi pi\u00f9 semplici era segno di povert\u00e0, ma ve l\u2019ho detto che son saltati i codici<\/strong>.<\/p>\n\n\n\n<p>Son talmente saltati che il ministro, che essendo americano non capisce granch\u00e9 d\u2019eleganza, sbaglia raccomandazione. La sbaglia rispetto a un\u2019epoca che ha in uggia il concetto di dress code, si tratti di dire agli studenti che non si va a scuola coi jeans strappati o alle adulte che non si va ai battesimi vestite di nero, certo. Ma la sbaglia anche dall\u2019altro lato; la sbaglia perch\u00e9, mi ripeto, i tempi sono ormai troppo complicati per essere gestibili con regole nette. Cent\u2019anni fa un abito formale e uno da lavoro erano ben diversi. Adesso, un pigiama di Gucci o di Olivia von Halle \u00e8 ben pi\u00f9 elegante di un abito da sera d\u2019acrilico. E quindi cosa vuoi, sui tuoi voli affollati e ritardatari: gente con lo strascico ma tessuti non traspiranti, o gente che si pu\u00f2 permettere di stare costosamente comoda? E, se una volta stabilita la nuova regola, poi qualcuno facesse trapelare quei messaggi con cui il ministro irrideva un passeggero malvestito chattando con la moglie?&nbsp;<strong>L\u2019internet \u00e8 scritta a penna, ma il bon ton \u00e8 ormai tracciabile solo a matita, e soggetto a continue correzioni<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lisander\u00a0 22 Dicembre 2025 di Guia Soncini Quando \u00e8 cominciata l\u2019epoca in cui viviamo? Direi nell\u2019autunno del 2010, quando \u00e8 uscito un film di quel genere che avrebbe poi quasi monopolizzato l\u2019industria dello spettacolo negli anni successivi: biografie (o episodi di cronaca) rielaborate in finzioni narrative. In quel film l\u00ec,&nbsp;The social network, Mark Zuckerberg era &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/che-fine-hanno-fatto-le-buone-maniere\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":64266,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[2127,208],"class_list":["post-64262","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-costume","tag-buona-educazione","tag-galateo","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Che fine hanno fatto le buone maniere? - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Che fine hanno fatto le buone maniere? Quando \u00e8 cominciata l\u2019epoca in cui viviamo? La maleducazione via social\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/che-fine-hanno-fatto-le-buone-maniere\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Che fine hanno fatto le buone maniere? - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Che fine hanno fatto le buone maniere? Quando \u00e8 cominciata l\u2019epoca in cui viviamo? La maleducazione via social\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/che-fine-hanno-fatto-le-buone-maniere\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-12T00:05:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2026\/02\/galateo_educazione.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"612\" \/>\n\t<meta property=\"og:image:height\" content=\"396\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"17 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/che-fine-hanno-fatto-le-buone-maniere\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/che-fine-hanno-fatto-le-buone-maniere\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Che fine hanno fatto le buone maniere?\",\"datePublished\":\"2026-02-12T00:05:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/che-fine-hanno-fatto-le-buone-maniere\\\/\"},\"wordCount\":2797,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/che-fine-hanno-fatto-le-buone-maniere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/galateo_educazione.jpg\",\"keywords\":[\"buona educazione\",\"galateo\"],\"articleSection\":[\"Costume\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/che-fine-hanno-fatto-le-buone-maniere\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/che-fine-hanno-fatto-le-buone-maniere\\\/\",\"name\":\"Che fine hanno fatto le buone maniere? - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/che-fine-hanno-fatto-le-buone-maniere\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/che-fine-hanno-fatto-le-buone-maniere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/galateo_educazione.jpg\",\"datePublished\":\"2026-02-12T00:05:00+00:00\",\"description\":\"Che fine hanno fatto le buone maniere? Quando \u00e8 cominciata l\u2019epoca in cui viviamo? La maleducazione via social\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/che-fine-hanno-fatto-le-buone-maniere\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/che-fine-hanno-fatto-le-buone-maniere\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/che-fine-hanno-fatto-le-buone-maniere\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/galateo_educazione.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/galateo_educazione.jpg\",\"width\":612,\"height\":396,\"caption\":\"Drunken man raises his hands to the top, thanking him for a bottle of wine - 1896\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/che-fine-hanno-fatto-le-buone-maniere\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Che fine hanno fatto le buone maniere?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Che fine hanno fatto le buone maniere? - Rassegna Stampa Cattolica","description":"Che fine hanno fatto le buone maniere? Quando \u00e8 cominciata l\u2019epoca in cui viviamo? La maleducazione via social","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/che-fine-hanno-fatto-le-buone-maniere\/","og_locale":"it_IT","og_type":"article","og_title":"Che fine hanno fatto le buone maniere? - Rassegna Stampa Cattolica","og_description":"Che fine hanno fatto le buone maniere? Quando \u00e8 cominciata l\u2019epoca in cui viviamo? La maleducazione via social","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/che-fine-hanno-fatto-le-buone-maniere\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2026-02-12T00:05:00+00:00","og_image":[{"width":612,"height":396,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2026\/02\/galateo_educazione.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"17 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/che-fine-hanno-fatto-le-buone-maniere\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/che-fine-hanno-fatto-le-buone-maniere\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Che fine hanno fatto le buone maniere?","datePublished":"2026-02-12T00:05:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/che-fine-hanno-fatto-le-buone-maniere\/"},"wordCount":2797,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/che-fine-hanno-fatto-le-buone-maniere\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2026\/02\/galateo_educazione.jpg","keywords":["buona educazione","galateo"],"articleSection":["Costume"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/che-fine-hanno-fatto-le-buone-maniere\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/che-fine-hanno-fatto-le-buone-maniere\/","name":"Che fine hanno fatto le buone maniere? - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/che-fine-hanno-fatto-le-buone-maniere\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/che-fine-hanno-fatto-le-buone-maniere\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2026\/02\/galateo_educazione.jpg","datePublished":"2026-02-12T00:05:00+00:00","description":"Che fine hanno fatto le buone maniere? Quando \u00e8 cominciata l\u2019epoca in cui viviamo? La maleducazione via social","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/che-fine-hanno-fatto-le-buone-maniere\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/che-fine-hanno-fatto-le-buone-maniere\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/che-fine-hanno-fatto-le-buone-maniere\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2026\/02\/galateo_educazione.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2026\/02\/galateo_educazione.jpg","width":612,"height":396,"caption":"Drunken man raises his hands to the top, thanking him for a bottle of wine - 1896"},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/che-fine-hanno-fatto-le-buone-maniere\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Che fine hanno fatto le buone maniere?"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/64262","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=64262"}],"version-history":[{"count":1,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/64262\/revisions"}],"predecessor-version":[{"id":64267,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/64262\/revisions\/64267"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/64266"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=64262"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=64262"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=64262"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}