{"id":64232,"date":"2026-02-05T01:08:00","date_gmt":"2026-02-05T00:08:00","guid":{"rendered":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=64232"},"modified":"2026-02-04T10:27:44","modified_gmt":"2026-02-04T09:27:44","slug":"davos-la-realta-irrompe-sulla-montagna-incantata-del-globalismo","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/davos-la-realta-irrompe-sulla-montagna-incantata-del-globalismo\/","title":{"rendered":"Davos, la realt\u00e0 irrompe sulla montagna incantata del globalismo"},"content":{"rendered":"\n<p class=\"has-text-align-center\"><strong><a href=\"https:\/\/www.nicolaporro.it\/\" target=\"_blank\" rel=\"noreferrer noopener\">Atlantico<\/a><\/strong> 2 Febbraio 2026<\/p>\n\n\n\n<p><em>Ritorno della storia e della politica tradizionali, messo alle corde il mondo incantato e irreale (ma che ha fatto danni molto reali) del globalismo astratto e dei suoi esperti<\/em><\/p>\n\n\n\n<p class=\"has-text-align-center\">di <strong><a href=\"https:\/\/www.nicolaporro.it\/autori\/fabrizio-borasi\/\" target=\"_blank\" rel=\"noreferrer noopener\">Fabrizio Borasi<\/a><\/strong><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/11\/Davos_reset.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/11\/Davos_reset-1024x576.jpg\" alt=\"\" class=\"wp-image-49297\" style=\"width:460px;height:auto\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/11\/Davos_reset-1024x576.jpg 1024w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/11\/Davos_reset-300x169.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/11\/Davos_reset-768x432.jpg 768w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/11\/Davos_reset.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/div>\n\n\n<!--more-->\n\n\n\n<p>Ci\u00f2 che \u00e8 avvenuto negli scorsi giorni durante lo svolgimento della riunione annuale del <em>World Economic Forum<\/em> tenutasi nella cittadina turistica di Davos, nelle Alpi svizzere, \u00e8 stato il segnale di <strong>come \u00e8 cambiato il mondo<\/strong> negli ultimi anni.<\/p>\n\n\n\n<h4 class=\"wp-block-heading has-text-align-center\"><strong>Gli \u201cilluminati\u201d di Davos<\/strong><\/h4>\n\n\n\n<p>La riunione di Davos, alla quale da sempre partecipano alcuni dei maggiori esperti in campo economico e finanziario, nonch\u00e9 i responsabili delle pi\u00f9 importanti istituzioni internazionali sia pubbliche che private che operano in quei settori, ha rappresentato per decenni una sorta di vetrina delle migliori idee in materia e al tempo stesso un modello da seguire al quale i rappresentanti degli stati, anch\u2019essi sempre presenti alle suddette riunioni, erano <strong>\u201cmoralmente\u201d tenuti ad adeguarsi<\/strong>.<\/p>\n\n\n\n<p>Essa ha rappresentato per anni il <strong>fiore all\u2019occhiello della globalizzazione<\/strong>, il luogo dove venivano indicati gli obiettivi da raggiungere e le strade da percorrere per realizzare il mondo nuovo, il mondo perfetto che doveva seguire la fine della storia tradizionale, e in particolare la fine della storia dei Paesi occidentali, dominata dalle decisioni politiche degli stati sovrani.<\/p>\n\n\n\n<p>Naturalmente le riunioni di Davos sono sempre state un concentrato di idee competenti e profonde, ma come sempre accade, quando le stesse non sono basate sul principio del miglioramento empirico e verificabile della realt\u00e0, ma su quello della sua <strong>radicale e definitiva trasformazione<\/strong>, le stesse hanno inevitabilmente assunto un valore astratto, legato pi\u00f9 ai numeri e alle statistiche che alla realt\u00e0 concreta e alle societ\u00e0 fatte di uomini in carne ed ossa.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2026\/02\/T.Mann_cover.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"671\" height=\"1024\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2026\/02\/T.Mann_cover-671x1024.jpg\" alt=\"\" class=\"wp-image-64233\" style=\"width:209px;height:auto\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2026\/02\/T.Mann_cover-671x1024.jpg 671w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2026\/02\/T.Mann_cover-197x300.jpg 197w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2026\/02\/T.Mann_cover-768x1172.jpg 768w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2026\/02\/T.Mann_cover-1007x1536.jpg 1007w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2026\/02\/T.Mann_cover-595x908.jpg 595w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2026\/02\/T.Mann_cover.jpg 1024w\" sizes=\"auto, (max-width: 671px) 100vw, 671px\" \/><\/a><\/figure><\/div>\n\n\n<p>Le enunciazioni dei vari esperti ed operatori hanno a loro volta assunto il <strong>tono di dogmi indiscutibili<\/strong>, basati su una forma di \u201cscienza\u201d (economica e sociale) ampiamente staccata dalla realt\u00e0 empirica.<\/p>\n\n\n\n<p>In sostanza la mentalit\u00e0 presente a Davos, con tutto il rispetto per la competenza e le buone intenzioni dei partecipanti \u00e8 sempre stata quella, per usare un termine del pensatore ed economista empirico <strong>Thomas Sowell<\/strong>, degli intellettuali <strong>\u201cunti\u201d o \u201cilluminati\u201d<\/strong>, chiamati ad enunciare una serie di principi da calare nella realt\u00e0, come un calco sulla creta, in genere senza tenere in gran conto dei risultati spesso negativi di tale impostazione.<\/p>\n\n\n\n<p>Insomma era come se, anche fisicamente, i principi del mondo globalista venissero decantati e definiti in maniera pura nell\u2019aria rarefatta delle montagne svizzere per poi essere <strong>calati sui luoghi bassi dell\u2019umanit\u00e0<\/strong>: una mentalit\u00e0 culturale, pi\u00f9 che un atteggiamento psicologico si badi bene, molto pi\u00f9 vicina alle concezioni evolutive della storia di <strong>Karl Marx<\/strong> che a quelle empiriche e concrete di <strong>Adam Smith<\/strong>.<\/p>\n\n\n\n<h4 class=\"wp-block-heading has-text-align-center\"><strong>La montagna incantata<\/strong><\/h4>\n\n\n\n<p>Eppure, a chi avesse voluto coglierlo, esisteva nella tradizione della cultura occidentale, in particolare in quella letteraria, un sorta di avvertimento che avrebbe potuto mettere in guardia rispetto alla <strong>pretesa di calare dall\u2019alto le proprie idee<\/strong>.<\/p>\n\n\n\n<p>Davos, com\u2019\u00e8 noto, costituisce il luogo dove \u00e8 ambientato il capolavoro dello scrittore tedesco <strong>Thomas Mann<\/strong> (1875 \u2013 1955), <em>\u201cLa montagna incantata\u201d<\/em>, pubblicato nel 1924. Il romanzo si svolge negli anni immediatamente precedenti la Prima Guerra Mondiale quando Davos, situata alle pendici del monte Schatzalp che d\u00e0 il titolo al libro, era essenzialmente un luogo di cura per le malattie polmonari e narra le vicende di un gruppo di pazienti di un sanatorio (oggi trasformato in un albergo di lusso) dove lo stesso Mann fu ricoverato insieme alla moglie.<\/p>\n\n\n\n<p>Insieme al protagonista, un giovane tedesco aspirante ingegnere, si concentrano una serie pazienti \u201cintellettuali\u201d, che espongono e dibattono, talora con esiti tragici come una sfida a duello tra due di loro, i massimi principi <strong>destinati a riformare il genere umano<\/strong>, principi non cos\u00ec diversi \u2013 tanto che qualcuno come l\u2019economista britannico <strong>Sephen D. King<\/strong> nel suo libro del 2017 <em>\u201cGrave New World\u201d<\/em> ha provato a fare l\u2019analogia \u2013 da quelli proclamati dagli esperti del <em>World Economic Forum<\/em> nello stesso luogo.<\/p>\n\n\n\n<p>Il romanzo di Mann \u2013 uno dei capolavori della letteratura del XX secolo \u2013 copre sette anni di permanenza nel sanatorio del protagonista, durante i quali il tempo stesso sembra staccarsi e diventare <strong>astratto dalla realt\u00e0<\/strong> per seguire l\u2019onda dei dibattiti, ora pacati ora accesi tra i protagonisti, scorrendo ora lento ora velocissimo.<\/p>\n\n\n\n<h4 class=\"wp-block-heading has-text-align-center\"><strong>Ritorno alla realt\u00e0<\/strong><\/h4>\n\n\n\n<p>Solo alla fine dell\u2019opera con lo scoppio della guerra e la decisione del protagonista di arruolarsi che lo porter\u00e0 a morire in battaglia (anche se la cosa non \u00e8 detta esplicitamente) <strong>la realt\u00e0 irrompe<\/strong> nel mondo astratto ed ideale posto ad un\u2019altitudine superiore a quella della vita quotidiana.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2026\/02\/Trump_Davos_2025.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2026\/02\/Trump_Davos_2025-1024x683.jpg\" alt=\"\" class=\"wp-image-64234\" style=\"width:446px;height:auto\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2026\/02\/Trump_Davos_2025-1024x683.jpg 1024w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2026\/02\/Trump_Davos_2025-300x200.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2026\/02\/Trump_Davos_2025-768x512.jpg 768w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2026\/02\/Trump_Davos_2025-595x397.jpg 595w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2026\/02\/Trump_Davos_2025.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/div>\n\n\n<p>Qualcosa di simile, ma per fortuna di molto meno tragico \u00e8 accaduto durante l\u2019ultima riunione del <em>Word Economic Forum<\/em>: per dirla in sintesi, la politica \u00e8 salita sulla montagna incantata e con la politica sono ritornate la fallibilit\u00e0 umana, la inevitabile divergenza di opinioni e soprattutto \u00e8 <strong>ritornata la storia<\/strong>, che solo la pretesa di perfezione degli esperti aveva avuto la presunzione di mettere da parte.<\/p>\n\n\n\n<p>Forse inevitabilmente, la messa in discussione dei dogmi economici e sociali del&nbsp;<em>Forum<\/em>&nbsp;\u00e8 venuta dagli Stati Uniti, il Paese pi\u00f9 legato di tutti sia alla libert\u00e0 individuale che alla tradizione storica, dove le varie tesi (comprese quelle globaliste) possono avere successo, ma non diventano mai verit\u00e0 assolute e sono <strong>sempre soggette a critica<\/strong>.<\/p>\n\n\n\n<p>Cos\u00ec il mondo della politica, con le sue scelte concrete, spesso non perfette ma basate sul principio del male minore, e con le sue decisioni prese non in base a una propria competenza \u201csuperiore\u201d, ma in forza della responsabilit\u00e0 che ci si assume con esse, ha <strong>spezzato l\u2019incanto del mondo tecnocratico<\/strong>, mettendone in luce gli errori passati e i pericoli futuri.<\/p>\n\n\n\n<h4 class=\"wp-block-heading has-text-align-center\"><strong>La debolezza dei dogmi globalisti<\/strong><\/h4>\n\n\n\n<p>Le pretese equilibrate ma ferme del presidente <strong>Donald Trump<\/strong> (chi scrive spera che si sia ormai compreso che i suoi atteggiamenti da spaccamontagne rappresentano solo delle volute provocazioni) con il loro richiamo alla responsabilit\u00e0 nel campo della difesa militare, o le critiche pi\u00f9 dirette alle scelte economiche europee e alle concezioni globaliste in genere pronunciate dal segretario al commercio <strong>Howard Lutnick<\/strong>, hanno messo in discussione e rivelato la <strong>debolezza a livello concreto di molti dei dogmi globalisti<\/strong>, proclamati negli scorsi anni durante le riunioni di Davos.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/04\/globalizzazione.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"574\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/04\/globalizzazione-1024x574.jpg\" alt=\"\" class=\"wp-image-46836\" style=\"width:460px;height:auto\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/04\/globalizzazione-1024x574.jpg 1024w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/04\/globalizzazione-300x168.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/04\/globalizzazione-768x431.jpg 768w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/04\/globalizzazione.jpg 1300w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/div>\n\n\n<p>Innanzitutto, la fine irreversibile degli stati nazionali, destinati ad essere soppiantati dal mondo unificato in base ai principi del mercato finanziario e ai suoi \u201cspiriti animali\u201d, considerati capaci di produrre ricchezza, benessere ed eguaglianza in tutto il pianeta, livellando le attuali ingiustizie, in base ad una concezione del \u201clibero\u201d mercato globale <strong>non troppo diversa da quella marxista<\/strong> (il che spiega anche le improvvise \u201cconversioni\u201d di molti dal comunismo al presunto liberismo globale avvenute negli scorsi anni).<\/p>\n\n\n\n<p>L\u2019azione del presidente Trump ha indotto anche i Paesi europei ad adottare <strong>un\u2019ottica statale<\/strong>: favorevoli o contrari al rafforzamento della presenza militare americana in Groenlandia i vari stati europei non si sono basati sui mercati e sul loro ruolo invincibile, ma sulle posizioni dei rispettivi governi.<\/p>\n\n\n\n<p>Di fronte al possibile innalzamento dei dazi americani, non si sono levati gli esperti ad affermare che i mercati finanziati avrebbero resi inutili i dazi stessi, ma sono stati minacciati dei contro-dazi: come la si pensi (e chi scrive condivide la sostanza, anche se non i modi, delle azioni del presidente Trump) si tratta di un deciso ritorno della storia tradizionale e della politica, che <strong>mette alle corde il mondo incantato e irreale<\/strong> (ma che ha avuto nel recente passato conseguenze negative molto reali) del globalismo astratto e dei suoi esperti.<\/p>\n\n\n\n<p>Quest\u2019ultimo \u00e8 stato dominante soprattutto in Europa. Per anni le politiche statali e per quanto riguarda i Paesi aderenti all\u2019euro, la politica monetaria della Banca centrale europea si sono basate su <strong>concetti tanto dogmatici quanto astratti<\/strong>: i limiti al debito pubblico, la differenza di prezzo (lo <em>spread<\/em>) sui mercati finanziari dei rispettivi titoli di stato e cose simili hanno rappresentato, anzich\u00e9 degli indicatori utili ma non decisivi ai fini delle scelte politiche, dei veri e propri <em>totem<\/em>, sull\u2019altare dei quali sono state sacrificate le politiche sociali e le scelte economiche dei diversi stati.<\/p>\n\n\n\n<p>Con conseguenze devastanti per molti Paesi, che hanno visto <strong>emigrare le proprie industrie<\/strong> e, cosa che vale anche per l\u2019Italia, hanno visto in parte svanire il benessere frutto dell\u2019industrializzazione portata avanti con fatica negli \u201950 e \u201960, e questo tra gli applausi di molti esperti nonch\u00e9 di politici che vantavano i pregi della concorrenza globale, una concorrenza peraltro sempre \u201cdrogata\u201d dai minori costi di produzione dei beni (derivanti dai minori costi del lavoro) nei Paesi emergenti quali la Cina.<\/p>\n\n\n\n<h4 class=\"wp-block-heading has-text-align-center\"><strong>Due concezioni del potere<\/strong><\/h4>\n\n\n\n<p>Mi sono soffermato un poco pi\u00f9 a lungo sulla differenze tra gli stati Uniti e i Paesi europei, in particolare quelli continentali (la Gran Bretagna, pur ambivalente nella sua politica attuale \u00e8 molto probabile che nel lungo periodo si allinei alle concezioni americane, dato che la comune cultura politica milita a favore di questa soluzione) perch\u00e9 dietro i contrasti avvenuti proprio durante il tradizionalmente molto corretto e unanime forum di Davos, si celano <strong>due concezioni diverse della societ\u00e0<\/strong>, o meglio del rapporto tra \u00e9lites e societ\u00e0.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/11\/America_Usa.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"239\" height=\"211\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/11\/America_Usa.jpg\" alt=\"\" class=\"wp-image-55051\" style=\"width:335px;height:auto\"\/><\/a><\/figure><\/div>\n\n\n<p>Pare che qualche alto burocrate europeo abbia affermato a voce non tanto bassa che tra qualche anno Trump non sar\u00e0 pi\u00f9 al potere, sottintendendo che i burocrati e gli esperti saranno ancora al loro posto. Proprio in questo sta la grande differenza: chi gestisce il potere pubblico anche in campo economico negli Stati Uniti \u00e8 un rappresentante della popolazione e alla popolazione risponde, e forse gi\u00e0 con le elezioni di mezzo termine del prossimo novembre <strong>Trump potrebbe vedere diminuire il suo potere<\/strong>.<\/p>\n\n\n\n<p>In Europa, sia a livello di Unione che in misura crescente a livello di singoli stati,&nbsp;<strong>il potere viene gestito da tecnici<\/strong>&nbsp;che non sono responsabili della loro azione di fronte alla popolazione perch\u00e9 sottratti di diritto o di fatto al giudizio elettorale, e sempre maggiori sono le insofferenze verso l\u2019elezione democratica: si ricordi quanto accaduto in Romania lo scorso anno.<\/p>\n\n\n\n<h4 class=\"wp-block-heading has-text-align-center\"><strong>Declino dell\u2019Europa<\/strong><\/h4>\n\n\n\n<p>Nell\u2019epoca in cui <strong>Thomas Mann<\/strong> ambient\u00f2 il suo romanzo, l\u2019Europa era al massimo del suo successo e del suo potere e gli Usa erano solo una potenza emergente, ma le idee espresse dai personaggi della <em>\u201cMontagna incantata\u201d<\/em> con la loro astrattezza e la loro pretesa di disciplinare le cose umane davano <strong>gi\u00e0 il segno dell\u2019imminente crisi<\/strong> che avrebbe sconvolto il vecchio continente nel XX secolo con le feroci dittature e le due guerre mondiali.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/03\/unione-europea.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"259\" height=\"194\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/03\/unione-europea.jpg\" alt=\"\" class=\"wp-image-28193\" style=\"width:359px;height:auto\"\/><\/a><\/figure><\/div>\n\n\n<p>Da allora l\u2019Europa ha perduto gran parte della sua forza militare, e ha visto <strong>ridimensionare in maniera drastica<\/strong> sia il suo peso politico che quello economico, dato che oggi il primato globale \u00e8 stabilmente americano e per fare riferimento ad un parametro spesso usato (ed abusato) dagli esperti tecnici, un punto di Pil americano in valore assoluto pesa pi\u00f9 del doppio di un punto di Pil dell\u2019Unione europea (anche aggregando i dati spesso contraddittori dei diversi stati).<\/p>\n\n\n\n<p>Lungi da chi scrive dire che gli Stati Uniti sono perfetti, anche oltreoceano vi sono molte cose che non vanno, ma mi augurerei che a mente fredda e lasciando perdere quello spirito di confronto e antiamericano del tutto irragionevole che pervade molti esponenti delle \u00e9lites europee, anche nel vecchio continente si abbandonasse definitivamente la montagna incantata per confrontarsi responsabilmente con la realt\u00e0 empirica: i <strong>dogmi del perfettismo<\/strong>, economico e politico a parere di chi scrive, hanno gi\u00e0 fatto fin troppi danni.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Atlantico 2 Febbraio 2026 Ritorno della storia e della politica tradizionali, messo alle corde il mondo incantato e irreale (ma che ha fatto danni molto reali) del globalismo astratto e dei suoi esperti di Fabrizio Borasi<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/davos-la-realta-irrompe-sulla-montagna-incantata-del-globalismo\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":49297,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[59],"tags":[166,648,2401,2946],"class_list":["post-64232","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tecnocrazia","tag-europa","tag-globalizzazione","tag-stati-uniti","tag-world-economic-found","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Davos, la realt\u00e0 irrompe sulla montagna incantata del globalismo - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Davos, la realt\u00e0 irrompe sulla montagna incantata del globalismo col Ritorno della storia e della politica tradizionali,\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/davos-la-realta-irrompe-sulla-montagna-incantata-del-globalismo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Davos, la realt\u00e0 irrompe sulla montagna incantata del globalismo - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Davos, la realt\u00e0 irrompe sulla montagna incantata del globalismo col Ritorno della storia e della politica tradizionali,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/davos-la-realta-irrompe-sulla-montagna-incantata-del-globalismo\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-05T00:08:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/11\/Davos_reset.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/davos-la-realta-irrompe-sulla-montagna-incantata-del-globalismo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/davos-la-realta-irrompe-sulla-montagna-incantata-del-globalismo\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Davos, la realt\u00e0 irrompe sulla montagna incantata del globalismo\",\"datePublished\":\"2026-02-05T00:08:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/davos-la-realta-irrompe-sulla-montagna-incantata-del-globalismo\\\/\"},\"wordCount\":1892,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/davos-la-realta-irrompe-sulla-montagna-incantata-del-globalismo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Davos_reset.jpg\",\"keywords\":[\"Europa\",\"globalizzazione\",\"Stati Uniti\",\"World Economic Found\"],\"articleSection\":[\"Tecnocrazia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/davos-la-realta-irrompe-sulla-montagna-incantata-del-globalismo\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/davos-la-realta-irrompe-sulla-montagna-incantata-del-globalismo\\\/\",\"name\":\"Davos, la realt\u00e0 irrompe sulla montagna incantata del globalismo - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/davos-la-realta-irrompe-sulla-montagna-incantata-del-globalismo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/davos-la-realta-irrompe-sulla-montagna-incantata-del-globalismo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Davos_reset.jpg\",\"datePublished\":\"2026-02-05T00:08:00+00:00\",\"description\":\"Davos, la realt\u00e0 irrompe sulla montagna incantata del globalismo col Ritorno della storia e della politica tradizionali,\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/davos-la-realta-irrompe-sulla-montagna-incantata-del-globalismo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/davos-la-realta-irrompe-sulla-montagna-incantata-del-globalismo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/davos-la-realta-irrompe-sulla-montagna-incantata-del-globalismo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Davos_reset.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Davos_reset.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/davos-la-realta-irrompe-sulla-montagna-incantata-del-globalismo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Davos, la realt\u00e0 irrompe sulla montagna incantata del globalismo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Davos, la realt\u00e0 irrompe sulla montagna incantata del globalismo - Rassegna Stampa Cattolica","description":"Davos, la realt\u00e0 irrompe sulla montagna incantata del globalismo col Ritorno della storia e della politica tradizionali,","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/davos-la-realta-irrompe-sulla-montagna-incantata-del-globalismo\/","og_locale":"it_IT","og_type":"article","og_title":"Davos, la realt\u00e0 irrompe sulla montagna incantata del globalismo - Rassegna Stampa Cattolica","og_description":"Davos, la realt\u00e0 irrompe sulla montagna incantata del globalismo col Ritorno della storia e della politica tradizionali,","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/davos-la-realta-irrompe-sulla-montagna-incantata-del-globalismo\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2026-02-05T00:08:00+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/11\/Davos_reset.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"12 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/davos-la-realta-irrompe-sulla-montagna-incantata-del-globalismo\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/davos-la-realta-irrompe-sulla-montagna-incantata-del-globalismo\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Davos, la realt\u00e0 irrompe sulla montagna incantata del globalismo","datePublished":"2026-02-05T00:08:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/davos-la-realta-irrompe-sulla-montagna-incantata-del-globalismo\/"},"wordCount":1892,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/davos-la-realta-irrompe-sulla-montagna-incantata-del-globalismo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/11\/Davos_reset.jpg","keywords":["Europa","globalizzazione","Stati Uniti","World Economic Found"],"articleSection":["Tecnocrazia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/davos-la-realta-irrompe-sulla-montagna-incantata-del-globalismo\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/davos-la-realta-irrompe-sulla-montagna-incantata-del-globalismo\/","name":"Davos, la realt\u00e0 irrompe sulla montagna incantata del globalismo - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/davos-la-realta-irrompe-sulla-montagna-incantata-del-globalismo\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/davos-la-realta-irrompe-sulla-montagna-incantata-del-globalismo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/11\/Davos_reset.jpg","datePublished":"2026-02-05T00:08:00+00:00","description":"Davos, la realt\u00e0 irrompe sulla montagna incantata del globalismo col Ritorno della storia e della politica tradizionali,","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/davos-la-realta-irrompe-sulla-montagna-incantata-del-globalismo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/davos-la-realta-irrompe-sulla-montagna-incantata-del-globalismo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/davos-la-realta-irrompe-sulla-montagna-incantata-del-globalismo\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/11\/Davos_reset.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/11\/Davos_reset.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/davos-la-realta-irrompe-sulla-montagna-incantata-del-globalismo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Davos, la realt\u00e0 irrompe sulla montagna incantata del globalismo"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/64232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=64232"}],"version-history":[{"count":1,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/64232\/revisions"}],"predecessor-version":[{"id":64235,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/64232\/revisions\/64235"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/49297"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=64232"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=64232"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=64232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}