{"id":6353,"date":"2014-03-10T09:47:25","date_gmt":"2014-03-10T08:47:25","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=6353"},"modified":"2015-11-10T10:37:52","modified_gmt":"2015-11-10T09:37:52","slug":"e-la-vita-da-dove-viene","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/e-la-vita-da-dove-viene\/","title":{"rendered":"\u201cE la vita da dove viene?\u201d"},"content":{"rendered":"<p style=\"text-align: center;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/03\/vita_origine.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-27285\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/03\/vita_origine.jpg\" alt=\"vita_origine\" width=\"327\" height=\"143\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/03\/vita_origine.jpg 340w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/03\/vita_origine-300x130.jpg 300w\" sizes=\"auto, (max-width: 327px) 100vw, 327px\" \/><\/a>Il Timone<\/strong><\/p>\n<p style=\"text-align: center;\">n.128 dicembre 2013<\/p>\n<p style=\"text-align: justify;\"><em>Agli studenti viene insegnato che \u00e8 quasi tutto chiaro. Ma di fronte a questo sommo enigma la scienza brancola nel buio e si aggrappa alle ipotesi pi\u00f9 improbabili: tra comete &#8220;fecondatici&#8221;, visite di alieni sulla Terra e combinazioni chimiche che ricordano quelle degli antichi alchimisti<\/em><\/p>\n<p style=\"text-align: center;\"><strong>Enzo Pennetta<\/strong><\/p>\n<p style=\"text-align: center;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Ci sono tre grandi domande alle quali la scienza non sa rispondere: la prima \u00e8 quella sull&#8217;origine dell&#8217;Universo, la seconda riguarda l&#8217;origine della vita e la terza l&#8217;origine della coscienza umana e della capacit\u00e0 di comunicazione simbolica. Sulla prima, la scienza non potr\u00e0 mai rispondere, perch\u00e9 per definizione non pu\u00f2 indagare su qualcosa che avviene al di fuori dello spazio e del tempo, sulla terza non pu\u00f2 dire molto perch\u00e9 non sappiamo cosa sia la coscienza, ed \u00e8 infine solo sull&#8217;origine della vita la che scienza non pu\u00f2 sottrarsi al suo compito di dare una risposta.<\/p>\n<p style=\"text-align: justify;\">La spiegazione che viene data nelle scuole \u00e8 che in un brodo primordiale di circa 3,8 miliardi di anni fa vennero a formarsi casualmente le condizioni adatte. A dimostrazione di ci\u00f2, viene riportato un famoso esperimento del biochimico statunitense Stanley Miller che all&#8217;inizio degli anni &#8217;50 produsse un esperimento nel quale, a partire da ipotetiche condizioni dell&#8217;atmosfera primordiale, si sarebbero potuti formare gli elementi base delle proteine, gli aminoacidi. Da quel momento, sempre in modo del tutto casuale, con una serie di combinazioni fortunate sarebbe nata la prima cellula.<\/p>\n<p style=\"text-align: justify;\">Al di l\u00e0 del discutibile ricorso alla fortuna per spiegare un fenomeno naturale, quello che viene taciuto \u00e8 l&#8217;abisso che separa quei semplici componenti del brodo primordiale dalla complessit\u00e0 della prima cellula e cos\u00ec gli studenti resteranno con l&#8217;ingenua convinzione che in fondo l&#8217;origine della vita abbia una spiegazione soddisfacente.<\/p>\n<p style=\"text-align: justify;\"><strong>Il calcolo dell&#8217;improbabilit\u00e0<\/strong><\/p>\n<p style=\"text-align: justify;\">Nessuno dice che dall&#8217;esperimento di Miller sono passati oltre sessant&#8217;anni e che nel frattempo nessun progresso \u00e8 stato fatto nella ricostruzione dell&#8217;origine della vita, nessuno far\u00e0 sapere che la nascita per puro caso della prima cellula \u00e8 cos\u00ec improbabile che negli anni &#8217;80 \u00e8 stata paragonata dal famoso astronomo Fred Hoyle (ateo e quindi non sospettabile di simpatie creazioniste) alla possibilit\u00e0 che un tornado passando su un deposito di rottami possa lasciare assemblato un aereo di linea.<\/p>\n<p style=\"text-align: justify;\">Se nelle nostre scuole gli studenti fossero informati di questi problemi, potrebbero venire a sapere che fu proprio per questa consapevolezza che lo stesso Hoyle fu portato a ipotizzare che l&#8217;Universo fosse eterno e che quindi ci fosse stato un tempo infinito a disposizione affinch\u00e8, anche ci\u00f2 che la matematica indica come fortemente improbabile, possa essere accaduto. E proprio per avere una misura scientifica di quanto fosse improbabile la nascita per puro caso della vita, Hoyle incaric\u00f2 un suo collaboratore, Chandra Wickramasinghe, di calcolare quali fossero matematicamente le probabilit\u00e0 che la prima cellula si fosse formata casualmente.<\/p>\n<p style=\"text-align: justify;\">Il risultato fu impressionante: una su 10<sup>40000<\/sup>, la stessa probabilit\u00e0 che si avrebbe di vincere alla roulette per 25.000 volte di seguito. Ma poich\u00e9 la Terra esiste solamente da 4,5 miliardi di anni, la vita non avrebbe avuto abbastanza tempo per formarsi aspettando il verificarsi di un cos\u00ec incredibile colpo di fortuna e allora Hoyle, per poter chiamare in causa un tempo infinito, fu costretto a dire che la vita sarebbe giunta dallo spazio.<\/p>\n<p style=\"text-align: justify;\">Questa teoria non era in realt\u00e0 nuova: consapevoli della brevit\u00e0 dell&#8217;et\u00e0 della Terra l&#8217;avevano gi\u00e0 proposta tra la fine dell&#8217;800 e l&#8217;inizio del &#8216;900 grandi nomi come Lord Kelvin e il Nobel per la chimica Svante Arrhenius. Ma Fred Hoyle non fu il solo a prendere nuovamente in considerazione l&#8217;ipotesi che la vita fosse giunta dallo spazio; infatti, nel 1972 Francis Crick, che dieci anni prima aveva vinto il Nobel per la scoperta della struttura del DNA, pubblic\u00f2 un articolo nel quale proponeva addirittura una tesi decisamente fantascientifica, quella di una &#8220;panspermia guidata&#8221;.<\/p>\n<p style=\"text-align: justify;\">Analogamente a quanto sostenuto da Hoyle, la vita sulla Terra secondo Crick sarebbe giunta dallo spazio, ma per superare le mortali condizioni che avrebbe dovuto affrontare nel viaggio, essa sarebbe stata trasportata su navi spaziali appositamente costruite da civilt\u00e0 extraterrestri. Si tratta di un&#8217;idea che uno scienziato serio deve avere delle difficolt\u00e0 a proporre pubblicamente, ma proprio l&#8217;aver fatto ricorso a questa ipotesi hollywoodiana dimostra le insormontabili difficolt\u00e0 di fronte alle quali la scienza si \u00e8 trovata cercando di rispondere alle domande sull&#8217;origine della vita.<\/p>\n<p style=\"text-align: justify;\">A pi\u00f9 di trent&#8217;anni dall&#8217;articolo di Francis Crick, l&#8217;ipotesi delle navi spaziali che portarono in tempi remoti la vita sulla Terra \u00e8 stata ripresa da Richard Dawkins, il pi\u00f9 famoso dei divulgatori del darwinismo, il quale nel 2008, in un&#8217;intervista, conferm\u00f2 che probabilmente la vita sul nostro pianeta \u00e8 stata &#8220;seminata&#8221; da una civilt\u00e0 extraterrestre perch\u00e9 \u00abse si osservano i dettagli della biochimica, della biologia molecolare, si pu\u00f2 trovare una specie di firma di un progettista di qualche genere\u00bb.<\/p>\n<p style=\"text-align: justify;\"><strong>Arrivano i marziani<\/strong><\/p>\n<p style=\"text-align: justify;\">Ma, in attesa che queste ipotesi ardite possano essere confermate, una serie di ricercatori ha abbassato il tiro ed \u00e8 tornata a cercare l&#8217;origine della vita senza far ricorso agli extraterrestri, senza per questo rinunciare all&#8217;origine spaziale. In questi ultimi tempi sembra infatti essere scoppiata una nuova moda dei marziani, un po&#8217; una riedizione di quella che alla fine dell&#8217;800 fece puntare i telescopi di tutto il mondo sul pianeta rosso alla ricerca delle tracce di una lontana civilt\u00e0. Adesso che per\u00f2 le sonde spaziali hanno mostrato una superficie desolatamente desertica, anzich\u00e9 gli omini verdi su Marte si cercano le tracce di forme di vita elementari, anzi neanche quelle: ci si accontenta solo di cercare sostanze che per qualche stravagante teoria dovrebbero aver facilitato la nascita della vita.<\/p>\n<p style=\"text-align: justify;\">Ecco dunque giungere le proposte come quella del prof. Steven Benner del The Westheimer Insitute for Science and Technology (Usa), che alla fine del mese di agosto 2013 ha annunciato che la vita \u00e8 arrivata da Marte e che quindi noi siamo i marziani. Il motivo di tale conclusione \u00e8 nel fatto che sul pianeta rosso \u00e8 presente l&#8217;elemento molibdeno in forma ossidata che, sempre secondo il prof. Benner, sarebbe in grado di facilitare la nascita della vita. Superfluo specificare che nei laboratori il molibdeno ossidato non ha mai portato alla nascita di alcunch\u00e9.<\/p>\n<p style=\"text-align: justify;\">Negli stessi giorni veniva riportata la notizia che C. T. Adcock, E. M. Hausrath e R M. Forster, autori di uno studio pubblicato su\u00a0<em>Nature,\u00a0<\/em>avevano invece indicato sempre Marte come origine della vita, ma per un altro motivo, questa volta non per la presenza di molibdeno ossidato, bens\u00ec per quella di fosfati. Anche in questo caso, inutile sottolineare che in nessun laboratorio la presenza di fosfati \u00e8 sufficiente a generare nulla che ricordi anche lontanamente una cellula.<\/p>\n<p style=\"text-align: justify;\"><strong>Ferro e zolfo: la nuova Pietra filosofale<\/strong><\/p>\n<p style=\"text-align: justify;\">Tra gli scienziati impegnati nella ricerca delle origini della vita, va ricordata anche la giovane promessa statunitense Sheref S. Mansy, conosciuto anche come &#8220;Million dollar man&#8221; per essere riuscito a farsi finanziare dalla Simons Foundation di New York per ben due volte con la cifra di un milione di dollari che ha poi portato in dote presso l&#8217;Universit\u00e0 degli studi di Trento. Stavolta non verr\u00e0 chiamato in causa Marte: Mansy, a differenza degli altri, non vede il mistero dell&#8217;origine della vita n\u00e9 nel molibdeno n\u00e9 nei fosfati; il ricercatore statunitense \u00e8 invece convinto che il segreto della vita sia da cercare nel ferro e nello zolfo, elementi importanti per i processi metabolici, ma anch&#8217;essi del tutto insufficienti a generare niente che si possa definire vivente.<\/p>\n<p style=\"text-align: justify;\">Sul comunicato stampa dell&#8217;Universit\u00e0 di Trento che annuncia il secondo finanziamento per i lavori di Mansy si legge una curiosa affermazione: \u00abAgli occhi del saggio il ferro \u00e8 incomparabilmente pi\u00f9 nobile dell&#8217;oro&#8230; contiene molto zolfo stabile, di un colore rosso scuro&#8230;, scriveva Fulcanelli, l&#8217;ultimo famoso alchimista del XX secolo intuendo il ruolo chiave di questi due elementi per la nascita della vita\u00bb.<\/p>\n<p style=\"text-align: justify;\">Molibdeno, fosforo, ferro e zolfo sono elementi che non possono davvero spiegare nulla riguardo l&#8217;origine della vita, ma che finiscono col rendere queste moderne ricerche delle nuove versioni dell&#8217;alchimia rinascimentale; i nuovi alchimisti cercano invano di trasformare gli elementi naturali in materia vivente allo stesso modo in cui quelli antichi cercavano di ottenere la Pietra Filosofale per trasformare il piombo in oro.<\/p>\n<p style=\"text-align: justify;\">E cos\u00ec, persa tra storie improbabili come quelle su comete portatrici di vita, di alieni sulle loro navi spaziali e di alchimisti alla ricerca della Pietra Filosofale, l&#8217;origine della vita continua a essere un mistero. Ma agli studenti sar\u00e0 insegnato che abbiamo capito quasi tutto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Timone n.128 dicembre 2013 Agli studenti viene insegnato che \u00e8 quasi tutto chiaro. Ma di fronte a questo sommo enigma la scienza brancola nel buio e si aggrappa alle ipotesi pi\u00f9 improbabili: tra comete &#8220;fecondatici&#8221;, visite di alieni sulla Terra e combinazioni chimiche che ricordano quelle degli antichi alchimisti Enzo Pennetta<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/e-la-vita-da-dove-viene\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":27285,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[261,292],"class_list":["post-6353","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-scienza","tag-scienza-2","tag-vita","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u201cE la vita da dove viene?\u201d - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/e-la-vita-da-dove-viene\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201cE la vita da dove viene?\u201d - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/e-la-vita-da-dove-viene\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2014-03-10T08:47:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-11-10T09:37:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/03\/vita_origine.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"340\" \/>\n\t<meta property=\"og:image:height\" content=\"148\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/e-la-vita-da-dove-viene\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/e-la-vita-da-dove-viene\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"\u201cE la vita da dove viene?\u201d\",\"datePublished\":\"2014-03-10T08:47:25+00:00\",\"dateModified\":\"2015-11-10T09:37:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/e-la-vita-da-dove-viene\\\/\"},\"wordCount\":1414,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/e-la-vita-da-dove-viene\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/03\\\/vita_origine.jpg\",\"keywords\":[\"scienza\",\"vita\"],\"articleSection\":[\"Scienza\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/e-la-vita-da-dove-viene\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/e-la-vita-da-dove-viene\\\/\",\"name\":\"\u201cE la vita da dove viene?\u201d - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/e-la-vita-da-dove-viene\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/e-la-vita-da-dove-viene\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/03\\\/vita_origine.jpg\",\"datePublished\":\"2014-03-10T08:47:25+00:00\",\"dateModified\":\"2015-11-10T09:37:52+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/e-la-vita-da-dove-viene\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/e-la-vita-da-dove-viene\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/e-la-vita-da-dove-viene\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/03\\\/vita_origine.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/03\\\/vita_origine.jpg\",\"width\":340,\"height\":148},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/e-la-vita-da-dove-viene\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201cE la vita da dove viene?\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u201cE la vita da dove viene?\u201d - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/e-la-vita-da-dove-viene\/","og_locale":"it_IT","og_type":"article","og_title":"\u201cE la vita da dove viene?\u201d - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/e-la-vita-da-dove-viene\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2014-03-10T08:47:25+00:00","article_modified_time":"2015-11-10T09:37:52+00:00","og_image":[{"width":340,"height":148,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/03\/vita_origine.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/e-la-vita-da-dove-viene\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/e-la-vita-da-dove-viene\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"\u201cE la vita da dove viene?\u201d","datePublished":"2014-03-10T08:47:25+00:00","dateModified":"2015-11-10T09:37:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/e-la-vita-da-dove-viene\/"},"wordCount":1414,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/e-la-vita-da-dove-viene\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/03\/vita_origine.jpg","keywords":["scienza","vita"],"articleSection":["Scienza"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/e-la-vita-da-dove-viene\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/e-la-vita-da-dove-viene\/","name":"\u201cE la vita da dove viene?\u201d - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/e-la-vita-da-dove-viene\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/e-la-vita-da-dove-viene\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/03\/vita_origine.jpg","datePublished":"2014-03-10T08:47:25+00:00","dateModified":"2015-11-10T09:37:52+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/e-la-vita-da-dove-viene\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/e-la-vita-da-dove-viene\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/e-la-vita-da-dove-viene\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/03\/vita_origine.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/03\/vita_origine.jpg","width":340,"height":148},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/e-la-vita-da-dove-viene\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"\u201cE la vita da dove viene?\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/6353","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=6353"}],"version-history":[{"count":7,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/6353\/revisions"}],"predecessor-version":[{"id":27287,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/6353\/revisions\/27287"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/27285"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=6353"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=6353"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=6353"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}