{"id":61251,"date":"2024-09-22T18:16:49","date_gmt":"2024-09-22T16:16:49","guid":{"rendered":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=61251"},"modified":"2024-09-22T18:16:51","modified_gmt":"2024-09-22T16:16:51","slug":"ll-modernismo-nella-chiesa","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ll-modernismo-nella-chiesa\/","title":{"rendered":"<i>ll modernismo nella Chiesa <\/i>"},"content":{"rendered":"<p style=\"text-align: center;\"><span style=\"color: #0000ff;\"><strong><a style=\"color: #0000ff;\" href=\"https:\/\/www.informazionecattolica.it\/\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-44189 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/08\/modernismo-277x300.jpg\" alt=\"Modernismo eresia del XX secolo\" width=\"221\" height=\"239\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/08\/modernismo-277x300.jpg 277w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/08\/modernismo-768x832.jpg 768w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/08\/modernismo-945x1024.jpg 945w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/08\/modernismo.jpg 1200w\" sizes=\"auto, (max-width: 221px) 100vw, 221px\" \/>InFormazione cattolica<\/a><\/strong><\/span> <span style=\"color: #000000;\">17 Settembre 2021 <\/span><\/p>\n<h4 style=\"text-align: center;\"><strong>Possiamo parlare di un modernismo prima del modernismo? <\/strong>\u00a0<\/h4>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\"><em>Modernismo e \u201cspirito modernista\u201d<\/em> <\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\">di <strong>Aurelio Porfiri<\/strong> <\/span><\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Abbiamo visto in precedenza come il modernismo sia un movimento complesso, difficilmente riconducibile ad uno stesso autore. Proprio perch\u00e9 esso si presenta come l\u2019insieme di diverse eresie, metterlo tutto sotto un cappello \u00e8 difficile, anche se possiamo, come fece san Pio X, vederne un intento comune nell\u2019accomodamento della Chiesa alla mentalit\u00e0 moderna, proprio quella mentalit\u00e0 che si presenta nelle sue premesse e nei suoi fini opposta alla visione Cristiana.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-54460 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/07\/Pio_X_chiesa_modernismo.jpg\" alt=\"\" width=\"216\" height=\"270\" \/>Ecco allora che possiamo guardare a dei filoni di pensiero, anche di autori che poi giudicheremmo in parte buoni, come preparazione di quel coacervo di idee che si concretizzer\u00e0 in senso storico nella battaglia che contro di esse ingaggi\u00f2 san Pio X, ma che in realt\u00e0 non \u00e8 certo finita l\u00ec, come lo stesso Pontefice aveva ben capito.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Alcuni autori distinguono fra modernismo e spirito modernista.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Se il primo lo possiamo collocare nel periodo di cui sopra, lo spirito modernista \u00e8 defluito nelle vene della Chiesa per secoli e secoli. \u00c8 stata una costante lotta fra bene e male, una battaglia che andr\u00e0 avanti fino alla consumazione dei tempi. Lo spirito modernista ha informato vari autori, anche di statura intellettuale eccelsa e spesso con le migliori intenzioni: tutti coloro che hanno inteso prostrare la sana Tradizione ad una malsana idea di progresso.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Quindi non ci si dovr\u00e0 sorprendere di trovare nomi che non ci si aspetterebbe, essi testimoniano che la battaglia fu spesso combattuta non solo in campo aperto, ma anche fronteggiando il fuoco amico. Eppure questa battaglia campale \u00e8 veramente quella decisiva, quella in cui dovremo con coraggio prendere le armi ed avventurarci sul fronte, se riteniamo che non vogliamo solo difendere un insieme di pratiche e di usi, ma una profonda identit\u00e0 morale e spirituale.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Ed \u00e8 proprio quello che ci appresteremo a fare con alcuni prossimi articoli che saranno pubblicati su<\/span> <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/www.informazionecattolica.it\/\" target=\"_blank\" rel=\"noopener\"><em>inFormazione Cattolica<\/em><\/a><\/span>.<\/p>\n<p style=\"text-align: center;\"><strong>__________________________________________<\/strong><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #0000ff;\"><strong><a style=\"color: #0000ff;\" href=\"https:\/\/www.informazionecattolica.it\/\" target=\"_blank\" rel=\"noopener\">InFormazione Cattolica<\/a><\/strong> <span style=\"color: #000000;\">31 Ottobre 2021<\/span><\/span><\/p>\n<h4 style=\"text-align: center;\"><span style=\"color: #000000;\"><strong>Il modernismo: da dove viene e dove va<\/strong><\/span><\/h4>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><em>ll modernismo, al contrario di quello che si pu\u00f2 pensare, non cresce dal nulla ma si sviluppa da vari filoni di pensiero che sar\u00e0 utile investigare andando a scovare alcuni pensatori del passato\u2026<\/em><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\">di <strong>Aurelio Porfiri<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-61252 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2024\/09\/Fogazzaro_cover.jpg\" alt=\"\" width=\"154\" height=\"274\" \/>Forse non molti sono a conoscenza di quel complesso fenomeno che va sotto il nome di modernismo. Gli storici lo fanno coincidere, con molte difficolt\u00e0, con il papato di san Pio X (1903-1914) anche se ben si conosce come lo stesso fenomeno si sia esteso ben pi\u00f9 in l\u00e0 di quella data, costantemente trasformandosi nei campi pi\u00f9 vari fino ad avere una influenza fondamentale sullo sviluppo della Chiesa fino ai nostri giorni.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Ma cosa \u00e8 il modernismo? \u00c8 l\u2019<em>accomodamento<\/em> della Chiesa al mondo moderno. Ma non \u00e8 questa una cosa buona? Certo la Chiesa deve adattare alcune sue azioni ai soggetti della sua evangelizzazione, ma quando essa sembra arrendersi ad una mentalit\u00e0 del mondo che la corrode dall\u2019interno, ecco che il modernismo compie la sua azione distruttrice, pur se da alcuni portata avanti con le migliori intenzioni.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Nel romanzo \u201c<em>Il santo<\/em>\u201d (1905) di Antonio Fogazzaro (1842-1911), si prefigurava questa azione di cambiamento interno alla Chiesa. In una riunione di \u201cmodernisti\u201d (anche se loro non si sarebbero definiti tali) era detto: \u00ab<em>Ecco \u2013 diss\u2019egli \u2013 siamo parecchi cattolici, in Italia e fuori d\u2019Italia, ecclesiastici e laici, che desideriamo una riforma della Chiesa. La desideriamo senza ribellioni, operata dall\u2019autorit\u00e0 legittima. Desideriamo riforme dell\u2019insegnamento religioso, riforme del culto, riforme della disciplina del clero, riforme anche nel supremo governo della Chiesa. Per questo abbiamo bisogno di creare un\u2019opinione che induca l\u2019autorit\u00e0 legittima ad agire di conformit\u00e0 sia pure fra venti, trenta, cinquant\u2019anni. Ora noi che pensiamo cosi siamo affatto disgregati. Non sappiamo l\u2019uno dell\u2019altro, eccetto i pochi che pubblicano articoli o libri. Molto probabilmente vi \u00e8 nel mondo cattolico una grandissima quantit\u00e0 di persone religiose e colte che pensano come noi. Io ho pensato che sarebbe utilissimo, per la propaganda delle nostre idee, almeno di conoscerci. Stasera ci si riunisce in pochi per una prima intesa<\/em>\u00bb.<\/span><\/p>\n<div id=\"attachment_45837\" style=\"width: 194px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-45837\" class=\"wp-image-45837 size-full\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/01\/Ernesto_Bonaiuti_modernismo.jpg\" alt=\"\" width=\"194\" height=\"259\" \/><p id=\"caption-attachment-45837\" class=\"wp-caption-text\">Ernesto Bonaiuti<\/p><\/div>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Del resto, Ernesto Buonaiuti (1881-1946), uno dei principali esponenti del modernismo, diceva che non bisognava conquistare la Chiesa <em>contro<\/em> Roma, ma <em>con<\/em> Roma.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Ma il modernismo, al contrario di quello che pu\u00f2 essere supposto, non cresce dal nulla e anzi si sviluppa da vari filoni di pensiero che sar\u00e0 utile investigare andando a scovare alcuni pensatori del passato.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Pensatori, sia detto chiaramente, che a volte hanno contribuito con intenzioni totalmente opposte. Eppure riteniamo che solo andando ad investigare indietro nel tempo, incontrando questi protagonisti del pensiero filosofico e teologico, possiamo capire da dove viene il modernismo e ben intravedere dove \u00e8 diretto, perch\u00e9 la sua parabola non \u00e8 certo conclusa. Ed \u00e8 proprio quello che, con timore e tremore, ci appresteremo a fare con alcuni prossimi articoli che saranno pubblicati su<\/span> <a href=\"https:\/\/www.informazionecattolica.it\/\" target=\"_blank\" rel=\"noopener\"><em>inFormazione Cattolica<\/em><\/a>.<\/p>\n<p style=\"text-align: center;\"><strong>__________________________________________<\/strong><\/p>\n<p style=\"text-align: center;\"><strong><a href=\"https:\/\/www.informazionecattolica.it\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">InFormazione cattolica<\/span><\/a><\/strong> <span style=\"color: #000000;\">9 Novembre 2021<\/span><\/p>\n<h4 style=\"text-align: center;\"><span style=\"color: #000000;\"><strong>Il modernismo \u00e8 un\u2019eresia?<\/strong><\/span><\/h4>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\"><em>L\u2019idea che, paradossalmente, il modernismo non \u00e8 moderno, \u00e8 veramente corretta<\/em><em>\u2026<\/em><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\">di <strong>Aurelio Porfiri<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-41331 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/11\/Sacra_Famiglia.jpg\" alt=\"\" width=\"225\" height=\"225\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/11\/Sacra_Famiglia.jpg 225w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/11\/Sacra_Famiglia-150x150.jpg 150w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/>Sembrer\u00e0 strano che ci si possa porre la domanda se il modernismo, il tentativo di accomodare la dottrina alla mentalit\u00e0 moderna, senza considerare quanto in questa mentalit\u00e0 vi \u00e8 di antitetico alla dottrina stessa, possa essere considerato un\u2019eresia.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Se guardiamo alla storia delle eresie, ci rendiamo conto quanto molte di esse siano una preparazione al modernismo. Gi\u00e0 nel primo secolo dell\u2019era Cristiana possiamo osservare gli ebioniti all\u2019opera, che credevano a Ges\u00f9 non come figlio di Dio ma come figlio di Giuseppe e Maria, e che al massimo sarebbe stato adottato dal Padre (adozionismo). Questo rifiuto del carattere divino di Ges\u00f9 sar\u00e0 presente in alcuni filoni del modernismo e prender\u00e0 varie forme, grazie all\u2019uso mirato del metodo storico-critico per l\u2019esegesi biblica.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Quindi, ritornando alla domanda da cui siamo partiti, dobbiamo avere la consapevolezza che il modernismo non fu di per s\u00e9 un\u2019eresia singola, ma un coacervo di tante eresie, fu la manifestazione di un \u201cfocolaio ereticale\u201d che non solo non si \u00e8 spento, ma ha viaggiato sotto traccia per arrivare fino a noi.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-61253 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2024\/09\/modernismo.jpg\" alt=\"\" width=\"267\" height=\"400\" \/>In un lavoro del 1908, il padre Norbert Jones cos\u00ec poteva osservare: \u201c<em>Il modernismo, visto dai suoi fondamenti non filosofici, non \u00e8 n\u00e9 moderno n\u00e9 cattolico, ma \u00e8 l\u2019opposto di entrambi. Come pu\u00f2 essere definito moderno quando \u00e8 pi\u00f9 simile a uno struzzo adornato con piume di pavone e fa s\u00ec che le persone credulone lo prendano per un pavone?\u00a0La filosofia di Kant \u00e8 piuttosto antica, quasi due secoli, e ha preso in prestito il suo sistema da Celso e Porfirio, molto tempo fa confutato dai dotti filosofi della Chiesa cattolica. Prendere il sistema di Immanuel Kant e nasconderlo sotto la nuova verbosit\u00e0 modernista, pu\u00f2 passare come originale e intelligente a menti superficiali, ma per qualsiasi neofita in filosofia non \u00e8 n\u00e9 originale n\u00e9 in alcun modo un risultato brillante. Non \u00e8 tutto oro quello che luccica. \u00c8 scambiato sotto un\u2019etichetta molto falsa. L\u2019etichetta \u00e8 eccellente; nessuno potrebbe essere migliore del cattolicesimo. Il modernismo, tuttavia, non ha pi\u00f9 diritto al termine cristiano di quanto non ne abbia il maomettanesimo o l\u2019ebraismo. Assomiglia a un pezzo d\u2019argento tedesco con un marchio di garanzia spurio, o, meglio ancora, \u00e8 come un certo numero di chierici anticonformisti che scrivono D.D. dopo i loro nomi fino a quando non si scopre di non avere diritto al titolo, avendolo ottenuto all\u2019Universit\u00e0 \u2018Bates\u2019<\/em>\u201d (Norbert Jones, <em>Old Truths, Not Modernist Errors Exposure of Modernism and Vindication of its Condemnation by the Pope in Understanding Modernism<\/em>, mia traduzione).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Questa idea che, paradossalmente, il modernismo non \u00e8 moderno, \u00e8 veramente corretta. E pure se Kant sar\u00e0 un momento importante dello stesso, come vedremo, non bisogna fermarsi certo a lui per capirlo.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Allora, riprende vigore la famosa definizione di san Pio X, che nella <em>Pascendi<\/em> (1907) cos\u00ec diceva: \u201c<em>Ora, se quasi di un solo sguardo abbracciamo l\u2019intero sistema, niuno si stupir\u00e0 ove Noi lo definiamo, affermando esser esso la sintesi di tutte le eresie. Certo, se taluno si fosse proposto di concentrare quasi il succo ed il sangue di quanti errori circa la fede furono sinora asseriti, non avrebbe mai potuto riuscire a far meglio di quel che han fatto i modernisti. Questi anzi tanto pi\u00f9 oltre si spinsero che, come gi\u00e0 osservammo, non pure il cattolicesimo ma ogni qualsiasi religione hanno distrutta. Cos\u00ec si spiegano i plausi dei razionalisti: perci\u00f2 coloro, che fra i razionalisti parlano pi\u00f9 franco ed aperto, si rallegrano di non avere alleati pi\u00f9 efficaci dei modernisti<\/em>\u201d.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Ecco, la sintesi di tutte le eresie, fa ben capire la portata della sfida che il modernismo porta alla Chiesa cattolica. Quindi questo ci fa ben capire perch\u00e9 \u00e8 utile studiare questo fenomeno in una prospettiva storica, prima che esso si facesse evidente alla fine del diciannovesimo secolo. Non comincer\u00f2 proprio dall\u2019inizio ma mi rifar\u00f2 a pensatori che, volenti o nolenti, dallo stesso modernismo sono stati usati per ricavarne nutrimento vitale.<\/span><\/p>\n<p style=\"text-align: center;\"><strong>__________________________________________<\/strong><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #0000ff;\"><strong><a style=\"color: #0000ff;\" href=\"https:\/\/www.informazionecattolica.it\/\" target=\"_blank\" rel=\"noopener\">InFormazione cattolica<\/a><\/strong><\/span> 22 Novembre 2021<\/p>\n<h4 style=\"text-align: center;\"><strong>\u00a0<\/strong><span style=\"color: #000000;\"><strong>La falsa idea di purezza dei modernisti<\/strong><\/span><\/h4>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\"><em>Il desiderio di \u201cpurezza\u201d del modernismo contro \u201cle costrizioni del dogma cattolico\u201d ha una lunga storia\u2026<\/em><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\">di<strong> Aurelio Porfiri<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-54463 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/07\/modernismo.jpg\" alt=\"\" width=\"291\" height=\"218\" \/>Nel fenomeno del modernismo concorrano tante idee che poi si coagulano in un certo periodo storico, grazie anche all\u2019attenzione che gli dedic\u00f2 il papa san Pio X, che ben vide come questo complesso movimento andava considerato come \u201csintesi di tutte le eresie\u201d.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Non dimentichiamo che questa \u00e8 una chiave di lettura importante per comprendere tutto il fenomeno, questa esigenza di purificazione storica e spirituale che di per s\u00e9 ci sembra una cosa buona se essa non fosse male indirizzata.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">C\u2019\u00e8 una cattiva comprensione del sistema dogmatico cattolico, che viene visto come una prigione, come rivela il noto modernista gesuita George Tyrrell (1861-1909) nella sua autobiografia: \u201cIl sistema dogmatico semplicemente sigilla la mente invece di aprirla; la rende antipatica e poco intelligente, anzich\u00e9 flessibile e comprensiva\u201d.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Certamente queste idee anti dogmatiche non erano nuove, questo desiderio di purezza contro \u201cle costrizioni del dogma cattolico\u201d ha una lunga storia.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">In effetti potremmo andare indietro di secoli, anche pi\u00f9 di un millennio per identificare le varie eresie che hanno inteso raggiungere una purezza che ritenevano perdita nel cattolicesimo ufficiale, arroccato nella sua dottrina. In fondo l\u2019eresia consiste in questo, nello staccarsi dal cattolicesimo ufficiale per ricongiungersi ad un cattolicesimo ritenuto migliore ma che spesso \u00e8 solo immaginario. In fondo il modernismo sintetizza questo, il tentativo di staccarsi dalla verit\u00e0 per raggiungerne una ancora pi\u00f9 vera.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Ma noi sappiamo che se la Chiesa ancora professa la verit\u00e0 per cui esiste, la sua imperfezione data dagli uomini che la governano non deve spaventarci. La Chiesa, prima che fosse vittima di mode ideologiche, ha praticato sempre un sano realismo, quel realismo per cui sapeva riconoscere le fragilit\u00e0 umane e comunque non perdeva di vista l\u2019obiettivo finale. Con il modernismo e con la situazione che viviamo oggi, sembra che l\u2019obiettivo finale \u00e8 divenuto la fragilit\u00e0 umana.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-7364 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/giovanni_paolo.jpg\" alt=\"\" width=\"235\" height=\"269\" \/>Forse, si \u00e8 equivocato quanto Giovanni Paolo II diceva nel 1979, nella sua<\/span> <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/www.vatican.va\/content\/john-paul-ii\/en\/encyclicals\/documents\/hf_jp-ii_enc_04031979_redemptor-hominis.html\" target=\"_blank\" rel=\"noopener\"><em>Redemptor Hominis<\/em><\/a><\/span>. <span style=\"color: #000000;\">In un passaggio noto affermava: \u201cLa Chiesa non pu\u00f2 abbandonare l\u2019uomo, la cui \u00absorte\u00bb, cio\u00e8 la scelta, la chiamata, la nascita e la morte, la salvezza o la perdizione, sono in modo cos\u00ec stretto ed indissolubile unite al Cristo. E si tratta proprio di ogni uomo su questo pianeta, in questa terra che il Creatore ha dato al primo uomo, dicendo all\u2019uomo e alla donna: \u00abSoggiogatela e dominatela\u00bb. Ogni uomo, in tutta la sua irripetibile realt\u00e0 dell\u2019essere e dell\u2019agire, dell\u2019intelletto e della volont\u00e0, della coscienza e del cuore. L\u2019uomo, nella sua singolare realt\u00e0 (perch\u00e9 \u00e8 \u00abpersona\u00bb), ha una propria storia della sua vita e, soprattutto, una propria storia della sua anima. L\u2019uomo che, conformemente all\u2019interiore apertura del suo spirito ed insieme a tanti e cos\u00ec diversi bisogni del suo corpo, della sua esistenza temporale, scrive questa sua storia personale mediante numerosi legami, contatti, situazioni, strutture sociali, che lo uniscono ad altri uomini, e ci\u00f2 egli fa sin dal primo momento della sua esistenza sulla terra, dal momento del suo concepimento e della sua nascita. L\u2019uomo, nella piena verit\u00e0 della sua esistenza, del suo essere personale ed insieme del suo essere comunitario e sociale \u2013 nell\u2019\u00e0mbito della propria famiglia, nell\u2019\u00e0mbito di societ\u00e0 e di contesti tanto diversi, nell\u2019\u00e0mbito della propria nazione, o popolo (e, forse, ancora solo del clan, o trib\u00f9), nell\u2019\u00e0mbito di tutta l\u2019umanit\u00e0 \u2013 quest\u2019uomo \u00e8 la prima strada che la Chiesa deve percorrere nel compimento della sua missione: egli \u00e8 la prima e fondamentale via della Chiesa, via tracciata da Cristo stesso, via che immutabilmente passa attraverso il mistero dell\u2019Incarnazione e della Redenzione\u201d.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Ecco, se si legge tutto il passaggio credo ben si intende quello che il Papa voleva significare, cio\u00e8 che l\u2019uomo \u00e8 via della Chiesa in quanto questa via \u00e8 tracciata da Cristo stesso, che \u00e8 Via, Verit\u00e0 e Vita. Non che l\u2019uomo \u00e8 il principale obiettivo della Chiesa a prescindere da Cristo e quindi le sue fragilit\u00e0, al di fuori di questa prospettiva, divengono un chiaro ostacolo da eradicare con una idea di purezza che \u00e8 al di fuori del sano realismo cristiano.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Del resto Giovanni Paolo II, nello stesso documento, poco prima aveva affermato: \u201cGes\u00f9 Cristo \u00e8 la via principale della Chiesa. Egli stesso \u00e8 la nostra via \u00aballa casa del Padre\u00bb, ed \u00e8 anche la via a ciascun uomo. Su questa via che conduce da Cristo all\u2019uomo, su questa via sulla quale Cristo si unisce ad ogni uomo, la Chiesa non pu\u00f2 esser fermata da nessuno. Questa \u00e8 l\u2019esigenza del bene temporale e del bene eterno dell\u2019uomo. La Chiesa, per riguardo a Cristo ed in ragione di quel mistero che costituisce la vita della Chiesa stessa, non pu\u00f2 rimanere insensibile a tutto ci\u00f2 che serve al vero bene dell\u2019uomo, cos\u00ec come non pu\u00f2 rimanere indifferente a ci\u00f2 che lo minaccia.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-47902 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/07\/chiesa_concilio_vaticano-300x145.jpg\" alt=\"\" width=\"346\" height=\"167\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/07\/chiesa_concilio_vaticano-300x145.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/07\/chiesa_concilio_vaticano-768x371.jpg 768w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/07\/chiesa_concilio_vaticano-1024x495.jpg 1024w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/07\/chiesa_concilio_vaticano.jpg 1588w\" sizes=\"auto, (max-width: 346px) 100vw, 346px\" \/>Il Concilio Vaticano II, in diversi passi dei suoi documenti, ha espresso questa fondamentale sollecitudine della Chiesa, affinch\u00e9 \u00abla vita nel mondo \u201dsia \u201d pi\u00f9 conforme all\u2019eminente dignit\u00e0 dell\u2019uomo\u00bb in tutti i suoi aspetti, per renderla \u00absempre pi\u00f9 umana\u00bb. Questa \u00e8 la sollecitudine di Cristo stesso, il buon Pastore di tutti gli uomini. In nome di tale sollecitudine \u2013 come leggiamo nella Costituzione pastorale del Concilio \u2013 \u00abla Chiesa che, in ragione del suo ufficio e della sua competenza, in nessuna maniera si confonde con la comunit\u00e0 politica e non \u00e8 legata ad alcun sistema politico, \u00e8 insieme il segno e la salvaguardia del carattere trascendente della persona umana\u00bb\u201d. Insomma, pur se questi passaggi possono prestarsi a qualche fraintendimento, il contesto di quello che il Papa voleva dire mi sembra chiaro.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">\u00c8 vero, la fede \u00e8 esigente, ma si misura sempre con il cuore dell\u2019uomo. Il modernismo, con la sua esigenza di \u201cpurezza\u201d, intendeva servire un uomo astratto, malgrado a loro cos\u00ec non sembrasse.<\/span><\/p>\n<p style=\"text-align: center;\"><strong>__________________________________________<\/strong><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #0000ff;\"><strong><a style=\"color: #0000ff;\" href=\"https:\/\/www.informazionecattolica.it\/\" target=\"_blank\" rel=\"noopener\">InFormazione cattolica<\/a> <\/strong><\/span>29 Novembre 2021<\/p>\n<h4 style=\"text-align: center;\"><span style=\"color: #000000;\"><strong>Il \u201csogno\u201d della Chiesa che verr\u00e0 di Gioacchino da Fiore<\/strong><\/span><\/h4>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\"><em>L\u2019idea, falsa, che ci sar\u00e0 un tempo in cui avremo \u201cla vera Chiesa\u201d, \u00e8 dietro al modernismo e a varie altre eresie <\/em><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\">di<strong> Aurelio Porfiri<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-61254 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2024\/09\/Gioacchino_da_Fore.jpeg\" alt=\"\" width=\"260\" height=\"373\" \/>Non c\u2019\u00e8 dubbio sul fatto che uno dei temi pi\u00f9 importanti per capire il fenomeno del modernismo \u00e8 quello di una distorta idea di purezza, cio\u00e8 che la Chiesa non viene vissuta per quella che \u00e8, cercando di migliorarla, ma per quello che dovrebbe essere o che \u00e8 stata in un passato ricostruito secondo le proprie coordinate ideologiche.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Possiamo trovare un\u2019idea di questo gi\u00e0 nell\u2019opera di Gioacchino da Fiore (1145-1202), un monaco cistercense ed esegeta che avr\u00e0 una importanza da non sottovalutare nelle idee di alcuni modernisti. Si pensi ad Ernesto Buonaiuti (1881-1946), che pubblicher\u00e0 lavori importanti su Gioacchino da Fiore, ai cui studi fu indirizzato anche con il desiderio di tenerlo lontano dall\u2019insegnamento.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Nell\u2019idea di Gioacchino c\u2019\u00e8 quella di una Chiesa che deve venire che sar\u00e0 quella dove finalmente regneranno pace e libert\u00e0: \u201c<em>Fulcro di tutto il pensiero di Gioacchino \u00e8 la considerazione dell\u2019unit\u00e0 e trinit\u00e0 di Dio, pensate non solo nell\u2019interiorit\u00e0 del processo divino, ma anche, e pi\u00f9, nel loro esplicarsi nella realt\u00e0 storica, che va perci\u00f2 intesa come il manifestarsi di una economia provvidenziale, in cui a ogni persona della Trinit\u00e0 corrisponde un\u2019era storica: cos\u00ec al Padre corrisponde l\u2019epoca precedente la venuta di Cristo e il relativo Libro sacro, il Vecchio Testamento; al Figlio l\u2019epoca appunto di Cristo e della Chiesa con il Nuovo Testamento; allo Spirito Santo, un\u2019epoca ancora futura, l\u2019et\u00e0 dello Spirito. Ma come le tre persone trinitarie costituiscono l\u2019unit\u00e0 divina, cos\u00ec le tre epoche sono legate tra loro da una corrispondenza proporzionale, per cui ogni personaggio storico della prima epoca ha l\u2019equivalente, sempre, nella seconda: per es., Abramo e Zaccaria, Sara ed Elisabetta, Isacco e Giovanni Battista, i dodici patriarchi e i dodici apostoli. Questa corrispondenza, chiamata da Gioacchino concordia, gli permette poi d\u2019intravedere le linee fondamentali della terza et\u00e0, che sar\u00e0 et\u00e0 di suprema libert\u00e0, di perfetta carit\u00e0, di completa spiritualit\u00e0. Guida del genere umano nella terza et\u00e0 sar\u00e0 un ordine religioso perfetto (pens\u00f2 ai suoi florensi? Certo i francescani pensarono al proprio ordine), che assorbir\u00e0 in s\u00e9 laici, clero e la stessa gerarchia ecclesiastica, avviando tutti i fedeli alla perfezione cristiana. Una Chiesa cos\u00ec costituita, nella terza et\u00e0, pu\u00f2 certo attendere senza timore la venuta dell\u2019Anticristo, con le terribili persecuzioni che l\u2019accompagneranno, e poi il giudizio di Dio. Profeta di questa nuova Chiesa, sottile ed entusiasta esegeta, Gioacchino esercit\u00f2 grande influenza sui suoi contemporanei, che o lo avversarono fieramente o ne furono ardenti seguaci (gioachimiti)<\/em>\u201d<\/span> (<span style=\"color: #0000ff;\">T<a style=\"color: #0000ff;\" href=\"http:\/\/treccani.it\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">treccani.it<\/span><\/a><\/span>).<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Certamente sono idee di grande fascino quelle del nostro monaco, che non avranno presa soltanto sui suoi contemporanei ma anche su tutti coloro che applicheranno alla Chiesa categorie rivoluzionarie, e i modernisti erano tra questi.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-61255 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2024\/09\/Bonaiuti_cover.jpg\" alt=\"\" width=\"251\" height=\"335\" \/>Cos\u00ec citava Gioacchino da Fiore, il succitato Ernesto Buonaiuti nella sua autobiografia\u00a0<em>Pellegrino di Roma<\/em>: \u201c<em>\u00abTutti i simboli sacramentali contenuti nelle pagine della rivelazione di Dio ci instillano la convinzione dei tre stati. Il primo stato \u00e8 quello durante il quale noi fummo sotto il dominio della Legge; il secondo \u00e8 quello durante il quale noi fummo sotto il dominio della grazia; il terzo \u00e8 quello che noi attendiamo da un giorno all\u2019altro, nel quale ci investir\u00e0 una pi\u00f9 ampia e generosa grazia. Il primo stato visse di conoscenza; il secondo si svolse nel potere della sapienza; il terzo si effonder\u00e0 nella plenitudine dell\u2019intendimento. Nel primo regn\u00f2 il servaggio servile; nel secondo la servit\u00f9 filiale; il terzo dar\u00e0 inizio alla libert\u00e0. Il primo stato trascorse nei flagelli; il secondo nell\u2019azione; il terzo trascorrer\u00e0 nella contemplazione. Il primo visse nell\u2019atmosfera del timore; il secondo in quella della fede; il terzo vivr\u00e0 nella carit\u00e0. Il primo segn\u00f2 l\u2019et\u00e0 dei servi; il secondo l\u2019et\u00e0 dei figli; il terzo non conoscer\u00e0 che amici. Il primo stato fu dominio di vecchi; il secondo di giovani; il terzo sar\u00e0 dominio di fanciulli. Il primo trem\u00f2 sotto l\u2019incerto chiarore delle stelle; il secondo contempl\u00f2 la luce dell\u2019aurora; solo nel terzo sfolgorer\u00e0 il meriggio. Il primo fu un inverno; il secondo un palpitare di primavera; il terzo conoscer\u00e0 la pinguedine dell\u2019estate. Il primo non produsse che ortiche; il secondo diede le rose; solo al terzo appartengono i gigli. Il primo vide le erbe; il secondo lo spuntar delle spighe; il terzo raccoglier\u00e0 il grano. Il primo ebbe in retaggio l\u2019acqua; il secondo il vino; il terzo spremer\u00e0 l\u2019olio. Il primo stato fu tempo di settuagesima; il secondo fu tempo di quaresima; il terzo\u00a0 solo scioglier\u00e0 le campane di Pasqua. In conclusione: il primo stato fu reame del Padre che \u00e8 il creatore dell\u2019universo; il secondo fu reame del Figlio, che si umili\u00f2 ad assumere il nostro corpo di\u00a0 fango; il terzo sar\u00e0 reame dello Spirito Santo, del quale dice l\u2019Apostolo: dove \u00e8 lo Spirito del Signore\u00a0 ivi \u00e8 la libert\u00e0\u00bb<\/em>\u201d.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Buonaiuti poi avvertiva che il sogno di Gioacchino ancora attendeva il suo compimento. Certo, si comprende come i voli di Gioacchino potessero affascinare i suoi contemporanei e come ancora affascinano vari pensatori. Eppure, malgrado il loro valore quasi poetiche, dobbiamo ben guardarci da quello che implicano, disprezzando il cammino storico della Chiesa, certo sempre nel bisogno di convertirsi. Questa idea che ci sar\u00e0 un tempo in cui avremo \u201cla vera Chiesa\u201d qui sulla terra non \u00e8 solo dietro al modernismo, ma a varie altre eresie.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-31610 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/eretici.jpg\" alt=\"\" width=\"393\" height=\"294\" \/>Luca Parisoli<\/span> (in <a href=\"http:\/\/iliesi.cnr.it\/\" target=\"_blank\" rel=\"noopener\">iliesi.cnr.it<\/a>) <span style=\"color: #000000;\">cos\u00ec ci avvicina il nome di Gioacchino con un certo cristianesimo esoterico e con le suggestioni moderniste: \u201c<em>Chi ci racconta la vita di Gioacchino, nei vari secoli che seguono la sua morte, ci parla di un contatto con Dio sul Monte Tabor, ma ci parla anche di successive illuminazioni e visioni che costellano la sua vita: se la retorica del narratore pone sullo stesso livello le varie visioni, siamo di fronte al resoconto di un\u2019esperienza mistica non dissimile da tante che vengono narrate nell\u2019agiografia medievale; al contrario, se la retorica del narratore insiste sulla preminenza di una visione che pu\u00f2 essere detta non solo una illuminazione, bens\u00ec l\u2019Illuminazione, allora siamo di fronte ad una occorrenza del paradigma degli illuminati seicenteschi. Con questo linguaggio simbolico, che non \u00e8 una dottrina particolare, bens\u00ec una cornice di possibili dottrine, si gioca l\u2019appartenenza di Gioacchino al cristianesimo essoterico, con le sfumature sue proprie che lo differenziano da altri pensatori cattolici oppure protestanti, oppure la sua appartenenza al cristianesimo esoterico, quello che Voegelin per il Medioevo (ed oltre) chiama lo gnosticismo politico, all\u2019interno di una visione della storia che rifiuta l\u2019immanenza a favore della trascendenza del Dio trinitario. E tutto questo senza cedere alle troppe ovvie suggestioni di vedere nelle profezie gioachimite un impulso alla devozione popolare, come avrebbe voluto Tondelli per il movimento dei flagellanti del 1260, tesi ricondotta nella sua dimensione meramente suggestiva da Manselli (R. Manselli,\u00a0L\u2019anno 1260 fu anno gioachimitico?, raccolto in Id.,\u00a0Da Gioacchino da Fiore a Cristoforo Colombo, pp. 34-35), che peraltro rifugge dall\u2019idea che la Terza Et\u00e0 dello Spirito sia una nuova Rivelazione, tesi fatta propria in senso apologetico dal modernismo cattolico, quanto piuttosto l\u2019et\u00e0 del trionfo del monachesimo rinnovato (Id.,\u00a0L\u2019attesa dell\u2019et\u00e0 nuova ed il gioachimismo, poi raccolto in Id.,\u00a0Da Gioacchino da Fiore a Cristoforo Colombo, pp. 38-40)<\/em>\u201d.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-33171 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2013\/03\/teologia_liberazione.jpg\" alt=\"\" width=\"207\" height=\"287\" \/>Un appartenente al cattolicesimo di marca progressista, come don Enzo Mazzi (1927-2011) cos\u00ec ci parla dei rapporti fra Gioacchino e un certo cattolicesimo di tipo modernista: \u201c<em>Gioacchino da Fiore, vissuto nella seconda met\u00e0 del XII secolo, monaco del monastero cistercense di S.Giovanni in Fiore, nella Sila, si rese interprete delle attese delle classi umili del tempo. A cominciare dagli inizi del secondo millennio era avvenuta una grande trasformazione della societ\u00e0 feudale: il declino del sistema di dipendenza della servit\u00f9 della gleba e la nascita di comunit\u00e0 di villaggio dotate di autonomia e formate da contadini non pi\u00f9 servi della gleba. Questo porta una nuova cultura, la cultura della cooperazione e della solidariet\u00e0. \u00c8 in questo clima che il monaco cistercense Gioacchino da Fiore lancia l\u2019annuncio della liberazione da tutti i poteri che in diversi modi dominano dall\u2019alto e l\u2019avvento di una societ\u00e0 dello Spirito e dell\u2019amore universale. Un annuncio che in diverso modo nutrir\u00e0 tutte le rivoluzioni moderne, come ci dicono molti storici autorevoli. Tracce della profezia di Gioacchino da Fiore si ritrovano nel modernismo a cui guardava con simpatia papa Giovanni e nei movimenti della liberazione post-moderna come ad esempio nella riflessione di un Teillard De Chardin, nelle comunit\u00e0 di base e nella Teologia della liberazione<\/em>\u201d (in<\/span> <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"http:\/\/teologiaeliberazione.blogspot.com\/\" target=\"_blank\" rel=\"noopener\">teologiaeliberazione.blogspot.com<\/a><\/span> <span style=\"color: #000000;\">articolo ripreso da\u00a0Il Manifesto). Insomma, le suggestioni gioachimite non sono certo assenti nel modernismo.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Il nostro monaco \u00e8 certo pensatore che va indagato pi\u00f9 in profondit\u00e0 in quanto in lui troviamo i semi di quello che verr\u00e0 raccolto alcuni secoli pi\u00f9 tardi.<\/span><\/p>\n<p>______________________________________<\/p>\n<p><strong>Leggi anche:<\/strong><\/p>\n<p><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-modernismo\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">Il modernismo<\/span><\/a><\/p>\n<p><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/modernismo-eresia-del-xx-secolo\/\" target=\"_blank\" rel=\"noopener\">Modernismo eresia del XX secolo<\/a><\/span><\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>InFormazione cattolica 17 Settembre 2021 Possiamo parlare di un modernismo prima del modernismo? \u00a0 Modernismo e \u201cspirito modernista\u201d di Aurelio Porfiri<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ll-modernismo-nella-chiesa\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":44189,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,29,45],"tags":[157,2390,427,286],"class_list":["post-61251","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chiesa","category-eresie-cristiane","category-progressismo-cattolico","tag-chiesa-2","tag-eresie-cristiane","tag-modernismo","tag-progressismo","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ll modernismo nella Chiesa  - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"ll modernismo nella Chiesa in una serie di articoli che spiegano questa &quot;sintesi di tutte le eresie&quot; (Pio X)\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ll-modernismo-nella-chiesa\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ll modernismo nella Chiesa  - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"ll modernismo nella Chiesa in una serie di articoli che spiegano questa &quot;sintesi di tutte le eresie&quot; (Pio X)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ll-modernismo-nella-chiesa\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-22T16:16:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-22T16:16:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/08\/modernismo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"24 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ll-modernismo-nella-chiesa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ll-modernismo-nella-chiesa\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"ll modernismo nella Chiesa\",\"datePublished\":\"2024-09-22T16:16:49+00:00\",\"dateModified\":\"2024-09-22T16:16:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ll-modernismo-nella-chiesa\\\/\"},\"wordCount\":3961,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ll-modernismo-nella-chiesa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/modernismo.jpg\",\"keywords\":[\"chiesa\",\"Eresie cristiane\",\"modernismo\",\"progressismo\"],\"articleSection\":[\"Chiesa\",\"Eresie cristiane\",\"Progressismo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ll-modernismo-nella-chiesa\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ll-modernismo-nella-chiesa\\\/\",\"name\":\"ll modernismo nella Chiesa - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ll-modernismo-nella-chiesa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ll-modernismo-nella-chiesa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/modernismo.jpg\",\"datePublished\":\"2024-09-22T16:16:49+00:00\",\"dateModified\":\"2024-09-22T16:16:51+00:00\",\"description\":\"ll modernismo nella Chiesa in una serie di articoli che spiegano questa \\\"sintesi di tutte le eresie\\\" (Pio X)\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ll-modernismo-nella-chiesa\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ll-modernismo-nella-chiesa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ll-modernismo-nella-chiesa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/modernismo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/modernismo.jpg\",\"width\":1200,\"height\":1300,\"caption\":\"Modernismo eresia del XX secolo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ll-modernismo-nella-chiesa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ll modernismo nella Chiesa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ll modernismo nella Chiesa  - Rassegna Stampa Cattolica","description":"ll modernismo nella Chiesa in una serie di articoli che spiegano questa \"sintesi di tutte le eresie\" (Pio X)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ll-modernismo-nella-chiesa\/","og_locale":"it_IT","og_type":"article","og_title":"ll modernismo nella Chiesa  - Rassegna Stampa Cattolica","og_description":"ll modernismo nella Chiesa in una serie di articoli che spiegano questa \"sintesi di tutte le eresie\" (Pio X)","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ll-modernismo-nella-chiesa\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2024-09-22T16:16:49+00:00","article_modified_time":"2024-09-22T16:16:51+00:00","og_image":[{"width":1200,"height":1300,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/08\/modernismo.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"24 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ll-modernismo-nella-chiesa\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ll-modernismo-nella-chiesa\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"ll modernismo nella Chiesa","datePublished":"2024-09-22T16:16:49+00:00","dateModified":"2024-09-22T16:16:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ll-modernismo-nella-chiesa\/"},"wordCount":3961,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ll-modernismo-nella-chiesa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/08\/modernismo.jpg","keywords":["chiesa","Eresie cristiane","modernismo","progressismo"],"articleSection":["Chiesa","Eresie cristiane","Progressismo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ll-modernismo-nella-chiesa\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ll-modernismo-nella-chiesa\/","name":"ll modernismo nella Chiesa - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ll-modernismo-nella-chiesa\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ll-modernismo-nella-chiesa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/08\/modernismo.jpg","datePublished":"2024-09-22T16:16:49+00:00","dateModified":"2024-09-22T16:16:51+00:00","description":"ll modernismo nella Chiesa in una serie di articoli che spiegano questa \"sintesi di tutte le eresie\" (Pio X)","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ll-modernismo-nella-chiesa\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ll-modernismo-nella-chiesa\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ll-modernismo-nella-chiesa\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/08\/modernismo.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/08\/modernismo.jpg","width":1200,"height":1300,"caption":"Modernismo eresia del XX secolo"},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ll-modernismo-nella-chiesa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"ll modernismo nella Chiesa"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/61251","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=61251"}],"version-history":[{"count":1,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/61251\/revisions"}],"predecessor-version":[{"id":61256,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/61251\/revisions\/61256"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/44189"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=61251"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=61251"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=61251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}