{"id":61,"date":"2004-11-05T11:54:23","date_gmt":"2004-11-05T10:54:23","guid":{"rendered":""},"modified":"2023-11-27T09:02:48","modified_gmt":"2023-11-27T08:02:48","slug":"i-cristiani-deuropa-e-il-dialogo-con-lislam","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-cristiani-deuropa-e-il-dialogo-con-lislam\/","title":{"rendered":"I cristiani d&#8217;Europa e il  dialogo con l&#8217;islam"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-57645 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2004\/11\/dialogo_islam.jpeg\" alt=\"\" width=\"314\" height=\"153\" \/>Abstract:<\/span> <\/strong><span style=\"color: #000000;\"><em>i cristiani d&#8217;Europa nel dialogo con l&#8217;Islam soffrono di &#8220;meaculpismo&#8221; che impedisce loro di comprendere i profondi cambiamenti che l&#8217;islam porta nelle nostre\u00a0 societ\u00e0 europee. Intervista ad un gesuita egiziano. I suoi consigli per non sconfinare in un multiculturalismo anonimo e indifferenziato\u00a0<\/em><\/span><\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\">Articolo pubblicato da <strong>Avvenire<\/strong>\u00a0il 28 marzo 1999<\/span><\/p>\n<h3 style=\"text-align: center;\">Dialogo? I cristiani d\u2019Europa soffrono di \u00abmeaculpismo\u00bb<\/h3>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><em>Il dialogo? Una necessit\u00e0 dettata dalla storia, ma che va costruito senza mettere tra parentesi le rispettive identit\u00e0. In un\u2019Europa che ha perso la memoria delle radici crescono i complessi d\u2019inferiorit\u00e0, una sorta di \u00abmeaculpismo\u00bb che impedisce di capire i cambiamenti che la crescita dell\u2019Islam pu\u00f2 produrre nel tessuto sociale.\u00a0<\/em><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\">Intervista al gesuita\u00a0<span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/www.oasiscenter.eu\/it\/samir-khalil-samir\" target=\"_blank\" rel=\"noopener\"><strong>Samir Khalil<\/strong><\/a><\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Il dialogo? Una necessit\u00e0 dettata dalla storia, ma che va costruito senza mettere tra parentesi le rispettive identit\u00e0. In un\u2019Europa che ha perso la memoria delle radici crescono i complessi d\u2019inferiorit\u00e0, una sorta di \u00abmeaculpismo\u00bb che impedisce di capire i cambiamenti che la crescita dell\u2019Islam pu\u00f2 produrre nel tessuto sociale. Parola di Samir Khalil Samir, egiziano, gesuita, docente all\u2019Universit\u00e0 Saint Joseph di Beirut e al Pontificio istituto orientale di Roma, autore di centinaia di saggi sui reciproci influssi tra cultura islamica e cristiana. Ma soprattutto, come tiene a sottolineare dal Libano, \u00abarabo e cristiano: la dimostrazione vivente che \u00e8 sbagliato identificare il mondo arabo con l\u2019Islam, e che anzi proprio dalla nostra esperienza di minoranza in Medio Oriente pu\u00f2 venire qualche utile insegnamento all\u2019Europa che sta imparando a convivere con milioni di immigrati musulmani\u00bb.<\/span><\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"color: #000000;\">Perch\u00e9 parla di \u00abmeaculpismo\u00bb dell\u2019Occidente nei confronti del mondo musulmano<\/span>?<\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">L\u2019epoca coloniale\u00a0 ha lasciato in eredit\u00e0 una cattiva coscienza legata alla preoccupazione di avere inquinato le radici storiche e culturali delle nazioni che erano state dominate, impedendo o ritardando un presunto autosviluppo in campo economico e politico. Un complesso di colpevolezza ce trae origine dall\u2019errata sovrapposizione tra civilt\u00e0 occidentale e cristianesimo, come se la Chiesa fosse responsabile degli errori commessi dai governi europei nel Terzo Mondo. Ma al fondo di questo equivoco c\u2019\u00e8 la crisi di identit\u00e0 dell\u2019Europa, dove tutto viene messo in discussione in nome di un relativismo che finisce per penalizzare il cristianesimo e favorisce le cosiddette \u201cnovit\u00e0 culturali\u201d: le spiritualit\u00e0 orientali, il New Age e anche la religione islamica vissuta come qualcosa di \u201cesotico\u201d. L\u2019Europa ha dimenticato le sue origini ed \u00e8 come se si vergognasse del suo presente diventando incapace di costruire un futuro. Esattamente il contrario di quello che Giovanni Paolo II chiede con insistenza: essere fieri delle proprie radici e a partire da questo costruire una convivenza tra culture diverse.<\/span><\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"color: #000000;\">La presenza in Europa di milioni di immigrati provenienti da Paesi di cultura musulmana \u00e8 una chance o pu\u00f2 diventare un pericolo per la civilt\u00e0 europea<\/span>?<\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Molto dipender\u00e0 dalla possibilit\u00e0 di realizzare un\u2019effettiva integrazione, in cui il rispetto delle loro specificit\u00e0 non metta in discussione i fondamenti su cui l\u2019Europa ha costruito la sua storia. Vivendo in emigrazione, milioni di arabo-musulmani hanno imparato ad apprezzare la democrazia, il pluralismo, i diritti umani, la centralit\u00e0 della persona. E l\u2019accoglienza ricevuta nelle strutture gestite dal volontariato ha contribuito a sfatare pregiudizi sul cristianesimo e la Chiesa, ancora molto radicati nei Paesi di origine \u2013 e questo \u00e8 l\u2019obiettivo pi\u00f9 interessante \u2013 in Europa i musulmani possono apprezzare la positivit\u00e0 tra religione e Stato, capire che la laicit\u00e0 non \u00e8 l\u2019anticamera dell\u2019ateismo ma la possibilit\u00e0 di costruire una societ\u00e0 che non discrimina sulla base dell\u2019appartenenza religiosa, ma mette al centro la persona e i suoi diritti.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>Il timore di una progressiva penetrazione islamica attraverso il canale dell\u2019immigrazione \u00e8 una teoria o una preoccupazione fondata?<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Secondo alcuni esponenti islamici la tolleranza e la libert\u00e0 di cui si gode in Europa rappresentano una chance per la diffusione dell\u2019Islam, e in effetti qualcuno lavora per una \u201creislamizzazione\u201d in chiave politico-radicale degli immigrati che vengono nei vostri Paesi per motivi fondamentalmente economici. Molto dipender\u00e0 dalle componenti che prevarranno nelle comunit\u00e0 in emigrazione<\/span>.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>Quale ruolo possono svolgere in queste dinamiche le moschee, che si vanno moltiplicando anche in Italia<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Chiariamo innanzitutto che la moschea non \u00e8 una \u201cchiesa musulmana\u201d. Oltre che luogo di preghiera \u00e8 un centro di aggregazione dove si insegna l\u2019arabo e il Corano e che assume una forte valenza sociale e spesso politica. C\u2019\u00e8 chi sostiene che le moschee permettano un maggiore controllo sociale delle comunit\u00e0, che siano un antidoto alla ghettizzazione dei musulmani e un argine all\u2019infiltrazione degli elementi pi\u00f9 radicali, ma \u00e8 difficile formulare un giudizio univoco: dipende dalle intenzioni di chi le gestisce. Non \u00e8 un caso che in molti Paesi certe moschee vengono presidiate dalla polizia per prevenire disordino all\u2019uscita della preghiera<\/span>.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>Quali strade intravede per un dialogo costruttivo tra cristiani e musulmani nel contesto italiano?<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Chiarito che il dialogo \u00e8 una\u00a0 necessit\u00e0 dettata dalla vicinanza in cui cristiani e musulmani si trovano in seguito ai flussi migratori, credo che esso debba essere \u201cesigente\u201d e rispettare alcune condizioni senza le quali rischia di essere anonimo e improduttivo. Deve esserci da ambo le parti una forte carica di autenticit\u00e0: presentare solo una parte della propria fede per paura di offendere, di deludere, o di dividere \u2013 come spesso fanno molti cristiani che vivono un complesso di inferiorit\u00e0 \u2013 \u00e8 come dire una menzogna, e pu\u00f2 confermare l\u2019interlocutore musulmano nella sua convinzione che in fondo il cristiano \u00e8 un credente che non ha ancora terminato il cammino per raggiungere la piena verit\u00e0, che si troverebbe appunto nel Corano<\/span>.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Da parte cristiana \u00e8 importante testimoniare che fede e modernit\u00e0 possono camminare assieme, che la democrazia non \u00e8 nemica della religione, che il principio di cittadinanza porta in s\u00e9 anche quello della tolleranza e della tutela delle minoranze, senza per questo sconfinare in un multiculturalismo anonimo e indifferenziato che pu\u00f2 diventare la premessa per la moltiplicazione di ghetti anzich\u00e9 favorire una reale integrazione. E se tutto questo diventer\u00e0 patrimonio dei musulmani che vivono in Italia, col tempo potrebbero portare un influsso benefico nei paesi di provenienza. Mi permetta di aggiungere che da parte dello Stato ci vorrebbe pi\u00f9 coraggio nei rapporti diplomatici con certi Paesi dove i cristiani vivono in condizione di emarginazione sociale e patiscono discriminazioni, anche se gli affari che si concludono con quei Paesi fruttano fiumi di dollari alla vostra economia<\/span>.<\/p>\n<p>________________________________________<\/p>\n<p><span style=\"color: #000000;\"><strong>I cristiani e il dialogo con l&#8217;islam. Per approfondire<\/strong><\/span><\/p>\n<p><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/laccoglienza-puo-produrre-ghetti-lintegrazione-richiede-regole-di-ferro-intervista-a-khalil-samir\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">L\u2019accoglienza pu\u00f2 produrre ghetti, l\u2019integrazione richiede regole di ferro. Intervista a Khalil Samir<\/span><\/a><\/p>\n<p><span style=\"color: #0000ff;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-risveglio-dellislam-e-la-crisi-di-identita-delloccidente\/\" target=\"_blank\" rel=\"noopener\">Il risveglio dell&#8217;islam e la crisi di identit\u00e0 dell&#8217;Occidente<\/a>\u00a0<\/span><\/p>\n<p><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/cristianesimo-e-islam\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">Cristianesimo e islam<\/span><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Abstract: i cristiani d&#8217;Europa nel dialogo con l&#8217;Islam soffrono di &#8220;meaculpismo&#8221; che impedisce loro di comprendere i profondi cambiamenti che l&#8217;islam porta nelle nostre\u00a0 societ\u00e0 europee. Intervista ad un gesuita egiziano. I suoi consigli per non sconfinare in un multiculturalismo anonimo e indifferenziato\u00a0<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-cristiani-deuropa-e-il-dialogo-con-lislam\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":32593,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16,34],"tags":[161,517],"class_list":["post-61","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-islam","category-dialogo-con-l-islam","tag-islam-2","tag-islam-dialogo","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>I cristiani d&#039;Europa e il dialogo con l&#039;islam - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"I cristiani d&#039;Europa nel dialogo con l&#039;islam soffrono di &quot;meaculpismo&quot; e non si avvedono dei mutamenti profondi che l&#039;Islam comporta.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-cristiani-deuropa-e-il-dialogo-con-lislam\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"I cristiani d&#039;Europa e il dialogo con l&#039;islam - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"I cristiani d&#039;Europa nel dialogo con l&#039;islam soffrono di &quot;meaculpismo&quot; e non si avvedono dei mutamenti profondi che l&#039;Islam comporta.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-cristiani-deuropa-e-il-dialogo-con-lislam\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2004-11-05T10:54:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-27T08:02:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2004\/11\/crociate_film.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"200\" \/>\n\t<meta property=\"og:image:height\" content=\"252\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-cristiani-deuropa-e-il-dialogo-con-lislam\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-cristiani-deuropa-e-il-dialogo-con-lislam\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"I cristiani d&#8217;Europa e il dialogo con l&#8217;islam\",\"datePublished\":\"2004-11-05T10:54:23+00:00\",\"dateModified\":\"2023-11-27T08:02:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-cristiani-deuropa-e-il-dialogo-con-lislam\\\/\"},\"wordCount\":1091,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-cristiani-deuropa-e-il-dialogo-con-lislam\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2004\\\/11\\\/crociate_film.jpg\",\"keywords\":[\"islam\",\"Islam dialogo\"],\"articleSection\":[\"Islam\",\"Islam dialogo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-cristiani-deuropa-e-il-dialogo-con-lislam\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-cristiani-deuropa-e-il-dialogo-con-lislam\\\/\",\"name\":\"I cristiani d'Europa e il dialogo con l'islam - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-cristiani-deuropa-e-il-dialogo-con-lislam\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-cristiani-deuropa-e-il-dialogo-con-lislam\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2004\\\/11\\\/crociate_film.jpg\",\"datePublished\":\"2004-11-05T10:54:23+00:00\",\"dateModified\":\"2023-11-27T08:02:48+00:00\",\"description\":\"I cristiani d'Europa nel dialogo con l'islam soffrono di \\\"meaculpismo\\\" e non si avvedono dei mutamenti profondi che l'Islam comporta.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-cristiani-deuropa-e-il-dialogo-con-lislam\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-cristiani-deuropa-e-il-dialogo-con-lislam\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-cristiani-deuropa-e-il-dialogo-con-lislam\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2004\\\/11\\\/crociate_film.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2004\\\/11\\\/crociate_film.jpg\",\"width\":200,\"height\":252},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-cristiani-deuropa-e-il-dialogo-con-lislam\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"I cristiani d&#8217;Europa e il dialogo con l&#8217;islam\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"I cristiani d'Europa e il dialogo con l'islam - Rassegna Stampa Cattolica","description":"I cristiani d'Europa nel dialogo con l'islam soffrono di \"meaculpismo\" e non si avvedono dei mutamenti profondi che l'Islam comporta.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-cristiani-deuropa-e-il-dialogo-con-lislam\/","og_locale":"it_IT","og_type":"article","og_title":"I cristiani d'Europa e il dialogo con l'islam - Rassegna Stampa Cattolica","og_description":"I cristiani d'Europa nel dialogo con l'islam soffrono di \"meaculpismo\" e non si avvedono dei mutamenti profondi che l'Islam comporta.","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-cristiani-deuropa-e-il-dialogo-con-lislam\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2004-11-05T10:54:23+00:00","article_modified_time":"2023-11-27T08:02:48+00:00","og_image":[{"width":200,"height":252,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2004\/11\/crociate_film.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-cristiani-deuropa-e-il-dialogo-con-lislam\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-cristiani-deuropa-e-il-dialogo-con-lislam\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"I cristiani d&#8217;Europa e il dialogo con l&#8217;islam","datePublished":"2004-11-05T10:54:23+00:00","dateModified":"2023-11-27T08:02:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-cristiani-deuropa-e-il-dialogo-con-lislam\/"},"wordCount":1091,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-cristiani-deuropa-e-il-dialogo-con-lislam\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2004\/11\/crociate_film.jpg","keywords":["islam","Islam dialogo"],"articleSection":["Islam","Islam dialogo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-cristiani-deuropa-e-il-dialogo-con-lislam\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-cristiani-deuropa-e-il-dialogo-con-lislam\/","name":"I cristiani d'Europa e il dialogo con l'islam - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-cristiani-deuropa-e-il-dialogo-con-lislam\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-cristiani-deuropa-e-il-dialogo-con-lislam\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2004\/11\/crociate_film.jpg","datePublished":"2004-11-05T10:54:23+00:00","dateModified":"2023-11-27T08:02:48+00:00","description":"I cristiani d'Europa nel dialogo con l'islam soffrono di \"meaculpismo\" e non si avvedono dei mutamenti profondi che l'Islam comporta.","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-cristiani-deuropa-e-il-dialogo-con-lislam\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-cristiani-deuropa-e-il-dialogo-con-lislam\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-cristiani-deuropa-e-il-dialogo-con-lislam\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2004\/11\/crociate_film.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2004\/11\/crociate_film.jpg","width":200,"height":252},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-cristiani-deuropa-e-il-dialogo-con-lislam\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"I cristiani d&#8217;Europa e il dialogo con l&#8217;islam"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/61","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=61"}],"version-history":[{"count":5,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/61\/revisions"}],"predecessor-version":[{"id":57648,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/61\/revisions\/57648"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/32593"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=61"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=61"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=61"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}