{"id":59894,"date":"2024-03-29T18:21:46","date_gmt":"2024-03-29T17:21:46","guid":{"rendered":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=59894"},"modified":"2024-03-29T18:21:50","modified_gmt":"2024-03-29T17:21:50","slug":"transizione-green-impossibile-e-le-bugie-delleuropa","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/transizione-green-impossibile-e-le-bugie-delleuropa\/","title":{"rendered":"Transizione green impossibile e le bugie dell&#8217;Europa"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-47145 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/05\/ambiente_sostenibile-300x153.png\" alt=\"\" width=\"331\" height=\"169\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/05\/ambiente_sostenibile-300x153.png 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/05\/ambiente_sostenibile-768x391.png 768w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/05\/ambiente_sostenibile-1024x521.png 1024w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/05\/ambiente_sostenibile.png 1656w\" sizes=\"auto, (max-width: 331px) 100vw, 331px\" \/>Abstract:\u00a0<\/strong><em> transizione green impossibile e le bugie dell&#8217;Europa. Mentre la legislatura europea volge al termine, restano gli ultimi cascami del Green deal da approvare, cos\u00ec che la Commissione europea possa considerare concluso il suo programma politico. Il romanzo della transizione si sposa con il romanzo della tecnologi, che oggi si veste di intelligenza artificiale. L\u2019Ia ci salver\u00e0, ed il fatto che solo per istruire Char Gpt serva l\u2019energia di diverse centrali elettriche da migliaia di megawatt di potenza viene mascherato da incidente necessario, come effetto collaterale di una medicina buona il s\u00e9.<\/em><\/span><\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\"><a href=\"https:\/\/www.laverita.info\/\" target=\"_blank\" rel=\"noopener\"><strong>La Verit\u00e0<\/strong><\/a> mercoled\u00ec 20 Marzo 2024 \u00a0<\/span><\/p>\n<h3 style=\"text-align: center;\"><span style=\"color: #000000;\">La transizione impossibile. <\/span><\/h3>\n<h3 style=\"text-align: center;\"><span style=\"color: #000000;\">Cos\u00ec la Ue e i grandi media hanno creato le bugie green<\/span><\/h3>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">La<em> propaganda presenta ogni decisione inevitabile perch\u00e9 \u00abtecnica\u00bb. E occulta le contraddizione, indicando la salvezza nella tecnologia bench\u00e9 sia ultra energivora<\/em> <\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\">di <strong>Sergio Giraldo<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-46472 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/02\/ambiente_energia_eolico.jpg\" alt=\"La Net Zero dell'Unione europea \u00e8 una follia\" width=\"345\" height=\"217\" \/>Mentre la legislatura europea volge al termine, restano gli ultimi cascami del Green deal da approvare, cos\u00ec che la Commissione europea possa considerare concluso il suo programma politico. Luned\u00ec 18 marzo il Consiglio ha approvato la strategia sulle materie prime critiche (il Critical Raw Materials Act, Crma), ossia un tentativo (piuttosto misero) di ridurre la dipendenza dell&#8217;Unione europea dalla Cina su molti elementi necessari alla transizione energetica, dal cobalto al litio. Un altro scalpo che <strong>Ursula von der Leyen<\/strong> pu\u00f2 appendere alla cintura.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Il Green deal si \u00e8 rivelato essere un enorme piano di una quarantina tra direttive e regolamenti, comunicazioni, norme varie, la gran parte delle quali pessime. La Direttiva sulle cosiddette case green o il Regolamento sugli imballaggi sono una piccola parte del tutto. Dopo i primi anni in cui ben pochi (<em>La Verit\u00e0<\/em> tra questi) hanno sollevato l\u2019attenzione sui danni perpetrati dal Green deal, \u00e8 solo con la crisi energetica del 2022 che l\u2019opinione pubblica ha iniziati a rendersi conto sulla propria pelle del suicidio economico, sociale e geopolitico verso cui Bruxelles stava spingendo l\u2019Europa.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Ciononostante, dopo la crisi dei prezzi dell\u2019energia, la Commissione a guida <strong>Von der Leyen<\/strong> ha proseguito con pervicacia nell\u2019attuazione del proprio programma, facendo leva su argomenti ideologici e meccanismi di influenza dell\u2019opinione pubblica.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Vi \u00e8 infatti un\u2019ampia pubblicistica che tende a raccontare le politiche messe in atto da Bruxelles con toni da palingenesi, necessarie a creare consenso.<\/span><\/p>\n<p style=\"text-align: justify;\">I<span style=\"color: #000000;\">nnanzitutto, le politiche economiche imposte in nome della lotta al cambiamento climatico vengono sostenute attraverso la colpevolizzazione del singolo. Si cerca di far passare l\u2019idea che siano i comportamenti antisociali dell\u2019uomo occidentale ad aver provocato il cambiamento climatico. Se i ghiacci al polo si sciolgono e le isola Maldive rischiano di essere sommerse \u00e8 causa delle schiere di utilitarie con motore a scoppio che affollano le autostrade europee. E\u2019 colpa nostra. Dunque, per salvare vite innocenti occorre passare all\u2019utilizzo dell\u2019elettrica. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-39917 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/03\/auto_elettrica.jpg\" alt=\"\" width=\"347\" height=\"241\" \/>Secondo tale versione della storia, la libera scelta che ci ha portato ad utilizzare le automobili a benzina non \u00e8 pi\u00f9 un valore, perch\u00e9 ci porta alla distruzione del pianeta. Dunque occorre una volont\u00e0 superiore, la legge, che imponga un comportamento diverso. Il fatto che sia stata l\u2019industria di massa, cio\u00e8 in definitiva il capitale, ad aversi dotato di quest\u2019arma di distruzione a quattro ruote viene accuratamente occultato dietro una cortina di colpevolizzazione dell\u2019uomo occidentale in quanto tale, colpevole di avidit\u00e0 ed egoismo. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Su questo livello si innesta il racconto dello scontro generazionale, teso a creare una faglia tra \u00abgiovani preoccupati\u00bb e \u00abanziani egoisti\u00bb. <strong>Greta Thumberg<\/strong> \u00e8 stata la prima e la pi\u00f9 nota paladina del giovanilismo militante in nome del clima, su cui poi si \u00e8 innestatal\u2019azione di gruppi come Ultima generazione<\/span>.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Poich\u00e9 per\u00f2 l\u2019Unione europea si racconta come paladina del libero mercato (\u00abeconomia sociale di mercato fortemente competitiva\u00bb, recita il Trattato sull\u2019Unione europea), deve restare nel racconto pubblico l\u2019idea che siano le scelte individuali a salvare la situazione. Quindi si maschera l\u2019imposizione con la possibilit\u00e0 di scelta: si pu\u00f2 \u00abscegliere\u00bb quale modello di auto elettrica, si pu\u00f2 \u00abscegliere\u00bb di andare in bicicletta, o in treno, oppure di abitare in zone in cui l\u2019automobile non sia necessaria. Questo ventaglio di false scelte \u00e8 strettamente funzionale all\u2019imposizione di una tecnologia par la <\/span><span style=\"color: #000000;\">mobilit\u00e0 privata che di fatto amputa la libert\u00e0 di movimento<\/span>.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Il secondo aspetto su cui punta il racconto della transizione \u00e8 che al cambiamento climatico si pu\u00f2 porre rimedio nell\u2019ambito dei rapporti di produzione esistenti, producendo e comprando \u00abaltro\u00bb rispetto a quanto fatto sinora. Se sono scelte individuali dei consumatori ad averci portato qui, \u00e8 attraverso un cambio di ci\u00f2 che viene prodotto e consumato (e come) che si pu\u00f2 uscire dalla crisi climatica. Un argomento semplice, teso a creare nuovi mercati, che normalmente non sarebbero mai nati, una economia in cui i rendimenti decrescenti scatenano la finanza mondiale a caccia di nuovi profitti.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">E terzo argomento nel romanzo della transizione \u00e8 che il cambiamento climatico \u00e8 apolitico e riguarda tutto il mondo, dunque le scelte di governo devono essere depoliticizzate ed affidate ai tecnici, alla scienza. E\u2019 l\u2019ennesimo tentativo di svuotare le democrazie nazionali, non solo spostando il livello delle decisioni in un ambito sovranazionale, dunque fuori dal controllo politico degli elettori, ma anche sottraendolo ai politici di professione. Un\u2019operazione abbastanza semplice, data l\u2019opera ultradecennale di delegittimazione della politica<\/span>.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-57380 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2023\/11\/intelligenza_artificiale_tecnologia_digitale.jpg\" alt=\"Intelligenza artificiale e tecnologia digitale. La macchina propone modelli\" width=\"432\" height=\"263\" \/>Il quarto argomento \u00e8 che la tecnologia ci salver\u00e0. Dobbiamo fare le cose in modo diverso ed \u00e8 solo la tecnologia che pu\u00f2 aiutarci a farlo. Un elemento, questo, strettamente connesso al precedente, che assegna ai guru della tecnologia un ruolo salvifico e trasforma il progresso in un motore sociale inarrestabile, rendendoci partecipi di un cambiamento ineluttabile al grido di \u00abindietro non si torna<\/span>!\u00bb<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Il romanzo della transizione si sposa qui con il romanzo della tecnologi, che oggi si veste di intelligenza artificiale. L\u2019Ia ci salver\u00e0, ed il fatto che solo per istruire Char Gpt serva l\u2019energia di diverse centrali elettriche da migliaia di megawatt di potenza viene mascherato da incidente necessario, come effetto collaterale di una medicina buona il s\u00e9.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Il tutto, condito da racconti. Servono storie da trasformare in paradigmi comportamentali, perch\u00e9 possano istruire e conformare l\u2019opinione pubblica. In sintesi \u00e8 <strong>Von del Leyen<\/strong> che traccia il solco, ma sono i media che lo difendono<\/span>.<\/p>\n<p>_____________________________________________<\/p>\n<p><strong><span style=\"color: #000000;\">Leggi anche:<\/span><\/strong><\/p>\n<p><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ambientalisti-senza-moralita\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">Ambientalisti senza moralit\u00e0<\/span><\/a><\/p>\n<p><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/se-crollasse-la-diga-delle-bufale\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">Se crollasse la diga delle bufale<\/span><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Abstract:\u00a0 transizione green impossibile e le bugie dell&#8217;Europa. Mentre la legislatura europea volge al termine, restano gli ultimi cascami del Green deal da approvare, cos\u00ec che la Commissione europea possa considerare concluso il suo programma politico. Il romanzo della transizione si sposa con il romanzo della tecnologi, che oggi si veste di intelligenza artificiale. L\u2019Ia &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/transizione-green-impossibile-e-le-bugie-delleuropa\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":52462,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,14,2956],"tags":[2387,567,3032,2817],"class_list":["post-59894","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ambientalismo","category-europa-e-ue","category-tecnologia","tag-ambientalismo","tag-europa-eu","tag-green-deal","tag-tecnologia","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Transizione green impossibile e le bugie dell&#039;Europa - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Transizione green impossibile e le bugie dell&#039;Europa che occulta le contraddizioni di tecnologie salvifiche ma ultra energivore\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/transizione-green-impossibile-e-le-bugie-delleuropa\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Transizione green impossibile e le bugie dell&#039;Europa - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Transizione green impossibile e le bugie dell&#039;Europa che occulta le contraddizioni di tecnologie salvifiche ma ultra energivore\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/transizione-green-impossibile-e-le-bugie-delleuropa\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-29T17:21:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-29T17:21:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/09\/ambientalismo_rivoluzione.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/transizione-green-impossibile-e-le-bugie-delleuropa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/transizione-green-impossibile-e-le-bugie-delleuropa\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Transizione green impossibile e le bugie dell&#8217;Europa\",\"datePublished\":\"2024-03-29T17:21:46+00:00\",\"dateModified\":\"2024-03-29T17:21:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/transizione-green-impossibile-e-le-bugie-delleuropa\\\/\"},\"wordCount\":1043,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/transizione-green-impossibile-e-le-bugie-delleuropa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/ambientalismo_rivoluzione.jpg\",\"keywords\":[\"Ambientalismo\",\"Europa EU\",\"green deal\",\"tecnologia\"],\"articleSection\":[\"Ambientalismo\",\"Europa e UE\",\"Tecnologia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/transizione-green-impossibile-e-le-bugie-delleuropa\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/transizione-green-impossibile-e-le-bugie-delleuropa\\\/\",\"name\":\"Transizione green impossibile e le bugie dell'Europa - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/transizione-green-impossibile-e-le-bugie-delleuropa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/transizione-green-impossibile-e-le-bugie-delleuropa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/ambientalismo_rivoluzione.jpg\",\"datePublished\":\"2024-03-29T17:21:46+00:00\",\"dateModified\":\"2024-03-29T17:21:50+00:00\",\"description\":\"Transizione green impossibile e le bugie dell'Europa che occulta le contraddizioni di tecnologie salvifiche ma ultra energivore\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/transizione-green-impossibile-e-le-bugie-delleuropa\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/transizione-green-impossibile-e-le-bugie-delleuropa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/transizione-green-impossibile-e-le-bugie-delleuropa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/ambientalismo_rivoluzione.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/ambientalismo_rivoluzione.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/transizione-green-impossibile-e-le-bugie-delleuropa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Transizione green impossibile e le bugie dell&#8217;Europa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Transizione green impossibile e le bugie dell'Europa - Rassegna Stampa Cattolica","description":"Transizione green impossibile e le bugie dell'Europa che occulta le contraddizioni di tecnologie salvifiche ma ultra energivore","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/transizione-green-impossibile-e-le-bugie-delleuropa\/","og_locale":"it_IT","og_type":"article","og_title":"Transizione green impossibile e le bugie dell'Europa - Rassegna Stampa Cattolica","og_description":"Transizione green impossibile e le bugie dell'Europa che occulta le contraddizioni di tecnologie salvifiche ma ultra energivore","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/transizione-green-impossibile-e-le-bugie-delleuropa\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2024-03-29T17:21:46+00:00","article_modified_time":"2024-03-29T17:21:50+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/09\/ambientalismo_rivoluzione.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/transizione-green-impossibile-e-le-bugie-delleuropa\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/transizione-green-impossibile-e-le-bugie-delleuropa\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Transizione green impossibile e le bugie dell&#8217;Europa","datePublished":"2024-03-29T17:21:46+00:00","dateModified":"2024-03-29T17:21:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/transizione-green-impossibile-e-le-bugie-delleuropa\/"},"wordCount":1043,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/transizione-green-impossibile-e-le-bugie-delleuropa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/09\/ambientalismo_rivoluzione.jpg","keywords":["Ambientalismo","Europa EU","green deal","tecnologia"],"articleSection":["Ambientalismo","Europa e UE","Tecnologia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/transizione-green-impossibile-e-le-bugie-delleuropa\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/transizione-green-impossibile-e-le-bugie-delleuropa\/","name":"Transizione green impossibile e le bugie dell'Europa - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/transizione-green-impossibile-e-le-bugie-delleuropa\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/transizione-green-impossibile-e-le-bugie-delleuropa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/09\/ambientalismo_rivoluzione.jpg","datePublished":"2024-03-29T17:21:46+00:00","dateModified":"2024-03-29T17:21:50+00:00","description":"Transizione green impossibile e le bugie dell'Europa che occulta le contraddizioni di tecnologie salvifiche ma ultra energivore","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/transizione-green-impossibile-e-le-bugie-delleuropa\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/transizione-green-impossibile-e-le-bugie-delleuropa\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/transizione-green-impossibile-e-le-bugie-delleuropa\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/09\/ambientalismo_rivoluzione.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/09\/ambientalismo_rivoluzione.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/transizione-green-impossibile-e-le-bugie-delleuropa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Transizione green impossibile e le bugie dell&#8217;Europa"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/59894","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=59894"}],"version-history":[{"count":1,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/59894\/revisions"}],"predecessor-version":[{"id":59895,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/59894\/revisions\/59895"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/52462"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=59894"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=59894"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=59894"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}