{"id":59805,"date":"2024-03-14T00:00:00","date_gmt":"2024-03-13T23:00:00","guid":{"rendered":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=59805"},"modified":"2024-03-14T08:44:11","modified_gmt":"2024-03-14T07:44:11","slug":"adulti-bambini-e-trans-cavie-dei-medici-arcobaleno","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/adulti-bambini-e-trans-cavie-dei-medici-arcobaleno\/","title":{"rendered":"Adulti bambini e trans cavie dei medici arcobaleno"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-59806 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2024\/03\/Lgbt_disforia_genere_gender.jpeg\" alt=\"\" width=\"300\" height=\"193\" \/>Abstract: <\/strong><em>adulti bambini e trans cavie dei medici arcobaleno che nelle loro chat <\/em><\/span><em><span style=\"color: #000000;\">gli pseudo luminari che ufficialmente si presentano da alfieri dello scientificamente corretto abbiano pi\u00f9 dubbi che certezze. Come denuncia Envieronmental Progress \u00abI documentari rivelano una diffusa negligenza medica nei confronti di bambini e adulti vulnerabili\u00bb. Le conversazioni dei medici venute alla luce (chiamate WPath leaks) che discutono come trattare i pazienti stanno facendo il giro del pianeta e stanno suscitando un vespaio, anche perch\u00e9 nelle comunicazioni certificate gli stessi medici insistono nel definire i percorsi come \u00abnon pi\u00f9 sperimentali\u00bb.<\/span><\/em><span style=\"color: #000000;\">Al contrario sembra che lo siano. Sembra che si brancoli nel<\/span><\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\"><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/www.laverita.info\/\" target=\"_blank\" rel=\"noopener\"><strong>La Verit\u00e0<\/strong> <\/a><\/span>Gioved\u00ec 7 Marzo 2024\u00a0<\/span><\/p>\n<h3 style=\"text-align: center;\">La chat degli orrori dei medici arcobaleno che mutilano bimbi e adulti trans<\/h3>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\"><em>I messaggi tra i membri della WPath rivelano in preparazione e negligenza sul cambio di sesso soprattutto verso i minorenni <\/em><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\">di <strong>Giorgio Gandola <\/strong><\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-52581 size-medium alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/09\/transgender_gender-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/09\/transgender_gender-300x200.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/09\/transgender_gender-768x512.jpg 768w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/09\/transgender_gender-1024x683.jpg 1024w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/09\/transgender_gender.jpg 1440w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">\u00abSo che sto parlando con un muro bianco\u00bb. Il tema non \u00e8 secondario: il cambio di sesso. Quindi sarebbe importante far capire. Il destinatario del commento e l&#8217;adolescente che vorrebbe sottoporsi alla terapia ormonale. E l&#8217;autore e Daniel Metzger, endocrinologo canadese, il dottore che tenta di ottenere il consenso. In una chat con alcuni colleghi esperti in traversate transessuali si sbilancia: \u00abspesso i medici spiegano queste cose a persone che non hanno ancora studiato biologia alle scuole superiori\u00bb. Per forza, hanno 13-14 anni. Poi aggiunge che \u00abanche i pazienti adulti hanno una conoscenza molto scarsa degli effetti di questi interventi\u00bb. Punto siamo a cavallo.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Questa sarebbe la graniticit\u00e0 scientifica dei protocolli sulla disforia di genere il dottor <strong>Metzge<\/strong>r \u00e8 un membro di spicco del da WPath (World professional association for transgender health), l&#8217;associazione americana con tentacoli mondiali che promuove la salute dei pazienti transessuali, guida scientifico- a spirituale del mondo Lgbtq+, capace di orientare le azioni dei governi nell&#8217;occidente delle transizioni felici. In realt\u00e0 nella chat dei medici traspare soprattutto la preoccupazione di chi si \u00e8 incamminato su una strada sconosciuta e parla di giovani pazienti come se fossero cavie punto<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">\u00c8 la sensazione che si avverte dopo la pubblicazione di centinaia di post relativi a conversazioni interne fra specialisti WPath, ottenuti dalla Environmental Progress, l&#8217;organizzazione di ricerca indipendente fondata dal cacciatore di scoop <strong>Michael Schellenberger.<\/strong> Ed \u00e8 disarmante notare come gli pseudo luminari che ufficialmente si presentano da alfieri dello scientificamente corretto, nei forum interni abbiano pi\u00f9 dubbi che certezze. Come denuncia Envieronmental Progress \u00abI documentari rivelano una diffusa negligenza medica nei confronti di bambini e adulti vulnerabili\u00bb. Le conversazioni dei medici venute alla luce (chiamate WPath leaks) che discutono come trattare i pazienti stanno facendo il giro del pianeta e stanno suscitando un vespaio, anche perch\u00e9 nelle comunicazioni certificate gli stessi medici insistono nel definire i percorsi come \u00abnon pi\u00f9 sperimentali\u00bb.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-55090 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/11\/gender_disforia-300x168.jpg\" alt=\"\" width=\"400\" height=\"224\" \/>Al contrario sembra che lo siano. Sembra che si brancoli nel buio perch\u00e9 la giovane et\u00e0 dei \u00abmuri bianchi\u00bb impedisce di ottenere consensi davvero informati. E perch\u00e9 \u00ab\u00e8 difficile far capire le conseguenze alle quali vanno incontro i pazienti\u00bb che chiedono i bloccanti della pubert\u00e0 con \u00abeffetti potenti e alteranti\u00bb sulla loro vita. Sempre <strong>Metzer<\/strong> confida ai colleghi che \u00a0\u00abi giovani pazienti desiderano solo una voce pi\u00f9 profonda, senza peli sul viso, o assumono estrogeni senza sviluppare il seno. Cosa che suggerisce una comprensione molto scarsa del funzionamento del corpo umano\u00bb. In una chat abbastanza agghiacciante la psicologa infantile <strong>Diana Berg<\/strong> (definita un caposaldo del WPath) interviene per Aggiungere che \u00abnon si pu\u00f2 aspettare che gli adolescenti comprendano le conseguenze del trattamento perch\u00e9 \u00e8 fuori dalle loro capacit\u00e0\u00bb. Aggiunge<strong> Berg<\/strong>: \u00abDiranno che capiscono. Ma poi diranno qualcos\u2019altro che ti fa pensare: Oh, non hanno veramente compreso che avranno peli sul viso\u00bb.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Al di la del consenso impossibile, a porte chiuse i medici del WPath \u2013 secondo i segugi di <strong>Shellemberger <\/strong>entrati in possesso del materiale esplosivo &#8211; \u00abconfessano che le loro pratiche si basano sull\u2019improvvisazione\u00bb. La stessa presidente <strong>Marci Bowers<\/strong> spiega che \u00abnon \u00e8 ancora del tutto compreso l\u2019effetto dei bloccanti della pubert\u00e0 sulla fertilit\u00e0\u00bb. Non proprio un dettaglio. Impegnati a scardinare il genere binario, gli esperti di transizione ammettono di portare avanti le terapie anche con bambini che hanno deficit mentali.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Un esempio. Un professore della Yale\u00a0 School of Medicine chiede consiglio al gruppo sul metodo migliore da adottare con un giovane \u00abcon ritardo nello sviluppo cognitivo\u00bb e quanto sarebbe etico \u00abconsentirgli di passare alla terapia ormonale\u00bb. Risposta di uno psichiatra della Nuova Scozia: \u00abBisogna soppesare il danno di agire rispetto a quello di non agire\u00bb. Interviene <strong>Dan Karasich, <\/strong>professore della Universit\u00e0 della California (San Francisco), a mettere il punto esclamativo: \u00abLa semplice presenza di una malattia psichiatrica non dovrebbe bloccare la capacit\u00e0 di una persona di iniziare gli ormoni, se soffre di disforia di genere\u00bb.\u00a0 Non dovrebbe.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-49312 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/11\/gay_bandiera_gender-300x225.jpg\" alt=\"\" width=\"313\" height=\"235\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/11\/gay_bandiera_gender-300x225.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/11\/gay_bandiera_gender-768x576.jpg 768w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/11\/gay_bandiera_gender-1024x768.jpg 1024w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/11\/gay_bandiera_gender.jpg 1280w\" sizes=\"auto, (max-width: 313px) 100vw, 313px\" \/>Dai WPath leaks (alcuni li trovate in questa pagina) escono perplessit\u00e0 dovute alla presenza di un tumore al fegato su un minorenne dopo la terapia di ormoni: divagazioni sugli effetti collaterali della vaginoplastica (\u00abNon tutti hanno avuto risultati perfetti\u00bb scrive <strong>Cristine McGinn<\/strong> che ne ha fatte 20 in 17 anni); cure a base di estrogeni che provocano \u00abspaccature nella pelle che sanguinavano ed erano strazianti\u00bb (cos\u00ec parla un\u2019avvocatessa attivista transgender dopo anni di testosterone). Spicca un delirante conversario sulla \u00abnullification\u00bb, l\u2019annullamento del sesso con la riduzione della persona a bambola, operato in regime di copertura assicurativa. Come se in un domani distropico fosse possibile attuarlo con il servizio sanitario nazionale.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Alla luce di tutto questo risulta sacrosanto l\u2019invito degli ispettori del ministero della Sanit\u00e0 all\u2019ospedale di Careggi di Firenze, dove il trattamento della disforia di genere viene praticato con l\u2019uso della triptorelina. La verifica dei metodi \u00e8 fondamentale. Nei WPath leaks il verbo pi\u00f9 utilizzato \u00e8 \u00abpotrebbe\u00bb, di solito una coperta di Linus quando la scienza balbetta.<\/span><\/p>\n<p>________________________________________<\/p>\n<p><strong><span style=\"color: #000000;\">Leggi anche:<\/span><\/strong><\/p>\n<p><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/limpatto-delle-terapie-mediche-sui-minori-con-disforia-di-genere\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">L \u2019Appello a proposito dei discorsi ideologici su bambini e adolescenti<\/span><\/a><\/p>\n<p><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/new-york-times-demolisce-le-cure-di-genere-ai-minori\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">Bambini che non erano trans. E che sono diventati pedine politiche<\/span><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Abstract: adulti bambini e trans cavie dei medici arcobaleno che nelle loro chat gli pseudo luminari che ufficialmente si presentano da alfieri dello scientificamente corretto abbiano pi\u00f9 dubbi che certezze. Come denuncia Envieronmental Progress \u00abI documentari rivelano una diffusa negligenza medica nei confronti di bambini e adulti vulnerabili\u00bb. Le conversazioni dei medici venute alla luce &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/adulti-bambini-e-trans-cavie-dei-medici-arcobaleno\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":59806,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[125],"tags":[437,2279],"class_list":["post-59805","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ideologia-del-gender","tag-ideologia-del-gender-2","tag-transgender","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Adulti bambini e trans cavie dei medici arcobaleno - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Adulti bambini e trans cavie dei medici arcobaleno che nelle loro chat rivelano negligenza sul cambio di sesso specie verso i minrenni\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/adulti-bambini-e-trans-cavie-dei-medici-arcobaleno\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adulti bambini e trans cavie dei medici arcobaleno - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Adulti bambini e trans cavie dei medici arcobaleno che nelle loro chat rivelano negligenza sul cambio di sesso specie verso i minrenni\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/adulti-bambini-e-trans-cavie-dei-medici-arcobaleno\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-13T23:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-14T07:44:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2024\/03\/Lgbt_disforia_genere_gender.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"280\" \/>\n\t<meta property=\"og:image:height\" content=\"180\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/adulti-bambini-e-trans-cavie-dei-medici-arcobaleno\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/adulti-bambini-e-trans-cavie-dei-medici-arcobaleno\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Adulti bambini e trans cavie dei medici arcobaleno\",\"datePublished\":\"2024-03-13T23:00:00+00:00\",\"dateModified\":\"2024-03-14T07:44:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/adulti-bambini-e-trans-cavie-dei-medici-arcobaleno\\\/\"},\"wordCount\":984,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/adulti-bambini-e-trans-cavie-dei-medici-arcobaleno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Lgbt_disforia_genere_gender.jpeg\",\"keywords\":[\"ideologia del gender\",\"transgender\"],\"articleSection\":[\"Ideologia del gender\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/adulti-bambini-e-trans-cavie-dei-medici-arcobaleno\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/adulti-bambini-e-trans-cavie-dei-medici-arcobaleno\\\/\",\"name\":\"Adulti bambini e trans cavie dei medici arcobaleno - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/adulti-bambini-e-trans-cavie-dei-medici-arcobaleno\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/adulti-bambini-e-trans-cavie-dei-medici-arcobaleno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Lgbt_disforia_genere_gender.jpeg\",\"datePublished\":\"2024-03-13T23:00:00+00:00\",\"dateModified\":\"2024-03-14T07:44:11+00:00\",\"description\":\"Adulti bambini e trans cavie dei medici arcobaleno che nelle loro chat rivelano negligenza sul cambio di sesso specie verso i minrenni\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/adulti-bambini-e-trans-cavie-dei-medici-arcobaleno\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/adulti-bambini-e-trans-cavie-dei-medici-arcobaleno\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/adulti-bambini-e-trans-cavie-dei-medici-arcobaleno\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Lgbt_disforia_genere_gender.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Lgbt_disforia_genere_gender.jpeg\",\"width\":280,\"height\":180},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/adulti-bambini-e-trans-cavie-dei-medici-arcobaleno\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adulti bambini e trans cavie dei medici arcobaleno\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Adulti bambini e trans cavie dei medici arcobaleno - Rassegna Stampa Cattolica","description":"Adulti bambini e trans cavie dei medici arcobaleno che nelle loro chat rivelano negligenza sul cambio di sesso specie verso i minrenni","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/adulti-bambini-e-trans-cavie-dei-medici-arcobaleno\/","og_locale":"it_IT","og_type":"article","og_title":"Adulti bambini e trans cavie dei medici arcobaleno - Rassegna Stampa Cattolica","og_description":"Adulti bambini e trans cavie dei medici arcobaleno che nelle loro chat rivelano negligenza sul cambio di sesso specie verso i minrenni","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/adulti-bambini-e-trans-cavie-dei-medici-arcobaleno\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2024-03-13T23:00:00+00:00","article_modified_time":"2024-03-14T07:44:11+00:00","og_image":[{"width":280,"height":180,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2024\/03\/Lgbt_disforia_genere_gender.jpeg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/adulti-bambini-e-trans-cavie-dei-medici-arcobaleno\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/adulti-bambini-e-trans-cavie-dei-medici-arcobaleno\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Adulti bambini e trans cavie dei medici arcobaleno","datePublished":"2024-03-13T23:00:00+00:00","dateModified":"2024-03-14T07:44:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/adulti-bambini-e-trans-cavie-dei-medici-arcobaleno\/"},"wordCount":984,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/adulti-bambini-e-trans-cavie-dei-medici-arcobaleno\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2024\/03\/Lgbt_disforia_genere_gender.jpeg","keywords":["ideologia del gender","transgender"],"articleSection":["Ideologia del gender"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/adulti-bambini-e-trans-cavie-dei-medici-arcobaleno\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/adulti-bambini-e-trans-cavie-dei-medici-arcobaleno\/","name":"Adulti bambini e trans cavie dei medici arcobaleno - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/adulti-bambini-e-trans-cavie-dei-medici-arcobaleno\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/adulti-bambini-e-trans-cavie-dei-medici-arcobaleno\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2024\/03\/Lgbt_disforia_genere_gender.jpeg","datePublished":"2024-03-13T23:00:00+00:00","dateModified":"2024-03-14T07:44:11+00:00","description":"Adulti bambini e trans cavie dei medici arcobaleno che nelle loro chat rivelano negligenza sul cambio di sesso specie verso i minrenni","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/adulti-bambini-e-trans-cavie-dei-medici-arcobaleno\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/adulti-bambini-e-trans-cavie-dei-medici-arcobaleno\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/adulti-bambini-e-trans-cavie-dei-medici-arcobaleno\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2024\/03\/Lgbt_disforia_genere_gender.jpeg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2024\/03\/Lgbt_disforia_genere_gender.jpeg","width":280,"height":180},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/adulti-bambini-e-trans-cavie-dei-medici-arcobaleno\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Adulti bambini e trans cavie dei medici arcobaleno"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/59805","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=59805"}],"version-history":[{"count":1,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/59805\/revisions"}],"predecessor-version":[{"id":59807,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/59805\/revisions\/59807"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/59806"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=59805"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=59805"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=59805"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}