{"id":5798,"date":"2013-11-21T00:00:00","date_gmt":"2013-11-20T23:00:00","guid":{"rendered":""},"modified":"2015-06-11T11:54:14","modified_gmt":"2015-06-11T09:54:14","slug":"viva-papa-francesco","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/viva-papa-francesco\/","title":{"rendered":"Viva Papa Francesco!"},"content":{"rendered":"<p align=\"center\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2013\/11\/papaFrancesco.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-7128 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2013\/11\/papaFrancesco.jpg\" alt=\"papaFrancesco\" width=\"130\" height=\"160\" \/><\/a>Centro culturale Lepanto<\/strong>\u00a019 novembre 2013<\/p>\n<p style=\"text-align: justify;\"><em>Una breve riflessione sui motivi della particolare devozione che il Centro Culturale Lepanto, come tutti i veri tradizionalisti, ha nei confronti di Papa Francesco.<\/em><\/p>\n<p style=\"text-align: justify;\">\u00c8 noto il fervente appello con il quale San Francesco d\u2019 Assisi (1181- 1226) raccomanda ai suoi frati di non fare risparmio di stoffe e metalli preziosi per onorare il culto sacro in Chiese e cappelle: \u201c\u2026 i calici, i corporali, gli ornamenti dell\u2019altare e tutto ci\u00f2 che serve al sacrificio, devono essere preziosi. E se in qualche luogo trovassero il santissimo corpo del Signore collocato in modo miserevole, venga da essi posto e custodito in un luogo prezioso, secondo le disposizioni della Chiesa.\u201d[I].<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Questo appello trova il suo fondamento dichiaratamente nelle disposizioni della Chiesa ed implicitamente nel passo evangelico ove si critica Giuda Iscariota, il traditore, per la sua disapprovazione verso chi onora il Sacro Corpo di N.S. Ges\u00f9 con costosi materiali preziosi: \u201cMaria allora, presa una libbra di profumo di nardo puro, molto prezioso, unse i piedi di Ges\u00f9 e glieli asciug\u00f2 coi suoi capelli, sicch\u00e9 la casa fu ripiena del profumo dell\u2019unguento.<\/p>\n<p style=\"text-align: justify;\">Ma disse Giuda Iscariota, uno dei suoi discepoli, quello che stava per tradirlo: \u2018Perch\u00e9 tale unguento non si \u00e8 venduto per trecento denari che potevano essere dati ai poveri?\u2019. Disse questo, non perch\u00e9 gli importasse dei poveri, ma perch\u00e9 era ladro e, tenendo la borsa portava via quel che ci veniva messo dentro\u201d [II]<\/p>\n<p style=\"text-align: justify;\">Non si pu\u00f2 tuttavia negare la distanza emotiva che San Francesco sentiva verso il pur lecito, e talvolta persino doveroso manifestare da parte del clero, negli abiti e negli altri privilegi annessi, lo Status relativo al proprio livello nella Santa Gerarchia.<\/p>\n<p style=\"text-align: justify;\">Una distanza emotiva che \u00e8 in realt\u00e0 spesso presente in uomini d\u2019azione come fu San Francesco, gi\u00e0 valoroso cavaliere e poi rimasto sempre attaccato, per tutta la sua vita, all\u2019ideale pi\u00f9 puro della Cavalleria medievale, mentre, al contrario, istintivamente considerava con una certa diffidenza gli studi e la docenza accademici.<\/p>\n<p style=\"text-align: justify;\">Questo spirito d\u2019azione si mantenne nella famiglia francescana, tanto da ispirare la Santa Sede a chiedere ai figli di San Francesco la redazione di manuali e di veri e propr\u00ee stud\u00ee strategici per la guerra di Crociata [III].<\/p>\n<p style=\"text-align: justify;\">Pi\u00f9 importante poi fu la pratica che la grammatica se consideriamo figure come il Beato Marco d\u2019Aviano (1631-1699), padre cappuccino animatore della resistenza cristiana all\u2019assedio di Vienna (1683), o San Giovanni da Capestrano (1386-1456), padre minorita e fedele discepolo di San Bernardino da Siena (1380-1444), che nella battaglia di Belgrado (1456) \u201csi riveler\u00e0 uno straordinario combattente militare e crociato\u201d[IV].<\/p>\n<p style=\"text-align: justify;\">Se a suo tempo i teorici francescani della Crociata prescrivevano ai \u201cpugiles Christi\u201d come armi essenziali la preghiera e la carit\u00e0 [V], oggi Papa Francesco non propone altri mezzi, nella concreta situazione attuale, per raggiungere quella Pace di Cristo nell\u2019Ordine di Cristo che da sempre \u00e8 la prospettiva in cui si muove la Chiesa Cattolica<\/p>\n<p style=\"text-align: justify;\">Tuttavia, nel considerare la mirabile complementarit\u00e0 che la Divina Provvidenza ha ispirato e permesso nella coesistenza del Papa emerito Benedetto XVI, fine teologo ed attento studioso del valore storico e spirituale di ogni particolare degli usi e costumi della Chiesa, e dell\u2019uomo d\u2019azione, nella preghiera e nella carit\u00e0, che \u00e8 il Papa regnante Francesco, non si pu\u00f2 non far conto dell\u2019umana fragilit\u00e0 dei fedeli, che porta spesso a dare giudiz\u00ee superficiali.<\/p>\n<p style=\"text-align: justify;\">Superficialit\u00e0 che portava alcuni fedeli a trovare freddo e distante Papa Benedetto e che oggi porta altri fedeli a pensare che Papa Francesco faccia \u201cle sue dichiarazioni spontanee su temi delicati che riguardano la morale personale e sociale (\u2026) senza star a misurare gli effetti di ci\u00f2 che dice\u201d [VI]<\/p>\n<p style=\"text-align: justify;\">Questo fatto ci porta a ricordare il rimprovero di Ges\u00f9:\u201dVi abbiamo suonato il flauto e non avete ballato: abbiamo cantato lamenti e non vi siete battuti il petto. \u00c8 venuto infatti Giovanni, che non mangia n\u00e9 beve, e dicono: Ha un demonio. \u00c8 venuto il Figlio dell\u2019uomo, che mangia e beve, e dicono: Ecco un mangione ed un bevitore, amico dei pubblicani e dei peccatori.\u201d [VII]<\/p>\n<p style=\"text-align: justify;\">Pi\u00f9 grave \u00e8 il caso di gruppi organizzati, per fortuna minoritar\u00ee, che levano a freddo ingiuste critiche al Romano Pontefice. Qui non vogliamo parlare dei gruppi della Sinistra, che ovviamente sono a priori nemici del Principio di Autorit\u00e0, ma di quelli che hanno \u201cradici\u201d nel mondo tradizionalista<\/p>\n<p style=\"text-align: justify;\">Ges\u00f9 Cristo, Incarnazione della Divina Sapienza, ci indica per\u00f2 con chiarezza qual \u00e8 il Fondamento della Chiesa.\u00a0Nostro Signore avrebbe potuto benissimo porre come Fondamento le Sue Parole, delle quali ha pur detto: \u201cIl cielo e la terra passeranno, ma le mie parole non passeranno\u201d [VIII], ma non l\u2019ha fatto. Ancora meglio avrebbe potuto porre come Fondamento della Chiesa Se stesso, il Redentore, ed ha pur detto: \u201cRimanete in me ed io in voi. Come il tralcio non pu\u00f2 da s\u00e9 portare frutto, se non rimane unito alla vite, cos\u00ec nemmeno voi, se non rimanete in me\u201d [IX] ma non l\u2019ha fatto.<\/p>\n<p style=\"text-align: justify;\">Ges\u00f9 Cristo invece si rivolge non al Collegio Apostolico, che aveva di fronte, ma a Simone, figlio di Giona, con queste parole: \u201cEd io dico a Te, che tu sei Pietro, e su questa pietra edificher\u00f2 la mia Chiesa, e le porte dell\u2019inferno mai prevarranno contro di lei. E a te dar\u00f2 le chiavi del regno dei cieli: e qualunque cosa avrai legata sulla terra, sar\u00e0 legata anche nei cieli; e qualunque cosa avrai sciolta sulla terra, sar\u00e0 sciolta anche nei cieli\u201d [X].<\/p>\n<p style=\"text-align: justify;\">Si badi che questa missione viene affidata ad un singolo uomo, per di pi\u00f9 non un gigante dalla adamantina impeccabilit\u00e0 ma un misero peccatore, del quale i Vangeli volutamente sottolineano la fragilit\u00e0, le mancanze di fede, la paura di una folla ostile.\u00a0A te dico, a te dar\u00f2: ad una singola persona alla volta, come tutti noi fragile peccatore, da duemila anni \u00e8 dato il compito di essere il Fondamento di una realt\u00e0 cui spiritualmente si affidano centinaia e centinaia di milioni di anime.<\/p>\n<p style=\"text-align: justify;\">\u00c8 paradossale che persone che vantano il proprio tradizionalismo cattolico accettino invece gli schemi mentali di una colonna del pensiero moderno e materialista quale \u00e8 lo studioso del Diritto Hans Kelsen<b>\u00a0<\/b>(1881-1973), teorico dello Stato di Diritto, per il quale \u00e8 assurdo che una grande realt\u00e0 sociale si affidi ad un singolo uomo in carne ed ossa: \u201cL\u2019uomo \u00e8 un concetto biologico e fisiologico, in breve, un concetto delle scienze naturali\u201d [XI].<\/p>\n<p style=\"text-align: justify;\">Perci\u00f2, secondo lui, un \u201cmero fenomeno naturale, non pu\u00f2 mai essere \u2018sovrano\u2019 nel senso proprio della parola\u201d [XII], quindi \u201csoltanto un ordinamento giuridico pu\u00f2 essere \u2018sovrano\u2019, cio\u00e8 un\u2019autorit\u00e0 suprema\u201d [XIII].<\/p>\n<p style=\"text-align: justify;\">Questi cosiddetti \u201ctradizionalisti\u201d sembrano quindi credere col Kelsen, ma contro Cristo, che la Chiesa abbia come Fondamento non quel singolo fragile peccatore che la Divina Provvidenza ci d\u00e0 come Papa nei var\u00ee momenti della Storia, ma una istituzione giuridica detta Papato, retta da un millenario quadro normativo ossia la Tradizione, basata sulla Grundnorm delle Sacre Scritture: una fantomatica \u201cChiesa di Diritto\u201d alla luce del cui quadro normativo ogni \u201ccittadino della Chiesa\u201d o \u201cfedele\u201d possa mettere in stato d\u2019accusa davanti al \u201ctribunale\u201d della pubblica opinione il responsabile pro tempore del Papato.<\/p>\n<p style=\"text-align: justify;\">\u00c8 di grande evidenza che il calpestare la sovranit\u00e0 di questo singolo uomo che \u00e8 il soggetto-Papa implica il calpestare la sovranit\u00e0 individuale, cio\u00e8 rinnegare quel gran dono divino che \u00e8 il libero arbitrio, di ogni altro \u201cfenomeno biologico e fisiologico\u201d, ossia di ogni altro soggetto, cos\u00ec togliendo ogni senso all\u2019esistenza di creature razionali, quali sono gli Uomini ed anche gli Angeli, nonch\u00e9 del premio e della punizione, Paradiso e Inferno.<\/p>\n<p style=\"text-align: justify;\">Per quanto riguarda il Centro Culturale Lepanto, una sola \u00e8 la conclusione: Viva Papa Francesco.<\/p>\n<p style=\"text-align: center;\">_______________________<\/p>\n<p style=\"text-align: justify;\"><strong>[I]<\/strong>\u00a0S. Francesco d\u2019Assisi, Prima Lettera ai Custodi, \u00a7 241<\/p>\n<p style=\"text-align: justify;\"><strong>[II]<\/strong>\u00a0S. Giovanni, 12, 3-6.<\/p>\n<p style=\"text-align: justify;\"><strong>[III]<\/strong>\u00a0Cfr. P. Girolamo Gobulovich O.F.M., Biblioteca bio-bibliografica della Terra Santa e dell\u2019Oriente francescano, Firenze, Quaracchi, 1913, Tomo II, pp. 1-60; Paolo Evangelisti, Fidenzio da Padova e la letteratura crociato-missionaria minoritica, Bologna, Il mulino, 1998.<\/p>\n<p style=\"text-align: justify;\"><strong>[IV]<\/strong>\u00a0Paolo Evangelisti, cit., p. 231.<\/p>\n<p style=\"text-align: justify;\"><strong>[V]<\/strong>\u00a0Op. cit., pp. 42 e ss..<\/p>\n<p style=\"text-align: justify;\"><strong>[VI]<\/strong>\u00a0Mons. Bruno Forte, Sincerit\u00e0, semplicit\u00e0, sobriet\u00e0: ecco Francesco, in \u201cIl Sole 24 Ore\u201d, 17 Novembre 2013, p.17.<\/p>\n<p style=\"text-align: justify;\"><strong>[VII]<\/strong>\u00a0S. Matteo, 11, 17-19.<\/p>\n<p style=\"text-align: justify;\"><strong>[VIII]<\/strong>\u00a0S. Marco, 13, 31.<\/p>\n<p style=\"text-align: justify;\"><strong>[IX]<\/strong>\u00a0S. Giovanni, 15, 4.<\/p>\n<p style=\"text-align: justify;\"><strong>[X]<\/strong>\u00a0S. Matteo, 16, 18-19.<\/p>\n<p style=\"text-align: justify;\"><strong>[XI]<\/strong>\u00a0Hans Kelsen, Teoria generale del diritto e dello Stato, Milano, ETAS, 1994, p.373.<\/p>\n<p style=\"text-align: justify;\"><strong>[XII]<\/strong>\u00a0Op.cit., p.189<\/p>\n<p style=\"text-align: justify;\"><strong>[XIII]<\/strong>\u00a0Op-cit., p.389.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Centro culturale Lepanto\u00a019 novembre 2013 Una breve riflessione sui motivi della particolare devozione che il Centro Culturale Lepanto, come tutti i veri tradizionalisti, ha nei confronti di Papa Francesco. \u00c8 noto il fervente appello con il quale San Francesco d\u2019 Assisi (1181- 1226) raccomanda ai suoi frati di non fare risparmio di stoffe e metalli &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/viva-papa-francesco\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":7128,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,123],"tags":[157,291],"class_list":["post-5798","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chiesa","category-ss-francesco","tag-chiesa-2","tag-papa-francesco","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Viva Papa Francesco! - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/viva-papa-francesco\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Viva Papa Francesco! - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/viva-papa-francesco\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2013-11-20T23:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-06-11T09:54:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2013\/11\/papaFrancesco.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"196\" \/>\n\t<meta property=\"og:image:height\" content=\"257\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/viva-papa-francesco\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/viva-papa-francesco\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Viva Papa Francesco!\",\"datePublished\":\"2013-11-20T23:00:00+00:00\",\"dateModified\":\"2015-06-11T09:54:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/viva-papa-francesco\\\/\"},\"wordCount\":1373,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/viva-papa-francesco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2013\\\/11\\\/papaFrancesco.jpg\",\"keywords\":[\"chiesa\",\"Papa Francesco\"],\"articleSection\":[\"Chiesa\",\"SS Francesco\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/viva-papa-francesco\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/viva-papa-francesco\\\/\",\"name\":\"Viva Papa Francesco! - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/viva-papa-francesco\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/viva-papa-francesco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2013\\\/11\\\/papaFrancesco.jpg\",\"datePublished\":\"2013-11-20T23:00:00+00:00\",\"dateModified\":\"2015-06-11T09:54:14+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/viva-papa-francesco\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/viva-papa-francesco\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/viva-papa-francesco\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2013\\\/11\\\/papaFrancesco.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2013\\\/11\\\/papaFrancesco.jpg\",\"width\":196,\"height\":257},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/viva-papa-francesco\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Viva Papa Francesco!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Viva Papa Francesco! - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/viva-papa-francesco\/","og_locale":"it_IT","og_type":"article","og_title":"Viva Papa Francesco! - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/viva-papa-francesco\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2013-11-20T23:00:00+00:00","article_modified_time":"2015-06-11T09:54:14+00:00","og_image":[{"width":196,"height":257,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2013\/11\/papaFrancesco.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/viva-papa-francesco\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/viva-papa-francesco\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Viva Papa Francesco!","datePublished":"2013-11-20T23:00:00+00:00","dateModified":"2015-06-11T09:54:14+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/viva-papa-francesco\/"},"wordCount":1373,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/viva-papa-francesco\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2013\/11\/papaFrancesco.jpg","keywords":["chiesa","Papa Francesco"],"articleSection":["Chiesa","SS Francesco"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/viva-papa-francesco\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/viva-papa-francesco\/","name":"Viva Papa Francesco! - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/viva-papa-francesco\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/viva-papa-francesco\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2013\/11\/papaFrancesco.jpg","datePublished":"2013-11-20T23:00:00+00:00","dateModified":"2015-06-11T09:54:14+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/viva-papa-francesco\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/viva-papa-francesco\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/viva-papa-francesco\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2013\/11\/papaFrancesco.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2013\/11\/papaFrancesco.jpg","width":196,"height":257},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/viva-papa-francesco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Viva Papa Francesco!"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/5798","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=5798"}],"version-history":[{"count":7,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/5798\/revisions"}],"predecessor-version":[{"id":26064,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/5798\/revisions\/26064"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/7128"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=5798"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=5798"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=5798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}