{"id":571,"date":"2005-05-24T00:00:00","date_gmt":"2005-05-23T22:00:00","guid":{"rendered":""},"modified":"2015-11-19T17:17:44","modified_gmt":"2015-11-19T16:17:44","slug":"escalation-a-est-la-prova-di-forza-della-cina-sullatomica-nordcoreana","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/escalation-a-est-la-prova-di-forza-della-cina-sullatomica-nordcoreana\/","title":{"rendered":"Escalation a Est. La prova di forza della Cina sull\u2019atomica nordcoreana"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/05\/Korea-missile.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-27952\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/05\/Korea-missile.jpg\" alt=\"Korea-missile\" width=\"250\" height=\"166\" \/><\/a>Il Foglio<\/strong> 18 maggio 2005<\/div>\n<p style=\"text-align: justify;\"><em>La Cina non \u00e8 nostra amica. Questo lo dovremmo sapere gi\u00e0 da tempo. Si tratta invece di rendersi conto che la visione dominante della Cina come un paese cauto e contrario ad assumersi grossi rischi \u00e8 del tutto sbagliata. I cinesi hanno appena permesso che un paese come la Corea del Nord si dotasse di armamenti nucleari soltanto per ottenere un successo contro gli Stati Uniti nel grande gioco delle superpotenze. E\u2019 difficile immaginarsi un atto pi\u00f9 aggressivo e avventato di questo.<\/em><\/p>\n<p style=\"text-align: center;\">di <strong>David Frum<\/strong><\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">Qualsiasi cosa accada, lo stallo sulla penisola coreana \u00e8 stato certamente istruttivo. Sembra probabile che molto presto la Corea del Nord prover\u00e0 un nuovo ordigno nucleare. Se non lo far\u00e0, non sar\u00e0 perch\u00e9 non lo possiede o perch\u00e9 gli Stati Uniti l\u2019avranno persuasa, ma perch\u00e9 la Corea del Sud l\u2019avr\u00e0 convinta a suon di soldi.<\/div>\n<p style=\"text-align: justify;\">Ma a cosa serviranno questi soldi? Non certo a comprarsi la sicurezza: la Corea del Nord continuer\u00e0 a possedere la bomba atomica. N\u00e9, tantomeno, ad avviare dei concreti negoziati: la Corea del Nord \u00e8 gi\u00e0 da tempo arrivata alla conclusione che ottiene di pi\u00f9 comportandosi in modo deciso e intransigente anzich\u00e9 scendere a compromessi e trattative. Questi soldi serviranno soltanto a comperare la falsa impressione della sicurezza, un sollievo temporaneo dalla necessit\u00e0 di riconoscere la dura realt\u00e0: la dittatura pi\u00f9 instabile del mondo \u00e8 entrata a far parte del club nucleare.<\/p>\n<p style=\"text-align: justify;\">Come siamo giunti a questo disastro? La storia comincia alla fine degli anni Ottanta, quando gli Stati Uniti vennero per la prima volta a conoscenza del programma nucleare nordcoreano. L\u2019amministrazione di George Bush padre affront\u00f2 la minaccia nel modo sempre preferito dai nostri alleati europei: una silenziosa diplomazia multilaterale. Ma la diplomazia fall\u00ec e il programma nucleare nordcoreano and\u00f2 avanti.<\/p>\n<p style=\"text-align: justify;\">Nel 1992 Stati Uniti e Corea del Nord si trovarono quasi sul punto di una guerra. Ma l\u2019amministrazione del nuovo presidente Clinton si oppose subito all\u2019uso della forza militare. Clinton invi\u00f2 in Corea del Nord l\u2019ex presidente Jimmy Carter per intavolare dei negoziati. In cambio di cibo, petrolio e denaro, nonch\u00e9 la promessa di due reattori nucleari ad acqua leggera, la Corea del Nord accett\u00f2 di interrompere il proprio programma nucleare e, per dimostrare la propria buona fede, consent\u00ec addirittura che gli americani collocassero videocamere nei suoi laboratori.<\/p>\n<p style=\"text-align: justify;\">Poi, dopo aver ottenuto tutto quanto promesso, i nordcoreani costruirono nuovi laboratori e ripresero il proprio programma di sviluppo nucleare. Furono scoperti nel 2002, ma ormai erano vicinissimi alla produzione di una bomba atomica, se non l\u2019avevano addirittura gi\u00e0 costruita.<\/p>\n<p style=\"text-align: justify;\">Ecco quali lezioni dovremmo trarre da questa terribile esperienza:<\/p>\n<p style=\"text-align: justify;\">1) Non ci si pu\u00f2 fidare di regimi inaffidabili. Piuttosto ovvio, vero? Ma molte persone continuano a credere (o comunque a cercare di persuadere altri a farlo) che possiamo negoziare accordi con regimi come quello nordcoreano: per esempio, l\u2019Iran. Ma accordi di questo genere servono solo come stampelle psicologiche: un modo per illuderci che stiamo prendendo dei provvedimenti quando invece non stiamo facendo assolutamente nulla.<\/p>\n<p style=\"text-align: justify;\">2) Ci piace ripetere che la guerra deve essere sempre l\u2019ultima scelta. Ma, in retrospettiva, ci si accorge che, nei confronti della Corea del Nord, avevamo nel 1992 migliori opportunit\u00e0 militari che nel 2002. Se sappiamo che un regime pericoloso \u00e8 deciso a procurarsi armi nucleari, quanto pi\u00f9 agiamo rapidamente tanto pi\u00f9 numerose saranno le nostre speranze di successo.<\/p>\n<p style=\"text-align: justify;\">3) Senza l\u2019aiuto della Cina, il regime nordcoreano sarebbe crollato all\u2019inizio degli anni Novanta. Quando i nordcoreani fanno qualcosa che non l\u2019aggrada, la Cina chiude i rubinetti del petrolio e i nordcoreani cambiano subito atteggiamento. Le pressioni economiche cinesi avrebbero potuto persuadere la Corea del Nord a interrompere il proprio programma di sviluppo nucleare. Ma queste pressioni non sono mai state esercitate. Al contrario, la Cina sembra aver attivamente incoraggiato questo programma, apparentemente nella speranza che una Corea del Nord dotata di armi nucleari potereste ottenere maggiori aiuti dalla Corea del Sud e dal Giappone, riducendo cos\u00ec i costi sostenuti dalla Cina. Forse i cinesi speravano anche che in questo modo si sarebbe riusciti a persuadere la Corea del Sud ad abbandonare la protezione degli Stati Uniti e ad allearsi con la Cina. Se \u00e8 cos\u00ec, i loro piani sembrano sul punto di realizzarsi.<\/p>\n<p style=\"text-align: justify;\">Per quanto riguarda la Cina, la lezione che dobbiamo trarre non \u00e8 semplicemente che la Cina non \u00e8 nostra amica. Questo lo dovremmo sapere gi\u00e0 da tempo. Si tratta invece di rendersi conto che la visione dominante della Cina come un paese cauto e contrario ad assumersi grossi rischi \u00e8 del tutto sbagliata. I cinesi hanno appena permesso che un paese come la Corea del Nord si dotasse di armamenti nucleari soltanto per ottenere un successo contro gli Stati Uniti nel grande gioco delle superpotenze. E\u2019 difficile immaginarsi un atto pi\u00f9 aggressivo e avventato di questo.<\/p>\n<p style=\"text-align: justify;\">Proprio come l\u201911 settembre ha aperto gli occhi del mondo sulle minacciose realt\u00e0 del mondo musulmano, la crisi dell\u2019Asia nordorientale deve far comprendere la verit\u00e0 sulla Cina e il Pacifico, Auguriamoci che l\u2019illuminazione non sia giunta troppo tardi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Foglio 18 maggio 2005 La Cina non \u00e8 nostra amica. Questo lo dovremmo sapere gi\u00e0 da tempo. Si tratta invece di rendersi conto che la visione dominante della Cina come un paese cauto e contrario ad assumersi grossi rischi \u00e8 del tutto sbagliata. I cinesi hanno appena permesso che un paese come la Corea &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/escalation-a-est-la-prova-di-forza-della-cina-sullatomica-nordcoreana\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":27952,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56,19],"tags":[2395],"class_list":["post-571","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cina","category-politica-internazionale","tag-cina","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Escalation a Est. La prova di forza della Cina sull\u2019atomica nordcoreana - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/escalation-a-est-la-prova-di-forza-della-cina-sullatomica-nordcoreana\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Escalation a Est. La prova di forza della Cina sull\u2019atomica nordcoreana - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/escalation-a-est-la-prova-di-forza-della-cina-sullatomica-nordcoreana\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2005-05-23T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-11-19T16:17:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/05\/Korea-missile.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"275\" \/>\n\t<meta property=\"og:image:height\" content=\"183\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/escalation-a-est-la-prova-di-forza-della-cina-sullatomica-nordcoreana\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/escalation-a-est-la-prova-di-forza-della-cina-sullatomica-nordcoreana\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Escalation a Est. La prova di forza della Cina sull\u2019atomica nordcoreana\",\"datePublished\":\"2005-05-23T22:00:00+00:00\",\"dateModified\":\"2015-11-19T16:17:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/escalation-a-est-la-prova-di-forza-della-cina-sullatomica-nordcoreana\\\/\"},\"wordCount\":842,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/escalation-a-est-la-prova-di-forza-della-cina-sullatomica-nordcoreana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/05\\\/Korea-missile.jpg\",\"keywords\":[\"Cina\"],\"articleSection\":[\"Cina\",\"Politica internazionale\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/escalation-a-est-la-prova-di-forza-della-cina-sullatomica-nordcoreana\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/escalation-a-est-la-prova-di-forza-della-cina-sullatomica-nordcoreana\\\/\",\"name\":\"Escalation a Est. La prova di forza della Cina sull\u2019atomica nordcoreana - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/escalation-a-est-la-prova-di-forza-della-cina-sullatomica-nordcoreana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/escalation-a-est-la-prova-di-forza-della-cina-sullatomica-nordcoreana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/05\\\/Korea-missile.jpg\",\"datePublished\":\"2005-05-23T22:00:00+00:00\",\"dateModified\":\"2015-11-19T16:17:44+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/escalation-a-est-la-prova-di-forza-della-cina-sullatomica-nordcoreana\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/escalation-a-est-la-prova-di-forza-della-cina-sullatomica-nordcoreana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/escalation-a-est-la-prova-di-forza-della-cina-sullatomica-nordcoreana\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/05\\\/Korea-missile.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/05\\\/Korea-missile.jpg\",\"width\":275,\"height\":183},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/escalation-a-est-la-prova-di-forza-della-cina-sullatomica-nordcoreana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Escalation a Est. La prova di forza della Cina sull\u2019atomica nordcoreana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Escalation a Est. La prova di forza della Cina sull\u2019atomica nordcoreana - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/escalation-a-est-la-prova-di-forza-della-cina-sullatomica-nordcoreana\/","og_locale":"it_IT","og_type":"article","og_title":"Escalation a Est. La prova di forza della Cina sull\u2019atomica nordcoreana - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/escalation-a-est-la-prova-di-forza-della-cina-sullatomica-nordcoreana\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2005-05-23T22:00:00+00:00","article_modified_time":"2015-11-19T16:17:44+00:00","og_image":[{"width":275,"height":183,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/05\/Korea-missile.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/escalation-a-est-la-prova-di-forza-della-cina-sullatomica-nordcoreana\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/escalation-a-est-la-prova-di-forza-della-cina-sullatomica-nordcoreana\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Escalation a Est. La prova di forza della Cina sull\u2019atomica nordcoreana","datePublished":"2005-05-23T22:00:00+00:00","dateModified":"2015-11-19T16:17:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/escalation-a-est-la-prova-di-forza-della-cina-sullatomica-nordcoreana\/"},"wordCount":842,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/escalation-a-est-la-prova-di-forza-della-cina-sullatomica-nordcoreana\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/05\/Korea-missile.jpg","keywords":["Cina"],"articleSection":["Cina","Politica internazionale"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/escalation-a-est-la-prova-di-forza-della-cina-sullatomica-nordcoreana\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/escalation-a-est-la-prova-di-forza-della-cina-sullatomica-nordcoreana\/","name":"Escalation a Est. La prova di forza della Cina sull\u2019atomica nordcoreana - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/escalation-a-est-la-prova-di-forza-della-cina-sullatomica-nordcoreana\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/escalation-a-est-la-prova-di-forza-della-cina-sullatomica-nordcoreana\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/05\/Korea-missile.jpg","datePublished":"2005-05-23T22:00:00+00:00","dateModified":"2015-11-19T16:17:44+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/escalation-a-est-la-prova-di-forza-della-cina-sullatomica-nordcoreana\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/escalation-a-est-la-prova-di-forza-della-cina-sullatomica-nordcoreana\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/escalation-a-est-la-prova-di-forza-della-cina-sullatomica-nordcoreana\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/05\/Korea-missile.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/05\/Korea-missile.jpg","width":275,"height":183},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/escalation-a-est-la-prova-di-forza-della-cina-sullatomica-nordcoreana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Escalation a Est. La prova di forza della Cina sull\u2019atomica nordcoreana"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/571","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=571"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/571\/revisions"}],"predecessor-version":[{"id":27953,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/571\/revisions\/27953"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/27952"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=571"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=571"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=571"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}