{"id":56923,"date":"2023-10-05T00:00:00","date_gmt":"2023-10-04T22:00:00","guid":{"rendered":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=56923"},"modified":"2024-01-04T15:56:42","modified_gmt":"2024-01-04T14:56:42","slug":"a-bruxelles-una-lobby-lavora-per-il-superstato","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/a-bruxelles-una-lobby-lavora-per-il-superstato\/","title":{"rendered":"L&#8217;Unione europea verso un bolscevismo morbido"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-24674 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/12\/eurss.jpg\" alt=\"\" width=\"208\" height=\"191\" \/>Abstract:\u00a0<\/strong><em> <span style=\"color: #000000;\">l&#8217;Unione europea\u00a0 sta creando un superstato oligarchico che mira ad attuare una\u00a0 bolscevizzazione morbida del continente mediante una erosione graduale e\u00a0 strisciante delle competenze degli stati membri .\u00a0Le istituzioni Ue, in particolare la Commissione, il Parlamento europeo e la Corte di giustizia dell\u2019Unione europea, violano quattro principi: il principio di attribuzione, di sussidiariet\u00e0, di proporzionalit\u00e0\u00a0 e di prossimit\u00e0. Intervista a acek Saryusz Wolsky, polacco che ha maturato una lunga carriere a Bruxelles\u00a0<\/span><\/em><\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\"><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/www.bing.com\/ck\/a?!&amp;&amp;p=819f45094df1cd10JmltdHM9MTcwMDQzODQwMCZpZ3VpZD0xY2VkZGE5YS0yMTM5LTY4MjAtMmY0Zi1jYjVlMjBkODY5Y2MmaW5zaWQ9NTIzMA&amp;ptn=3&amp;ver=2&amp;hsh=3&amp;fclid=1cedda9a-2139-6820-2f4f-cb5e20d869cc&amp;psq=il+timone&amp;u=a1aHR0cHM6Ly93d3cuaWx0aW1vbmUub3JnLw&amp;ntb=1\" target=\"_blank\" rel=\"noopener\"><strong>Il Timone<\/strong><\/a><\/span> n. 231 Settembre 2023<\/span><\/p>\n<h3 style=\"text-align: center;\"><strong>A Bruxelles una lobby lavora per il Superstato<\/strong><\/h3>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><em>E\u2019 un\u2019erosione strisciante, graduale e illegittima di competenze a spese degli Stati membri. La compie un sistema di \u00abbolscevismo morbido\u00bb. L\u2019allarme del veterano polacco del Parlamento europeo Jacek Saryusz Wolsky<\/em><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\">di <strong>Wlodzimierz <span style=\"color: #000000;\">Redzioch<\/span> <\/strong><\/span><\/p>\n<div id=\"attachment_56925\" style=\"width: 287px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-56925\" class=\"wp-image-56925\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2023\/09\/Jacek_Saryusz_Wolsky_Polonia_Europa_Ue.jpg\" alt=\"\" width=\"287\" height=\"194\" \/><p id=\"caption-attachment-56925\" class=\"wp-caption-text\">Jacek Saryusz Wolsky<\/p><\/div>\n<p style=\"text-align: justify;\">J<span style=\"color: #000000;\">acek Saryusz Wolsky \u00e8 un economista e politico polacco, uno dei principali negoziatori dell\u2019adesione della Polonia all\u2019Unione europea. Negli anni 1991-1996 e 2000-2001 \u00e8 stato ministro degli affari europei, dal 2004, membro del Parlamento europeo nelle successive legislature: VI, VII, VIII e IX. Negli anni 2004-2007 \u00e8 stato anche vicepresidente del Parlamento europeo, dal 2007 al 2009 presidente della commissione per gli affari esteri del Parlamento popolare europeo. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Il 4 marzo 2017 ha proposto la sua candidatura alla carica di presidente del Consiglio europeo (allora era ministro degli affari esteri nel governo polacco di Beata Szydlo), carica occupata da Donald Tusk, suo compagno del partito Piattaforma civica. Lo stesso giorno fu rimosso da Piattaforma civica e, di conseguenza, ha perso anche la carica di vicepresidente del Partito popolare europeo. Nel febbraio 2019 \u00e8 stato nominato capolista della lista dell\u2019altro partito polacco, PiS (Leggi e giustizia), alle elezioni per il Parlamento europeo e nel marzo dello stesso anno \u00e8 entrato a far parte della fazione dei Conservatori e riformisti europei. A seguito del voto del maggio 2019 \u00e8 stato cos\u00ec eletto per la quarta volta al Parlamento europeo, del quale quindi oggi \u00e8 un veteran<\/span>o.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>Lei siede nel Parlamento europeo da vent\u2019anni e ha il privilegio di poter osservare cosa succede nel \u201ccuore\u201d politico dell\u2019Unione europea. Ma in questi vent\u2019anni il suo entusiasmo si \u00e8 tramutato in preoccupazione. Che cosa sta succedendo a Bruxelles?<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-7461 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/05\/europarlamento.jpg\" alt=\"\" width=\"280\" height=\"210\" \/>\u00abOggi, all\u2019interno della Ue, osserviamo molte attivit\u00e0 pericolose e tendenze alla centralizzazione che vengono promosse dal cosiddetto <em>mainstream<\/em> dell\u2019Ue, che chiamer\u00f2 il \u201cgruppo di potere\u201d. Va sottolineato che, contrariamente alla confusione terminologica, spesso voluta nei discorsi ufficiali, il processo a cui stiamo assistendo \u00e8 in realt\u00e0 la centralizzazione, non la federalizzazione dell\u2019Ue. Nel caso della federalizzazione, dove le componenti sono uguali o quasi, il sistema \u00e8 basato sull\u2019equilibrio: cos\u00ec funziona, ad esempio, il sistema dei Cantoni svizzeri, degli Stati americani e degli Stati federali tedeschi. A sua volta il Superstato oligarchico centralizzato &#8211; in cui alcuni governano e altri sono governati, c\u2019\u00e8 un egemone e le periferie \u2013 si basa su profonde diseguaglianze e sulla logica della forza della coercizione\u00bb.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>Cosa caratterizza questo Superstato oligarchico europeo in costruzione?<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">\u00abPrima di tutto, nel sistema Ue mancano i cosiddetti controlli ed equilibri adeguati, i cosiddetti <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/www.treccani.it\/enciclopedia\/check-and-balance\/\" target=\"_blank\" rel=\"noopener\"><em>checks and balances<\/em><\/a><\/span>. Non esistono meccanismi che possano difendere efficacemente gli interessi dei paesi di piccole e medie dimensioni. Si tratta invece di una tendenza a creare un concerto di poteri all\u2019interno della Ue, una sorta di direttorio basato sulla collusione dei grandi Stati e dei loro subalterni e sull\u2019esclusione degli altri. Sullo sfondo di questo predominio del direttorio dell\u2019Ue sono state create condizioni favorevoli per pratiche sleali e irregolarit\u00e0 come corruzione, conflitti di interesse, traffico d\u2019influenza, protezione retribuita, usurpazione di competenze\u00bb<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>Qualche esempio di tali pratiche?<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"> <img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-56926 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2023\/09\/Eu_Qatargate_europa.jpg\" alt=\"\" width=\"300\" height=\"171\" \/>\u00abGli esempi sono numerosi, come il recente scandalo di corruzione, il <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-gauche-qatar-cosi-la-sinistra-europea-ha-stretto-un-patto-con-i-fratelli-musulmani\/\" target=\"_blank\" rel=\"noopener\"><em>Qatargate<\/em>,<\/a><\/span> e le attivit\u00e0 descritte nel 2021 dal redattore Jean Quatremeter in <em>Lib\u00e9ration<\/em> riguardanti la Corte dei conti europea, la Corte di giustizia dell\u2019Unione europea, il Partito popolare europeo e la Commissione europea. Un altro elemento \u00e8 il fatto che lo spazio per il dialogo nell\u2019Unione \u00e8 sistematicamente limitato. Un politologo irlandese, il professor Peter Mair, nel suo articolo intitolato <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/www.cambridge.org\/core\/journals\/government-and-opposition\/article\/political-opposition-and-the-european-union1\/7C9AEB444CBFE3FF85AE655C9CD4DD93\" target=\"_blank\" rel=\"noopener\"><em>Political opposition and the European union<\/em><\/a><\/span>, gi\u00e0 nel 2007 sottolineava il fatto che l\u2019Ue non ha sviluppato un\u2019opposizione politica organizzata, il che rende\u00a0 l\u2019Ue una democrazia incompleta, imperfetta e immatura. Nell\u2019attuale Unione manca una formale opposizione politica, o addirittura manca il consenso all\u2019esistenza di essa. In pratica vengono isolate ed escluse dai processi decisionali quelle forze politich, partiti e gruppi che non sono d\u2019accordo con la corrente politica principale, il <em>mainstream<\/em>\u00bb.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>Allora di che sistema si tratta?<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-43992 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/08\/eurss_europa-300x168.jpg\" alt=\"\" width=\"300\" height=\"168\" \/>\u00abUsando un linguaggio giornalistico, io definirei \u201cbolscevismo morbido\u201d. Non c\u2019\u00e8 posto per il dialogo in questo sistema, invece c\u2019\u00e8 un consenso sistemico all\u2019uso della forza, che si manifesta nella violenza politica, istituzionale, legale e finanziaria ampiamente praticata. Di conseguenza lo squilibrio strutturale dell\u2019Ue e la relativa inclinazione sistemica ad applicare selettivamente la forza e la penalizzazione portano ad una centralizzazione oligarchica e antidemocratica della Ue. Ci\u00f2 si manifesta nella continua appropriazione e usurpazione di competenze da parte delle istituzioni della Ue. In breve si tratta di un\u2019acquisizione strisciante, graduale e illegittima di competenze da parte delle istituzioni dell\u2019Ue a spese degli altri Stati membri. L\u2019obiettivo di questo processo \u00e8 una modifica del sistema Ue al di fuori dei trattati e la costruzione di un superstato oligarchico\u00bb<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>Quali principi sanciti dai trattati vengono violati?<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">\u00abLe istituzioni Ue, in particolare la Commissione, il Parlamento europeo e la Corte di giustizia dell\u2019Unione europea, violano quattro principi: il principio di attribuzione, di sussidiariet\u00e0, di proporzionalit\u00e0\u00a0 e di prossimit\u00e0. Questi pincipi derivano direttamente dai Trattati, e i limiti di competenza sono disciplinati in modo molto chiaro nell\u2019articolo 5 e 10 del Trattato sull\u2019Unione europea. Sia gli Stati membri che le istituzioni Ue sono tenuti a rispettare questi principi, cosa che ostentatamente non fanno\u00bb.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>Gli attacchi alla Polonia sono un palese esempio di violazione di tali principi.<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-56927 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2023\/09\/polonia_europa_Ue.jpg\" alt=\"\" width=\"271\" height=\"198\" \/>\u00abGli attacchi alla Polonia sono un esempio di una aggressiva ingerenza delle istituzioni dell\u2019Ue nell\u2019organizzazione del sistema giudiziario di certi Stati membri al fine di forzare illegalmente i cambiamenti. Si usa anche l\u2019arma del ricatto finanziario. Questo \u00e8 ovviamente violazione dei trattati, agire <em>ultra vires<\/em>, al di la dei poteri. Questa ingerenza <em>ultra vires<\/em> ha un fine politico nascosto: convincere l\u2019opinione pubblica in Polonia e nella Ue che i tribunali sono di competenza dell\u2019Unione \u2013 anche se questo non \u00e8 vero -, al fine di facilitare ulteriori interferenze illecite e successivamente il cambiamento del sistema dell\u2019Ue tramite un nuovo trattato. E\u2019 una grande azione dell\u2019ingegneria sociale rivolta alle societ\u00e0 europee\u00bb.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>Quale \u00e8 lo scopo principale del \u201cdirettorio\u201d dell\u2019Ue?<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">\u00ab<span style=\"color: #000000;\">Tutte le azioni del direttorio servono a forzare le modifiche del Trattato nello spirito della centralizzazione , la transizione da un\u2019unione di Stati sovrani a un Superstato Ue con una sorta di sovranit\u00e0 autonoma sottratta agli Stati e privata del controllo e della supervisione democratica. Lo scopo ultimo \u00e8 cambiare il sistema dell\u2019Ue, cio\u00e8 creare un Superstato oligarchico. Ultimamente si \u00e8 tenuta la Conferenza sul futuro dell\u2019Europa\u00bb.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-56928 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2023\/09\/conferenza_europa_Ue.jpg\" alt=\"\" width=\"312\" height=\"231\" \/>Anche questa Conferenza serviva per raggiungere gli scopi del direttorio di cui lei ha parlato?<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">\u00abE\u2019 stata un esperimento e una manipolazione socio-tecnica su larga scala, volta a legittimare l\u2019assunzione di competenze da parte dell\u2019Unione e a minare l\u2019ordine giuridico e politico dell\u2019Ue. In questo spirito vanno interpretate anche alcune delle raccomandazioni della conferenza, compresi i postulati riguardanti l\u2019abolizione della regola dell\u2019unanimit\u00e0 sulle votazioni in Consiglio e l\u2019ulteriore trasferimento di competenze dal livello nazionale a quello comunitario\u00bb<\/span>.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>Gli ultimi anni sono stati caratterizzati dalla crisi causata dalla pandemia e adesso dalla guerra in Ucraina. Queste crisi come influiscono sulla Ue?<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">\u00abNelle istituzioni come il Parlamento europeo crisi come la pandemia di Coronavirus o la guerra in Ucraina vengono strumentalizzate: con questi pretesti si richiedono nuovi poteri per l\u2019Ue e la riforma del potere decisionale. Di qui le richieste di concedere nuove competenze all\u2019Ue, ad esempio nel campo della tutela della salute, e di abolire la regola dell\u2019unanimit\u00e0 nelle votazioni in Consiglio in materia di politica estera e di sicurezza\u00bb.<\/span><\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-56929 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2023\/09\/Europa_Ue_trattati.jpg\" alt=\"\" width=\"306\" height=\"204\" \/>Ci sarebbero altre vie per affrontare queste crisi?<\/span><\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">\u00abGli attuali Trattati offrono molte opportunit\u00e0 di azione e la vera ragione della debolezza dell\u2019Unione \u00e8 la mancanza di volont\u00e0 politica, l\u2019ostruzionismo e l\u2019egoismo dei maggiori Stati membri: Germania e Francia. Va tenuto presente che l\u2019abolizione del diritto di veto rafforzer\u00e0 i grandi Stati membri, che manterranno per s\u00e9 il veto <em>de facto<\/em> grazie al loro vantaggio, tenendo conto del peso demografico del loro voto, integrato dai loro Stati clientelari, e indebolir\u00e0 decisamente gli Stati medi e piccoli dell\u2019Ue\u00bb.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>Si dice a Bruxelles che, per un ulteriore allargamento dell\u2019Unione all\u2019Ucraina, occorra riformare il Trattato di Lisbona<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">\u00abQuesta \u00e8 una trappola e un ricatto allo stesso tempo. Chi vuole cambiare i Trattati dice: o acconsentite alla formazione di un Superstato dell\u2019Ue o si blocca l\u2019adesione dell\u2019Ucraina. Ovviamente per indebolire la resistenza degli Stati e ingannare l\u2019opinione pubblica, la narrazione ufficiale non parla di centralizzazione, ma parla della necessit\u00e0 di migliorare il processo decisionale. Ma tutto questo serve per realizzare gli interessi di Germania e Francia, rafforzare le istituzioni dell\u2019Ue dominate dal gruppo che detiene il potere e limitare l\u2019influenza degli altri Stati membri\u00bb<\/span>.<\/p>\n<p>_______________________________<\/p>\n<p><span style=\"color: #000000;\"><strong>Sulla bolscevizzazione dell&#8217;Unione europea leggi anche:<\/strong><\/span><\/p>\n<p><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/occhio-alla-ue-i-gulag-iniziarono-cosi-il-grido-di-vladimir-bukovsky\/\" target=\"_blank\" rel=\"noopener\">Occhio alla UE: i Gulag iniziarono cos\u00ec! Il grido di Vladimir Bukovsky<\/a><\/span><\/p>\n<p><span style=\"color: #000000;\"><a style=\"color: #000000;\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lue-e-le-troppe-analogie-con-lunione-sovietica\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">L\u2019Ue e le troppe analogie con l\u2019Unione Sovietica<\/span><\/a><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Abstract:\u00a0 l&#8217;Unione europea\u00a0 sta creando un superstato oligarchico che mira ad attuare una\u00a0 bolscevizzazione morbida del continente mediante una erosione graduale e\u00a0 strisciante delle competenze degli stati membri .\u00a0Le istituzioni Ue, in particolare la Commissione, il Parlamento europeo e la Corte di giustizia dell\u2019Unione europea, violano quattro principi: il principio di attribuzione, di sussidiariet\u00e0, di &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/a-bruxelles-una-lobby-lavora-per-il-superstato\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":56924,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[439],"class_list":["post-56923","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-europa-e-ue","tag-europa-ue","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&#039;Unione europea verso un bolscevismo morbido - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"&#039;Unione europea\u00a0 sta creando un superstato oligarchico che mira ad attuare una\u00a0 bolscevizzazione morbida del continente\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/a-bruxelles-una-lobby-lavora-per-il-superstato\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;Unione europea verso un bolscevismo morbido - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"&#039;Unione europea\u00a0 sta creando un superstato oligarchico che mira ad attuare una\u00a0 bolscevizzazione morbida del continente\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/a-bruxelles-una-lobby-lavora-per-il-superstato\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-04T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-04T14:56:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2023\/09\/Ue_europa_comunismo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"418\" \/>\n\t<meta property=\"og:image:height\" content=\"266\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/a-bruxelles-una-lobby-lavora-per-il-superstato\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/a-bruxelles-una-lobby-lavora-per-il-superstato\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"L&#8217;Unione europea verso un bolscevismo morbido\",\"datePublished\":\"2023-10-04T22:00:00+00:00\",\"dateModified\":\"2024-01-04T14:56:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/a-bruxelles-una-lobby-lavora-per-il-superstato\\\/\"},\"wordCount\":1575,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/a-bruxelles-una-lobby-lavora-per-il-superstato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Ue_europa_comunismo.jpg\",\"keywords\":[\"Europa UE\"],\"articleSection\":[\"Europa e UE\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/a-bruxelles-una-lobby-lavora-per-il-superstato\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/a-bruxelles-una-lobby-lavora-per-il-superstato\\\/\",\"name\":\"L'Unione europea verso un bolscevismo morbido - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/a-bruxelles-una-lobby-lavora-per-il-superstato\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/a-bruxelles-una-lobby-lavora-per-il-superstato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Ue_europa_comunismo.jpg\",\"datePublished\":\"2023-10-04T22:00:00+00:00\",\"dateModified\":\"2024-01-04T14:56:42+00:00\",\"description\":\"'Unione europea\u00a0 sta creando un superstato oligarchico che mira ad attuare una\u00a0 bolscevizzazione morbida del continente\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/a-bruxelles-una-lobby-lavora-per-il-superstato\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/a-bruxelles-una-lobby-lavora-per-il-superstato\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/a-bruxelles-una-lobby-lavora-per-il-superstato\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Ue_europa_comunismo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Ue_europa_comunismo.jpg\",\"width\":418,\"height\":266},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/a-bruxelles-una-lobby-lavora-per-il-superstato\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&#8217;Unione europea verso un bolscevismo morbido\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'Unione europea verso un bolscevismo morbido - Rassegna Stampa Cattolica","description":"'Unione europea\u00a0 sta creando un superstato oligarchico che mira ad attuare una\u00a0 bolscevizzazione morbida del continente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/a-bruxelles-una-lobby-lavora-per-il-superstato\/","og_locale":"it_IT","og_type":"article","og_title":"L'Unione europea verso un bolscevismo morbido - Rassegna Stampa Cattolica","og_description":"'Unione europea\u00a0 sta creando un superstato oligarchico che mira ad attuare una\u00a0 bolscevizzazione morbida del continente","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/a-bruxelles-una-lobby-lavora-per-il-superstato\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2023-10-04T22:00:00+00:00","article_modified_time":"2024-01-04T14:56:42+00:00","og_image":[{"width":418,"height":266,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2023\/09\/Ue_europa_comunismo.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"10 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/a-bruxelles-una-lobby-lavora-per-il-superstato\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/a-bruxelles-una-lobby-lavora-per-il-superstato\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"L&#8217;Unione europea verso un bolscevismo morbido","datePublished":"2023-10-04T22:00:00+00:00","dateModified":"2024-01-04T14:56:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/a-bruxelles-una-lobby-lavora-per-il-superstato\/"},"wordCount":1575,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/a-bruxelles-una-lobby-lavora-per-il-superstato\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2023\/09\/Ue_europa_comunismo.jpg","keywords":["Europa UE"],"articleSection":["Europa e UE"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/a-bruxelles-una-lobby-lavora-per-il-superstato\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/a-bruxelles-una-lobby-lavora-per-il-superstato\/","name":"L'Unione europea verso un bolscevismo morbido - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/a-bruxelles-una-lobby-lavora-per-il-superstato\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/a-bruxelles-una-lobby-lavora-per-il-superstato\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2023\/09\/Ue_europa_comunismo.jpg","datePublished":"2023-10-04T22:00:00+00:00","dateModified":"2024-01-04T14:56:42+00:00","description":"'Unione europea\u00a0 sta creando un superstato oligarchico che mira ad attuare una\u00a0 bolscevizzazione morbida del continente","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/a-bruxelles-una-lobby-lavora-per-il-superstato\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/a-bruxelles-una-lobby-lavora-per-il-superstato\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/a-bruxelles-una-lobby-lavora-per-il-superstato\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2023\/09\/Ue_europa_comunismo.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2023\/09\/Ue_europa_comunismo.jpg","width":418,"height":266},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/a-bruxelles-una-lobby-lavora-per-il-superstato\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"L&#8217;Unione europea verso un bolscevismo morbido"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/56923","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=56923"}],"version-history":[{"count":5,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/56923\/revisions"}],"predecessor-version":[{"id":58702,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/56923\/revisions\/58702"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/56924"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=56923"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=56923"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=56923"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}