{"id":56898,"date":"2023-09-28T00:00:00","date_gmt":"2023-09-27T22:00:00","guid":{"rendered":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=56898"},"modified":"2023-12-02T16:31:03","modified_gmt":"2023-12-02T15:31:03","slug":"la-religione-verde-sostituisce-il-cristianesimo","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-religione-verde-sostituisce-il-cristianesimo\/","title":{"rendered":"La religione verde sostituisce il Cristianesimo"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-56899 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2023\/09\/Guido_Vignelli.jpeg\" alt=\"cristianesimo sostituito dall'ecologia secondo Vignelli\" width=\"240\" height=\"181\" \/>Abstract: <\/strong>La religione verde sostituisce il Cristianesimo?\u00a0 una volta l&#8217;ecologia si occupava di proteggere il pineta dagli abusi dell&#8217;uomo, adesso l&#8217;ideologia ambientalista vuole sovvertire la societ\u00e0 riproponendo il fallito \u2013 ma sempiterno \u2013 progetto rivoluzionario, che sostituisce la vecchia idolatria dell\u2019uomo con la nuova idolatria della natura.<\/span><!--more--><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #0000ff;\"><strong><a style=\"color: #0000ff;\" href=\"https:\/\/vanthuanobservatory.com\/\" target=\"_blank\" rel=\"noopener\">Osservatorio Internazionale cardinale Van Thu\u00e2n<\/a> <\/strong><\/span><span style=\"color: #000000;\">13 Settembre 2023<strong> \u00a0<\/strong><\/span><\/p>\n<h3 style=\"text-align: center;\">Vogliono sostituire il cristianesimo con una nuova religione: l\u2019ecologismo.<\/h3>\n<h3 style=\"text-align: center;\">Martina Pastorelli intervista Guido Vignelli<\/h3>\n<p style=\"text-align: justify;\">[<span style=\"color: #000000;\"><em>Riprendiamo dal quotidiano \u201cLa Verit\u00e0\u201d l\u2019intervista di<\/em> <strong>Martina Pastorelli<\/strong> a <strong>Guido Vignelli<\/strong>, studioso amico del nostro Osservatorio, membro del nostro Collegio degli Autori e assiduo collaboratore<\/span>]<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-26634 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2004\/10\/ecologia.jpg\" alt=\"\" width=\"271\" height=\"271\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2004\/10\/ecologia.jpg 225w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2004\/10\/ecologia-150x150.jpg 150w\" sizes=\"auto, (max-width: 271px) 100vw, 271px\" \/>C\u2019era una volta l\u2019ecologia, la cura dell\u2019ambiente naturale in quanto dimora (<em>oikos <\/em>in greco significa \u201ccasa\u201d) di esseri umani che vivono in una relazione ordinata ed equilibrata con ci\u00f2 che li circonda. Oggi non c\u2019\u00e8 pi\u00f9: \u00e8 stata rimpiazzata dall\u2019ecologismo, ideologia che non mira a preservare la natura dalle prevaricazioni dell\u2019uomo ma a sovvertire la societ\u00e0 per instaurare un presunto mondo primitivo originario nel quale l\u2019uomo non \u00e8 pi\u00f9 \u201cpadrone\u201d della natura bens\u00ec torna a esserne servo.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">L\u2019ecologismo, in nome del quale ormai subiamo quotidiane vessazioni, altro non \u00e8 se non la riproposizione del fallito \u2013 ma sempiterno \u2013 progetto rivoluzionario, che sostituisce la vecchia idolatria dell\u2019uomo con la nuova idolatria della natura. Presentandosi quale nuova religione secolare, esso agisce mediante falsi predicatori (tipo gli ubiqui tele-climatologi), profeti di sventure (\u00e0 la Greta), martiri (come le \u201cvittime\u201d di Nuova Generazione) e perfino inquisitori (vedasi politici e intellettuali che parlano di reato di negazionismo climatico).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Figlio del progressismo, in realt\u00e0 prepara per l\u2019umanit\u00e0 una regressione: laddove, infatti, il Cristianesimo aveva insegnato all\u2019uomo a non avere paura della natura ma a rispettare Dio, oggi gli si insegna ad avere paura della natura ma a non rispettare Dio.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-55706 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2023\/02\/antiumanisti_ecologia-1.jpg\" alt=\"\" width=\"314\" height=\"209\" \/>Ruota intorno a questi ragionamenti \u201c<span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/www.mondadoristore.it\/Da-dio-bio-ecologismo-come-Guido-Vignelli\/eai978883139103\/\" target=\"_blank\" rel=\"noopener\">Da Dio al Bio<\/a><\/span>\u201d (ed. Maniero del Mirto), l\u2019ultimo libro di Guido Vignelli, studioso cattolico e saggista, che svela \u201cl\u2019altra storia\u201d dietro il progetto ambientalista, spiegandone caratteristiche e rischi. Un\u2019analisi lucida che trova conferma negli eventi pi\u00f9 recenti e che approfondiamo con l\u2019autore in questa intervista.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>Dopo quella sanitaria e bellica (peraltro non archiviate), siamo alla \u201cemergenza climatica\u201d, che cronologicamente \u00e8 la \u201cmadre di tutte le emergenze\u201d: quando nasce, perch\u00e9 e come si arriva all\u2019attuale religione ecologista, financo all\u2019umanesimo ambientale e animale?<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">L\u2019ecologismo nasce nel 1800 in ambiti specifici, come il darwinismo sociale, ma viene rilanciato con la crisi della sinistra classica, quella di matrice sovietica: \u00e8 nel \u201868 che si sviluppa sia come ramo eretico del marxismo che come ramo anarchico, quello che poi \u00e8 arrivato fino a noi. I primi a parlare di nuova rivoluzione ecologica sono proprio autori della sinistra, marxisti delusi come Andr\u00e9 Gorz o scienziati politicanti come Gregory Bateson, maestro della biologa Lynn Margulis che per prima parl\u00f2 di \u201cipotesi Gaia\u201d poi rilanciata da James Lovelock nel suo famoso libro. L\u2019ecologismo \u00e8 il frutto di una rivoluzione \u201cpost-moderna\u201d, che della modernit\u00e0 in chiave marxista riconosce il fallimento e si ricicla in una nuova veste. Dietro ci sono sicuramente interessi economici \u2013 come si evince dal tentativo di imporre nuove forme di alimentazione e di approvvigionamento energetico \u2013 ma le radici del fenomeno sono ideologiche: prima ancora della eco-economia e della transizione ecologica c\u2019\u00e8 una \u201ceco-sofia\u201d cio\u00e8 una nuova sapienza ecologica finto-religiosa che vede la natura non pi\u00f9 come un fattore materiale ma come una sorta di idolo. Diversi studiosi parlano della dea madre di tutti i viventi che chiamano \u201cGaia\u201d o \u201cGea\u201d e che abita nel Dio Oikos. Gli aspetti sempre pi\u00f9 mitici con cui si sviluppano questi concetti sono evidenti. Il grande Lucien Febvre aveva previsto uno sviluppo mitologico dell\u2019ideologia della sinistra: da scienza economico sociale a ideologia mitologica volta a creare una nuova fede che coinvolga tutti gli esseri viventi: uomini, animali, vegetal<\/span>i<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>Questo implica mettere da parte il Cristianesimo e la sua visione dell\u2019uomo nel mondo?<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-55705 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2023\/02\/antiumanisti_ecologia.jpg\" alt=\"\" width=\"333\" height=\"220\" \/>Auguste Comte usava ripetere che \u201cniente viene soppresso se non viene anche sostituito\u201d e sosteneva che per sopprimere definitivamente il Cristianesimo si sarebbe dovuto sostituirlo con una religione alternativa per soddisfare il bisogno di una fede \u2013 ma in questo caso direi di un idolo \u2013 della popolazione. \u00c8 quanto sta accadendo con l\u2019ecologicamente corretto, variante del politicamente corretto, i cui propagandisti che ieri attaccavano la concezione cristiana del creato in quanto a loro dire impediva lo sfruttamento della natura, oggi accusano la medesima visione poich\u00e9 avrebbe messo l\u2019uomo al centro, giustificando cos\u00ec la corruzione del creato. Le stesse persone sono passate da una accusa a quella opposta, entrambe false visto che l\u2019antropocentrismo cristiano implica dei doveri di custodia e di miglioria del creato. Ma tutto fa brodo pur di attaccare la religione cristiana<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>Questa incoerenza \u00e8 rincorrente su vari temi. Sul clima gli \u201cesperti\u201d ci dicono tutto e il suo contrario: dal pericolo di glaciazione, in pochi anni si \u00e8 passati al pericolo di desertificazione. \u00c8 il funerale della scienza?<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Questo \u00e8 un grosso guaio: screditata, giustamente, la classe intellettuale, quella politica e pure quella medica dopo il Covid, la gente non trova pi\u00f9 riferimenti nella scienza e nella tecnica; il lato positivo \u00e8 che toglie quell\u2019aura mitica all\u2019esperto e alla tecnocrazia, che ultimamente stava tentando di sostituirsi alle classi citate. \u00c8 un fenomeno a doppia valenza, che pu\u00f2 far pulizia di alcuni falsi miti, sperando per\u00f2 di recuperare le verit\u00e0 e i valori che possono salvarci<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>Quali sono le conseguenze politiche dell\u2019ambientalismo?<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-26632 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2004\/10\/wwf.jpg\" alt=\"\" width=\"223\" height=\"226\" \/>L\u2019ecologismo non \u00e8 pi\u00f9 quel fenomeno di pochi idealisti, misantropi e fantasiosi come ai tempi degli hippies. Da tempo ha sviluppato un progetto politico, sociale ed economico molto preciso, con elementi militanti \u2013 come il WWF \u2013 che puntano a diffondere l\u2019ecologismo nella cultura e perfino frange estremiste che programmano una graduale estinzione dell\u2019uomo in quanto cancro della natura, colpevole di causare al pianeta una febbre, che poi coinciderebbe con l\u2019aumento delle temperature. C\u2019\u00e8 alla base un progetto di societ\u00e0 fondata sull\u2019etica ecologica, che viene portato avanti da movimenti appoggiati dai grandi organismi internazionali \u2013 l\u2019Onu e i suoi satelliti: Unesco, Fao, Oms \u2013 e da molti governi, come quello canadese e tedesco. Basti pensare che la stessa Unesco -oggi grande propagandista culturale delle Nazioni Unite \u2013 fu fondata dopo la Seconda guerra mondiale da un team che gi\u00e0 parlava di ecologia e di transumanesimo. Rientra in questa propaganda l\u2019organizzazione di una serie di convegni internazionali, il pi\u00f9 famoso dei quali si tenne a Rio de Janeiro nel 2000 e promulg\u00f2 la \u201cCarta della Terra\u201d, una dichiarazione di principi etici che sostituiva la vecchia Carta dei Diritti dell\u2019uomo integrando le specie animali e vegetali<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>Una rivoluzione egalitaria insomma?<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-22668 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/07\/animalismo.jpg\" alt=\"\" width=\"330\" height=\"264\" \/>Certo, coadiuvata dalla lotta al cosiddetto \u201cspecismo\u201d, ovvero al concetto che l\u2019uomo possa rivendicare dei privilegi rispetto alle altre specie viventi poich\u00e9 questo sarebbe discriminazione e razzismo. Ma egualitarismo di tutte le specie significa conflittualit\u00e0 tra di esse, e infatti vediamo in atto una serie di misure che penalizzano l\u2019uomo e non di rado lo mettono all\u2019ultimo posto: non pi\u00f9 signore e \u201cpadrone\u201d della natura ma servo suo e di tutte le specie viventi. I progetti di \u201ccitt\u00e0 ecologiche\u201d in cui l\u2019uomo \u00e8 integrato nella natura, e non viceversa, vanno in questa direzione; il problema \u00e8 che sono costosissime e dunque inaccessibili per la maggioranza delle persone, che rimarrebbero confinate alle periferie vivendo una vita semi selvaggia. Questo modello ci viene sfacciatamente proposto e spiega perch\u00e9 molti super miliardari odierni siano ecologisti: non ci perdono nulla e anzi guadagnano da terreni e cibi ecologici<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>Una proposta che misteriosamente la gente sembra accettare, nonostante la promessa di \u201cmiseria felice\u201d che viene prospettata: come mai?<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-49366 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/12\/Urss_code_miseria.jpg\" alt=\"\" width=\"332\" height=\"224\" \/>Il recente prevalere dell\u2019ecologicamente corretto svela il potere delle ideologie sulla gente e quella ecologista ha la<\/span> <span style=\"color: #000000;\">caratteristica di essere molto seducente e di funzionare come \u201csoluzione\u201d alla fallita ideologia del progresso: quello che ieri era una conquista oggi deve diventare una rinuncia. Questo ribaltamento viene fatto digerire in nome di un bene maggiore, ovvero la salute del pianeta e la sopravvivenza delle generazioni future. \u00c8 ideologia anche questa ma funziona con l\u2019uomo comune, che davanti alle promesse smentite dai fatti e alla perdita delle conquiste civili di carattere economico-politico, pensa di dover aderire a questo nuovo stile di vita. Seduce chi \u00e8 stufo del consumismo e fa presa sui giovani ma \u00e8 al contempo molto preoccupante: il famoso motto \u201cnon avrai nulla e sarai felice\u201d del WEF significa in realt\u00e0 \u201cnon avrai nulla e non sarai nulla.\u201d Dalla transizione ecologica la gente, insomma, ha tutto da perdere e bisogna faglielo capire.<\/span><\/p>\n<p>____________________________<\/p>\n<p><span style=\"color: #000000;\"><strong>Cristianesimo sostituito dall&#8217;ecologia? Per approfondire:<\/strong><\/span><\/p>\n<p><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lavvilente-masochismo-di-una-civilta-prostrata-ai-piedi-di-un-dio-verde\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">L\u2019avvilente masochismo di una civilt\u00e0 prostrata ai piedi di un \u201cdio verde\u201d<\/span><\/a><\/p>\n<p><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-maggior-piano-di-scristianizzazione-e-di-totalitarismo-verde-della-storia\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">Il maggior piano di scristianizzazione e di totalitarismo \u201cverde\u201d della Storia<\/span><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Abstract: La religione verde sostituisce il Cristianesimo?\u00a0 una volta l&#8217;ecologia si occupava di proteggere il pineta dagli abusi dell&#8217;uomo, adesso l&#8217;ideologia ambientalista vuole sovvertire la societ\u00e0 riproponendo il fallito \u2013 ma sempiterno \u2013 progetto rivoluzionario, che sostituisce la vecchia idolatria dell\u2019uomo con la nuova idolatria della natura.<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-religione-verde-sostituisce-il-cristianesimo\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":56899,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[2387,1708],"class_list":["post-56898","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ambientalismo","tag-ambientalismo","tag-ecologismo","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La religione verde sostituisce il Cristianesimo - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"La religione verde sostituisce il Cristianesimo? L\u2019ecologismo non mira pi\u00f9 a preservare la natura ma vuole sovvertire la societ\u00e0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-religione-verde-sostituisce-il-cristianesimo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La religione verde sostituisce il Cristianesimo - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"La religione verde sostituisce il Cristianesimo? L\u2019ecologismo non mira pi\u00f9 a preservare la natura ma vuole sovvertire la societ\u00e0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-religione-verde-sostituisce-il-cristianesimo\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-27T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-02T15:31:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2023\/09\/Guido_Vignelli.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"240\" \/>\n\t<meta property=\"og:image:height\" content=\"181\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-religione-verde-sostituisce-il-cristianesimo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-religione-verde-sostituisce-il-cristianesimo\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"La religione verde sostituisce il Cristianesimo\",\"datePublished\":\"2023-09-27T22:00:00+00:00\",\"dateModified\":\"2023-12-02T15:31:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-religione-verde-sostituisce-il-cristianesimo\\\/\"},\"wordCount\":1450,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-religione-verde-sostituisce-il-cristianesimo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Guido_Vignelli.jpeg\",\"keywords\":[\"Ambientalismo\",\"ecologismo\"],\"articleSection\":[\"Ambientalismo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-religione-verde-sostituisce-il-cristianesimo\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-religione-verde-sostituisce-il-cristianesimo\\\/\",\"name\":\"La religione verde sostituisce il Cristianesimo - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-religione-verde-sostituisce-il-cristianesimo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-religione-verde-sostituisce-il-cristianesimo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Guido_Vignelli.jpeg\",\"datePublished\":\"2023-09-27T22:00:00+00:00\",\"dateModified\":\"2023-12-02T15:31:03+00:00\",\"description\":\"La religione verde sostituisce il Cristianesimo? L\u2019ecologismo non mira pi\u00f9 a preservare la natura ma vuole sovvertire la societ\u00e0\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-religione-verde-sostituisce-il-cristianesimo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-religione-verde-sostituisce-il-cristianesimo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-religione-verde-sostituisce-il-cristianesimo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Guido_Vignelli.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Guido_Vignelli.jpeg\",\"width\":240,\"height\":181,\"caption\":\"cristianesimo sostituito dall'ecologia secondo Vignelli\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-religione-verde-sostituisce-il-cristianesimo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La religione verde sostituisce il Cristianesimo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La religione verde sostituisce il Cristianesimo - Rassegna Stampa Cattolica","description":"La religione verde sostituisce il Cristianesimo? L\u2019ecologismo non mira pi\u00f9 a preservare la natura ma vuole sovvertire la societ\u00e0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-religione-verde-sostituisce-il-cristianesimo\/","og_locale":"it_IT","og_type":"article","og_title":"La religione verde sostituisce il Cristianesimo - Rassegna Stampa Cattolica","og_description":"La religione verde sostituisce il Cristianesimo? L\u2019ecologismo non mira pi\u00f9 a preservare la natura ma vuole sovvertire la societ\u00e0","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-religione-verde-sostituisce-il-cristianesimo\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2023-09-27T22:00:00+00:00","article_modified_time":"2023-12-02T15:31:03+00:00","og_image":[{"width":240,"height":181,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2023\/09\/Guido_Vignelli.jpeg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"9 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-religione-verde-sostituisce-il-cristianesimo\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-religione-verde-sostituisce-il-cristianesimo\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"La religione verde sostituisce il Cristianesimo","datePublished":"2023-09-27T22:00:00+00:00","dateModified":"2023-12-02T15:31:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-religione-verde-sostituisce-il-cristianesimo\/"},"wordCount":1450,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-religione-verde-sostituisce-il-cristianesimo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2023\/09\/Guido_Vignelli.jpeg","keywords":["Ambientalismo","ecologismo"],"articleSection":["Ambientalismo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-religione-verde-sostituisce-il-cristianesimo\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-religione-verde-sostituisce-il-cristianesimo\/","name":"La religione verde sostituisce il Cristianesimo - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-religione-verde-sostituisce-il-cristianesimo\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-religione-verde-sostituisce-il-cristianesimo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2023\/09\/Guido_Vignelli.jpeg","datePublished":"2023-09-27T22:00:00+00:00","dateModified":"2023-12-02T15:31:03+00:00","description":"La religione verde sostituisce il Cristianesimo? L\u2019ecologismo non mira pi\u00f9 a preservare la natura ma vuole sovvertire la societ\u00e0","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-religione-verde-sostituisce-il-cristianesimo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-religione-verde-sostituisce-il-cristianesimo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-religione-verde-sostituisce-il-cristianesimo\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2023\/09\/Guido_Vignelli.jpeg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2023\/09\/Guido_Vignelli.jpeg","width":240,"height":181,"caption":"cristianesimo sostituito dall'ecologia secondo Vignelli"},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-religione-verde-sostituisce-il-cristianesimo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"La religione verde sostituisce il Cristianesimo"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/56898","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=56898"}],"version-history":[{"count":5,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/56898\/revisions"}],"predecessor-version":[{"id":57899,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/56898\/revisions\/57899"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/56899"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=56898"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=56898"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=56898"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}