{"id":56816,"date":"2023-09-07T00:00:00","date_gmt":"2023-09-06T22:00:00","guid":{"rendered":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=56816"},"modified":"2024-01-04T16:21:42","modified_gmt":"2024-01-04T15:21:42","slug":"proposta-di-legge-per-limitare-laborto","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/proposta-di-legge-per-limitare-laborto\/","title":{"rendered":"Proposta di legge per limitare l&#8217;aborto"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-56817 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2023\/08\/aborto_legge_popolare.png\" alt=\"una proposta di legge per limitare l'aborto: un cuore che batte\" width=\"199\" height=\"282\" \/>Abstract:\u00a0 <\/strong><em>una proposta di legge popolare per limitare la piaga dell&#8217;aborto: &#8220;Un cuore che batte&#8221; , per ottenere di fare ascoltare il battito cardiaco del bambino nella pancia della madre che vuole abortire e una ecografia. Si svela cos\u00ec la menzogna abortista che il feto non \u00e8 vita umana. Nonostante il battage mediatico subito scatenato dallo schieramento abortista, si tratterebbe solo di una proposta minimale a difesa del pi\u00f9 debole e, insieme, di una opportunit\u00e0 alla donna di valutare pi\u00f9 consapevolmente, ai sensi delle scelte di cui all\u2019art 5 della stessa 194, la possibilit\u00e0 di opzioni differenti dall\u2019aborto che, comunque resta autorizzato e consentito come da legge.<\/em><\/span><\/p>\n<p style=\"text-align: center;\"><!--more--><span style=\"color: #000000;\"><strong>Il Borghese<\/strong> n.8\/9 Agosto 2023 <em>La proposta <\/em>pro-life<em> d\u2019iniziativa popolare<\/em> <\/span><\/p>\n<h3 style=\"text-align: center;\"><span style=\"color: #000000;\">Un cuore che batte<\/span><\/h3>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\">di <strong>Giuseppe Brienza<\/strong> <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">La Suprema Corte degli Stati Uniti, come noto, ha di recente ridimensionato la portata della storica sentenza \u201cRoe v. Wade\u201d che nel 1973 apr\u00ec la via alla legalizzazione dell\u2019aborto nel Paese. I singoli Stati dell\u2019Unione, a partire dalla causa Dobbs v. Jackson (24 giugno 2022) sono quindi liberi di applicare le loro leggi in materia, poich\u00e9 quello all\u2019aborto non \u00e8 pi\u00f9 considerato un \u201cdiritto costituzionale\u201d. Il Texas e il Missouri a guida repubblicana hanno gi\u00e0 l\u2019anno scorso provveduto a rendere praticamente illegale l&#8217;<em>interruzione volontaria della gravidanza <\/em>(Ivg), seguiti poi da altri Stati <em>prolife<\/em>.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Tale evoluzione, resa nota e discussa anche dai <em>media<\/em> italiani, ha riacceso dopo anni di silenzio il dibattito circa la legge nazionale sulla Ivg (n. 194 del 22 maggio 1978), che non pochi chiedono di verificare circa la sua corretta applicazione. Ricordiamo anche che nel 1981 ci fu un referendum proposto dal <em>Movimento per la vita<\/em> (Mpv) italiano allo scopo di abrogare alcune norme della legge 194 al fine di restringere i casi di liceit\u00e0 dell&#8217;aborto che, per\u00f2, solo il 32% dei votanti approv\u00f2. Tale insoddisfacente risultato &#8211; per i <em>prolife<\/em> &#8211; andrebbe comunque interpretato considerando i voti nulli o le schede bianche che si registrarono nell\u2019incandescente scenario referendario, che ammontarono a quasi 3 milioni (il 7,70% su totale dei votanti).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-23264 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/12\/ecografia.jpg\" alt=\"la proposta di legge vuole fare ascoltare il battito cardiaco\" width=\"308\" height=\"228\" \/>D\u2019allora, comunque, di acqua sotto i ponti ne \u00e8 passata e la stessa scienza medica ci ha rivelato che la soggettivit\u00e0, la \u201cvita segreta\u201d del feto, il suo protagonismo, parte ben prima dalla \u201csoglia\u201d di \u00a0abortivit\u00e0, ovvero quei primi 90 giorni di gestazione entro i quali pu\u00f2 secondo la legge italiana essere praticata una Ivg. Fin dal concepimento, in definitiva, una fitta rete di scambi con la madre, biochimici e psicologici, sono rilevabili grazie alle attuali tecniche ecografiche, e sono tali scambi che rendono possibile l\u2019impianto e il corretto proseguimento della gravidanza. Dal punto di vista scientifico, pertanto, sono destituite di qualsiasi fondamento razionale quelle rivendicazioni e slogan del femminismo tossico tipo \u201c<em>l\u2019utero \u00e8 mio e lo gestisco io<\/em>\u201d. L\u2019esperienza dei <em>Centri<\/em> e dei <em>Servizi di Aiuto alla Vita<\/em> (CAV e SAV) nonch\u00e9 della maggior parte dei consultori familiari di ispirazione cristiana dimostra piuttosto che assieme all\u2019embrione muore parte della donna ed \u00e8 quindi dovere della societ\u00e0 e dello Stato promuovere l\u2019accoglienza dei figli e, insieme, tutelare la salute della donna\/madre.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Lo scambio bidirezionale di cellule fetali e materne durante la gravidanza, dimostra la scienza, \u00a0va molto oltre a ci\u00f2 che credevamo in passato. \u00ab<em>Questo meccanismo<\/em> &#8211; ha scritto l\u2019ostetrica Cristina Danielis &#8211; <em>\u00e8 noto da diversi decenni ormai, ma solo di recente \u00e8 stato studiato in maniera dettagliata grazie alle nuove tecniche di ricerca. Se nei tempi passati si pensava che l\u2019utero fosse solo un contenitore isolato e che placenta e cordone ombelicale servissero solamente a far crescere e nutrire il <\/em>prodotto del concepimento<em>, ora si sostiene che tra mamma e figlio ci sia un rapporto ben pi\u00f9 stretto dell\u2019aspetto puramente biologico<\/em>\u00bb (<em>L\u2019amore materno tra scienza e attualit\u00e0<\/em>, in <em>Etica, Salute &amp; Famiglia<\/em>, anno XXVII, n. 4, luglio-agosto 2023, p. 9).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-52119 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/08\/aborto_femminismo.jpg\" alt=\"\" width=\"347\" height=\"202\" \/>Alla luce di quanto sinteticamente descritto finora e nell\u2019ottica di un non pi\u00f9 procastinabile \u201ctagliando\u201d alla legge 194, va segnalata la presentazione della Proposta di legge di iniziativa popolare (Plip), dal nome \u201c<em>Un cuore che batte<\/em>\u201d, partita a giugno ed aperta alla firma dei cittadini fino al 7 novembre 2023, per integrare uno dei principali articoli della legge sull\u2019aborto.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">La Plip vorrebbe in pratica introdurre un comma <em>1-bis<\/em> all\u2019articolo 14 della 194 disponendo che \u00ab<em>Il medico che effettua la visita che precede l\u2019interruzione volontaria di gravidanza<\/em>\u00bb ai sensi della legge, \u00ab<em>\u00e8 obbligato a far vedere, tramite esami strumentali, alla donna intenzionata ad abortire, il nascituro che porta nel grembo e a farle ascoltare il battito cardiaco dello stesso<\/em>\u00bb.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Nonostante il <em>battage<\/em> mediatico subito scatenato dallo schieramento abortista, si tratterebbe solo di una proposta minimale a difesa del pi\u00f9 debole e, insieme, di una opportunit\u00e0 alla donna di valutare pi\u00f9 consapevolmente, ai sensi delle scelte di cui all\u2019art 5 della stessa 194, la possibilit\u00e0 di opzioni differenti dall\u2019aborto che, comunque resta autorizzato e consentito come da legge.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-34900 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/12\/centro_aiuto_vita.jpg\" alt=\"limitare la piaga dell'aborto con una proposta di legge popolare\" width=\"347\" height=\"274\" \/>A promuovere la proposta di legge sono state 15 associazioni e comitati <em>prolife<\/em> fra i quali l\u2019Associazione <em>Pro vita &amp; Famiglia<\/em>, il Comitato<em> Verit\u00e0 e Vita <\/em>e la<em> Federazione dei Centri di Aiuto alla Vita, dei Movimenti per la vita, e delle Case di accoglienza <\/em>(Federvita) del Piemonte.<\/span><\/p>\n<p style=\"text-align: justify;\">V<span style=\"color: #000000;\">a ricordato in proposito che, fin dalla sua entrata in vigore, l\u2019articolo 5 della legge 194 ha previsto che il consultorio o la struttura socio-sanitaria che accolga la donna in gravidanza, oltre a dover garantire i necessari accertamenti medici, hanno anche il compito in ogni caso, e specialmente quando la richiesta di interruzione della gravidanza sia motivata dall\u2019incidenza delle condizioni economiche, o sociali, o familiari sulla salute della gestante, di esaminare con la donna e con il padre del concepito, ove la donna lo consenta, \u00ab<em>le possibili soluzioni dei problemi proposti, di aiutarla a rimuovere le cause che la porterebbero alla interruzione della gravidanza, di metterla in grado di far valere i suoi diritti di lavoratrice e di madre, di promuovere ogni opportuno intervento atto a sostenere la donna, offrendole tutti gli aiuti necessari sia durante la gravidanza sia dopo il parto<\/em>\u00bb.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">La proposta di legge di iniziativa popolare\u00a0\u201c<em>Un cuore che batte<\/em>\u201d \u00e8 attualmente depositata (per la firma dei residenti) in oltre 250 Comuni d\u2019Italia (l\u2019elenco completo si pu\u00f2 consultare sul sito <a style=\"color: #000000;\" href=\"http:\/\/www.oraetlaboraindifesadellavita.org\">www.oraetlaboraindifesadellavita.org<\/a>) oltre che nei seguenti dieci capoluoghi di Regione: <\/span>Ancona;\u00a0Bari; Cagliari; Firenze; Genova; Napoli; Roma; Torino; Trento; Trieste.\u00ec<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-35135 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/12\/voto_Montecitorio.jpg\" alt=\"\" width=\"350\" height=\"200\" \/>Far conoscere e promuovere di questa battaglia di civilt\u00e0 che ha come compito quello di difendere il <em>pi\u00f9 povero dei poveri<\/em> come il nascituro non voluto assumerebbe un significato anche democratico e di ampliamento delle libert\u00e0. Infatti, come era possibile immaginare, i proponenti della Plip hanno contro tutti: dai grandi <em>media<\/em> ai partiti di opposizione, dalla tecnocrazia europea e internazionale ai <em>Tech Giants<\/em>, senza contare purtroppo anche le due pi\u00f9 conosciute associazioni <em>prolife<\/em> e <em>profamily<\/em> italiane come il <em>Movimento per la vita <\/em>e il Comitato <em>Difendiamo i nostri figli <\/em>che non hanno finora aderito all\u2019iniziativa.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">L\u2019organizzazione di raccolta firme sta servendo, anche se in piccoli circoli, ad innescare un dibattito e una mobilitazione che possa contribuire a rimettere in discussione l\u2019attuale \u201ccristallizzazione\u201d della legge 194\/1978. La proposta vuole quindi diventare un volano per conferenze, dibattiti, tavole rotonde, confronti sui <em>media<\/em>, insomma per gridare che il concepito \u00e8 <em>uno di noi<\/em>!<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Abstract:\u00a0 una proposta di legge popolare per limitare la piaga dell&#8217;aborto: &#8220;Un cuore che batte&#8221; , per ottenere di fare ascoltare il battito cardiaco del bambino nella pancia della madre che vuole abortire e una ecografia. Si svela cos\u00ec la menzogna abortista che il feto non \u00e8 vita umana. Nonostante il battage mediatico subito scatenato &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/proposta-di-legge-per-limitare-laborto\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":27194,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[2386,1047],"class_list":["post-56816","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aborto","tag-aborto","tag-legge-194","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Proposta di legge per limitare l&#039;aborto - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Proposta di legge per limitare l&#039;aborto, \u00e8 lo scopo di &quot;Un cuore che batte&quot;, per smentire la menzogna abortista che il feto non \u00e8 vita umana\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/proposta-di-legge-per-limitare-laborto\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Proposta di legge per limitare l&#039;aborto - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Proposta di legge per limitare l&#039;aborto, \u00e8 lo scopo di &quot;Un cuore che batte&quot;, per smentire la menzogna abortista che il feto non \u00e8 vita umana\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/proposta-di-legge-per-limitare-laborto\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-06T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-04T15:21:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2013\/06\/aborto_194.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"282\" \/>\n\t<meta property=\"og:image:height\" content=\"179\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/proposta-di-legge-per-limitare-laborto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/proposta-di-legge-per-limitare-laborto\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Proposta di legge per limitare l&#8217;aborto\",\"datePublished\":\"2023-09-06T22:00:00+00:00\",\"dateModified\":\"2024-01-04T15:21:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/proposta-di-legge-per-limitare-laborto\\\/\"},\"wordCount\":1200,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/proposta-di-legge-per-limitare-laborto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2013\\\/06\\\/aborto_194.jpg\",\"keywords\":[\"Aborto\",\"legge 194\"],\"articleSection\":[\"Aborto\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/proposta-di-legge-per-limitare-laborto\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/proposta-di-legge-per-limitare-laborto\\\/\",\"name\":\"Proposta di legge per limitare l'aborto - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/proposta-di-legge-per-limitare-laborto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/proposta-di-legge-per-limitare-laborto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2013\\\/06\\\/aborto_194.jpg\",\"datePublished\":\"2023-09-06T22:00:00+00:00\",\"dateModified\":\"2024-01-04T15:21:42+00:00\",\"description\":\"Proposta di legge per limitare l'aborto, \u00e8 lo scopo di \\\"Un cuore che batte\\\", per smentire la menzogna abortista che il feto non \u00e8 vita umana\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/proposta-di-legge-per-limitare-laborto\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/proposta-di-legge-per-limitare-laborto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/proposta-di-legge-per-limitare-laborto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2013\\\/06\\\/aborto_194.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2013\\\/06\\\/aborto_194.jpg\",\"width\":282,\"height\":179},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/proposta-di-legge-per-limitare-laborto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Proposta di legge per limitare l&#8217;aborto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Proposta di legge per limitare l'aborto - Rassegna Stampa Cattolica","description":"Proposta di legge per limitare l'aborto, \u00e8 lo scopo di \"Un cuore che batte\", per smentire la menzogna abortista che il feto non \u00e8 vita umana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/proposta-di-legge-per-limitare-laborto\/","og_locale":"it_IT","og_type":"article","og_title":"Proposta di legge per limitare l'aborto - Rassegna Stampa Cattolica","og_description":"Proposta di legge per limitare l'aborto, \u00e8 lo scopo di \"Un cuore che batte\", per smentire la menzogna abortista che il feto non \u00e8 vita umana","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/proposta-di-legge-per-limitare-laborto\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2023-09-06T22:00:00+00:00","article_modified_time":"2024-01-04T15:21:42+00:00","og_image":[{"width":282,"height":179,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2013\/06\/aborto_194.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"8 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/proposta-di-legge-per-limitare-laborto\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/proposta-di-legge-per-limitare-laborto\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Proposta di legge per limitare l&#8217;aborto","datePublished":"2023-09-06T22:00:00+00:00","dateModified":"2024-01-04T15:21:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/proposta-di-legge-per-limitare-laborto\/"},"wordCount":1200,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/proposta-di-legge-per-limitare-laborto\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2013\/06\/aborto_194.jpg","keywords":["Aborto","legge 194"],"articleSection":["Aborto"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/proposta-di-legge-per-limitare-laborto\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/proposta-di-legge-per-limitare-laborto\/","name":"Proposta di legge per limitare l'aborto - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/proposta-di-legge-per-limitare-laborto\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/proposta-di-legge-per-limitare-laborto\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2013\/06\/aborto_194.jpg","datePublished":"2023-09-06T22:00:00+00:00","dateModified":"2024-01-04T15:21:42+00:00","description":"Proposta di legge per limitare l'aborto, \u00e8 lo scopo di \"Un cuore che batte\", per smentire la menzogna abortista che il feto non \u00e8 vita umana","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/proposta-di-legge-per-limitare-laborto\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/proposta-di-legge-per-limitare-laborto\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/proposta-di-legge-per-limitare-laborto\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2013\/06\/aborto_194.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2013\/06\/aborto_194.jpg","width":282,"height":179},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/proposta-di-legge-per-limitare-laborto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Proposta di legge per limitare l&#8217;aborto"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/56816","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=56816"}],"version-history":[{"count":3,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/56816\/revisions"}],"predecessor-version":[{"id":58718,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/56816\/revisions\/58718"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/27194"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=56816"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=56816"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=56816"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}