{"id":56712,"date":"2023-07-20T00:00:00","date_gmt":"2023-07-19T22:00:00","guid":{"rendered":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=56712"},"modified":"2023-12-10T16:27:55","modified_gmt":"2023-12-10T15:27:55","slug":"laborto-mina-la-salute-mentale-della-donna","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/laborto-mina-la-salute-mentale-della-donna\/","title":{"rendered":"L&#8217;aborto mina la salute mentale della donna"},"content":{"rendered":"<p style=\"text-align: center;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-34906 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/09\/donna_aborto.jpg\" alt=\"\" width=\"280\" height=\"180\" \/><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>Abstract: <\/strong><em>L&#8217;aborto mina la salute mentale della donna- lo rivela uno studio di recente pubblicazione. Le donne che hanno dato alla luce i loro primi figli hanno effettivamente utilizzato i servizi di salute mentale a un tasso pi\u00f9 elevato prima della gravidanza rispetto a quelle il cui primo figlio \u00e8 stato ucciso attraverso l\u2019aborto, suggerendo che l\u2019aborto stesso aumenta i problemi di salute mentale. Maggior anche il rischio suicidio<\/em><\/span><\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\">Dal blog di <strong>Sabino Paciolla<\/strong> 16 Luglio 2023<\/span><\/p>\n<h3 style=\"text-align: center;\">Uno studio mostra che le donne che abortiscono<\/h3>\n<h3 style=\"text-align: center;\">il primo figlio corrono un rischio maggiore<\/h3>\n<h3 style=\"text-align: center;\">di problemi di salute mentale<\/h3>\n<p style=\"text-align: justify;\"><em><span style=\"color: #000000;\">I risultati suggeriscono che l\u2019aborto, e non altri fattori, \u00e8 legato a un maggiore ricorso alle risorse per la salute mentale. Di seguito segnalo all\u2019attenzione e alla riflessione dei lettori di questo blog l\u2019articolo scritto da Emily Mangiaracina e pubblicato su<\/span> <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/www.lifesitenews.com\/news\/study-shows-women-who-abort-first-child-suffer-heightened-risk-of-mental-health-issues\/?fbclid=IwAR23WM7fkC_Dbq-nyv78WdrjgayNfn53xBDjTQEIV8hulGiOg6QzJwvk0YY\" target=\"_blank\" rel=\"noopener\"><strong>Lifesitenews<\/strong><\/a><\/span>. <span style=\"color: #000000;\">Visitate il sito e valutate liberamente le varie opzioni offerte e le eventuali richieste. Ecco l\u2019articolo nella nostra traduzione.\u00a0<\/span><\/em><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Uno<\/span> <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/www.dovepress.com\/articles.php?article_id=84488\" target=\"_blank\" rel=\"noopener\"><strong>studio peer-reviewed<\/strong> <\/a><\/span><span style=\"color: #000000;\">di recente pubblicazione dimostra che le donne che interrompono la loro prima gravidanza con un aborto ricorrono ai servizi di salute mentale a tassi significativamente pi\u00f9 alti rispetto alle donne che hanno avuto un parto vivo. Le donne che hanno dato alla luce i loro primi figli hanno effettivamente utilizzato i servizi di salute mentale a un tasso pi\u00f9 elevato prima della gravidanza rispetto a quelle il cui primo figlio \u00e8 stato ucciso attraverso l\u2019aborto, suggerendo che l\u2019aborto stesso aumenta i problemi di salute mentale.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-26651 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2004\/10\/post-aborto.jpg\" alt=\"\" width=\"331\" height=\"220\" \/>Un team di esperti dell\u2019Istituto Charlotte Lozier ha scoperto i risultati analizzando i dati delle richieste di rimborso Medicaid per oltre 4.800 donne in un periodo di 17 anni negli Stati in cui sono state presentate tutte le richieste di rimborso per quel periodo.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">\u201cIn questo modo, il team ha evitato le limitazioni delle indagini che si basano sull\u2019autodichiarazione, come la scarsa partecipazione, la perdita di follow-up e la distorsione da richiamo\u201d,<\/span> <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/lozierinstitute.org\/study-abortion-in-first-pregnancy-linked-to-much-higher-use-of-mental-health-services\/\" target=\"_blank\" rel=\"noopener\"><strong>ha sottolineato<\/strong> <\/a><\/span>l<span style=\"color: #000000;\">o Charlotte Lozier Institute.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">I ricercatori hanno scoperto che, rispetto alle donne che hanno dato alla luce il loro primo figlio, quelle che hanno subito un aborto hanno aumentato il ricorso ai servizi di salute mentale in tre categorie:<\/span><\/p>\n<ul>\n<li style=\"text-align: justify;\"><span style=\"color: #000000;\">Visite ambulatoriali: probabilit\u00e0 di aumento 3,4 volte superiore.<\/span><\/li>\n<li style=\"text-align: justify;\"><span style=\"color: #000000;\">Ricoveri ospedalieri ospedalieri: probabilit\u00e0 di aumento 5,7 volte superiore.<\/span><\/li>\n<li style=\"text-align: justify;\"><span style=\"color: #000000;\">Giorni di degenza ospedaliera: probabilit\u00e0 di aumento 19,6 volte superiore.<\/span><\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-23640 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/03\/sindrome_post_aborto.jpg\" alt=\"\" width=\"367\" height=\"262\" \/>Tessa Longbons, ricercatrice senior di Lozier e coautrice dello studio, ha concluso: \u201cLe prove sono chiare: l\u2019aborto di una prima gravidanza \u00e8 associato a danni sostanziali per la salute mentale delle donne. Le donne hanno il diritto di saperlo e di capire la portata di questi danni prima di prendere una decisione che cambia la loro vita\u201d.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">L\u2019autore principale James Studnicki, Sc.D., vicepresidente e direttore dell\u2019analisi dei dati della CLI, ha sottolineato che i risultati dell\u2019\u00e9quipe confermano gli studi condotti in<\/span> <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/journals.sagepub.com\/doi\/10.1177\/1403494814560844\" target=\"_blank\" rel=\"noopener\"><strong>Finlandia<\/strong><\/a><\/span>, <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/link.springer.com\/article\/10.1007\/s00737-019-00977-1\" target=\"_blank\" rel=\"noopener\"><strong>Italia<\/strong><\/a><\/span>, <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/bmcpublichealth.biomedcentral.com\/articles\/10.1186\/s12889-018-5527-1\" target=\"_blank\" rel=\"noopener\"><strong>Cina<\/strong><\/a><\/span>, <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/31048110\/\" target=\"_blank\" rel=\"noopener\"><strong>Germania<\/strong><\/a>, <a style=\"color: #0000ff;\" href=\"https:\/\/www.sciencedirect.com\/science\/article\/pii\/S1028455918303024?via%3Dihub\" target=\"_blank\" rel=\"noopener\"><strong>Corea<\/strong><\/a> <\/span>e <a href=\"https:\/\/journals.sagepub.com\/doi\/10.1177\/2050312116665997\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\"><strong>Stati Uniti<\/strong>,<\/span><\/a> <span style=\"color: #000000;\">che hanno tutti collegato l\u2019aborto a un rischio maggiore di peggioramento dei problemi di salute mentale, tra cui ansia, depressione e suicidio.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Alcuni ricercatori insistono sul fatto che qualsiasi limite all\u2019aborto per proteggere madri e bambini crei \u201cdanni alla salute mentale\u201d\u201d,<\/span> <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/lozierinstitute.org\/study-abortion-in-first-pregnancy-linked-to-much-higher-use-of-mental-health-services\/\" target=\"_blank\" rel=\"noopener\"><strong>ha dichiarato<\/strong><\/a><\/span> <span style=\"color: #000000;\">Studnicki in una dichiarazione per la CLI. \u201cIl nostro studio, che utilizza anni di dati sulle richieste di risarcimento, si aggiunge a un ampio corpus di dati scientifici internazionali, sottoposti a revisione paritaria, che dimostrano il contrario: l\u2019aborto in s\u00e9 ha un impatto negativo significativo su diverse misure di salute mentale\u201d.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-33960 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/09\/aborto.jpg\" alt=\"\" width=\"334\" height=\"210\" \/>Gli studi sull\u2019aborto non voluto dell\u2019Istituto hanno rilevato che la maggior parte delle donne che hanno abortito<\/span><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/www.cureus.com\/articles\/146123-the-effects-of-abortion-decision-rightness-and-decision-type-on-womens-satisfaction-and-mental-health#!\/\" target=\"_blank\" rel=\"noopener\"><strong> descrivono<\/strong> <\/a><\/span><span style=\"color: #000000;\">l\u2019aborto come indesiderato, forzato o incoerente con i propri valori, il che, come ha osservato l\u2019Istituto, \u00e8 \u201cfortemente associato a un autodescritto declino della salute mentale\u201d.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Un sondaggio condotto su 226 donne con una storia di aborto ha rilevato che il 33% ha definito l\u2019aborto come voluto, il 43% come \u201caccettato ma non coerente con i propri valori e preferenze\u201d e il 24% come non voluto o costretto. LifeSiteNews<\/span> <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/www.lifesitenews.com\/news\/largest-ever-study-finds-abortion-increases-risk-of-severe-mental-health-pr\/\"><strong>ha spesso riportato <\/strong><\/a>i <a style=\"color: #0000ff;\" href=\"https:\/\/www.lifesitenews.com\/news\/new-zealand-study-finds-abortion-increases-risk-of-mental-health-problems\/\"><strong>risultati di ricerche<\/strong><\/a> <\/span><span style=\"color: #000000;\">secondo cui l\u2019aborto \u00e8<\/span> <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/www.lifesitenews.com\/news\/study-shows-abortion-takes-toll-on-adolescent-mental-health\/\" target=\"_blank\" rel=\"noopener\"><strong>associato<\/strong><\/a><\/span> a <a href=\"https:\/\/www.lifesitenews.com\/news\/study-confirms-mental-health-risk-after-abortion\/\"><strong>risultati<\/strong> <\/a><span style=\"color: #000000;\">negativi per la salute mentale.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-23264 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2011\/12\/ecografia.jpg\" alt=\"\" width=\"296\" height=\"219\" \/>Uno studio pubblicato sul British Journal of Psychiatry ha rilevato che le donne che hanno abortito hanno avuto un aumento dell\u201981% del rischio di problemi di salute mentale. La ricerca ha rivelato che l\u2019aborto \u00e8 stato associato a un aumento del 34% del rischio di disturbi d\u2019ansia; del 37% del rischio di depressione; del 110% del rischio di abuso di alcol e del 220% del rischio di uso\/abuso di marijuana.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">L\u2019aborto \u00e8 stato anche collegato a un rischio maggiore del 155% di tentare il suicidio.<\/span><\/p>\n<p>_________________________<\/p>\n<p><strong>Per approfondire:<\/strong><\/p>\n<p><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-sindrome-post-abortiva-descrizione-e-atteggiamento-terapeutico\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">La sindrome post-abortiva. Descrizione e atteggiamento terapeutico<\/span><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Abstract: L&#8217;aborto mina la salute mentale della donna- lo rivela uno studio di recente pubblicazione. Le donne che hanno dato alla luce i loro primi figli hanno effettivamente utilizzato i servizi di salute mentale a un tasso pi\u00f9 elevato prima della gravidanza rispetto a quelle il cui primo figlio \u00e8 stato ucciso attraverso l\u2019aborto, suggerendo &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/laborto-mina-la-salute-mentale-della-donna\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":34906,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[2386],"class_list":["post-56712","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aborto","tag-aborto","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&#039;aborto mina la salute mentale della donna - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"L&#039;aborto mina la salute mentale della donna; lo rivela uno studio di recente pubblicazione. Maggior anche il rischio suicidio\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/laborto-mina-la-salute-mentale-della-donna\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;aborto mina la salute mentale della donna - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"L&#039;aborto mina la salute mentale della donna; lo rivela uno studio di recente pubblicazione. Maggior anche il rischio suicidio\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/laborto-mina-la-salute-mentale-della-donna\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-19T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-10T15:27:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/09\/donna_aborto.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"280\" \/>\n\t<meta property=\"og:image:height\" content=\"180\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/laborto-mina-la-salute-mentale-della-donna\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/laborto-mina-la-salute-mentale-della-donna\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"L&#8217;aborto mina la salute mentale della donna\",\"datePublished\":\"2023-07-19T22:00:00+00:00\",\"dateModified\":\"2023-12-10T15:27:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/laborto-mina-la-salute-mentale-della-donna\\\/\"},\"wordCount\":782,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/laborto-mina-la-salute-mentale-della-donna\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/09\\\/donna_aborto.jpg\",\"keywords\":[\"Aborto\"],\"articleSection\":[\"Aborto\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/laborto-mina-la-salute-mentale-della-donna\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/laborto-mina-la-salute-mentale-della-donna\\\/\",\"name\":\"L'aborto mina la salute mentale della donna - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/laborto-mina-la-salute-mentale-della-donna\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/laborto-mina-la-salute-mentale-della-donna\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/09\\\/donna_aborto.jpg\",\"datePublished\":\"2023-07-19T22:00:00+00:00\",\"dateModified\":\"2023-12-10T15:27:55+00:00\",\"description\":\"L'aborto mina la salute mentale della donna; lo rivela uno studio di recente pubblicazione. Maggior anche il rischio suicidio\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/laborto-mina-la-salute-mentale-della-donna\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/laborto-mina-la-salute-mentale-della-donna\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/laborto-mina-la-salute-mentale-della-donna\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/09\\\/donna_aborto.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/09\\\/donna_aborto.jpg\",\"width\":280,\"height\":180},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/laborto-mina-la-salute-mentale-della-donna\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&#8217;aborto mina la salute mentale della donna\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'aborto mina la salute mentale della donna - Rassegna Stampa Cattolica","description":"L'aborto mina la salute mentale della donna; lo rivela uno studio di recente pubblicazione. Maggior anche il rischio suicidio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/laborto-mina-la-salute-mentale-della-donna\/","og_locale":"it_IT","og_type":"article","og_title":"L'aborto mina la salute mentale della donna - Rassegna Stampa Cattolica","og_description":"L'aborto mina la salute mentale della donna; lo rivela uno studio di recente pubblicazione. Maggior anche il rischio suicidio","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/laborto-mina-la-salute-mentale-della-donna\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2023-07-19T22:00:00+00:00","article_modified_time":"2023-12-10T15:27:55+00:00","og_image":[{"width":280,"height":180,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/09\/donna_aborto.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/laborto-mina-la-salute-mentale-della-donna\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/laborto-mina-la-salute-mentale-della-donna\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"L&#8217;aborto mina la salute mentale della donna","datePublished":"2023-07-19T22:00:00+00:00","dateModified":"2023-12-10T15:27:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/laborto-mina-la-salute-mentale-della-donna\/"},"wordCount":782,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/laborto-mina-la-salute-mentale-della-donna\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/09\/donna_aborto.jpg","keywords":["Aborto"],"articleSection":["Aborto"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/laborto-mina-la-salute-mentale-della-donna\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/laborto-mina-la-salute-mentale-della-donna\/","name":"L'aborto mina la salute mentale della donna - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/laborto-mina-la-salute-mentale-della-donna\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/laborto-mina-la-salute-mentale-della-donna\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/09\/donna_aborto.jpg","datePublished":"2023-07-19T22:00:00+00:00","dateModified":"2023-12-10T15:27:55+00:00","description":"L'aborto mina la salute mentale della donna; lo rivela uno studio di recente pubblicazione. Maggior anche il rischio suicidio","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/laborto-mina-la-salute-mentale-della-donna\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/laborto-mina-la-salute-mentale-della-donna\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/laborto-mina-la-salute-mentale-della-donna\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/09\/donna_aborto.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/09\/donna_aborto.jpg","width":280,"height":180},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/laborto-mina-la-salute-mentale-della-donna\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"L&#8217;aborto mina la salute mentale della donna"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/56712","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=56712"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/56712\/revisions"}],"predecessor-version":[{"id":58096,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/56712\/revisions\/58096"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/34906"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=56712"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=56712"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=56712"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}