{"id":5631,"date":"2013-06-27T00:00:00","date_gmt":"2013-06-26T22:00:00","guid":{"rendered":""},"modified":"2016-12-02T14:06:16","modified_gmt":"2016-12-02T13:06:16","slug":"salviamo-le-donne-dal-femmicidio","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/salviamo-le-donne-dal-femmicidio\/","title":{"rendered":"Salviamo le donne dal Femmicidio"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2013\/06\/donne.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-25526\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2013\/06\/donne.jpg\" alt=\"donne\" width=\"250\" height=\"182\" \/><\/a>Studi Cattolici<\/strong> n.627 Maggio 2013<\/div>\n<p style=\"text-align: center;\">di <strong>Pier Giorgio Liverani<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00abNon ci consideriamo donne, ma cittadine\u00bb. Riparleremo tra poco di questa affermazione, fatta nel <em>Women\u2019s Day<\/em> del marzo scorso, durante un incontro femminista, a Roma, da una \u00abgiornalista blogger\u00bb araba. Come prima cosa sembra giusto annoverare la traduzione in inglese della Festa delle Donne (l&#8217;8 marzo) non solo nell&#8217;italianicidio linguistico ormai dilagante, ma anche nello scenario del \u00abfemminicidio\u00bb, anzi, pi\u00f9 correttamente del \u00abfemmicidio\u00bb.<\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">Questi due neologismi, molto vicini tra loro, sono letture diverse delle uccisioni delle donne. Il \u00abfemminicidio\u00bb \u00e8 la manifestazione estrema della violenza maschile-maschilista contro le donne. Invece il \u00abfemmicidio\u00bb &#8211; secondo la definizione della \u00abTavola sul Femminicidio\u00bb tenutasi a Roma nel novembre dell&#8217;anno scorso \u2014 \u00e8 \u00abl&#8217;uccisione di una donna proprio perch\u00e9 donna, che, nella ricerca criminologica, include anche le situazioni in cui la morte della donna rappresenta l&#8217;esito\/la conseguenza di pratiche sociali misogine\u00bb.<\/div>\n<p style=\"text-align: justify;\">In Italia i femminicidi sembrano seguire un andamento crescente: ottantaquattro casi nel 2005, centouno nel 2006 e cos\u00ec via fino ai centoventi del 2012. Naturalmente \u00e8 giusto condividere pienamente il severo giudizio che di entrambi se ne da e la preoccupazione per la loro frequenza e per il luogo in cui in maggioranza avvengono: la famiglia o un \u00e0mbito affettivo fra i tanti.\u00a0 Lo scorso 25 novembre l&#8217;Onu ha celebrato la \u00abGiornata Internazionale per il contrasto alla violenza sulle donne\u00bb, confermando che per l&#8217;85 per cento costoro sono vittime all&#8217;interno di rapporti sentimentali.<\/p>\n<p style=\"text-align: justify;\">A questi dati (che non distinguono i femminicidi dai femmicidi) \u00e8 possibile, per\u00f2, contrapporre l&#8217;elenco, polemicamente pubblicato su un sito web (<em>Pontifex.it<\/em>), che raccoglie novantadue casi di&#8230; \u00abmaschicidi\u00bb compiuti da donne nell&#8217;anno da poco terminato: dall&#8217;omicidio tentato da un killer assoldato da una poliziotta (Torino, 10 gennaio) per ammazzare l&#8217;ex marito, al delitto di una donna 43enne (Modena, 20 dicembre), che ha ucciso il fratello con trenta colpi di pistola. Niente male. Ma bisognerebbe mettere nel bilancio anche la donna di 35 anni che, per gelosia, ha ucciso la sua \u00abcompagna\u00bb di 34 anni con un colpo di pistola.<\/p>\n<p style=\"text-align: justify;\">Quest&#8217;elenco &#8211; che quasi pareggia i conti tra le violenze reciproche dei due sessi \u2014 \u00e8 stato taciuto dai media, sicuramente perch\u00e9 avrebbe contrastato la provocazione, ricercata, della reazione emotiva delle donne. In ogni caso esso non toglie valore alla denuncia dell&#8217;Orni e all&#8217;indignazione preoccupata di ogni persona di buon senso. In pi\u00f9, forse, pu\u00f2 spiegare il basso tono del <em>Women s Day<\/em> italiano di quest&#8217;anno.<\/p>\n<p style=\"text-align: justify;\">La giornata delle donne, ormai non pi\u00f9 festosa e celebrata piuttosto sul versante della tristezza, avrebbe dovuto distinguere fra femminicidi e femmicidi, se non altro perch\u00e9, come dimostra l&#8217;affermazione citata all&#8217;inizio, c&#8217;\u00e8 nel mondo femminile qualche inquietudine e qualche incertezza nell&#8217;autopercezione di s\u00e9 stesse, che nemmeno la Commissione Femm &#8211; in altre parole per i \u00abDiritti della donna e l&#8217;uguaglianza di genere\u00bb, che \u00e8 una delle commissioni permanenti del Parlamento Europeo &#8211; \u00e8 riuscita a superare quando, a met\u00e0 dello scorso mese di marzo a Ginevra, si \u00e8 riunita presso il Consiglio dei Diritti dell&#8217;Uomo e mentre era in corso la Conferenza annuale dell&#8217;Onu sulla violenza contro le donne.<\/p>\n<p style=\"text-align: justify;\">In realt\u00e0 l&#8217;interrogativo implicito in quel \u00abNon ci consideriamo donne ma cittadine\u00bb \u00e8 drammatico. Che cosa vale di pi\u00f9, infatti, tra \u00abdonna\u00bb e \u00abcittadina\u00bb? E quale delle due condizioni \u00e8 pi\u00f9 rischiosa? Ed \u00e8 maggiore o minore il pericolo del femmicidio rispetto al femminicidio? Chi scrive propende per la maggiore drammaticit\u00e0 della prima delle due figure delittuose. E questo anche perch\u00e9, in ossequio ai princ\u00ecpi di Yogyacarta (1) e secondo le notizie che provengono da Bruxelles come da Strasburgo, gi\u00e0 dal 2016 nelle carte d&#8217;identit\u00e0 europee il termine \u00absesso\u00bb sar\u00e0 sostituito dalla pi\u00f9 moderna e liberale formula \u00abIG\u00bb, che significa \u00abidentit\u00e0 di genere\u00bb, cio\u00e8 il sesso (il gender) che ciascuno si sceglier\u00e0, anche contro quello di nascita. Cosa che render\u00e0 ancora pi\u00f9 debole e leggero il valore e il peso del sesso femminile. Allora e nel caso specifico cui qui ci si \u00e8 riferiti, meglio \u00abcittadina\u00bb, che non \u00e8 soggetto a mutazioni sessuali.<\/p>\n<p style=\"text-align: justify;\"><strong>Uccisione ideologica<\/strong><\/p>\n<p style=\"text-align: justify;\">II \u00abfemmicidio\u00bb, si diceva, ossia quello che nelle figurazioni antropologiche del femminile non \u00e8 ancora emerso e di cui nessuno parla. Eppure \u00e8 quello che fa pi\u00f9 paura, perch\u00e9 non \u00e8 considerato un crimine nonostante ne abbia la sostanza n\u00e9 \u00e8 soggetto alle repressioni poliziesche: il vero femmicidio \u00e8 l&#8217;uccisione non fisica ma ideologica, o se volete antropologica dell&#8217;idea stessa di donna.<\/p>\n<p style=\"text-align: justify;\">Un omicidio che non \u00e8 previsto da alcun codice penale, anzi \u00e8 autorizzato e protetto dalle leggi e dalla nuova Europa. Un delitto etico pi\u00f9 grave, se possibile, del delitto \u00abfisico\u00bb. Lo dice la definizione stessa del neologismo \u00abfemmicidio\u00bb, inteso &#8211; \u00e8 la fattispecie che qui ci interessa &#8211; nel senso dell&#8217;uccisione del concetto \u00abteleologico\u00bb della donna, ossia del perch\u00e9 essa esiste, opera, vive e fa la sua parte nell&#8217;esistenza del genere umano (e, per i credenti, nel disegno di Dio).<\/p>\n<p style=\"text-align: justify;\">Il \u00abfemmicidio\u00bb colpisce la condizione di soggetto giuridico della donna, di persona, di cittadina titolare di una serie di diritti umani, civili e politici e di compiti e doveri, il suo essere persona sessuata, sposa, madre, membro di una famiglia con il nome nobilitante di donna, cio\u00e8 di domina, signora, Signora del Creato (\u00abDominate la Terra\u00bb, cio\u00e8 signoreggiatela&#8230;). Il che implica, sia ben chiaro, anche tutto l&#8217;altro che la donna gi\u00e0 fa e far\u00e0 nella famiglia e nella societ\u00e0 oltre a ci\u00f2 che di lei \u00e8 esclusivo. Donna o cittadina? Soltanto femmina (umana) come desolatamente sembra dire la giornalista-blogger araba o figura di tanto alta dignit\u00e0, nel progetto della creazione, da poter essere definita la \u00abmet\u00e0 pi\u00f9 una\u00bb del cielo?<\/p>\n<p style=\"text-align: justify;\">\u00c8 questa la risposta che non \u00e8 venuta dalla Commissione Femm n\u00e9 dalle Nazioni Unite n\u00e9 dagli organismi della Grande Europa e tantomeno dalle varie organizzazioni femministe che esaltano a vuoto il nome di Donna. Eppure ci dev&#8217;essere un motivo nascosto e da riscoprire del perch\u00e9 il numero delle donne \u00e8 sempre maggiore di quello dei maschi, perch\u00e9 la vita media delle donne \u00e8 pi\u00f9 lunga di quella degli uomini, perch\u00e9 \u00e8 la donna che genera anche il maschio.<\/p>\n<p style=\"text-align: justify;\">Perch\u00e9 gi\u00e0 l&#8217;Antico Testamento e pi\u00f9 ancora quello Nuovo, pur contando meno personaggi femminili di quelli maschili, rendono esplicita pi\u00f9 volte la femminilit\u00e0 e la maternit\u00e0 del Signore Dio? Perch\u00e9 \u00e8 alla donna che il Creatore ha affidato la \u00abcura\u00bb dell&#8217;uomo? E perch\u00e9 oggi, in una societ\u00e0 femminista, \u00e8 alle donne che si vuole affidare piuttosto l&#8217;insindacabile <em>jus vitae ac necis <\/em>sulle creature che esse portano nel loro grembo, cio\u00e8 la terribile <em>potestas,<\/em> che gli antichi Romani avevano riservato al<em> paterfamilias,<\/em> il padre-padrone della famiglia?<\/p>\n<p style=\"text-align: justify;\">Per trovare una risposta bisogna rileggere la lettera apostolica <em>Mulieris Dignitatem<\/em> di Giovanni Paolo II, che sembra giacere, per\u00f2, tra i volumi meno richiesti nella biblioteca magisteriale della Chiesa.<\/p>\n<p style=\"text-align: justify;\"><strong>Un delitto antropologico<\/strong><\/p>\n<p style=\"text-align: justify;\">Le donne sono uccise in tanti modi anche non sanguinosi. Bisogna andare oltre la cronaca, le circostanze e le motivazioni \u2014 sempre banali &#8211; dei delitti contati e catalogati semplicemente come femminicidi. \u00c8 tempo di prendere coscienza di una violenza radicalmente diversa e che va oltre l&#8217;uccisione del corpo femminile e colpisce invece la donna come tale: un delitto antropologico che chiama in causa non il codice penale, ma i cosiddetti \u00abdiritti civili\u00bb, quelle nefaste caricature dei diritti dell&#8217;uomo, prive di sostanza giuridica e frutto delle mutevoli convinzioni e dei desideri \u00abculturali\u00bb della nostra epoca e, soprattutto, di un preteso ma inesistente diritto, in questo caso femminile, all&#8217;autodeterminazione.<\/p>\n<p style=\"text-align: justify;\">Essi sostanziano il caos etico della nostra era e della nostra societ\u00e0, trasformando il delitto in diritto come, 25 anni fa, scriveva Giovanni Paolo II nella <em>Evangelium Vitae. <\/em>I \u00abdiritti civili\u00bb sono, in realt\u00e0, \u00abdistorti civili\u00bb, una distorsione del diritto, sono diritti di morte. Se non altro dopo cinque milioni e mezzo di bambini morti prima di nascere, occorre finalmente che il femminismo si chieda se l&#8217;asserito \u00abdiritto civile di abortire\u00bb, ormai riconosciuto dall&#8217;ordinamento italiano, lasci indenne o piuttosto ferisca quasi mortalmente il \u00abvolto\u00bb della donna, la <em>mulieris dignitas <\/em>e, con questa, anche \u00abla sua vocazione\u00bb di maternit\u00e0 e di cura, inducendola a violare il patto nuziale stretto nell&#8217;incontro coniugale con il futuro deluso padre.<\/p>\n<p style=\"text-align: justify;\">La Lettera apostolica di Giovanni Paolo II appena richiamata, ricordava proprio nel suo <em>incipit <\/em>alcune parole assai esplicite di papa Montini: \u00abNel cristianesimo, infatti, pi\u00f9 che in ogni altra religione, la donna ha fin dalle origini uno speciale statuto di dignit\u00e0, di cui il Nuovo Testamento ci attesta non pochi <em>e <\/em>non piccoli aspetti (2)\u00bb. Non si tratta, tuttavia, soltanto di aborto. Anche il divorzio \u00e8 un <em>vul<\/em><em>nus <\/em>palese alla \u00abvocazione\u00bb femminile e alla sua dignit\u00e0 di donna (cio\u00e8 di <em>domina, <\/em>che non pu\u00f2 essere \u00abusata\u00bb), che mira a un&#8217;unione coniugale perenne che solo la morte pu\u00f2 sciogliere (e io spero che duri anche oltre, nell&#8217;altra vita).<\/p>\n<p style=\"text-align: justify;\">\u00c8 femmicidio la pratica dell&#8217;omosessualit\u00e0 femminile che, nel rifiuto dell&#8217;incontro con la diversit\u00e0 dell&#8217;uomo, nega (analogamente a ci\u00f2 che accade nel maschio) l&#8217;essenza procreatrice della femminilit\u00e0 per preferirle la sterilit\u00e0 di una donna non pi\u00f9 \u00abaltra\u00bb, ma inutilmente \u00abeguale\u00bb. Va perduta cos\u00ec la ricchezza femminile, che si realizza specialmente nell&#8217;incontro-confronto con la maschilit\u00e0 per cui \u00e8 stata creata.<\/p>\n<p style=\"text-align: justify;\"><strong>Il figlio come \u00abprodotto\u00bb<\/strong><\/p>\n<p style=\"text-align: justify;\">Analogamente \u00e8 femmicidio la fecondazione artificiale, che non solo porta a morte milioni di figli in embrione condannati all&#8217;ergastolo nel gelo di un bidone a meno 196 gradi, ma si compie mediante l&#8217;intrusione, a volte a-dulterina, di terze persone, vale a dire trasformando in estraneit\u00e0 un processo di reciproca integrazione e intimit\u00e0 donna-uomo che maggiore non potrebbe esservi. Invece di un figlio <em>(l\u2019una <\/em><em>caro), <\/em>il suo esito voluto <em>\u00e8 <\/em>progettato come un \u00abprodotto\u00bb, di cui spesso si esige la garanzia di qualit\u00e0, pena il rifiuto.<\/p>\n<p style=\"text-align: justify;\">Ancora: la contraccezione, vera negazione <em>a priori <\/em>della vocazione della donna; la \u00abcoppia di fatto\u00bb, in cui la donna \u00e8 ridotta a semplice \u00abcompagna\u00bb; e infine il <em>gender, <\/em>dove (come nell&#8217;uomo) l&#8217;essere donna non \u00e8 un \u00abper sempre\u00bb, ma soltanto una questione di voglia, di moda, di tempo.<\/p>\n<p style=\"text-align: justify;\">E, per finire, la questione delle \u00abquote rosa\u00bb obbligatorie per legge, che accusano la donna di un&#8217;inesistente incapacit\u00e0 a emergere per forza propria e riducono il genere femminile a una sorta di specie protetta, quasi fosse a rischio di estinzione (reale, se si proseguir\u00e0 con questi femmicidi).<\/p>\n<p style=\"text-align: justify;\">Durante la conferenza ginevrina del Consiglio dei diritti dell&#8217;uomo, cui si \u00e8 accennato all&#8217;inizio, una deputata olandese, Kartika Tamara Liotard, ha denunciato \u00abl&#8217;eccessiva esposizione dei corpi, troppo spesso sessualizzati\u00bb. Che riduce la donna a femmina. Cosa facilmente costatabile anche senza bisogno delle denunce Onu, ma che fa pensare a quel parroco di Lerici (La Spezia) che, alla fine del dicembre scorso, i media hanno condannato alla gogna e il Vescovo ha mandato in ferie per avere esposto un manifestino in cui si accusavano di provocazione al proprio omicidio le donne in minigonne eccessive. Don Piero non aveva tutti i torti. Andava soprattutto contro corrente.<\/p>\n<p style=\"text-align: justify;\">Troppi fantasmi di donne senza volto si aggirano in Europa e nel mondo. Io credo che, piuttosto o prima che cittadine, sia molto meglio essere donne. I cittadini, infatti, non hanno sesso e perci\u00f2, se tali fossero, le donne rischierebbero di valere soltanto quanto gli uomini.<\/p>\n<p style=\"text-align: justify;\"><strong>Note<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>1)<\/strong> \u00c8 una citt\u00e0 turistica dell&#8217;isola di Giava, in Indonesia, con circa 3 milioni di abitanti. I \u00abPrinc\u00ecpi\u00bb, elaborati nel novembre 2006, riguardano la salvaguardia dei diritti umani in relazione, per\u00f2, all&#8217;orientamento sessuale e all&#8217;identit\u00e0 di genere.<\/p>\n<p style=\"text-align: justify;\"><strong>2)<\/strong><em> Mulieris Dignitatem, <\/em>1, che richiama: Paolo VI, <em>Discorso alle partecipanti al <\/em><em>Convegno Nazionale del Centro Femmini<\/em><em>le Italiano <\/em>(6 dicembre 1976).<\/p>\n<p style=\"text-align: justify;\">________________________<\/p>\n<p style=\"text-align: justify;\"><strong>Leggi anche:<\/strong><\/p>\n<p><a title=\"PermaLink a Femminicidio? I dati sulle violenze dicono il contrario\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=31796\" target=\"_blank\" rel=\"bookmark\">Femminicidio? I dati sulle violenze dicono il contrario<\/a><br \/>\n<a title=\"PermaLink a Femminicidio. I dati di un allarme inventato\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=5754\" target=\"_blank\" rel=\"bookmark\">Femminicidio. I dati di un allarme inventato<\/a><br \/>\n<a title=\"PermaLink a Femminicidio, ma gli uomini uccisi sono di pi\u00f9\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=5685\" target=\"_blank\" rel=\"bookmark\">Femminicidio, ma gli uomini uccisi sono di pi\u00f9<\/a>\u00a0[con in\u00a0appendice articoli tratti dalla cronaca di omicidi di uomini perppetrati da donne]<br \/>\n<a title=\"PermaLink a Femminicidio, invenzione di regime\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=5682\" target=\"_blank\" rel=\"bookmark\">Femminicidio, invenzione di regime<\/a><br \/>\n<a title=\"PermaLink a Convenzione di Istanbul, donne e dubbi\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=5606\" target=\"_blank\" rel=\"bookmark\">Convenzione di Istanbul, donne e dubbi<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Studi Cattolici n.627 Maggio 2013 di Pier Giorgio Liverani \u00abNon ci consideriamo donne, ma cittadine\u00bb. Riparleremo tra poco di questa affermazione, fatta nel Women\u2019s Day del marzo scorso, durante un incontro femminista, a Roma, da una \u00abgiornalista blogger\u00bb araba. Come prima cosa sembra giusto annoverare la traduzione in inglese della Festa delle Donne (l&#8217;8 marzo) &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/salviamo-le-donne-dal-femmicidio\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":25526,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25],"tags":[256,340],"class_list":["post-5631","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sguardo-sul-nostro-tempo","tag-donne","tag-femminicidio","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Salviamo le donne dal Femmicidio - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/salviamo-le-donne-dal-femmicidio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Salviamo le donne dal Femmicidio - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/salviamo-le-donne-dal-femmicidio\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2013-06-26T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-12-02T13:06:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2013\/06\/donne.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"263\" \/>\n\t<meta property=\"og:image:height\" content=\"191\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/salviamo-le-donne-dal-femmicidio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/salviamo-le-donne-dal-femmicidio\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Salviamo le donne dal Femmicidio\",\"datePublished\":\"2013-06-26T22:00:00+00:00\",\"dateModified\":\"2016-12-02T13:06:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/salviamo-le-donne-dal-femmicidio\\\/\"},\"wordCount\":1962,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/salviamo-le-donne-dal-femmicidio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2013\\\/06\\\/donne.jpg\",\"keywords\":[\"donne\",\"femminicidio\"],\"articleSection\":[\"Sguardo sul nostro tempo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/salviamo-le-donne-dal-femmicidio\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/salviamo-le-donne-dal-femmicidio\\\/\",\"name\":\"Salviamo le donne dal Femmicidio - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/salviamo-le-donne-dal-femmicidio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/salviamo-le-donne-dal-femmicidio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2013\\\/06\\\/donne.jpg\",\"datePublished\":\"2013-06-26T22:00:00+00:00\",\"dateModified\":\"2016-12-02T13:06:16+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/salviamo-le-donne-dal-femmicidio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/salviamo-le-donne-dal-femmicidio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/salviamo-le-donne-dal-femmicidio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2013\\\/06\\\/donne.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2013\\\/06\\\/donne.jpg\",\"width\":263,\"height\":191},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/salviamo-le-donne-dal-femmicidio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Salviamo le donne dal Femmicidio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Salviamo le donne dal Femmicidio - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/salviamo-le-donne-dal-femmicidio\/","og_locale":"it_IT","og_type":"article","og_title":"Salviamo le donne dal Femmicidio - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/salviamo-le-donne-dal-femmicidio\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2013-06-26T22:00:00+00:00","article_modified_time":"2016-12-02T13:06:16+00:00","og_image":[{"width":263,"height":191,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2013\/06\/donne.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"10 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/salviamo-le-donne-dal-femmicidio\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/salviamo-le-donne-dal-femmicidio\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Salviamo le donne dal Femmicidio","datePublished":"2013-06-26T22:00:00+00:00","dateModified":"2016-12-02T13:06:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/salviamo-le-donne-dal-femmicidio\/"},"wordCount":1962,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/salviamo-le-donne-dal-femmicidio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2013\/06\/donne.jpg","keywords":["donne","femminicidio"],"articleSection":["Sguardo sul nostro tempo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/salviamo-le-donne-dal-femmicidio\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/salviamo-le-donne-dal-femmicidio\/","name":"Salviamo le donne dal Femmicidio - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/salviamo-le-donne-dal-femmicidio\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/salviamo-le-donne-dal-femmicidio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2013\/06\/donne.jpg","datePublished":"2013-06-26T22:00:00+00:00","dateModified":"2016-12-02T13:06:16+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/salviamo-le-donne-dal-femmicidio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/salviamo-le-donne-dal-femmicidio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/salviamo-le-donne-dal-femmicidio\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2013\/06\/donne.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2013\/06\/donne.jpg","width":263,"height":191},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/salviamo-le-donne-dal-femmicidio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Salviamo le donne dal Femmicidio"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/5631","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=5631"}],"version-history":[{"count":5,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/5631\/revisions"}],"predecessor-version":[{"id":36851,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/5631\/revisions\/36851"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/25526"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=5631"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=5631"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=5631"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}