{"id":56278,"date":"2023-05-04T00:00:00","date_gmt":"2023-05-03T22:00:00","guid":{"rendered":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=56278"},"modified":"2023-12-28T13:16:40","modified_gmt":"2023-12-28T12:16:40","slug":"corruzione-un-male-antico","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/corruzione-un-male-antico\/","title":{"rendered":"Corruzione, un male antico"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-34641 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/senato-romano.jpg\" alt=\"\" width=\"314\" height=\"196\" \/><\/em><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>Abstract:<\/strong> c<em>orruzione, un male antico.<\/em> <em>Correva l\u2019anno 70 a.C. ai primi di gennaio, un giovane avvocato dell\u2019Urbe di nome Marco Tullio Cicerone, presenta al pretore Manlio Acilio Glabrione, presidente del tribunale per i reati di concussione, una richiesta formale di accusa contro Gaio Verre, governatore di Roma nella provincia di Sicilia per tre anni. <\/em><\/span><\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.centrostudilivatino.it\/\" target=\"_blank\" rel=\"noopener\"><strong><span style=\"color: #0000ff;\">Centro Studi Rosario Livatino<\/span><\/strong> <\/a><span style=\"color: #000000;\">29 Aprile 2023<\/span><\/p>\n<h3 style=\"text-align: center;\"><span style=\"color: #000000;\"><strong>Cicerone e la corruzione come male antico<\/strong><\/span><\/h3>\n<p class=\"has-text-align-justify has-black-color has-text-color\" style=\"text-align: justify;\"><em>Correva l\u2019anno 70 a.C. ai primi di gennaio, un giovane avvocato dell\u2019Urbe di nome Marco Tullio Cicerone, presenta al pretore Manlio Acilio Glabrione, presidente del tribunale per i reati di concussione, una richiesta formale di accusa contro Gaio Verre, governatore di Roma nella provincia di Sicilia per tre anni. Glabrione concede all\u2019avvocato Cicerone 110 giorni per trovare tutte le prove possibili per incastrare l\u2019accusato e arrivare al processo, fissato per la fine di aprile, con l\u2019inchiesta chiusa. Il reato \u00e8 quello di avere sfruttato a suo favore una provincia per assecondare i suoi giochi politici. Le requisitorie contro Verre divennero famose nel mondo antico e ancora oggi, conosciute con il nome di Verrine. Quest\u2019opera oltre ad avere avuto un impatto letterario di rilievo, che ancora continua ad esercitare il suo fascino, offre molteplici spunti d\u2019indagine al fine di sondare il terreno friabile del fenomeno corruttivo. Il processo a Verre e le orazioni ciceroniane rivelano infatti tratti di sorprendente attualit\u00e0 e pongono il focus su alcuni profili della corruzione che non smettono mai di creare interrogativi.<\/em><\/p>\n<p class=\"has-text-align-justify has-black-color has-text-color\" style=\"text-align: center;\">di <strong>Daniele Onori<\/strong><\/p>\n<p class=\"has-text-align-justify has-black-color has-text-color\" style=\"text-align: justify;\"><span style=\"color: var(--wp--preset--color--black); font-size: revert;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-41369 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/10\/corruzione-1920x1000-300x156.jpg\" alt=\"\" width=\"371\" height=\"193\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/10\/corruzione-1920x1000-300x156.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/10\/corruzione-1920x1000-768x400.jpg 768w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/10\/corruzione-1920x1000-1024x533.jpg 1024w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/10\/corruzione-1920x1000.jpg 1920w\" sizes=\"auto, (max-width: 371px) 100vw, 371px\" \/>La corruzione pu\u00f2 essere a giusto titolo inquadrata tra i mali pi\u00f9 antichi della civilt\u00e0. Risalgono alla Magna Grecia le prime testimonianze documentate [1], che descrivono la corruzione in termini di atto contrario alla morale pubblica e danno economico per la collettivit\u00e0. Spunti storici sono offerti dalle molteplici testimonianze dell\u2019oratore e politico Demostene, che nel 324 a.C., in occasione della nuova Olimpiade ad Atene, fu accusato pubblicamente di aver sottratto le somme destinate all\u2019organizzazione dei giochi olimpici, custodite da Arpalo, tesoriere di Alessandro Magno. Grazie alla veemente oratoria di Iperide, accusatore nel processo, la vicenda \u2013 tecnicamente qualificata come un furto \u2013 scosse l\u2019opinione pubblica come mai era accaduto prima di allora.<\/span><\/p>\n<p class=\"has-text-align-justify has-black-color has-text-color\" style=\"text-align: justify;\">Le vicende corruttive dell\u2019Impero Romano sono permeate da una retorica tradizione che voleva l\u2019Urbe dei primi giorni di gloria opposta \u2013 per virt\u00f9, morigeratezza e onore \u2013 alla Roma degli ultimi anni repubblicani e a quella degli imperatori detentori del potere assoluto. Questa convinzione si alimenta, principalmente, dell\u2019assenza di testi e testimonianze anche indirette sul fenomeno. Quando infatti si giunge alle prime produzioni letterarie sull\u2019argomento, con particolare menzione per l\u2019acuta penna di Plauto [2], il luogo comune dell\u2019integrit\u00e0 morale della Roma repubblicana si dissolve lasciando il proscenio ad ampi e persistenti grumi di malcostume politico e sociale, dall\u2019evasione fiscale all\u2019abuso di potere.<\/p>\n<p class=\"has-text-align-justify has-black-color has-text-color\" style=\"text-align: justify;\"><span style=\"color: var(--wp--preset--color--black); font-size: revert;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-34517 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/Senato_romano-1.jpg\" alt=\"\" width=\"275\" height=\"183\" \/>Durante l\u2019espansione nel Mediterraneo, e comunque ben prima della caduta di Cartagine, Catone il Censore arriv\u00f2 a denunciare pubblicamente in Senato il malaffare che avvolgeva gli uomini politici[3]; ed in particolare erano i governatori locali i soggetti pi\u00f9 inclini alla violazione della legge.<\/span><\/p>\n<p class=\"has-text-align-justify has-black-color has-text-color\" style=\"text-align: justify;\">I motivi sono presto detti: tali cariche erano un passaggio fondamentale nel cursus honorum di qualsiasi personaggio influente a Roma, le campagne elettorali chiedevano un impiego di denaro impressionante e di conseguenza ogni romano illustre doveva finanziarsi in modo vergognoso, indebitandosi e firmando ignobili compromessi e clientele.\u00f9<\/p>\n<p class=\"has-text-align-justify has-black-color has-text-color\" style=\"text-align: justify;\">Colp\u00ec per pervicacia il comportamento del propretore di Sicilia Verre, definito dalla letteratura \u2013 in uno slancio ironico \u2013 \u201c<em>arch\u00e8tipo originario del tangentocrate incallito<\/em>\u201d, che tra il 73 e il 71 a.C. comp\u00ec concussioni e ruberie che gli costarono, dopo il processo che vide assoluto protagonista il giovane accusatore Cicerone, la condanna a morte.<\/p>\n<p class=\"has-text-align-justify has-black-color has-text-color\" style=\"text-align: justify;\">Da pi\u00f9 di duemila anni le Verrine, cio\u00e8 le orazioni con cui Cicerone riusc\u00ec a inchiodare il propretore alle sue malversazioni in Sicilia sono state presentate \u2013 anche o soprattutto per la qualit\u00e0 di scrittura \u2013 come un modello in tutte le storie della letteratura latina.\u00a0<\/p>\n<p class=\"has-text-align-justify has-black-color has-text-color\" style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-48976 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/11\/senato_roma_toga.jpg\" alt=\"\" width=\"323\" height=\"224\" \/>Da quel 70 a.C. mai si \u00e8 avuta una denuncia per casi di corruzione in cui l\u2019accusatore non abbia provato a riprodurne ritmo, concatenazione di argomenti e stile incalzante. Da duemila anni \u00e8 stato quasi automatico che chi si accingeva a fare insinuazioni circa la moralit\u00e0 di qualche uomo politico iniziasse con il definirlo \u00abnovello Verre\u00bb. Lo ha fatto l\u2019autore dei Viaggi di Gulliver, Jonathan Swift, allorch\u00e9 sulle pagine di \u00abThe Examiner\u00bb fece a pezzi Thomas Wharton, gi\u00e0 Lord Luogotenente d\u2019Irlanda. E anche il filosofo Edmund Burke, quando chiese (senza successo) l\u2019impeachment di Warren Hastings, ex governatore generale del Bengala.<\/p>\n<p class=\"has-text-align-justify has-black-color has-text-color\" style=\"text-align: justify;\">A rendere celeberrimo il procedimento giudiziario in cui Cicerone assunse il ruolo del mattatore, fu la circostanza che il dibattimento si svolse di fronte a un gran numero di spettatori: il processo spettacolo \u00e8 un\u2019invenzione dei Romani e quello contro Verre fu, appunto, un processo spettacolo.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Il processo di Verre inizi\u00f2 il 5 agosto del 70 a.C., ma le sue fasi preliminari occuparono tutti i precedenti mesi dell\u2019anno, successivi al ritorno di Verre a Roma dalla Sicilia. Le Verrine costituiscono uno straordinario documento sulla procedura penale della tarda repubblica e, nello specifico, sul funzionamento del tribunale permanente (<em>quaestio perpetua<\/em>) che giudicava i crimini di concussione, la <em>quaestio repetundarum<\/em>.<\/p>\n<p class=\"has-text-align-justify has-black-color has-text-color\" style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-35681 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/impero_Roma.jpg\" alt=\"\" width=\"295\" height=\"198\" \/>Essa era il pi\u00f9 antico tribunale permanente romano, istituito nel 149 a.C. con lo scopo di sanzionare i crimini pecuniari dei magistrati romani contro gli alleati che risiedevano nelle province sottoposte al controllo di Roma [4]<\/p>\n<p class=\"has-text-align-justify has-black-color has-text-color\" style=\"text-align: justify;\">Il governatore Verre aveva finito il suo mandato in Sicilia nel gennaio del 70 a.C. ma non ebbe nemmeno il tempo di tornare a Roma che le citt\u00e0 dell\u2019isola, stremate per le vessazioni del politico, decisero di rivolgersi al brillante avvocato di Arpino, in virt\u00f9 del forte legame che l\u2019oratore aveva contratto con gli abitanti dell\u2019isola nel 75 a.C., quando era stato questore a Marsala, per intentare contro di lui una causa per corruzione.<\/p>\n<p class=\"has-text-align-justify has-black-color has-text-color\" style=\"text-align: justify;\">Contemporaneamente, si present\u00f2 di fronte al medesimo tribunale un altro aspirante accusatore di Verre, Quinto Cecilio Nigro, un liberto siciliano che era stato questore di Verre nel primo anno del suo governo provinciale: egli rivendicava per s\u00e9 il ruolo di accusatore sia in nome di una iniuria subita da Verre (div. Caec. 52-58), sia per il fatto di essere persona informata sui fatti contestati all\u2019imputato (div. Caec. 61-63). Qualora di fronte alla quaestio si presentassero pi\u00f9 accusatori, la procedura prevedeva il ricorso alla <em>divinatio<\/em>, ossia a un esame, da parte di una commissione di giudici, delle ragioni che gli accusatori adducevano per motivare la loro richiesta, che ciascuno esponeva in un discorso, e al successivo verdetto, senza il ricorso a documentazione probatoria o a testimoni, sul candidato pi\u00f9 idoneo a svolgere la funzione.<\/p>\n<p class=\"has-text-align-justify has-black-color has-text-color\" style=\"text-align: justify;\"><span style=\"color: var(--wp--preset--color--black); font-size: revert;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-47419 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/06\/Roma_cicerone.jpg\" alt=\"\" width=\"193\" height=\"261\" \/>Il confronto tra Cicerone e Cecilio si tenne alla fine di gennaio: nel suo discorso, la <\/span><em style=\"color: var(--wp--preset--color--black); font-size: revert;\">divinatio in Q. Caecilium<\/em><span style=\"color: var(--wp--preset--color--black); font-size: revert;\">, Cicerone punt\u00f2 sull\u2019inesperienza forense del giovane Cecilio e dimostr\u00f2 che egli non era un vero accusatore bens\u00ec un <\/span><em style=\"color: var(--wp--preset--color--black); font-size: revert;\">praevaricator<\/em><span style=\"color: var(--wp--preset--color--black); font-size: revert;\"> (div. Caec. 12; 29; 58), ossia un falso accusatore che agiva d\u2019intesa con l\u2019imputato e la sua difesa e che una volta ottenuta l\u2019accusa si sarebbe adoperato per prevenire la condanna.<\/span><\/p>\n<p class=\"has-text-align-justify has-black-color has-text-color\" style=\"text-align: justify;\">Gli argomenti di Cicerone convinsero la commissione, che gli affid\u00f2 l\u2019incarico di accusatore, concedendogli contestualmente un periodo di 110 giorni per svolgere indagini (<em>tempus inquirendi<\/em>) in Sicilia al fine di acquisire documenti, testimonianze e ogni altro genere di prove utili alla sua accusa.<\/p>\n<p class=\"has-text-align-justify has-black-color has-text-color\" style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-27564 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/09\/antichi-romani.jpg\" alt=\"\" width=\"255\" height=\"198\" \/>Si ritiene utile qui riportare un breve passo per comprendere quali sono le ragioni che indussero Cicerone ad accettare un mandato cos\u00ec difficile: <em>L\u2019occasione che era soprattutto desiderabile, o giudici, l\u2019occasione che pi\u00f9 d\u2019ogni altra serviva a placare l\u2019ostilit\u00e0 verso la vostra classe e il discredito dell\u2019amministrazione giudiziaria sembra data e offerta a voi, in un momento critico per lo Stato, non per decisione umana ma quasi per volere divino. Gi\u00e0 da tempo, infatti, \u00e8 invalsa questa opinione, dannosa per lo Stato e pericolosa per voi, che si \u00e8 diffusa per i discorsi di tutti non solo fra il popolo romano, ma anche fra le nazioni estere; che con l\u2019attuale amministrazione della giustizia un uomo danaroso, colpevole quanto si voglia, non pu\u00f2 in nessun caso essere condannato. [\u2026] Io ho assunto questa causa, giudici, con pieno consenso e vivissima attesa da parte del popolo romano, non per accrescere l\u2019ostilit\u00e0 verso una classe sociale, ma per porre rimedio al discredito generale. Infatti, ho portato in Tribunale un uomo che vi desse la possibilit\u00e0 di ristabilire nell\u2019amministrazione giudiziaria la stima perduta, di riconquistare il favore del popolo romano. <\/em>[5]\u00a0<\/p>\n<p class=\"has-text-align-justify has-black-color has-text-color\" style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-56289 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2023\/05\/Rona_giustizia_processo.jpg\" alt=\"\" width=\"227\" height=\"283\" \/>Di contro Verre non si lesin\u00f2 a chiamare a sua volta il migliore avvocato di Roma, Quinto Ortensio Ortalo per la difesa. Per prima cosa il Principe del Foro, amico del governatore corrotto, cerc\u00f2 di far slittare il processo oltre l\u2019autunno, quando, per il suo cliente, i tempi politici potevano essere sicuramente migliori. Visto fallire il tentativo di influenzare il processo con la nomina di Cecilio ad accusatore, ricorse a un nuovo espediente per ostacolare Cicerone: subito dopo l\u2019accettazione della denuncia contro di lui da parte della <em>quaestio<\/em> (<em>nominis receptio<\/em>), si present\u00f2 di fronte a essa un accusatore, il cui nome rimane ignoto, che intendeva avviare un\u2019azione per dei crimini compiuti in Grecia da un altrettanto ignoto governatore della Macedonia.<\/p>\n<p class=\"has-text-align-justify has-black-color has-text-color\" style=\"text-align: justify;\">Questo accusatore chiese 108 giorni per la sua <em>inquisitio<\/em> in Grecia, cio\u00e8 appena due giorni in meno rispetto a quelli accordati a Cicerone: ci\u00f2 implicava che il processo contro il governatore macedone avesse la precedenza su quello contro Verre, come di fatto avvenne. Cicerone accusa esplicitamente Verre e i suoi sostenitori di aver orchestrato un processo-farsa per rimandare l\u2019inizio delle udienze a suo carico e di avere a tal proposito subornato un accusatore compiacente, che dopo aver richiesto 108 giorni per le sue indagini non si rec\u00f2 nemmeno a Brindisi per imbarcarsi per la Grecia (Verr. 1,6; 2,1,30).\u00a0<\/p>\n<p class=\"has-text-align-justify has-black-color has-text-color\" style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-56290 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2023\/05\/Navi_Roma_commercio.jpg\" alt=\"\" width=\"318\" height=\"158\" \/>Nonostante ci\u00f2, Cicerone part\u00ec per la Sicilia, dove svolse accurate indagini, e rientr\u00f2 a Roma allo scadere esatto dei 110 giorni, intorno alla met\u00e0 di aprile, nello stesso periodo in cui sarebbe dovuto rientrare dalla Grecia l\u2019altro accusatore. A quel punto inizi\u00f2 il processo contro il governatore macedone, che tenne occupata la quaestio nei mesi di maggio e giugno, che per Cicerone sarebbero stati i pi\u00f9 utili a svolgere il processo per la quasi totale assenza di ludi che interrompessero l\u2019attivit\u00e0 giudiziaria.<\/p>\n<p class=\"has-text-align-justify has-black-color has-text-color\" style=\"text-align: justify;\">Ad ogni modo, con solerzia e abilit\u00e0, Cicerone fece s\u00ec che il processo fosse messo a ruolo prima dell\u2019interruzione estiva. Verre perdeva gi\u00e0 il primo vantaggio: quello di poter essere giudicato da giudici amici. Allo stesso tempo il giovane avvocato riusc\u00ec a trattenere per s\u00e9 l\u2019accusa cui era particolarmente legato, sia per amore della giustizia sia per il salto di carriera che si accingeva a compiere. Era il suo primo incarico come difensore della parte civile: negli anni precedenti era sempre stato difensore dell\u2019imputato.<\/p>\n<p class=\"has-text-align-justify has-black-color has-text-color\" style=\"text-align: justify;\"><span style=\"color: var(--wp--preset--color--black); font-size: revert;\"> <img loading=\"lazy\" decoding=\"async\" class=\" wp-image-58453 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2023\/05\/romani_patrizi_roma.jpeg\" alt=\"\" width=\"315\" height=\"211\" \/>Molti si recarono nel Foro per ascoltare Cicerone: quel processo rappresentava un autentico punto di non ritorno nella vita della Repubblica. Era infatti presentato come un\u2019occasione imperdibile per la riaffermazione di una legalit\u00e0 ormai sempre pi\u00f9 disattesa.<\/span><\/p>\n<p class=\"has-text-align-justify has-black-color has-text-color\" style=\"text-align: justify;\">Per questi motivi molti a Roma guardavano con attenzione a questo processo: sapevano che la sentenza sarebbe stato un segnale. Positivo per molti derubati, bistrattati e ormai sfiduciati cittadini, negativo e d\u2019allarme per i potenti.\u00a0<\/p>\n<p class=\"has-text-align-justify has-black-color has-text-color\" style=\"text-align: justify;\">Quando Cicerone, pronunciando le pi\u00f9 violente invettive contro Verre si fa paladino del diritto a ottenere giustizia concesso dalla legge al nobile popolo di Sicilia angariato e ridotto all\u2019estrema rovina, quando tocca la corda del sentimento a favore dei poveri provinciali spogliati e oppressi, non bisogna lasciarsi commuovere. Ma Cicerone era un avvocato, e le accorate espressioni a lode e onore dei Siciliani non sono che le belle frasi di un grande oratore. Fra gli scopi del processo di Verre non \u00e8 dato scorgere quello che a noi parrebbe ovvio, ma che n\u00e9 a Cicerone n\u00e9 ai suoi compatrioti pass\u00f2 neppure per la mente: un miglioramento delle condizioni dei provinciali.<\/p>\n<p class=\"has-text-align-justify has-black-color has-text-color\" style=\"text-align: justify;\"><span style=\"color: var(--wp--preset--color--black); font-size: revert;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-56293 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2023\/05\/Roma_Marco_Tullio_Cicerone.jpg\" alt=\"\" width=\"194\" height=\"259\" \/>Il processo di Verre non produsse nessuna conseguenza per l\u2019amministrazione delle province. Semplicemente si inser\u00ec nel gioco degli interessi politici: serv\u00ec a Pompeo [6] che con la riforma giudiziaria registr\u00f2 un successo della sua politica; serv\u00ec all\u2019ordine equestre che, riconquistando la supremazia nei tribunali, ottenne ogni libert\u00e0 d\u2019azione nello sfruttamento delle province; serv\u00ec infine anche al senato che, condannando Verre, si salv\u00f2 almeno una partecipazione ai tribunali. In particolare, giov\u00f2 a Cicerone, nocque ad Ortensio, allontan\u00f2 per sempre Verre da ogni pubblico ufficio. Ma per i Siciliani tutto rest\u00f2 come prima, fatalmente peggio di prima.<\/span><\/p>\n<p class=\"has-text-align-justify has-black-color has-text-color\" style=\"text-align: justify;\">Nessun processo poteva sollevarli, nessuna legge giudiziaria poteva risolvere i problemi della loro isola. La causa della loro iattura aveva radici nel sistema stesso della amministrazione, che nessuno intendeva modificare perch\u00e9 si prestava troppo bene agli interessi di una societ\u00e0 cos\u00ec agitata da continui torbidi politici e tensioni sociali come quella romana alla fine della repubblica.<\/p>\n<p class=\"has-text-align-justify has-black-color has-text-color\" style=\"text-align: justify;\"><span style=\"color: var(--wp--preset--color--black); font-size: revert;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-58453 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2023\/05\/romani_patrizi_roma.jpeg\" alt=\"\" width=\"329\" height=\"220\" \/>Elevando Verre a \u00abparadigma del male\u00bb e intendendo colpire in lui il sistema di Silla, che a quel punto era gi\u00e0 andato in frantumi, l\u2019arpinate (Cicerone era nato ad Arpino) riusc\u00ec a porre le fondamenta della propria carriera politica. Non senza qualche punta di cinismo. Talch\u00e9 su Cicerone torna qui il giudizio \u00abpolitico\u00bb che ne diede Theodor Mommsen nella Storia di Roma antica (Sansoni): \u00abCome uomo di Stato, senza perspicacia, senza opinioni e senza fini, egli ha successivamente figurato come democratico, come aristocratico e come strumento dei monarchi, e non \u00e8 mai stato altro che un egoista di vista corta\u00bb. Quanto alla fattispecie del processo a Verre, scrive Fezzi, \u00abnella ricostruzione ciceroniana della \u201ccarriera criminale\u201d dell\u2019imputato, molto, a ben vedere, potrebbe essere messo in discussione\u00bb. E per quel che riguarda l\u2019operato di Verre in Sicilia, insiste Fezzi, \u00ab<\/span><em style=\"color: var(--wp--preset--color--black); font-size: revert;\">l\u2019impressione \u2013 in noi molto forte \u2013 \u00e8 che l\u2019indagine ciceroniana propriamente intesa abbia presto ceduto il passo all\u2019organizzazione e, forse, alla manipolazione delle prove<\/em><span style=\"color: var(--wp--preset--color--black); font-size: revert;\">\u00bb. [7]<\/span><\/p>\n<p class=\"has-text-align-justify has-black-color has-text-color\" style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-56295 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2023\/05\/Verrine_cover_cicerone.jpg\" alt=\"\" width=\"171\" height=\"295\" \/>Nelle Verrine sono palesate le ragioni della corruzione romana. Egli denunciava la corruttela nella politica, palesando ai cittadini romani che, chiunque volesse diventare un personaggio influente a Roma doveva passare per la carica di governatore locale, e le campagne elettorali richiedevano un impegno notevole di danaro; la tal cosa spingeva i contendenti ad indebitarsi e a costruire una fitta rete di clientele. La genesi del fenomeno corruttivo va, dunque, individuata nella cieca ambizione dell\u2019uomo, in particolare delle classi dirigenti, sempre pronte ad accettare qualunque turpe compromesso pur di assicurarsi un egoistico tornaconto. Un assunto, che, purtroppo, \u00e8 ancora di una straordinaria attualit\u00e0.<\/p>\n<p class=\"has-text-align-justify has-black-color has-text-color\" style=\"text-align: justify;\">Come a Roma, nel processo contro il governatore Verre, Cicerone invocava a gran voce una decisione che potesse essere da monito per i potenti e potesse gettare un segnale contro il fenomeno corruttivo, in Italia ancor oggi si chiede una posizione netta e decisa contro lo stesso fenomeno, perch\u00e9 se da un lato i pi\u00f9 si apprestino a dire che tanto si fa e si \u00e8 fatto, altri ribattono che le riforme, probabilmente mosse dalla fretta di placare l\u2019opinione pubblica, siano meri buchi nell\u2019acqua e non producano frutti concreti. Invero, esattamente come accade nelle Verrine, la decisione sulla corruzione \u00e8 una decisione culturale prima ancora che giuridica.<\/p>\n<p class=\"has-text-align-justify has-black-color has-text-color\" style=\"text-align: justify;\"><span style=\"color: var(--wp--preset--color--black); font-size: revert;\">L\u2019attualit\u00e0 dell\u2019\u201cAffaire Verre\u201d \u00e8 impressionante: nelle dinamiche politiche, come nell\u2019amministrazione della giustizia, nelle azioni di lobby, nell\u2019attivit\u00e0 dilatoria dei processi, nella corruzione, nel crimine organizzato.\u00a0<\/span><\/p>\n<p class=\"has-text-align-justify has-black-color has-text-color\" style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-41370 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/10\/corruzione_Anac_logo-300x168.jpg\" alt=\"\" width=\"312\" height=\"175\" \/>Pi\u00f9 che ieri, il testo che ci rimane sembra scritto oggi ed \u00e8 per l\u2019oggi che ricopre una grande importanza. Una storia dai risvolti, sociali, processuali, politici talmente attuali da fare capire che in duemila anni nulla abbiamo inventato e che costituisce un esempio assoluto di lotta contro il crimine.<\/p>\n<p class=\"has-text-align-justify has-black-color has-text-color\" style=\"text-align: justify;\">Non bastano, dunque, gli interventi tecnici, le riforme di diritto ma, \u00e8 necessaria una vera e propria \u201criforma etica\u201d per ristabilire una fiducia tra governati e governanti.\u00a0<\/p>\n<p class=\"has-text-align-justify has-black-color has-text-color\" style=\"text-align: justify;\">La questione non pu\u00f2 essere ridotta ad un mero intervento burocratico con provvedimenti di carattere legislativo ma bisogna piuttosto intervenire a monte, innescando una vera e propria rivoluzione delle coscienze. La stessa vicenda di Tangentopoli lo ha dimostrato: fare \u201cpiazza pulita\u201d non \u00e8 sufficiente se non si scende alla radice del problema, al fine di incentivare una vera e propria consapevolezza e capacit\u00e0 di opporsi e rifiutare un sistema corrotto.<\/p>\n<p class=\"has-text-align-justify has-black-color has-text-color\" style=\"text-align: justify;\">______________________________________<\/p>\n<p class=\"has-text-align-justify has-black-color has-text-color\" style=\"text-align: justify;\"><strong>[1]<\/strong> Si veda per un\u2019ampia trattazione sull\u2019argomento J. T. NOONAN JR., <em>Ungere le ruote. Storia della corruzione politica dal 3000 a.C. alla Rivoluzione francese<\/em>, Sugarco 1987.<\/p>\n<p class=\"has-text-align-justify has-black-color has-text-color\" style=\"text-align: justify;\"><strong>[2]<\/strong> Ci si riferisce in particolare alla commedia Aulularia, rappresentata verosimilmente la prima volta tra il 200 a.C. e il 191 a.C.<\/p>\n<p class=\"has-text-align-justify has-black-color has-text-color\" style=\"text-align: justify;\"><strong>[3]<\/strong> \u201cI ladri di beni privati passano la vita in carcere e in catene, quelli di beni pubblici nelle ricchezze e negli onori\u201d (Traduzione dell\u2019autore. Citato in A. GELLO, Noctes Atticae: liber III, Giardini, Pisa 1993, pag. 173).<\/p>\n<p class=\"has-text-align-justify has-black-color has-text-color\" style=\"text-align: justify;\"><strong>[4]<\/strong> Nel corso degli anni varie leggi ne avevano regolato il funzionamento, con un\u02bcalternanza tra provvedimenti di ispirazione popolare, come la lex repetundarum fatta approvare da Gaio Gracco nel 123-122 a.C. e la lex Servilia Glauciae del 101-100 a.C., e altri di natura filosenatoria, come la lex Cornelia iudiciaria emanata da Silla nell\u02bc81 a.C., che disciplin\u00f2 la composizione delle giurie delle quaestiones perpetuae estromettendo da esse i cavalieri e riservandole ai soli nobili<\/p>\n<p class=\"has-text-align-justify has-black-color has-text-color\" style=\"text-align: justify;\"><strong>[5]<\/strong> M. T. CICERONE, <em>In Verrem, Actio<\/em> prima I-3, traduzione di N. Marinone, in L. CANALI, M. C. CARDONA, Camena, Letteratura Latina, op.cit., pp. 193-194.<\/p>\n<p class=\"has-text-align-justify has-black-color has-text-color\" style=\"text-align: justify;\"><strong>[6]<\/strong> Appena giunto alle porte di Roma nel 71, Pompeo nel suo primo discorso elettorale aveva promesso, tra le acclamazioni della folla, la piena restaurazione del potere tribunizio e la riforma giudiziaria. Poche settimane dopo la sua elezione la lex Pompeia Licinia restituiva ai dieci magistrati popolari tutte le loro attribuzioni: il colpo era grave per il senato, che si vedeva sottoposto al beneplacito di una demagogia talora asservita all\u2019oro dei cavalieri o, peggio, alla forza militare dei generali vittoriosi. Per\u00f2 non fu che il primo di una serie di provvedimenti destinati in quello stesso anno 70 ad esautorare completamente l\u2019oligarchia della nobilt\u00e0 senatoriale. Poco dopo infatti il pretore Lucio Aurelio Cotta volle confermare la legge di Silla che comminava l\u2019ineleggibilit\u00e0 per dieci anni a chi avesse fatto ricorso alla corruzione elettorale. Se si considera che la maggior parte dei senatori ricorreva a questo sistema per ottenere i suffragi, diventachiaro il significato del provvedimento. Vennero inoltre rimessi in funzione i censori, che dall\u201983 non avevano pi\u00f9 adempiuto al loro ufficio e le conseguenze immediate furono una severa epurazione del senato e una accurata selezione dei cavalieri. L\u2019ordinamento di Silla era distrutto. I nobili si aggrappavano ancora alla amministrazione della giustizia come all\u2019unico importante privilegio che restava loro. Era questo il secondo cardine del programma enunciato da Pompeo, con cui egli intendeva legare sempre pi\u00f9 strettamente a s\u00e9 la classe dei cavalieri, i grandi capitalisti della repubblica. Quando propose in senato la legge sul potere tribunizio, l\u2019assemblea comprese che ben presto sarebbe sorta fatalmente anche l\u2019altra questione, pi\u00f9 scottante di tutte in quanto non ammetteva nessun ripiego. Del resto parecchi tra i senatori si sentivano la coscienza sporca: per molti anni esercitando le funzioni di giudici avevano protetto quelli della loro casta e venduto le assoluzioni ai colpevoli di crimini manifesti. Nel clima di rinnovamento creato dalla iniziative di Pompeo la riforma dei tribunali divenne l\u2019argomento del giorno. Mancava solo un fatto nuovo per far precipitare la situazione critica a cui si era ridotta l\u2019intransigenza del senato, un grosso scandalo che polarizzasse l\u2019attenzione delle masse sul problema, e questo fu il processo di Verre.<\/p>\n<p class=\"has-text-align-justify has-black-color has-text-color\" style=\"text-align: justify;\"><strong>[7]<\/strong> P. Mieli, <em>Il cinismo di Cicerone<\/em>, Corriere della Sera, 2 febbraio 2016<\/p>\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Abstract: corruzione, un male antico. Correva l\u2019anno 70 a.C. ai primi di gennaio, un giovane avvocato dell\u2019Urbe di nome Marco Tullio Cicerone, presenta al pretore Manlio Acilio Glabrione, presidente del tribunale per i reati di concussione, una richiesta formale di accusa contro Gaio Verre, governatore di Roma nella provincia di Sicilia per tre anni.<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/corruzione-un-male-antico\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,24],"tags":[2957,180,162],"class_list":["post-56278","post","type-post","status-publish","format-standard","hentry","category-diritto","category-storia","tag-cicerone","tag-diritto-2","tag-storia-2","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Corruzione, un male antico - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Corruzione, un male antico. Nel caso di Cicerone contro Verre impressiona l&#039;attualit\u00e0 delle dinamiche politiche e l&#039;azione delle lobby\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/corruzione-un-male-antico\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Corruzione, un male antico - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Corruzione, un male antico. Nel caso di Cicerone contro Verre impressiona l&#039;attualit\u00e0 delle dinamiche politiche e l&#039;azione delle lobby\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/corruzione-un-male-antico\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-03T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-28T12:16:40+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/senato-romano.jpg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"20 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/corruzione-un-male-antico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/corruzione-un-male-antico\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Corruzione, un male antico\",\"datePublished\":\"2023-05-03T22:00:00+00:00\",\"dateModified\":\"2023-12-28T12:16:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/corruzione-un-male-antico\\\/\"},\"wordCount\":3247,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/corruzione-un-male-antico\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/07\\\/senato-romano.jpg\",\"keywords\":[\"Cicerone\",\"diritto\",\"storia\"],\"articleSection\":[\"Diritto\",\"Storia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/corruzione-un-male-antico\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/corruzione-un-male-antico\\\/\",\"name\":\"Corruzione, un male antico - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/corruzione-un-male-antico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/corruzione-un-male-antico\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/07\\\/senato-romano.jpg\",\"datePublished\":\"2023-05-03T22:00:00+00:00\",\"dateModified\":\"2023-12-28T12:16:40+00:00\",\"description\":\"Corruzione, un male antico. Nel caso di Cicerone contro Verre impressiona l'attualit\u00e0 delle dinamiche politiche e l'azione delle lobby\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/corruzione-un-male-antico\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/corruzione-un-male-antico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/corruzione-un-male-antico\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/07\\\/senato-romano.jpg\",\"contentUrl\":\"http:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/07\\\/senato-romano.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/corruzione-un-male-antico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Corruzione, un male antico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Corruzione, un male antico - Rassegna Stampa Cattolica","description":"Corruzione, un male antico. Nel caso di Cicerone contro Verre impressiona l'attualit\u00e0 delle dinamiche politiche e l'azione delle lobby","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/corruzione-un-male-antico\/","og_locale":"it_IT","og_type":"article","og_title":"Corruzione, un male antico - Rassegna Stampa Cattolica","og_description":"Corruzione, un male antico. Nel caso di Cicerone contro Verre impressiona l'attualit\u00e0 delle dinamiche politiche e l'azione delle lobby","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/corruzione-un-male-antico\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2023-05-03T22:00:00+00:00","article_modified_time":"2023-12-28T12:16:40+00:00","og_image":[{"url":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/senato-romano.jpg","type":"","width":"","height":""}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"20 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/corruzione-un-male-antico\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/corruzione-un-male-antico\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Corruzione, un male antico","datePublished":"2023-05-03T22:00:00+00:00","dateModified":"2023-12-28T12:16:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/corruzione-un-male-antico\/"},"wordCount":3247,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/corruzione-un-male-antico\/#primaryimage"},"thumbnailUrl":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/senato-romano.jpg","keywords":["Cicerone","diritto","storia"],"articleSection":["Diritto","Storia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/corruzione-un-male-antico\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/corruzione-un-male-antico\/","name":"Corruzione, un male antico - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/corruzione-un-male-antico\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/corruzione-un-male-antico\/#primaryimage"},"thumbnailUrl":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/senato-romano.jpg","datePublished":"2023-05-03T22:00:00+00:00","dateModified":"2023-12-28T12:16:40+00:00","description":"Corruzione, un male antico. Nel caso di Cicerone contro Verre impressiona l'attualit\u00e0 delle dinamiche politiche e l'azione delle lobby","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/corruzione-un-male-antico\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/corruzione-un-male-antico\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/corruzione-un-male-antico\/#primaryimage","url":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/senato-romano.jpg","contentUrl":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/senato-romano.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/corruzione-un-male-antico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Corruzione, un male antico"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/56278","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=56278"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/56278\/revisions"}],"predecessor-version":[{"id":58454,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/56278\/revisions\/58454"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=56278"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=56278"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=56278"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}