{"id":56086,"date":"2023-03-30T00:00:56","date_gmt":"2023-03-29T22:00:56","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=56086"},"modified":"2024-01-07T15:12:05","modified_gmt":"2024-01-07T14:12:05","slug":"islam-alla-conquista-delle-nostre-anime","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/islam-alla-conquista-delle-nostre-anime\/","title":{"rendered":"Islam alla conquista delle nostre anime"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-28968 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/02\/islam_in_Europa-300x159.jpg\" alt=\"\" width=\"319\" height=\"169\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/02\/islam_in_Europa-300x159.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/02\/islam_in_Europa.jpg 308w\" sizes=\"auto, (max-width: 319px) 100vw, 319px\" \/><span style=\"color: #000000;\">Abstract: <\/span><\/strong><span style=\"color: #000000;\"><em>islam alla conquista delle nostre anime. L\u2019Occidente prosegue nel suo declino mentre i fedeli di Allah continuano ad avanzare e a sottomettere l\u2019Europa. Che non pu\u00f2 far convivere due religioni. Una dovr\u00e0 soccombere e sar\u00e0 quella pi\u00f9 vecchia: il cristianesimo. Lo impone la legge della biologia.<\/em><\/span><\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: center;\"><strong><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/www.laverita.info\/\" target=\"_blank\" rel=\"noopener\">La Verit\u00e0<\/a><\/span><\/strong> <span style=\"color: #000000;\">marted\u00ec 21 Marzo 2023<\/span><\/p>\n<h3 style=\"text-align: center;\">L\u2019islam ci conquista vincendo le nostre anime<\/h3>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><em>L\u2019Occidente prosegue nel suo declino mentre i fedeli di Allah continuano ad avanzare e a sottomettere l\u2019Europa. Che non pu\u00f2 far convivere due religioni. Una dovr\u00e0 soccombere e sar\u00e0 quella pi\u00f9 vecchia: il cristianesimo. Lo impone la legge della biologia. <\/em><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\">di <strong>Boualem Sansal<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-56087 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2023\/03\/meotti_cover.jpg\" alt=\"\" width=\"219\" height=\"316\" \/><span style=\"color: #000000;\">Pubblichaiamo la prefazione di Boualem Sansal al libro di Giulio Meotti <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/www.edizionicantagalli.com\/shop\/la-dolce-conquista\/\" target=\"_blank\" rel=\"noopener\"><em>La dolce conquista. L\u2019Europa si arrende all\u2019islam<\/em> <\/a><\/span>(Cantagalli editore 22 euro, in libreria il 24 Marzo), che racconta il \u00abprogetto\u00bb di conquista dell\u2019Occidente organizzato dai regimi islamici ai danni dell\u2019Europa. Meotti \u00e8 un giornalista de <em>Il Foglio<\/em> dal 2003. Ha scritto quattro libri su Israele, tradotti in pi\u00f9 lingue, e si occupa spesso anche nei suoi articoli di medio Oriente, antisemitismo e situazione degli ebrei in Europa e nel mondo<\/span><\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Noi \u00ablanciatori d\u2019allerta\u00bb, che da decenni mettiamo in guardia contro i pericoli dell\u2019islam politico non solo i nostri compatrioti ma tutti i popoli della terra,dovremo infine prendere atto\u00a0 della nostra incapacit\u00e0 di destare le persone, smettere di suonare le campane a martello e finirla \u00a0con l\u2019importunarle. Il cittadino medio non se ne accorge ma, ma la realt\u00e0 di fondo \u00e8 questa: l\u2019islamismo sta colonizzando il mondo e procede a balzi dalla periferia al centro [\u2026]<\/span><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-51675 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/06\/Francia_Islam_Europa.jpg\" alt=\"\" width=\"190\" height=\"266\" \/><span style=\"color: #000000;\">Il nostro attivismo donchisciottesco \u00e8 chiaramente un combattimento condotto dalle retrovie, lo riconosco. Come abbiamo potuto pensare che saremmo riusciti a persuadere le persone a contrastare insieme il progetto messianico dei servi di Allah? Non c\u2019\u00e8 un profeta, nessuno in grado di risvegliare le coscienze. Mentre ne sono circondate, abituate fin dall\u2019infanzia a vedere il blu ovunque, le persone libere, come se ne possono ancora trovare nell\u2019emisfero settentrionale, cantano, ballano e giurano che domani andr\u00e0 meglio.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Ridono di noi, del nostro lamentarsi, delle nostre pur fondate previsioni, e ci negano persino il diritto fraterno di preoccuparci\u00a0 per loro, per i loro figli, per il loro Paese; giurano di non avere nessun problema con i musulmani, cosa che ben sappiamo essere vera e per la quale ci congratuliamo con loro; ma bisogna anche andare a vedere se vale il viceversa, perch\u00e9 la maggior parte dei musulmani non ha ancora ufficialmente rotto con la sharia, che continua ancora oggi, in questo XXI secolo di presunto globalismo, a obbligarli con tutta la sua forza.<\/span><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-51649 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/06\/Francia_Islam_europa-300x200.jpg\" alt=\"\" width=\"324\" height=\"216\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/06\/Francia_Islam_europa-300x200.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/06\/Francia_Islam_europa-768x512.jpg 768w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/06\/Francia_Islam_europa-1024x682.jpg 1024w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/06\/Francia_Islam_europa.jpg 1280w\" sizes=\"auto, (max-width: 324px) 100vw, 324px\" \/><span style=\"color: #000000;\">Felice, la gente afferma con orgoglio che l\u2019islamismo non pu\u00f2 fare nulla contro di loro, che sono intelligenti e brillanti, che la loro democrazia laica li protegge dalle dannose intromissioni religiose e ideologiche , che i loro paesi sono potenti, che le loro societ\u00e0 sono immuni e che sono in grado di accogliere e integrare anche il pi\u00f9 rica\u00f2lcitrante dei credenti.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Come argomento chiave ci ricordano che la Germania di <strong>Angela Merkel<\/strong> ha accolto un milione di migranti siriani in poche settimane, senza problemi, Ha dato loro conforto, li ha formati, ha concesso loro la cittadinanza e li ha mandati a lavorare nelle sue fabbriche, nella quali si trasformeranno in perfetti tedeschi, disciplinati e produttivi. Hanno dimenticato ci\u00f2 che \u00e8 stato loro ripetuto per anni, oppure lo hanno udito ma non compreso, e cio\u00e8 che l\u2019islamismo agisce apertamente solo quando \u00e8 ben radicato nel Paese, quando ha sedato la diffidenza del popolo, sedotto gli ingenui, arruolato i fondamentalisti islamici e gli utili idioti, quando si \u00e8 infiltrato nelle universit\u00e0. Nei club sportivi, negli ambienti degli artisti intrisi di wokismo, quando ha istaurato una fiorente economia halal, preso il controllo dei grandi traffici e persuaso la classe dirigente che non c\u2019\u00e8 futuro per essa senza la benedizione di Allah e dei suoi rappresentanti<\/span>.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-42581 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/03\/Islam_Europa-300x196.jpg\" alt=\"\" width=\"343\" height=\"224\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/03\/Islam_Europa-300x196.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/03\/Islam_Europa-768x501.jpg 768w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/03\/Islam_Europa-1024x668.jpg 1024w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/03\/Islam_Europa.jpg 2000w\" sizes=\"auto, (max-width: 343px) 100vw, 343px\" \/><span style=\"color: #000000;\">Si sono dimenticati, inoltre, che l\u2019islam ha una vocazione universale, che le sue \u00e9lite costituiscono una fratellanza planetaria molto pi\u00f9 potente di tutte le altre fratellanze umane messe insieme [\u2026] Non ha scheletro, forma o cervello, solo tentacoli che si agitano in tutte le direzioni. [\u2026] L\u2019islamismo \u00e8 stato creato dai grandi conquistatori musulmani dei primi secoli per far trionfare la religione di Allah, non per mandarla in rovina tra miserabili miscredenti. In verit\u00e0, l\u2019islam vince sempre, perch\u00e9 viene a conquistare ci\u00f2 che nessuno protegge, ci\u00f2 che nessuno difende, nemmeno i diretti interessati: l\u2019anima delle persone, in primo luogo quelle che non sanno di averne una e quelle che credono che essa appartenga solo a Dio.<\/span><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-38395 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/09\/islam_Europa.jpg\" alt=\"\" width=\"318\" height=\"206\" \/><span style=\"color: #000000;\">Gli altri seguiranno, per codardia, opportunismo, wokismo. Quando poi, sfortunatamente per loro e per noi, essi si imbattono nella realt\u00e0, quando il sangue scorre e le teste rotolano, accusano noi \u00ablanciatori d\u2019allerta\u00bb di aver sconvolto i musulmani con i nostri discorsi , di averli stigmatizzati e di aver spinto i pi\u00f9 fragili a radicalizzarsi.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Loro, invece, sanno bene che i primi a soffrire a causa degli islamisti e dei loro <em>missi dominici<\/em>, dei dhimmi di ieri e dei fondamentalisti di oggi sono proprio i musulmani . \u00abIn Francia salutiamo coloro che appiccano i roghi e perseguitiamo coloro che suonano la campana a martello\u00bb, diceva <strong>Nicolas de Chamfort,<\/strong> giornalista moralista francese del XVIII secolo, spesso citato da <strong>Eric Zammour,<\/strong> giornalista polemista e re dei suonatori di campana a martello in Francia.<\/span><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-53348 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/01\/germania_islam_europa-300x150.jpg\" alt=\"\" width=\"346\" height=\"173\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/01\/germania_islam_europa-300x150.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/01\/germania_islam_europa.jpg 308w\" sizes=\"auto, (max-width: 346px) 100vw, 346px\" \/><span style=\"color: #000000;\">Quanto a stigma, lui, ebreo, algerino, ne sa qualcosa, gli hanno appiccicato addosso qualunque cosa perch\u00e9 gli ingenui possano accorgersi con chi hanno a che fare: un paio di corna in testa, zoccoli al posto dei piedi, una coda appuntita che parte dal fondoschiena e un tridente in mano. Per convincerli una volta per tutte, dovranno spingere fino in fondo la loro logica e bruciarlo sulla pubblica piazza.<\/span><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-42707 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/04\/moschea_Roma_islam-300x225.jpg\" alt=\"\" width=\"324\" height=\"243\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/04\/moschea_Roma_islam-300x225.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/04\/moschea_Roma_islam-768x576.jpg 768w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/04\/moschea_Roma_islam-1024x768.jpg 1024w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/04\/moschea_Roma_islam.jpg 1100w\" sizes=\"auto, (max-width: 324px) 100vw, 324px\" \/>Che fare? La battaglia \u00e8 persa? <span style=\"color: #000000;\">Dobbiamo venir meno al nostro dovere e accontentarci del conforto dell\u2019indifferenza? A quale prezzo? Ci sono altre possibilit\u00e0, pi\u00f9 vili, come imparare a tradire e a monetizzare la nostra complicit\u00e0; dopotutto la causa degli islamisti e dei fondamentalisti islamici \u00e8 onorevole se sei un islamista o i fondamentalista islamico e se vuoi recare danno a coloro che la legge islamica \u2013 a meno di accettare l\u2019eventuale pentimenti \u2013 ha gi\u00e0 irrimediabilmente condannato: cristiani, ebrei, atei, apostati, bestemmiatori, sodomiti, adulteri, ecc., ecc., l\u2019elenco \u00e8 lungo<\/span>.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Si pu\u00f2 anche cambiare Paese, ma dove andare senza correre il rischio di vedere un giorno l\u2019islamismo sbarcare anche l\u00ec? A parte la Corea del Nord, dove non pu\u00f2 entrare nemmeno una mosca sperando di uscirne viva, e il Giappone, che tiene a distanza di sicurezza tutti gli stranieri, non vedo altra possibilit\u00e0. Quella laggi\u00f9 \u00e8 l\u2019Asia: un mondo di popoli ostinati con il senso dell\u2019eternit\u00e0 e che nessuna moda \u2013 che in Europa va e viene come le onde dell\u2019oceano , e finisce per rovinare tutto ci\u00f2 che incontra sul proprio cammino \u2013 ha potuto sviare<\/span>.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-55796 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2023\/03\/islam_donne_burka_Afghanistan-300x168.jpg\" alt=\"\" width=\"350\" height=\"196\" \/><span style=\"color: #000000;\">Non hanno conosciuto n\u00e9 i ruggenti anni Venti, n\u00e9 la moda hippy, n\u00e9 la moda y\u00e9y\u00e8, n\u00e9 la moda woke e non conosceranno la moda che sta arrivando ora, che chiameremo \u00abbaby\u00bb, quando ci si divertir\u00e0 a fabbricare bambini come si coltivano i cavoli, in terreni presi in affitto situati all\u2019altro capo del mondo e che, una volta pronti, saranno recapitati tramite corriere espresso ai loro nuovi genitori.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">La vecchia Europa prosegue nel suo declino e continua a coprirsi di ridicolo. essa si trova di fronte a un problema insolubile: culla della civilt\u00e0 occidentale, credeva <img loading=\"lazy\" decoding=\"async\" class=\" wp-image-48935 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/10\/islam.png\" alt=\"\" width=\"332\" height=\"221\" \/>di aver chiuso con le religioni o, quantomeno, si era convinta di aver istaurato\u00a0 con esse un modus vivendi che garantisse a tutti la libert\u00e0 di coscienza all\u2019interno di una convivenza laica ed indolore. Noi abitanti di questo calamitoso XXI secolo, abbiamo il terribile privilegio di essere testimoni attoniti del declino di una grande civilt\u00e0, senza dubbio la pi\u00f9 feconda della storia dell\u2019umanit\u00e0, quella occidentale. Abbiamo individuato mille cause della sua rovina, tra le pi\u00f9 decisive c\u2019\u00e8 l\u2019invecchiamento della sua popolazione e la concorrenza spietata dei nuovi leader mondiali<\/span>.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Ma c\u2019\u00e8 un\u2019altra spiegazione, pi\u00f9 radicale, che non si pu\u00f2 indicare apertamente , ossia l\u2019incontro con l\u2019islam del VII secolo, in Medio Oriente. Lo shock fu violento e decisivo, sono seguiti secoli di conflitti per i territori e per la legittimit\u00e0 davanti a Dio e agli uomini. Flussi e riflussi: l\u2019islam ha cacciati il cristianesimo dal Medio Oriente, dal Nord Africa, dalla Spagna, da Bisanzio e da molti territori del Sacro romano impero e nel frattempo ha sottoposto gli ebrei alla dhimma o li ha spinti a disperdersi in tutto il mondo. In seguito, le potenze europee coalizzate, che avevano perso tutte le Crociate, a partire dal XVI secolo sono riuscite a riconquistare la Spagna, il Nord Africa e il medio oriente; l\u2019abolizione del califfato ottomano\u00a0 nel 1924 ha segnato la fine della dominazione musulmana e il declino della sua civilt\u00e0<\/span><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-48949 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/10\/islam_corano-300x169.jpg\" alt=\"\" width=\"346\" height=\"195\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/10\/islam_corano-300x169.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/10\/islam_corano-768x432.jpg 768w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/10\/islam_corano-1024x576.jpg 1024w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/10\/islam_corano.jpg 1280w\" sizes=\"auto, (max-width: 346px) 100vw, 346px\" \/><span style=\"color: #000000;\">Ma, lungi dallo scomparire, l\u2019islam ha ripreso subito l\u2019iniziativa, ha liberato le sue terre dalla colonizzazione e ha iniziato una nuova conquista dell\u2019Europa. E\u2019 una legge della biologia: come non si possono mettere due galli in un pollaio, cos\u00ec non si possono far convivere\u00a0 due racconti delle origini dell\u2019umanit\u00e0; la terra non \u00e8 grande abbastanza per ospitare due Verit\u00e0, due religioni, entrambe dedicate allo stesso unico Dio. Una delle due dovr\u00e0 farsi da parte. Ovviamente sar\u00e0 quella pi\u00f9 vecchia, perch\u00e9 ci\u00f2 impone la legge della biologia.<\/span><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-48827 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/10\/Francia_Islam-2-300x169.jpg\" alt=\"\" width=\"378\" height=\"213\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/10\/Francia_Islam-2-300x169.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/10\/Francia_Islam-2-768x432.jpg 768w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/10\/Francia_Islam-2-1024x576.jpg 1024w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/10\/Francia_Islam-2.jpg 1920w\" sizes=\"auto, (max-width: 378px) 100vw, 378px\" \/><span style=\"color: #000000;\">Ed ecco che questo Occidente cristiano, che appariva invincibile e proiettava\u00a0 con fierezza il proprio futuro nella conquista dello spazio e dell\u2019onnipotente universo del digitale, si sta disfacendo davanti ai nostri occhi\u00a0 sgomenti; non \u00e8 altro che un vecchio corpo flaccido che la furia degli eventi sballotta di qua e di l\u00e0. Sono sempre meno coloro che ritengono che rester\u00e0 ancora a lungo il leader mondiale che \u00e8 sempre stato fin dal medioevo. Il suo tempo sarebbe scaduto, i \u00ablanciatori d\u2019allerta\u00bb lo ripetono ogni giorno pi\u00f9 forte<\/span>.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>Giulio Meotti<\/strong> presenta un contributo decisivo davanti al tribunale della storia. Descrive una realt\u00e0 che fa rabbrividire. Ci parla della moschea pi\u00f9 grande <img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-37621 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/05\/Islam.jpg\" alt=\"\" width=\"243\" height=\"293\" \/>d\u2019Europa costruita a Roma, cuore della cristianit\u00e0, dall\u2019Arabia, cuore dell\u2019Islam; ci parla della grande moschea di Colonia, che l\u2019amministrazione comunale ha appena autorizzato a schierare muezzin per chiamare i fedeli alla preghiera; ci parla di Malm\u00f6 in Svezia, dove l\u2019islamismo regna indisturbato; ci parla di Amsterdam e del suo spirito woke che \u00e8 arrivato al punto di tagliare dall\u2019<em>Inferno<\/em> di Dante un passaggio su <strong>Maometto<\/strong> ritenuto offensivo per i musulmani; ci parla di Parigi e del \u00abcane dell\u2019inferno\u00bb decapitato da un islamista; ci parla di Londra, dove \u00e8 piacevole vivere\u00a0 quando sei un islamista duro e puro; ci parla di Bruxelles, capitare d\u2019Europa e centro di smistamento dei Fratelli musulmani e di altri attivisti<\/span>.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Riuscir\u00e0 il suo reportage a mutare lo sguardo degli ingenui, affascinati come sono dai discorsi civettuoli degli islamisti e della sinistra islamista? Scommetto di no. [\u2026] Il suo racconto susciter\u00e0 la curiosit\u00e0 delle autorit\u00e0 pubbliche? Scommetto di no, hanno tante altre cose da fare. [\u2026]L\u2019islam politico e rivoluzionario pu\u00f2 attendere<\/span>.<\/p>\n<p>____________________________________<\/p>\n<p><span style=\"color: #000000;\"><strong>Si legga anche:<\/strong><\/span><\/p>\n<p><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lislam-ha-conquistato-anche-i-libri-di-scuola\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">L\u2019Islam ha conquistato anche i libri di scuola<\/span><\/a><\/p>\n<p><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/alla-conquista-delloccidente\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">Alla conquista dell\u2019Occidente<\/span><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Abstract: islam alla conquista delle nostre anime. L\u2019Occidente prosegue nel suo declino mentre i fedeli di Allah continuano ad avanzare e a sottomettere l\u2019Europa. Che non pu\u00f2 far convivere due religioni. Una dovr\u00e0 soccombere e sar\u00e0 quella pi\u00f9 vecchia: il cristianesimo. Lo impone la legge della biologia.<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/islam-alla-conquista-delle-nostre-anime\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":28968,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16,111],"tags":[2837,161,2408],"class_list":["post-56086","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-islam","category-islam-in-europa","tag-crisi-delloccidente","tag-islam-2","tag-islam-in-europa","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Islam alla conquista delle nostre anime - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Islam alla conquista delle nostre anime. L\u2019Occidente \u00e8 in declino mentre i fedeli di Allah continuano ad avanzare e a sottomettere\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/islam-alla-conquista-delle-nostre-anime\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Islam alla conquista delle nostre anime - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Islam alla conquista delle nostre anime. L\u2019Occidente \u00e8 in declino mentre i fedeli di Allah continuano ad avanzare e a sottomettere\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/islam-alla-conquista-delle-nostre-anime\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-29T22:00:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-07T14:12:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/02\/islam_in_Europa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"308\" \/>\n\t<meta property=\"og:image:height\" content=\"164\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"13 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/islam-alla-conquista-delle-nostre-anime\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/islam-alla-conquista-delle-nostre-anime\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Islam alla conquista delle nostre anime\",\"datePublished\":\"2023-03-29T22:00:56+00:00\",\"dateModified\":\"2024-01-07T14:12:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/islam-alla-conquista-delle-nostre-anime\\\/\"},\"wordCount\":1871,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/islam-alla-conquista-delle-nostre-anime\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2006\\\/02\\\/islam_in_Europa.jpg\",\"keywords\":[\"crisi dell&#039;Occidente\",\"islam\",\"Islam in Europa\"],\"articleSection\":[\"Islam\",\"Islam in Europa\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/islam-alla-conquista-delle-nostre-anime\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/islam-alla-conquista-delle-nostre-anime\\\/\",\"name\":\"Islam alla conquista delle nostre anime - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/islam-alla-conquista-delle-nostre-anime\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/islam-alla-conquista-delle-nostre-anime\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2006\\\/02\\\/islam_in_Europa.jpg\",\"datePublished\":\"2023-03-29T22:00:56+00:00\",\"dateModified\":\"2024-01-07T14:12:05+00:00\",\"description\":\"Islam alla conquista delle nostre anime. L\u2019Occidente \u00e8 in declino mentre i fedeli di Allah continuano ad avanzare e a sottomettere\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/islam-alla-conquista-delle-nostre-anime\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/islam-alla-conquista-delle-nostre-anime\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/islam-alla-conquista-delle-nostre-anime\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2006\\\/02\\\/islam_in_Europa.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2006\\\/02\\\/islam_in_Europa.jpg\",\"width\":308,\"height\":164},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/islam-alla-conquista-delle-nostre-anime\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Islam alla conquista delle nostre anime\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Islam alla conquista delle nostre anime - Rassegna Stampa Cattolica","description":"Islam alla conquista delle nostre anime. L\u2019Occidente \u00e8 in declino mentre i fedeli di Allah continuano ad avanzare e a sottomettere","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/islam-alla-conquista-delle-nostre-anime\/","og_locale":"it_IT","og_type":"article","og_title":"Islam alla conquista delle nostre anime - Rassegna Stampa Cattolica","og_description":"Islam alla conquista delle nostre anime. L\u2019Occidente \u00e8 in declino mentre i fedeli di Allah continuano ad avanzare e a sottomettere","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/islam-alla-conquista-delle-nostre-anime\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2023-03-29T22:00:56+00:00","article_modified_time":"2024-01-07T14:12:05+00:00","og_image":[{"width":308,"height":164,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/02\/islam_in_Europa.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"13 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/islam-alla-conquista-delle-nostre-anime\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/islam-alla-conquista-delle-nostre-anime\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Islam alla conquista delle nostre anime","datePublished":"2023-03-29T22:00:56+00:00","dateModified":"2024-01-07T14:12:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/islam-alla-conquista-delle-nostre-anime\/"},"wordCount":1871,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/islam-alla-conquista-delle-nostre-anime\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/02\/islam_in_Europa.jpg","keywords":["crisi dell&#039;Occidente","islam","Islam in Europa"],"articleSection":["Islam","Islam in Europa"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/islam-alla-conquista-delle-nostre-anime\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/islam-alla-conquista-delle-nostre-anime\/","name":"Islam alla conquista delle nostre anime - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/islam-alla-conquista-delle-nostre-anime\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/islam-alla-conquista-delle-nostre-anime\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/02\/islam_in_Europa.jpg","datePublished":"2023-03-29T22:00:56+00:00","dateModified":"2024-01-07T14:12:05+00:00","description":"Islam alla conquista delle nostre anime. L\u2019Occidente \u00e8 in declino mentre i fedeli di Allah continuano ad avanzare e a sottomettere","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/islam-alla-conquista-delle-nostre-anime\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/islam-alla-conquista-delle-nostre-anime\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/islam-alla-conquista-delle-nostre-anime\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/02\/islam_in_Europa.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/02\/islam_in_Europa.jpg","width":308,"height":164},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/islam-alla-conquista-delle-nostre-anime\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Islam alla conquista delle nostre anime"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/56086","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=56086"}],"version-history":[{"count":3,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/56086\/revisions"}],"predecessor-version":[{"id":58970,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/56086\/revisions\/58970"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/28968"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=56086"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=56086"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=56086"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}