{"id":54978,"date":"2022-11-03T00:00:06","date_gmt":"2022-11-02T23:00:06","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=54978"},"modified":"2024-02-14T17:15:18","modified_gmt":"2024-02-14T16:15:18","slug":"la-tragedia-del-libano-un-paese-che-muore","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-tragedia-del-libano-un-paese-che-muore\/","title":{"rendered":"La tragedia del Libano, un paese che muore"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-46832 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/04\/libano-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/04\/libano-300x200.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/04\/libano-768x513.jpg 768w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/04\/libano-1024x684.jpg 1024w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/04\/libano.jpg 1445w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><span style=\"color: #000000;\">Abstract: <\/span><\/strong><span style=\"color: #000000;\"><em>la tragedia del Libano, un paese che muore. Una serie di corrispondenze dal Paese dei Cedri, ridotto allo stremo dalle sanzioni, dalla devastante esplosione che ha devastato il porto e parte della capitale e ancora una volta sull&#8217;orlo della guerra civile con gran parte della popolazione ridotta in povert\u00e0 e dove si muore anche per le malattie pi\u00f9 banali<\/em><\/span><\/span><\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\"><strong><a href=\"https:\/\/www.tempi.it\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">Tempi<\/span><\/a><\/strong><a href=\"https:\/\/www.tempi.it\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #000000;\">26 <\/span><\/a>Ottobre 2022<\/span><\/p>\n<h3 style=\"text-align: center;\">Reportage dal Libano,<\/h3>\n<h3 style=\"text-align: center;\">il paese che non ha pane per vivere<\/h3>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><em>Elettricit\u00e0 solo due ore al giorno, molti mendicanti, tanta disperazione. Parlano mons. Jules Boutros e il deputato Mehlem Khalaf <\/em><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\">di <strong>Rodolfo Casadei<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><em><span style=\"color: #000000;\">Grazie al sostegno di Orizzonti e di Romagna Solidale l\u2019inviato di Tempi Rodolfo Casadei si trova in Libano. Qui trovate la prima delle sue corrispondenze per il sito, che lasciamo aperta alla lettura anche dei non abbonati. Il reportage completo potr\u00e0 essere letto sul prossimo numero di<\/span> <a href=\"https:\/\/www.tempi.it\/hai-visto-che-tempi-abbonamento\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong><span style=\"color: #0000ff;\">Tempi mensile<\/span><\/strong><\/a> <\/em><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>Beirut<\/strong> \u2013 \u00c8 una strana povert\u00e0 quella del<\/span> <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/www.tempi.it\/?s=libano\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Libano<\/strong> <\/a><\/span><span style=\"color: #000000;\">entrato nel terzo anno di una crisi sistemica che investe finanza, economia e politica. Le statistiche raccontano <img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-51296 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/06\/Lira_Libano_moneta-300x138.jpg\" alt=\"\" width=\"300\" height=\"138\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/06\/Lira_Libano_moneta-300x138.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/06\/Lira_Libano_moneta-768x354.jpg 768w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/06\/Lira_Libano_moneta-1024x473.jpg 1024w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/06\/Lira_Libano_moneta.jpg 2000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>un paese dove nel giro di due anni la popolazione in condizioni di povert\u00e0 relativa \u00e8 passata dal 40 all\u201980 per cento, dove a causa dell\u2019iperinflazione che ha portato via il 95 per cento del suo valore alla moneta nazionale met\u00e0 delle persone che lavorano ora devono accontentarsi di stipendi equivalenti a 36-90 dollari al mese, mentre le banche ostacolano in tutti i modi i prelievi dei risparmi dai conti correnti bancari, dove i carburanti costano sedici volte di pi\u00f9 di due anni fa, e il gas per la casa 40 volte in pi\u00f9.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"> Eppure chi arriva a Beirut di sera incontra il solito traffico caotico e senza tregua che la accomuna alle altre capitali mediorientali, e migliaia di finestre illuminate, per non parlare dei pannelli giganti della pubblicit\u00e0. Basta per\u00f2 scendere dall\u2019automobile e fare due passi per le vie di qualsiasi quartiere, o sdraiarsi sul letto della propria stanza in qualunque struttura di ospitalit\u00e0, per udire ovunque un ronzio sordo e ininterrotto: quello dei generatori diesel di quartiere, pagati dai privati cittadini a privati gestori, per avere quelle ore di corrente elettrica che normalmente vanno dalle 6.30 della mattina a mezzanotte. Perch\u00e9 la Societ\u00e0 elettrica nazionale non garantisce pi\u00f9 che una-due ore al giorno di energia dalla rete, e subito fuori Beirut nemmeno quella.<\/span><\/p>\n<h4 style=\"text-align: center;\"><span style=\"color: #000000;\"><strong>Appena fuori dal ristorante<\/strong><\/span><\/h4>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-53473 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/02\/Libano-300x168.jpg\" alt=\"\" width=\"300\" height=\"168\" \/>Se si entra nel quartiere cristiano di Gemmaizeh, famoso per il mix architettonico, le botteghe artigiane e i locali di tendenza, si resta colpiti dalla vivacit\u00e0 della vita notturna, fra le vetrine ben illuminate e ben fornite e auto di passaggio di ogni cilindrata; si notano locali molto frequentati o addirittura senza tavoli liberi. Ma basta avvicinarsi, osservare i frequentatori, ascoltare i loro discorsi che passano senza soluzione di continuit\u00e0 dall\u2019inglese all\u2019arabo al francese, per rendersi conto che si tratta nella grande maggioranza di espatriati (operatori di Ong, turisti, studenti stranieri) o di libanesi della diaspora, che fanno la spola fra l\u2019Europa e il Libano.\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"> <img loading=\"lazy\" decoding=\"async\" class=\" wp-image-53451 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/01\/Libano_baracche_poveri-300x168.jpg\" alt=\"\" width=\"311\" height=\"174\" \/>Basta uscire dal ristorante e ci si imbatte nei mendicanti che non sono pi\u00f9 rappresentati solo dai profughi siriani (fra un milione e un milione e mezzo, specialisti degli incroci con semaforo e dei cavalcavia, sotto i quali si sistemano anche con pile di materassi che vengono sparpagliati a terra la sera) o da invalidi civili locali, ma da quella signora cinquantenne, pantaloni e decente maglia a maniche corte, che fuori da una trattoria cerca di raccontare le disgrazie sanitarie della sua famiglia e chiede un\u2019offerta in denaro a chi ha appena cenato.<\/span><\/p>\n<h4 style=\"text-align: center;\"><span style=\"color: #000000;\"><strong>Ong e agenzie di cooperazione<\/strong><\/span><\/h4>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"> Alla luce del giorno stupisce scoprire che i quartieri devastati dall\u2019esplosione del porto dell\u2019agosto 2019 \u2013 Gemmaizeh, Mar Mikhail, Achrafieh \u2013 hanno avuto tutte le case e i palazzi restaurati o addirittura ricostruiti, persino le case disabitate hanno riavuto i vetri alle finestre. Resta spettrale e privo di qualunque segno di ricostruzione, gli uffici su 20 piani trasformati in centinaia di occhiaie vuote che guardano sia il mare verso l\u2019esterno che il quartiere verso l\u2019interno, il palazzo dell\u2019Electricit\u00e9 du Liban, sede centrale della societ\u00e0 pubblica che dovrebbe fornire l\u2019energia elettrica al paese.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-54148 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/05\/Libano_Beirut_porto-300x168.jpg\" alt=\"\" width=\"300\" height=\"168\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/05\/Libano_Beirut_porto-300x168.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/05\/Libano_Beirut_porto.jpg 316w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>E allora il mistero comincia a svelarsi: Gemmaizeh e le altre aree danneggiate di Beirut sono state ricostruite grazie alla solidariet\u00e0 internazionale che ha operato attraverso Ong e agenzie di cooperazione dei vari paesi, e alla solidariet\u00e0 della diaspora libanese, che ha finanziato la ricostruzione e l\u2019installazione di migliaia di pannelli solari che complementano l\u2019energia prodotta dai generatori.<\/span><\/p>\n<h4 style=\"text-align: center;\"><span style=\"color: #000000;\"><strong>Soldi dall\u2019estero\u00a0<\/strong><\/span><\/h4>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"> Quella diaspora che ufficialmente invia a casa 6 miliardi di dollari all\u2019anno, cifra che nel 2019 era pari al 16 per cento del Prodotto interno lordo, ma che l\u2019anno scorso equivaleva a un terzo, e alla fine di quest\u2019anno ancora di pi\u00f9. Cifra probabilmente sottostimata. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-50804 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/05\/Libano-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/05\/Libano-300x169.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/05\/Libano-768x432.jpg 768w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/05\/Libano-1024x576.jpg 1024w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/05\/Libano.jpg 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Insomma, il Libano sopravvive grazie al lavoro di chi \u00e8 andato all\u2019estero e all\u2019ingegno di chi \u00e8 rimasto in patria. Spesso controvoglia: secondo l\u2019ultimo rapporto sulle tendenze migratorie nei paesi di lingua araba, il 48 per cento dei libanesi (che sono circa 4,5 milioni, poi ci sono altri 2 milioni e passa di abitanti costituiti da profughi siriani, palestinesi e stranieri di varia provenienza) desidera emigrare. Fra il 2017 e la fine del 2021 secondo le statistiche ufficiali 215.653 libanesi hanno abbandonato il Paese, cio\u00e8 quasi il 5 per cento di chi ha la cittadinanza<strong>.\u00a0<\/strong><\/span><\/p>\n<h4 style=\"text-align: center;\"><span style=\"color: #000000;\"> <strong>Il vescovo cattolico pi\u00f9 giovane al mondo<\/strong><\/span><\/h4>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">\u00abNon posso dire ai nostri giovani, alle nostre famiglie: \u201cNon emigrate!\u201d. Gli uomini non sono alberi, a volte non trovano nutrimento sufficiente l\u00ec dove sono nati, e allora si spostano nel mondo\u00bb, dice mons. Jules Boutros, da maggio vescovo siro-cattolico di curia del patriarcato di Antiochia. Coi suoi 39 anni Boutros \u00e8 attualmente il vescovo pi\u00f9 giovane del mondo cattolico, e la pastorale giovanile \u00e8 da sempre il suo campo di azione preferito. \u00c8 responsabile della pastorale universitaria e dei movimenti laicali. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-54979 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/10\/mons.-Jules-Boutros_Libano-168x300.jpg\" alt=\"\" width=\"168\" height=\"300\" \/>Nei mesi successivi all\u2019esplosione nel porto di Beirut ha guidato squadre di giovani che partecipavano ai soccorsi, visitavano le famiglie, censivano i bisogni e cercavano di soddisfarli. \u00abA chi parte raccomando di vivere la chiamata alla santit\u00e0 l\u00e0 dove andr\u00e0. Tanti emigrano pensando di cambiare in meglio la propria vita grazie al fatto che dove vanno c\u2019\u00e8 sempre l\u2019elettricit\u00e0, si trova un lavoro e i salari sono decenti. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Tutto questo d\u00e0 sicurezza, ma non d\u00e0 gioia: dopo un po\u2019 sentiranno il peso della solitudine. Io dico a questi giovani: l\u2019uomo \u00e8 creato per servire Dio, solo in questo trova la sua gioia. L\u00ec dove andate non dovete essere solo una buona manodopera, dei professionisti efficienti, dovete essere dei missionari! I paesi dove andate hanno bisogno della nostra fede pi\u00f9 ancora che della nostra manodopera, hanno bisogno dell\u2019ardore di Cristo che \u00e8 nei nostri cuori\u00bb. <\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-49482 size-medium\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/12\/povert\u00e0_Libano-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/12\/povert\u00e0_Libano-300x200.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/12\/povert\u00e0_Libano-768x512.jpg 768w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/12\/povert\u00e0_Libano-1024x683.jpg 1024w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/12\/povert\u00e0_Libano.jpg 1476w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">\u00abPer tenere viva la fede e la missionariet\u00e0 dei nostri emigrati in questi anni li ho visitati nei paesi dove emigrano: in Olanda, Belgio, Francia, Italia, Germania, Svezia, Turchia, ecc. L\u2019etimologia originaria della parola \u201cdiaspora\u201d \u00e8 \u201cseminagione\u201d. \u00c8 un\u2019immagine di vita, l\u2019immagine di piante che crescono e danno frutto. Ma bisogna aiutarli con la vicinanza perch\u00e9 non cadano nella trappola delle false libert\u00e0 dei paesi in cui emigrano. Perch\u00e9 non finiscano come il Figliol prodigo\u00bb.\u00a0<\/span><\/p>\n<h4 style=\"text-align: center;\"><span style=\"color: #000000;\"><strong>\u00abLo Stato \u00e8 paralizzato\u00bb<\/strong><\/span><\/h4>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">\u00abHo vergogna di me stesso di essere deputato, e di non poter soddisfare i miei connazionali che chiedono il pane per vivere, le medicine per curarsi, il latte in polvere per i loro bambini che vanno a cercare fino a Dubai, l\u2019elettricit\u00e0 per lavorare, la possibilit\u00e0 di prelevare i loro risparmi. Lo Stato \u00e8 paralizzato, in via di decomposizione, e le nostre voci in parlamento non vengono ascoltate, siamo stati esclusi dalle presidenze di tutte le 17 Commissioni parlamentari\u00bb.\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-45135 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/11\/Libano-1.jpg\" alt=\"\" width=\"276\" height=\"182\" \/>Siamo nello studio di Mehlem Khalaf, avvocato di fama, gi\u00e0 presidente dell\u2019Ordine, e da qualche mese deputato del parlamento nazionale, nel quartiere di Badaro; all\u2019angolo della via una coda di una ventina di persone attende di poter entrare nella Blom Bank, uno dei tanti istituti di credito che da mesi esasperano i depositanti impedendo loro di prelevare somme significative dai loro conti correnti bancari. Si entra solo su appuntamento, un paio di persone alla volta: in questi mesi si sono succeduti casi di correntisti che hanno minacciato di usare la forza o di suicidarsi nei locali delle banche che rifiutavano di permettere loro prelievi e operazioni.<\/span><\/p>\n<h4 style=\"text-align: center;\"><span style=\"color: #000000;\"><strong>Sistema di potere\u00a0<\/strong><\/span><\/h4>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"> In realt\u00e0 Mehlem Khalaf \u00e8 uno dei deputati che meno dovrebbero vergognarsi della situazione di crisi: \u00e8 stato eletto per la prima volta alle ultime elezioni, \u00e8 un esponente della societ\u00e0 civile interconfessionale che \u00e8 scesa in piazza nell\u2019ottobre del 2019 per protestare contro il malgoverno giunto all\u2019apice, fa parte del gruppo delle Forze per il Cambiamento, un gruppo di parlamentari eletti fuori dalle logiche partitiche confessionali, che sotto il mantello del governo di unit\u00e0 nazionale hanno impoverito il paese.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"> <img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-54980 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/10\/Libano_assemblea_nazionale.jpg\" alt=\"\" width=\"275\" height=\"183\" \/>\u00abDemocrazia consensuale, governo di unit\u00e0 nazionale o di coesione nazionale, sono gli slogan dietro a cui in questi anni si \u00e8 creato un sistema di potere basato sul raccordo fra esponenti dei partiti che dicono di rappresentare e proteggere la propria comunit\u00e0 religiosa di riferimento, ma che in realt\u00e0 si sono spartiti le spoglie del paese, soprattutto attraverso appalti gonfiati e pilotati di opere pubbliche e di servizi pubblici affidati a privati di loro gradimento. In questo paese la corruzione \u00e8 sia verticale che orizzontale, anche i cittadini comuni sono costretti a diventare corruttori per ottenere licenze e permessi che altrimenti verrebbero loro negati o ritardati enormemente\u00bb.<\/span><\/p>\n<h4 style=\"text-align: center;\"><span style=\"color: #000000;\"><strong>I 3 miliardi del Fmi<\/strong>\u00a0<\/span><\/h4>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"> Nonostante l\u2019insofferenza generalizzata dei libanesi per il mondo politico tradizionale, gli esponenti delle Forze del Cambiamento hanno portato a casa solo 13 seggi sui 120 a disposizione. Hezbollah e Amal, le Forze Libanesi, il partito del presidente Aoun e quello druso dei Jumblatt continuano a restare sulla breccia.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-47599 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/06\/fondo_monetario_banca_economia.jpg\" alt=\"\" width=\"135\" height=\"135\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/06\/fondo_monetario_banca_economia.jpg 225w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/06\/fondo_monetario_banca_economia-150x150.jpg 150w\" sizes=\"auto, (max-width: 135px) 100vw, 135px\" \/>\u00abColpa di una legge elettorale e di un disegno dei collegi che premia le forze confessionali, regionali, clientelari e punisce le novit\u00e0 politiche. I nostri candidati hanno raccolto pi\u00f9 di un quarto di tutti i voti espressi, ma solo un decimo dei seggi\u00bb. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Con tutto questo, da maggio scorso non \u00e8 stato formato nessun nuovo governo e quello uscente continua ad amministrare; il 31 ottobre scade il termine utile per eleggere il nuovo capo dello Stato, dopodich\u00e9 in caso di mancata elezione la carica rester\u00e0 vacante. Niente di buono per un paese chiamato a riformare il suo sistema finanziario se vuole ottenere i 3 miliardi di dollari di prestiti del Fondo monetario internazionale che soli possono dare ossigeno al sistema ed evitare che imploda da un momento all\u2019altro [<em>1. continua<\/em>].<\/span><\/p>\n<p style=\"text-align: center;\">__________________________<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\"><a href=\"https:\/\/www.tempi.it\/\" target=\"_blank\" rel=\"noopener\"><strong>Tempi<\/strong> <\/a>28 Ottobre 2022 <\/span><\/p>\n<h3 style=\"text-align: center;\"><span style=\"color: #000000;\"><strong>\u00abSenza cristiani non c\u2019\u00e8 Libano\u00bb<\/strong><strong><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/em><\/strong><\/span><\/h3>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><em>Le difficolt\u00e0 di convivenza nel paese in cui si vorrebbe \u201cvivere insieme\u201d. Ma dove solo i cristiani riescono a stare con tutti. Reportage da Beirut<\/em><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\">di <strong>Rodolfo Casadei <\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><em>Grazie al sostegno di Orizzonti e di Romagna Solidale l\u2019inviato di <\/em>Tempi <\/span><em><span style=\"color: #000000;\">Rodolfo Casadei si trova<\/span><\/em><em><span style=\"color: #000000;\"> in Libano. Qui trovate la seconda delle sue corrispondenze per il sito, che lasciamo aperta alla lettura anche dei non abbonati. Il reportage completo potr\u00e0 essere letto sul prossimo numero di<\/span> <a href=\"https:\/\/www.tempi.it\/hai-visto-che-tempi-abbonamento\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong><span style=\"color: #0000ff;\">Tempi mensile<\/span><\/strong><\/a>. <\/em><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>Beirut <\/strong>\u2013 La voce femminile secca e alterata risuona per tutto l\u2019ufficio del giudice e <img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-54981 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/10\/Libano_tribunale-300x160.jpg\" alt=\"\" width=\"300\" height=\"160\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/10\/Libano_tribunale-300x160.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/10\/Libano_tribunale.jpg 307w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>ben oltre la porta di legno e vetro. La sequela di invettive e di lamentele culmina col pi\u00f9 sanguinoso degli insulti: \u00abMio marito non \u00e8 un vero uomo!\u00bb. Il marito in questione, anzi l\u2019ex marito, non muove un muscolo, impassibile e remissivo nel suo volto calmo e baffuto. Ha appena recitato la formula del divorzio, cos\u00ec come ha fatto quella che da questo momento \u00e8 la sua ex moglie. Quando escono dalla sala addirittura le apre la porta e le cede il passo, bench\u00e9 lei non si sia affatto calmata.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Mohamed Nokkari, giudice del tribunale sunnita per le cause civili del quartiere di Tarik el Jadideh, \u00e8 uomo di grande esperienza non solo giuridica ma anche psicologica e sociologica. \u00abIl numero dei divorzi si \u00e8 impennato in questi ultimi tre anni, a motivo della crisi economica e del confinamento a causa del Covid. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-42570 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/03\/donne_islam.jpg\" alt=\"\" width=\"281\" height=\"179\" \/>All\u2019esasperazione per le lunghe convivenze forzate si \u00e8 aggiunta l\u2019incapacit\u00e0 finanziaria del marito di mantenere la famiglia, di pagare l\u2019affitto e la scuola per i figli. Per avere meno spese le coppie si dividono tornando a vivere presso i rispettivi genitori, i rapporti si allentano e si arriva facilmente al divorzio. In precedenza c\u2019era stata l\u2019ondata dei divorzi per \u201cinfedelt\u00e0 virtuale\u201d, figli di Facebook e di Whatsapp: le persone sposate non sanno gestire le tentazioni informatiche, inviano messaggi compromettenti a uomini e donne che hanno conosciuto online, a volte filmati in cui si denudano, il coniuge lo scopre e chiede il divorzio. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Il primo storico forte aumento dei tassi di divorzio all\u2019interno della comunit\u00e0 musulmana sunnita c\u2019era stato quando le donne hanno cominciato a lavorare fuori di casa, a disporre di finanze proprie, a viaggiare sole\u00bb.<\/span><\/p>\n<h4 style=\"text-align: center;\"><span style=\"color: #000000;\"><strong>Abbigliamento femminile in tribunale<\/strong> <\/span><\/h4>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-36809 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/11\/donna_islam.jpg\" alt=\"\" width=\"276\" height=\"183\" \/>Nokkari non \u00e8 affatto un bigotto n\u00e9 un nostalgico del tempo andato. Interpretando al meglio lo spirito libanese del \u201cvivere insieme\u201d, \u00e8 stato promotore congiuntamente ad esponenti cristiani e sciiti della ufficializzazione della festa dell\u2019Annunciazione di Maria come festivit\u00e0 nazionale islamo-cristiana il 25 marzo. Nel 2010 \u00e8 stato insignito del premio Onu Sergio Vieira De Mello per il dialogo interreligioso. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">\u00c8 perfettamente consapevole delle dinamiche sociali in atto all\u2019interno della comunit\u00e0 sunnita (che rappresenta fra il 27 e il 30 per cento della popolazione libanese), di cui \u00e8 un sintomo l\u2019abbigliamento delle donne che si rivolgono al suo tribunale: tutte le querelanti indossano l\u2019hijab o altro velo, ma la maggior parte in maniera scorretta, lasciando scoperta parte della capigliatura; segno che abitualmente, nella vita quotidiana, non lo portano, ed \u00e8 solo per rispetto della sede giudiziaria religiosa che quel giorno lo indossano.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-46194 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/02\/libano_proteste-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/02\/libano_proteste-300x169.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/02\/libano_proteste-768x432.jpg 768w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/02\/libano_proteste-1024x576.jpg 1024w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/02\/libano_proteste.jpg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Del resto \u00e8 quello che si nota facendo due passi nel quartiere popolare, per niente sofisticato, di Tarek el Jadideh, sunnita quasi al cento per cento: donne velate e donne senza velo si equivalgono numericamente, e nessun niqab (velatura integrale che copre anche mani e volto) si intravvede all\u2019orizzonte; un panorama ben diverso da quello del vicino Egitto. Del resto all\u2019interno stesso del tribunale sciaraitico le cose non vanno come ci si potrebbe immaginare: nella successione delle udienze si fa notare una giovane avvocata stile pantera, tacchi alti, pantaloni e corpetto nero attillato, rossetto accentuato e capelli liberi e fluenti mesciati di biondo. E questo \u00e8 un tribunale dove si applica la sharia alle cause civili\u2026 (matrimoni, eredit\u00e0, successioni, ecc.).<\/span><\/p>\n<h4 style=\"text-align: center;\"><span style=\"color: #000000;\"><strong>Se lo Stato fosse laico<\/strong>\u2026<\/span><\/h4>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-39599 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/01\/gen-Aoun_Libano-300x168.png\" alt=\"\" width=\"300\" height=\"168\" \/>\u00abIl confessionalismo va abolito a livello politico e mantenuto a livello religioso\u00bb, dice Nokkkari esprimendo il suo punto di vista. \u00abNon ha pi\u00f9 senso ripartire i posti di potere in base all\u2019appartenenza religiosa, devono governare e amministrare i pi\u00f9 capaci, solo le capacit\u00e0 individuali devono contare. In passato il confessionalismo politico aveva senso come soluzione per la salvaguardia delle comunit\u00e0, ma oggi non pi\u00f9. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Deve restare il patrimonio religioso rappresentato dalle 18 diverse identit\u00e0 religiose, perch\u00e9 \u00e8 la specificit\u00e0 del Libano. Io sono favorevole al mantenimento delle scuole e dei tribunali confessionali, ma con dei cambiamenti. Lo Stato dovrebbe farsi carico degli attuali tribunali sciaraitici e canonici, musulmani e cristiani, e affiancare al diritto di famiglia di cristiani e musulmani anche un diritto di famiglia strettamente civile per i non praticanti e per i non religiosi; le persone che intentano una causa dovrebbero essere poi libere di rivolgersi ai giudici del diritto sciaraitico o canonico, oppure a quelli del diritto civile non religioso. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Se lo Stato fosse interamente laico, ci sarebbe un pericolo di estinzione per le comunit\u00e0 pi\u00f9 piccole. Io immagino un sistema intermedio fra lo Stato laico e il sistema confessionale attuale\u00bb.<\/span><\/p>\n<h4 style=\"text-align: center;\"><span style=\"color: #000000;\"><strong>Sempre meno cristiani<\/strong><\/span><\/h4>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-19509 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/02\/Libano-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/02\/Libano-300x225.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/02\/Libano.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Un\u2019altra persona preoccupata di conservare l\u2019identit\u00e0 religiosa nel mentre che si modernizza e si laicizza lo Stato, e con essa la specificit\u00e0 del Libano, \u00e8 Fouad Abou Nader, presidente della Ong Nawraj, che ha come scopo sociale il mantenimento della presenza cristiana in Libano. Nader \u00e8 stato niente meno che comandante in capo delle formazioni combattenti delle Forze Libanesi durante la guerra civile (1975-1990) fra il 1984 e il 1985; oggi si dedica anima e corpo all\u2019obiettivo che nella sua visione solo pu\u00f2 garantire la pace in Libano, e cio\u00e8 la permanenza del pi\u00f9 alto numero possibile di cristiani nel paese. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Mentre infatti al momento dell\u2019indipendenza (1943) i cristiani costituivano la maggioranza assoluta della popolazione libanese (52 per cento), oggi la loro percentuale \u00e8 variamente stimata fra il 30 e il 40 per cento del totale (non si tengono censimenti ufficiali delle affiliazioni religiose dal 1932<strong>!).<\/strong><\/span><\/p>\n<h4 style=\"text-align: center;\"><span style=\"color: #000000;\"><strong>I cristiani vivono con tutti<\/strong><\/span><\/h4>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"> <img loading=\"lazy\" decoding=\"async\" class=\" wp-image-54149 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/05\/libano-300x169.jpg\" alt=\"\" width=\"334\" height=\"188\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/05\/libano-300x169.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/05\/libano.jpg 500w\" sizes=\"auto, (max-width: 334px) 100vw, 334px\" \/>\u00ab\u00c8 importante \u2013 dice a <em>Tempi<\/em> \u2013 che il numero dei cristiani in Libano resti significativo perch\u00e9 senza cristiani non c\u2019\u00e8 Libano, cio\u00e8 non ci sarebbe l\u2019unico paese di questa parte del mondo che non ha una religione di Stato, dove cristiani e musulmani sono uguali davanti alla legge, dove non ci sono cittadini di seconda classe, l\u2019unico al mondo dove cristiani e musulmani festeggiano insieme l\u2019Annunciazione a Maria. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Oggi il grande problema politico del Medio Oriente \u00e8 il conflitto fra sunniti e sciiti, che ricorda le guerre di religione europee. Noi cristiani siamo l\u2019elemento di moderazione che pu\u00f2 impedire a questo conflitto di precipitare. In Libano ci sono 1.611 villaggi, ma in nessuno di questi convivono sunniti e sciiti, oppure drusi e sciiti, oppure drusi e sunniti. Ma ci sono tanti villaggi dove i cristiani convivono coi sunniti, o con gli sciiti, o con i drusi. Noi siamo il ponte fra le diverse comunit\u00e0 religiose\u00bb.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"> <img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-54982 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/10\/Libano_cristiani.jpg\" alt=\"\" width=\"284\" height=\"177\" \/>Per rendere convincente il suo ragionamento Nader fa l\u2019esempio di una mediazione fra comunit\u00e0 religiose favorita da lui e da Nawraj. \u00abNel 2014 c\u2019\u00e8 stato un attacco di Daesh (lo Stato Islamico) proveniente dalla Siria nella zone di Arsal, nel nord-est del Libano, e 41 soldati libanesi sciiti sono stati presi in ostaggio dai terroristi, mentre 3 venivano uccisi immediatamente. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Per rappresaglia gli sciiti della regione hanno rapito un numero equivalente di sunniti, e hanno minacciato di trucidarli se succedeva qualcosa agli ostaggi sciiti. Noi abbiamo mobilitato il sindaco cristiano di Ras Baalbek, che ha contattato il sindaco sunnita di Arsal e il sindaco sciita della cittadina di Hermel e si \u00e8 offerto di mediare uno scambio di prigionieri. La mediazione \u00e8 andata a buon fine, e gli ostaggi delle due confessioni islamiche sono stati scambiati a Ras Baalbek e sono tornati a casa sani e salvi\u00bb.<\/span><\/p>\n<h4 style=\"text-align: center;\"><span style=\"color: #000000;\"><strong>\u00abQuesta citt\u00e0 sta perdendo la sua anima\u00bb<\/strong><\/span><\/h4>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-54983 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/10\/Beirut_Libano.jpg\" alt=\"\" width=\"320\" height=\"197\" \/>Un\u2019altra personalit\u00e0 originale che vuole preservare la specificit\u00e0 libanese, su un piano diverso ma complementare a quelli di uomini come Mohamed Nokkari e Fouad Abou Nader, \u00e8 Suheil Mneimneh, presidente della Beirut Heritage Society, una fondazione che ha per obiettivo la conservazione del patrimonio architettonico e culturale in senso lato della citt\u00e0 di Beirut, con particolare attenzione alla musica e alla letteratura popolare, ai paesaggi urbani, agli edifici storici. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Organizzata in comitati, l\u2019associazione organizza visite guidate di scolaresche nella citt\u00e0 vecchia, allestisce mostre fotografiche, celebra anniversari, premia personalit\u00e0 viventi, commemora grandi figure trapassate, stampa libri come uno recentissimo, fotografico, sulle decine di sale cinematografiche di Beirut (ma anche di altre localit\u00e0 libanesi) che hanno chiuso da tempo i battenti.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"> <img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-54984 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/10\/Beirut_Libano-1-300x168.jpg\" alt=\"\" width=\"300\" height=\"168\" \/>\u00abQuesta citt\u00e0 sta perdendo la sua anima\u00bb, spiega sconsolato. \u00abLa ricostruzione dopo la fine della guerra civile in gran parte non \u00e8 stata rispettosa dell\u2019identit\u00e0 di questa citt\u00e0, e non parlo di storia, ma di tessuto sociale. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Quando gli appartenenti alla generazione che ha vissuto la guerra civile visitano i quartieri ricostruiti da Solidere (la grande impresa edilizia legata al primo ministro Rafic Hariri \u2013 ndr) dove loro abitavano, dicono tutti: \u201cQuesta non \u00e8 Beirut, questa \u00e8 un\u2019altra cosa, e noi non possiamo adattarci\u201d. Non possiamo fermare la modernizzazione, ma questo non pu\u00f2 avvenire a spese del tessuto sociale, a spese degli \u201cheritages sites\u201d, luoghi che meritano di essere trasmessi da una generazione all\u2019altra. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Ci sono leggi che dovrebbero proteggere questo patrimonio, ma sono ritagliate su misura per gli interessi degli speculatori edilizi e dei loro protettori politici, oppure semplicemente non vengono applicate. Contro tutto questo noi ci battiamo, e la gente ci appoggia, come dimostra il successo dei video che pubblichiamo sul nostro canale Youtube. Perch\u00e9 senza eredit\u00e0 non c\u2019\u00e8 identit\u00e0\u00bb.<\/span><\/p>\n<p style=\"text-align: center;\">___________________________<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.tempi.it\/\" target=\"_blank\" rel=\"noopener\"><strong>Tempi<\/strong> <\/a>2 Novembre 2022<\/p>\n<h3 style=\"text-align: center;\"><strong>La tragedia del Libano, dove ormai si muore per malattie curabili<\/strong><\/h3>\n<p><em>Il crollo del valore della moneta ha impoverito tutti, e tanti non hanno soldi neppure per il paracetamolo. Giudici fermi, medici in fuga, e un progetto di Pro Terra Sancta che prova a costruire qualcosa. Reportage <\/em><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\">di <strong>Rodolfo Casadei\u00a0<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-53474 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/02\/Libano_sanit\u00e0-ospedali.jpg\" alt=\"\" width=\"255\" height=\"255\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/02\/Libano_sanit\u00e0-ospedali.jpg 225w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/02\/Libano_sanit\u00e0-ospedali-150x150.jpg 150w\" sizes=\"auto, (max-width: 255px) 100vw, 255px\" \/>Cinque anni. Amir \u00e8 morto a cinque anni per una questione che si poteva risolvere con 4 o 5 euro. Quattro o cinque euro, il costo di una confezione di tachipirina\u2026 <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Ma quei soldi la sua famiglia non ce li aveva, e in Libano al giorno d\u2019oggi non c\u2019\u00e8 piet\u00e0 per nessuno. Stephanie ti guarda dritto negli occhi e la sua voce \u00e8 un crescendo: \u00abGli \u00e8 venuta la febbre, altissima. Hanno fatto il giro delle farmacie della loro zona, ma sono talmente mal ridotte che nessuna aveva il paracetamolo. Allora sono corsi all\u2019ospedale. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Gli hanno detto: \u201cSe non avete da pagare non possiamo darvi niente\u201d. Il bambino ha avuto le convulsioni, \u00e8 andato in coma e in poco tempo \u00e8 morto. Come lui sono morte altre tre persone che erano nostri assistiti: non a causa della gravit\u00e0 della malattia, ma perch\u00e9 non si sono potute curare o perch\u00e9 non si sono potute ospedalizzare. Deve credermi: la gente in Libano sta morendo per malattie curabilissime!\u00bb.<\/span><\/p>\n<h4 style=\"text-align: center;\"><strong>La goccia nel mare di Pro Terra Sancta in Libano<\/strong><\/h4>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-54997 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/11\/terra_santa_chiesa.png\" alt=\"\" width=\"225\" height=\"225\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/11\/terra_santa_chiesa.png 225w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/11\/terra_santa_chiesa-150x150.png 150w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/>Stephanie, laurea in Farmacia, fa parte dell\u2019\u00e9quipe di <strong><a href=\"https:\/\/www.proterrasancta.org\/it\/\"><span style=\"color: #0000ff;\">Pro Terra Sancta<\/span><\/a><\/strong> (la Ong legata ai Francescani di Terra Santa) che da quasi un anno fornisce assistenza medica alle famiglie indigenti di Tripoli, la pi\u00f9 povera fra le grandi citt\u00e0 libanesi. Sono pi\u00f9 di 1.500 gli adulti e i bambini che fino a oggi hanno ricevuto assistenza gratuita. Ma \u00e8 una goccia nel mare.<\/p>\n<p style=\"text-align: justify;\">\u00abIn Libano gli ospedali pubblici si occupano di chi non ha una copertura sanitaria, gli ospedali privati di chi ce l\u2019ha. I primi sono un disastro, i secondi funzionano. Ma da quando \u00e8 cominciata la crisi respingono anche i pazienti coperti dalla previdenza sociale, e chiedono il pagamento in dollari: 8 mila per un parto senza complicazioni, 20 mila per un\u2019operazione al cuore. E li esigono in contanti!\u00bb.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-54999 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/11\/Libano_caritas.jpg\" alt=\"\" width=\"299\" height=\"168\" \/>Padre Michel Abboud, carmelitano presidente della Caritas nazionale, conferma: \u00abOgni settimana ci arrivano notizie credibili di persone decedute soltanto perch\u00e9 non avevano i soldi per acquistare farmaci salvavita o perch\u00e9 gli ospedali li respingevano in quanto non potevano pagare ricovero e intervento. Nel recente passato i libanesi in posizione di lavoro dipendente andavano nelle cliniche private convenzionate, e la previdenza sociale a cui erano stati fatti i versamenti attraverso i prelievi in busta paga saldava il costo della prestazione.<\/p>\n<p style=\"text-align: justify;\">Col crollo del 95 per cento del valore della lira libanese l\u2019importo dei versamenti \u00e8 diventato risibile, e di conseguenza la previdenza non \u00e8 pi\u00f9 in grado di rimborsare nulla. Allora gli ospedali esigono di essere pagati direttamente e anticipatamente da chi chiede la prestazione, ma costoro non hanno pi\u00f9 soldi, perch\u00e9 il valore degli stipendi \u00e8 crollato insieme a quello dei versamenti previdenziali! Gente che prima guadagnava l\u2019equivalente di 1.500 dollari al mese, adesso in busta paga ne trova l\u2019equivalente di 50. E deve affrontare le stesse spese di prima\u2026\u00bb.<\/p>\n<h4 style=\"text-align: center;\"><strong>\u00c8 crollato anche il sistema giudiziario<\/strong><\/h4>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-55000 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/11\/Libano_tribunale.jpg\" alt=\"\" width=\"334\" height=\"222\" \/>Trovare riscontro a queste affermazioni \u00e8 facilissimo: \u00abMio padre \u00e8 un militare, ed \u00e8 esattamente una di quelle persone che prima del crollo della lira guadagnavano 1.500 dollari: oggi si sono ridotti a 50 appena!\u00bb, racconta Sally, una bella ragazza di 27 anni laureata in Legge che sta per sposarsi. \u00abIo lavoro da due anni in uno studio di avvocati, e le nostre parcelle si sono disintegrate, perch\u00e9 ormai non si celebrano pi\u00f9 processi.<\/p>\n<p style=\"text-align: justify;\">I giudici erano persone che prima del tracollo finanziario guadagnavano 6 mila dollari al mese, e adesso ne vedono 200! Perci\u00f2 non convocano pi\u00f9 le udienze, perch\u00e9 si dedicano ad altre attivit\u00e0 per poter sopravvivere. Lasciamo stare i soldi, pensi alle conseguenze giudiziarie e umane: i detenuti in attesa di giudizio restano in carcere, i permessi per le visite dei familiari ai detenuti o i provvedimenti per la concessione degli arresti domiciliari non vengono pi\u00f9 disposti. E naturalmente gli avvocati non vengono pi\u00f9 pagati\u00bb.<\/p>\n<h4 style=\"text-align: center;\"><strong>Jimmy il geniaccio e i medici in fuga\u00a0<\/strong><\/h4>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-48167 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/08\/Libano.jpg\" alt=\"\" width=\"279\" height=\"263\" \/>I giudici non sono i soli pubblici ufficiali che hanno preso l\u2019abitudine di marcar visita: a Beirut come nel resto del paese la polizia municipale \u00e8 diventata quasi invisibile. Impegnati in doppi o tripli lavori per portare a casa l\u2019indispensabile, i vigili urbani non si presentano al lavoro pi\u00f9 di un giorno o due alla settimana. Nella capitale del Libano non si staccano pi\u00f9 multe per divieto di sosta: dopo le proteste dell\u2019ottobre 2019, i parchimetri sono stati divelti o manomessi e mai pi\u00f9 aggiustati, i vigili sono quasi scomparsi dalle strade, gli abitanti di Beirut parcheggiano ovunque gratis e senza subire mai alcuna sanzione.<\/p>\n<p style=\"text-align: justify;\">Jimmy \u00e8 un geniaccio. A 27 anni lavora nella polizia militare e ha gi\u00e0 preso o sta per prendere una serie impressionante di lauree e diplomi di alta qualificazione: patologia clinica forense, management dei grandi disastri, gestione degli esplosivi, psicologia clinica. Faceva parte di una delle \u00e9quipes che hanno eseguito i rilievi dell\u2019esplosione del porto di Beirut dell\u2019agosto 2019, ma \u00e8 stato allontanato perch\u00e9 considerato un ficcanaso (l\u2019inchiesta \u00e8 stata ostacolata e virtualmente insabbiata per le pressioni del partito Hezbollah).<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-29291 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/01\/Libano-11-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/01\/Libano-11-225x300.jpg 225w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/01\/Libano-11-768x1024.jpg 768w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/01\/Libano-11.jpg 1200w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/>\u00abMia madre ha una bottega di frutta e verdura che faceva profitti per 1.000 dollari al mese, adesso \u00e8 tanto se arriva a 30. Io avevo uno stipendio da 1.300 dollari, che sono diventati 50. Abbiamo dovuto lasciare la casa nella capitale, che avevamo restaurato dopo i danni per l\u2019esplosione del porto, e trasferirci in campagna. Io vorrei emigrare perch\u00e9 con le mie qualifiche potrei trovare lavoro all\u2019estero, ma essendo militare non mi lasciano andare!\u00bb. Chi invece se ne va dal paese sono medici e infermieri: lo scorso anno 5 mila dei 16 mila dottori iscritti all\u2019Ordine sono emigrati, e le cifre che riguardano gli infermieri sembrano non essere molto diverse.<\/p>\n<h4 style=\"text-align: center;\"><strong>Il dilemma dei giovani: partire o restare in Libano?<\/strong><\/h4>\n<p style=\"text-align: justify;\">\u00abI giovani si trovano di fronte a un dilemma morale: partire e aiutare le loro famiglie dall\u2019estero, col rischio di perdere le proprie radici, oppure restare e cercare di costruire qui qualcosa di nuovo, col rischio di fallire e di non potere pi\u00f9 assicurare le condizioni della vita materiale a s\u00e9 e ai propri cari\u00bb, spiega mons. Mounir Khairallah, vescovo maronita di Batroun.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-28086 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/08\/Libano_war.jpg\" alt=\"\" width=\"295\" height=\"250\" \/>\u00abMio nipote ora ha 39 anni, \u00e8 un ingegnere informatico. Otto anni fa \u00e8 emigrato in Nigeria dove fra mille difficolt\u00e0 ambientali ha messo da parte un tesoretto che ha trasferito sul suo conto corrente in una banca libanese, cambiando i dollari in lire per ottenere interessi migliori.<\/p>\n<p style=\"text-align: justify;\">Quando \u00e8 tornato, ha scoperto che il deposito aveva perso il 95 per cento del suo valore, e che in aggiunta c\u2019erano problemi per i prelievi, a causa delle limitazioni che le banche di loro iniziativa hanno imposto. I sacrifici di un decennio di vita sono andati perduti, deve ripartire da zero. Doveva decidere se ripartire da zero in Libano o se ripartire da zero all\u2019estero\u00bb.<\/p>\n<p style=\"text-align: justify;\">\u00abCi siamo parlati a lungo, e alla fine mi ha detto: \u201cZio, io voglio vivere e costruire qualcosa qui in Libano, le cose devono cambiare\u201d. Il paese \u00e8 pieno di giovani come lui, pi\u00f9 giovani di lui, che stanno comportandosi in modo commovente: mentre prima erano i genitori ad aiutarli economicamente, ora sono loro che cercano di rendere meno dura la vita di loro padre e di loro madre.<\/p>\n<p style=\"text-align: justify;\">Fanno sacrifici eroici per non pesare sui genitori. Alcuni di loro emigrano, con l\u2019obiettivo di garantire un futuro migliore a se stessi e ai loro cari che restano in Libano, ai quali invieranno rimesse come emigranti. Io dico loro: \u201cAndate, non esitate. Ma tornate, un giorno! Grazie al vostro aiuto da fuori qui comincer\u00e0 una societ\u00e0 nuova, con un sistema politico diverso e uno Stato pi\u00f9 efficiente. Insieme, voi all\u2019estero e noi qui, ce la faremo\u201d\u00bb.<\/p>\n<h4 style=\"text-align: center;\"><strong>Il progetto \u201cWork in Progress\u201d di Pro Terra Sancta<\/strong><\/h4>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-55001 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/11\/libano.jpg\" alt=\"\" width=\"340\" height=\"192\" \/>Intenzionati a restare sono i giovani e meno giovani che hanno preso parte al progetto in tre tappe per la microimprenditoria in Libano \u201cWork in Progress\u201d, promosso da Pro Terra Sancta.<\/p>\n<p style=\"text-align: justify;\">Si sono presentati 100 candidati, ai quali \u00e8 stata data la possibilit\u00e0 di frequentare un corso di sei settimane sui fondamentali del business e del management. Fra loro ne sono stati poi selezionati 30 che hanno dimostrato le migliori capacit\u00e0 imprenditoriali e che hanno avuto diritto al \u201ccoaching\u201d indispensabile per mettere a punto il loro business plan (idea, piano finanziario e analisi di mercato) da parte di un gruppo di esperti italiani e libanesi.<\/p>\n<p style=\"text-align: justify;\">Fra questi 30 verranno infine scelti i 5 progetti mertitevoli di diventare realt\u00e0 da un comitato di imprenditori e accademici universitari di facolt\u00e0 economico-finanziarie: i loro promotori riceveranno 5 mila euro a testa per avviare la loro startup.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-51950 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/07\/Libano-300x120.jpg\" alt=\"\" width=\"338\" height=\"135\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/07\/Libano-300x120.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/07\/Libano-768x308.jpg 768w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/07\/Libano-1024x411.jpg 1024w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/07\/Libano.jpg 1992w\" sizes=\"auto, (max-width: 338px) 100vw, 338px\" \/>Ma che ne sar\u00e0 dei 25 perdenti, chiediamo a Peter Hayek, un giovane dirigente del team di Pro Terra Sancta, che ha lasciato un lavoro ben remunerato nell\u2019ambito del merchandising per operare nel settore dell\u2019umanitario?<\/p>\n<p style=\"text-align: justify;\">\u00abA causa della crisi tanti giovani e meno giovani sono caduti in depressione, si sono chiusi in casa, alcuni si sono suicidati: hanno visto il loro mondo quotidiano scomparire nel giro di poco tempo, il loro stile di vita normale diventare impossibile, amici e parenti che partivano per l\u2019estero e li lasciavano soli. Il nostro progetto ha tirato fuori da casa e dal pozzo della depressione tanti che avevano perduto la fiducia in se stessi e nel prossimo.<\/p>\n<p style=\"text-align: justify;\">Anche chi non vincer\u00e0 il premio di 5 mila euro potr\u00e0 cercare di realizzare il progetto che \u00e8 stato aiutato a formulare in termini corretti; avr\u00e0 comunque scoperto che esiste ancora la possibilit\u00e0 di relazionarsi ad altri e di fare leva sulle proprie personali qualit\u00e0\u00bb.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-55002 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/11\/cibo_orti_ambiente.jpg\" alt=\"\" width=\"299\" height=\"210\" \/>\u00abCome definirei quello che stiamo facendo in questo periodo noi che partecipiamo a \u201cWork in Progress\u201d?\u00bb, risponde Jimmy il geniaccio, il cui progetto per la creazione di orti urbani su balconi e terrazze \u00e8 stato selezionato fra i 30 dell\u2019ultima scrematura.<\/p>\n<p style=\"text-align: justify;\">\u00abLo spettacolo delle fenici che risorgono dalla cenere\u00bb. Non si fa in tempo a chiedere a Jimmy se ha letto Erodoto o Ovidio, perch\u00e9 sta gi\u00e0 parlando col professor Paolo Fumagalli che insegna scienze bancarie, finanziarie e assicurative all\u2019Universit\u00e0 Cattolica di Milano. La fenice ha preso il volo (<em>3.fine<\/em>).<\/p>\n<p>_________________________________________________<\/p>\n<p><span style=\"color: #000000;\"><strong>Per conoscere il Libano<\/strong><\/span><\/p>\n<p><span style=\"color: #0000ff;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/cristo-e-il-libano-di-virgil-gheorghiu\/\" target=\"_blank\" rel=\"noopener\">Cristo e il Libano (di Virgil Gheorghiu)\u00a0<\/a> <span style=\"color: #000000;\">&#8211; libro\u00a0<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Abstract: la tragedia del Libano, un paese che muore. Una serie di corrispondenze dal Paese dei Cedri, ridotto allo stremo dalle sanzioni, dalla devastante esplosione che ha devastato il porto e parte della capitale e ancora una volta sull&#8217;orlo della guerra civile con gran parte della popolazione ridotta in povert\u00e0 e dove si muore anche &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-tragedia-del-libano-un-paese-che-muore\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":47444,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[108],"tags":[373,545],"class_list":["post-54978","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-paesi-e-continenti","tag-libano","tag-paesi-e-continenti-2","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La tragedia del Libano, un paese che muore - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"La tragedia del Libano, un paese che muore, raccontata e descritta in un reportage in tre puntate che descrive la disperata situazione\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-tragedia-del-libano-un-paese-che-muore\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La tragedia del Libano, un paese che muore - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"La tragedia del Libano, un paese che muore, raccontata e descritta in un reportage in tre puntate che descrive la disperata situazione\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-tragedia-del-libano-un-paese-che-muore\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-02T23:00:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-14T16:15:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/06\/Libano.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"34 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-tragedia-del-libano-un-paese-che-muore\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-tragedia-del-libano-un-paese-che-muore\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"La tragedia del Libano, un paese che muore\",\"datePublished\":\"2022-11-02T23:00:06+00:00\",\"dateModified\":\"2024-02-14T16:15:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-tragedia-del-libano-un-paese-che-muore\\\/\"},\"wordCount\":5044,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-tragedia-del-libano-un-paese-che-muore\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Libano.jpg\",\"keywords\":[\"Libano\",\"paesi e continenti\"],\"articleSection\":[\"Paesi e continenti\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-tragedia-del-libano-un-paese-che-muore\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-tragedia-del-libano-un-paese-che-muore\\\/\",\"name\":\"La tragedia del Libano, un paese che muore - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-tragedia-del-libano-un-paese-che-muore\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-tragedia-del-libano-un-paese-che-muore\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Libano.jpg\",\"datePublished\":\"2022-11-02T23:00:06+00:00\",\"dateModified\":\"2024-02-14T16:15:18+00:00\",\"description\":\"La tragedia del Libano, un paese che muore, raccontata e descritta in un reportage in tre puntate che descrive la disperata situazione\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-tragedia-del-libano-un-paese-che-muore\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-tragedia-del-libano-un-paese-che-muore\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-tragedia-del-libano-un-paese-che-muore\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Libano.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Libano.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-tragedia-del-libano-un-paese-che-muore\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La tragedia del Libano, un paese che muore\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La tragedia del Libano, un paese che muore - Rassegna Stampa Cattolica","description":"La tragedia del Libano, un paese che muore, raccontata e descritta in un reportage in tre puntate che descrive la disperata situazione","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-tragedia-del-libano-un-paese-che-muore\/","og_locale":"it_IT","og_type":"article","og_title":"La tragedia del Libano, un paese che muore - Rassegna Stampa Cattolica","og_description":"La tragedia del Libano, un paese che muore, raccontata e descritta in un reportage in tre puntate che descrive la disperata situazione","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-tragedia-del-libano-un-paese-che-muore\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2022-11-02T23:00:06+00:00","article_modified_time":"2024-02-14T16:15:18+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/06\/Libano.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"34 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-tragedia-del-libano-un-paese-che-muore\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-tragedia-del-libano-un-paese-che-muore\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"La tragedia del Libano, un paese che muore","datePublished":"2022-11-02T23:00:06+00:00","dateModified":"2024-02-14T16:15:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-tragedia-del-libano-un-paese-che-muore\/"},"wordCount":5044,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-tragedia-del-libano-un-paese-che-muore\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/06\/Libano.jpg","keywords":["Libano","paesi e continenti"],"articleSection":["Paesi e continenti"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-tragedia-del-libano-un-paese-che-muore\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-tragedia-del-libano-un-paese-che-muore\/","name":"La tragedia del Libano, un paese che muore - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-tragedia-del-libano-un-paese-che-muore\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-tragedia-del-libano-un-paese-che-muore\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/06\/Libano.jpg","datePublished":"2022-11-02T23:00:06+00:00","dateModified":"2024-02-14T16:15:18+00:00","description":"La tragedia del Libano, un paese che muore, raccontata e descritta in un reportage in tre puntate che descrive la disperata situazione","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-tragedia-del-libano-un-paese-che-muore\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-tragedia-del-libano-un-paese-che-muore\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-tragedia-del-libano-un-paese-che-muore\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/06\/Libano.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/06\/Libano.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-tragedia-del-libano-un-paese-che-muore\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"La tragedia del Libano, un paese che muore"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/54978","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=54978"}],"version-history":[{"count":3,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/54978\/revisions"}],"predecessor-version":[{"id":59623,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/54978\/revisions\/59623"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/47444"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=54978"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=54978"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=54978"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}