{"id":5493,"date":"2013-03-14T02:56:48","date_gmt":"2013-03-14T01:56:48","guid":{"rendered":""},"modified":"2015-05-25T09:26:57","modified_gmt":"2015-05-25T07:26:57","slug":"casaleggio-e-gaia-mondo-da-incubo","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/casaleggio-e-gaia-mondo-da-incubo\/","title":{"rendered":"Casaleggio e Gaia, mondo da incubo"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2013\/03\/Grillo_Casaleggio.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-25088\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2013\/03\/Grillo_Casaleggio.jpg\" alt=\"Grillo_Casaleggio\" width=\"200\" height=\"172\" \/><\/a>La Nuova Bussola Quotidiana<\/strong>, 13 marzo 2013<\/div>\n<p style=\"text-align: center;\">di <strong>Roberto Dal Bosco<\/strong><\/p>\n<p style=\"text-align: justify;\">Grillo e Casaleggio, Casaleggio e Grillo. Alla fine il Movimento 5 Stelle sono loro due. Ma se Beppe Grillo lo conosciamo ormai da molti anni, misteriosa \u00e8 invece la figura di Gianroberto Casaleggio, uscito allo scoperto soltanto alla viglia delle elezioni, che appare per\u00f2 come il vero guru del movimento. Ma per capire il suo credo e il suo progetto non c&#8217;\u00e8\u00a0miglior materiale se non il <strong><a href=\"http:\/\/www.youtube.com\/watch?v=JodFiwBlsYs\" target=\"_blank\">video Gaia<\/a><\/strong>, prodotto dalla Casaleggio e Associati. considerabile come il manifesto della sua idea dello sviluppo dell&#8217;umanit\u00e0 nell&#8217;era della rete.<\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\"><strong>I contenuti sono oramai noti:<\/strong> con sapiente uso di infografica, ci viene raccontato che nel 2020 scoppier\u00e0 la Terza Guerra Mondiale tra l&#8217;Occidente e la Russia, la Cina e il Medio-Oriente (identificato graficamente nel video con l&#8217;Iran, per la gioia del filo-iraniano, per parte di moglie e di suocera, Beppe Grillo): due blocchi separati esenzialmente dal fatto che in uno internet \u00e8 libero, nell&#8217;altro invece \u00e8 sotto controllo.<\/div>\n<p style=\"text-align: justify;\">Nell&#8217;immane conflitto, si far\u00e0 ampio uso di armi batteriologiche. Gli oceani si innalzeranno di 12 metri. La popolazione mondiale si ridurr\u00e0 ad un miliardo di persone. Nel 2040 la guerra finir\u00e0. Vincer\u00e0 il blocco occidentale, dove internet \u00e8 libero. Poi 2047 ad ogni abitante della terra sar\u00e0 assegnato un account su un social network mondiale a nome Earthlink. Infine nel 2054 ci saranno, le prime consultazioni globali via rete che eleggeranno Gaia, il governo mondiale. La proclamazione di Gaia sar\u00e0 il 14 agosto 2054.<\/p>\n<p style=\"text-align: justify;\"><strong>Si tratta di un semplice video di fantascientifica creativit\u00e0?<\/strong> Molti fatti, emersi ultimamente, dimostrano di no. Casaleggio e il fido Grillo (che anche in questo si dimostra sua goffa marionetta) all&#8217;apocalisse dei batteri narrata nel film Gaia ci credono veramente: abbiamo appreso questa settimana dall&#8217;articolo de <em>L&#8217;Espresso<\/em>, che il genovese stava investendo in Costa Rica nella creazione di un resort chiamato \u201cEcofeudo\u201d (marchio che gi\u00e0 tradisce l&#8217;appassionato ruolo che vi pu\u00f2 avere il Casaleggio, ecologista e cultore del medioevo cavalleresco).<\/p>\n<p style=\"text-align: justify;\">Sulle spiagge di quello che sino al 2009 era nelle black list dei paradisi fiscali, come prestanome lo pseudocognato tuttofare, il Grillo sta costruendo un villaggio vacanze composto da villette di lusso, ognuna ecologicamente concepita e dotata dell&#8217;immancabile wifi, nonch\u00e9 opportunamente attrezzata per resistere alla fine del mondo: \u00abOgni abitazione sar\u00e0 dotata di un bunker antiatomico fornito di particolari filtri depuratori progettati per difendersi da contaminazioni chimiche, biologiche e batteriologiche\u00bb &#8211; scrive il sito del progetto, aggiungendo che \u00abla propriet\u00e0, in posizione collinare, \u00e8 circondata da pendii e si trova a 155 metri sopra il livello del mare. Questa particolare dislocazione \u00e8 stata pensata per via del global warming che influenza e caratterizza un lento ma continuo aumento del livello del mare\u00bb.<\/p>\n<p style=\"text-align: justify;\">Nel video-manifesto di Casaleggio, si parlava puntualmente proprio di questo: \u00abuso di armi batteriologiche e innalzamento dei mari di 12 metri\u00bb a causa di cambiamenti climatici accelerati (attorno al minuto 5:00 del video).<\/p>\n<p style=\"text-align: justify;\"><strong>In pratica, l&#8217;idea dell&#8217;\u201cEcofeudo\u201d era quella di creare un rifugio<\/strong> che salvi i ricchi convenuti dall&#8217;apocalisse: come in una visione da survivalist della provincia USA, solo declinata nei sogni turistici dell&#8217;alta borghesia da cui provengono Casaleggio e Grillo.<\/p>\n<p style=\"text-align: justify;\"><strong>Non \u00e8 certo una novit\u00e0, che un movimento millenarista produca uno spazio fisico<\/strong> in cui salvarsi dalla mega-distruzione che invoca. Pensiamo per esempio al caso di Aum Shinrikyo, la setta giapponese che nel 1995 mise il gas sarin nella chikatetsu, il metr\u00f2 di Tokyo, uccidendo appena una decina di persone e intossicandone migliaia, ma mancando clamorosamente il piano di sterminare buona parte dell&#8217;umanit\u00e0 vivente nella conurbazione Tokyo-Chiba-Yokohama che si riversa nel metr\u00f2 all&#8217;ora di punta. Il Guru Asahara, il cui fine era scatenare una guerra mondiale da cui sarebbe emersa una umanit\u00e0 di sopravvissuti guidati unicamente da lui, aveva investito in terreni a Banjawarn Station, nel deserto Victoria, in Australia.<\/p>\n<p style=\"text-align: justify;\">L&#8217;appezzamento era pensato come rifugio per i membri della setta una volta partita l&#8217;apocalisse; secondo una voce sulla quale si sono interrogati anche i giornali australiani, il luogo sarebbe stato usato invece come una sorta di privato poligono nucleare per testare armi di distruzione totale che il movimento si stava procurando.<\/p>\n<p style=\"text-align: justify;\">Aum infatti si stava dotando di armi di ogni genere, dai mitragliatori al sarin, dai batteri di antrace (che us\u00f2 pure in precedenti attentati minori) al sogno di comprare nell&#8217;ex URSS eltiniana una testata atomica. Il guru Asahara alla luce del sole predicava l&#8217;arrivo dell&#8217;apocalisse, mentre nel segreto dei suoi templi cercava di provocarla nel concreto, produrla materialmente.<\/p>\n<p style=\"text-align: justify;\">Il libro che analizza meglio il fenomeno di Aum ha scritto il grande psichiatra americano Robert Jay Lifton, e si intitola <em>Destroy the World in order to save it<\/em>, \u201cDistruggi il mondo per salvarlo\u201d: potrebbe essere senza nemmeno un ritocco un nuovo slogan grillino. Secondo Lifton, la fase finale ultradistruttiva di Asahara fu innescata da una umiliazione elettorale: presentatosi alle elezioni del 1990, il partito di Aum raccolse tristemente meno voti di quanti fossero gli iscritti.<\/p>\n<p style=\"text-align: justify;\"><strong>Con Casaleggio, quindi, non c&#8217;\u00e8 al momento questo rischio,<\/strong> visto che queste elezioni le ha vinte. Rimangono altri punti di contatti con la storia di Asahara: apocalisse evocata e finanche desiderata, interesse per le armi di distruzione di massa specialmente batteriologiche, costruzione di un rifugio per l&#8217;\u00e9lite che guidi il mondo dei sopravvissuti.<\/p>\n<p style=\"text-align: justify;\"><strong>Su tutto, Asahara e Casaleggio si identificano per la centralit\u00e0 assoluta del proprio ego messianico<\/strong> rispetto alle sorti dell&#8217;umanit\u00e0. Alla faccia dell&#8217;\u00abognuno vale uno\u00bb che si sciroppano beotamente le masse di attivisti grillini, la prova della terrificante fantastia megalomaniaca di Casaleggio sta sempre nel video Gaia. Prendete le prime parole: \u00abGaia. Un Nuovo Ordine Mondiale \u00e8 nato oggi, il 14 agosto 2054\u00bb. In questa data nasce, dopo tanto dolore e distruzione, la nuova terra unita, senza pi\u00f9 guerre e divisione, con la democrazia elettronica a garantire ad aeternum l&#8217;et\u00e0 dell&#8217;oro dell&#8217;umanit\u00e0.<\/p>\n<p style=\"text-align: justify;\">Anche qui, con Casaleggio state attenti ai numeri: il 14 agosto 2054 sarebbe nella realt\u00e0 nientemeno che il centesimo compleanno di Casaleggio, che \u00e8 nato il 14 agosto 1954. Manca totalmente in rete, infatti, l&#8217;informazione sull&#8217;esatta data di nascita di Casaleggio, di cui sui siti compare solo l&#8217;anno (appunto, il 1954). Un pacifico sito che fa gli oroscopi, dichesegnosei.it, \u00e8 l&#8217;unico che ha cercato la data di nascita del guru, e dice che la data del 14 agosto 1954 gli arriva da una \u201cfonte sufficientemente attendibile\u201d.L&#8217;avvento del Nuovo Ordine Mondiale nasce nel centenario della nativit\u00e0 di Gianroberto Casaleggio.<\/p>\n<p style=\"text-align: justify;\">Basta questo per capire che dobbiamo davvero avere paura del potere in mano ad un simile personaggio?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Nuova Bussola Quotidiana, 13 marzo 2013 di Roberto Dal Bosco Grillo e Casaleggio, Casaleggio e Grillo. Alla fine il Movimento 5 Stelle sono loro due. Ma se Beppe Grillo lo conosciamo ormai da molti anni, misteriosa \u00e8 invece la figura di Gianroberto Casaleggio, uscito allo scoperto soltanto alla viglia delle elezioni, che appare per\u00f2 &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/casaleggio-e-gaia-mondo-da-incubo\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":25088,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[2152,2101],"class_list":["post-5493","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica-nazionale","tag-gianroberto-casaleggio","tag-m5s","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Casaleggio e Gaia, mondo da incubo - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/casaleggio-e-gaia-mondo-da-incubo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Casaleggio e Gaia, mondo da incubo - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/casaleggio-e-gaia-mondo-da-incubo\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2013-03-14T01:56:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-05-25T07:26:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2013\/03\/Grillo_Casaleggio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"242\" \/>\n\t<meta property=\"og:image:height\" content=\"208\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/casaleggio-e-gaia-mondo-da-incubo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/casaleggio-e-gaia-mondo-da-incubo\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Casaleggio e Gaia, mondo da incubo\",\"datePublished\":\"2013-03-14T01:56:48+00:00\",\"dateModified\":\"2015-05-25T07:26:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/casaleggio-e-gaia-mondo-da-incubo\\\/\"},\"wordCount\":1083,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/casaleggio-e-gaia-mondo-da-incubo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2013\\\/03\\\/Grillo_Casaleggio.jpg\",\"keywords\":[\"Gianroberto Casaleggio\",\"M5S\"],\"articleSection\":[\"Politica nazionale\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/casaleggio-e-gaia-mondo-da-incubo\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/casaleggio-e-gaia-mondo-da-incubo\\\/\",\"name\":\"Casaleggio e Gaia, mondo da incubo - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/casaleggio-e-gaia-mondo-da-incubo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/casaleggio-e-gaia-mondo-da-incubo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2013\\\/03\\\/Grillo_Casaleggio.jpg\",\"datePublished\":\"2013-03-14T01:56:48+00:00\",\"dateModified\":\"2015-05-25T07:26:57+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/casaleggio-e-gaia-mondo-da-incubo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/casaleggio-e-gaia-mondo-da-incubo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/casaleggio-e-gaia-mondo-da-incubo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2013\\\/03\\\/Grillo_Casaleggio.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2013\\\/03\\\/Grillo_Casaleggio.jpg\",\"width\":242,\"height\":208},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/casaleggio-e-gaia-mondo-da-incubo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Casaleggio e Gaia, mondo da incubo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Casaleggio e Gaia, mondo da incubo - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/casaleggio-e-gaia-mondo-da-incubo\/","og_locale":"it_IT","og_type":"article","og_title":"Casaleggio e Gaia, mondo da incubo - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/casaleggio-e-gaia-mondo-da-incubo\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2013-03-14T01:56:48+00:00","article_modified_time":"2015-05-25T07:26:57+00:00","og_image":[{"width":242,"height":208,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2013\/03\/Grillo_Casaleggio.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/casaleggio-e-gaia-mondo-da-incubo\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/casaleggio-e-gaia-mondo-da-incubo\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Casaleggio e Gaia, mondo da incubo","datePublished":"2013-03-14T01:56:48+00:00","dateModified":"2015-05-25T07:26:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/casaleggio-e-gaia-mondo-da-incubo\/"},"wordCount":1083,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/casaleggio-e-gaia-mondo-da-incubo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2013\/03\/Grillo_Casaleggio.jpg","keywords":["Gianroberto Casaleggio","M5S"],"articleSection":["Politica nazionale"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/casaleggio-e-gaia-mondo-da-incubo\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/casaleggio-e-gaia-mondo-da-incubo\/","name":"Casaleggio e Gaia, mondo da incubo - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/casaleggio-e-gaia-mondo-da-incubo\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/casaleggio-e-gaia-mondo-da-incubo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2013\/03\/Grillo_Casaleggio.jpg","datePublished":"2013-03-14T01:56:48+00:00","dateModified":"2015-05-25T07:26:57+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/casaleggio-e-gaia-mondo-da-incubo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/casaleggio-e-gaia-mondo-da-incubo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/casaleggio-e-gaia-mondo-da-incubo\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2013\/03\/Grillo_Casaleggio.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2013\/03\/Grillo_Casaleggio.jpg","width":242,"height":208},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/casaleggio-e-gaia-mondo-da-incubo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Casaleggio e Gaia, mondo da incubo"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/5493","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=5493"}],"version-history":[{"count":3,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/5493\/revisions"}],"predecessor-version":[{"id":25089,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/5493\/revisions\/25089"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/25088"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=5493"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=5493"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=5493"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}