{"id":5478,"date":"2013-03-07T00:46:19","date_gmt":"2013-03-06T23:46:19","guid":{"rendered":""},"modified":"2016-06-13T10:18:43","modified_gmt":"2016-06-13T08:18:43","slug":"la-nostra-speranza-in-qualcuno","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-nostra-speranza-in-qualcuno\/","title":{"rendered":"La nostra speranza &egrave; in Qualcuno"},"content":{"rendered":"<div style=\"text-align: justify;\"><em><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-34547\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2013\/03\/Italia.jpg\" alt=\"Italia\" width=\"240\" height=\"177\" \/>Proponiamo due articoli che sembrano contraddirsi, ma che, in fondo, si integrano. Il primo, che non \u00e8 di per s\u00e9 condivisibile senza l\u2019altro, descrive efficacemente una sensazione che \u2013 evidentemente \u2013 non \u00e8 solo nostra.<br \/>\n<\/em><\/div>\n<p style=\"text-align: center;\"><em>* * * <\/em><\/p>\n<p style=\"text-align: center;\"><!--more--><\/p>\n<p style=\"text-align: center;\"><strong>Il Giornale<\/strong> mercoled\u00ec 6 marzo 2013<\/p>\n<p style=\"text-align: center;\"><strong>L&#8217;apocalisse senza rivoluzione<\/strong><\/p>\n<p style=\"text-align: justify;\"><em>E&#8217; grave; terribile assistere inermi alla catastrofe del tuo Paese, anzi, sentirti dentro la barca che affonda, persino a due passi dall&#8217;epicentro<\/em><\/p>\n<p style=\"text-align: center;\"><strong>Marcello Veneziani<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00c8 terribile assistere inermi alla catastrofe del tuo Paese, anzi, sentirti dentro la barca che affonda, persino a due passi dall&#8217;epicentro, tra le sedi vacanti del Potere e non scorgere neanche un segnale di svolta. Ti accorgi che dopo lunghe tempeste e lugubri annunci, ora stiamo veramente inabissandoci e non vedi l&#8217;ombra di una reazione n\u00e9 una via di uscita. La corruzione stavolta non \u00e8 pi\u00f9 affare penale; \u00e8 la corruzione che altera i corpi senza vita.<\/p>\n<p style=\"text-align: justify;\">Non \u00e8 malaffare ma putrefazione.<\/p>\n<p style=\"text-align: justify;\">La scena \u00e8 divisa tra vecchi rottami e rottamatori del vecchio, non c&#8217;\u00e8 nessuno che rappresenti davvero il nuovo, che abbia l&#8217;ardore del nuovo, la fresca energia unita alla precisa determinazione; e non solo la demolizione del vecchio. E a rovescio, non c&#8217;\u00e8 nemmeno chi rappresenta il permanente, la sicurezza affidabile di una continuit\u00e0 oltre il tempo; persino il massimo custode della tradizione ha rinunciato all&#8217;impresa, lo Spirito Santo non copre pi\u00f9 i sinistri oltre una certa et\u00e0. Senti aria di apocalisse nelle strade di Roma; apocalisse gaia, almeno quando occhieggia la primavera.<\/p>\n<p style=\"text-align: justify;\">Qualche traccia della dolcezza di vivere, che qui fu di casa, ancora si affaccia negli anfratti, nelle osterie e sui terrazzi. Ma si avverte che stavolta ci siamo, non si pu\u00f2 sfuggire. Il Paese collassa, l&#8217;aria \u00e8 satura e il clima \u00e8 propizio per una rivoluzione, per un nuovo ordine e perfino una nuova religione. Se solo ci fosse una sparuta schiera di valorosi che pensi in grande e agisca di conseguenza&#8230; Urgono veri conservatori e\/o veri rivoluzionari.<\/p>\n<p style=\"text-align: center;\">_______________________<\/p>\n<p style=\"text-align: center;\"><strong>La Nuova Bussola<\/strong> <strong>quotidiana<\/strong> 5 marzo 2013<\/p>\n<p style=\"text-align: center;\"><strong>La nostra speranza \u00e8 in Qualcuno<\/strong><\/p>\n<p style=\"text-align: center;\">di Piero Gheddo<\/p>\n<p style=\"text-align: justify;\">In questi giorni oscuri e tormentati sto rileggendo e meditando l\u2019enciclica del nostro amato padre e Papa Benedetto \u201cSpe salvi\u201d (del 2007), per ritrovare anch\u2019io, prete da 60 anni, la forza e la gioia della speranza cristiana. S\u00ec, perch\u00e9 noi italiani, con tutte le sofferenze, i crimini, i fallimenti, le povert\u00e0 che vediamo attorno a noi, manchiamo di speranza. Siamo non solo preoccupati ma angosciati, pessimisti, a volte disperati o quasi. I nostri discorsi sono volti al peggio, i nostri giornali e telegiornali pare che non diano alcuna speranza di poter vedere la fine dei molti ingorghi di urgenze ed emergenze il cui la nostra cara Patria \u00e8 precipitata.<\/p>\n<p style=\"text-align: justify;\">E allora, ricorriamo a una delle tre encicliche di Papa Benedetto che tratta proprio della Speranza. Il testo latino dell\u2019enciclica inizia con queste parole: \u201cSpe salvi facti sumus\u201d (Nella speranza siamo stati salvati) e si riferisce alla prima enciclica \u201cDeus Caritas est\u201d, Dio \u00e8 Amore, Dio ci ha creati e ci ama sempre, anche nella situazione drammatica in cui ci troviamo.<\/p>\n<p style=\"text-align: justify;\">\u201cSpe salvi\u201d tratta il tema che la fede d\u00e0 la speranza della Vita eterna con Dio, ma ci conforta e sostiene anche nella vita terrena in questo mondo. In altre parole: senza la speranza che Dio che \u00e8 Amore d\u00e0 all\u2019uomo, l\u2019uomo stesso non pu\u00f2 vivere bene, perch\u00e9, come scrive il Papa: \u201cSolo quando il futuro \u00e8 realt\u00e0 positiva, diventa vivibile anche il presente\u2026 Chi ha speranza vive diversamente, gli \u00e8 donata una vita nuova\u201d (n. 2). Il cristianesimo non \u00e8 solo comunicazione della \u201cBuona Notizia\u201d, ma infusione della forza della Fede e della Speranza cristiana, che non \u00e8 \u201cin qualcosa\u201d, ma \u201cin Qualcuno\u201d.<\/p>\n<p style=\"text-align: justify;\">E Papa Benedetto, per concretizzare queste parole, porta l\u2019esempio del nostro Salvatore. Nel mondo in cui viveva Ges\u00f9 vigeva la schiavit\u00f9. Le persone venivano comperate e vendute al mercato degli schiavi ed erano del tutto nelle mani dei loro padroni. Situazioni orrende, spaventose, certo molto peggiori della nostra. \u201cGes\u00f9 Cristo \u2013 scrive Benedetto XVI &#8211; non era Spartaco o Barabba, non era un combattente per una liberazione politica\u201d.<\/p>\n<p style=\"text-align: justify;\">Anzi \u201c\u00e8 morto Egli stesso in Croce\u201d; ma ci ha condotti all\u2019\u201cincontro con il Dio vivente e cos\u00ec l\u2019incontro con una speranza che era pi\u00f9 forte delle sofferenze della schiavit\u00f9 e che per questo trasformava dal di dentro la vita e il mondo\u2026 Anche se le strutture esterne rimanevano le stesse, questo cambiava la societ\u00e0 dal di dentro\u201d (n. 4).<\/p>\n<p style=\"text-align: justify;\">L\u2019enciclica cita anche l\u2019esempio pi\u00f9 attuale di Giuseppina Bakhita, nata nel 1869 nel Darfur, in Sudan. \u201cAll\u2019et\u00e0 di nove anni &#8211; \u201cSpe Salvi\u201d (n. 3) &#8211; venne rapita da trafficanti di schiavi e venduta cinque volte sui mercati del Sudan. L\u2019ultima volta era al servizio della madre e della moglie di un generale e ogni giorno veniva fustigata a sangue, per tutta la vita le rimasero sul corpo 144 cicatrici\u201d.<\/p>\n<p style=\"text-align: justify;\">Nel 1882 \u00e8 comperata dal console italiano Callisto Legnani. Aveva sempre avuto \u201cpadroni che la maltrattavano e la disprezzavano o, nel migliore dei casi, la consideravano una schiava utile. Ora per\u00f2 sente dire che esiste un Padrone al di sopra di tutti i padroni, il Signore di tutti i Signori, e che questo Signore \u00e8 buono, \u00e8 la bont\u00e0 in persona e che ama anche lei. Anche lei \u00e8 amata, e proprio dal Padrone supremo, davanti al quale tutti gli altri padroni sono essi stessi soltanto miseri servi\u201d.<\/p>\n<p style=\"text-align: justify;\">Cos\u00ec Bakhita scopre la Speranza cristiana e quando Legnani torna in Italia, la ragazzina gli chiede di portare anche lei nel suo paese. Cos\u00ec arriva a Venezia ed \u00e8 affidata alle Suore Canossiane, che la curano, le vogliono bene e la educano nella Fede cristiana.\u00a0 Battezzata nel 1890, diventa suora Canossiana nel 1896, muore a Schio (Vicenza) l\u20198 febbraio 1947, dopo una lunga e dolorosa malattia.<\/p>\n<p style=\"text-align: justify;\">E\u2019 canonizzata nel 2000 da Giovanni Paolo II.\u00a0 Benedetto XVI conclude che Bakhita, \u201ccerc\u00f2 in vari viaggi in Italia soprattutto di sollecitare alla missione. La liberazione che aveva ricevuto mediante l\u2019incontro con il Dio di Ges\u00f9 Cristo, sentiva di doverla estendere, doveva essere donata anche ad altri, al maggior numero possibile. La speranza che era nata in lei e l\u2019aveva redenta, non poteva tenerla per s\u00e9 questa speranza, doveva raggiungere molti, raggiungere tutti\u201d.<\/p>\n<p style=\"text-align: justify;\">Speriamo, e preghiamo, che raggiunga anche tutti noi italiani e ci ridoni il sorriso e la Speranza di un futuro migliore. Per noi uomini \u00e8 difficile, ma nulla \u00e8 impossibile a Dio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Proponiamo due articoli che sembrano contraddirsi, ma che, in fondo, si integrano. Il primo, che non \u00e8 di per s\u00e9 condivisibile senza l\u2019altro, descrive efficacemente una sensazione che \u2013 evidentemente \u2013 non \u00e8 solo nostra. * * *<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-nostra-speranza-in-qualcuno\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":34547,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[1571],"class_list":["post-5478","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chiesa","tag-spe-salvi","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La nostra speranza &egrave; in Qualcuno - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-nostra-speranza-in-qualcuno\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La nostra speranza &egrave; in Qualcuno - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-nostra-speranza-in-qualcuno\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2013-03-06T23:46:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-06-13T08:18:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2013\/03\/Italia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"262\" \/>\n\t<meta property=\"og:image:height\" content=\"193\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-nostra-speranza-in-qualcuno\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-nostra-speranza-in-qualcuno\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"La nostra speranza &egrave; in Qualcuno\",\"datePublished\":\"2013-03-06T23:46:19+00:00\",\"dateModified\":\"2016-06-13T08:18:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-nostra-speranza-in-qualcuno\\\/\"},\"wordCount\":1053,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-nostra-speranza-in-qualcuno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2013\\\/03\\\/Italia.jpg\",\"keywords\":[\"Spe salvi\"],\"articleSection\":[\"Chiesa\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-nostra-speranza-in-qualcuno\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-nostra-speranza-in-qualcuno\\\/\",\"name\":\"La nostra speranza &egrave; in Qualcuno - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-nostra-speranza-in-qualcuno\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-nostra-speranza-in-qualcuno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2013\\\/03\\\/Italia.jpg\",\"datePublished\":\"2013-03-06T23:46:19+00:00\",\"dateModified\":\"2016-06-13T08:18:43+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-nostra-speranza-in-qualcuno\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-nostra-speranza-in-qualcuno\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-nostra-speranza-in-qualcuno\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2013\\\/03\\\/Italia.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2013\\\/03\\\/Italia.jpg\",\"width\":262,\"height\":193},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-nostra-speranza-in-qualcuno\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La nostra speranza &egrave; in Qualcuno\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La nostra speranza &egrave; in Qualcuno - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-nostra-speranza-in-qualcuno\/","og_locale":"it_IT","og_type":"article","og_title":"La nostra speranza &egrave; in Qualcuno - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-nostra-speranza-in-qualcuno\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2013-03-06T23:46:19+00:00","article_modified_time":"2016-06-13T08:18:43+00:00","og_image":[{"width":262,"height":193,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2013\/03\/Italia.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-nostra-speranza-in-qualcuno\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-nostra-speranza-in-qualcuno\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"La nostra speranza &egrave; in Qualcuno","datePublished":"2013-03-06T23:46:19+00:00","dateModified":"2016-06-13T08:18:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-nostra-speranza-in-qualcuno\/"},"wordCount":1053,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-nostra-speranza-in-qualcuno\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2013\/03\/Italia.jpg","keywords":["Spe salvi"],"articleSection":["Chiesa"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-nostra-speranza-in-qualcuno\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-nostra-speranza-in-qualcuno\/","name":"La nostra speranza &egrave; in Qualcuno - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-nostra-speranza-in-qualcuno\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-nostra-speranza-in-qualcuno\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2013\/03\/Italia.jpg","datePublished":"2013-03-06T23:46:19+00:00","dateModified":"2016-06-13T08:18:43+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-nostra-speranza-in-qualcuno\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-nostra-speranza-in-qualcuno\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-nostra-speranza-in-qualcuno\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2013\/03\/Italia.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2013\/03\/Italia.jpg","width":262,"height":193},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-nostra-speranza-in-qualcuno\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"La nostra speranza &egrave; in Qualcuno"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/5478","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=5478"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/5478\/revisions"}],"predecessor-version":[{"id":34548,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/5478\/revisions\/34548"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/34547"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=5478"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=5478"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=5478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}