{"id":54622,"date":"2022-09-01T00:00:53","date_gmt":"2022-08-31T22:00:53","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=54622"},"modified":"2024-03-15T10:16:32","modified_gmt":"2024-03-15T09:16:32","slug":"lautocensura-delloccidente-di-fronte-allislam-e-non-solo","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lautocensura-delloccidente-di-fronte-allislam-e-non-solo\/","title":{"rendered":"L&#8217;autocensura dell&#8217;Occidente di fronte all&#8217;Islam e non solo"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-54623 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/08\/attentato_Rushdie_islam-300x200.jpg\" alt=\"\" width=\"317\" height=\"211\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/08\/attentato_Rushdie_islam-300x200.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/08\/attentato_Rushdie_islam-768x513.jpg 768w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/08\/attentato_Rushdie_islam.jpg 962w\" sizes=\"auto, (max-width: 317px) 100vw, 317px\" \/>Abstract: <\/strong><em>L&#8217;autocensura dell&#8217;Occidente di fronte all&#8217;Islam e non solo. Oggi la nostra cultura \u00e8 dominata da coloro che danno credito all&#8217;idea che parole, arte, libri per bambini o editoriali siano la stessa cosa della violenza. Siamo cos\u00ec abituati a questa visione del mondo e a ci\u00f2 che richiede \u2013 scusarsi, umiliare, cancellare, umiliare ancora un po&#8217; \u2013 che non ce ne accorgiamo pi\u00f9\u201d.<\/em><\/span><!--more--><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/meotti.substack.com\/\" target=\"_blank\" rel=\"noopener\"><strong>Newsletter <\/strong>di Giulio Meotti\u00a0 <\/a><\/span><span style=\"color: #000000;\">16 Agosto 2022<\/span><\/p>\n<h3 style=\"text-align: center;\"><span style=\"color: #000000;\">Quello schizzo di sangue sulla nostra cultura, <\/span><\/h3>\n<h3 style=\"text-align: center;\"><span style=\"color: #000000;\">ridotta a pagina bianca\u00a0\u00a0<\/span><\/h3>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><em>Vaniloqui, depistaggi e perifrasi del mainstream su Rushdie sono solo fumo negli occhi. Autocensura, punizioni e pensiero unico sono invece la regola in Occidente (e non solo sull&#8217;Islam)<\/em><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\">di <strong>Giulio Meotti<\/strong><\/span><\/p>\n<div id=\"attachment_54624\" style=\"width: 177px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-54624\" class=\"wp-image-54624 size-full\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/08\/Salman_Rushdie_islam.jpg\" alt=\"\" width=\"177\" height=\"284\" \/><p id=\"caption-attachment-54624\" class=\"wp-caption-text\">Salman Rushdie<\/p><\/div>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Parlando alla <em>Bbc<\/em>, l&#8217;editorialista inglese<\/span> <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/www.nytimes.com\/2022\/08\/15\/arts\/salman-rushdie-free-speech.html?utm_source=substack&amp;utm_medium=email\" target=\"_blank\" rel=\"noreferrer noopener\">Kenan Malik<\/a><\/span> <span style=\"color: #000000;\">ha detto che se i critici di Salman Rushdie hanno \u201cperso la battaglia\u201d, hanno invece \u201cvinto la guerra\u201d. \u201cIl romanzo, &#8216;I versetti satanici&#8217;, continua a essere pubblicato. Ma l&#8217;argomento che \u00e8 sbagliato offendere determinate persone e gruppi \u00e8 diventato molto diffuso. In una certa misura si potrebbe dire che la societ\u00e0 ha interiorizzato la fatwa e introdotto una forma di autocensura\u201d. Lo scrittore americano David Rieff nelle stesse ore ha aggiunto: \u201cA Rushdie oggi verrebbe detto che le \u2018parole sono violenza\u2019, proprio come diceva la fatwa\u201d.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Spiega la brava<\/span> <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/www.commonsense.news\/p\/we-ignored-salman-rushdies-warning?utm_source=substack&amp;utm_medium=email\" target=\"_blank\" rel=\"noreferrer noopener\"><span style=\"color: #0000ff;\">Bari Weiss<\/span><\/a><\/span> <span style=\"color: #000000;\">nella sua newsletter che \u201cviviamo in una cultura in cui molte delle persone pi\u00f9 celebri che occupano i posti pi\u00f9 alti credono che le parole siano violenza. Hanno molto in comune con l&#8217;ayatollah Khomeini, che ha emesso la fatwa contro Salman Rushdie nel 1989, e con Hadi Matar, che ha adempiuto al suo comando quando ha accoltellato Rushdie su un palcoscenico a New York. Il primo gruppo crede di essere motivato dall&#8217;inclusione e dalla tolleranza e che \u00e8 possibile creare una societ\u00e0 utopica in cui nessuno si offende mai. I secondi li riconosciamo tutti come fanatici religiosi.<br \/>\n<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-31085 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/11\/politically-correct.jpg\" alt=\"\" width=\"276\" height=\"183\" \/>Ma \u00e8 l&#8217;indulgenza e la codardia di chi pensa che le \u2018parole sono violente\u2019 che ha rafforzato i secondi e ci ha portato qui, a un fanatico che si precipita sul palco di una conferenza letteraria con un coltello e lo affonda in uno degli scrittori pi\u00f9 coraggiosi del mondo. Oggi la nostra cultura \u00e8 dominata da coloro che danno credito all&#8217;idea che parole, arte, libri per bambini o editoriali siano la stessa cosa della violenza. Siamo cos\u00ec abituati a questa visione del mondo e a ci\u00f2 che richiede \u2013 scusarsi, umiliare, cancellare, umiliare ancora un po&#8217; \u2013 che non ce ne accorgiamo pi\u00f9\u201d.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><a href=\"https:\/\/www.youtube.com\/watch?v=IoPkT8JQj-I\" target=\"_blank\" rel=\"noopener noreferrer\"> <img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-54625 aligncenter\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/08\/video-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/08\/video-300x169.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/08\/video.jpg 550w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Basta pensare che soltanto a maggio il comico<\/span> <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/www.nbcnews.com\/news\/us-news\/man-suspected-attacking-dave-chappelle-stage-says-show-was-triggering-rcna30057?utm_source=substack&amp;utm_medium=email\" target=\"_blank\" rel=\"noreferrer noopener\">Dave Chappelle <\/a><\/span><span style=\"color: #000000;\">\u00e8 stato aggredito e buttato a terra mentre si esibiva a Los Angeles. L\u2019aggressore aveva con s\u00e9 una pistola giocattolo e un coltello all&#8217;interno. Qual \u00e8 la \u201ccolpa\u201d di Chappelle? Aver irriso l\u2019ideologia transgender. Se non bastasse, dopo l\u2019attacco lo show di Chapelle \u00e8 stato<\/span><span style=\"color: #0000ff;\"> <a style=\"color: #0000ff;\" href=\"https:\/\/www.bbc.com\/news\/entertainment-arts-62249771?utm_source=substack&amp;utm_medium=email\" target=\"_blank\" rel=\"noreferrer noopener\">cancellato<\/a> <\/span><span style=\"color: #000000;\">in un atto di incredibile autocensura da parte di alcuni teatri americani.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-41258 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/10\/Travaglio_Saviano.jpg\" alt=\"\" width=\"290\" height=\"174\" \/>Per questo non lasciamoci ingannare dai vaniloqui alla Roberto Saviano e degli altri corifei della stampa mainstream e dalle perifrasi ipocrite di condanna su Rushdie. &#8220;Nessuno oggi avrebbe le palle per scrivere &#8216;I versetti satanici&#8217;, per non parlare di pubblicarlo&#8221;, ha detto lo scrittore<\/span> <a href=\"https:\/\/www.prospectmagazine.co.uk\/magazine\/kureishiontherushdieaffair?utm_source=substack&amp;utm_medium=email\" target=\"_blank\" rel=\"noreferrer noopener\"><span style=\"color: #0000ff;\">Hanif<\/span> <span style=\"color: #0000ff;\">Kureishi<\/span><\/a><span style=\"color: #0000ff;\">.<\/span> <span style=\"color: #000000;\">&#8220;Gli scrittori sono terrorizzati&#8221;. Il compianto filosofo<\/span> <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/www.thetimes.co.uk\/article\/government-sacks-sir-roger-scruton-over-soros-and-islamophobia-remarks-f3r833n38?utm_source=substack&amp;utm_medium=email\" target=\"_blank\" rel=\"noreferrer noopener\">Roger Scruton<\/a><\/span> <span style=\"color: #000000;\">prima di morire venne licenziato da un comitato governativo per aver affermato che la parola &#8220;islamofobia&#8221; \u00e8 stata inventata dai Fratelli Musulmani. E come biasimare il nostro silenzio? Un celebre artista britannico,<\/span> <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/www.thetimes.co.uk\/article\/artists-too-frightened-to-tackle-radical-islam-v926dqnrfz7?utm_source=substack&amp;utm_medium=email\" target=\"_blank\" rel=\"noreferrer noopener\">Grayson Perry<\/a><\/span>, <span style=\"color: #000000;\">ha confessato di essersi censurato per non fare la fine di Theo van Gogh.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"> &#8220;Mi sono censurato&#8221;, ha detto Perry. &#8220;La ragione per cui non ho pi\u00f9 attaccato l&#8217;islamismo nelle mie opere \u00e8 che nutro una paura reale di finire con la gola tagliata&#8221;. I Liberal-democratici inglesi<\/span> <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/metro.co.uk\/2019\/04\/18\/lib-dem-candidate-suspended-comments-muslims-9243430\/?utm_source=substack&amp;utm_medium=email\" target=\"_blank\" rel=\"noreferrer noopener\">hanno sospeso<\/a><\/span> <span style=\"color: #000000;\">il candidato D\u00e1niel T\u00f3th-Nagy per aver affermato che &#8220;l&#8217;islamofobia non esiste&#8221; e aver scritto: &#8220;E le mutilazioni genitali femminili? I delitti d&#8217;onore? I matrimoni forzati? Cosa ne pensa delle proteste delle donne in Iran, in Arabia Saudita e in altri paesi islamici contro l&#8217;uso obbligatorio dell&#8217;hijab? E la Sharia in Gran Bretagna?&#8221;. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-54628 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/09\/stampa_giornali-300x169.jpg\" alt=\"\" width=\"353\" height=\"199\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/09\/stampa_giornali-300x169.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/09\/stampa_giornali.jpg 640w\" sizes=\"auto, (max-width: 353px) 100vw, 353px\" \/>Il<\/span> <em><a href=\"https:\/\/www.bbc.com\/news\/uk-scotland-33474347?utm_source=substack&amp;utm_medium=email\" target=\"_blank\" rel=\"noreferrer noopener\"><span style=\"color: #0000ff;\">West Highland Free Press<\/span><\/a><\/em> <span style=\"color: #000000;\">\u00e8 un quotidiano scozzese di sinistra. Brian Wilson, ex dirigente del Labour ed ex ministro di Tony Blair, \u00e8 stato messo alla porta dal <em>West Highland Free Press <\/em>dopo averci scritto per 38 dei 43 anni di vita del giornale, da quando Wilson lo fond\u00f2 nel 1972. Cacciato per aver difeso un collega, il professor Donald Macleod, che aveva osato scrivere di Islam. La prima testa a rotolare in questa vicenda \u00e8 stata quella di Donald Macleod, reo di aver firmato un articolo sulla trasformazione dell\u2019Europa. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">\u201cLa nostra libert\u00e0 non potr\u00e0 mai sopravvivere sotto un Islam dominante. Nessun paese musulmano al mondo garantisce diritti civili o la libert\u00e0 di parola ai cittadini. In Arabia Saudita, nessuna donna pu\u00f2 guidare la macchina. E nei paesi della cosiddetta \u2018primavera araba\u2019, la primavera si \u00e8 trasformata rapidamente in inverno\u201d. E ancora: \u201cAbbiamo barriere intellettuali, ideologiche o spirituali da sollevare nei confronti dell\u2019Islam? L\u2019umanesimo dominante \u00e8 troppo impegnato a odiare il Cristianesimo, che in molte parti della Gran Bretagna \u00e8 diventato invisibile. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-54430 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/07\/Katholikentag_2022_Germania_chiesa-1.jpg\" alt=\"\" width=\"194\" height=\"259\" \/>La Chiesa si \u00e8 ritirata, lasciando un vuoto religioso, e una generazione spiritualmente senza spina dorsale. Sono deliri apocalittici di un cervello invecchiato? Forse, ma prendiamo in considerazione Agostino, la pi\u00f9 grande mente cristiana che il mondo abbia mai visto. Nato in Algeria, divenne vescovo di Ippona (in Algeria) nel 396. Il Cristianesimo sembrava al sicuro per i tempi a venire. Ma nel 622 Maometto si \u00e8 stabilito a Medina, e un centinaio di anni pi\u00f9 tardi il Cristianesimo \u00e8 stato cancellato in Algeria.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"> La diocesi di Agostino era stata semplicemente sopraffatta da un esercito musulmano. La storia non deve ripetersi. Ma dormire da ritti \u00e8 la strada verso la perdita di tutte le nostre libert\u00e0\u201d. Macleod ha perso il posto. Quando l\u2019ex direttore Wilson lo ha scoperto ha deciso di usare la sua rubrica per difendere l\u2019ex collega, definendo il suo articolo \u201cil pi\u00f9 erudito, ben scritto e intellettualmente stimolante del giornalismo inglese\u201d. E anche lui \u00e8 stato cancellato.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"> <img loading=\"lazy\" decoding=\"async\" class=\"wp-image-54629 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/09\/computer_tecnologia-300x188.jpg\" alt=\"\" width=\"332\" height=\"208\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/09\/computer_tecnologia-300x188.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/09\/computer_tecnologia-595x375.jpg 595w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/09\/computer_tecnologia.jpg 600w\" sizes=\"auto, (max-width: 332px) 100vw, 332px\" \/>Il presidente del Pen America al<\/span> <em><a href=\"https:\/\/www.nytimes.com\/2022\/08\/15\/arts\/salman-rushdie-free-speech.html?utm_source=substack&amp;utm_medium=email\" target=\"_blank\" rel=\"noreferrer noopener\"><span style=\"color: #0000ff;\">New York Times<\/span><\/a><\/em> <span style=\"color: #000000;\">di oggi afferma che per molti difendere Rushdie pu\u00f2 essere facile, scontato, retorico, ma la difesa &#8220;deve applicarsi anche dove abbiamo meno unanimit\u00e0. Questo \u00e8 ci\u00f2 che significa avere un principio&#8221;. Sante parole. Ma autodaf\u00e9, autocensura, repressione e pensiero unico sono la regola in Occidente (e non solo sull&#8217;Islam). <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">\u201cI limiti di quello che si pu\u00f2 dire senza timore di ritorsioni si sono assottigliati\u201d, recita la<\/span> <a href=\"https:\/\/www.theguardian.com\/books\/2020\/jul\/08\/jk-rowling-rushdie-and-atwood-warn-against-intolerance-in-open-letter?utm_source=substack&amp;utm_medium=email\">f<span style=\"color: #0000ff;\">amosa lettera pubblicata su <em>Harper\u2019s<\/em><\/span><\/a> <span style=\"color: #000000;\">contro la <em>cancel culture<\/em>e \u00a0firmata proprio da Salman Rushdie e da J.K. Rowling. \u201cStiamo gi\u00e0 pagandone il prezzo, in termini di minore propensione al rischio tra gli scrittori, gli artisti e i giornalisti che sono preoccupati di perdere il lavoro se si allontanano dal consenso generale, o anche solo se non dimostrano sufficiente entusiasmo nel dirsi d\u2019accordo\u201d. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-50717 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/04\/cancel_culture_sinistra.jpg\" alt=\"\" width=\"296\" height=\"212\" \/>Thomas Chatterton Williams, il giornalista e scrittore che ha organizzato la lettera su <em>Harper\u2019s<\/em>, ha detto a<\/span> <span style=\"color: #0000ff;\"><em><a style=\"color: #0000ff;\" href=\"https:\/\/www.philomag.com\/articles\/thomas-chatterton-williams-je-crains-quune-generation-dintellectuels-et-dartistes-se?utm_source=substack&amp;utm_medium=email\" target=\"_blank\" rel=\"noreferrer noopener\">Philosophe Magazine<\/a><\/em>:<\/span> <span style=\"color: #000000;\">\u201cUn clima di terrore ha pervaso la sfera culturale, le universit\u00e0, l&#8217;industria cinematografica, l&#8217;editoria. Se il tuo lavoro \u00e8 ritenuto politicamente scorretto, puoi, da un giorno all&#8217;altro, essere \u2018cancellato\u2019, inserito nella lista nera, senza avere la possibilit\u00e0 di difenderti. Una generazione di intellettuali e artisti si trova paralizzata da questo clima\u201d.\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"> La paura di dire e pensare \u00e8 talmente pervasiva che il governo francese \u00e8 arrivato a mettere la censura agli spot con bambini affetti da sindrome di Down, racconta il<\/span> <span style=\"color: #0000ff;\"><em><a style=\"color: #0000ff;\" href=\"https:\/\/www.wsj.com\/articles\/frances-war-on-anti-abortion-speech-1480552815?utm_source=substack&amp;utm_medium=email\" target=\"_blank\" rel=\"noreferrer noopener\">Wall Street Journal.<\/a><\/em><\/span> <span style=\"color: #000000;\">E un sondaggio<\/span> <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/www.rtl.fr\/actu\/debats-societe\/samuel-paty-1-enseignant-sur-4-n-approuve-pas-son-choix-de-montrer-les-caricatures-7800951157?utm_source=substack&amp;utm_medium=email\" target=\"_blank\" rel=\"noreferrer noopener\">rivela<\/a><\/span> <span style=\"color: #000000;\">il livello di autocensura tra gli insegnanti francesi sull\u2019Islam. Per evitare possibili incidenti, un docente su due ammette di autocensurarsi in classe.<\/span> <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/ionainstitute.ie\/news-roundup\/professor-in-sweden-under-investigation-for-teaching-biological-differences-between-men-women\/?utm_source=substack&amp;utm_medium=email\" target=\"_blank\" rel=\"noreferrer noopener\">Germund Hesslow<\/a>,<\/span> <span style=\"color: #000000;\">professore di neurofisiologia a Lund, in Svezia, \u00e8 finito sotto inchiesta per avere affermato che \u201cesistono differenze biologiche tra maschi e femmine\u201d. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-42536 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/03\/Antonio_Gramsci.jpg\" alt=\"\" width=\"308\" height=\"231\" \/>Un dibattito organizzato sul libro della filosofa Sabine Prokhoris, critica del MeToo, \u00e8 stato cancellato dalla facolt\u00e0 Cartesio di Parigi. &#8220;#MeToo: irragionevolezza collettiva, panico sessuale&#8221;. Questo il titolo del dibattito attorno al libro di Prokhoris <em>Le Mirage #MeToo<\/em>. Prokhoris, parlando con il settimanale<\/span> <span style=\"color: #0000ff;\"><em><a style=\"color: #0000ff;\" href=\"https:\/\/www.marianne.net\/societe\/education\/un-debat-sur-les-derives-de-metoo-annule-au-dernier-moment-par-la-fac-necker?utm_source=substack&amp;utm_medium=email\" target=\"_blank\" rel=\"noreferrer noopener\">Marianne,<\/a><\/em> <\/span><span style=\"color: #000000;\">dice che \u201coggi siamo di fronte a un programma metapolitico, per usare un termine derivato da Gramsci: una minoranza si sta diffondendo nell&#8217;opinione pubblica, conquistando le \u00e9lite intellettuali e prendendo il potere nelle istituzioni\u201d.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Ha ragione la filosofa francese Elisabeth Badinter quando a<\/span> <em><a href=\"https:\/\/www.lexpress.fr\/actualite\/idees-et-debats\/elisabeth-badinter-privilege-blanc-racises-c-est-la-naissance-d-un-nouveau-racisme_2128325.html?xtatc=INT-135-%5Bbloc_article_suivant_abonne_connecte%5D&amp;utm_source=substack&amp;utm_medium=email\" target=\"_blank\" rel=\"noreferrer noopener\"><span style=\"color: #0000ff;\">L\u2019Express<\/span><\/a><\/em> <span style=\"color: #000000;\">dichiara che \u201cc\u2019\u00e8 paura di essere ridicolizzati per aver dato una piattaforma a questa o a quell&#8217;idea. Una minoranza sta imponendo la sua legge alla maggioranza: la legge del silenzio. Quando, per paura di offendere, di scioccare, di dispiacere, una societ\u00e0 \u00e8 costretta al silenzio, questo \u00e8 un veleno. \u00c8 un male che rode la cultura occidentale\u201d. In America sono arrivati a censurare persino<\/span> <span style=\"color: #0000ff;\"><em><a style=\"color: #0000ff;\" href=\"https:\/\/variety.com\/2020\/digital\/news\/gone-with-the-wind-hbo-max-disclaimer-horrors-slavery-1234648726\/?utm_source=substack&amp;utm_medium=email\" target=\"_blank\" rel=\"noreferrer noopener\">Via col vento<\/a><\/em>,<\/span><span style=\"color: #000000;\"> in odore di \u201crazzismo\u201d.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-47864 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/07\/Usa_confederazione_secessione.jpg\" alt=\"\" width=\"268\" height=\"213\" \/>Non si pu\u00f2 dichiarare che si nasce maschi e femmine e che il genere non cancella il sesso (\u201dtransofobo\u201d), che l\u2019Islam ha qualche problema con la convivenza e con l\u2019Occidente (\u201cislamofobo\u201d), che il matrimonio \u00e8 fra un uomo e una donna (\u201comofobi\u201d) e cos\u00ec via. I<\/span>l <span style=\"color: #0000ff;\"><em><a style=\"color: #0000ff;\" href=\"https:\/\/www.wsj.com\/articles\/americas-jacobin-moment-11592867349?utm_source=substack&amp;utm_medium=email\" target=\"_blank\" rel=\"noreferrer noopener\">Wall Street Journal<\/a><\/em><\/span> <span style=\"color: #000000;\">lo chiama \u201cmomento giacobino. La ghigliottina non \u00e8 in uso, ma l\u2019impulso \u00e8 lo stesso a distruggere\u201d.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/www.nytimes.com\/2020\/06\/24\/arts\/design\/met-museum-staff-letter-racism.html?utm_source=substack&amp;utm_medium=email\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-54630 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/09\/ghigliottina_rivoluzione_francese-300x198.jpg\" alt=\"\" width=\"342\" height=\"226\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/09\/ghigliottina_rivoluzione_francese-300x198.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/09\/ghigliottina_rivoluzione_francese.jpg 600w\" sizes=\"auto, (max-width: 342px) 100vw, 342px\" \/>Keith Christiansen<\/a><\/span> <span style=\"color: #000000;\">lavora da cinquant\u2019anni al Metropolitan Museum of Art di New York, dove \u00e8 arrivato a diventare il curatore dell\u2019arte europea. Scioccato dalla devastazione di monumenti in Occidente, Christiansen ha postato un quadro che ritrae Alexandre Lenoir mentre cerca di fermare i giacobini durante la Rivoluzione francese, quando le statue di Notre Dame furono abbattute e la cattedrale rinominata \u201cTempio della Ragione\u201d. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">\u201cAlexandre Lenoir che combatte i rivoluzionari fanatici intenti a distruggere le tombe reali a Saint Denis\u201d, ha scritto Christiansen. \u201cQuante grandi opere d\u2019arte sono state perse per il desiderio di liberarci di un passato che non approviamo\u201d. Numerosi membri dello staff del Met hanno inviato una lettera alla direzione per sollecitarla a riconoscere \u201csupremazia bianca e cultura del razzismo sistemico nella nostra istituzione\u201d. Christiansen \u00e8 stato travolto dalle polemiche.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"> <img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-54631 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/09\/JK_Rowling_Potter-300x168.jpg\" alt=\"\" width=\"300\" height=\"168\" \/>Nei giorni scorsi la Rowling \u00e8 stata<\/span> <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/www.telegraph.co.uk\/news\/2022\/08\/13\/jk-rowling-told-next-reacting-salman-rushdie-attack\/?utm_source=substack&amp;utm_medium=email\" target=\"_blank\" rel=\"noreferrer noopener\">minacciata di morte<\/a><\/span> <span style=\"color: #000000;\">per aver espresso solidariet\u00e0 a Rushdie: \u201cSarai la prossima\u201d, gli ha scritto un pakistano. Ma l\u2019autrice di <em>Harry Potter <\/em>nelle stesse ore parlando al <\/span><span style=\"color: #0000ff;\"><em><a style=\"color: #0000ff;\" href=\"https:\/\/www.thetimes.co.uk\/article\/jk-rowling-attacks-chocolat-author-joanne-harris-for-failing-to-defend-gender-critical-writers-cw9m50zgv?utm_source=substack&amp;utm_medium=email\" target=\"_blank\" rel=\"noreferrer noopener\">Times<\/a><\/em><\/span> <span style=\"color: #000000;\">non lasciava passare inosservata la mancanza di solidariet\u00e0 delle colleghe scrittrici per via delle sue idee critiche sul gender di Rowling. Ha ragione un editoriale su<\/span> <span style=\"color: #0000ff;\"><em><a style=\"color: #0000ff;\" href=\"https:\/\/www.scotsman.com\/news\/opinion\/euan-mccolm-salman-rushdie-attack-shines-light-on-female-writers-bombarded-with-death-threats-3804982?utm_source=substack&amp;utm_medium=email\" target=\"_blank\" rel=\"noreferrer noopener\">The Scotsman<\/a><\/em> <\/span><span style=\"color: #000000;\">quando dice che gli attacchi a Rushdie e a Rowling condividono la stessa matrice di intolleranza ideologica.\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"> Come alla poetessa Jenny Lindsay, cui \u00e8 stato consigliato di non partecipare a eventi se non accompagnata (come una Rushdie femminile), dopo essere stata presa di mira sui social, accusata di \u201ctransfobia\u201d. In un<\/span> <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/www.thedarkhorsemagazine.com\/anatomy-of-a-hounding-lindsay?utm_source=substack&amp;utm_medium=email\" target=\"_blank\" rel=\"noreferrer noopener\">saggio<\/a><\/span> <span style=\"color: #000000;\">sulla rivista di poesia <em>Dark Horse<\/em>, Lindsay ha raccontato come \u00e8 stata messa a tacere. \u201cHo cominciato a sentire che stavo vivendo una sorveglianza e una denigrazione kafkiana, senza sapere quali fossero le esatte accuse, senza i mezzi per contestarle. Il mio reddito \u00e8 diminuito notevolmente rispetto agli anni precedenti\u201d.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Rowling ha<\/span> <a href=\"https:\/\/www.thetimes.co.uk\/article\/jk-rowling-exposes-twitter-trolls-pipe-bomb-threat-vjgk9w8vm?utm_source=substack&amp;utm_medium=email\" target=\"_blank\" rel=\"noreferrer noopener\"><span style=\"color: #0000ff;\">condiviso<\/span><\/a> <span style=\"color: #000000;\">sul suo account alcuni messaggi che ha ricevuto: &#8220;Spero che tu possa trovare una bomba nella tua cassetta della posta&#8221;. \u201cOra che centinaia di attivisti trans hanno minacciato di picchiarmi, stuprarmi, uccidermi o farmi esplodere ho capito che questo movimento non mette in pericolo le donne&#8221;, ha scritto Rowling, con un tocco di malcelata ironia. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">\u00f9Librerie<\/span> <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/www.independent.co.uk\/arts-entertainment\/books\/jk-rowling-transphobia-harry-potter-books-robert-galbraith-terf-australia-perth-b452803.html?utm_source=substack&amp;utm_medium=email\" target=\"_blank\" rel=\"noreferrer noopener\">hanno annunciato<\/a> <\/span><span style=\"color: #000000;\">di non vendere pi\u00f9 Rowling, come avvenne nel 1989 su Rushdie. \u201cMi aspettavo le minacce di violenza, che mi venisse detto che stavo letteralmente uccidendo le persone trans con il mio odio, che i miei libri venissero bruciati, anche se un uomo particolarmente violento mi ha detto che li aveva messi nel compost\u201d, ha<\/span><span style=\"color: #0000ff;\"> <a style=\"color: #0000ff;\" href=\"https:\/\/www.nbcnews.com\/feature\/nbc-out\/j-k-rowling-doubles-down-what-some-critics-call-transphobic-n1229351?utm_source=substack&amp;utm_medium=email\" target=\"_blank\" rel=\"noreferrer noopener\">scritto<\/a> <\/span><span style=\"color: #000000;\">Rowling. I social sono pieni di<\/span> <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/www.newsweek.com\/jk-rowling-books-burned-tiktok-transgender-issues-1532330?utm_source=substack&amp;utm_medium=email\" target=\"_blank\" rel=\"noreferrer noopener\">video<\/a> <\/span><span style=\"color: #000000;\">di persone che bruciano i suoi libri.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"> <img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-54632 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/09\/foto-300x180.jpg\" alt=\"\" width=\"300\" height=\"180\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/09\/foto-300x180.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/09\/foto-768x462.jpg 768w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/09\/foto-1024x616.jpg 1024w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/09\/foto.jpg 1176w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Quando Kathleen Stock si \u00e8 dimessa dal suo incarico di professoressa di filosofia all&#8217;Universit\u00e0 del Sussex a seguito di un&#8217;incessante campagna di linciaggi e attacchi anche fisici, l\u2019esultanza \u00e8 stata senza freni: \u201cLa strega \u00e8 morta\u201d. Il<\/span><span style=\"color: #0000ff;\"> <em><a style=\"color: #0000ff;\" href=\"https:\/\/www.ft.com\/content\/9504baa4-5cf9-40b5-87b5-04d24f19f2b6?utm_source=substack&amp;utm_medium=email\" target=\"_blank\" rel=\"noreferrer noopener\">Financial Times<\/a><\/em> <\/span><span style=\"color: #000000;\">racconta: \u201cLa tensione a cui \u00e8 sottoposta Stock \u00e8 palpabile: \u00e8 scoppiata in lacrime due volte durante la nostra conversazione. A un certo punto, siamo stati interrotti dalla consegna di una telecamera, che la polizia le aveva detto di installare\u201d.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"> Poetesse che tengono conferenze sotto sorveglianza e professoresse che installano telecamere a casa. Rushdie lo ha scritto nel suo penultimo libro <\/span><em><a href=\"https:\/\/www.nationalreview.com\/2021\/06\/book-review-languages-of-truth-salman-rushdie-strikes-again\/?utm_source=substack&amp;utm_medium=email\" target=\"_blank\" rel=\"noreferrer noopener\"><span style=\"color: #0000ff;\">Languages of truth. <\/span><\/a><\/em><span style=\"color: #000000;\">\u201cL\u2019idea che ferire i sentimenti delle persone, offendere la sensibilit\u00e0 delle persone, stia andando troppo oltre ora ha un ampio credito. E quando sento brave persone dire <img loading=\"lazy\" decoding=\"async\" class=\" wp-image-45249 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/11\/censura-300x168.jpg\" alt=\"\" width=\"334\" height=\"187\" \/>cose del genere, sento che il vecchio apparato della blasfemia e dell\u2019anatema, tutto questo potrebbe essere sulla via del ritorno sotto forma laica. Posso sostenere e sostengo che una societ\u00e0 aperta debba consentire l\u2019espressione di opinioni che alcuni membri di quella societ\u00e0 possono trovare spiacevoli; altrimenti, se accettiamo di censurare i sentimenti sgradevoli, entriamo nel problema di chi dovrebbe avere il potere di censura. <em>Quis custodiet ipsos custodes<\/em>, come si dice in latino. Chi ci protegger\u00e0 dai guardiani?\u201d. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Nessuno e l\u2019autocensura \u00e8 la regola ormai. La celebre scrittrice Lionel Shriver rivela al<\/span> <span style=\"color: #0000ff;\"><em><a style=\"color: #0000ff;\" href=\"https:\/\/www.thetimes.co.uk\/article\/lionel-shriver-we-need-to-talk-about-cancel-culture-rsjvrn3vb?utm_source=substack&amp;utm_medium=email\" target=\"_blank\" rel=\"noreferrer noopener\">Times<\/a> <\/em><\/span><span style=\"color: #000000;\">di essersi censurata per il suo nuovo romanzo: \u201cAvevo messo un po\u2019 di accento africano. Sono stata scoraggiata dall&#8217;usarlo e ho obbedito. La mia casa editrice, Harper Collins, era in ansia\u201d. Oggi si \u00e8 vittime dell'&#8221;autocancellazione&#8221; perch\u00e9 si preferisce rimanere in silenzio piuttosto che subire contraccolpi (per non arrivare alle coltellate contro Rushdie), ha detto Sir<\/span> <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/www.telegraph.co.uk\/news\/2021\/08\/06\/cancel-culture-leaves-people-screwed-life-casual-comments-warns\/?utm_source=substack&amp;utm_medium=email\" target=\"_blank\" rel=\"noreferrer noopener\">Tom Stoppard<\/a>. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Il grande drammaturgo inglese ha affermato che l&#8217;erosione della libert\u00e0 di parola ha lasciato le persone a rischio di essere &#8220;spacciate&#8221; a vita per i commenti \u201csbagliati\u201d. Lo scrittore originario di Leopoldstadt ha detto: &#8220;La libert\u00e0 di dire ci\u00f2 che si vuole entro i limiti della legge \u00e8 la libert\u00e0 da cui dipendono tutte le altre libert\u00e0. Non \u00e8 tanto la cancellazione quanto l&#8217;autocancellazione. Le persone vanno con cautela, stanno attente a quello che dicono. Dico solo una cosa casuale e sono fottuto per il resto della mia vita&#8221;. La paura di offendere \u00e8 talmente endemica che anche gli editori si stanno autocensurando, racconta il<\/span> <span style=\"color: #0000ff;\"><em><a style=\"color: #0000ff;\" href=\"https:\/\/www.thetimes.co.uk\/article\/defend-your-writers-publishers-or-be-damned-how-the-books-trade-went-woke-2chbcxm3s?utm_source=substack&amp;utm_medium=email\" target=\"_blank\" rel=\"noreferrer noopener\">Times<\/a><\/em>.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-54633 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/09\/Universit\u00e0_contestazione_cancel-300x213.jpg\" alt=\"\" width=\"318\" height=\"226\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/09\/Universit\u00e0_contestazione_cancel-300x213.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/09\/Universit\u00e0_contestazione_cancel-768x545.jpg 768w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/09\/Universit\u00e0_contestazione_cancel.jpg 1024w\" sizes=\"auto, (max-width: 318px) 100vw, 318px\" \/>La censura dilaga al punto che, come ha rivelato a<\/span> <span style=\"color: #0000ff;\"><em><a style=\"color: #0000ff;\" href=\"https:\/\/elpais.com\/eps\/2022-01-08\/pascal-bruckner-hay-una-caza-de-brujas-el-neofeminismo-es-venganza-cortar-cabezas-una-detras-de-otra.html?utm_source=substack&amp;utm_medium=email\" target=\"_blank\" rel=\"noreferrer noopener\">El Pais<\/a><\/em><\/span> <span style=\"color: #000000;\">il filosofo francese Pascal Bruckner, \u201cse non cadi nell\u2019autocensura allora lo faranno per te. A Grasset, l&#8217;editore che mi pubblica, tutti i libri vengono letti prima da un avvocato\u201d. E anche il premio Nobel per la Letteratura Kazuo Ishiguro, l\u2019autore di <em>Quel che resta del giorno<\/em>, alla<\/span> <span style=\"color: #0000ff;\"><em><a style=\"color: #0000ff;\" href=\"https:\/\/www.bbc.com\/news\/entertainment-arts-56208347?utm_source=substack&amp;utm_medium=email\" target=\"_blank\" rel=\"noreferrer noopener\">Bbc<\/a><\/em><\/span> <span style=\"color: #000000;\">ha detto che un \u201cclima di paura\u201d sta incoraggiando l\u2019autocensura. La nota casa editrice Rowman &amp; Littlefield ha<\/span> <a href=\"https:\/\/www.wsj.com\/articles\/the-cancel-mob-comes-back-for-more-11602091733?utm_source=substack&amp;utm_medium=email\" target=\"_blank\" rel=\"noreferrer noopener\"><span style=\"color: #0000ff;\">ritirato<\/span><\/a> <span style=\"color: #000000;\">e mandato al macero la biografia di un imperialista britannico, <em>The Last Imperialist: Sir Alan Burns\u2019 Epic Defense of the British Empire <\/em>di Bruce Gilley, perch\u00e9 non abbastanza perfida con la storia inglese.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Nelle universit\u00e0 non si pu\u00f2 pi\u00f9 dire niente di scomodo. Il<\/span> <span style=\"color: #0000ff;\"><em><a style=\"color: #0000ff;\" href=\"https:\/\/www.thetimes.co.uk\/article\/200-academics-tell-of-death-threats-and-abuse-as-battle-rages-for-free-speech-hp99fnzjh?utm_source=substack&amp;utm_medium=email\" target=\"_blank\" rel=\"noreferrer noopener\">Sunday Times<\/a><\/em><\/span> <span style=\"color: #000000;\">ha pubblicato una inchiesta sui docenti minacciati, anche di morte, per aver sfidato l\u2019opinione corrente. \u201c200 accademici raccontano di minacce di morte e abusi mentre infuria la battaglia per la libert\u00e0 di parola\u201d, il titolo. La dissidente iraniana<\/span> <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/www.independent.co.uk\/news\/uk\/home-news\/maryam-namazie-secular-activist-barred-from-speaking-at-warwick-university-over-fears-of-inciting-hatred-against-muslim-students-10517296.html\" target=\"_blank\" rel=\"noreferrer noopener\">Maryam Namazie<\/a> <\/span><span style=\"color: #000000;\">\u00e8 stato bandita da alcuni college inglesi, come il Goldsmiths e il Warwick, perch\u00e9 avrebbe \u201coffeso\u201d gli studenti di fede islamica. L\u2019editorialista cattolico<\/span> <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/www.bbc.co.uk\/news\/uk-england-hampshire-47156907?utm_source=substack&amp;utm_medium=email\" target=\"_blank\" rel=\"noreferrer noopener\">Peter Hitchens<\/a> <\/span><span style=\"color: #000000;\">\u00e8 stato cancellato all\u2019Universit\u00e0 di Portsmouth perch\u00e9 contrario alle nozze gay. Ma anche all\u2019icona dei diritti gay<\/span> <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/www.theguardian.com\/uk-news\/2016\/feb\/13\/peter-tatchell-snubbed-students-free-speech-veteran-gay-rights-activist?utm_source=substack&amp;utm_medium=email\" target=\"_blank\" rel=\"noreferrer noopener\">Peter Tatchell<\/a><\/span> <span style=\"color: #000000;\">\u00e8 stato impedito di parlare all\u2019Universit\u00e0 di Canterbury solo perch\u00e9 aveva firmato una lettera in cui dichiarava che anche alle persone con opinioni differenti dovrebbe essere consentito di partecipare ai dibattiti.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-54634 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/09\/charlie_ebdo.jpg\" alt=\"\" width=\"211\" height=\"263\" \/>St\u00e9phane Charbonnier \u00e8 il direttore di <em>Charlie Hebdo<\/em> morto sotto i colpi dei terroristi. Prima di morire, \u201cCharb\u201d stava lavorando a un libro che sarebbe uscito postumo, una<\/span> <span style=\"color: #0000ff;\"><em><a style=\"color: #0000ff;\" href=\"https:\/\/www.amazon.it\/Lettera-truffatori-dellislamofobia-fanno-razzisti\/dp\/8856650029?utm_source=substack&amp;utm_medium=email\" target=\"_blank\" rel=\"noreferrer noopener\">Lettera ai truffatori della islamofobia<\/a><\/em>.<\/span> <span style=\"color: #000000;\">Consegn\u00f2 queste pagine al suo editore il 5 gennaio. Due giorni dopo ci fu il massacro. In una intervista a<\/span><span style=\"color: #0000ff;\"> <em><a style=\"color: #0000ff;\" href=\"https:\/\/www.lexpress.fr\/actualite\/societe\/piece-de-charb-la-plupart-du-temps-on-n-a-pas-eu-de-reponse-des-facs_2149409.html?utm_source=substack&amp;utm_medium=email\" target=\"_blank\" rel=\"noreferrer noopener\">L\u2019Express<\/a><\/em><\/span>,<span style=\"color: #000000;\"> il regista che ha portato in scena quel testo macchiato di sangue, G\u00e9rald Dumont, ha rivelato che le universit\u00e0 lo boicottano tutte. \u201cLe volte che abbiamo fatto richiesta non abbiamo ricevuto risposta\u201d. E quando sembravano esserci riusciti ci sono state cancellazioni in serie. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">\u201cA Parigi VII (Diderot), c&#8217;\u00e8 stata una mobilitazione dei sindacati contro lo svolgimento della lettura, che hanno minacciato di occupare la sala. Hanno manifestato con slogan come \u2018razzismo e islamofobia\u2019. All\u2019Universit\u00e0 di Lille, il rettore ha annullato lo spettacolo due settimane prima. All&#8217;Universit\u00e0 di Valenciennes, c&#8217;erano pi\u00f9 poliziotti che spettatori\u201d. <\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\"><strong>No, non siamo tutti Rushdie.<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-54635 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/09\/Hebdo_cover-215x300.jpg\" alt=\"\" width=\"187\" height=\"261\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/09\/Hebdo_cover-215x300.jpg 215w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/09\/Hebdo_cover.jpg 348w\" sizes=\"auto, (max-width: 187px) 100vw, 187px\" \/>Un college di Oxford, che nacque sotto gli auspici dei vescovi medievali, ha<\/span> <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/www.thetimes.co.uk\/article\/balliol-college-oxford-bans-christians-from-freshers-fair-nj89j75q5?utm_source=substack&amp;utm_medium=email\" target=\"_blank\" rel=\"noreferrer noopener\">vietato alle organizzazioni cristiane<\/a><\/span> <span style=\"color: #000000;\">di partecipare alla tradizionale fiera delle matricole, accusando il Cristianesimo di essere &#8220;una scusa per l&#8217;omofobia e il neocolonialismo&#8221;. A Oxford \u00e8 stata lanciata una \u201cfatwa morale\u201d contro il celebre filosofo cattolico del diritto John Finnis, professore emerito all\u2019universit\u00e0 contrario alle nozze gay. Sul <em>Guardian<\/em> sono apparsi articoli dal titolo:<\/span> \u201c<span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/www.theguardian.com\/commentisfree\/2019\/jan\/11\/john-finnis-oxford-university-academic-freedom-law?utm_source=substack&amp;utm_medium=email\" target=\"_blank\" rel=\"noreferrer noopener\">Ecco perch\u00e9 Finnis non dovrebbe insegnare a Oxford<\/a><\/span>\u201d. <span style=\"color: #000000;\">\u201cA Ges\u00f9 oggi sarebbe impedito di parlare a Oxford\u201d, ha detto il collega di Finnis,<\/span><span style=\"color: #0000ff;\"> <a style=\"color: #0000ff;\" href=\"https:\/\/www.independent.co.uk\/student\/news\/jesus-christ-would-be-prevented-from-speaking-at-britain-s-universities-says-oxford-academic-a7058056.html\" target=\"_blank\" rel=\"noreferrer noopener\">Timothy Garton Ash<\/a>.<\/span> <span style=\"color: #000000;\">Per aver detto che la schiavit\u00f9 non pu\u00f2 essere definita una forma di \u201cgenocidio\u201d, il celebre storico David Starkey \u00e8 stato<\/span> <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/www.bbc.com\/news\/entertainment-arts-53279273?utm_source=substack&amp;utm_medium=email\" target=\"_blank\" rel=\"noreferrer noopener\">licenziato<\/a><\/span> <span style=\"color: #000000;\">da Cambridge. Carriera finita.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-41594 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/11\/cristianesimo_islam.jpg\" alt=\"\" width=\"240\" height=\"160\" \/>Quando \u00e8 uscito il libro<\/span> <span style=\"color: #0000ff;\"><em><a style=\"color: #0000ff;\" href=\"https:\/\/www.amazon.it\/Aristote-Mont-Saint-Michel-racines-grecques-chr%C3%A9tienne\/dp\/2020965410\" target=\"_blank\" rel=\"noreferrer noopener\">Aristotele a Mont-Saint-Michel<\/a><\/em>,<\/span> <span style=\"color: #000000;\">dove lo storico Sylvain Gouguenheim, ordinario alla Normale di Lione, ha spiegato che l\u2019eredit\u00e0 greca nel Medioevo fu trasmessa all\u2019Europa da Costantinopoli, riducendo il ruolo intermediario del mondo islamico (\u201cla cultura greca non torn\u00f2 all\u2019Occidente solo grazie all\u2019Islam: a salvare dall\u2019oblio i filosofi antichi sarebbe stato innanzitutto il lavoro dei cristiani d\u2019oriente, caduti sotto dominio musulmano, e dunque arabizzati\u201d) iniziarono a circolare <\/span><a href=\"https:\/\/www.nytimes.com\/2008\/04\/28\/world\/europe\/28iht-politicus.2.12398698.html?utm_source=substack&amp;utm_medium=email\" target=\"_blank\" rel=\"noreferrer noopener\"><span style=\"color: #0000ff;\">peti<\/span>z<span style=\"color: #0000ff;\">ioni contro Gouguenheim<\/span><\/a> <span style=\"color: #000000;\">su <em>Le Monde<\/em>, su <em>Lib\u00e9ration<\/em> e su <em>Le Monde Diplomatique<\/em>. \u201cGouguenheim \u00e8 un islamofobo\u201d. Stesso destino per un altro storico di rango, Olivier P\u00e9tr\u00e9-Grenouilleau, reo di aver scritto il libro<\/span> <span style=\"color: #0000ff;\"><em><a style=\"color: #0000ff;\" href=\"https:\/\/www.amazon.it\/traites-Noirs-sais-je-3248-French-ebook\/dp\/B07D8SBQP1\/ref=sr_1_1?ie=UTF8&amp;qid=1548066270&amp;sr=8-1&amp;keywords=La%20Traite%20des%20Noirs&amp;utm_source=substack&amp;utm_medium=email\" target=\"_blank\" rel=\"noreferrer noopener\">La Traite des Noirs,<\/a><\/em> <\/span><span style=\"color: #000000;\">in cui dichiara: \u201cIl numero degli schiavi cristiani razziati dai musulmani supera quello degli africani deportati nelle Americhe\u201d.\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"> Il quotidiano tedesco<\/span><span style=\"color: #0000ff;\"> <em><a style=\"color: #0000ff;\" href=\"https:\/\/www.faz.net\/aktuell\/rhein-main\/frankfurt\/freiheit-in-der-wissenschaft-tabu-themen-fuer-forschung-und-lehre-17846360.html?utm_source=substack&amp;utm_medium=email\" target=\"_blank\" rel=\"noreferrer noopener\">Frankfurter Allgemeine Zeitung<\/a><\/em><\/span> <span style=\"color: #000000;\">racconta che la posizione sull\u2019Islam di un ricercatore gioca ora un ruolo importante nella sua futura carriera. \u201cSe parla bene dell\u2019Islam, far\u00e0 carriera, altrimenti no. Se un antropologo si occupa di islamismo, la sua carriera \u00e8 finita\u201d. Quando il sociologo egiziano Hamed Abdel-Samad ha ricevuto la<\/span> <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/www.cicero.de\/kultur\/rassismus-debatte-was-rassisten-und-antirassisten-gemein-haben?utm_source=substack&amp;utm_medium=email\" target=\"_blank\" rel=\"noreferrer noopener\">medaglia Josef Neuberger<\/a><\/span> <span style=\"color: #000000;\">militanti Antifa lo hanno aggredito all\u2019Universit\u00e0 di Monaco. Uno ha cercato di dargli un pugno perch\u00e9 Samad aveva scritto un libro che criticava Maometto.<\/span> <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/www.reuters.com\/article\/us-germany-islam-book-idUSTRE5952Y120091006?utm_source=substack&amp;utm_medium=email\" target=\"_blank\" rel=\"noreferrer noopener\">Gabrielle Brinkman<\/a> <\/span><span style=\"color: #000000;\">col suo romanzo <em>Wem ehre Geburt<\/em> (A chi \u00e8 dovuto l\u2019onore) avrebbe potuto irritare la comunit\u00e0 islamica. Cos\u00ec alla scrittrice \u00e8 stato chiesto dalla casa editrice Droste di censurare i passi pi\u00f9 delicati. Brinkman si \u00e8 rifiutata ed \u00e8 rimasta senza editore.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"> Racconta<\/span> il <span style=\"color: #0000ff;\"><em><a style=\"color: #0000ff;\" href=\"https:\/\/www.nytimes.com\/2017\/09\/24\/opinion\/milo-yiannopoulos-free-speech-week-berkeley.html?utm_source=substack&amp;utm_medium=email\" target=\"_blank\" rel=\"noreferrer noopener\">New York Times<\/a><\/em><\/span> <span style=\"color: #000000;\">che per coprire i costi della sicurezza e consentire ad alcuni oratori di parlare nel campus che ha inventato il <em>free speech<\/em>, l\u2019Universit\u00e0 di Berkeley ha speso 1,5 milioni di dollari.<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\"><strong>Siamo tutti Salman Rushdie? <\/strong><\/span><\/p>\n<p><a href=\"https:\/\/substackcdn.com\/image\/youtube\/w_550,c_limit\/l_youtube_play_qyqt8q,w_120\/-PSYPrE5LrQ\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-54636 aligncenter\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/09\/video-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/09\/video-300x169.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/09\/video.jpg 550w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Il Middlebury College nel Vermont, lo stato pi\u00f9 liberal d\u2019America, ha invitato <\/span><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/www.theatlantic.com\/politics\/archive\/2017\/03\/middlebury-free-speech-violence\/518667\/?utm_source=substack&amp;utm_medium=email\" target=\"_blank\" rel=\"noreferrer noopener\">Charles Murray<\/a><\/span>, <span style=\"color: #000000;\">un famoso sociologo conservative. Quando Murray \u00e8 salito sul palco, quattrocento studenti gli hanno urlato \u201crazzista, sessista, anti-gay\u201d. Murray \u00e8 fuggito in un ufficio, in modo che Allison Stanger, docente di Politica ed Economia, lo potesse intervistare in streaming. Quando Murray e Stanger sono usciti sono stati attaccati da un gruppo di manifestanti. Lei \u00e8 stata tirata per i capelli e portata in ospedale, mentre manifestanti salivano sul tetto dell\u2019auto di Murray, fino a che la polizia non \u00e8 riuscita a scortarlo via.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-54639 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/09\/Panebianco_contestato-300x158.jpg\" alt=\"\" width=\"300\" height=\"158\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/09\/Panebianco_contestato-300x158.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/09\/Panebianco_contestato.jpg 310w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>E non c\u2019\u00e8 nemmeno bisogno di andare cos\u00ec lontano. Angelo Panebianco ha potuto tenere le sue ultime lezioni all\u2019Universit\u00e0 di Bologna grazie a un cordone di carabinieri. Il politologo si \u00e8 visto interrompere le lezioni due volte, aggredito e accusato di essere un \u201cguerrafondaio\u201d per i suoi articoli sul <em>Corriere della Sera<\/em>. Manifesti contro la \u201ccasta guerrafondaia\u201d, come recita il tazebao dei collettivi, sono stati appesi negli studi dei docenti che hanno espresso solidariet\u00e0 a Panebianco, la cui libert\u00e0 di espressione e di insegnamento (e forse non solo) \u00e8 stata garantita da agenti in borghese posti a sua protezione.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-54640 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/09\/Paivi_Rasanem_Finlandia-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/09\/Paivi_Rasanem_Finlandia-300x169.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/09\/Paivi_Rasanem_Finlandia.jpg 538w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>In Finlandia \u00e8 stata processata per \u201cincitamento all\u2019odio\u201d l\u2019ex ministro dell\u2019Interno<\/span> <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/www.bbc.com\/news\/world-europe-60111140?utm_source=substack&amp;utm_medium=email\" target=\"_blank\" rel=\"noreferrer noopener\">Paivi Rasanen<\/a>,<\/span> <span style=\"color: #000000;\">colpevole di aver citato la Bibbia sui social a difesa del matrimonio uomo-donna. La procura di Parigi ha aperto una inchiesta sul giurista di origine armena della Sorbona<\/span> <a href=\"https:\/\/www.valeursactuelles.com\/societe\/le-cas-aram-mardirossian-ou-la-dictature-de-la-bien-pensance-a-luniversite\/?utm_source=substack&amp;utm_medium=email\" target=\"_blank\" rel=\"noreferrer noopener\"><span style=\"color: #0000ff;\">Aram Mardirossian<\/span><\/a> <span style=\"color: #000000;\">sempre per \u201cincitamento all\u2019odio\u201d (sei mesi di carcere e 22.500 euro di ammenda) perch\u00e9 ha criticato il matrimonio gay. In Inghilterra una femminista,<\/span> <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/www.telegraph.co.uk\/news\/2022\/01\/30\/police-reported-watchdog-visiting-womens-charity-boss-question\/?utm_source=substack&amp;utm_medium=email\" target=\"_blank\" rel=\"noreferrer noopener\">Nicola Murray<\/a>,<\/span> <span style=\"color: #000000;\">si \u00e8 vista arrivare a casa la polizia dopo una denuncia per istigazione all\u2019odio (aveva criticato il transgender). <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-50477 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/04\/Woke_usa_blak_live.jpg\" alt=\"\" width=\"205\" height=\"246\" \/>La scrittrice<\/span> <a href=\"https:\/\/www.dailymail.co.uk\/news\/article-8490821\/Best-selling-childrens-author-sacked-posting-hashtag-stand-JK-Rowling-Twitter.html?utm_source=substack&amp;utm_medium=email\" target=\"_blank\" rel=\"noreferrer noopener\"><span style=\"color: #0000ff;\">Gillian Phillip<\/span><\/a> <span style=\"color: #000000;\">ha perso il lavoro per aver espresso solidariet\u00e0 sul gender alla Rowling, alla saggista di origine somala<\/span> <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/en.wikipedia.org\/wiki\/Ayaan_Hirsi_Ali?utm_source=substack&amp;utm_medium=email\" target=\"_blank\" rel=\"noreferrer noopener\">Ayaan Hirsi Ali<\/a><\/span> <span style=\"color: #000000;\">\u00e8 stato impedito di parlare a una universit\u00e0, l\u2019economista<\/span> <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/www.theatlantic.com\/ideas\/archive\/2020\/07\/perils-us-or-against-us\/613981\/?utm_source=substack&amp;utm_medium=email\" target=\"_blank\" rel=\"noreferrer noopener\">Herald Uhlig<\/a><\/span> <span style=\"color: #000000;\">\u00e8 stato messo sotto processo dall\u2019Universit\u00e0 di Chicago per aver criticato Black Lives Matter, la storica di Oxford<\/span> <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/www.bbc.com\/news\/uk-england-oxfordshire-51737206?utm_source=substack&amp;utm_medium=email\" target=\"_blank\" rel=\"noreferrer noopener\">Selina Todd<\/a> <\/span><span style=\"color: #000000;\">deve tenere lezione all\u2019universit\u00e0 con le guardie del corpo per aver difeso la realt\u00e0 del sesso biologico, al saggist<\/span>a <a href=\"https:\/\/www.newsweek.com\/best-selling-controversial-book-transgender-people-removed-amazon-3-years-after-publication-1571087?utm_source=substack&amp;utm_medium=email\" target=\"_blank\" rel=\"noreferrer noopener\"><span style=\"color: #0000ff;\">Ryan Anderson<\/span><\/a> <span style=\"color: #000000;\">\u00e8 stato fatto sparire un libro da Amazon perch\u00e9 critico del gender e Sasha White \u00e8 stata<\/span> <a href=\"https:\/\/www.newsweek.com\/best-selling-controversial-book-transgender-people-removed-amazon-3-years-after-publication-1571087?utm_source=substack&amp;utm_medium=email\" target=\"_blank\" rel=\"noreferrer noopener\"><span style=\"color: #0000ff;\">licenziata<\/span><\/a> <span style=\"color: #000000;\">da una agenzia letteraria di New York dopo avere espresso solidariet\u00e0 a Rowling e aver scritto che \u201cil gender non conformista \u00e8 meraviglioso; negare il sesso biologico no\u201d. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">L\u2019emittente radiofonica pubblica francese <em>France Inter<\/em> a Natale ha<\/span> <a href=\"https:\/\/www.lefigaro.fr\/actualite-france\/france-inter-refuse-une-publicite-a-l-oeuvre-d-orient-parce-qu-elle-contient-le-mot-chretien-20201207?utm_source=substack&amp;utm_medium=email\" target=\"_blank\" rel=\"noreferrer noopener\"><span style=\"color: #0000ff;\">rifiutato<\/span><\/a> <span style=\"color: #000000;\">una campagna pubblicitaria dell\u2019Oeuvre d\u2019Orient, che si batte per i cristiani perseguitati. La radio aveva chiesto che venisse rimossa una sola parola: \u201ccristiano\u201d. La frase \u201cau profit des chr\u00e9tiens d\u2019Orient\u201d, ovvero gli introiti sarebbero andati ai cristiani d\u2019Oriente, doveva sparire e i cartelloni ristampati. \u201cI messaggi pubblicitari non devono contenere alcun elemento che possa offendere le convinzioni religiose degli ascoltatori\u201d, aveva fatto sapere, prima di ammettere la pubblicit\u00e0 per le proteste.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">No, non tutte le \u201cconvinzioni religiose degli ascoltatori\u201d, solo quelle dell\u2019Islam, proprio come ha imposto nel mondo la fatwa Rushdie.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"> <img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-54641 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/09\/roghi-libri-germania_nazismo-300x226.jpg\" alt=\"\" width=\"300\" height=\"226\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/09\/roghi-libri-germania_nazismo-300x226.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/09\/roghi-libri-germania_nazismo.jpg 740w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>In Canada ci sono scuole che hanno persino bruciato<\/span> <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/thecanadian.news\/2021\/09\/09\/5000-childrens-books-and-comics-of-asterix-or-tintin-burned-in-canada-for-offending-indigenous-people\/?utm_source=substack&amp;utm_medium=email\" target=\"_blank\" rel=\"noreferrer noopener\">5.000 libri per bambini<\/a>,<\/span> <span style=\"color: #000000;\">come hanno fatto i seguaci dell\u2019editto iraniano in Inghilterra nel 1989. Erano vecchi classici macchiati della colpa del \u201crazzismo\u201d. E membri del Partito liberale del Canada (la formazione del primo ministro Justin Trudeau) hanno<\/span> <a href=\"https:\/\/www.lefigaro.fr\/culture\/ouvrages-brules-par-des-ecoles-canadiennes-l-imposture-suzy-kies-gardienne-du-savoir-autochtone-20210909?utm_source=substack&amp;utm_medium=email\" target=\"_blank\" rel=\"noreferrer noopener\"><span style=\"color: #0000ff;\">cos\u00ec<\/span><\/a><span style=\"color: #000000;\"> giustificato il rogo di libri: \u201cNon stiamo cercando di cancellare la storia, ma di correggerla\u201d. E il consiglio scolastico di Toronto &#8211; il pi\u00f9 grande del Canada &#8211; ha ritirato il sostegno a un club del libro dedicato alle ragazze. La presenza di un Premio Nobel per la pace, la yazida sopravvissuta agli stupri dell\u2019Isis<\/span> <a href=\"https:\/\/www.lefigaro.fr\/culture\/de-peur-d-offenser-leurs-eleves-des-ecoles-canadiennes-censurent-nadia-murad-nobel-de-la-paix-2018-20211118?utm_source=substack&amp;utm_medium=email\" target=\"_blank\" rel=\"noreferrer noopener\"><span style=\"color: #0000ff;\">Nadia Murad<\/span>,<\/a> <span style=\"color: #000000;\">avrebbe &#8220;promosso l&#8217;islamofobia\u201d.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">No, non siamo tutti Rushdie. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">\u201cTrent&#8217;anni fa, qualsiasi aspirante Cassandra sarebbe stata derisa se avesse affermato che un giorno ci saremmo ritrovati cos\u00ec\u201d ha scritto Andrew Doyle in<\/span> <span style=\"color: #0000ff;\"><em><a style=\"color: #0000ff;\" href=\"https:\/\/www.google.it\/books\/edition\/Free_Speech_and_Why_It_Matters\/AQr-zQEACAAJ?hl=it&amp;utm_source=substack&amp;utm_medium=email\" target=\"_blank\" rel=\"noreferrer noopener\">Free speech and wha it matters<\/a><\/em>.<\/span> <span style=\"color: #000000;\">Trent\u2019anni \u00e8 il tempo che ci separa dalla fatwa contro Rushdie. \u201cIn altri 30 anni potremmo esserci rassegnati all&#8217;autocensura e al conformismo, con il libero pensiero visto come la stranezza di un tempo semi-dimenticato\u201d. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">L\u2019Occidente oggi \u00e8 pieno di Khomeini travestiti da meschini funzionari \u201cinclusivi\u201d. E stanno vincendo questa guerra.<\/span><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/meotti.substack.com\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\"><strong>abbonati alla newsletter<\/strong><\/span><\/a><\/p>\n<p>___________________________________________<\/p>\n<p><span style=\"color: #000000;\"><strong>Leggi anche:<\/strong><\/span><\/p>\n<p><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lislam-in-europa\/\" target=\"_blank\" rel=\"noopener\"><strong>L&#8217;Islam in Europa<\/strong><\/a><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Abstract: L&#8217;autocensura dell&#8217;Occidente di fronte all&#8217;Islam e non solo. Oggi la nostra cultura \u00e8 dominata da coloro che danno credito all&#8217;idea che parole, arte, libri per bambini o editoriali siano la stessa cosa della violenza. Siamo cos\u00ec abituati a questa visione del mondo e a ci\u00f2 che richiede \u2013 scusarsi, umiliare, cancellare, umiliare ancora un &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lautocensura-delloccidente-di-fronte-allislam-e-non-solo\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":50718,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,16],"tags":[2857,2837,161,1835],"class_list":["post-54622","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-costume","category-islam","tag-cancel-culture","tag-crisi-delloccidente","tag-islam-2","tag-politicamente-corretto","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&#039;autocensura dell&#039;Occidente di fronte all&#039;Islam e non solo - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"L&#039;autocensura dell&#039;Occidente di fronte all&#039;Islam e non solo. Ormai la ritirata di fronte a tutto ci\u00f2 che \u00e8 &quot;sensibile&quot; \u00e8 diventata la regola\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lautocensura-delloccidente-di-fronte-allislam-e-non-solo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;autocensura dell&#039;Occidente di fronte all&#039;Islam e non solo - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"L&#039;autocensura dell&#039;Occidente di fronte all&#039;Islam e non solo. Ormai la ritirata di fronte a tutto ci\u00f2 che \u00e8 &quot;sensibile&quot; \u00e8 diventata la regola\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lautocensura-delloccidente-di-fronte-allislam-e-non-solo\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-31T22:00:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-15T09:16:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/04\/cancel_culture_sinistra-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"26 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lautocensura-delloccidente-di-fronte-allislam-e-non-solo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lautocensura-delloccidente-di-fronte-allislam-e-non-solo\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"L&#8217;autocensura dell&#8217;Occidente di fronte all&#8217;Islam e non solo\",\"datePublished\":\"2022-08-31T22:00:53+00:00\",\"dateModified\":\"2024-03-15T09:16:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lautocensura-delloccidente-di-fronte-allislam-e-non-solo\\\/\"},\"wordCount\":3870,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lautocensura-delloccidente-di-fronte-allislam-e-non-solo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/cancel_culture_sinistra-1.jpg\",\"keywords\":[\"cancel-culture\",\"crisi dell&#039;Occidente\",\"islam\",\"politicamente corretto\"],\"articleSection\":[\"Costume\",\"Islam\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lautocensura-delloccidente-di-fronte-allislam-e-non-solo\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lautocensura-delloccidente-di-fronte-allislam-e-non-solo\\\/\",\"name\":\"L'autocensura dell'Occidente di fronte all'Islam e non solo - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lautocensura-delloccidente-di-fronte-allislam-e-non-solo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lautocensura-delloccidente-di-fronte-allislam-e-non-solo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/cancel_culture_sinistra-1.jpg\",\"datePublished\":\"2022-08-31T22:00:53+00:00\",\"dateModified\":\"2024-03-15T09:16:32+00:00\",\"description\":\"L'autocensura dell'Occidente di fronte all'Islam e non solo. Ormai la ritirata di fronte a tutto ci\u00f2 che \u00e8 \\\"sensibile\\\" \u00e8 diventata la regola\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lautocensura-delloccidente-di-fronte-allislam-e-non-solo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lautocensura-delloccidente-di-fronte-allislam-e-non-solo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lautocensura-delloccidente-di-fronte-allislam-e-non-solo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/cancel_culture_sinistra-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/cancel_culture_sinistra-1.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lautocensura-delloccidente-di-fronte-allislam-e-non-solo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&#8217;autocensura dell&#8217;Occidente di fronte all&#8217;Islam e non solo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'autocensura dell'Occidente di fronte all'Islam e non solo - Rassegna Stampa Cattolica","description":"L'autocensura dell'Occidente di fronte all'Islam e non solo. Ormai la ritirata di fronte a tutto ci\u00f2 che \u00e8 \"sensibile\" \u00e8 diventata la regola","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lautocensura-delloccidente-di-fronte-allislam-e-non-solo\/","og_locale":"it_IT","og_type":"article","og_title":"L'autocensura dell'Occidente di fronte all'Islam e non solo - Rassegna Stampa Cattolica","og_description":"L'autocensura dell'Occidente di fronte all'Islam e non solo. Ormai la ritirata di fronte a tutto ci\u00f2 che \u00e8 \"sensibile\" \u00e8 diventata la regola","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lautocensura-delloccidente-di-fronte-allislam-e-non-solo\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2022-08-31T22:00:53+00:00","article_modified_time":"2024-03-15T09:16:32+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/04\/cancel_culture_sinistra-1.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"26 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lautocensura-delloccidente-di-fronte-allislam-e-non-solo\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lautocensura-delloccidente-di-fronte-allislam-e-non-solo\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"L&#8217;autocensura dell&#8217;Occidente di fronte all&#8217;Islam e non solo","datePublished":"2022-08-31T22:00:53+00:00","dateModified":"2024-03-15T09:16:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lautocensura-delloccidente-di-fronte-allislam-e-non-solo\/"},"wordCount":3870,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lautocensura-delloccidente-di-fronte-allislam-e-non-solo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/04\/cancel_culture_sinistra-1.jpg","keywords":["cancel-culture","crisi dell&#039;Occidente","islam","politicamente corretto"],"articleSection":["Costume","Islam"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lautocensura-delloccidente-di-fronte-allislam-e-non-solo\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lautocensura-delloccidente-di-fronte-allislam-e-non-solo\/","name":"L'autocensura dell'Occidente di fronte all'Islam e non solo - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lautocensura-delloccidente-di-fronte-allislam-e-non-solo\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lautocensura-delloccidente-di-fronte-allislam-e-non-solo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/04\/cancel_culture_sinistra-1.jpg","datePublished":"2022-08-31T22:00:53+00:00","dateModified":"2024-03-15T09:16:32+00:00","description":"L'autocensura dell'Occidente di fronte all'Islam e non solo. Ormai la ritirata di fronte a tutto ci\u00f2 che \u00e8 \"sensibile\" \u00e8 diventata la regola","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lautocensura-delloccidente-di-fronte-allislam-e-non-solo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lautocensura-delloccidente-di-fronte-allislam-e-non-solo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lautocensura-delloccidente-di-fronte-allislam-e-non-solo\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/04\/cancel_culture_sinistra-1.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/04\/cancel_culture_sinistra-1.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lautocensura-delloccidente-di-fronte-allislam-e-non-solo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"L&#8217;autocensura dell&#8217;Occidente di fronte all&#8217;Islam e non solo"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/54622","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=54622"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/54622\/revisions"}],"predecessor-version":[{"id":59856,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/54622\/revisions\/59856"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/50718"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=54622"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=54622"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=54622"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}