{"id":546,"date":"2005-05-21T00:00:00","date_gmt":"2005-05-20T22:00:00","guid":{"rendered":""},"modified":"2015-12-16T15:59:40","modified_gmt":"2015-12-16T14:59:40","slug":"il-capitalismo-selvaggio-e-il-comunismo","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-capitalismo-selvaggio-e-il-comunismo\/","title":{"rendered":"Il capitalismo selvaggio e il comunismo"},"content":{"rendered":"<div style=\"text-align: justify;\"><em><em><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/05\/ferocia.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-28847\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/05\/ferocia.jpg\" alt=\"ferocia\" width=\"250\" height=\"173\" \/><\/a>Liberismo, comunismo e nazismo sono ideologie materialiste che pretendono di applicare agli uomini le stessa legge che regola l&#8217;evoluzione della specie nel mondo animale: la lotta.<\/em><\/em><\/div>\n<p style=\"text-align: center;\">* * *<\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">La Rivoluzione francese, nata dal pensiero illuminista, crea le condizioni per lo sfruttamento degli operai.La rivoluzione francese<br \/>\n1) abbassa i salari minimi dovuti agli operai<br \/>\n2) abolisce la possibilit\u00e0 di scioperare<br \/>\n3) vieta qualunque associazione di lavoratori. In economia d\u00e0 origine alla fisiocrazia.<\/p>\n<div><\/div>\n<p>Per la fisiocrazia l\u2019iniziativa dell\u2019uomo in economia \u00e8 sempre buona e non deve essere regolata: \u00e8 come dire che la circolazione stradale \u00e8 sempre buona e che non deve esistere il codice della strada. Dalla fisiocrazia nasce il capitalismo selvaggio che non rispetta i diritti dei lavoratori. Dallo spirito della fisiocrazia nasce la tratta degli schiavi neri. Nel medioevo la regina cattolica della Francia, Batilde, abolisce la schiavit\u00f9 nel 650.<\/p>\n<div><\/div>\n<p>Nel 1700, con l\u2019illuminismo, rinasce la schiavit\u00f9: Voltaire, padre della Rivoluzione francese, era favorevole alla schiavit\u00f9 dei neri. Liberismo, comunismo e nazismo sono ideologie materialiste che pretendono di applicare agli uomini le stessa legge che regola l&#8217;evoluzione della specie nel mondo animale: la lotta. Il liberismo \u00e8 il principio darviniano applicato nel mondo dell\u2019economia e del mercato, esso pu\u00f2 essere definito come la concezione del &#8211; capitalismo selvaggio &#8211; o del &#8211; mercato selvaggio -, cio\u00e8 del mercato senza regole, senza solidariet\u00e0, separato dall\u2019ordine morale.<br \/>\nDarwin scriveva: &#8221; <em>tra tutti gli uomini ci deve essere lotta aperta; (\u2026) le razze umane pi\u00f9 civili stermineranno e si sostituiranno in tutto il mondo a quelle selvagge&#8221;<\/em> (cfr Giuseppe Sermonti, Roberto Fondi, <em>Dopo Darwin, critica all\u2019evoluzionismo,<\/em> Rusconi, Milano 1980, p.6). I darwinisti sociali non si rendono conto che nell&#8217;uomo, a differenza del semplice animale, compare la ragione e per questo l&#8217;uomo viene detto animale razionale. Mentre gli animali seguono solo l&#8217;istinto e si mantengono in vita con la lotta, l&#8217;uomo pu\u00f2 controllare e guidare gli istinti con la volont\u00e0 e con la ragione e pu\u00f2 mettere l\u2019istinto di aggressivit\u00e0 al servizio della giustizia e dei diritti degli altri.<\/p>\n<p>Il capitalismo selvaggio segue Darwin e pensa che la lotta economica fra gli uomini, migliori l&#8217;umanit\u00e0 perch\u00e9 distrugge i deboli e fa sopravvivere i forti: giganti del capitalismo selvaggio come John D. Rockefeller e Andrew Carnegie facevano regolarmente appello ai principi darviniani <em>(cfr James Rachels, Creati dagli animali, implicazioni morali del darwinismo,<\/em> edizioni di comunit\u00e0, Milano 1996, p .77 ).<\/p>\n<p>Il comunismo segue Darwin e pensa che la lotta di classe porti al miglioramento della materia: Marx dichiarava che il libro di Darwin era molto importante perch\u00e9 permetteva di fondare la lotta di classe sul principio della selezione naturale e Iosif Stalin diventava rivoluzionario dopo aver letto Darwin (cfr James Rachels, ivi, p.4; cfr Richard Wurmbrand, <em>L\u2019altra faccia di Carlo Marx,<\/em> Editrice Uomini Nuovi, Marchirolo\u00a0[ Varese ],1984, trad. italiana, p.80 ).<\/p>\n<p>Il marxista Ludwig Woltmann, dirigente socialista tedesco, univa organicamente la filosofia marxista con il darwinismo: per Woltmann la lotta di classe era solo un aspetto della universale lotta fra le razze, necessaria all\u2019evoluzione dell\u2019umanit\u00e0. Egli, pur essendo di origini ebraiche, sosteneva la superiorit\u00e0 razziale dell\u2019ariano e del tedesco. <em>(<\/em>cfr Zeev Sternhell, <em>La destra rivoluzionaria,<\/em> Corbaccio, Milano 1977, trad. italiana, pp.173 &#8211; 174 )<\/p>\n<p>Anche il nazional-socialismo segue Darwin e crede che la lotta fra le razze sia necessaria per il miglioramento dell&#8217;umanit\u00e0 Il comunismo, dottrina inventata da Karl Marx e Friedrich Engels, \u00e8 una soluzione falsa ai problemi del capitalismo selvaggio. Per il comunismo il mondo \u00e8 materia in continua evoluzione verso il meglio, l\u2019uomo \u00e8 solo un prodotto della materia. La guerra fra gli uomini &#8211; <em>lotta di classe<\/em> &#8211; porta al miglioramento della materia e il partito comunista deve favorire la lotta fra gli uomini. Scrive Engels che il comunismo distrugge &#8211; (\u2026) <em>tutte le nozioni di verit\u00e0 assoluta, definitiva (\u2026). Non vi \u00e8 niente di definitivo, di assoluto, di sacro (\u2026) non esiste altro che il processo ininterrotto del divenire e del transitorio.- (<\/em>cfr Jean Daujat<em>, Conoscere il ComunismoSociet\u00e0<\/em> editrice Il Falco, trad. italiana, Milano 1977, p.36 ).<\/p>\n<p>Marx e Engels, nel Manifesto del Partito comunista scrivono che il comunismo abolisce tutte le verit\u00e0 come il diritto, la morale, la religione, la libert\u00e0 (cfr K. Marx e F. Engels, <em>il Manifesto del partito comunista,<\/em> Einaudi, Torinio 1974, trad. italiana, p.156 ). Nel comunismo non esiste pi\u00f9 alcun diritto, alcuna libert\u00e0, alcuna verit\u00e0, esistono solo le esigenze dell\u2019evoluzione della materia e le esigenze della lotta di classe che deve accelerarla. Nei loro scritti sull\u2019India e sulla Cina, Marx e Engels si rallegrano cinicamente della miseria generata dai tentativi inglesi di industrializzazione forzata dell\u2019Oriente perch\u00e9 essa alimenter\u00e0 la rivoluzione: i crimini sociali ed il disagio sociale sono lo strumento prezioso della storia <em>(cfr Karl Marx, la dominazione britannica in India,<\/em> in Marx-Engels, India-Cina-Russia, Il Saggiatore, Milano 1970, pp.76-77 ).<\/p>\n<p>Marx afferma che &#8211; <em>la violenza \u00e8 la levatrice della storia<\/em>-. Nel Manifesto del Partito Comunista, Marx e Engels riassumono tutto il comunismo in due princ\u00ecpi: <em>abolizione della propriet\u00e0 e abolizione della famiglia<\/em> (cfr K. Marx e F. Engels,<em> il Manifesto del Partito Comunista,<\/em> op. cit., p.148 e p. 152).<\/p>\n<p>La dottrina della Chiesa Cattolica insegna che il comunismo \u00e8 una dottrina perversa e spiega che il comunismo, l\u00e0 dove giunge al potere, \u00e8 un sistema peggiore del capitalismo selvaggio che pretende di combattere. Infatti il comunismo crea una forma di capitalismo pi\u00f9 feroce<em>: il capitalismo di stato<\/em>. L\u2019abolizione della propriet\u00e0 privata attuata dai comunisti distrugge ogni forma di libert\u00e0 creando una schiavit\u00f9 totale e porta la societ\u00e0 alla miseria e alla fame: <em>dove esiste la tirannia, il comunismo porta la schiavit\u00f9, dove esiste la povert\u00e0, il comunismo porta la morte per fame.<\/em><\/p>\n<p>L\u2019abolizione della propriet\u00e0 privata provoc\u00f2 in URSS la morte per fame di 13 milioni di persone nel 1930. In Cina l\u2019abolizione della propriet\u00e0 privata provoc\u00f2 la morte per fame di 60 milioni di persone negli anni 1958-1960.<\/p>\n<p>La seconda guerra mondiale ha provocato 60 milioni di morti &#8211; in Italia 1 milione di morti -. Il comunismo, con la sua politica di repressione detta proletaria, finalizzata alla costruzione del paradiso socialista, ha provocato 212 milioni di morti, tra morti ammazzati e morti per fame: 60 milioni di morti in URSS, 150 milioni di morti in Cina, 2 milioni di morti in Cambogia, 7 mila religiosi massacrati dagli anarco-comunisti in Spagna.<\/p>\n<p>Vladimir Il\u2019ic Ul\u2019janov, detto Lenin, primo segretario del partito comunista sovietico, scrive: &#8221; <em>nella nostra lotta per il potere non dobbiamo arrestarci davanti a nessun principio morale. Dobbiamo essere pronti a compiere qualsiasi illegalit\u00e0, inganno menzogna<\/em>&#8221; <em>(V.I. Lenin, Opere scelte,<\/em> edizioni in lingue estere, Mosca 1946-1948; cfr F. Camillo Gubetti<em>, Per uno stato nuovo,<\/em> Volpe ditore, Roma 1972, p.120 ). E ancora: &#8220;<em>se per la causa del comunismo dovessimo eliminare i nove decimi della popolazione non dobbiamo fermarci davanti a ci\u00f2<\/em>&#8221; ( V.I. Lenin, ibidem; cfr F. Camillo Gubetti, ibidem, p. 73 ).<\/p>\n<p>I campi di concentramento sovietici <em>&#8211; gulag<\/em> &#8211; precedono Stalin: infatti essi vengono istituiti da Lenin il 23 luglio 1918 e sar\u00e0 Lenin a volere lo sterminio dei nobili e del clero, dei social-rivoluzionari di sinistra, dei menscevichi ( partito operaio social-democratico russo ), degli anarchici e dei marinai di Kronstadt (cfr Jean Claude Chesnais,<em> Il gulag \u00e8 scomparso ?, <\/em>Quaderni di Crisrtianit\u00e0, anno II, n.5, Piacenza estate- inverno 1986, p.58 ).<\/p>\n<p>Liberalismo selvaggio, comunismo e nazional-socialismo negano l&#8217;origine divina dell&#8217;uomo: per queste ideologie <em>l&#8217;uomo non \u00e8 un valore ma soltanto un prodotto dell&#8217;economia o della biologia<\/em> e quindi la guerra fra gli uomini serve per migliorare l&#8217;economia o la razza. Mentre l\u2019idea nazista \u00e8 stata uccisa dal genocidio che ha compiuto &#8211; <em>dopo Aushwitz non si pu\u00f2 pi\u00f9 essere nazisti<\/em> -, l\u2019idea comunista continua ad essere giustificata nonostante i 212 milioni di morti. Anche se le due ideologie, nazional &#8211; socialismo e comunismo, hanno provocato milioni di morti, anche se entrambe hanno avuto un\u2019analoga inclinazione <em>sterminazionista, <\/em>permane una disparit\u00e0 di trattamento fra i due <em>gemelli eterozigoti<\/em>, secondo la definizione dello storico della Sorbona, Pierre Chaunu.<br \/>\n<em><br \/>\nIl nazismo viene considerato come il male assoluto mentre il comunismo continua ad essere considerato una bella utopia realizzata male.<\/em> Questo avviene perch\u00e9 la vera natura del comunismo <em>&#8211; cio\u00e8 la filosofia del materialismo dialettico di Karl Marx e Friedrich Engels &#8211;<\/em> viene coperta da un\u2019utopia liberatrice e portatrice di giustizia sociale e la maggior parte degli uomini vede e considera solo gli aspetti esteriori del comunismo e cede alla tentazione delle sue abbaglianti promesse.<\/p>\n<p>Il comunismo, scrive Alain Besancon, membro dell\u2019Institut de France, <em>\u00e8 pi\u00f9 perverso<\/em> del nazismo perch\u00e9 si serve strumentalmente dello spirito di liberazione e di giustizia sociale ed \u00e8 capace di trasformare brava gente in criminali, facendo passare il crimine per una ineluttabile necessit\u00e0 storica. Dice Besancon<em>:- il comunismo, a differenza del nazismo, si presenta come un\u2019ideologia liberatrice, portatrice di giustizia. Ma siccome produce risultati come l\u2019espropriazione e l\u2019assassinio, direi che aggiunge semplicemente la menzogna al crimine. (\u2026) Il nazismo \u00e8 apertamente criminale a priori, l\u2019altro \u00e8 criminale a posteriori. Ma questa bugia iniziale del comunismo lo rende pi\u00f9 perverso perch\u00e9 capace di trasformare brava gente in criminali e persone normalmente intelligenti in abbrutiti. &#8211;<\/em> (PierLuca Pucci Poppi<em>, Nazismo e comunismo, le due orribili facce di una stessa medaglia,<\/em> intervista ad Alain Besancon, Pierluigi Battista, Sergio Romano e Thierry Wolton, in Il Giornale, 14 settembre 2000, p. 34; cfr Alain Besancon,<em> Novecento il Secolo del male, nazismo, comunismo, shoa, <\/em>ideazione editrice, Roma 2000 )<em>.<\/em><\/p>\n<p>Papa Pio XI, nella enciclica <em>Divini Redemptoris<\/em>, aveva profeticamente individuato questa perversit\u00e0 tipica del comunismo. Egli scriveva:- <em>ma come mai pu\u00f2 avvenire che un tale sistema, scientificamente da lungo tempo sorpassato, confutato dalla realt\u00e0 pratica; come pu\u00f2 avvenire, diciamo, che un tale sistema possa diffondersi cos\u00ec rapidamente in tutte le parti del mondo? La spiegazione sta nel fatto che assai pochi hanno potuto penetrare la vera natura del comunismo; i pi\u00f9 invece cedono alla tentazione abilmente presentata sotto le pi\u00f9 abbaglianti promesse. Sotto pretesto che si vuole soltanto migliorare la sorte delle classi lavoratrici, togliere abusi reali prodotti dall\u2019economia liberale e ottenere una pi\u00f9 equa distribuzione dei beni terreni ( scopi senza dubbio pienamente legittimi ), e profittando della mondiale crisi economica, si riesce ad attirare nella sfera d\u2019influenza del comunismo anche quei ceti della popolazione che per principio rigettano ogni materialismo e ogni terrorismo. E siccome ogni errore contiene sempre una parte di vero, questo lato della verit\u00e0 che abbiamo accennato, messo astutamente in mostra a tempo e luogo per coprire, quando conviene, la crudezza ributtante e inumana dei principi e dei metodi del comunismo, seduce anche spiriti non volgari, fino a diventarne a loro volta gli apostoli presso giovani intelligenze ancora poco atte ad avvertirne gli intrinseci errori<\/em>.- (Pio XI, Lettera Enciclica <em>Divini Redemptoris sul comunismo ateo,<\/em> 19 marzo 1937, n.15).<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Liberismo, comunismo e nazismo sono ideologie materialiste che pretendono di applicare agli uomini le stessa legge che regola l&#8217;evoluzione della specie nel mondo animale: la lotta. * * *<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-capitalismo-selvaggio-e-il-comunismo\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":28847,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[32,94],"tags":[139,389,486],"class_list":["post-546","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-filosofia-del-comunismo","category-nazionalsocialismo","tag-comunismo","tag-filosofia-del-comunismo-2","tag-nazionalsocialismo-2","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il capitalismo selvaggio e il comunismo - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-capitalismo-selvaggio-e-il-comunismo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il capitalismo selvaggio e il comunismo - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-capitalismo-selvaggio-e-il-comunismo\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2005-05-20T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-12-16T14:59:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/05\/ferocia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"270\" \/>\n\t<meta property=\"og:image:height\" content=\"187\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-capitalismo-selvaggio-e-il-comunismo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-capitalismo-selvaggio-e-il-comunismo\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Il capitalismo selvaggio e il comunismo\",\"datePublished\":\"2005-05-20T22:00:00+00:00\",\"dateModified\":\"2015-12-16T14:59:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-capitalismo-selvaggio-e-il-comunismo\\\/\"},\"wordCount\":1769,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-capitalismo-selvaggio-e-il-comunismo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/05\\\/ferocia.jpg\",\"keywords\":[\"comunismo\",\"filosofia del comunismo\",\"nazionalsocialismo\"],\"articleSection\":[\"Comunismo\",\"Nazionalsocialismo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-capitalismo-selvaggio-e-il-comunismo\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-capitalismo-selvaggio-e-il-comunismo\\\/\",\"name\":\"Il capitalismo selvaggio e il comunismo - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-capitalismo-selvaggio-e-il-comunismo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-capitalismo-selvaggio-e-il-comunismo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/05\\\/ferocia.jpg\",\"datePublished\":\"2005-05-20T22:00:00+00:00\",\"dateModified\":\"2015-12-16T14:59:40+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-capitalismo-selvaggio-e-il-comunismo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-capitalismo-selvaggio-e-il-comunismo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-capitalismo-selvaggio-e-il-comunismo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/05\\\/ferocia.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/05\\\/ferocia.jpg\",\"width\":270,\"height\":187},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-capitalismo-selvaggio-e-il-comunismo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il capitalismo selvaggio e il comunismo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il capitalismo selvaggio e il comunismo - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-capitalismo-selvaggio-e-il-comunismo\/","og_locale":"it_IT","og_type":"article","og_title":"Il capitalismo selvaggio e il comunismo - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-capitalismo-selvaggio-e-il-comunismo\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2005-05-20T22:00:00+00:00","article_modified_time":"2015-12-16T14:59:40+00:00","og_image":[{"width":270,"height":187,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/05\/ferocia.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"9 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-capitalismo-selvaggio-e-il-comunismo\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-capitalismo-selvaggio-e-il-comunismo\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Il capitalismo selvaggio e il comunismo","datePublished":"2005-05-20T22:00:00+00:00","dateModified":"2015-12-16T14:59:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-capitalismo-selvaggio-e-il-comunismo\/"},"wordCount":1769,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-capitalismo-selvaggio-e-il-comunismo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/05\/ferocia.jpg","keywords":["comunismo","filosofia del comunismo","nazionalsocialismo"],"articleSection":["Comunismo","Nazionalsocialismo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-capitalismo-selvaggio-e-il-comunismo\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-capitalismo-selvaggio-e-il-comunismo\/","name":"Il capitalismo selvaggio e il comunismo - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-capitalismo-selvaggio-e-il-comunismo\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-capitalismo-selvaggio-e-il-comunismo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/05\/ferocia.jpg","datePublished":"2005-05-20T22:00:00+00:00","dateModified":"2015-12-16T14:59:40+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-capitalismo-selvaggio-e-il-comunismo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-capitalismo-selvaggio-e-il-comunismo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-capitalismo-selvaggio-e-il-comunismo\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/05\/ferocia.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/05\/ferocia.jpg","width":270,"height":187},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-capitalismo-selvaggio-e-il-comunismo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Il capitalismo selvaggio e il comunismo"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/546","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=546"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/546\/revisions"}],"predecessor-version":[{"id":28849,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/546\/revisions\/28849"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/28847"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=546"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=546"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=546"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}