{"id":54423,"date":"2022-07-14T00:00:57","date_gmt":"2022-07-13T22:00:57","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=54423"},"modified":"2024-04-12T10:38:48","modified_gmt":"2024-04-12T08:38:48","slug":"la-corte-suprema-usa-ha-rimesso-ordine-sullaborto","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-corte-suprema-usa-ha-rimesso-ordine-sullaborto\/","title":{"rendered":"La Corte suprema Usa ha rimesso ordine sull&#8217;aborto"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-54373 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/06\/aborto_corte_suprema_Usa.jpg\" alt=\"\" width=\"295\" height=\"157\" \/>Abstract: <\/strong><em>la Corte suprema Usa ha rimesso ordine sull&#8217;aborto\u00a0 facendo si che le corti statali non possano aggirare la legislazione federale . Un esempio anche per l&#8217;Italia in cui il pregiudizio abortista \u00e8 forte, tanto da far passare sotto silenzio la deriva &#8220;giuristocratica&#8221;<br \/>\n<\/em><\/span><\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\"><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/www.centrostudilivatino.it\/rosario-livatino\/\" target=\"_blank\" rel=\"noopener\"><strong>Centro Studi Rosario Livatino<\/strong><\/a> <\/span>\u00a0<\/span><span style=\"color: #000000;\">14 Luglio 2022\u00a0<\/span><\/p>\n<h3 style=\"text-align: center;\">La Corte Suprema ha rimesso al loro posto i giudici<\/h3>\n<h3 style=\"text-align: center;\">(non solo sull\u2019aborto)<\/h3>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"> <em>Da pi\u00f9 di tre decenni schiere di giuristi propongono apertis verbis l\u2019aggiramento dell\u2019autorit\u00e0 rappresentativa come qualcosa di salutare e di raccomandabile.<\/em><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\">di <strong>Alfredo Mantovano<\/strong>,<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"> <img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-52910 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/11\/Usa_corte_suprema.jpg\" alt=\"\" width=\"225\" height=\"225\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/11\/Usa_corte_suprema.jpg 225w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/11\/Usa_corte_suprema-150x150.jpg 150w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/>\u201cUn Paese che ha un disperato bisogno di ritrovare il senso della politica che \u00e8 dialogo (\u2026) sprofonda sempre pi\u00f9 nelle guerre culturali: conflitti basati su convincimenti ideologici che rendono pressoch\u00e9 impossibile ricucire i fili di un dialogo democratico\u201d: in questi termini il <em>Corriere della sera<\/em> ha commentato la sentenza della Corte Suprema USA in tema di aborto, il 25 giugno scorso, all\u2019indomani della pronuncia. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Dunque, per il principale quotidiano italiano, con un editoriale comparso in prima pagina, il \u201cdialogo democratico\u201d si realizza per imposizione di sentenza, non per dibattito in un Parlamento. Dobbs v. Jackson, al netto della questione aborto, \u00e8 il provvedimento giudiziario pi\u00f9 odiato degli ultimi decenni anche perch\u00e9 si contrappone a questo convincimento. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-41290 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/10\/colonie_Inglesi_America-300x287.jpg\" alt=\"\" width=\"300\" height=\"287\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/10\/colonie_Inglesi_America-300x287.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/10\/colonie_Inglesi_America.jpg 321w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Facciamo un passo indietro. Gli USA sono una Repubblica che nel corso dei decenni si \u00e8 formata per progressiva federazione di Stati gi\u00e0 esistenti. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Ricordarlo \u00e8 banale, ma non guasta, soprattutto per noi italiani, vista la nostra storia di unificazione forzata da parte di una realt\u00e0 statuale centralizzata. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Tornando agli USA, ciascuno Stato, dai 13 iniziali in poi, possedeva gi\u00e0, allorch\u00e9 si federava, e poi ha mantenuto, un proprio Parlamento, proprie leggi, non necessariamente coincidenti con quelle dello Stato confinante, una propria giurisdizione, financo una propria Corte Suprema; fra Stato e Stato sono diverse le sanzioni penali pi\u00f9 pesanti, se \u00e8 vero che la pena di morte \u00e8 oggi prevista da un numero di Stati inferiore rispetto a quelli che l\u2019hanno abolita.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>Dialogo democratico? <\/strong>Il Congresso americano \u2013 Camera dei rappresentanti e Senato \u2013 ha competenza nelle materie riconducibili ai principi fondanti e alla Costituzione federale, senza sovrapporsi a quel che spetta ai singoli Stati, e la Corte Suprema federale \u00e8 giudice di ultima istanza sui casi per i quali sia controversa l\u2019applicazione del diritto federale. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">In sintesi, essa ha un ruolo importantissimo \u2013 oltre ad annullare una legge, pu\u00f2 cancellare gli ordini esecutivi del Presidente, se l\u2019una o gli altri violino la Costituzione \u2013 ma limitato.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-49076 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/11\/Usa_Campidoglio.jpg\" alt=\"\" width=\"329\" height=\"224\" \/>Questa noiosa premessa per dire che sull\u2019aborto l\u2019anomalia non si \u00e8 realizzata il 24 giugno 2022, bens\u00ec nel 1973, con la precedente sentenza Roe vs. Wade. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Fino a quel giorno negli USA l\u2019aborto era disciplinato da ciascuno Stato federato con una legge propria, in modo diversificato fra Stato e Stato, come era e continua a essere per la pena capitale: alcuni Parlamenti statali si erano gi\u00e0 espressi, altri lo avrebbero fatto. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Mentre il \u201cdialogo democratico\u201d \u2013 per riprendere il Corriere \u2013 era in corso nelle istituzioni dedicate al suo esercizio, il 22 gennaio 1973 sette (su nove) giudici della Corte Suprema federale chiusero ogni confronto imponendo a tutti gli States l\u2019aborto a richiesta, uniformando per sentenza le differenti legislazioni.\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"> <img loading=\"lazy\" decoding=\"async\" class=\" wp-image-53429 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/01\/tribunale_Usa_America_giustizia.jpg\" alt=\"\" width=\"328\" height=\"197\" \/>Negli USA il dibattito sui limiti di intervento della Corte Suprema non inizia adesso. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Ha due secoli abbondanti di vita: il primo caso controverso, Marbury vs Madison, risale al 1803, fu un evidente esempio di pronuncia oltre i confini della giurisdizione; fu talmente criticata che per giungere a una vicenda analoga si dovette attendere anche qui mezzo secolo, col caso Dred Scott v. Sandford del 1857, sentenza pur essa ritenuta scandalosa nella forma, e nella sostanza filoschiavista. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Questo per dire che nella pur breve storia degli USA il rispetto delle prerogative dei singoli Stati \u00e8 tema ben vivo nel dibattito politico, prima ancora che giuridico; questo spiega perch\u00e9 nell\u2019incipit della sentenza del 24 giugno i giudici della Corte suprema abbiano sottolineato che \u201cil nostro lavoro \u00e8 interpretare la legge\u201d.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"> <strong>L\u2019invenzione del diritto. <\/strong>La Dobbs v. Jackson \u00e8 importante per ci\u00f2 che afferma in tema di aborto, ma \u00e8 altrettanto importante perch\u00e9 rimette a posto il quadro costituzionale: creare le norme \u2013 essa sancisce \u2013 non spetta alle Corti, bens\u00ec ai rappresentati del popolo, democraticamente eletti, poich\u00e9 ci\u00f2 comporta scelte sulle quali prima ci si confronta in campagna elettorale, al momento dell\u2019assunzione degli impegni con i cittadini votanti, poi nella discussione e nel voto nei Parlamenti. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Impegni similari, e la correlata responsabilit\u00e0 politica, sono invece estranei al ruolo del giudice.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-44494 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/11\/corte_costituzionale.jpg\" alt=\"\" width=\"370\" height=\"246\" \/>Il tab\u00f9 che la Corte Suprema ha fatto cadere non \u00e8 una esclusiva a stelle e strisce: attraversa tutti gli ordinamenti occidentali, Italia in testa. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Da noi l\u2019\u201cinvenzione del diritto\u201d, per riprendere il titolo del libro di un ex presidente della Corte costituzionale, \u00e8 iniziata negli anni 1960 come \u201csupplenza\u201d, il cui esercizio da parte della magistratura \u00e8 stato favorito dall\u2019averla considerata come un intervento neutrale, connotato da terziet\u00e0: ma la realt\u00e0 ha dimostrato l\u2019illusoriet\u00e0 di una prospettiva del genere. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Oggi in tanti riconoscono che la \u201csupplenza\u201d \u00e8 divenuta una categoria ideologica e una forma di controllo delle scelte della politica: lo denunciano e ne scrivono da tempo \u2013 e bene \u2013 intellettuali liberal, e progressisti con significative esperienze istituzionali.\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"> <img loading=\"lazy\" decoding=\"async\" class=\" wp-image-43068 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/05\/parlamento_politica-300x200.jpg\" alt=\"\" width=\"354\" height=\"236\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/05\/parlamento_politica-300x200.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/05\/parlamento_politica-768x512.jpg 768w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/05\/parlamento_politica-1024x682.jpg 1024w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/05\/parlamento_politica.jpg 1400w\" sizes=\"auto, (max-width: 354px) 100vw, 354px\" \/>Questo accade perch\u00e9 da pi\u00f9 di tre decenni schiere di giuristi, taluni dei quali sono diventati anche presidenti della Consulta, propongono apertis verbis l\u2019aggiramento dell\u2019autorit\u00e0 rappresentativa come qualcosa di salutare e di raccomandabile. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Sostengono che il luogo della decisione non \u00e8 bene che sia ancora il Parlamento, perch\u00e9 in esso avvengono scontri di parte; nella loro prospettiva \u00e8 opportuno invece che quella decisione passi al giudice, in quanto gestore di una \u201cprocedura\u201d soft e meno conflittuale: in questo il <em>Corriere della sera<\/em> ha fatto semplicemente eco a una tendenza ideologica, divenuta prassi consolidata.<\/span><\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"color: #000000;\">Un punto di partenza.<\/span> <\/strong><span style=\"color: #000000;\">La sovrapposizione del cosiddetto diritto vivente al diritto vigente, la sostituzione del governo dei giudici al governo della legge \u00e8 accaduto non soltanto per le materie eticamente sensibili, come il fine vita, per es. con la sentenza della Cassazione sul caso di Eluana Englaro, o con quella della Corte costituzionale sul suicidio assistito, bens\u00ec pure in tema di appalti, con conseguenti blocchi di importanti opere pubbliche, o per l\u2019area sanitaria, con le pericolose illusioni nella lotta ai tumori \u2013 ricordiamo la sponda giudiziaria offerta alla cura Di Bella o a Stamina? -, o con disastri ambientali come la xylella. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-47634 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/06\/aborto-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/06\/aborto-300x169.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/06\/aborto-768x432.jpg 768w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/06\/aborto-1024x576.jpg 1024w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/06\/aborto.jpg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Quel che colpisce nel dibattito italiano seguito alla sentenza Dobbs v. Jackson \u00e8 che il pregiudizio abortista \u00e8 da noi cos\u00ec radicato da aver fatto da velo, per coloro che pure denunciano la deriva \u2018giuristocratica\u2019, nel cogliere la portata dell\u2019affermazione della Corte suprema secondo cui il giudice applica, e non inventa, la legge, e i magistrati esercitano la giurisdizione, ma non governano una Nazione. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Invece che ricorrere a quesiti referendari farlocchi o a pseudoriforme peggiorative, \u00e8 questo il punto di partenza per una riforma della giustizia degna di questo nome. Che faccia recuperare l\u2019evidente ritardo culturale che ci separa da Oltre Oceano.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"> da <em>Tempi mensile<\/em>, luglio 2022.\u00a0<\/span><\/p>\n<p>____________________________________________<\/p>\n<p><span style=\"color: #000000;\"><strong>Leggi anche:<\/strong><\/span><\/p>\n<p><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/aborto-usa-ora-anche-per-i-giudici-ce-un-interesse-alla-vita-che-non-si-cancella\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">ABORTO USA\/ Ora anche per i giudici c\u2019\u00e8 un \u201cinteresse alla vita\u201d che non si cancella<\/span><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Abstract: la Corte suprema Usa ha rimesso ordine sull&#8217;aborto\u00a0 facendo si che le corti statali non possano aggirare la legislazione federale . Un esempio anche per l&#8217;Italia in cui il pregiudizio abortista \u00e8 forte, tanto da far passare sotto silenzio la deriva &#8220;giuristocratica&#8221;<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-corte-suprema-usa-ha-rimesso-ordine-sullaborto\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":52405,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,10,76],"tags":[2386,180,2401],"class_list":["post-54423","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aborto","category-diritto","category-stati-uniti","tag-aborto","tag-diritto-2","tag-stati-uniti","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Corte suprema Usa ha rimesso ordine sull&#039;aborto - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"La Corte suprema Usa ha rimesso ordine sull&#039;aborto limitando l&#039;anarchia dei giudici statali che aggiravano l&#039;autorit\u00e0 federale\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-corte-suprema-usa-ha-rimesso-ordine-sullaborto\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Corte suprema Usa ha rimesso ordine sull&#039;aborto - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"La Corte suprema Usa ha rimesso ordine sull&#039;aborto limitando l&#039;anarchia dei giudici statali che aggiravano l&#039;autorit\u00e0 federale\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-corte-suprema-usa-ha-rimesso-ordine-sullaborto\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-13T22:00:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-12T08:38:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/09\/legge_diritto_giustizia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1723\" \/>\n\t<meta property=\"og:image:height\" content=\"1103\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-corte-suprema-usa-ha-rimesso-ordine-sullaborto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-corte-suprema-usa-ha-rimesso-ordine-sullaborto\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"La Corte suprema Usa ha rimesso ordine sull&#8217;aborto\",\"datePublished\":\"2022-07-13T22:00:57+00:00\",\"dateModified\":\"2024-04-12T08:38:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-corte-suprema-usa-ha-rimesso-ordine-sullaborto\\\/\"},\"wordCount\":1173,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-corte-suprema-usa-ha-rimesso-ordine-sullaborto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/legge_diritto_giustizia.jpg\",\"keywords\":[\"Aborto\",\"diritto\",\"Stati Uniti\"],\"articleSection\":[\"Aborto\",\"Diritto\",\"Stati Uniti\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-corte-suprema-usa-ha-rimesso-ordine-sullaborto\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-corte-suprema-usa-ha-rimesso-ordine-sullaborto\\\/\",\"name\":\"La Corte suprema Usa ha rimesso ordine sull'aborto - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-corte-suprema-usa-ha-rimesso-ordine-sullaborto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-corte-suprema-usa-ha-rimesso-ordine-sullaborto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/legge_diritto_giustizia.jpg\",\"datePublished\":\"2022-07-13T22:00:57+00:00\",\"dateModified\":\"2024-04-12T08:38:48+00:00\",\"description\":\"La Corte suprema Usa ha rimesso ordine sull'aborto limitando l'anarchia dei giudici statali che aggiravano l'autorit\u00e0 federale\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-corte-suprema-usa-ha-rimesso-ordine-sullaborto\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-corte-suprema-usa-ha-rimesso-ordine-sullaborto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-corte-suprema-usa-ha-rimesso-ordine-sullaborto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/legge_diritto_giustizia.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/legge_diritto_giustizia.jpg\",\"width\":1723,\"height\":1103,\"caption\":\"Gold scales of justice and books on brown background\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-corte-suprema-usa-ha-rimesso-ordine-sullaborto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Corte suprema Usa ha rimesso ordine sull&#8217;aborto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Corte suprema Usa ha rimesso ordine sull'aborto - Rassegna Stampa Cattolica","description":"La Corte suprema Usa ha rimesso ordine sull'aborto limitando l'anarchia dei giudici statali che aggiravano l'autorit\u00e0 federale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-corte-suprema-usa-ha-rimesso-ordine-sullaborto\/","og_locale":"it_IT","og_type":"article","og_title":"La Corte suprema Usa ha rimesso ordine sull'aborto - Rassegna Stampa Cattolica","og_description":"La Corte suprema Usa ha rimesso ordine sull'aborto limitando l'anarchia dei giudici statali che aggiravano l'autorit\u00e0 federale","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-corte-suprema-usa-ha-rimesso-ordine-sullaborto\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2022-07-13T22:00:57+00:00","article_modified_time":"2024-04-12T08:38:48+00:00","og_image":[{"width":1723,"height":1103,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/09\/legge_diritto_giustizia.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"9 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-corte-suprema-usa-ha-rimesso-ordine-sullaborto\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-corte-suprema-usa-ha-rimesso-ordine-sullaborto\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"La Corte suprema Usa ha rimesso ordine sull&#8217;aborto","datePublished":"2022-07-13T22:00:57+00:00","dateModified":"2024-04-12T08:38:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-corte-suprema-usa-ha-rimesso-ordine-sullaborto\/"},"wordCount":1173,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-corte-suprema-usa-ha-rimesso-ordine-sullaborto\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/09\/legge_diritto_giustizia.jpg","keywords":["Aborto","diritto","Stati Uniti"],"articleSection":["Aborto","Diritto","Stati Uniti"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-corte-suprema-usa-ha-rimesso-ordine-sullaborto\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-corte-suprema-usa-ha-rimesso-ordine-sullaborto\/","name":"La Corte suprema Usa ha rimesso ordine sull'aborto - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-corte-suprema-usa-ha-rimesso-ordine-sullaborto\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-corte-suprema-usa-ha-rimesso-ordine-sullaborto\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/09\/legge_diritto_giustizia.jpg","datePublished":"2022-07-13T22:00:57+00:00","dateModified":"2024-04-12T08:38:48+00:00","description":"La Corte suprema Usa ha rimesso ordine sull'aborto limitando l'anarchia dei giudici statali che aggiravano l'autorit\u00e0 federale","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-corte-suprema-usa-ha-rimesso-ordine-sullaborto\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-corte-suprema-usa-ha-rimesso-ordine-sullaborto\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-corte-suprema-usa-ha-rimesso-ordine-sullaborto\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/09\/legge_diritto_giustizia.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/09\/legge_diritto_giustizia.jpg","width":1723,"height":1103,"caption":"Gold scales of justice and books on brown background"},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-corte-suprema-usa-ha-rimesso-ordine-sullaborto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"La Corte suprema Usa ha rimesso ordine sull&#8217;aborto"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/54423","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=54423"}],"version-history":[{"count":3,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/54423\/revisions"}],"predecessor-version":[{"id":59989,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/54423\/revisions\/59989"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/52405"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=54423"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=54423"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=54423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}