{"id":54361,"date":"2022-06-30T00:00:40","date_gmt":"2022-06-29T22:00:40","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=54361"},"modified":"2024-04-13T11:21:16","modified_gmt":"2024-04-13T09:21:16","slug":"una-guerra-culturale-globale-che-loccidente-deve-vincere","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-guerra-culturale-globale-che-loccidente-deve-vincere\/","title":{"rendered":"Una guerra culturale globale che l&#8217;Occidente deve vincere\u00a0\u00a0\u00a0\u00a0"},"content":{"rendered":"<p style=\"text-align: center;\"><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/atfp.it\/\" target=\"_blank\" rel=\"noopener\"><strong>Tradizione Famiglia Propriet\u00e0<\/strong><\/a><\/span><span style=\"color: #000000;\"> newsletter 28 Giugno 2022<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-54362 aligncenter\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/06\/getta_bambino_acqua_sporca-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/06\/getta_bambino_acqua_sporca-300x225.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/06\/getta_bambino_acqua_sporca-768x576.jpg 768w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/06\/getta_bambino_acqua_sporca.jpg 960w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\">di<strong> John Horvat <\/strong><\/span><\/p>\n<h4 style=\"text-align: center;\"><span style=\"color: #000000;\"><strong>Falso e vero Occidente<\/strong><\/span><\/h4>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">La guerra in Ucraina \u00e8 pi\u00f9 di un&#8217;ingiusta guerra di aggressione da parte della Russia. Ha come obiettivo anche l&#8217;Occidente come concetto e come blocco geopolitico. Una guerra culturale globale si profila all&#8217;orizzonte, minacciando di distruggere ogni cosa.<\/span><\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-53563 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/02\/Russia_Ucraina.jpg\" alt=\"\" width=\"166\" height=\"180\" \/>Due nozioni di ci\u00f2 che si intende per &#8220;Occidente&#8221;, una vera e l&#8217;altra falsa, sono al centro di questa battaglia culturale. Questi due modelli uniscono i <em>liberal <\/em>e mettono i conservatori l&#8217;uno contro l&#8217;altro. L&#8217;opinione pubblica si trova confusa, incapace di determinare quale versione debba essere difesa o quale contrastata.<\/span><\/p>\n<h4 style=\"text-align: center;\"><span style=\"color: #000000;\"><strong>La nozione di Cristianit\u00e0<\/strong><\/span><\/h4>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">L\u2019autentica nozione potrebbe essere chiamata Occidente &#8220;veramente cristiano&#8221; e corrisponde a quel blocco di nazioni che hanno guidato il mondo grazie al loro legame con il passato europeo e in modo particolare, con la sua ricca cultura cristiana. Quell\u2019Occidente coincide con la Cristianit\u00e0 e si applica a tutte quelle aree \u2013 anche nel Nuovo Mondo &#8211; che hanno condiviso una visione metafisica e religiosa della vita.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-49752 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2021\/01\/Europa_cristiana_cristianit\u00e0.jpg\" alt=\"\" width=\"289\" height=\"192\" \/>Questo Occidente ha sviluppato sistemi di legge, educazione, di logica e di morale che favoriscono il progresso e la prosperit\u00e0 umana. La sua metafisica si basa sulla natura delle cose e su una verit\u00e0 oggettiva conoscibile. Il centro di questa civilt\u00e0 \u00e8 Dio, la sua legge e la Chiesa.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">La societ\u00e0 moderna beneficia dei resti sopravvissuti di questa Cristianit\u00e0, anche se ripudia le sue lontane radici. Se oggi c&#8217;\u00e8 un resto di ordine nella societ\u00e0 occidentale \u00e8 perch\u00e9 le tracce di essa si trovano ancora nelle sue strutture, leggi e istituzioni.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Ma la societ\u00e0 secolare postmoderna di oggi rifiuta questo modello. Anzi, l&#8217;establishment &#8220;occidentale&#8221; e la sua corrispondente cultura scristianizzata e decadente, lo disprezzano.<\/span><\/p>\n<h4 style=\"text-align: center;\"><span style=\"color: #000000;\"><strong>L&#8217;Occidente guidato da Davos <\/strong><\/span><\/h4>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Il secondo concetto di &#8220;Occidente&#8221; \u00e8 qualcosa di completamente diverso dal concetto di Cristianit\u00e0. Sia la sinistra che la destra usano questa definizione per attaccare il vero Occidente cristiano. Questo &#8220;Occidente&#8221; \u00e8 associato a quelle stesse nazioni legate in un modo o nell\u2019altro all&#8217;Europa, e si esprime in vaste reti economiche e politiche che incarnano un ordine basato su regole che sostengono il liberalismo come sistema politico della modernit\u00e0. Tale \u201cOccidente\u201d potrebbe essere definito come l&#8217;Occidente guidato da Davos.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-49297 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/11\/Davos_reset-300x169.jpg\" alt=\"\" width=\"283\" height=\"159\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/11\/Davos_reset-300x169.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/11\/Davos_reset-768x432.jpg 768w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/11\/Davos_reset-1024x576.jpg 1024w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/11\/Davos_reset.jpg 1280w\" sizes=\"auto, (max-width: 283px) 100vw, 283px\" \/>Questo &#8220;Occidente&#8221; prende in prestito enormemente dal capitale sociale e dall&#8217;infrastruttura razionale dell&#8217;Occidente cristiano, anche se mai riconosce questo debito. Esso \u00e8 vittima della paradossale tenebrosit\u00e0 dei pensatori cosiddetti illuministi che hanno rotto l&#8217;unit\u00e0 sociale e morale del vero Occidente cristiano promuovendo un mondo individualista e materialista. Tuttavia, questo \u201cOccidente\u201d diffonde anche la propria decadenza secolare accelerando la sua caduta.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-46561 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/03\/liberalismo-300x166.jpg\" alt=\"\" width=\"264\" height=\"146\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/03\/liberalismo-300x166.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/03\/liberalismo.jpg 302w\" sizes=\"auto, (max-width: 264px) 100vw, 264px\" \/>Se il vero Occidente cristiano \u00e8 il bambino, la versione guidata da Davos \u00e8 l&#8217;acqua della vasca (1). La seconda viene usata contro la prima. I <em>liberal<\/em> odiano i valori del vero Occidente cristiano, pur godendo di tutte le comodit\u00e0 e i progressi che ne derivano. I conservatori ripudiano l&#8217;Occidente guidato da Davos mentre devono lottare per sopravvivere in mezzo alla sua depravazione morale e al suo secolarismo senza Dio.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-33170 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/caduta_Muro.jpg\" alt=\"\" width=\"279\" height=\"180\" \/>Questo Occidente guidato da Davos sembrava aver trionfato ovunque nel periodo successivo alla Guerra Fredda. Tutto pareva andare diritto verso un unico villaggio globale che inseguiva piaceri e passioni in un festival di frenetica sregolatezza, senza alcun riconoscimento di Dio. La sua tecnologia avanzata ha permesso poi di unire tutte le cose in modo istantaneo e senza sforzo.<\/span><\/p>\n<h4 style=\"text-align: center;\"><span style=\"color: #000000;\"><strong>La frantumazione dell\u2019Occidente guidato da Davos<\/strong><\/span><\/h4>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"> <img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-53295 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/01\/virus-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/01\/virus-300x169.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/01\/virus.jpg 305w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Questo trionfo \u00e8 parso sicuro fino a quando il COVID e poi l&#8217;Ucraina hanno destabilizzato ulteriormente le cose. Il conflitto in Ucraina prende di mira l&#8217;Occidente guidato da Davos e le sue vaste reti. Le reti globali che mantenevano l&#8217;egemonia occidentale sono ora lacerate. In pochi mesi, la guerra in Ucraina ha spazzato via il lavoro di globalizzazione di una intera generazione.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Entrambe le parti sono impegnate in un lavoro di disaccoppiamento. Ogni nuova sanzione imposta alla Russia rende pi\u00f9 difficile la ricostituzione di un mondo globalizzato. Ogni nuovo passo della Russia dentro il territorio dell&#8217;Ucraina rappresenta la frantumazione del mondo in nuove egemonie, blocchi commerciali, correnti ideologiche e partnership scomode. Il risultato finale sar\u00e0 l&#8217;irreparabile separazione dell&#8217;Est dall&#8217;Ovest.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"> <img loading=\"lazy\" decoding=\"async\" class=\" wp-image-46643 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/03\/sovranit\u00e0_stati_mondo-300x149.jpg\" alt=\"\" width=\"268\" height=\"133\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/03\/sovranit\u00e0_stati_mondo-300x149.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/03\/sovranit\u00e0_stati_mondo-768x381.jpg 768w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/03\/sovranit\u00e0_stati_mondo-1024x508.jpg 1024w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/03\/sovranit\u00e0_stati_mondo.jpg 2000w\" sizes=\"auto, (max-width: 268px) 100vw, 268px\" \/>Questo Occidente come unit\u00e0 geopolitica si sta frantumando, aprendo la strada a un mondo multipolare sconosciuto. Molti a destra accolgono questo sviluppo come una liberazione da quella &#8216;acqua sporca\u2019 che occupa la vasca culturale. Allo stesso tempo, gli esponenti della sinistra celebrano la scomparsa dell&#8217;influenza del \u2018bambino\u2019, cio\u00e8 di quell\u2019Occidente cristiano che ancora mantiene un certo ordine morale nella societ\u00e0. <\/span><\/p>\n<h4 style=\"text-align: center;\"><span style=\"color: #000000;\"><strong>L&#8217;annientamento del vero Occidente cristiano <\/strong><\/span><\/h4>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-45111 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/11\/chiesa_brucia_persecuzioni.jpg\" alt=\"\" width=\"265\" height=\"149\" \/>Tuttavia, l&#8217;obiettivo pi\u00f9 importante della guerra in Ucraina \u00e8 il vero Occidente cristiano. La Russia non si \u00e8 mai del tutto unita a questo vero Occidente cristiano. \u00c8 una nazione dell&#8217;Europa orientale che l&#8217;Ortodossia di stampo orientale ha dominato per quasi un millennio. Partendo da questo passato, il movimento eurasiatico di Vladimir Putin cerca di creare una rete anti-occidentale di Paesi orientati da strane ideologie e rigide autocrazie. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-54363 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/06\/Cina_Russia_Pitin_Xi_Jiping.jpg\" alt=\"\" width=\"275\" height=\"183\" \/>La Russia, la Cina e i loro Stati clienti cercano di soppiantare il vero Occidente cristiano con un quadro che ricicla vecchi errori (molti dei quali paradossalmente occidentali) basati su un misto di nazionalismo, marxismo, gnosticismo e persino elementi mistici. In effetti, ci\u00f2 che unisce l&#8217;euroasiatismo pan-slavo della Russia odierna (e di Alexander Dugin) con la &#8220;nuova era del socialismo con caratteristiche cinesi&#8221; di Xi Jinping \u00e8 il loro comune carattere militante anti-occidentale e filo-marxista.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Gli ideologi russi euroasiatisti odiano le tracce del vero Occidente cristiano che ancora sopravvivono nelle istituzioni, nelle regole e nei sistemi di oggi. Da molto, prendono di mira soprattutto la Chiesa cattolica e le sue dottrine che mettono in crisi la stagnante ortodossia. Questi pensatori rifiutano l&#8217;ordine razionale dell&#8217;Occidente e immaginano una Russia primitiva, mistica, comunitaria e tribale.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-54364 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/06\/cover.jpg\" alt=\"\" width=\"194\" height=\"259\" \/>Molti filosofi occidentali, alcuni dei quali si auto-definiscono pagani o occultisti, si uniscono alla loro controparte euroasiatica nell&#8217;ammirare questo ideale russo primitivo. L&#8217;autore Matthew Rose nel suo libro del 2022, <em>Un mondo dopo il liberalismo: Filosofi della Destra Radicale <\/em>(2)<\/span> [<a href=\"https:\/\/www.atfp.it\/notizie\/306-analisi\/2271-un-mondo-post-liberale-dovrebbe-volere-la-restaurazione-della-cristianita\" target=\"_blank\" rel=\"noreferrer noopener\"><span style=\"color: #0000ff;\">qui una recensione<\/span><\/a>], <span style=\"color: #000000;\">esplora il pensiero di cinque figure chiave che hanno influenzato l&#8217;attuale dibattito contro l&#8217;Occidente: Oswald Spengler, Julius Evola, Alain de Benoist, Francis Parker Yockey e Samuel Francis. La loro posizione filorussa include critiche severe al cristianesimo occidentale che, secondo loro, devitalizza gli impulsi naturali e deforma le relazioni sociali. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-35908 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/03\/sinistra.jpg\" alt=\"\" width=\"241\" height=\"209\" \/>E poi c\u2019\u00e8 la sinistra mondiale che odia tutte le manifestazioni del vero Occidente cristiano perch\u00e9 insinua una forma di superiorit\u00e0 in un mondo che deve essere egualitario. L&#8217;odio \u00e8 cos\u00ec intenso che l&#8217;establishment <em>woke <\/em><em>(3)<\/em> ora \u00e8 impegnato in quella che si potrebbe definire una &#8220;guerra civile contro tutto e tutti&#8221;, nel tentativo di annientare qualsiasi valore cristiano nella societ\u00e0 occidentale.\u00a0<\/span><\/p>\n<h4 style=\"text-align: center;\"><span style=\"color: #000000;\"> <strong>Il bersaglio \u00e8 sempre l&#8217;Occidente<\/strong><\/span><\/h4>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">La Russia odierna rifiuta quindi entrambi gli Occidenti, quello vero e quello falso. Cerca di distruggere le vaste reti del falso Occidente guidato da Davos, credendo erroneamente che, togliendogli la prosperit\u00e0, anche il vero Occidente verr\u00e0 rovinato. Russia e Cina sfidano le reti di Davos contrapponendole un Oriente anti-Davos, che creer\u00e0 il caos economico e distrugger\u00e0 la preminenza americana. Inoltre, la Russia odierna propone false ideologie che sostituirebbero ogni traccia di civilt\u00e0 cristiana occidentale.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"> <img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-53545 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/02\/navi_trasporti_porti.jpg\" alt=\"\" width=\"296\" height=\"166\" \/>D\u2019altra parte, la guerra sta spezzando l&#8217;unit\u00e0 delle vaste reti e catene di approvvigionamento, gi\u00e0 compromesse da decenni di fiducia dagli accordi commerciali con i comunisti.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Pi\u00f9 tragico ancora, le nazioni occidentali se la prendono in ogni modo contro la loro origine cristiana. La guerra culturale all&#8217;interno del vero Occidente cristiano sta trascinando quest\u2019ultimo verso un mondo simile a quello pagano, panteista e selvaggio, che distrugger\u00e0 la civilt\u00e0 moderna, buttando sia il bambino che l&#8217;acqua sporca. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">\u00c8 quindi iniziata una guerra culturale globale e la posta in gioco \u00e8 il futuro dell&#8217;Occidente.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-27290 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2013\/09\/crisi_Occidente.jpg\" alt=\"\" width=\"273\" height=\"184\" \/>Per combattere in questa guerra, l&#8217;Occidente non deve rifiutare l&#8217;ordine razionale, lo Stato di diritto e la metafisica oggettiva che gli conferiscono struttura e ordine. Deve resistere alla distruzione postmoderna della logica e alle narrazioni strambe. Soprattutto, l&#8217;Occidente deve tornare alle sue origini che si trovano in Dio, nella sua legge e nella sua santa Chiesa.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Queste soluzioni ricordano quei messaggi inascoltati che furono rivelati dalla Madonna a Fatima nel 1917, quando il pericolo russo esplose sulla scena mondiale, validi oggi come allora.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>Note<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>1)<\/strong> L\u2019immagine impiegata si riferisce al detto popolare \u201cnon buttare il bambino con l\u2019acqua sporca\u201d.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>2)<\/strong> A World After Liberalism: Philosophers of the Radical Right.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>3)<\/strong> Denominazione che viene data alla nuova sinistra occidentale decostruzionista. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>Fonte<\/strong>:<\/span> <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/www.tfp.org\/a-global-culture-war-that-the-west-must-win\/\" target=\"_blank\" rel=\"noreferrer noopener\">Tfp.org<\/a><\/span>, <span style=\"color: #000000;\">20 giugno 2022. \u00a0<em>Traduzione a cura di Tradizione Famiglia Propriet\u00e0 \u2013 Italia.<\/em><\/span><\/p>\n<p>________________________________________<\/p>\n<p><span style=\"color: #000000;\"><strong>Leggi anche:<\/strong><\/span><\/p>\n<p><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-guerra-in-ucraina-e-il-risentimento-occidentale-contro-il-cristianesimo\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">La guerra in Ucraina e il risentimento occidentale contro il cristianesimo<\/span><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tradizione Famiglia Propriet\u00e0 newsletter 28 Giugno 2022 di John Horvat Falso e vero Occidente La guerra in Ucraina \u00e8 pi\u00f9 di un&#8217;ingiusta guerra di aggressione da parte della Russia. Ha come obiettivo anche l&#8217;Occidente come concetto e come blocco geopolitico. Una guerra culturale globale si profila all&#8217;orizzonte, minacciando di distruggere ogni cosa.<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-guerra-culturale-globale-che-loccidente-deve-vincere\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":46643,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56,103,19,116],"tags":[2395,2837,1043,2409],"class_list":["post-54361","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cina","category-laicismo","category-politica-internazionale","category-russia","tag-cina","tag-crisi-delloccidente","tag-occidente","tag-russia","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Una guerra culturale globale che l&#039;Occidente deve vincere\u00a0\u00a0\u00a0\u00a0 - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Una guerra culturale globale che l&#039;Occidente deve vincere. La guerra in Ucraina ha come obiettivo anche l&#039;Occidente\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-guerra-culturale-globale-che-loccidente-deve-vincere\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Una guerra culturale globale che l&#039;Occidente deve vincere\u00a0\u00a0\u00a0\u00a0 - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Una guerra culturale globale che l&#039;Occidente deve vincere. La guerra in Ucraina ha come obiettivo anche l&#039;Occidente\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-guerra-culturale-globale-che-loccidente-deve-vincere\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-29T22:00:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-13T09:21:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/03\/sovranit\u00e0_stati_mondo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"993\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/una-guerra-culturale-globale-che-loccidente-deve-vincere\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/una-guerra-culturale-globale-che-loccidente-deve-vincere\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Una guerra culturale globale che l&#8217;Occidente deve vincere\u00a0\u00a0\u00a0\u00a0\",\"datePublished\":\"2022-06-29T22:00:40+00:00\",\"dateModified\":\"2024-04-13T09:21:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/una-guerra-culturale-globale-che-loccidente-deve-vincere\\\/\"},\"wordCount\":1451,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/una-guerra-culturale-globale-che-loccidente-deve-vincere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/sovranit\u00e0_stati_mondo.jpg\",\"keywords\":[\"Cina\",\"crisi dell&#039;Occidente\",\"occidente\",\"Russia\"],\"articleSection\":[\"Cina\",\"Laicismo\",\"Politica internazionale\",\"Russia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/una-guerra-culturale-globale-che-loccidente-deve-vincere\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/una-guerra-culturale-globale-che-loccidente-deve-vincere\\\/\",\"name\":\"Una guerra culturale globale che l'Occidente deve vincere\u00a0\u00a0\u00a0\u00a0 - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/una-guerra-culturale-globale-che-loccidente-deve-vincere\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/una-guerra-culturale-globale-che-loccidente-deve-vincere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/sovranit\u00e0_stati_mondo.jpg\",\"datePublished\":\"2022-06-29T22:00:40+00:00\",\"dateModified\":\"2024-04-13T09:21:16+00:00\",\"description\":\"Una guerra culturale globale che l'Occidente deve vincere. La guerra in Ucraina ha come obiettivo anche l'Occidente\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/una-guerra-culturale-globale-che-loccidente-deve-vincere\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/una-guerra-culturale-globale-che-loccidente-deve-vincere\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/una-guerra-culturale-globale-che-loccidente-deve-vincere\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/sovranit\u00e0_stati_mondo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/sovranit\u00e0_stati_mondo.jpg\",\"width\":2000,\"height\":993},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/una-guerra-culturale-globale-che-loccidente-deve-vincere\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Una guerra culturale globale che l&#8217;Occidente deve vincere\u00a0\u00a0\u00a0\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Una guerra culturale globale che l'Occidente deve vincere\u00a0\u00a0\u00a0\u00a0 - Rassegna Stampa Cattolica","description":"Una guerra culturale globale che l'Occidente deve vincere. La guerra in Ucraina ha come obiettivo anche l'Occidente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-guerra-culturale-globale-che-loccidente-deve-vincere\/","og_locale":"it_IT","og_type":"article","og_title":"Una guerra culturale globale che l'Occidente deve vincere\u00a0\u00a0\u00a0\u00a0 - Rassegna Stampa Cattolica","og_description":"Una guerra culturale globale che l'Occidente deve vincere. La guerra in Ucraina ha come obiettivo anche l'Occidente","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-guerra-culturale-globale-che-loccidente-deve-vincere\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2022-06-29T22:00:40+00:00","article_modified_time":"2024-04-13T09:21:16+00:00","og_image":[{"width":2000,"height":993,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/03\/sovranit\u00e0_stati_mondo.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"11 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-guerra-culturale-globale-che-loccidente-deve-vincere\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-guerra-culturale-globale-che-loccidente-deve-vincere\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Una guerra culturale globale che l&#8217;Occidente deve vincere\u00a0\u00a0\u00a0\u00a0","datePublished":"2022-06-29T22:00:40+00:00","dateModified":"2024-04-13T09:21:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-guerra-culturale-globale-che-loccidente-deve-vincere\/"},"wordCount":1451,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-guerra-culturale-globale-che-loccidente-deve-vincere\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/03\/sovranit\u00e0_stati_mondo.jpg","keywords":["Cina","crisi dell&#039;Occidente","occidente","Russia"],"articleSection":["Cina","Laicismo","Politica internazionale","Russia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-guerra-culturale-globale-che-loccidente-deve-vincere\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-guerra-culturale-globale-che-loccidente-deve-vincere\/","name":"Una guerra culturale globale che l'Occidente deve vincere\u00a0\u00a0\u00a0\u00a0 - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-guerra-culturale-globale-che-loccidente-deve-vincere\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-guerra-culturale-globale-che-loccidente-deve-vincere\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/03\/sovranit\u00e0_stati_mondo.jpg","datePublished":"2022-06-29T22:00:40+00:00","dateModified":"2024-04-13T09:21:16+00:00","description":"Una guerra culturale globale che l'Occidente deve vincere. La guerra in Ucraina ha come obiettivo anche l'Occidente","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-guerra-culturale-globale-che-loccidente-deve-vincere\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-guerra-culturale-globale-che-loccidente-deve-vincere\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-guerra-culturale-globale-che-loccidente-deve-vincere\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/03\/sovranit\u00e0_stati_mondo.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/03\/sovranit\u00e0_stati_mondo.jpg","width":2000,"height":993},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-guerra-culturale-globale-che-loccidente-deve-vincere\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Una guerra culturale globale che l&#8217;Occidente deve vincere\u00a0\u00a0\u00a0\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/54361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=54361"}],"version-history":[{"count":3,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/54361\/revisions"}],"predecessor-version":[{"id":60021,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/54361\/revisions\/60021"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/46643"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=54361"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=54361"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=54361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}