{"id":53982,"date":"2022-04-28T00:00:52","date_gmt":"2022-04-27T22:00:52","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=53982"},"modified":"2024-04-27T12:24:18","modified_gmt":"2024-04-27T10:24:18","slug":"25-aprile-anche-una-ccasione-per-eliminare-i-nemici-borghesi","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/25-aprile-anche-una-ccasione-per-eliminare-i-nemici-borghesi\/","title":{"rendered":"25 Aprile: anche una occasione per eliminare i nemici \u201cborghesi&#8221;."},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-53983 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/04\/partigiani.jpg\" alt=\"\" width=\"305\" height=\"179\" \/><span style=\"color: #000000;\">Abstract: <\/span><\/strong><span style=\"color: #000000;\"><em>25 Aprile: anche una occasione per eliminare i nemici \u201cborghesi&#8221;. La testimonianza di chi ha visto e vissuto gli omicidi e la persecuzione a guerra finita dei &#8220;partigiani&#8221; rossi. Per non lasciare che siano solo i vincitori a scrivere la storia\u00a0 e far si che i valori di libert\u00e0 e democrazia possano essere\u00a0 pi\u00f9 autentici<\/em><\/span><\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\"><a href=\"https:\/\/www.nicolaporro.it\/atlanticoquotidiano\/\" target=\"_blank\" rel=\"noopener\"><strong>Atlantico Quotidiano <\/strong><\/a>25 Aprile 2022<\/span><\/p>\n<h3 style=\"text-align: center;\"><span style=\"color: #000000;\">25 Aprile: per i comunisti fu anche l\u2019occasione <\/span><\/h3>\n<h3 style=\"text-align: center;\"><span style=\"color: #000000;\">per eliminare i nemici \u201cborghesi&#8221;. <\/span><\/h3>\n<h3 style=\"text-align: center;\"><span style=\"color: #000000;\">La testimonianza di Pierluigi Lenzi\u00a0\u00a0<\/span><\/h3>\n<p style=\"text-align: center;\"><em>R<span style=\"color: #000000;\">iceviamo e volentieri pubblichiamo da Giuseppe Lenzi\u00a0<\/span><\/em><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><em> Egregio direttore, scrivo a nome di mio padre che prima di morire (ha 87 anni) sente il dovere e l\u2019onore di raccontare anche un\u2019altra verit\u00e0 su quei giorni: cosa \u00e8 accaduto a Bologna nell\u2019aprile del \u201945. Il nostro Paese sar\u00e0 uscito dalla guerra civile (sono passati 77 anni) solo dopo che avr\u00e0 fatto verit\u00e0: solo sapendo che sono successe anche cose diverse dalla storia che ha fatto comodo politicamente raccontare, solo nella consapevolezza che ci sono stati galantuomini e martiri in entrambi gli schieramenti, solo cos\u00ec potranno essere autentici e credibili i valori di libert\u00e0, democrazia, giustizia sui cui si fonda il Paese. Grazie direttore per l\u2019attenzione e grazie se avrete la cortesia di dare un po\u2019 di spazio anche al \u201csangue dei vinti\u201d. Giuseppe Lenzi, a nome di Pierluigi Lenzi <\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-46311 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/02\/partigiani.jpg\" alt=\"\" width=\"218\" height=\"290\" \/><span style=\"color: #000000;\">Fra poco quelli della mia generazione non potranno pi\u00f9 testimoniare cosa accadde a Bologna nei giorni della liberazione, ma rimarr\u00e0 solo la storia tramandata, scritta dai vincitori, come \u00e8 sempre successo\u2026 <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">La liberazione \u00e8 stata anche (non solo ovviamente) occasione di eliminazione dei nemici \u201cborghesi\u201d ad opera di partigiani comunisti, per sostituire la classe dirigente e fare la \u201crivoluzione\u201d: a Bologna e dintorni commisero innumerevoli omicidi che devono essere ricordati. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Certa stampa li defin\u00ec \u201cincresciosi incidenti\u201d, ma spesso erano preordinati perch\u00e9 nelle cellule comuniste esistevano elenchi delle persone da eliminare.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Furono uccisi il direttore dell\u2019azienda del gas, l\u2019ingegnere Cuno della Timo, Edoardo Weber, grande inventore e capitano di industria, che fu sequestrato in fabbrica e mai ritrovato (alla Certosa, nella tomba fatta costruire dalla moglie, signora Bolelli, c\u2019\u00e8 solo lei!). <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">I tre fratelli Ducati Bruno, Adriano, Marcello erano gi\u00e0 stati spinti da alcuni partigiani contro il muro del cortile della loro fabbrica per essere fucilati quando entr\u00f2 casualmente (per chiedere una informazione) un camion di militari polacchi\u2026 che li salvarono.<\/span><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-46005 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/09\/partigiani-4.jpg\" alt=\"\" width=\"315\" height=\"181\" \/><span style=\"color: #000000;\">La <em>Ducati <\/em>era l\u2019industria pi\u00f9 grande di<\/span> <span style=\"color: #000000;\">Bologna, con 8 mila dipendenti, mensa aziendale e asilo nido interno (fatto eccezionale per l\u2019epoca). <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">I fratelli <em>Ducati<\/em> a loro spese avevano fatto prolungare fino a Borgo Panigale le rotaie del tram che erano ai due lati della via Emilia. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Per invidia, stupidit\u00e0 e non si capisce per quale altro demerito, politica e banche non finanziarono la ricostruzione dello stabilimento (spesa anticipata dai <em>Ducati <\/em>per poter ricominciare prima possibile a lavorare!), che era stato gravemente danneggiato dai bombardamenti.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Non furono riconosciuti i danni di guerra, con conseguente fallimento e smembramento dei vari settori di produzione: condensatori, valvole, ottica, macchine fotografiche (microcamera <em>Ducati<\/em>), radio, citofoni, calcolatrici (<em>Duconta<\/em>), rasoi elettrici, meccanica, strumenti di misura. Adriano Ducati era uno scienziato, un progettista geniale, lasci\u00f2 Bologna, and\u00f2 negli Stati Uniti, richiesto da Von Braun come collaboratore per realizzare il vettore che doveva andare sulla luna, che poi raggiunsero.<\/span><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-30857 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/01\/partigiani-300x256.jpg\" alt=\"\" width=\"300\" height=\"256\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/01\/partigiani-300x256.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/01\/partigiani.jpg 398w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><span style=\"color: #000000;\">Ai pi\u00f9 giovani \u00e8 difficile far capire il clima di vendetta mortale che si era creato: un amico pi\u00f9 grande di me, si chiamava Goberti, giocava a rugby e lavorava alla <em>Weber<\/em>, part\u00ec volontario per l\u2019Africa e fu uno dei pochi superstiti di Bir El Gobi (\u201cmanc\u00f2 la fortuna, non l\u2019onore!\u201d), fu rimpatriato e ritorn\u00f2 al lavoro. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Per un mese lo minacciarono di morte, quando alla sera sarebbe uscito per tornare a casa. Poi per fortuna col passare del tempo fu ristabilita un po\u2019 di legalit\u00e0.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Mio padre, l\u2019ingegnere Giuseppe Lenzi, era il direttore dell\u2019Istituto Autonomo Case Popolari. Fu sequestrato il 24 aprile pomeriggio in ufficio da due partigiani (inquilini) armati di mitra con un ordine di comparizione del Comando 7 Gap. L\u2019Istituto era in via Santa Margherita 2: fu condotto attraversando il centro di Bologna in via Magarotti (ora via de\u2019 Bersaglieri), alla fine del portico dei Servi.<\/span><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-19499 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/05\/partigiani.jpg\" alt=\"\" width=\"279\" height=\"244\" \/><span style=\"color: #000000;\">Ho rifatto mentalmente tante volte quel tragitto: piazza Celestini, via D\u2019Azeglio, piazza Maggiore davanti a San Petronio, portico del Pavaglione, via Rizzoli, due Torri, Strada Maggiore. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Ricordo che quelle poche volte che sono uscito con mio padre lo salutavano tutti, quindi in quella occasione lo videro sicuramente decine di persone. Lo segu\u00ec a distanza un collega dell\u2019ufficio tecnico: rifer\u00ec a mia madre che entrarono in caserma. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Fu trovato ucciso il giorno dopo in via Scandellara con l\u2019ispettore dell\u2019Istituto, Bruno Domenichini, l\u2019impiegata Ester Verdelli e l\u2019assistente Luigi Scanabissi e altri tre irriconoscibili. Rubarono a mio padre l\u2019orologio <em>Longines <\/em>(di acciaio!), le scarpe, il vestito (rivoltato! Nel taschino il portamine giallo e il regolo calcolatore): il bottino dei briganti!<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">La citt\u00e0 gli doveva molto: aveva formato una squadra di lavoratori entusiasti e l\u2019Istituto dal 1930 ai primi del \u201940 riusc\u00ec a costruire 129 fabbricati in via Casarini, via Malvasia, via dello Scalo, via Pier Crescenzi, alla Bolognina, le Popolarissime di via Libia (la Cirenaica), tutto il villaggio di case bianche in via ora Irma Bandiera angolo via Andrea Costa (gi\u00e0 Duca d\u2019Aosta) in un solo anno. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Pochissimi erano rimasti senza un tetto! Ma chi non aveva pi\u00f9 diritto alla casa popolare, salvo le \u201cmorosit\u00e0 pietose\u201d previste nello statuto, o chi non rispettava le regole della civile convivenza, veniva mandato via.<\/span><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-32277 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/partigiani.jpg\" alt=\"\" width=\"321\" height=\"247\" \/><span style=\"color: #000000;\">Spararono a mio padre appoggiandogli la canna di un\u2019arma vicino al naso. Il proiettile provoc\u00f2 un foro di uscita con sfondamento della calotta cranica, che vidi molti anni dopo quando fu eseguita la riduzione dei resti. \u00f9<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Aveva un carattere intransigente con se stesso e probabilmente pretendeva molto dagli altri. Ricordo di aver giocato con lui, come avrei voluto, poche volte: non ha mai fatto le ferie, tornava tardi la sera (ma io ero gi\u00e0 a letto) e usciva presto la mattina.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Non avevamo una casa nostra, ma eravamo in affitto da un privato: perch\u00e9 non si potesse neanche pensare che si fosse approfittato della sua posizione. Cose che oggi fanno quasi sorridere nella loro onestissima follia. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Mia madre non percep\u00ec alcuna pensione, perch\u00e9 il babbo non aveva maturato l\u2019anzianit\u00e0, n\u00e9 si era messo in tasca nulla oltre lo stipendio\u2026 doveva essere cos\u00ec.<\/span><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-21293 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2010\/07\/partigiani.jpg\" alt=\"\" width=\"329\" height=\"209\" \/><span style=\"color: #000000;\">Mio padre aveva 43 anni, si era laureato a 23 col massimo dei voti. And\u00f2 a lavorare per cinque anni a Genova presso l\u2019impresa <em>Assereto Schmidt<\/em>, specializzata in costruzioni in cemento armato, che ebbe l\u2019appalto dei cementi armati del Littoriale, della piscina coperta e scoperta, all\u2019epoca il lavoro pi\u00f9 importante a Bologna. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Poi per rimanere a Bologna partecip\u00f2 e vinse il concorso per la direzione tecnica dell\u2019Istituto Case Popolari e a 30 anni fu nominato direttore generale.<\/span><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-33263 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/01\/partigiani_rossi.jpg\" alt=\"\" width=\"324\" height=\"244\" \/><span style=\"color: #000000;\">Probabilmente non cap\u00ec perch\u00e9 dopo aver lavorato tanto e bene potesse essere ucciso da un cialtrone: era irrazionale e assurdo! <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Memorie spaventose mi ritornano incancellabili alla mente: l\u2019immagine della montagna di casse di tutti i morti ammazzati, anche fuori nel cortile dell\u2019Istituto di Medicina Legale in via Irnerio e sul marciapiedi, perch\u00e9 dentro non c\u2019era pi\u00f9 posto! Il puzzo di morto e di creosoto\u2026<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Una donna che si chiamava Cesira, comunista, che veniva ad aiutare quando si faceva il bucato, saputa la fine che aveva fatto mio padre, confid\u00f2 a mia madre di aver saputo che il nome di mio padre era incluso in una lista di persone da eliminare in una cellula di via San Vitale e di aver commentato loro <em>\u201cavi mazz\u00e9 un galantomen\u201d<\/em> e di essere andata a San Luca\u2026<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-32266 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/03\/25_aprile.jpg\" alt=\"\" width=\"336\" height=\"200\" \/>Dopo l\u2019uccisione di mio padre molti non ci salutavano pi\u00f9, forse per paura, perch\u00e9 compromettente. Si provava una sensazione dolorosa indescrivibile. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Nella disperazione di mia madre (malata da tempo mor\u00ec pochi anni dopo, nel 1951) si riconobbero i veri amici: in particolare ci aiut\u00f2 l\u2019ingegner Mario Agnoli, amico di mio padre e ultimo podest\u00e0 di Bologna, che mi present\u00f2 per un lavoro (avevo 16 anni e non sapevo fare molto) presso una industria locale. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Riuscimmo a sopravvivere solo nella consapevolezza di essere profondamente delle persone per bene e di non aver nulla di cui vergognarci.<\/span><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-53984 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/04\/partigiani-1.jpg\" alt=\"\" width=\"296\" height=\"205\" \/><span style=\"color: #000000;\">Pochi sanno che l\u2019ingegner Agnoli, padre Acerbi (domenicano), il cardinale Nasalli Rocca, ottennero nel 1944 dal generale Kesserling del comando tedesco la dichiarazione di Bologna Citt\u00e0 Ospedaliera, per aver realizzato entro le Vecchie Mura moltissimi ospedali: tale accordo fu rispettato sia dai tedeschi che dagli americani, che non bombardarono pi\u00f9 la citt\u00e0, salvaguardando cos\u00ec molte vite e monumenti. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Una ventina di anni fa, in occasione dell\u2019anniversario dell\u2019entrata dei polacchi a Bologna, \u00e8 stata scoperta una lapide nel convento di San Domenico che ricorda questo pregevole avvenimento, poco riportato dai giornali, che riconosceva dopo tanti anni che anche tra i fascisti c\u2019erano delle persone per bene\u2026<\/span><\/p>\n<p style=\"text-align: right;\"><span style=\"color: #000000;\"><em>Pierluigi Lenzi<\/em><\/span><\/p>\n<p>__________________________________________<\/p>\n<p><span style=\"color: #000000;\"><strong>Leggi anche:<\/strong><\/span><\/p>\n<p><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/altro-che-25-aprile\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">Altro che 25 Aprile<\/span><\/a><\/p>\n<p><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/25-aprile-una-data-strumentalizzata-che-non-pu-fondare-una-nazione\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">25 Aprile: una data strumentalizzata. Che non pu\u00f2 fondare una nazione<\/span><\/a><\/p>\n<p><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-fine-del-25-aprile\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">La fine del 25 Aprile<\/span><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Abstract: 25 Aprile: anche una occasione per eliminare i nemici \u201cborghesi&#8221;. La testimonianza di chi ha visto e vissuto gli omicidi e la persecuzione a guerra finita dei &#8220;partigiani&#8221; rossi. Per non lasciare che siano solo i vincitori a scrivere la storia\u00a0 e far si che i valori di libert\u00e0 e democrazia possano essere\u00a0 pi\u00f9 &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/25-aprile-anche-una-ccasione-per-eliminare-i-nemici-borghesi\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":45953,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[82,90,24,96],"tags":[1233,424,779,423,162,404],"class_list":["post-53982","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunismo-in-italia","category-ii-guerra-mondiale","category-storia","category-storia-italiana","tag-25-aprile","tag-comunismo-in-italia-2","tag-ii-guerra-mondiale-2","tag-resistenza-2","tag-storia-2","tag-storia-italiana-2","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>25 Aprile: anche una occasione per eliminare i nemici \u201cborghesi&quot;. - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"25 Aprile: anche una occasione per eliminare i nemici \u201cborghesi&quot;. La testimonianza di un testimone di quei giorni\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/25-aprile-anche-una-ccasione-per-eliminare-i-nemici-borghesi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"25 Aprile: anche una occasione per eliminare i nemici \u201cborghesi&quot;. - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"25 Aprile: anche una occasione per eliminare i nemici \u201cborghesi&quot;. La testimonianza di un testimone di quei giorni\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/25-aprile-anche-una-ccasione-per-eliminare-i-nemici-borghesi\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-27T22:00:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-27T10:24:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/01\/partigiani_Anpi.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"917\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/25-aprile-anche-una-ccasione-per-eliminare-i-nemici-borghesi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/25-aprile-anche-una-ccasione-per-eliminare-i-nemici-borghesi\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"25 Aprile: anche una occasione per eliminare i nemici \u201cborghesi&#8221;.\",\"datePublished\":\"2022-04-27T22:00:52+00:00\",\"dateModified\":\"2024-04-27T10:24:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/25-aprile-anche-una-ccasione-per-eliminare-i-nemici-borghesi\\\/\"},\"wordCount\":1500,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/25-aprile-anche-una-ccasione-per-eliminare-i-nemici-borghesi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/partigiani_Anpi.jpg\",\"keywords\":[\"25 aprile\",\"comunismo in Italia\",\"II guerra mondiale\",\"resistenza\",\"storia\",\"storia italiana\"],\"articleSection\":[\"Comunismo in Italia\",\"II Guerra Mondiale\",\"Storia\",\"Storia italiana\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/25-aprile-anche-una-ccasione-per-eliminare-i-nemici-borghesi\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/25-aprile-anche-una-ccasione-per-eliminare-i-nemici-borghesi\\\/\",\"name\":\"25 Aprile: anche una occasione per eliminare i nemici \u201cborghesi\\\". - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/25-aprile-anche-una-ccasione-per-eliminare-i-nemici-borghesi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/25-aprile-anche-una-ccasione-per-eliminare-i-nemici-borghesi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/partigiani_Anpi.jpg\",\"datePublished\":\"2022-04-27T22:00:52+00:00\",\"dateModified\":\"2024-04-27T10:24:18+00:00\",\"description\":\"25 Aprile: anche una occasione per eliminare i nemici \u201cborghesi\\\". La testimonianza di un testimone di quei giorni\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/25-aprile-anche-una-ccasione-per-eliminare-i-nemici-borghesi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/25-aprile-anche-una-ccasione-per-eliminare-i-nemici-borghesi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/25-aprile-anche-una-ccasione-per-eliminare-i-nemici-borghesi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/partigiani_Anpi.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/partigiani_Anpi.jpg\",\"width\":1280,\"height\":917},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/25-aprile-anche-una-ccasione-per-eliminare-i-nemici-borghesi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"25 Aprile: anche una occasione per eliminare i nemici \u201cborghesi&#8221;.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"25 Aprile: anche una occasione per eliminare i nemici \u201cborghesi\". - Rassegna Stampa Cattolica","description":"25 Aprile: anche una occasione per eliminare i nemici \u201cborghesi\". La testimonianza di un testimone di quei giorni","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/25-aprile-anche-una-ccasione-per-eliminare-i-nemici-borghesi\/","og_locale":"it_IT","og_type":"article","og_title":"25 Aprile: anche una occasione per eliminare i nemici \u201cborghesi\". - Rassegna Stampa Cattolica","og_description":"25 Aprile: anche una occasione per eliminare i nemici \u201cborghesi\". La testimonianza di un testimone di quei giorni","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/25-aprile-anche-una-ccasione-per-eliminare-i-nemici-borghesi\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2022-04-27T22:00:52+00:00","article_modified_time":"2024-04-27T10:24:18+00:00","og_image":[{"width":1280,"height":917,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/01\/partigiani_Anpi.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"11 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/25-aprile-anche-una-ccasione-per-eliminare-i-nemici-borghesi\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/25-aprile-anche-una-ccasione-per-eliminare-i-nemici-borghesi\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"25 Aprile: anche una occasione per eliminare i nemici \u201cborghesi&#8221;.","datePublished":"2022-04-27T22:00:52+00:00","dateModified":"2024-04-27T10:24:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/25-aprile-anche-una-ccasione-per-eliminare-i-nemici-borghesi\/"},"wordCount":1500,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/25-aprile-anche-una-ccasione-per-eliminare-i-nemici-borghesi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/01\/partigiani_Anpi.jpg","keywords":["25 aprile","comunismo in Italia","II guerra mondiale","resistenza","storia","storia italiana"],"articleSection":["Comunismo in Italia","II Guerra Mondiale","Storia","Storia italiana"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/25-aprile-anche-una-ccasione-per-eliminare-i-nemici-borghesi\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/25-aprile-anche-una-ccasione-per-eliminare-i-nemici-borghesi\/","name":"25 Aprile: anche una occasione per eliminare i nemici \u201cborghesi\". - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/25-aprile-anche-una-ccasione-per-eliminare-i-nemici-borghesi\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/25-aprile-anche-una-ccasione-per-eliminare-i-nemici-borghesi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/01\/partigiani_Anpi.jpg","datePublished":"2022-04-27T22:00:52+00:00","dateModified":"2024-04-27T10:24:18+00:00","description":"25 Aprile: anche una occasione per eliminare i nemici \u201cborghesi\". La testimonianza di un testimone di quei giorni","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/25-aprile-anche-una-ccasione-per-eliminare-i-nemici-borghesi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/25-aprile-anche-una-ccasione-per-eliminare-i-nemici-borghesi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/25-aprile-anche-una-ccasione-per-eliminare-i-nemici-borghesi\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/01\/partigiani_Anpi.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/01\/partigiani_Anpi.jpg","width":1280,"height":917},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/25-aprile-anche-una-ccasione-per-eliminare-i-nemici-borghesi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"25 Aprile: anche una occasione per eliminare i nemici \u201cborghesi&#8221;."}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/53982","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=53982"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/53982\/revisions"}],"predecessor-version":[{"id":60230,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/53982\/revisions\/60230"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/45953"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=53982"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=53982"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=53982"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}