{"id":53491,"date":"2022-02-17T00:00:01","date_gmt":"2022-02-16T23:00:01","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=53491"},"modified":"2025-07-14T12:18:33","modified_gmt":"2025-07-14T10:18:33","slug":"leone-xiii-e-il-pensiero-di-plinio-correa-de-oliveira-sulla-storia","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/leone-xiii-e-il-pensiero-di-plinio-correa-de-oliveira-sulla-storia\/","title":{"rendered":"La teologia della storia, l\u2019insegnamento di Leone XIII e il pensiero di Plinio Corr\u00eaa De Oliveira"},"content":{"rendered":"\n<p class=\"has-text-align-center\"><a href=\"https:\/\/atfp.it\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\"><strong>Tradizione Famiglia Propriet\u00e0 <\/strong><\/span><\/a>newsletter 10 Febbraio 2022<\/p>\n\n\n\n<p><span style=\"color: #000000;\"><em>Il 19 marzo ricorrono i 120 anni della Lettera apostolica <\/em>Annum ingressi,<em> di Leone XIII, che analizza magistralmente le radici profonde della crisi contemporanea. Si tratta di un documento straordinario, oggi purtroppo dimenticato, che ebbe profonda influenza sul pensiero di Plinio Corr\u00eaa de Oliveira.<\/em><\/span><\/p>\n\n\n\n<p class=\"has-text-align-center\">di <strong>Nelson R. Fragelli<\/strong><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/02\/chiesa_Leone_XIII.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/02\/chiesa_Leone_XIII-1024x576.jpg\" alt=\"\" class=\"wp-image-53496\" style=\"width:447px;height:auto\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/02\/chiesa_Leone_XIII-1024x576.jpg 1024w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/02\/chiesa_Leone_XIII-300x169.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/02\/chiesa_Leone_XIII-768x432.jpg 768w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/02\/chiesa_Leone_XIII.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/div>\n\n\n<!--more-->\n\n\n\n<p><span style=\"color: #000000;\">Studioso assiduo dei documenti del Magistero ecclesiastico, dove trovava gli argomenti necessari alla sua lotta ideologica nel Movimento Cattolico (1), Plinio Corr\u00eaa de Oliveira ebbe un particolare apprezzamento per la Lettera apostolica di Leone XIII <em>Annum ingressi<\/em>, nota in italiano come <em>Vigesimo quinto anno<\/em>, o <em>Parvenu \u00e0 la vingt-cinqui\u00e8me ann\u00e9e<\/em>, titolo originale in francese (2).<\/span><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"281\" height=\"179\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/Plinio-Corr\u00eaa-de-Oliveira.jpg\" alt=\"\" class=\"wp-image-28101\" style=\"width:435px;height:auto\"\/><\/figure><\/div>\n\n\n<p><span style=\"color: #000000;\">La Lettera fu pubblicata il 19 marzo 1902 in occasione del 25\u00b0 anno del Pontificato. Il dott. Plinio le dedic\u00f2 diversi articoli sul <em>Legion\u00e1rio<\/em>, il settimanale cattolico da lui diretto (3), e in seguito anche sul mensile <em>Catolicismo<\/em> (4). Questo documento rappresenta uno degli insegnamenti pi\u00f9 importanti di papa Pecci sugli eventi storici dei tempi moderni.<\/span><\/p>\n\n\n\n<p><span style=\"color: #000000;\">Ogni credente, zelante per le sorti della Chiesa, dovrebbe rallegrarsi di questi ammaestramenti trovandovi validi principi di teologia della storia insegnati da un Pontefice che si accorse della terribile tempesta in cui navigava la Barca di Pietro. Purtroppo, questa Lettera apostolica, qualificata da Plinio Corr\u00eaa de Oliveira \u201c<em>tanto monumentale quanto ignorata<\/em>\u201d, fu oggetto di una vera e propria campagna di silenzio.<\/span><\/p>\n\n\n\n<h4 class=\"wp-block-heading has-text-align-center\"><strong>Penetrazione delle massime rivoluzionarie del 1789<\/strong><\/h4>\n\n\n\n<p>Il Papa apre facendo appello al senso storico dei cattolici. Le vicende sociali e politiche del tempo, scrive, si comprendono solo avendo una chiara visione degli avvenimenti dei popoli. Questa visione \u00e8 assolutamente necessaria soprattutto per il cattolico militante che voglia modellare la societ\u00e0 secondo i principi della sua religione.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"199\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/05\/ghigliottina_rivoluzione_francese-300x199.jpg\" alt=\"\" class=\"wp-image-43042\" style=\"width:452px;height:auto\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/05\/ghigliottina_rivoluzione_francese-300x199.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/05\/ghigliottina_rivoluzione_francese-768x510.jpg 768w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/05\/ghigliottina_rivoluzione_francese-1024x680.jpg 1024w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/05\/ghigliottina_rivoluzione_francese.jpg 1401w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure><\/div>\n\n\n<p><span style=\"color: #000000;\">Lungo l\u2019Ottocento, le idee della Rivoluzione francese erano man mano penetrate negli ambienti ecclesiastici. I liberali allora iniziavano a tendere la mano ai cattolici, proponendo loro un\u2019intesa: passata la bufera rivoluzionaria, i fedeli avrebbero potuto pregare in pace, frequentare le loro chiese e compiere le loro devozioni purch\u00e9 si fossero astenuti dall\u2019intervenire nelle questioni politiche e ideologiche del tempo. Le centinaia di migliaia di martiri della ghigliottina e delle guerre della Vandea sarebbero stati dimenticati, e tutti avrebbero potuto vivere in pace.<\/span><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"211\" height=\"239\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/05\/rivoluzione_francese-3.jpg\" alt=\"\" class=\"wp-image-43054\" style=\"width:335px;height:auto\"\/><\/figure><\/div>\n\n\n<p>Sebbene tale tattica avrebbe chiaramente favorito la corrente rivoluzionaria vittoriosa in Francia nel 1789, l\u2019invito ai cattolici sembrava comunque allettante. Essi avrebbero avuto pace e tranquillit\u00e0, le loro chiese non sarebbero state minacciate n\u00e9 i loro seminari chiusi. L\u2019idea implicava una vera e propria \u201ceresia dell\u2019azione\u201d perch\u00e9 avrebbe permesso, nel concreto, la libera circolazione delle massime rivoluzionarie nelle scuole, negli istituti di formazione giovanile, nelle universit\u00e0, nelle fabbriche, nelle associazioni commerciali e bancarie, e via dicendo. Di per s\u00e9 inaccettabile per un cattolico, l\u2019idea trov\u00f2 purtroppo simpatizzanti nei ranghi della Chiesa.<\/p>\n\n\n\n<h4 class=\"wp-block-heading has-text-align-center\"><strong>La necessit\u00e0 di saldi principi dottrinali<\/strong><\/h4>\n\n\n\n<p>Per Plinio Corr\u00eaa de Oliveira, l\u2019appello di Leone XIII ai cattolici ad avere una teologia della storia e, di conseguenza, uno spirito militante di fronte ai problemi del tempo, aveva una ricaduta immediata sull\u2019apostolato concreto. Infatti, la proposta liberale conteneva un invitante corollario travestito da agnello.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"271\" height=\"186\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/02\/vandea.jpg\" alt=\"\" class=\"wp-image-30103\" style=\"width:463px;height:auto\"\/><\/figure><\/div>\n\n\n<p>Togliendo ai cattolici la grande visione della storia, e richiudendoli quindi nelle sacrestie, la proposta liberale mirava a instillare nella giovent\u00f9 cattolica una disposizione d\u2019animo secondo cui l\u2019ideale di un giovane o di una ragazza del Movimento Cattolico doveva essere quello di conoscersi onestamente e di sposarsi, salvo poi praticare la religione nella tranquillit\u00e0 del focolare, concentrandosi sull\u2019educazione dei propri figli. Era un invito implicito ad abbandonare lo spirito militante e l\u2019attivismo contro i mali del tempo. Semmai, sarebbero state le future generazioni a occuparsene\u2026<\/p>\n\n\n\n<p>Un altro pericolo in agguato per i giovani cattolici del suo tempo, secondo Plinio Corr\u00eaa de Oliveria, era quello di essere etichettati come &#8220;bacchettoni&#8221;, cio\u00e8 di devoti timidi e apatici, il cui orizzonte mentale non va oltre le pareti delle sacrestie; uno \u201cscemo\u201d incapace di avere nozioni chiare sui temi di attualit\u00e0; un \u201cdebole\u201d inetto a intervenire nelle polemiche del tempo. Insomma, una persona dolce e buonista, disposta a ogni sorta di cedimenti che, invariabilmente, lo porta verso sinistra.<\/p>\n\n\n\n<p>La Lettera apostolica di Leone XIII, ricordava il dottor Plinio, equivaleva a un potente richiamo a studiare la storia e le questioni ideologiche, sociali e politiche del tempo; conteneva anche un richiamo alla lotta, cio\u00e8 un invito a scontrarsi con lo spirito del mondo. Il documento sollecitava i cattolici ad avere saldi principi dottrinali e una concezione della societ\u00e0 alla luce del Magistero della Chiesa. Il <em>Legion\u00e1rio<\/em> rispondeva all\u2019appello pontificio con un possente <em>Eccomi!<\/em><\/p>\n\n\n\n<h4 class=\"wp-block-heading has-text-align-center\"><strong>\u201cLa Croce resta salda mentre il mondo gira\u201d<\/strong><\/h4>\n\n\n\n<p>Nessun\u2019altra autorit\u00e0 ha una parola cos\u00ec privilegiata come quella di un Romano Pontefice per evocare il senso della storia. Nessun\u2019altra istituzione occupa un posto cos\u00ec centrale negli affari umani come la Roma dei Papi.<\/p>\n\n\n\n<p>La storia si svolge ai piedi della Croce secondo il motto certosino <em>Stat Crux dum volvitur orbis<\/em> (la Croce resta salda mentre il mondo gira). \u00c8, quindi, nello studio della storia della Chiesa e della Civilt\u00e0 Cristiana che possiamo trovare l\u2019unica vera chiave interpretativa degli eventi di ogni tempo. Per noi cristiani, la storia della Chiesa \u00e8 un trattato di vita spirituale in cui scorgere tracce di eroismo, d\u2019intelligenza e di creativit\u00e0 come in nessun altro racconto. La Lettera apostolica <em>Annum ingressi<\/em> offre un\u2019analisi chiara e succinta delle radici profonde della crisi contemporanea.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"265\" height=\"190\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/02\/Legionario_plinio_correa_oliveira.jpg\" alt=\"\" class=\"wp-image-53495\" style=\"width:425px;height:auto\"\/><\/figure><\/div>\n\n\n<p>Dalle pagine del <em>Legion\u00e1rio<\/em>, Plinio Corr\u00eaa de Oliveira aveva spesso manifestato la sua immensa preoccupazione per i cambiamenti sociali rapidi, a volte folli, specie dopo il secondo dopoguerra. Nel 1902, la Lettera apostolica di Leone XIII apparve come un raggio di Luce e di Verit\u00e0. Mezzo secolo dopo, Plinio Corr\u00eaa de Oliveira mostr\u00f2 al mondo che quella Luce era perenne e che, in contrasto con quella Verit\u00e0 era possibile riconoscere gli errori contenuti in quei cambiamenti.<\/p>\n\n\n\n<h4 class=\"wp-block-heading has-text-align-center\"><strong>Tre tappe nel processo di distruzione della Civilt\u00e0 Cristiana<\/strong><\/h4>\n\n\n\n<p>Ponendo affianco due scene, una dei \u201c<em>tempi in cui la filosofia del Vangelo governava gli Stati<\/em>\u201d, cio\u00e8 il Medioevo, e l\u2019altra della societ\u00e0 odierna, la domanda sorge spontanea: come \u00e8 stata possibile una tale trasformazione? Come mai i principi del Vangelo sono stati cos\u00ec radicalmente negati?<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"191\" height=\"263\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/07\/Lutero.jpg\" alt=\"\" class=\"wp-image-36049\" style=\"width:281px;height:auto\"\/><\/figure><\/div>\n\n\n<p>Il documento di Leone XIII presenta le linee generali di questa negazione. In realt\u00e0 \u00e8 un\u2019unica negazione in tre tappe successive. La prima tappa fu la negazione di Lutero, anche questa triplice: negazione del Papato, negazione del ruolo centrale della Madonna nella storia della salvezza, negazione della Santa Eucaristia.<\/p>\n\n\n\n<p>La seconda grande tappa storica fu la Rivoluzione francese. Essa port\u00f2 a compimento i principi ugualitari della rivolta luterana applicandoli nel campo sociale. I rivoluzionari del 1789 si sollevarono contro il Re, come Lutero si era ribellato al Papa, proclamando la sovranit\u00e0 popolare proprio alla stregua di quanto fatto da alcune sette protestanti. Poi venne la terza tappa, il comunismo, che applicava gli stessi principi nel campo economico e politico.<\/p>\n\n\n\n<p>Leone XIII fa notare che, in fondo, si tratta di un\u2019implacabile guerra condotta contro la Santa Chiesa e contro la Civilt\u00e0 Cristiana. Perch\u00e9 distruggere il cristianesimo medievale, che ha portato \u201c<em>frutti che pi\u00f9 preziosi non si potrebbe pensare<\/em>\u201d (5), si chiede il Pontefice.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"195\" height=\"259\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/09\/crocifisso-1.jpg\" alt=\"\" class=\"wp-image-31310\" style=\"width:291px;height:auto\"\/><\/figure><\/div>\n\n\n<p>Il Papa si chiede ancora, stabilendo un parallelo tra la storia della Chiesa e la vita del suo Divino Fondatore: \u201c<em>Chi offese mai, o in che demerit\u00f2 il divin Redentore? Disceso tra gli uomini per impulso di carit\u00e0 infinita, aveva insegnato una dottrina immacolata, confortatrice, efficacissima ad affratellare l\u2019umanit\u00e0 nella pace e nell\u2019amore; non aveva agognato n\u00e9 grandezze terrene, n\u00e9 onori, non aveva usurpato il diritto di alcuno: era stato invece sommamente pietoso ai deboli, ai malati, ai poveri, ai peccatori, agli oppressi, onde la sua vita non fu che un passaggio per seminare tra gli uomini a larga mano il benefizio<\/em>\u201d.<\/p>\n\n\n\n<p>Tuttavia, Egli fu crocefisso. Non sorprende, quindi, che la Chiesa cattolica, continuatrice della sua missione divina e depositaria incorruttibile della sua verit\u00e0, abbia trovato la stessa sorte del suo Maestro.<\/p>\n\n\n\n<h4 class=\"wp-block-heading has-text-align-center\"><strong>L\u2019egualitarismo, sostrato comune delle tre rivoluzioni<\/strong><\/h4>\n\n\n\n<p>Nel suo capolavoro <em>Rivoluzione e Contro-Rivoluzione<\/em>, Plinio Corr\u00eaa de Oliveira sviluppa il concetto di Rivoluzione proposto da papa Leone XIII, che la definisce \u201c<em>opera perniciosa e sleale &#8230; la cui ragione d\u2019essere consiste nella guerra a Dio e alla sua Chiesa<\/em>\u201d. Il pensatore brasiliano mostra come il substrato della Rivoluzione, in tutte le sue tappe e manifestazioni, sia l\u2019egualitarismo: uguaglianza ecclesiastica nel protestantesimo, uguaglianza sociale nella Rivoluzione francese, uguaglianza economica nel regime comunista.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"232\" height=\"217\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/10\/libert\u00e8_egalit\u00e8_fraternit\u00e8.jpg\" alt=\"\" class=\"wp-image-44766\" style=\"width:404px;height:auto\"\/><\/figure><\/div>\n\n\n<p>L\u2019egualitarismo costituisce un principio tendente a dissolvere la Civilt\u00e0 Cristiana. Leone XIII parla di una \u201c<em>societ\u00e0 al rovescio<\/em>\u201d. Essa proclama l\u2019assoluta uguaglianza delle persone, l\u2019uguaglianza dei sessi, l\u2019uguaglianza nell\u2019abbigliamento, l\u2019uguaglianza anche tra la Religione Cattolica e i culti pagani. Poich\u00e9 Dio, secondo quanto spiega S. Tommaso, ha creato gli uomini ineguali, l\u2019imposizione dell\u2019uguaglianza nella societ\u00e0 assume il carattere di un vero e proprio odio contro di Lui. Negando le naturali differenze, il caos si diffonde ampiamente in tutti gli aspetti della societ\u00e0, preparando un\u2019esplosione di vendetta della natura violata.<\/p>\n\n\n\n<h4 class=\"wp-block-heading has-text-align-center\"><strong>Silenzio incomprensibile su un documento pontificio cos\u00ec rilevante <\/strong><\/h4>\n\n\n\n<p>La Lettera apostolica del Papa, contenente principi vitali per il mondo cattolico, fu largamente ignorata negli ambienti ecclesiastici. Di essa si parl\u00f2 poco. Nelle numerose associazioni cattoliche d\u2019inizio Novecento, il documento non costitu\u00ec tema di studio n\u00e9 di dibattito. I commenti non andarono oltre alle reazioni pro forma. Sulla Lettera cal\u00f2 un silenzio incomprensibile tanto pi\u00f9 che essa conteneva l\u2019unica vera soluzione per i mali che affliggevano la Chiesa e la Civilt\u00e0 Cristiana. Plinio Corr\u00eaa de Oliveira era convinto che la Lettera contenesse un programma percorribile di riscossa cattolica.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"277\" height=\"300\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/08\/modernismo-277x300.jpg\" alt=\"\" class=\"wp-image-44189\" style=\"width:353px;height:auto\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/08\/modernismo-277x300.jpg 277w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/08\/modernismo-768x832.jpg 768w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/08\/modernismo-945x1024.jpg 945w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/08\/modernismo.jpg 1200w\" sizes=\"auto, (max-width: 277px) 100vw, 277px\" \/><\/figure><\/div>\n\n\n<p>Non si possono giudicare le intenzioni, ma \u00e8 lecito domandarsi perch\u00e9 tanto disprezzo per un documento pontificio di cos\u00ec tanta rilevanza. La risposta pi\u00f9 plausibile sembra essere che la Lettera apostolica <em>Annun ingressi<\/em> conteneva un\u2019interpretazione dei fatti storici che cozzava frontalmente con le tendenze che, purtroppo, gi\u00e0 allora stavano disegnando ci\u00f2 che poi sarebbe stato chiamato Modernismo (tanto teologico quanto sociale), padre della <em>Nouvelle Th\u00e9ologie<\/em> e poi della Teologia della liberazione. Queste tendenze eretiche, oggi dominanti nella Chiesa, propongono un\u2019interpretazione storica agli antipodi rispetto a quella di papa Leone XIII.<\/p>\n\n\n\n<p>\u00c8 opinione di Plinio Corr\u00eaa de Oliveira che se i cattolici si fossero mobilitati attorno all\u2019insegnamento di papa Leone XIII, il caos rivoluzionario in cui piomb\u00f2 il secolo XX si sarebbe potuto evitare.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Note<\/strong><\/h4>\n\n\n\n<p><strong>1)<\/strong>. \u201cMovimento cattolico\u201d era il nome dato in Brasile all\u2019insieme dei movimenti laicali. Plinio Corr\u00eaa de Oliveira era il leader delle Congregazioni Mariane, la punta di diamante del Movimento.<\/p>\n\n\n\n<p><strong>2)<\/strong>. La Lettera fu scritta originariamente in francese e italiano, e poi tradotta in tedesco. Solo in seguito ne usc\u00ec il testo latino.<\/p>\n\n\n\n<p><strong>3)<\/strong>. Nova et Vetera. \u201cParvenu \u00e0 la vingt-cinqui\u00e8me ann\u00e9e\u201d, <em>Legion\u00e1rio<\/em>, 18 marzo 1945, n\u00b0 658; \u201cAs enc\u00edclicas de Le\u00e3o XIII\u201d, <em>Legion\u00e1rio<\/em>, 20 luglio 1941, n\u00b0 462; \u201cUm recuo estrat\u00e9gico\u201d, <em>Legion\u00e1rio<\/em>, 15 ottobre 1944, n\u00b0 636; \u201cPartidos, Candidatos, Elei\u00e7\u00f5es\u201d, <em>Legion\u00e1rio<\/em>, n\u00b0 694, 25 novembre 1945.<\/p>\n\n\n\n<p><strong>4)<\/strong>. \u201cO s\u00e9culo da guerra, da morte e do pecado\u201d, <em>Catolicismo<\/em> n\u00ba 2, febbraio 1951; \u201cHeresiarcas de hoje e de outrora\u201d, <em>Catolicismo<\/em> n\u00ba 16, aprile 1952. <strong>5)<\/strong>. Leone XIII, Enciclica <em>Immortale Dei<\/em>, dell\u20191-11-1885, in ASS, vol. XVIII, p. 169.<\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong>Fonte<\/strong>: Rivista Tradizione Famiglia Propriet\u00e0, Febbraio-Marzo 2022.<\/p>\n\n\n\n<p>__________________________________________<\/p>\n\n\n\n<p><strong><span style=\"color: #000000;\">Leggi anche:<\/span><\/strong><\/p>\n\n\n\n<p><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/teologia-della-storia-di-r-th-calmel-o-p\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">Teologia della storia (di R. Th. Calmel O.P.)<\/span><\/a> <span style=\"color: #000000;\">&#8211; libro<\/span><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tradizione Famiglia Propriet\u00e0 newsletter 10 Febbraio 2022 Il 19 marzo ricorrono i 120 anni della Lettera apostolica Annum ingressi, di Leone XIII, che analizza magistralmente le radici profonde della crisi contemporanea. Si tratta di un documento straordinario, oggi purtroppo dimenticato, che ebbe profonda influenza sul pensiero di Plinio Corr\u00eaa de Oliveira. di Nelson R. Fragelli<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/leone-xiii-e-il-pensiero-di-plinio-correa-de-oliveira-sulla-storia\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":53496,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,24],"tags":[1785,2900],"class_list":["post-53491","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chiesa","category-storia","tag-leone-xiii","tag-teologia-della-storia","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La teologia della storia, l\u2019insegnamento di Leone XIII e il pensiero di Plinio Corr\u00eaa De Oliveira - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Leone XIII e il pensiero di Plinio Corr\u00eaa De Oliveira sulla storia. Una analisi sulle radici della crisi contemporanea\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/leone-xiii-e-il-pensiero-di-plinio-correa-de-oliveira-sulla-storia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La teologia della storia, l\u2019insegnamento di Leone XIII e il pensiero di Plinio Corr\u00eaa De Oliveira - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Leone XIII e il pensiero di Plinio Corr\u00eaa De Oliveira sulla storia. Una analisi sulle radici della crisi contemporanea\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/leone-xiii-e-il-pensiero-di-plinio-correa-de-oliveira-sulla-storia\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-16T23:00:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-14T10:18:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/02\/chiesa_Leone_XIII.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"13 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/leone-xiii-e-il-pensiero-di-plinio-correa-de-oliveira-sulla-storia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/leone-xiii-e-il-pensiero-di-plinio-correa-de-oliveira-sulla-storia\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"La teologia della storia, l\u2019insegnamento di Leone XIII e il pensiero di Plinio Corr\u00eaa De Oliveira\",\"datePublished\":\"2022-02-16T23:00:01+00:00\",\"dateModified\":\"2025-07-14T10:18:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/leone-xiii-e-il-pensiero-di-plinio-correa-de-oliveira-sulla-storia\\\/\"},\"wordCount\":1891,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/leone-xiii-e-il-pensiero-di-plinio-correa-de-oliveira-sulla-storia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/chiesa_Leone_XIII.jpg\",\"keywords\":[\"Leone XIII\",\"teologia della storia\"],\"articleSection\":[\"Chiesa\",\"Storia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/leone-xiii-e-il-pensiero-di-plinio-correa-de-oliveira-sulla-storia\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/leone-xiii-e-il-pensiero-di-plinio-correa-de-oliveira-sulla-storia\\\/\",\"name\":\"La teologia della storia, l\u2019insegnamento di Leone XIII e il pensiero di Plinio Corr\u00eaa De Oliveira - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/leone-xiii-e-il-pensiero-di-plinio-correa-de-oliveira-sulla-storia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/leone-xiii-e-il-pensiero-di-plinio-correa-de-oliveira-sulla-storia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/chiesa_Leone_XIII.jpg\",\"datePublished\":\"2022-02-16T23:00:01+00:00\",\"dateModified\":\"2025-07-14T10:18:33+00:00\",\"description\":\"Leone XIII e il pensiero di Plinio Corr\u00eaa De Oliveira sulla storia. Una analisi sulle radici della crisi contemporanea\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/leone-xiii-e-il-pensiero-di-plinio-correa-de-oliveira-sulla-storia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/leone-xiii-e-il-pensiero-di-plinio-correa-de-oliveira-sulla-storia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/leone-xiii-e-il-pensiero-di-plinio-correa-de-oliveira-sulla-storia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/chiesa_Leone_XIII.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/chiesa_Leone_XIII.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/leone-xiii-e-il-pensiero-di-plinio-correa-de-oliveira-sulla-storia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La teologia della storia, l\u2019insegnamento di Leone XIII e il pensiero di Plinio Corr\u00eaa De Oliveira\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La teologia della storia, l\u2019insegnamento di Leone XIII e il pensiero di Plinio Corr\u00eaa De Oliveira - Rassegna Stampa Cattolica","description":"Leone XIII e il pensiero di Plinio Corr\u00eaa De Oliveira sulla storia. Una analisi sulle radici della crisi contemporanea","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/leone-xiii-e-il-pensiero-di-plinio-correa-de-oliveira-sulla-storia\/","og_locale":"it_IT","og_type":"article","og_title":"La teologia della storia, l\u2019insegnamento di Leone XIII e il pensiero di Plinio Corr\u00eaa De Oliveira - Rassegna Stampa Cattolica","og_description":"Leone XIII e il pensiero di Plinio Corr\u00eaa De Oliveira sulla storia. Una analisi sulle radici della crisi contemporanea","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/leone-xiii-e-il-pensiero-di-plinio-correa-de-oliveira-sulla-storia\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2022-02-16T23:00:01+00:00","article_modified_time":"2025-07-14T10:18:33+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/02\/chiesa_Leone_XIII.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"13 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/leone-xiii-e-il-pensiero-di-plinio-correa-de-oliveira-sulla-storia\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/leone-xiii-e-il-pensiero-di-plinio-correa-de-oliveira-sulla-storia\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"La teologia della storia, l\u2019insegnamento di Leone XIII e il pensiero di Plinio Corr\u00eaa De Oliveira","datePublished":"2022-02-16T23:00:01+00:00","dateModified":"2025-07-14T10:18:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/leone-xiii-e-il-pensiero-di-plinio-correa-de-oliveira-sulla-storia\/"},"wordCount":1891,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/leone-xiii-e-il-pensiero-di-plinio-correa-de-oliveira-sulla-storia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/02\/chiesa_Leone_XIII.jpg","keywords":["Leone XIII","teologia della storia"],"articleSection":["Chiesa","Storia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/leone-xiii-e-il-pensiero-di-plinio-correa-de-oliveira-sulla-storia\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/leone-xiii-e-il-pensiero-di-plinio-correa-de-oliveira-sulla-storia\/","name":"La teologia della storia, l\u2019insegnamento di Leone XIII e il pensiero di Plinio Corr\u00eaa De Oliveira - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/leone-xiii-e-il-pensiero-di-plinio-correa-de-oliveira-sulla-storia\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/leone-xiii-e-il-pensiero-di-plinio-correa-de-oliveira-sulla-storia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/02\/chiesa_Leone_XIII.jpg","datePublished":"2022-02-16T23:00:01+00:00","dateModified":"2025-07-14T10:18:33+00:00","description":"Leone XIII e il pensiero di Plinio Corr\u00eaa De Oliveira sulla storia. Una analisi sulle radici della crisi contemporanea","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/leone-xiii-e-il-pensiero-di-plinio-correa-de-oliveira-sulla-storia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/leone-xiii-e-il-pensiero-di-plinio-correa-de-oliveira-sulla-storia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/leone-xiii-e-il-pensiero-di-plinio-correa-de-oliveira-sulla-storia\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/02\/chiesa_Leone_XIII.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2022\/02\/chiesa_Leone_XIII.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/leone-xiii-e-il-pensiero-di-plinio-correa-de-oliveira-sulla-storia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"La teologia della storia, l\u2019insegnamento di Leone XIII e il pensiero di Plinio Corr\u00eaa De Oliveira"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/53491","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=53491"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/53491\/revisions"}],"predecessor-version":[{"id":63262,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/53491\/revisions\/63262"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/53496"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=53491"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=53491"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=53491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}