{"id":5332,"date":"2012-12-14T10:52:20","date_gmt":"2012-12-14T09:52:20","guid":{"rendered":""},"modified":"2015-12-01T11:05:17","modified_gmt":"2015-12-01T10:05:17","slug":"una-nazione-spaccata","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-nazione-spaccata\/","title":{"rendered":"Una nazione spaccata"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/12\/Obama.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-28328\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/12\/Obama.jpg\" alt=\"Obama\" width=\"250\" height=\"140\" \/><\/a>Radici Cristiane<\/strong> n.80 dicembre 2012<\/div>\n<p style=\"text-align: justify;\"><em>La rielezione di Barack Hussein Obama implica una vera e propria rivoluzione che sostanzialmente il quadro psicologico, e quindi anche sociale e politico, degli Stati Uniti<br \/>\n<\/em><\/p>\n<p style=\"text-align: center;\">di <strong>Julio Loredo<\/strong><\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">Dopo l&#8217;attacco proditorio a Pearl Harbour, rispondendo alle adulazioni degli ufficiali che si complimentavano con lui per la vittoria, l&#8217;ammiraglio Isoroku Yamamoto ebbe quel &#8220;<em>mot c\u00e9l\u00e8bre<\/em>&#8220;: \u00ab<em>Abbiamo solo svegliato il gigante assopito<\/em>\u00bb.<\/div>\n<p style=\"text-align: justify;\">OBAMA; NON LIBERAL, MA RADICAL<\/p>\n<p style=\"text-align: justify;\">Qualcosa di simile si potrebbe dire, almeno riguardo a una parte del Paese, della recente rielezione di Barack Hussein Obama, anche se per un margine assai esiguo del voto popolare: poco pi\u00f9 del 2%. Al tempo della sua elezione, nel 2008, analizzando il tipo di cambiamenti ai quali la nazione andava incontro, un opinionista scrisse: \u00abNon bisogna domandarsi quali rivoluzioni potr\u00e0 realizzare il nuovo presidente, lui stesso \u00e8 la Rivoluzione\u00bb.<\/p>\n<p style=\"text-align: justify;\">Infatti, per la prima volta nella storia degli Stati Uniti era stato eletto un presidente nero, seguace della <em>Black Theology of Liberation<\/em>, nella quale scorge \u00abun forte potenziale rivoluzionario\u00bb di idee apertamente socialiste improntate a quel &#8220;socialismo populista&#8221; avanzato da Saul Alinsky, del quale \u00e8 discepolo, partigiano di ogni forma di aborto, compreso l&#8217;orribile <em>partialbirth abortion<\/em>, nel quale il bimbo \u00e8 ucciso mentre nasce, sostenitore delle frange pi\u00f9 estreme dei movimenti omosessualista e femminista, favorevole alla liberazione delle droghe, nemico giurato delle sane tradizioni del Paese, e via dicendo.<\/p>\n<p style=\"text-align: justify;\">Per usare il gergo politico americano, per la prima volta era stato eletto non un <em>liberal<\/em> ma un <em>radical.<\/em><\/p>\n<p style=\"text-align: justify;\">Non tutti hanno intuito sul momento le ultime conseguenze di questo evento epocale. Anche il fatto che Obama abbia poi mantenuto praticamente immutata la politica estera statunitense ha indotto taluni analisti a vedervi una continuit\u00e0 istituzionale, quando in realt\u00e0 si \u00e8 trattato di una vera e propria cesura storica, appunto di una Rivoluzione.<\/p>\n<p style=\"text-align: justify;\">Una Rivoluzione che, nell&#8217;opinione di un numero crescente di analisti, sia politici che ecclesiastici, sta ponendo le condizioni per lo scoppio di una guerra civile. Perch\u00e9 questo giudizio non sembri esagerato, bisogna spendere due parole sulla mentalit\u00e0 americana.<\/p>\n<p style=\"text-align: justify;\">VERSO LA GUERRA CIVILE?<\/p>\n<p style=\"text-align: justify;\">Gli Stati Uniti si sono sempre caratterizzati per una <em>way of life <\/em>affabile e aperta, che considera con distacco i contrasti di opinione, una <em>way of <\/em><em>life <\/em>ottimista e irenica che predilige il pragmatismo e rifugge dalla disquisizione teorica, sempre pe\u00adricolosa in quanto facile premessa di idee assolute e, quindi, di perniciose divisioni.<\/p>\n<p style=\"text-align: justify;\">Questa <em>way of life <\/em>permise di stabilire un clima di tranquilla convivenza e di consenso \u2014 il famoso <em>&#8220;American compact&#8221; &#8211; <\/em>distante anni luci dall&#8217;ambiente europeo, endemicamente lacerato da polemiche e da guerre. La Guerra Civile del 1861-1864, seppur molto cruenta, costitu\u00ec appena una parentesi in questa lunga storia di concordia nazionale.<\/p>\n<p style=\"text-align: justify;\">Permissivo per natura, questo stato di spirito poteva facilmente degenerare in un liberalismo sfrenato, atto a suscitare reazioni che avrebbero potuto dilacerare il tessuto nazionale, dando perfino vita a movimenti di tipo contro-rivoluzionario e, quindi, a guerre tipo Vandea.<\/p>\n<p style=\"text-align: justify;\">Per evitare questo, lo Stato assunse la difesa della religione cristiana in genere quale fondamento dell&#8217;ordine morale, sociale e politico. Donde il paradosso di uno Stato costituzionalmente aconfessionale che si proclamava tuttavia apertamente cristiano, perfino incorporando nella sua vita pubblica non poche manifestazioni religiose. Era la cosiddetta <em>civil religion.<\/em><\/p>\n<p style=\"text-align: justify;\">La salvaguarda di questa <em>way of life <\/em>presupponeva l&#8217;assenza di conflitti che potessero lacerarla. Presupponeva quindi la manutenzione di un ampio consenso intorno alla <em>civil religion <\/em>quale fondamento dell&#8217;ordine americano. E, infatti, per pi\u00f9 di duecento anni le polemiche dottrinali, culturali e politiche si erano sempre mantenute entro certi parametri che vedevano opposti <em>co<\/em><em>servatives <\/em>e <em>liberals<\/em>. Le componenti <em>radical<\/em> (come d&#8217;altronde quelle tradizionaliste in senso europeo), pur presenti, erano marginali.<\/p>\n<p style=\"text-align: justify;\">L&#8217;elezione di Obama nel 2008 ha fatto saltare in aria questo equilibrio. I pesanti interventi governativi in aree cos\u00ec sensibili della realt\u00e0 nazionale che nessuno avrebbe mai sognato di toccare, stanno creando spaccature e rancori non molto dissimili a quelli che precedettero il conflitto del 1861.<\/p>\n<p style=\"text-align: justify;\">Prendiamone un esempio. La riforma sanitaria proposta dal Presidente, la famigerata <em>Obamacare, <\/em>non solo introduce sostanziali modifiche nel sistema sanitario nazionale, ma mette la scure alle radici stesse della mentalit\u00e0 americana, fondata sull&#8217;idea di responsabilit\u00e0 individuale e non sull&#8217;assistenzialismo dello Stato, cosa del tutto aliena al sistema americano. Oltre agli aspetti politici ed economici, gi\u00e0 di per s\u00e9 preoccupanti, l\u2019 <em>Obamacare <\/em>implica un&#8217;immensa rivoluzione culturale che potrebbe cambiare per sempre la stessa mentalit\u00e0 di ampi settori del Paese.<\/p>\n<p style=\"text-align: justify;\">UNA &#8220;CROCIATA IN DIFESA DELL&#8217;ORDINE AMERICANO&#8221;<\/p>\n<p style=\"text-align: justify;\">Come gli \u00e8 riuscito a Obama questo <em>tour de force<\/em>? Egli ha fatto leva su settori della popolazione inclini a ricorrere agli aiuti statali &#8211; particolarmente gente di colore e ispanici &#8211; che, nonostante tutta la retorica sul <em>melting pot, <\/em>non si sono mai integrati perfettamente nel sistema americano, e adesso sembra che vi abbiano rinunciato del tutto. Sono proprio i settori ai quali si riferiva Rommey quando ha dichiarato \u00ab<em>costoro non voteranno mai per me<\/em>\u00bb. E cos\u00ec \u00e8 andata.<\/p>\n<p style=\"text-align: justify;\">Ma, come dicono gli americani, <em>there ain\u2019t no free lunch<\/em>, &#8220;non c&#8217;\u00e8 pranzo gratuito&#8221;. Qualcuno deve pure pagare il conto. Chi pagher\u00e0? Ovviamente quella parte della popolazione che, nel tipico <em>american style<\/em>, non si adagia sull&#8217;assistenzialismo statale ma preferisce lavorare sodo. Sar\u00e0 disposta a farlo? Basta leggere i giornali e i blog americani di questi ultimi mesi per accorgersi quanto questa parte della popolazione si senta presa in giro e stia mostrando una insofferenza crescente di cui non \u00e8 possibile prevedere gli ultimi sviluppi.<\/p>\n<p style=\"text-align: justify;\">Si comincia a parlare di &#8220;crociata in difesa dell&#8217;ordine americano&#8221;. L&#8217;intervento radicale di Obama ha provocato una reazione altrettanto radicale. E qui stiamo parlando del 48% degli americani, vale a dire di coloro che hanno votato Mitt Rommey e che, in futuro, potranno votare Rick Santorum.<\/p>\n<p style=\"text-align: justify;\">UNO SPARTIACQUE STORICO<\/p>\n<p style=\"text-align: justify;\">L&#8217;area dove l&#8217;ingerenza obamista sta provocando maggiori disagi, per\u00f2, \u00e8 il campo religioso.<\/p>\n<p style=\"text-align: justify;\">Rompendo ogni equilibrio storico, e calpestando anche un fondamento del sistema americano, cio\u00e8 la libert\u00e0 religiosa, Obama ha cancellato l&#8217;obiezione di coscienza nelle strutture sanitarie nazionali, L\u2019<em>Obamacare<\/em> prevede, infatti, che medici e infermieri non possano pi\u00f9 addurre un conflitto di coscienza quando si tratti di eseguire interventi contrari alla morale cristiana, come l&#8217;aborto, l&#8217;eutanasia o la somministrazione di contraccettivi.<\/p>\n<p style=\"text-align: justify;\">La reazione dei cattolici \u00e8 stata decisa e compatta. Perfino molti vescovi, finora silenziosi quando non schiera con i <em>liberal<\/em>, hanno alzato la voce contro il governo. Il cardinale Raymond Burke, gi\u00e0 arcivescovo di Saint Louis e attuale Prefetto della Segnato Apostolica del Vaticano, \u00e8 stato molto chiaro: \u00ab<em>Ci stiamo inoltrando in una vera e propria situazione di persecuzione religiosa<\/em>\u00bb. Una persecuzione totalmente aliena all&#8217;<em>american way of life <\/em>e che, in pratica, ne costituisce la negazione.<\/p>\n<p style=\"text-align: justify;\">Preoccupato per la fortissima reazione dei cattolici \u2014 dei quali dipende il 40% del sistema sanitario nazionale &#8211; Obama ha sospeso fino 2013 l&#8217;applicazione di questa clausola della riforma. Ma cosa succeder\u00e0 dopo? Tutto il personale sanitario cattolico, e non solo, sar\u00e0 costretto a scegliere fra l&#8217;obbedienza alla leggi di Dio e l&#8217;obbedienza alla legge di Barack Hussein Obama.<\/p>\n<p style=\"text-align: justify;\">Se a questo aggiungiamo una serie di disposizioni legali che, sotto il pretesto della &#8220;non discrimazione&#8221;, praticamente vietano alla Chiese Cattolica di insegnare la sua dottrina in campo morale, possiamo capire le inquietanti dichiarazioni del cardinale Francis George, arcivescovo di Chicago: \u00ab<em>Io spero di morire nel mio letto. Il mio successore morir\u00e0 certamente in prigione. Il suo successori morir\u00e0 martire sulla piazza pubblica<\/em>\u00bb.<\/p>\n<p style=\"text-align: justify;\">Quando si pu\u00f2 parlare di martirio in piazza pubblica negli Stati Uniti, \u00e8 chiaro che \u00e8 stato superato un confine. Da parte loro, non vi \u00e8 pi\u00f9 il rispetto per i parametri tradizionali del sistema americano. Sono disposti a calpestare qualsiasi principio pur di imporre la Rivoluzione. Da parte nostra, cresce la consapevolezza di dover arrivare fino al martirio pur di difendere i principi non negoziabili.<\/p>\n<p style=\"text-align: justify;\">Il &#8220;gigante assopito&#8221; si sta risvegliando. Con quali conseguenze? Solo il futuro lo dir\u00e0. Il fatto \u00e8 che, a nostro parere, le ultime due elezioni americane costituiscono uno spartiacque storico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Radici Cristiane n.80 dicembre 2012 La rielezione di Barack Hussein Obama implica una vera e propria rivoluzione che sostanzialmente il quadro psicologico, e quindi anche sociale e politico, degli Stati Uniti di Julio Loredo<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-nazione-spaccata\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":28328,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[108,76],"tags":[150],"class_list":["post-5332","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-paesi-e-continenti","category-stati-uniti","tag-usa","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Una nazione spaccata - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-nazione-spaccata\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Una nazione spaccata - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-nazione-spaccata\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2012-12-14T09:52:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-12-01T10:05:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/12\/Obama.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"168\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/una-nazione-spaccata\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/una-nazione-spaccata\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Una nazione spaccata\",\"datePublished\":\"2012-12-14T09:52:20+00:00\",\"dateModified\":\"2015-12-01T10:05:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/una-nazione-spaccata\\\/\"},\"wordCount\":1327,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/una-nazione-spaccata\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2012\\\/12\\\/Obama.jpg\",\"keywords\":[\"Usa\"],\"articleSection\":[\"Paesi e continenti\",\"Stati Uniti\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/una-nazione-spaccata\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/una-nazione-spaccata\\\/\",\"name\":\"Una nazione spaccata - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/una-nazione-spaccata\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/una-nazione-spaccata\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2012\\\/12\\\/Obama.jpg\",\"datePublished\":\"2012-12-14T09:52:20+00:00\",\"dateModified\":\"2015-12-01T10:05:17+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/una-nazione-spaccata\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/una-nazione-spaccata\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/una-nazione-spaccata\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2012\\\/12\\\/Obama.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2012\\\/12\\\/Obama.jpg\",\"width\":300,\"height\":168},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/una-nazione-spaccata\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Una nazione spaccata\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Una nazione spaccata - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-nazione-spaccata\/","og_locale":"it_IT","og_type":"article","og_title":"Una nazione spaccata - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-nazione-spaccata\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2012-12-14T09:52:20+00:00","article_modified_time":"2015-12-01T10:05:17+00:00","og_image":[{"width":300,"height":168,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/12\/Obama.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-nazione-spaccata\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-nazione-spaccata\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Una nazione spaccata","datePublished":"2012-12-14T09:52:20+00:00","dateModified":"2015-12-01T10:05:17+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-nazione-spaccata\/"},"wordCount":1327,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-nazione-spaccata\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/12\/Obama.jpg","keywords":["Usa"],"articleSection":["Paesi e continenti","Stati Uniti"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-nazione-spaccata\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-nazione-spaccata\/","name":"Una nazione spaccata - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-nazione-spaccata\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-nazione-spaccata\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/12\/Obama.jpg","datePublished":"2012-12-14T09:52:20+00:00","dateModified":"2015-12-01T10:05:17+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-nazione-spaccata\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-nazione-spaccata\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-nazione-spaccata\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/12\/Obama.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/12\/Obama.jpg","width":300,"height":168},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-nazione-spaccata\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Una nazione spaccata"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/5332","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=5332"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/5332\/revisions"}],"predecessor-version":[{"id":28329,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/5332\/revisions\/28329"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/28328"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=5332"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=5332"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=5332"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}