{"id":5328,"date":"2012-12-12T00:00:00","date_gmt":"2012-12-11T23:00:00","guid":{"rendered":""},"modified":"2016-03-02T14:48:35","modified_gmt":"2016-03-02T13:48:35","slug":"pi-preziosi-del-petrolio","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/pi-preziosi-del-petrolio\/","title":{"rendered":"Pi&ugrave; preziosi del petrolio"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-31340\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/12\/bambini.jpg\" alt=\"bambini\" width=\"250\" height=\"133\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/12\/bambini.jpg 308w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/12\/bambini-300x160.jpg 300w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" \/>Avvenire <\/strong>mercoled\u00ec 5 dicembre 2012<\/div>\n<p style=\"text-align: center;\"><em>I figli:la risorsa che manca all\u2019Italia<\/em><\/p>\n<p style=\"text-align: center;\">di <strong>Marina Corradi<\/strong><\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">\u00abPi\u00f9 preziosi del petrolio in esaurimento\u00bb: cos\u00ec saranno in Italia i bambini, nell&#8217;anno 2030. Lo dice <em>Save th\u00e8 Children<\/em>, la grande e laica organizzazione internazionale che sorveglia la situazione dell&#8217;infanzia nel mondo. Gli ultimi dati sulla evoluzione demografica, si legge nel rapporto sull&#8217;Italia, inducono a un ulteriore pessimismo.<\/div>\n<p style=\"text-align: justify;\">Nella congiuntura di crisi economica e arresto dei flussi migratori, la lieve crescita della natalit\u00e0 degli utimi anni si \u00e8 arrestata; e nel 2011 sono stati 15 mila i nati in meno, rispetto al 2010. (Anche questo \u00e8 un numero della crisi: quindicimila figli non nati. Figli magari desiderati, e negati; figli, forse, cancellati da madri che si sono dette: non ce la posso fare).<\/p>\n<p style=\"text-align: justify;\">Ma il rapporto va oltre, e incrocia i dati disegnando un triste futuro. Nel 2030 ogni 100 persone che lavorano, ce ne saranno 63 inattive. Pi\u00f9 avanti, andr\u00e0 peggio. (In una situazione cos\u00ec quale welfare sar\u00e0 realisticamente sostenibile, viene da chiedersi, quale assistenza sanitaria potr\u00e0 essere garantita alla grande e crescente fascia di popolazione anziana?) I lettori di <em>Avvenire <\/em>queste cose le sanno da tempo.<\/p>\n<p style=\"text-align: justify;\">L&#8217;allarme demografico \u00e8 da anni denunciato dalla Chiesa italiana e da questo giornale. Tant&#8217;\u00e8 che per molto tempo \u00e8 apparso come una preoccupazione &#8220;cattolica &#8211; come a dire, in certo pensiero mediaticamente dominante, una questione di retroguardia, non allineata alla modernit\u00e0. (E fino a non molti anni fa addirittura in Italia parlare di incrementare la natalit\u00e0 suonava male, risvegliava impresentabili echi di politiche demografiche del ventennio fascista. Assurdo, ma l&#8217;ideologia \u00e8 dura a morire).<\/p>\n<p style=\"text-align: justify;\">Ora che anche le Ong laiche convengono che il problema \u00e8 serio, pare che quell&#8217;allarme fosse invece avanguardia. Amara soddisfazione, leggendo i grafici di quest&#8217;ultimo rapporto con le loro linee inesorabilmente calanti, malinconico ritratto di un tramonto collettivo.<\/p>\n<p style=\"text-align: justify;\">Declino di natalit\u00e0 \u00e8 declino di vita e di energie; ma anche di consumi, di lavoro, di ricchezza, di contributi che sostentino le pensioni dei vecchi. Uno \u00absmottamento generazionale\u00bb, dice il rapporto. E pare di vedere una societ\u00e0, la nostra, insediata su un terreno finora solido, e che invece, e neanche tanto lentamente, si sfalda.<\/p>\n<p style=\"text-align: justify;\"><em>Save the children<\/em> nel rapporto immagina, a esorcizzare questo declino, un patto generazionale, e riforme del welfare, e un&#8217;Italia del 2030 piena di nidi e asili, e di scuole che \u00abdovranno funzionare come orologi svizzeri\u00bb. Se non lo dicesse una seria e stimata Ong, diremmo: fantascienza.<\/p>\n<p style=\"text-align: justify;\">Perch\u00e9, allo stato delle cose, non si vede in Italia una vera coscienza politica dell&#8217;emergenza demografica. N\u00e9 pare di scorgere la questione tra i temi portanti della campagna elettorale. Quasi che i figli fossero in realt\u00e0 una questione solo e strettamente individuale; e averne e averne nell&#8217;ambiente migliore possibile (una famiglia fondata sul matrimonio tra madre e padre, e tendenzialmente stabile) o non a-verne affatto, fosse cosa socialmente irrilevante. Come se invece che un Paese fossimo ormai solo tanti individui, casualmente affiancati; e solidariet\u00e0 e futuro, vocaboli desueti.<\/p>\n<p style=\"text-align: justify;\">O come se guadagnasse consenso anche da noi quel neo-pensiero che teorizza la bellezza e la libert\u00e0 del non avere figli; e quell&#8217;interessata ma miope ottica di mercato che in Occidente da tempo vezzeggia i <em>dink<\/em>, ovvero <em>double income no kids<\/em>, le coppie con due stipendi e nessun figlio, eccellenti consumatori.<\/p>\n<p style=\"text-align: justify;\">Senonch\u00e9 anche i <em>dink <\/em>invecchiano, e si comincia ad avvertire che quei consumi non potranno essere mantenuti giacch\u00e9 mancano i figli, per sostenerli. L&#8217;amara evidenza che \u00e8 difficile pensare a una &#8220;crescita&#8221; continua e inarrestabile, se le culle e le scuole si svuotano. I bambini preziosi, fra pochi anni, \u00abcome il petrolio in esaurimento\u00bb?<\/p>\n<p style=\"text-align: justify;\">Servisse, questa immagine dura e concreta, a muovere un ampio e condiviso pensiero politico. Potrebbe anche essere un modo per ricominciare. Per guardare in avanti e non solo all&#8217;attimo presente; per progettare un futuro pi\u00f9 umano. E per sperare insieme, e desiderare di continuare una storia, la nostra. Compito che pure spetterebbe a una politica tesa al bene comune, e vera.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avvenire mercoled\u00ec 5 dicembre 2012 I figli:la risorsa che manca all\u2019Italia di Marina Corradi<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/pi-preziosi-del-petrolio\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":31340,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9,108],"tags":[1251],"class_list":["post-5328","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-demografia","category-paesi-e-continenti","tag-italia","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pi&ugrave; preziosi del petrolio - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/pi-preziosi-del-petrolio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pi&ugrave; preziosi del petrolio - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/pi-preziosi-del-petrolio\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2012-12-11T23:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-03-02T13:48:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/12\/bambini.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"308\" \/>\n\t<meta property=\"og:image:height\" content=\"164\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/pi-preziosi-del-petrolio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/pi-preziosi-del-petrolio\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Pi&ugrave; preziosi del petrolio\",\"datePublished\":\"2012-12-11T23:00:00+00:00\",\"dateModified\":\"2016-03-02T13:48:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/pi-preziosi-del-petrolio\\\/\"},\"wordCount\":661,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/pi-preziosi-del-petrolio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2012\\\/12\\\/bambini.jpg\",\"keywords\":[\"Italia\"],\"articleSection\":[\"Demografia\",\"Paesi e continenti\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/pi-preziosi-del-petrolio\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/pi-preziosi-del-petrolio\\\/\",\"name\":\"Pi&ugrave; preziosi del petrolio - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/pi-preziosi-del-petrolio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/pi-preziosi-del-petrolio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2012\\\/12\\\/bambini.jpg\",\"datePublished\":\"2012-12-11T23:00:00+00:00\",\"dateModified\":\"2016-03-02T13:48:35+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/pi-preziosi-del-petrolio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/pi-preziosi-del-petrolio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/pi-preziosi-del-petrolio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2012\\\/12\\\/bambini.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2012\\\/12\\\/bambini.jpg\",\"width\":308,\"height\":164},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/pi-preziosi-del-petrolio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pi&ugrave; preziosi del petrolio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pi&ugrave; preziosi del petrolio - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/pi-preziosi-del-petrolio\/","og_locale":"it_IT","og_type":"article","og_title":"Pi&ugrave; preziosi del petrolio - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/pi-preziosi-del-petrolio\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2012-12-11T23:00:00+00:00","article_modified_time":"2016-03-02T13:48:35+00:00","og_image":[{"width":308,"height":164,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/12\/bambini.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/pi-preziosi-del-petrolio\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/pi-preziosi-del-petrolio\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Pi&ugrave; preziosi del petrolio","datePublished":"2012-12-11T23:00:00+00:00","dateModified":"2016-03-02T13:48:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/pi-preziosi-del-petrolio\/"},"wordCount":661,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/pi-preziosi-del-petrolio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/12\/bambini.jpg","keywords":["Italia"],"articleSection":["Demografia","Paesi e continenti"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/pi-preziosi-del-petrolio\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/pi-preziosi-del-petrolio\/","name":"Pi&ugrave; preziosi del petrolio - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/pi-preziosi-del-petrolio\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/pi-preziosi-del-petrolio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/12\/bambini.jpg","datePublished":"2012-12-11T23:00:00+00:00","dateModified":"2016-03-02T13:48:35+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/pi-preziosi-del-petrolio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/pi-preziosi-del-petrolio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/pi-preziosi-del-petrolio\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/12\/bambini.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/12\/bambini.jpg","width":308,"height":164},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/pi-preziosi-del-petrolio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Pi&ugrave; preziosi del petrolio"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/5328","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=5328"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/5328\/revisions"}],"predecessor-version":[{"id":31341,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/5328\/revisions\/31341"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/31340"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=5328"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=5328"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=5328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}