{"id":5318,"date":"2012-12-06T00:00:00","date_gmt":"2012-12-05T23:00:00","guid":{"rendered":""},"modified":"2016-01-22T10:22:47","modified_gmt":"2016-01-22T09:22:47","slug":"pio-xii-e-loperazione-sturzo","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/pio-xii-e-loperazione-sturzo\/","title":{"rendered":"Pio XII e l\u2019operazione Sturzo"},"content":{"rendered":"<div style=\"text-align: center;\">\n<div id=\"attachment_29595\" style=\"width: 250px\" class=\"wp-caption alignright\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/12\/De-Gasperi.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-29595\" class=\"wp-image-29595\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/12\/De-Gasperi.jpg\" alt=\"De Gasperi\" width=\"250\" height=\"145\" \/><\/a><p id=\"caption-attachment-29595\" class=\"wp-caption-text\">Alcide De Gasperi<\/p><\/div>\n<p><strong>Il Timone<\/strong> n.117 novembre 2012<\/div>\n<p style=\"text-align: justify;\"><em>Maggio 1952: il Papa incoraggia un patto politico dei cattolici intorno a un programma. Si tratta di difendere la Roma cristiana. Alcide De Gasperi si oppone. Perch\u00e9 vuole un partito laico e aconfessionale, e lavora per l&#8217;apertura a sinistra. Ottaviani sta con Pio XII, Montini con De Gasperi<\/em><\/p>\n<p style=\"text-align: center;\">di <strong>Roberto de Mattei<\/strong><\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">Tra le molteplici cause del processo di secolarizzazione della societ\u00e0 italiana, non va dimenticato il fallimento della cosiddetta &#8220;operazione Sturzo&#8221;, concepita sessant&#8217;anni fa da Luigi Gedda, con l&#8217;avallo di Pio XII. La guerra si era appena conclusa e Pio XII proponeva un progetto di restaurazione della societ\u00e0 cristiana sulla stessa linea del programma di san Pio X: &#8220;tutto restaurare e riordinare in Cristo&#8221;. Papa Pacelli voleva realizzare l&#8217;unit\u00e0 dei cattolici non attorno ad un partito, ma a un programma, come era accaduto nelle elezioni del 1913, con il Patto Gentiloni approvato da san Pio X.<\/div>\n<p style=\"text-align: justify;\">Luigi Gedda, l&#8217;artefice della schiacciante vittoria elettorale del 18 aprile 1948, sembrava l&#8217;uomo pi\u00f9 adatto a realizzare il piano del Pontefice. Il primo banco di prova sarebbero state le elezioni amministrative del maggio 1952, che precedevano di un anno quelle politiche. Il 22 gennaio di quell&#8217;anno Luigi Gedda veniva nominato presidente dell&#8217;Azione Cattolica, cumulando questa carica con quella di presidente dei Comitati Civici.<\/p>\n<p style=\"text-align: justify;\">Il 10 febbraio, Pio XII lanciava al popolo romano un &#8220;grido di risveglio&#8221;, mirabilmente sintetizzato in queste parole: \u00ab\u00c8 tempo di scuotere il funesto letargo, \u00e8 tempo di ripetere con l&#8217;Apostolo: <em>tor\u00e0 iam nos de somno surgere<\/em>. \u00c8 tutto un mondo che occorre rifare dalle fondamenta, che bisogna trasformare da selvatico in umano, e da umano in divino, vale a dire secondo il cuore di Dio\u00bb.<\/p>\n<p style=\"text-align: justify;\">Pio XII intendeva promuovere un rinnovamento cristiano del mondo a partire da Roma e intendeva affidare a Luigi Gedda questo compito. Pio XII e Gedda incontrarono per\u00f2 l&#8217;opposizione di Alcide De Gasperi, creatore, tra il 1943 e il 1946, della Democrazia Cristiana, che si presentava quale erede dal Partito Popolare Italiano fondato nel 1919 da don Luigi Sturzo, e si richiamava, oltre che allo stesso Sturzo, a don Romolo Murri, fondatore in Italia del modernismo politico e scomunicato da san Pio X nel 1909.<\/p>\n<p style=\"text-align: justify;\">De Gasperi e i suoi compagni, influenzati anche dal pensiero di Jacques Maritain (che era stato ambasciatore di Francia presso la Santa Sede dal 1944 al 1948), propugnavano uno Stato e quindi un partito laico e aconfessionale, e credevano nella necessit\u00e0 di un accordo con i partiti di sinistra, nella convinzione che in questa direzione irreversibile volgesse ormai la storia. Fin dal 1946 un avvocato romano, Carlo Francesco D&#8217;Agostino, aveva presentato al Sant&#8217;Uffizio una denuncia contro gli errori dottrinali della Democrazia Cristiana.<\/p>\n<p style=\"text-align: justify;\">Lo stesso D&#8217;Agostino, agli inizi degli anni Cinquanta, aveva rinnovato la sua denuncia con una lettera aperta dal titolo <em>La illusione democristiana.<\/em><\/p>\n<p style=\"text-align: justify;\">Il mondo cattolico era per\u00f2 diviso. Tra i collaboratori di Pio XII, alcuni, come il cardinale Ottaviani, condividevano le riserve del Pontefice verso la Democrazia Cristiana, altri, come il Sostituto Segretario di Stato per gli Affari Straordinari Giovanni Battista Montini, erano convinti sostenitori dell&#8217;unit\u00e0 dei cattolici attorno a De Gasperi.<\/p>\n<p style=\"text-align: justify;\">Nonostante le elezioni del 18 aprile avessero dato alla DC la maggioranza assoluta, permettendole di governare da sola senza le sinistre, De Gasperi, dal maggio1948, aveva associato al suo Governo anche i socialdemocratici del PSLI e i repubblicani, con l&#8217;opposizione della sinistra socialcomunista e delle destre, rappresentate dal Partito Nazionale Monarchico (PNM) di Achille Lauro e dal Movimento Sociale Italiano (MSI) di Augusto de Marsanich.<\/p>\n<p style=\"text-align: justify;\">Il problema che ora si apriva era quello della citt\u00e0 di Roma dove, senza un accordo con il MSI e il PNM, la Democrazia cristiana rischiava di regalare il Campidoglio al &#8220;Blocco del Popolo&#8221; delle sinistre, guidato dall&#8217;ex presidente del Consiglio Francesco Saverio Nitti.<\/p>\n<p style=\"text-align: justify;\">Con l&#8217;incoraggiamento di Pio XII, Gedda si fece allora promotore di una lista civica, aperta al sostegno di tutti gli anticomunisti, compresi i monarchici e i missini. La lista sarebbe stata capeggiata dall&#8217;anziano, ma rappresentativo, don Luigi Sturzo, divenuto critico nei confronti della politica di De Gasperi.<\/p>\n<p style=\"text-align: justify;\">Dietro le quinte si muoveva uno dei principali ideatori del progetto, il vescovo Roberto Ronca, esponente di punta del &#8220;partito romano&#8221;, fedele a Pio XII. Quella che fu detta \u201cl\u2019operazione Sturzo&#8221; fu per\u00f2 pesantemente contrastata da Alcide De Gasperi e da Carlo Carretto, presidente dei Giovani di Azione Cattolica, sensibile, come molti giovani democristiani, all&#8217;influenza di Giuseppe Dossetti.<\/p>\n<p style=\"text-align: justify;\">Nelle sue <em>Memorie <\/em>(Mondadori, Milano 1998), Gedda ha scritto che \u00abla divergenza di fondo con i democristiani dipendeva dalla loro convinzione che il comunismo avrebbe ineluttabilmente conquistato il potere e che il problema dunque era quello di cercare fin da subito forme di coesistenza con il futuro vincitore\u00bb.<\/p>\n<p style=\"text-align: justify;\">Il 22 aprile fu annunciato l&#8217;appello che don Sturzo lanciava a tutti i partiti per la \u00abformazione di una lista amministrativa composta da persone competenti e al di fuori di ogni colorazione politica, sulla quale potessero convergere i voti di quanti si preoccupano di salvaguardare il carattere unico e specialissimo di Roma, capitale d&#8217;Italia e sede del Papato\u00bb.<\/p>\n<p style=\"text-align: justify;\">Il giorno successivo per\u00f2 don Sturzo, in seguito alle forti resistenze di parte della DC e del mondo cattolico, fu costretto a rinunciare alla sua lista e l&#8217;operazione naufrag\u00f2. Era la sconfitta di Gedda, ma anche quella di De Gasperi. Le elezioni videro infatti il successo delle destre, che conquistarono molte citt\u00e0 del Sud, a cominciare da Napoli.<\/p>\n<p style=\"text-align: justify;\">Per impedire che le destre divenissero determinanti nella successiva legislatura, De Gasperi ide\u00f2 allora un mutamento della legge elettorale, in modo da attribuire il 65% dei seggi della Camera alla lista che avesse ottenuto pi\u00f9 del 50% dei voti. Ribattezzata &#8220;legge truffa&#8221; e combattuta sia dalla destra che dalla sinistra, la legge maggioritaria fu promulgata il 31 marzo 1953.<\/p>\n<p style=\"text-align: justify;\">Tuttavia, nelle elezioni del 7 giugno dello stesso anno, la DC e i partiti di centro raggiunsero il 49,7%, mancando per 54.000 voti la maggioranza assoluta. La De perse molti consensi, mentre aumentarono il Partito Nazionale Monarchico (PNM) (da 14 a 40 deputati) e il Movimento Sociale Italiano (MSI) (da 6 a 28).<\/p>\n<p style=\"text-align: justify;\">De Gasperi cerc\u00f2 di costituire il suo ottavo ministero, il 28 luglio 1953, ma non ottenne la fiducia in parlamento. Tre giorni dopo, la &#8220;legge truffa&#8221; fu abrogata. Nel gennaio 1954, lo scrittore Giovannino Guareschi pubblic\u00f2 sul giornale &#8220;II Candido&#8221;, da lui diretto, la copia di due lettere autografe di De Gasperi in cui il futuro leader DC chiedeva agli inglesi, nel 1944, di bombardare la periferia di Roma.<\/p>\n<p style=\"text-align: justify;\">De Gasperi denunci\u00f2 per diffamazione Guareschi, che venne condannato a tredici mesi di carcere e non present\u00f2 appello contro la sentenza, ma scont\u00f2 tutta la sua pena in galera. La storiografia non ha ancora pronunciato una parola definitiva sull&#8217;autenticit\u00e0 di quei documenti, ma libri come quelli di Ubaldo Giuliani Balestrino (<em>Il<\/em> <em>Carteggio Churchill-Mussolin alla luce del processo Guareschi, <\/em>Settimo Sigillo, 2010) sollevano pesanti interrogativi nei confronti dell&#8217;uomo politico trentino, di cui \u00e8 in corso la causa di beatificazione.<\/p>\n<p style=\"text-align: justify;\">Le riserve di Pio XII nei confronti di De Gasperi e della nascente Democrazia Cristiana sono peraltro storicamente documentate. L&#8217;esito dell&#8217; \u201cope-razione Sturzo&#8221; contribu\u00ec a fare definitivamente svanire la fiducia del Papa in De Gasperi, giudicato dal Pontefice non pi\u00f9 capace di resistere alla avanzata del comunismo.<\/p>\n<p style=\"text-align: justify;\">Nel giugno 1952, a poche settimane da questo episodio, il Papa rifiut\u00f2 di ricevere De Gasperi in udienza, in occasione del suo trentesimo di matrimonio e della professione perpetua della figlia suor Lucia. Maria Romana Catti De Gasperi ha raccontato l&#8217;amarezza che tale rifiuto provoc\u00f2 al padre, il quale dichiar\u00f2 all&#8217;ambasciatore d&#8217;Italia presso la Santa Sede che se come cristiano accettava l&#8217;umiliazione, come presidente del consiglio protestava e chiedeva spiegazioni.<\/p>\n<p style=\"text-align: justify;\">Pio XII fu poi irritato dal discorso pronunziato da De Gasperi il 20 marzo 1954 al Consiglio Nazionale della DC, in cui egli ribadiva che la DC non era \u00abun partito confessionale, emanazione dell&#8217;autorit\u00e0 ecclesiastica\u00bb, e ricordava la sua costante sollecitudine di associare al governo forze di altra ispirazione, unico mezzo per consolidare la nascente democrazia italiana, e criticava i Comitati Civici, che, \u00abper quanto benemeriti per la loro efficace opera di mobilitazione, non hanno mai preteso a funzioni di rappresentanza e responsabilit\u00e0 politica\u00bb.<\/p>\n<p style=\"text-align: justify;\">Pio XII ordin\u00f2 alla <em>&#8220;Civilt\u00e0 Cattolica&#8221; <\/em>di scrivere un articolo contro De Gasperi, precisando quella che a suo avviso era la vera dottrina della Chiesa. Nello stesso periodo diminu\u00ec anche l&#8217;influenza all&#8217;interno del Vaticano di mons. Giovanni Battista Montini, che fece ogni sforzo per far recedere Pio XII dalla decisione di non ricevere De Gasperi.<\/p>\n<p style=\"text-align: justify;\">Nel novembre 1954 mons. Montini fu allontanato dalla Curia con la nomina ad arcivescovo di Milano, senza per\u00f2 essere creato cardinale da Pio XII. Alcide De Gasperi era morto il 19 agosto 1954. Sturzo, che nel novembre del 1953 era stato fatto senatore a vita dal presidente della Repubblica Luigi Einaudi, scomparve l&#8217;8 agosto 1959.<\/p>\n<p style=\"text-align: justify;\">Ma fu solo la fine di Pio XII, il 9 ottobre del 1958, a chiudere l&#8217;epoca storica, a cui solo Luigi Gedda sopravvisse in silenzio, tornando a Dio il 26 settembre 2000. Oggi si pu\u00f2 dire che il fallimento dell&#8217;operazione Sturzo, ricordato sempre con <em>amarezza <\/em>da Luigi Gedda, apr\u00ec la strada verso il centro-sinistra e il compromesso storico.<\/p>\n<p style=\"text-align: justify;\">Un percorso in cui gli eredi di De Gasperi non &#8220;tradirono&#8221; l&#8217;uomo politico trentino, come spesso si crede, ma ne continuarono con coerenza la politica di &#8220;secolarizzazione&#8221; della societ\u00e0.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Timone n.117 novembre 2012 Maggio 1952: il Papa incoraggia un patto politico dei cattolici intorno a un programma. Si tratta di difendere la Roma cristiana. Alcide De Gasperi si oppone. Perch\u00e9 vuole un partito laico e aconfessionale, e lavora per l&#8217;apertura a sinistra. Ottaviani sta con Pio XII, Montini con De Gasperi di Roberto &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/pio-xii-e-loperazione-sturzo\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":29595,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[79,96],"tags":[803,890],"class_list":["post-5318","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-democrazia-cristiana","category-storia-italiana","tag-luigi-gedda","tag-pio-xii","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pio XII e l\u2019operazione Sturzo - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/pio-xii-e-loperazione-sturzo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pio XII e l\u2019operazione Sturzo - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/pio-xii-e-loperazione-sturzo\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2012-12-05T23:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-01-22T09:22:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/12\/De-Gasperi.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"294\" \/>\n\t<meta property=\"og:image:height\" content=\"171\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/pio-xii-e-loperazione-sturzo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/pio-xii-e-loperazione-sturzo\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Pio XII e l\u2019operazione Sturzo\",\"datePublished\":\"2012-12-05T23:00:00+00:00\",\"dateModified\":\"2016-01-22T09:22:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/pio-xii-e-loperazione-sturzo\\\/\"},\"wordCount\":1556,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/pio-xii-e-loperazione-sturzo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2012\\\/12\\\/De-Gasperi.jpg\",\"keywords\":[\"Luigi Gedda\",\"Pio XII\"],\"articleSection\":[\"Democrazia cristiana\",\"Storia italiana\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/pio-xii-e-loperazione-sturzo\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/pio-xii-e-loperazione-sturzo\\\/\",\"name\":\"Pio XII e l\u2019operazione Sturzo - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/pio-xii-e-loperazione-sturzo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/pio-xii-e-loperazione-sturzo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2012\\\/12\\\/De-Gasperi.jpg\",\"datePublished\":\"2012-12-05T23:00:00+00:00\",\"dateModified\":\"2016-01-22T09:22:47+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/pio-xii-e-loperazione-sturzo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/pio-xii-e-loperazione-sturzo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/pio-xii-e-loperazione-sturzo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2012\\\/12\\\/De-Gasperi.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2012\\\/12\\\/De-Gasperi.jpg\",\"width\":294,\"height\":171},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/pio-xii-e-loperazione-sturzo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pio XII e l\u2019operazione Sturzo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pio XII e l\u2019operazione Sturzo - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/pio-xii-e-loperazione-sturzo\/","og_locale":"it_IT","og_type":"article","og_title":"Pio XII e l\u2019operazione Sturzo - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/pio-xii-e-loperazione-sturzo\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2012-12-05T23:00:00+00:00","article_modified_time":"2016-01-22T09:22:47+00:00","og_image":[{"width":294,"height":171,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/12\/De-Gasperi.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"8 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/pio-xii-e-loperazione-sturzo\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/pio-xii-e-loperazione-sturzo\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Pio XII e l\u2019operazione Sturzo","datePublished":"2012-12-05T23:00:00+00:00","dateModified":"2016-01-22T09:22:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/pio-xii-e-loperazione-sturzo\/"},"wordCount":1556,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/pio-xii-e-loperazione-sturzo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/12\/De-Gasperi.jpg","keywords":["Luigi Gedda","Pio XII"],"articleSection":["Democrazia cristiana","Storia italiana"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/pio-xii-e-loperazione-sturzo\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/pio-xii-e-loperazione-sturzo\/","name":"Pio XII e l\u2019operazione Sturzo - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/pio-xii-e-loperazione-sturzo\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/pio-xii-e-loperazione-sturzo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/12\/De-Gasperi.jpg","datePublished":"2012-12-05T23:00:00+00:00","dateModified":"2016-01-22T09:22:47+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/pio-xii-e-loperazione-sturzo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/pio-xii-e-loperazione-sturzo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/pio-xii-e-loperazione-sturzo\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/12\/De-Gasperi.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2012\/12\/De-Gasperi.jpg","width":294,"height":171},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/pio-xii-e-loperazione-sturzo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Pio XII e l\u2019operazione Sturzo"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/5318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=5318"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/5318\/revisions"}],"predecessor-version":[{"id":29596,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/5318\/revisions\/29596"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/29595"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=5318"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=5318"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=5318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}